{"id":548,"date":"2021-05-11T06:17:20","date_gmt":"2021-05-11T06:17:20","guid":{"rendered":"https:\/\/feinamc.eu\/home\/"},"modified":"2021-06-24T06:40:18","modified_gmt":"2021-06-24T06:40:18","slug":"home","status":"publish","type":"page","link":"https:\/\/feinamc.eu\/it\/","title":{"rendered":"Home"},"content":{"rendered":"<div><svg width=\"1622\" height=\"1010\" viewBox=\"0 0 1622 1010\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n<g id=\"whiteBackground 1\" clip-path=\"url(#clip0)\">\n<g id=\"Group\">\n<g id=\"Layer 2\">\n<g id=\"Layer 1\">\n<g id=\"Group_2\" style=\"mix-blend-mode:multiply\" opacity=\"0.8\">\n<g id=\"Vector\" style=\"mix-blend-mode:multiply\" opacity=\"0.15\">\n<path d=\"M1621.12 936L64.5199 1009.4L18.4399 18.44H1573.44L1621.12 936Z\" fill=\"#332D2D\"\/>\n<\/g>\n<\/g>\n<path id=\"Vector_2\" d=\"M1602.68 917.56L46.08 990.97L0 0H1555L1602.68 917.56Z\" fill=\"white\"\/>\n<\/g>\n<\/g>\n<\/g>\n<\/g>\n<defs>\n<clipPath id=\"clip0\">\n<rect width=\"1621.12\" height=\"1009.4\" fill=\"white\"\/>\n<\/clipPath>\n<\/defs>\n<\/svg>\n<\/div>\n<h1><strong>Diffondere ed approfondire buone pratiche per promuovere l\u2019inclusione educativa di migranti appena arrivati<\/strong><\/h1>\n<div><svg width=\"1207\" height=\"540\" viewBox=\"0 0 1207 540\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n<g id=\"no-children 1\">\n<g id=\"children 2\">\n<g id=\"children 1\">\n<g id=\"Group\">\n<g id=\"Layer 2\">\n<g id=\"Layer 1\">\n<path id=\"Vector689132\" d=\"M1009 48.47C1009 50.93 998.49 52.93 985.53 52.93C972.57 52.93 962.05 50.93 962.05 48.47\" stroke=\"#EB6D79\" stroke-width=\"2\" stroke-miterlimit=\"10\"\/>\n<path id=\"Vector689132 2\" d=\"M962.06 48.47C962.06 46 972.57 44 985.54 44C998.51 44 1009 46 1009 48.47\" stroke=\"#EB6D79\" stroke-width=\"2\" stroke-miterlimit=\"10\"\/>\n<path id=\"Vector689132 3\" d=\"M1009 101.53C1009 104 998.49 106 985.53 106C972.57 106 962.05 104 962.05 101.53\" stroke=\"#EB6D79\" stroke-width=\"2\" stroke-miterlimit=\"10\"\/>\n<path id=\"Vector689132 4\" d=\"M962.06 101.53C962.06 99.07 972.57 97.07 985.54 97.07C998.51 97.07 1009.01 99.07 1009.01 101.53\" stroke=\"#EB6D79\" stroke-width=\"2\" stroke-miterlimit=\"10\"\/>\n<path id=\"Vector689132 5\" d=\"M962.06 48.73V101.53\" stroke=\"#EB6D79\" stroke-width=\"2\" stroke-miterlimit=\"10\"\/>\n<path id=\"Vector689132 6\" d=\"M1009.01 48.73V101.53\" stroke=\"#EB6D79\" stroke-width=\"2\" stroke-miterlimit=\"10\"\/>\n<path id=\"Vector689132 7\" d=\"M955.96 45.5601V104.58\" stroke=\"#EB6D79\" stroke-width=\"2\" stroke-miterlimit=\"10\"\/>\n<path id=\"Vector689132 8\" d=\"M954.3 45.42H957.63\" stroke=\"#EB6D79\" stroke-width=\"2\" stroke-miterlimit=\"10\"\/>\n<path id=\"Vector689132 9\" d=\"M954.3 104.58H957.63\" stroke=\"#EB6D79\" stroke-width=\"2\" stroke-miterlimit=\"10\"\/>\n<path id=\"b-move\" d=\"M952.423 72.668C952.423 74.4626 952.01 75.9062 951.185 76.9989C950.36 78.0844 949.253 78.6271 947.864 78.6271C946.38 78.6271 945.233 78.1025 944.423 77.0532L944.325 78.41H942.48V61.7375H944.488V67.9571C945.298 66.9513 946.416 66.4484 947.842 66.4484C949.268 66.4484 950.386 66.9875 951.196 68.0657C952.014 69.1439 952.423 70.6201 952.423 72.4943V72.668ZM950.414 72.44C950.414 71.0724 950.15 70.0159 949.622 69.2705C949.094 68.5252 948.334 68.1525 947.343 68.1525C946.018 68.1525 945.067 68.7676 944.488 69.9978V75.0777C945.103 76.3079 946.062 76.9229 947.364 76.9229C948.327 76.9229 949.076 76.5503 949.611 75.8049C950.147 75.0596 950.414 73.938 950.414 72.44Z\" fill=\"#EB6D79\"\/>\n<path id=\"Vector689132 156\" d=\"M608.62 205.4H397.43\" stroke=\"#EB6D79\" stroke-width=\"2\" stroke-miterlimit=\"10\"\/>\n<path id=\"abnormal\" d=\"M567.42 221.4C567.42 221.4 567.22 180.09 556.08 179.48C544.94 178.87 547.78 231.72 532.59 234.76C517.4 237.8 538.08 138.18 503.59 138.18C469.1 138.18 499.22 251 467.31 251C435.4 251 452.11 176.28 434.39 174.46C416.67 172.64 433.89 235.46 414.14 235.46\" stroke=\"#EB6D79\" stroke-width=\"2\" stroke-miterlimit=\"10\"\/>\n<path id=\"Vector689132 158\" d=\"M503.03 101.12V274.85\" stroke=\"#EB6D79\" stroke-width=\"2\" stroke-miterlimit=\"10\"\/>\n<path id=\"x\" d=\"M391.089 197.155L395.454 189.97H399.383L392.944 199.701L399.583 209.65H395.691L391.143 202.284L386.596 209.65H382.686L389.325 199.701L382.886 189.97H386.778L391.089 197.155Z\" fill=\"#EB6D79\"\/>\n<path id=\"y\" d=\"M503.305 85.0609L507.889 70.3101H511.49L503.578 93.0275C502.353 96.3014 500.407 97.9384 497.74 97.9384L497.103 97.8838L495.848 97.6473V94.9191L496.757 94.9918C497.897 94.9918 498.782 94.7614 499.413 94.3007C500.056 93.8399 500.583 92.9972 500.995 91.7725L501.741 89.7717L494.72 70.3101H498.394L503.305 85.0609Z\" fill=\"#EB6D79\"\/>\n<g id=\"circlea\">\n<path id=\"a\" d=\"M182.816 179.49C182.622 179.102 182.465 178.411 182.344 177.417C180.779 179.041 178.912 179.854 176.741 179.854C174.801 179.854 173.207 179.308 171.958 178.217C170.721 177.113 170.103 175.719 170.103 174.033C170.103 171.984 170.879 170.396 172.431 169.268C173.995 168.128 176.19 167.558 179.015 167.558H182.289V166.012C182.289 164.836 181.937 163.902 181.234 163.211C180.531 162.508 179.494 162.156 178.124 162.156C176.923 162.156 175.917 162.46 175.104 163.066C174.292 163.672 173.886 164.406 173.886 165.267H170.503C170.503 164.284 170.848 163.339 171.54 162.429C172.243 161.508 173.189 160.78 174.377 160.247C175.577 159.713 176.893 159.446 178.324 159.446C180.591 159.446 182.368 160.016 183.653 161.156C184.938 162.284 185.605 163.842 185.654 165.83V174.888C185.654 176.695 185.884 178.132 186.345 179.199V179.49H182.816ZM177.233 176.925C178.287 176.925 179.288 176.653 180.234 176.107C181.179 175.561 181.865 174.852 182.289 173.979V169.941H179.652C175.529 169.941 173.468 171.148 173.468 173.561C173.468 174.615 173.819 175.44 174.522 176.034C175.226 176.628 176.129 176.925 177.233 176.925Z\" fill=\"#5198BF\"\/>\n<path id=\"Vector689132 501\" d=\"M159.84 216.47C140.84 198.8 136.45 170 149.9 147.83C155.204 138.827 163.106 131.639 172.57 127.21C187.29 120.56 205.64 121.36 220.74 130.49C235.84 139.62 247 157.24 247.74 175C248.019 182.464 246.591 189.893 243.563 196.721C240.536 203.549 235.989 209.596 230.27 214.4C219.27 223.59 204.9 227.73 190.32 228.06C185.22 228.18 169.32 225.21 160.25 216.88L159.84 216.47Z\" stroke=\"#5198BF\" stroke-width=\"2\" stroke-miterlimit=\"10\"\/>\n<\/g>\n<g id=\"circleb\">\n<path id=\"Vector689132 502\" d=\"M215.47 233.79C200.19 219.57 196.77 196.29 207.77 178.56C211.996 171.543 218.217 165.944 225.64 162.48C231.795 159.794 238.506 158.629 245.205 159.085C251.905 159.541 258.396 161.604 264.13 165.1C276.19 172.39 285.13 186.47 285.73 200.66C285.947 206.627 284.798 212.564 282.372 218.02C279.946 223.475 276.306 228.305 271.73 232.14C262.96 239.48 251.46 242.79 239.81 243.05C235.73 243.15 223.05 240.77 215.81 234.12L215.47 233.79Z\" stroke=\"#5198BF\" stroke-width=\"2\" stroke-miterlimit=\"10\"\/>\n<path id=\"b 2\" d=\"M269.667 204.028C269.667 207.035 268.976 209.455 267.594 211.285C266.211 213.104 264.356 214.014 262.028 214.014C259.542 214.014 257.62 213.135 256.262 211.376L256.099 213.65H253.006V185.712H256.371V196.134C257.729 194.449 259.603 193.606 261.992 193.606C264.38 193.606 266.254 194.51 267.612 196.316C268.982 198.123 269.667 200.597 269.667 203.737V204.028ZM266.302 203.646C266.302 201.355 265.86 199.584 264.974 198.335C264.089 197.086 262.816 196.462 261.155 196.462C258.936 196.462 257.341 197.493 256.371 199.554V208.066C257.402 210.127 259.009 211.158 261.191 211.158C262.804 211.158 264.059 210.534 264.956 209.285C265.854 208.036 266.302 206.156 266.302 203.646Z\" fill=\"#5198BF\"\/>\n<\/g>\n<g id=\"circlec\">\n<path id=\"Vector689132 503\" d=\"M261.11 99.8C277.03 108.06 286.38 125.45 283.44 141.35C282.312 147.012 279.839 152.32 276.23 156.826C272.62 161.332 267.98 164.904 262.7 167.24C251.63 172.17 237.32 171.56 226.99 165.03C222.67 162.262 219.038 158.544 216.373 154.16C213.707 149.775 212.078 144.84 211.61 139.73C210.74 129.94 214.04 120.19 219.61 111.84C221.55 108.91 229.45 101.12 237.71 99.26C251.49 96.14 261.11 99.8 261.11 99.8Z\" stroke=\"#5198BF\" stroke-width=\"2\" stroke-miterlimit=\"10\"\/>\n<path id=\"c\" d=\"M258.99 135.327C260.191 135.327 261.24 134.964 262.137 134.236C263.034 133.508 263.531 132.599 263.628 131.508H266.811C266.751 132.635 266.363 133.709 265.647 134.727C264.932 135.746 263.974 136.558 262.773 137.164C261.585 137.771 260.324 138.074 258.99 138.074C256.31 138.074 254.176 137.183 252.588 135.4C251.012 133.605 250.223 131.156 250.223 128.052V127.488C250.223 125.572 250.575 123.869 251.278 122.377C251.982 120.886 252.988 119.728 254.298 118.903C255.619 118.079 257.177 117.666 258.972 117.666C261.179 117.666 263.01 118.327 264.465 119.649C265.932 120.971 266.714 122.686 266.811 124.796H263.628C263.531 123.523 263.046 122.48 262.173 121.668C261.312 120.843 260.245 120.431 258.972 120.431C257.262 120.431 255.935 121.049 254.989 122.286C254.055 123.511 253.588 125.287 253.588 127.615V128.252C253.588 130.519 254.055 132.266 254.989 133.49C255.922 134.715 257.256 135.327 258.99 135.327Z\" fill=\"#5198BF\"\/>\n<\/g>\n<path id=\"Vector689132 915\" d=\"M202.56 283.63L200.07 368.08L177.73 358.66L202.56 283.66V283.63ZM205 270L175.29 359.78L202 371.06L205 270Z\" fill=\"#5198BF\"\/>\n<path id=\"Vector689132 916\" d=\"M205.74 270L238.31 362.29L201.98 371.06\" stroke=\"#5198BF\" stroke-width=\"2\" stroke-miterlimit=\"10\"\/>\n<path id=\"Vector689132 917\" d=\"M175.25 359.78L177.22 359.43\" stroke=\"#5198BF\" stroke-width=\"2\" stroke-miterlimit=\"10\"\/>\n<path id=\"Vector689132 919\" d=\"M215.46 352.62L217.43 352.27L217.13 350.29\" stroke=\"#5198BF\" stroke-width=\"2\" stroke-miterlimit=\"10\"\/>\n<path id=\"Vector689132 921\" d=\"M205.26 271.98L204.96 270\" stroke=\"#5198BF\" stroke-width=\"2\" stroke-miterlimit=\"10\"\/>\n<g id=\"dotted\">\n<path id=\"Vector689132 918\" d=\"M181.47 358.68L213.34 353\" stroke=\"#5198BF\" stroke-width=\"2\" stroke-miterlimit=\"10\" stroke-dasharray=\"4.32 4.32\"\/>\n<path id=\"Vector689132 920\" d=\"M216.51 346.17L205.57 274.04\" stroke=\"#5198BF\" stroke-width=\"2\" stroke-miterlimit=\"10\" stroke-dasharray=\"4.17 4.17\"\/>\n<path id=\"Vector689132 922\" d=\"M238.31 362.29L217.43 352.27\" stroke=\"#5198BF\" stroke-width=\"2\" stroke-miterlimit=\"10\" stroke-dasharray=\"4 4\"\/>\n<\/g>\n<path id=\"poseid\" d=\"M563.42 100.22C563.42 100.22 571.58 103.31 571.33 86.81C571.21 78.93 571.21 71.11 571.23 65.09C571.23 57.09 579.86 51.77 586.76 55.72C587.92 56.3215 588.891 57.2321 589.565 58.351C590.239 59.47 590.59 60.7537 590.58 62.06C590.83 73.06 577.58 71.56 577.58 71.56C577.58 71.56 592.58 71.31 592.58 83.31C592.58 95.31 574.75 94.64 574.75 89.22\" stroke=\"#EB6D79\" stroke-width=\"2\" stroke-miterlimit=\"10\"\/>\n<path id=\"poseid\" d=\"M1025.63 6.33002C1025.63 6.33002 1031.63 2.67002 1032.63 8.67002C1033.63 14.67 1025.63 38 1037.63 38C1049.63 38 1038 9.33002 1041 6.33002C1044 3.33002 1049.67 6.67002 1049.67 6.67002\" stroke=\"#EB6D79\" stroke-width=\"2\" stroke-miterlimit=\"10\"\/>\n<path id=\"poseid\" d=\"M1036.96 0V51\" stroke=\"#EB6D79\" stroke-width=\"2\" stroke-miterlimit=\"10\"\/>\n<\/g>\n<\/g>\n<\/g>\n<\/g>\n<\/g>\n<\/g>\n<\/svg>\n<\/div>\n<p><img decoding=\"async\" src=\"\/wp-content\/uploads\/2021\/05\/boy11.svg\" alt=\"\"><\/p>\n<div><img decoding=\"async\" src=\"\/wp-content\/uploads\/2021\/05\/girl-img.svg\"><\/div>\n<p><img decoding=\"async\" src=\"\/wp-content\/uploads\/2021\/05\/girl11.svg\" alt=\"\"><\/p>\n<div><svg width=\"372\" height=\"409\" viewBox=\"0 0 372 409\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n<g id=\"standing-boy 1\">\n<g id=\"Standingboy 1\">\n<g id=\"Group\">\n<g id=\"Layer 2\">\n<g id=\"Layer 1\">\n<path id=\"Vector5656231\" d=\"M305.26 356.95H307.89V349.13H305.26V356.95Z\" fill=\"#AB805B\"\/>\n<path id=\"Vector5656231 2\" d=\"M285.23 361.45L306.57 356.42L327.9 361.45V363.39H285.23V361.45Z\" fill=\"#AB805B\"\/>\n<path id=\"Vector5656231 3\" d=\"M327.74 361.41L327.9 361.45V363.39H285.23V361.45L285.4 361.41H327.74Z\" fill=\"#FFB640\"\/>\n<path id=\"Vector5656231 4\" d=\"M263.47 270.11L265.47 272.25C260.313 279.876 257.405 288.799 257.08 298C256.19 325.47 278.75 347.74 307.46 347.74C315.281 347.742 323.011 346.068 330.13 342.83L332.13 344.97C321.879 350.905 309.908 353.162 298.199 351.367C286.491 349.573 275.746 343.835 267.742 335.102C259.739 326.37 254.956 315.166 254.187 303.346C253.417 291.525 256.706 279.797 263.51 270.1L263.47 270.11Z\" fill=\"#AB805B\"\/>\n<g id=\"worldrota\">\n<path id=\"Vector5656231 5\" d=\"M307.03 345.54C333.413 345.54 354.8 324.153 354.8 297.77C354.8 271.387 333.413 250 307.03 250C280.647 250 259.26 271.387 259.26 297.77C259.26 324.153 280.647 345.54 307.03 345.54Z\" fill=\"#47AAD1\"\/>\n<path id=\"Vector5656231 6\" d=\"M295.88 340.06C295.602 340.012 295.338 339.904 295.107 339.744C294.875 339.583 294.682 339.373 294.54 339.13C294.186 338.239 294.123 337.259 294.36 336.33C294.428 335.927 294.458 335.519 294.45 335.11C294.293 334.233 294.007 333.383 293.6 332.59C292.973 330.962 291.919 329.532 290.55 328.45C289.857 328.033 289.119 327.698 288.35 327.45L287.43 327.11C285.48 326.352 283.686 325.24 282.14 323.83C281.757 323.521 281.478 323.102 281.34 322.63C281.251 322.177 281.279 321.709 281.42 321.27C282.136 318.449 282.046 315.483 281.16 312.71C281.036 312.421 280.973 312.11 280.973 311.795C280.973 311.48 281.036 311.169 281.16 310.88C281.245 310.727 281.349 310.586 281.47 310.46C281.431 310.397 281.38 310.343 281.32 310.3C280.97 310.055 280.693 309.721 280.517 309.332C280.341 308.943 280.273 308.514 280.32 308.09C280.454 307.565 280.778 307.109 281.23 306.81C282.109 306.196 283.064 305.699 284.07 305.33C284.655 305.101 285.226 304.838 285.78 304.54C286.283 304.249 286.77 303.932 287.24 303.59C287.74 303.24 288.24 302.88 288.77 302.59C289.83 302.02 290.942 301.551 292.09 301.19L295.17 300.11C296.188 299.712 297.248 299.433 298.33 299.28C300.175 299.179 302.023 299.437 303.77 300.04C304.497 300.205 305.194 300.478 305.84 300.85C306.08 301 306.31 301.18 306.54 301.35C306.77 301.52 306.87 301.61 307.05 301.73C307.733 302.085 308.502 302.244 309.27 302.19L310.35 302.08V302.13H310.6L310.73 304.13H310.42C309.945 304.2 309.508 304.429 309.18 304.78C308.984 304.993 308.803 305.221 308.64 305.46L307.95 306.46C308.67 308.06 309.17 309.85 308.3 311.46C307.899 312.135 307.356 312.714 306.71 313.16C306.333 313.415 305.996 313.725 305.71 314.08C305.575 314.286 305.451 314.5 305.34 314.72C305.057 315.424 304.56 316.022 303.92 316.43L303.59 316.59C303.676 316.791 303.794 316.977 303.94 317.14L305.58 319.02L303.3 318.84C303.22 318.97 303.12 319.17 303.05 319.31C302.923 319.617 302.762 319.909 302.57 320.18C302.371 320.448 302.139 320.69 301.88 320.9C301.776 320.978 301.679 321.065 301.59 321.16C301.268 321.569 301.049 322.049 300.95 322.56C300.51 324.93 300.51 327.36 300.95 329.73L301.1 330.95C301.296 332.346 301.296 333.764 301.1 335.16C300.899 336.714 300.13 338.139 298.94 339.16C298.083 339.814 297.016 340.134 295.94 340.06H295.88ZM301.94 315.21C302.208 314.953 302.529 314.759 302.88 314.64C303.139 314.398 303.341 314.1 303.47 313.77C303.62 313.474 303.787 313.187 303.97 312.91C304.363 312.393 304.832 311.938 305.36 311.56C305.781 311.275 306.145 310.911 306.43 310.49C306.96 309.49 306.43 308.05 305.79 306.78L305.52 306.23L306.95 304.23L307.15 303.95C306.717 303.827 306.303 303.645 305.92 303.41C305.68 303.26 305.45 303.08 305.23 302.91C305.01 302.74 304.9 302.65 304.72 302.53C304.241 302.272 303.73 302.08 303.2 301.96C301.713 301.445 300.143 301.211 298.57 301.27C297.64 301.419 296.728 301.668 295.85 302.01L292.76 303.09C291.724 303.411 290.72 303.826 289.76 304.33C289.29 304.61 288.84 304.93 288.39 305.24C287.864 305.628 287.317 305.985 286.75 306.31C286.128 306.645 285.487 306.942 284.83 307.2C283.986 307.511 283.183 307.924 282.44 308.43L282.36 308.49C282.42 308.54 282.5 308.63 282.64 308.75C283.03 309.017 283.32 309.408 283.461 309.86C283.602 310.312 283.588 310.798 283.42 311.24C283.332 311.433 283.194 311.598 283.02 311.72C283.042 311.846 283.075 311.97 283.12 312.09C284.123 315.232 284.23 318.591 283.43 321.79C283.43 321.91 283.35 322.09 283.34 322.11C283.395 322.178 283.455 322.242 283.52 322.3C284.875 323.531 286.444 324.504 288.15 325.17L289.01 325.49C289.939 325.779 290.83 326.182 291.66 326.69C293.366 327.975 294.684 329.705 295.47 331.69C295.953 332.673 296.29 333.72 296.47 334.8C296.512 335.391 296.481 335.986 296.38 336.57C296.32 337.05 296.22 337.85 296.19 337.96C296.706 337.966 297.208 337.801 297.62 337.49C298.396 336.781 298.89 335.815 299.01 334.77C299.181 333.563 299.181 332.337 299.01 331.13L298.86 329.94C298.365 327.316 298.365 324.624 298.86 322C299.032 321.15 299.425 320.36 300 319.71C300.139 319.566 300.286 319.429 300.44 319.3C300.574 319.199 300.695 319.081 300.8 318.95C300.92 318.771 301.02 318.58 301.1 318.38C301.254 318.048 301.442 317.733 301.66 317.44C301.478 317.083 301.407 316.68 301.457 316.282C301.507 315.884 301.675 315.511 301.94 315.21Z\" fill=\"#4880AA\"\/>\n<path id=\"Vector5656231 7\" d=\"M308.25 303.42V303.16C308.255 302.945 308.176 302.737 308.03 302.58C307.96 302.51 307.89 302.46 307.83 302.47H305.94L310.14 296.12L310.94 296.48C311.18 296.57 311.73 296.57 312.94 295.31C313.191 295.099 313.39 294.832 313.52 294.53C313.536 294.449 313.532 294.364 313.51 294.285C313.487 294.205 313.446 294.131 313.39 294.07C313.186 293.828 312.895 293.674 312.58 293.64C312.04 293.664 311.507 293.772 311 293.96C310.573 294.098 310.139 294.211 309.7 294.3L306.33 294.89L308.77 292.58C308.841 292.462 308.883 292.329 308.891 292.191C308.9 292.054 308.876 291.916 308.82 291.79C308.614 291.367 308.308 291 307.93 290.72C307.193 290.093 306.396 289.54 305.55 289.07C305.025 288.837 304.61 288.411 304.39 287.88C304.297 287.555 304.26 287.217 304.28 286.88C304.28 286.64 303.93 286.44 303.64 286.37C303.383 286.316 303.122 286.283 302.86 286.27C302.399 286.248 301.943 286.171 301.5 286.04C300.222 285.506 299.138 284.596 298.39 283.43L296.53 281.03C296.241 280.687 296.076 280.258 296.06 279.81C296.095 279.36 296.291 278.938 296.61 278.62L299.61 275.17C301.46 273.07 303.32 271.17 305.84 270.77C306.771 270.633 307.722 270.722 308.611 271.03C309.501 271.338 310.303 271.856 310.95 272.54L311.25 272.86L311.08 275.49C311.388 275.646 311.725 275.735 312.07 275.751C312.415 275.766 312.759 275.708 313.08 275.58C313.21 275.483 313.319 275.36 313.4 275.219C313.481 275.078 313.532 274.922 313.55 274.76C313.577 274.626 313.552 274.486 313.48 274.37L310.39 271.25L314.12 272.62C314.038 272.336 313.906 272.068 313.73 271.83L313.47 271.4C313.202 270.994 313.054 270.52 313.043 270.034C313.032 269.547 313.16 269.067 313.41 268.65L313.75 268.2L314.32 268.26C316.508 268.42 318.673 268.808 320.78 269.42C321.801 269.777 322.802 270.187 323.78 270.65C325.78 271.54 327.67 272.39 329.62 272.26H330.28C331.53 272.14 333.2 271.98 334.28 273.13C337.42 273.53 340.505 274.278 343.48 275.36L343.78 275.47L343.96 275.72C345.844 278.21 347.459 280.891 348.78 283.72L349.18 284.59L348.35 285L347.75 285.31C347.446 285.54 347.109 285.722 346.75 285.85C346.005 286.073 345.207 286.045 344.48 285.77C343.444 285.434 342.46 284.953 341.56 284.34L341.25 284.12C340.61 283.67 339.94 283.2 339.5 283.33C339.174 283.471 338.878 283.675 338.63 283.93L338.37 284.16C337.734 284.669 337.066 285.137 336.37 285.56C335.215 286.152 334.226 287.021 333.49 288.09C333.38 288.29 333.29 288.49 333.2 288.7C333.11 288.91 332.97 289.19 332.84 289.42C332.47 290.051 332.031 290.638 331.53 291.17L326.1 297.43C325.492 298.241 324.701 298.895 323.79 299.34C323.647 299.399 323.5 299.449 323.35 299.49C323.185 299.534 323.026 299.601 322.88 299.69C322.749 299.856 322.644 300.042 322.57 300.24C322.441 300.599 322.259 300.936 322.03 301.24C321.03 302.46 319.43 302.24 318.28 302.07C316.345 301.805 314.374 302.061 312.57 302.81C311.886 303.46 311.08 303.97 310.2 304.31C309.948 304.405 309.691 304.485 309.43 304.55L308 305L308.25 303.42ZM342.49 282.42L342.78 282.62C343.502 283.118 344.294 283.505 345.13 283.77C345.444 283.909 345.793 283.947 346.13 283.88C346.308 283.801 346.476 283.7 346.63 283.58C345.501 281.285 344.162 279.099 342.63 277.05C339.765 276.026 336.792 275.331 333.77 274.98L333.29 274.93L333.01 274.53C332.66 274.01 331.83 274.05 330.59 274.17L329.87 274.23C327.41 274.39 325.18 273.39 323.03 272.44C322.111 272.003 321.17 271.616 320.21 271.28C318.583 270.771 316.907 270.436 315.21 270.28C315.21 270.33 315.26 270.39 315.3 270.45L315.51 270.79C315.848 271.273 316.08 271.821 316.19 272.4C316.23 272.722 316.198 273.049 316.096 273.357C315.994 273.665 315.825 273.946 315.6 274.18C315.635 274.449 315.635 274.721 315.6 274.99C315.55 275.446 315.398 275.884 315.155 276.274C314.913 276.663 314.587 276.993 314.2 277.24C313.605 277.53 312.952 277.681 312.29 277.681C311.628 277.681 310.975 277.53 310.38 277.24C309.907 277.091 309.509 276.765 309.27 276.33C309.123 275.997 309.064 275.632 309.1 275.27L309.2 273.5C308.79 273.152 308.31 272.895 307.793 272.747C307.275 272.599 306.732 272.562 306.2 272.64C304.35 272.93 302.77 274.58 301.2 276.4L298.2 279.83L300.02 282.18C300.507 282.974 301.198 283.623 302.02 284.06C302.319 284.131 302.623 284.178 302.93 284.2C303.294 284.219 303.655 284.269 304.01 284.35C304.581 284.455 305.105 284.734 305.509 285.15C305.914 285.566 306.18 286.097 306.27 286.67C306.301 286.815 306.301 286.965 306.27 287.11L306.52 287.26C307.492 287.799 308.407 288.435 309.25 289.16C309.892 289.658 310.401 290.307 310.73 291.05C310.822 291.291 310.883 291.543 310.91 291.8C311.458 291.636 312.028 291.558 312.6 291.57C313.064 291.598 313.518 291.723 313.931 291.937C314.344 292.15 314.708 292.448 315 292.81C315.246 293.108 315.421 293.459 315.509 293.835C315.598 294.212 315.598 294.603 315.51 294.98C315.312 295.629 314.938 296.21 314.43 296.66C313.87 297.22 312.54 298.57 310.98 298.47L309.3 301.02C309.358 301.065 309.412 301.115 309.46 301.17C309.696 301.408 309.889 301.686 310.03 301.99C310.506 301.736 310.944 301.416 311.33 301.04L311.64 300.82C313.866 299.863 316.313 299.541 318.71 299.89C319.6 300.01 320.24 300.07 320.52 299.74C320.63 299.578 320.721 299.403 320.79 299.22C320.96 298.774 321.223 298.368 321.56 298.03C321.909 297.737 322.319 297.525 322.76 297.41L323.06 297.31C323.674 296.961 324.209 296.487 324.63 295.92L330.08 289.66C330.484 289.228 330.843 288.756 331.15 288.25C331.25 288.06 331.35 287.86 331.44 287.65C331.53 287.44 331.67 287.16 331.8 286.92C332.674 285.562 333.888 284.456 335.32 283.71C335.943 283.333 336.541 282.915 337.11 282.46L337.34 282.26C337.797 281.798 338.36 281.455 338.98 281.26C339.358 281.171 339.752 281.171 340.13 281.26C340.992 281.454 341.799 281.84 342.49 282.39V282.42Z\" fill=\"#4880AA\"\/>\n<path id=\"Vector5656231 8\" d=\"M289.19 270.15C288.8 269.82 288.42 269.49 288.03 269.21C287.64 268.93 287.17 268.63 286.73 268.35C285.425 267.679 284.305 266.697 283.47 265.49L282.99 264.7L283.75 264.19C287.743 261.516 292.158 259.535 296.81 258.33L297.07 258.26L297.33 258.33C299.66 258.91 311.39 261.86 314.06 263.26L316.27 264.42L313.9 265.06C312.664 265.401 311.408 265.665 310.14 265.85C309.55 265.94 308.96 266.01 308.36 266.08C306.535 266.194 304.737 266.585 303.03 267.24L302.77 267.36C302.228 267.645 301.638 267.828 301.03 267.9C300.784 267.92 300.536 267.92 300.29 267.9C300.111 267.868 299.929 267.868 299.75 267.9C299.43 268 299.2 268.56 298.97 269.11C298.849 269.41 298.712 269.704 298.56 269.99C298.173 270.622 297.655 271.164 297.041 271.58C296.427 271.996 295.731 272.275 295 272.4C294.415 272.55 293.806 272.577 293.21 272.48C291.683 272.083 290.293 271.278 289.19 270.15ZM309.78 263.9H310.11C306.87 262.9 301.83 261.51 297.11 260.35C293.107 261.415 289.29 263.084 285.79 265.3C286.403 265.85 287.074 266.333 287.79 266.74C288.28 267.05 288.79 267.35 289.22 267.69C289.65 268.03 290.07 268.37 290.5 268.69C292.06 270.02 293.1 270.81 294.38 270.49C294.854 270.427 295.308 270.262 295.712 270.006C296.116 269.751 296.46 269.411 296.72 269.01C296.842 268.791 296.949 268.564 297.04 268.33C297.18 267.822 297.432 267.353 297.778 266.956C298.125 266.56 298.556 266.247 299.04 266.04C299.477 265.909 299.937 265.871 300.39 265.93C300.906 265.995 301.428 265.871 301.86 265.58L302.15 265.45C304.042 264.713 306.034 264.267 308.06 264.13C308.64 264.07 309.21 264 309.79 263.91L309.78 263.9Z\" fill=\"#4880AA\"\/>\n<path id=\"Vector5656231 9\" d=\"M309.49 302.83H310.18C309.746 302.833 309.317 302.924 308.919 303.095C308.52 303.267 308.16 303.517 307.86 303.83C307.621 304.091 307.401 304.369 307.2 304.66C306.84 305.16 306.48 305.66 306.11 306.17C306.84 307.68 307.58 309.54 306.77 311.03C306.16 312.17 304.86 312.63 304.13 313.68C303.62 314.4 303.36 315.42 302.62 315.82C302.359 315.911 302.115 316.047 301.9 316.22C301.39 316.75 301.9 317.66 302.35 318.22C301.56 318.16 301.35 319.4 300.84 320.09C300.547 320.413 300.233 320.717 299.9 321C299.427 321.556 299.104 322.224 298.96 322.94C298.21 325.94 298.78 329.08 299.14 332.15C299.33 333.52 299.33 334.91 299.14 336.28C298.966 337.645 298.301 338.899 297.27 339.81C296.63 340.32 294.79 341.04 294.27 340.08C293.82 339.32 294.45 337.23 294.32 336.26C294.135 335.217 293.798 334.206 293.32 333.26C292.58 331.357 291.331 329.693 289.71 328.45C288.602 327.833 287.432 327.334 286.22 326.96C284.302 326.203 282.537 325.105 281.01 323.72C280.775 323.538 280.597 323.291 280.5 323.01C280.456 322.704 280.487 322.392 280.59 322.1C281.38 318.94 281.273 315.622 280.28 312.52C280.119 312.175 280.094 311.782 280.21 311.42C280.33 311.2 280.54 311.06 280.65 310.84C280.89 310.36 280.49 309.84 280.11 309.5C279.73 309.16 279.28 308.74 279.39 308.21C279.483 307.916 279.678 307.664 279.94 307.5C281.36 306.44 283.08 306.04 284.6 305.19C285.69 304.58 286.67 303.75 287.75 303.12C288.807 302.554 289.916 302.089 291.06 301.73L294.29 300.6C295.287 300.213 296.323 299.935 297.38 299.77C299.176 299.684 300.971 299.942 302.67 300.53C303.332 300.682 303.968 300.928 304.56 301.26C305 301.54 305.39 301.91 305.83 302.18C306.726 302.678 307.747 302.907 308.77 302.84C308.775 302.903 308.775 302.967 308.77 303.03C309.015 302.985 309.256 302.918 309.49 302.83Z\" fill=\"#C7D14A\"\/>\n<path id=\"Vector5656231 10\" d=\"M347.91 283.49C347.343 283.639 346.743 283.6 346.2 283.38C345.213 283.073 344.279 282.618 343.43 282.03C342.48 281.38 341.43 280.52 340.36 280.81C339.764 281.052 339.226 281.416 338.78 281.88C337 283.39 334.62 284.18 333.44 286.3C333.18 286.75 333 287.24 332.75 287.7C332.391 288.295 331.972 288.851 331.5 289.36L325.78 295.93C325.253 296.651 324.569 297.242 323.78 297.66C323.329 297.771 322.901 297.964 322.52 298.23C322.04 298.66 321.93 299.42 321.52 299.92C320.82 300.78 319.59 300.58 318.52 300.43C316.227 300.113 313.891 300.434 311.77 301.36C311.124 302.003 310.351 302.504 309.5 302.83C309.277 302.923 309.046 302.996 308.81 303.05C308.815 302.987 308.815 302.923 308.81 302.86C308.836 302.415 308.693 301.977 308.409 301.634C308.125 301.29 307.722 301.067 307.28 301.01C308.23 299.57 309.18 298.14 310.12 296.7C311.29 297.23 312.53 296.2 313.47 295.26C313.868 294.914 314.168 294.469 314.34 293.97C314.63 292.79 313.43 291.75 312.34 291.7C311.228 291.82 310.132 292.058 309.07 292.41C309.309 292.142 309.464 291.81 309.517 291.455C309.571 291.099 309.52 290.737 309.37 290.41C309.093 289.797 308.667 289.264 308.13 288.86C307.301 288.145 306.399 287.518 305.44 286.99C305.134 286.859 304.883 286.626 304.73 286.33C304.68 286.066 304.66 285.798 304.67 285.53C304.602 285.155 304.42 284.81 304.147 284.543C303.875 284.276 303.527 284.1 303.15 284.04C302.43 283.87 301.68 283.93 300.97 283.71C299.851 283.212 298.907 282.39 298.26 281.35L296.26 278.83C296.103 278.664 296.008 278.448 295.99 278.22C296.019 277.982 296.132 277.762 296.31 277.6L299.49 273.98C301.17 272.07 303.03 270.05 305.41 269.69C306.212 269.575 307.031 269.654 307.796 269.92C308.562 270.186 309.252 270.632 309.81 271.22C309.81 272 309.72 272.78 309.68 273.57C309.653 273.769 309.677 273.973 309.75 274.16C309.877 274.37 310.082 274.521 310.32 274.58C310.8 274.807 311.324 274.925 311.855 274.925C312.386 274.925 312.91 274.807 313.39 274.58C313.628 274.439 313.834 274.25 313.995 274.025C314.157 273.8 314.27 273.545 314.327 273.274C314.384 273.003 314.385 272.724 314.329 272.453C314.272 272.182 314.16 271.925 314 271.7C314.55 271.91 315.06 271.14 315 270.5C314.835 269.893 314.557 269.323 314.18 268.82C313.998 268.559 313.891 268.254 313.87 267.937C313.849 267.62 313.915 267.303 314.06 267.02C316.282 267.178 318.481 267.57 320.62 268.19C323.87 269.27 326.95 271.45 330.34 271.24C331.86 271.14 333.72 270.7 334.63 272.03C338 272.42 341.313 273.205 344.5 274.37C346.432 276.914 348.088 279.656 349.44 282.55C349.276 282.613 349.115 282.687 348.96 282.77C348.637 283.047 348.285 283.288 347.91 283.49Z\" fill=\"#C7D14A\"\/>\n<path id=\"Vector5656231 11\" d=\"M310.2 263.82C307.6 264.2 304.9 264.28 302.45 265.36C301.907 265.657 301.319 265.863 300.71 265.97C300.172 265.9 299.628 265.9 299.09 265.97C298.03 266.33 297.79 267.72 297.27 268.63C296.925 269.167 296.469 269.623 295.933 269.968C295.396 270.313 294.791 270.539 294.16 270.63C291.58 271.28 289.73 268.88 287.8 267.46C286.25 266.32 284.29 265.53 283.29 263.87C287.392 261.133 291.925 259.104 296.7 257.87C302.26 259.26 311.78 261.78 314.02 262.96C312.766 263.327 311.49 263.615 310.2 263.82Z\" fill=\"#C7D14A\"\/>\n<\/g>\n<g id=\"Vector5656231 12\" style=\"mix-blend-mode:multiply\" opacity=\"0.5\">\n<g id=\"Vector\" style=\"mix-blend-mode:multiply\" opacity=\"0.5\">\n<g id=\"Vector_2\" style=\"mix-blend-mode:multiply\" opacity=\"0.5\">\n<path d=\"M299.8 339.4C309.186 339.409 318.367 336.652 326.196 331.473C334.024 326.294 340.153 318.924 343.817 310.282C347.481 301.64 348.517 292.11 346.796 282.883C345.075 273.656 340.673 265.14 334.14 258.4C339.6 262.201 344.207 267.1 347.664 272.784C351.121 278.467 353.353 284.811 354.216 291.407C355.08 298.004 354.556 304.708 352.678 311.09C350.801 317.472 347.611 323.392 343.313 328.47C339.015 333.548 333.703 337.672 327.719 340.578C321.734 343.485 315.209 345.109 308.561 345.347C301.912 345.585 295.287 344.432 289.11 341.962C282.933 339.491 277.34 335.757 272.69 331C280.663 336.49 290.12 339.421 299.8 339.4Z\" fill=\"#2E90B7\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 13\" style=\"mix-blend-mode:multiply\" opacity=\"0.5\">\n<g id=\"Vector_2_2\" style=\"mix-blend-mode:multiply\" opacity=\"0.5\">\n<g id=\"Vector_3\" style=\"mix-blend-mode:multiply\" opacity=\"0.5\">\n<path d=\"M306.16 343.79C314.217 343.79 322.142 341.752 329.2 337.866C336.257 333.98 342.217 328.372 346.525 321.564C350.833 314.756 353.35 306.969 353.84 298.928C354.33 290.886 352.779 282.851 349.33 275.57C354.67 285.713 356.183 297.439 353.594 308.605C351.005 319.772 344.487 329.635 335.228 336.394C325.97 343.152 314.589 346.356 303.165 345.419C291.74 344.482 281.034 339.467 273 331.29L273.67 331.04C282.493 339.253 294.106 343.81 306.16 343.79Z\" fill=\"#2E90B7\"\/>\n<\/g>\n<\/g>\n<\/g>\n<path id=\"Vector5656231 14\" d=\"M307 250C316.166 249.989 325.139 252.629 332.84 257.6C322.077 251.229 309.245 249.333 297.1 252.32C284.954 255.307 274.465 262.937 267.884 273.573C261.303 284.209 259.156 297.002 261.904 309.203C264.652 321.405 272.075 332.042 282.58 338.83C273.586 333.482 266.597 325.329 262.686 315.624C258.775 305.918 258.159 295.197 260.933 285.107C263.707 275.018 269.716 266.118 278.039 259.776C286.361 253.433 296.536 249.999 307 250Z\" fill=\"#77D1ED\"\/>\n<path id=\"Vector5656231 15\" d=\"M339.71 363.79H319.25C314.66 363.79 314.66 373.63 319.25 373.63H339.71V363.79Z\" fill=\"#EAC5A2\"\/>\n<path id=\"Vector5656231 16\" d=\"M336.16 365.68H320.66C317.18 365.68 317.18 371.97 320.66 371.97H336.16V365.68Z\" fill=\"#FFEBD4\"\/>\n<path id=\"Vector5656231 17\" d=\"M320.8 372.55H336.31C339.79 372.55 337.91 365.03 334.43 365.03H318.92L320.8 372.55Z\" fill=\"#EAC5A2\"\/>\n<path id=\"Vector5656231 18\" d=\"M320 373.31C315.4 373.31 315.4 364.24 320 364.24H341.15V362.82H317C311.89 362.82 311.89 374.59 317 374.59H341.1V373.31H320Z\" fill=\"#9B902C\"\/>\n<path id=\"Vector5656231 19\" d=\"M317.45 362.9V362.82H257.65C253.15 362.82 253.15 374.57 257.65 374.57H317.45V374.5C313.67 373.65 313.67 363.77 317.45 362.9Z\" fill=\"#C4C439\"\/>\n<path id=\"Vector5656231 20\" d=\"M315.4 372.62H255.06C255.252 373.168 255.599 373.649 256.058 374.004C256.518 374.359 257.071 374.573 257.65 374.62H317.45V374.55C316.983 374.408 316.555 374.16 316.199 373.825C315.843 373.49 315.57 373.078 315.4 372.62Z\" fill=\"#B5B133\"\/>\n<path id=\"Vector5656231 21\" d=\"M329.75 375.27H318.51C312.78 375.27 312.78 389.43 318.51 389.43H329.75V375.27Z\" fill=\"#EAC5A2\"\/>\n<path id=\"Vector5656231 22\" d=\"M332.93 377.35H321.69C315.96 377.35 316.4 387.98 322.12 387.98H333.36L332.93 377.35Z\" fill=\"#FFEBD4\"\/>\n<path id=\"Vector5656231 23\" d=\"M324.18 388.63H335.43C341.15 388.63 338.55 376.7 332.82 376.7H321.58L324.18 388.63Z\" fill=\"#EAC5A2\"\/>\n<path id=\"Vector5656231 24\" d=\"M318.71 383.46L326.56 383.97L336.2 383.46H318.71Z\" fill=\"#EAC5A2\"\/>\n<path id=\"Vector5656231 25\" d=\"M319.39 389C313.67 389 313.67 375.94 319.39 375.94H333V373.94H315.71C309.35 373.94 309.35 390.88 315.71 390.88H333V389H319.39Z\" fill=\"#FF9945\"\/>\n<path id=\"Vector5656231 26\" d=\"M316.26 374V373.89H241.72C236.12 373.89 236.12 390.79 241.72 390.79H316.27V390.69C310.84 390.7 310.84 374 316.26 374Z\" fill=\"#FFB255\"\/>\n<path id=\"Vector5656231 27\" d=\"M302 373.88H241.68C236.08 373.88 236.08 390.78 241.68 390.78H265.29C269.82 382.75 284.29 375.75 302 373.88Z\" fill=\"#FFC05A\"\/>\n<path id=\"Vector5656231 28\" d=\"M314.19 389.68H239.49C239.753 390.021 240.089 390.298 240.473 390.492C240.857 390.686 241.28 390.791 241.71 390.8H316.26V390.7C315.862 390.691 315.47 390.595 315.112 390.419C314.755 390.242 314.44 389.99 314.19 389.68Z\" fill=\"#FFB048\"\/>\n<path id=\"Vector5656231 29\" d=\"M339.07 392.26H283.68C277.83 392.26 277.83 407.12 283.68 407.12H339.07V392.26Z\" fill=\"#EAC5A2\"\/>\n<path id=\"Vector5656231 30\" d=\"M339.07 395.18H288C282.6 395.18 282.6 405.66 288 405.66H339.09L339.07 395.18Z\" fill=\"#FFEBD4\"\/>\n<path id=\"Vector5656231 31\" d=\"M338.44 392.82H322.39L325.57 406.9H341.63L338.44 392.82Z\" fill=\"#EAC5A2\"\/>\n<path id=\"Vector5656231 32\" d=\"M284.12 390.7H245.42C238.91 390.7 238.91 408.48 245.42 408.48H284.12C277.08 402.44 278 396.53 284.12 390.7Z\" fill=\"#EB6D79\"\/>\n<path id=\"Vector5656231 33\" d=\"M282.59 407H242.59C242.918 407.438 243.341 407.796 243.828 408.046C244.315 408.295 244.853 408.43 245.4 408.44H284.1C283.553 407.987 283.05 407.507 282.59 407Z\" fill=\"#EA3F50\"\/>\n<path id=\"Vector5656231 34\" d=\"M284.94 406.54C279.09 406.54 279.09 392.84 284.94 392.84H343.86V390.7H282.27C275.76 390.7 275.76 408.48 282.27 408.48H343.86V406.54H284.94Z\" fill=\"#B5535E\"\/>\n<path id=\"Vector5656231 35\" d=\"M347.17 351.75H320.06L333.67 407.92H360.79L347.17 351.75Z\" fill=\"#AF37AF\"\/>\n<path id=\"Vector5656231 36\" d=\"M346.27 352.31H319.16L332.77 408.48H359.88L360.76 407.92L346.27 352.31Z\" fill=\"#4988AB\"\/>\n<path id=\"Vector5656231 37\" d=\"M347.9 351.39H320.79L334.4 407.56H358.93L366.86 403.49L347.9 351.39Z\" fill=\"#EAC5A2\"\/>\n<path id=\"Vector5656231 38\" d=\"M354.96 348.13H327.84L340.96 404.29H367.69L368.77 403.66L354.96 348.13Z\" fill=\"#4988AB\"\/>\n<path id=\"Vector5656231 39\" d=\"M329.09 347.77C325.09 348.53 322.17 349.6 320.17 351.94L333.8 408.31C336.016 406.023 338.928 404.536 342.08 404.08L342.56 400.97L329.09 347.77Z\" fill=\"#4988AB\"\/>\n<path id=\"Vector5656231 40\" d=\"M328 347.49C324 348.25 321 349.77 319 352.11L332.63 408.48C335.006 405.912 338.175 404.215 341.63 403.66L341.43 401.14L328 347.49Z\" fill=\"#5198BF\"\/>\n<path id=\"Vector5656231 41\" d=\"M355.16 347.49H328.04L341.65 403.66H368.77L355.16 347.49Z\" fill=\"#5198BF\"\/>\n<path id=\"Vector5656231 42\" d=\"M355.16 347.49H328.04L354.1 349.48L368.77 403.66L355.16 347.49Z\" fill=\"#4988AB\"\/>\n<g id=\"Group 2\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector5656231 43\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_3_2\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_4\" style=\"mix-blend-mode:overlay\">\n<path d=\"M367.73 402.77H342.12L342.07 402.55L329.25 349.16H354.86L354.91 349.38L367.73 402.77ZM342.58 402.19H367L354.4 349.74H330L342.58 402.19Z\" fill=\"#5B6E9B\"\/>\n<\/g>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Group 3\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector5656231 44\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_4_2\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_5\" style=\"mix-blend-mode:overlay\">\n<path d=\"M323.28 363.22L321 353.93L321.09 353.82C321.713 353.005 322.501 352.33 323.402 351.839C324.303 351.348 325.297 351.052 326.32 350.97H326.57L329.04 360.97H328.72C326.868 361.153 325.103 361.845 323.62 362.97L323.28 363.22ZM321.64 354.07L323.64 362.2C325.047 361.251 326.656 360.644 328.34 360.43L326.15 351.57C324.375 351.775 322.754 352.674 321.64 354.07Z\" fill=\"#5B6E9B\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 45\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_5_2\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_6\" style=\"mix-blend-mode:overlay\">\n<path d=\"M333.11 403.47L329.11 387L329.2 386.89C329.875 386.113 330.721 385.503 331.672 385.109C332.623 384.715 333.653 384.548 334.68 384.62H334.94L338.88 400.53H338.56C336.12 400.81 334.56 401.53 333.5 402.94L333.11 403.47ZM329.72 387.15L333.39 402.15C334.669 400.889 336.358 400.13 338.15 400.01L334.47 385.17C333.582 385.133 332.696 385.291 331.875 385.633C331.054 385.975 330.319 386.493 329.72 387.15Z\" fill=\"#5B6E9B\"\/>\n<\/g>\n<\/g>\n<\/g>\n<\/g>\n<path id=\"Vector5656231 46\" d=\"M309.46 389.27H243.25L243.16 389.17C241.16 386.67 241.16 378 243.16 375.52L243.25 375.41H309.42V375.98L309.23 376.06C308.67 376.3 308.08 378.41 308.05 381.99C308.05 385.77 308.64 388.39 309.24 388.65L309.41 388.73L309.46 389.27ZM243.53 388.7H308.53C307.53 387.11 307.53 382.56 307.53 381.98C307.53 380.8 307.64 377.32 308.53 375.98H243.53C241.76 378.38 241.75 386.29 243.53 388.7Z\" fill=\"#FFE3BB\"\/>\n<path id=\"Vector5656231 47\" d=\"M291.59 401.47L303.38 401.97L317.84 401.47H291.59Z\" fill=\"#EAC5A2\"\/>\n<path id=\"Vector5656231 48\" d=\"M301.93 397.35L313.72 397.85L328.18 397.35H301.93Z\" fill=\"#EAC5A2\"\/>\n<g id=\"Group 4\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector5656231 49\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_6_2\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_7\" style=\"mix-blend-mode:overlay\">\n<path d=\"M277.68 407.83H246.82C243.75 407.83 242.35 403.56 242.35 399.59C242.35 395.62 243.75 391.35 246.82 391.35H277.82V391.93C275.82 392.24 274.82 396.58 274.97 400.6C275.09 404.45 276.16 407.12 277.62 407.26L277.68 407.83ZM246.82 391.93C244.27 391.93 242.93 395.78 242.93 399.59C242.93 403.4 244.27 407.26 246.82 407.26H276.41C275.12 406.06 274.56 403.26 274.47 400.62C274.35 397.07 275.08 393.35 276.66 391.93H246.82Z\" fill=\"#FFEBD4\"\/>\n<\/g>\n<\/g>\n<\/g>\n<\/g>\n<path id=\"Vector5656231 50\" d=\"M279.06 365C292.36 365 303.99 364.13 310.37 362.82H257.65C257.241 362.828 256.839 362.934 256.479 363.129C256.119 363.324 255.811 363.602 255.58 363.94C261.92 364.61 270.11 365 279.06 365Z\" fill=\"#DBD749\"\/>\n<g id=\"Group 5\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector5656231 51\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_7_2\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_8\" style=\"mix-blend-mode:overlay\">\n<path d=\"M336.88 367.56C336.88 367.73 336.96 367.8 337 367.96L337.23 368.8C337.23 368.92 337.23 369.05 337.31 369.16C337.39 369.27 337.31 369.28 337.31 369.34H338.54H339.09H339.47C339.53 369.34 339.54 369.34 339.56 369.45C339.58 369.56 339.56 369.59 339.56 369.67C339.56 369.75 339.56 369.76 339.46 369.76H339.35C339.137 369.747 338.923 369.747 338.71 369.76H337.2C337.164 369.766 337.128 369.758 337.098 369.737C337.068 369.717 337.047 369.685 337.04 369.65C337.04 369.65 337.04 369.58 337.04 369.54C337.04 369.5 337.04 369.54 337.04 369.47C337.04 369.4 337.04 369.38 336.92 369.07C336.8 368.76 336.64 368.07 336.52 367.61C336.4 367.15 336.26 366.43 336.18 366.14C336.1 365.85 335.97 365.32 335.89 365.06C335.81 364.8 336.13 364.91 336.31 364.91C336.49 364.91 336.96 364.91 337.31 364.91H338.31C338.44 364.91 338.44 365.03 338.46 365.1V365.18C338.46 365.25 338.51 365.34 338.46 365.34C338.41 365.34 338.38 365.34 338.27 365.34H336.7H336.44H336.31V365.53C336.31 365.64 336.31 365.76 336.39 365.87C336.47 365.98 336.51 366.25 336.55 366.41L336.62 366.7C336.637 366.758 336.657 366.814 336.68 366.87H337.07C337.17 366.87 337.28 366.87 337.46 366.87C337.64 366.87 337.85 366.87 337.92 366.87H338.22H338.63H338.75C338.773 366.872 338.795 366.882 338.811 366.899C338.828 366.915 338.838 366.937 338.84 366.96C338.84 366.96 338.89 367.16 338.89 367.21C338.89 367.26 338.89 367.29 338.83 367.29C338.77 367.29 338.23 367.21 338 367.21C337.77 367.21 337.51 367.21 337.28 367.21C337.167 367.225 337.053 367.225 336.94 367.21H336.78V367.33C336.84 367.4 336.86 367.48 336.88 367.56Z\" fill=\"#FFEBD4\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 52\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_8_2\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_9\" style=\"mix-blend-mode:overlay\">\n<path d=\"M340.61 364.83C340.56 364.62 340.74 364.63 340.86 364.63C341.068 364.627 341.275 364.61 341.48 364.58C341.64 364.58 341.67 364.68 341.71 364.9C341.75 365.12 341.89 365.64 342.06 366.31L342.47 367.91C342.63 368.51 343.05 370 342.97 369.68C342.97 369.77 342.97 369.8 342.91 369.8H342.74H342.3C342.14 369.8 342.07 369.72 341.95 369.54C341.83 369.36 341.56 368.91 341.29 368.54C341.16 368.37 340.91 368 340.68 367.68L340.28 367.1L340.35 367.37L340.47 367.86C340.56 368.18 340.87 369.35 340.94 369.54C340.946 369.57 340.946 369.6 340.94 369.63C340.94 369.73 340.94 369.73 340.86 369.73H340.41C340.3 369.73 340.27 369.73 340.21 369.47C340.15 369.21 339.87 368.26 339.63 367.4C339.48 366.8 339.3 366.01 339.17 365.49L339.03 365.01C339.007 364.958 338.987 364.904 338.97 364.85C338.92 364.65 338.97 364.62 339.07 364.63C339.179 364.656 339.291 364.656 339.4 364.63H339.52C339.59 364.63 339.63 364.63 339.8 364.63C339.97 364.63 340.26 365.02 340.43 365.24C340.51 365.358 340.597 365.472 340.69 365.58L340.82 365.74L340.72 365.35C340.69 365.17 340.63 364.93 340.61 364.83Z\" fill=\"#FFEBD4\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 53\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_9_2\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_10\" style=\"mix-blend-mode:overlay\">\n<path d=\"M344.61 367.67C344.5 367.67 344.48 367.61 344.47 367.57C344.46 367.477 344.46 367.383 344.47 367.29C344.47 367.12 344.52 367.14 344.58 367.14C344.64 367.14 344.84 367.19 345.08 367.21C345.32 367.23 345.68 367.33 345.86 367.34C345.897 367.341 345.933 367.353 345.963 367.375C345.993 367.396 346.016 367.426 346.03 367.46C346.034 367.5 346.034 367.54 346.03 367.58C346.43 369.49 345.72 369.89 345.22 369.89C344.72 369.89 343.53 369.53 342.98 367.39C342.34 364.93 343.43 364.69 343.85 364.69C344.156 364.732 344.447 364.844 344.702 365.018C344.957 365.191 345.169 365.421 345.32 365.69C345.37 365.76 345.44 365.91 345.48 365.97C345.52 366.03 345.48 365.97 345.48 365.97C345.48 365.97 345.48 365.97 345.4 366.07L345.04 366.33L344.79 366.58C344.765 366.618 344.735 366.651 344.7 366.68C344.7 366.68 344.63 366.6 344.58 366.55C344.53 366.5 344.42 366.31 344.27 366.31C344.12 366.31 344.06 366.92 344.16 367.31C344.26 367.7 344.42 368.39 344.81 368.39C344.99 368.39 345.04 368.21 345.04 368.04C345.041 367.918 345.024 367.797 344.99 367.68H344.87L344.61 367.67Z\" fill=\"#FFEBD4\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 54\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_10_2\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_11\" style=\"mix-blend-mode:overlay\">\n<path d=\"M350.15 369.71C350.15 369.76 350.15 369.76 350.03 369.76H348.87H347.94H347.26C347.13 369.76 347.15 369.76 347.12 369.58C347.09 369.4 346.86 368.47 346.82 368.31C346.78 368.15 346.63 367.69 346.57 367.45C346.66 367.79 346.34 366.28 346.28 366.07L346.07 365.27L345.94 364.81C345.94 364.72 346.02 364.76 346.07 364.76H346.35C346.35 364.76 346.35 364.76 346.4 364.81C346.45 364.86 346.69 366.1 346.74 366.3L347 367.3C347 367.41 347.13 367.74 347.18 367.96C347.185 368.02 347.185 368.08 347.18 368.14C347.176 368.183 347.176 368.227 347.18 368.27H347.32H348.71H349.6C349.65 368.27 349.67 368.27 349.67 368.27C349.676 368.296 349.676 368.324 349.67 368.35L349.76 368.67C349.92 369 350.13 369.63 350.15 369.71Z\" fill=\"#FFEBD4\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 55\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_11_2\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_12\" style=\"mix-blend-mode:overlay\">\n<path d=\"M349.81 365.85C349.91 366.24 350.18 367.45 350.27 367.85C350.36 368.25 350.71 369.46 350.77 369.64C350.773 369.673 350.773 369.707 350.77 369.74C350.77 369.82 350.77 369.83 350.77 369.85C350.77 369.87 350.67 369.85 350.6 369.85C350.53 369.85 350.47 369.85 350.38 369.55C350.29 369.25 349.9 367.55 349.78 367.13C349.66 366.71 349.36 365.29 349.3 365.13C349.24 364.97 349.3 365.03 349.3 364.98C349.3 364.93 349.3 364.8 349.3 364.8H349.52C349.57 364.8 349.59 364.85 349.6 364.9C349.61 364.95 349.6 365.02 349.6 365.07C349.6 365.12 349.72 365.46 349.81 365.85Z\" fill=\"#FFEBD4\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 56\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_12_2\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_13\" style=\"mix-blend-mode:overlay\">\n<path d=\"M353 365.48V365.54C353 365.54 353 365.6 353 365.64C353 365.68 352.93 365.91 352.89 366C352.85 366.09 352.89 366.12 352.8 366.12C352.71 366.12 352.02 365.39 351.59 365.39C351.44 365.39 351.22 365.39 351.35 365.88C351.48 366.37 351.93 366.54 352.24 366.68C352.648 366.835 353.01 367.091 353.293 367.423C353.576 367.755 353.771 368.153 353.86 368.58C354.1 369.51 353.58 369.94 352.64 369.94C352.345 369.926 352.056 369.848 351.795 369.709C351.534 369.571 351.307 369.377 351.13 369.14C351.126 369.117 351.126 369.093 351.13 369.07C351.124 369.037 351.124 369.003 351.13 368.97C351.166 368.865 351.213 368.765 351.27 368.67C351.27 368.67 351.36 368.75 351.42 368.81C351.661 369.045 351.975 369.19 352.31 369.22C352.52 369.22 352.85 369.17 352.73 368.73C352.543 368.31 352.228 367.96 351.83 367.73C351.51 367.5 350.63 367.18 350.39 366.26C350.337 366.104 350.319 365.939 350.336 365.775C350.354 365.612 350.406 365.454 350.491 365.313C350.576 365.172 350.69 365.052 350.827 364.96C350.963 364.867 351.118 364.806 351.28 364.78C351.918 364.801 352.528 365.049 353 365.48Z\" fill=\"#FFEBD4\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 57\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_13_2\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_14\" style=\"mix-blend-mode:overlay\">\n<path d=\"M355.36 366.75H355.58H355.82H355.95V366.53L355.88 366.19C355.83 366.02 355.61 365.08 355.58 364.95C355.55 364.82 355.58 364.78 355.63 364.77C355.737 364.777 355.843 364.777 355.95 364.77H356.12H356.43C356.55 364.77 356.53 364.82 356.58 364.94C356.63 365.06 356.75 365.77 356.81 366C356.87 366.23 357.01 367 357.08 367.29C357.15 367.58 357.38 368.41 357.45 368.7C357.52 368.99 357.67 369.54 357.73 369.7C357.73 369.84 357.73 369.81 357.64 369.81H357.37C357.197 369.819 357.023 369.819 356.85 369.81C356.75 369.81 356.75 369.74 356.73 369.64C356.71 369.54 356.53 368.89 356.44 368.64C356.35 368.39 356.34 368.3 356.3 368.12C356.264 368.012 356.234 367.902 356.21 367.79H355.43L355.53 368.24C355.53 368.49 355.64 368.75 355.67 368.89C355.7 369.03 355.73 369.12 355.77 369.25C355.81 369.38 355.87 369.63 355.9 369.71C355.93 369.79 355.9 369.83 355.77 369.83H355.43C355.33 369.83 355.1 369.83 354.97 369.83C354.84 369.83 354.81 369.73 354.78 369.63L354.6 368.85C354.6 368.71 354.43 368.15 354.32 367.73C354.32 367.58 354.25 367.45 354.22 367.37C354.168 367.233 354.125 367.093 354.09 366.95C354.03 366.68 353.96 366.4 353.92 366.24C353.88 366.08 353.67 365.06 353.63 364.93C353.59 364.8 353.63 364.83 353.68 364.83H353.76C353.906 364.842 354.054 364.842 354.2 364.83H354.62C354.67 364.83 354.68 364.9 354.7 364.96C354.72 365.02 354.83 365.44 354.93 365.81C354.98 366.01 355.03 366.23 355.07 366.42L355.15 366.75H355.36Z\" fill=\"#FFEBD4\"\/>\n<\/g>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Group 6\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector5656231 58\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_14_2\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_15\" style=\"mix-blend-mode:overlay\">\n<path d=\"M338.52 375.55V375.4L338.17 374.13C338.09 373.78 337.97 373.31 337.91 373.13C337.85 372.95 337.72 372.46 337.68 372.32C337.64 372.18 337.63 372.11 337.68 372.11H338.12H338.56C338.67 372.11 338.86 372.11 339.34 372.51C339.747 372.904 340.023 373.414 340.13 373.97C340.271 374.446 340.225 374.957 340 375.4C339.735 375.59 339.416 375.692 339.09 375.69H338.66C338.53 375.64 338.51 375.59 338.52 375.55ZM338.66 373.48C338.74 373.79 338.84 374.05 338.89 374.28C338.94 374.51 339 374.68 339.06 374.94C339.12 375.2 339.14 375.26 339.19 375.44C339.367 375.463 339.546 375.416 339.69 375.31C339.91 375.15 340.08 374.75 339.87 373.92C339.769 373.344 339.446 372.83 338.97 372.49C338.796 372.38 338.596 372.317 338.39 372.31L338.5 372.78C338.55 373 338.63 373.33 338.66 373.48Z\" fill=\"#FFEBD4\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 59\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_15_2\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_16\" style=\"mix-blend-mode:overlay\">\n<path d=\"M340.05 372.19C340.05 372.02 340.05 371.99 340.05 371.99C340.12 371.99 340.26 371.99 340.39 371.99C340.52 371.99 340.49 371.99 340.5 372.07C340.51 372.15 340.5 372.14 340.5 372.18C340.54 372.487 340.6 372.791 340.68 373.09L340.78 373.5C340.88 373.87 340.97 374.2 340.99 374.29C341.01 374.38 341.12 374.71 341.16 374.9C341.166 374.94 341.166 374.98 341.16 375.02C341.155 375.06 341.155 375.1 341.16 375.14C341.16 375.28 341.26 375.5 341.28 375.58C341.3 375.66 341.28 375.68 341.18 375.67H340.79C340.7 375.67 340.67 375.6 340.65 375.51C340.63 375.42 340.65 375.25 340.56 375.07C340.47 374.89 340.33 373.98 340.3 373.84C340.27 373.7 340.09 372.99 340.06 372.84C340.03 372.69 340.06 372.66 340 372.56V372.37L340.05 372.19Z\" fill=\"#FFEBD4\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 60\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_16_2\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_17\" style=\"mix-blend-mode:overlay\">\n<path d=\"M343.65 375.05V375.11C343.626 375.276 343.543 375.428 343.416 375.538C343.29 375.648 343.128 375.709 342.96 375.71C342.4 375.71 341.66 374.89 341.38 373.81C341.1 372.73 341.43 372 341.91 372C342.076 372.009 342.239 372.052 342.387 372.128C342.535 372.204 342.666 372.31 342.77 372.44C342.806 372.469 342.834 372.507 342.85 372.55C342.85 372.55 342.85 372.6 342.85 372.63C342.775 372.733 342.711 372.843 342.66 372.96C342.66 373.03 342.6 373.09 342.56 373.09C342.52 373.09 342.56 373.09 342.48 373.09C342.4 373.09 342.28 372.87 342.17 372.87C342.06 372.87 341.78 373.14 342 373.99C342.22 374.84 342.64 374.99 342.76 374.99C342.88 374.99 342.97 374.84 343.01 374.79C343.05 374.74 343.01 374.72 343.01 374.72H343.07L343.49 374.96C343.58 375 343.64 375 343.65 375.05Z\" fill=\"#FFEBD4\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 61\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_17_2\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_18\" style=\"mix-blend-mode:overlay\">\n<path d=\"M345.38 374.06C345.49 374.49 345.75 375.25 345.8 375.45C345.85 375.65 345.72 375.61 345.47 375.61H344.47C344.47 375.61 344.41 375.61 344.4 375.51C344.39 375.41 344.4 375.29 344.32 375.16C344.24 375.03 344.25 374.92 344.19 374.69C344.06 374.15 343.85 373.32 343.78 372.95C343.76 372.829 343.734 372.708 343.7 372.59C343.7 372.43 343.62 372.3 343.59 372.21H343.16C343.16 372.21 343.16 372.21 343.1 372.13C343.105 372.093 343.105 372.057 343.1 372.02C343.1 371.96 343.1 371.95 343.1 371.95H345.2C345.29 371.95 345.29 372.03 345.31 372.11C345.33 372.19 345.31 372.23 345.24 372.23H344.86C345 372.58 345.28 373.7 345.38 374.06Z\" fill=\"#FFEBD4\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 62\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_18_2\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_19\" style=\"mix-blend-mode:overlay\">\n<path d=\"M346.13 372.77C346.2 373.05 346.39 373.93 346.46 374.2C346.53 374.47 346.78 375.37 346.82 375.5C346.824 375.527 346.824 375.553 346.82 375.58C346.82 375.63 346.82 375.64 346.82 375.66C346.82 375.68 346.74 375.66 346.69 375.66C346.64 375.66 346.59 375.66 346.53 375.44C346.47 375.22 346.18 374.02 346.09 373.68C346 373.34 345.79 372.33 345.74 372.2V372.09C345.74 372.02 345.74 371.96 345.74 371.96H345.9C345.9 371.96 345.9 371.96 345.96 372.03C346.02 372.1 345.96 372.11 345.96 372.15C346.005 372.36 346.062 372.567 346.13 372.77Z\" fill=\"#FFEBD4\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 63\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_19_2\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_20\" style=\"mix-blend-mode:overlay\">\n<path d=\"M349.11 373.8C349.21 374.15 349.53 375.7 348.38 375.7C347.81 375.7 347.38 375.2 347.12 374.7C346.954 374.379 346.817 374.045 346.71 373.7C346.47 372.76 346.8 371.92 347.36 371.92C347.57 371.891 347.783 371.93 347.97 372.03C348.521 372.49 348.919 373.108 349.11 373.8ZM348.76 373.8C348.54 372.95 348.03 372.22 347.52 372.22C347.37 372.22 347.24 372.22 347.17 372.37C347.04 372.572 346.957 372.802 346.927 373.041C346.898 373.279 346.923 373.522 347 373.75C347.21 374.57 347.65 375.41 348.29 375.41C348.93 375.41 349 374.65 348.76 373.8Z\" fill=\"#FFEBD4\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 64\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_20_2\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_21\" style=\"mix-blend-mode:overlay\">\n<path d=\"M350.42 373.82C350.51 374.18 350.72 374.93 350.76 375.08C350.8 375.23 350.89 375.5 350.91 375.58C350.91 375.65 350.91 375.66 350.85 375.66H350.57H350.16C350.05 375.66 350.04 375.58 350.01 375.51C349.98 375.44 350.01 375.41 349.93 375.28L349.88 375.07C349.81 374.77 349.65 374.16 349.62 373.93C349.59 373.7 349.4 372.8 349.34 372.59C349.28 372.38 349.24 372.18 349.2 371.98C349.16 371.78 349.2 371.84 349.28 371.84H349.75C349.796 371.834 349.843 371.841 349.886 371.861C349.928 371.88 349.964 371.911 349.99 371.95L350.43 372.64L351.22 373.89C351.31 374.02 351.45 374.21 351.57 374.4L351.78 374.71L351.7 374.41L351.55 373.9C351.545 373.85 351.545 373.8 351.55 373.75C351.49 373.53 351.44 373.32 351.41 373.17C351.38 373.02 351.25 372.62 351.21 372.43L351.09 371.93C351.09 371.87 351.09 371.85 351.14 371.85H351.23H351.38C351.38 371.85 351.44 371.85 351.45 371.85C351.446 371.887 351.446 371.923 351.45 371.96C351.45 372.06 351.76 373.18 351.83 373.45V373.6C351.91 373.9 352.05 374.34 352.1 374.53C352.15 374.72 352.33 375.34 352.35 375.44C352.35 375.53 352.35 375.54 352.3 375.53H352.1C352.05 375.53 352.05 375.53 351.98 375.43C351.91 375.33 351.5 374.62 351.37 374.43C351.24 374.24 350.73 373.43 350.57 373.18C350.41 372.93 350.37 372.88 350.27 372.73L350.07 372.46L350.21 372.95C350.29 373.34 350.38 373.64 350.42 373.82Z\" fill=\"#FFEBD4\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 65\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_21_2\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_22\" style=\"mix-blend-mode:overlay\">\n<path d=\"M352.69 375C352.683 374.873 352.683 374.747 352.69 374.62C352.69 374.48 352.69 374.18 352.69 374.03C352.69 373.88 352.69 373.65 352.69 373.54C352.69 373.43 352.69 373.16 352.69 373C352.684 372.88 352.684 372.76 352.69 372.64C352.69 372.56 352.69 372.27 352.69 372.13C352.69 371.99 352.69 371.88 352.77 371.88C352.85 371.88 352.87 372 352.95 372.14C353.03 372.28 353.23 372.7 353.27 372.78C353.31 372.86 353.65 373.48 353.7 373.57C353.75 373.66 354.04 374.18 354.12 374.31C354.2 374.44 354.39 374.82 354.46 374.98C354.53 375.14 354.74 375.47 354.78 375.54C354.776 375.556 354.776 375.574 354.78 375.59C354.78 375.59 354.78 375.59 354.73 375.59H354.5C354.5 375.59 354.5 375.59 354.44 375.59L354.34 375.4L354.23 375.17C354.18 375.045 354.12 374.925 354.05 374.81C354.005 374.739 353.965 374.666 353.93 374.59L353.85 374.44C353.8 374.36 353.79 374.36 353.76 374.36H352.87C352.87 374.36 352.87 374.36 352.87 374.42V374.57C352.87 374.65 352.87 375.05 352.87 375.1C352.875 375.157 352.875 375.213 352.87 375.27V375.43C352.865 375.477 352.865 375.523 352.87 375.57H352.79C352.79 375.57 352.79 375.57 352.79 375.51C352.785 375.487 352.785 375.463 352.79 375.44V375.25C352.762 375.165 352.728 375.081 352.69 375ZM353.56 374C353.546 373.957 353.526 373.917 353.5 373.88C353.45 373.79 353.29 373.45 353.2 373.3C353.11 373.15 352.92 372.74 352.89 372.65C352.846 372.555 352.792 372.464 352.73 372.38C352.73 372.38 352.73 372.51 352.73 372.63C352.73 372.75 352.73 373.21 352.73 373.34C352.73 373.47 352.73 373.85 352.73 373.96C352.73 374.02 352.82 374.01 352.86 374.01H353.48C353.48 374.01 353.57 374 353.56 374Z\" fill=\"#FFEBD4\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 66\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_22_2\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_23\" style=\"mix-blend-mode:overlay\">\n<path d=\"M354.83 373.93C354.91 374.16 355.24 375.44 355.27 375.57C355.3 375.7 355.19 375.7 355.14 375.7C355.09 375.7 355.07 375.61 355.05 375.55C355.022 375.472 354.998 375.391 354.98 375.31C354.975 375.26 354.975 375.21 354.98 375.16C354.98 375.04 354.64 373.76 354.43 372.93C354.34 372.57 354.26 372.3 354.24 372.23C354.236 372.193 354.236 372.157 354.24 372.12C354.24 372.02 354.24 372.01 354.24 372.01H354.87C355.05 372.01 355.69 372.07 355.81 372.52C355.97 373.14 355.29 373.23 355.08 373.23H355C355.06 373.23 356.74 375.23 356.94 375.43C357.14 375.63 357.1 375.59 357.1 375.62C357.1 375.65 357.1 375.62 357.1 375.62C357.041 375.635 356.979 375.635 356.92 375.62C356.74 375.62 356.75 375.62 356.67 375.48C356.59 375.34 356.07 374.8 355.77 374.48C355.62 374.3 355.36 374.01 355.14 373.77L354.74 373.32V373.53C354.76 373.68 354.8 373.82 354.83 373.93ZM354.83 373.02C354.953 373.035 355.077 373.035 355.2 373.02C355.41 372.97 355.57 372.91 355.51 372.68C355.45 372.45 355.07 372.35 354.9 372.35H354.46L354.62 373.08L354.83 373.02Z\" fill=\"#FFEBD4\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 67\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_23_2\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_24\" style=\"mix-blend-mode:overlay\">\n<path d=\"M357.87 375.65H357.71C357.71 375.65 357.71 375.65 357.65 375.65V375.59C357.65 375.54 357.65 375.17 357.65 375.09C357.65 375.01 357.65 374.8 357.65 374.7C357.65 374.6 357.65 374.57 357.65 374.51C357.65 374.45 357.49 374.18 357.42 374.06C357.35 373.94 357.26 373.75 357.17 373.59C357.08 373.43 356.61 372.59 356.54 372.43C356.47 372.27 356.4 372.21 356.39 372.16C356.38 372.11 356.39 372.09 356.5 372.09H356.84C356.92 372.09 356.9 372.14 356.93 372.2L357.15 372.63C357.22 372.76 357.33 372.98 357.41 373.12C357.49 373.26 357.56 373.37 357.63 373.51C357.7 373.65 357.72 373.67 357.76 373.76V373.63C357.755 373.557 357.755 373.483 357.76 373.41V373.12C357.757 373.073 357.757 373.027 357.76 372.98C357.754 372.93 357.754 372.88 357.76 372.83C357.775 372.634 357.775 372.436 357.76 372.24C357.76 372.06 357.83 372.09 357.89 372.09H358.15C358.23 372.09 358.25 372.09 358.26 372.14V372.19C358.26 372.25 358.26 372.6 358.26 372.79C358.26 372.98 358.2 373.73 358.19 373.95C358.18 374.17 358.11 375.1 358.12 375.19C358.11 375.316 358.11 375.444 358.12 375.57C358.12 375.64 358.12 375.67 358.12 375.67H357.84L357.87 375.65Z\" fill=\"#FFEBD4\"\/>\n<\/g>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Group 7\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector5656231 68\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_24_2\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_25\" style=\"mix-blend-mode:overlay\">\n<path d=\"M249.63 377.66C249.63 377.45 249.69 377.41 249.75 377.41H249.8C249.943 377.4 250.087 377.4 250.23 377.41C250.33 377.41 250.35 377.46 250.35 377.51C250.354 377.557 250.354 377.603 250.35 377.65C250.35 377.8 250.27 378.16 250.23 378.76C250.23 378.92 250.23 379.1 250.23 379.27C250.23 379.72 250.23 380.12 250.23 380.27C250.23 380.42 250.23 380.78 250.23 381.01C250.234 381.057 250.234 381.103 250.23 381.15C250.23 381.15 250.23 381.24 250.23 381.3C250.23 381.36 250.23 381.74 250.23 381.84C250.23 381.94 250.14 381.96 250.06 381.96H249.55C249.43 381.96 249.43 381.87 249.43 381.76C249.43 381.65 249.48 381.45 249.5 381.22C249.52 380.99 249.64 379.89 249.65 379.72C249.66 379.55 249.73 378.67 249.74 378.52C249.75 378.37 249.74 378.3 249.74 378.18V377.95L249.63 377.66Z\" fill=\"#FFE3BB\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 69\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_25_2\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_26\" style=\"mix-blend-mode:overlay\">\n<path d=\"M253.16 381.16V381.23C253.055 381.452 252.891 381.64 252.687 381.776C252.483 381.912 252.245 381.989 252 382C251.27 382 250.64 381 250.71 379.69C250.78 378.38 251.51 377.47 252.13 377.47C252.331 377.46 252.531 377.507 252.708 377.604C252.884 377.701 253.03 377.845 253.13 378.02C253.142 378.063 253.142 378.107 253.13 378.15C253.121 378.191 253.096 378.227 253.06 378.25C252.921 378.371 252.794 378.505 252.68 378.65C252.61 378.74 252.55 378.81 252.5 378.81C252.481 378.808 252.463 378.801 252.448 378.791C252.432 378.78 252.419 378.766 252.41 378.75C252.31 378.62 252.23 378.48 252.09 378.48C251.95 378.48 251.48 378.81 251.42 379.85C251.36 380.89 251.85 381.08 252 381.08C252.15 381.08 252.34 380.9 252.41 380.83C252.48 380.76 252.47 380.76 252.49 380.76C252.513 380.752 252.537 380.752 252.56 380.76L253.01 381.06C253.09 381.07 253.16 381.09 253.16 381.16Z\" fill=\"#FFE3BB\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 70\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_26_2\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_27\" style=\"mix-blend-mode:overlay\">\n<path d=\"M255.81 379.94C255.81 380.47 255.81 381.4 255.81 381.64C255.81 381.88 255.64 381.84 255.31 381.84H254.06C254.01 381.84 254.01 381.79 254.01 381.72C254.01 381.65 254.01 381.45 254.06 381.29C254.11 381.13 254.06 381 254.06 380.72C254.06 380.06 254.17 379.05 254.22 378.6C254.22 378.43 254.22 378.29 254.22 378.15C254.22 378.01 254.22 377.79 254.22 377.69H253.66C253.66 377.69 253.66 377.69 253.66 377.59C253.66 377.49 253.66 377.5 253.66 377.45C253.66 377.4 253.66 377.37 253.73 377.37H255.04H256.47C256.59 377.37 256.56 377.46 256.55 377.57C256.54 377.68 256.55 377.72 256.41 377.72H256C255.93 378.13 255.84 379.5 255.81 379.94Z\" fill=\"#FFE3BB\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 71\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_27_2\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_28\" style=\"mix-blend-mode:overlay\">\n<path d=\"M257.31 378.37C257.31 378.71 257.19 379.79 257.17 380.11C257.15 380.43 257.11 381.55 257.11 381.71C257.115 381.74 257.115 381.77 257.11 381.8C257.11 381.87 257.11 381.88 257.04 381.9C256.984 381.912 256.926 381.912 256.87 381.9C256.69 381.9 256.74 381.9 256.75 381.64C256.76 381.38 256.87 379.9 256.89 379.48C256.91 379.06 257.04 377.83 257.03 377.68V377.55C257.03 377.46 257.03 377.38 257.13 377.38H257.34C257.34 377.38 257.34 377.38 257.34 377.47C257.334 377.52 257.334 377.57 257.34 377.62C257.35 377.78 257.34 378 257.31 378.37Z\" fill=\"#FFE3BB\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 72\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_28_2\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_29\" style=\"mix-blend-mode:overlay\">\n<path d=\"M260.79 379.62C260.79 380.05 260.56 381.95 259.07 381.95C258.32 381.95 257.99 381.34 257.83 380.73C257.733 380.328 257.689 379.914 257.7 379.5C257.76 378.36 258.53 377.33 259.26 377.33C259.518 377.289 259.781 377.334 260.01 377.46C260.278 377.749 260.486 378.09 260.62 378.461C260.754 378.832 260.812 379.226 260.79 379.62ZM260.33 379.62C260.39 378.62 260.01 377.7 259.33 377.7C259.13 377.7 258.97 377.7 258.81 377.88C258.341 378.321 258.062 378.927 258.03 379.57C257.98 380.57 258.21 381.57 259.03 381.57C259.85 381.57 260.27 380.66 260.33 379.62Z\" fill=\"#FFE3BB\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 73\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_29_2\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_30\" style=\"mix-blend-mode:overlay\">\n<path d=\"M262.48 379.66C262.48 380.09 262.43 381 262.42 381.19C262.41 381.38 262.42 381.7 262.42 381.8C262.42 381.89 262.36 381.91 262.31 381.91H261.93H261.4C261.25 381.91 261.26 381.82 261.25 381.74C261.243 381.647 261.243 381.553 261.25 381.46C261.25 381.39 261.25 381.31 261.25 381.2C261.25 380.84 261.33 380.08 261.37 379.8C261.41 379.52 261.54 378.42 261.55 378.17C261.56 377.92 261.55 377.67 261.61 377.42C261.67 377.17 261.7 377.25 261.78 377.25H262.39C262.55 377.25 262.62 377.25 262.66 377.37C262.7 377.49 262.84 377.9 262.95 378.22C263.06 378.54 263.37 379.44 263.48 379.75L263.73 380.37L263.88 380.75V379.57C263.88 379.3 263.88 379.05 263.88 378.87C263.88 378.69 263.88 378.19 263.88 377.96L263.93 377.35C263.93 377.28 263.98 377.26 264.02 377.26H264.13C264.193 377.271 264.257 377.271 264.32 377.26C264.38 377.26 264.39 377.26 264.39 377.32C264.393 377.36 264.393 377.4 264.39 377.44C264.39 377.56 264.3 378.94 264.28 379.27C264.28 379.27 264.28 379.38 264.28 379.45C264.28 379.82 264.28 380.35 264.28 380.59C264.28 380.83 264.28 381.59 264.28 381.7C264.28 381.81 264.22 381.82 264.17 381.81H264.1C264.037 381.815 263.973 381.815 263.91 381.81C263.85 381.81 263.85 381.81 263.79 381.69C263.73 381.57 263.5 380.69 263.41 380.45C263.32 380.21 262.97 379.22 262.87 378.92C262.82 378.77 262.73 378.55 262.66 378.37L262.51 378.04V378.64C262.5 379.06 262.49 379.43 262.48 379.66Z\" fill=\"#FFE3BB\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 74\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_30_2\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_31\" style=\"mix-blend-mode:overlay\">\n<path d=\"M266.78 377.45C266.78 377.26 266.95 377.28 267.07 377.28C267.273 377.294 267.477 377.294 267.68 377.28C267.84 377.28 267.83 377.36 267.8 377.56C267.77 377.76 267.75 378.23 267.72 378.82C267.69 379.41 267.65 380.04 267.64 380.25C267.64 380.79 267.58 382.12 267.59 381.83C267.59 381.91 267.59 381.93 267.5 381.93H267.34H266.92C266.77 381.93 266.72 381.86 266.66 381.69C266.6 381.52 266.47 381.14 266.32 380.81L266 380L265.78 379.47V379.71C265.78 379.86 265.78 380.01 265.78 380.15C265.78 380.29 265.71 381.48 265.73 381.65V381.73C265.73 381.83 265.68 381.83 265.62 381.82H265.18C265.07 381.82 265.05 381.82 265.07 381.59C265.09 381.36 265.07 380.51 265.13 379.74C265.13 379.2 265.22 378.5 265.25 378.03C265.25 377.85 265.25 377.7 265.25 377.61C265.245 377.56 265.245 377.51 265.25 377.46C265.25 377.29 265.33 377.26 265.41 377.27C265.519 377.285 265.63 377.285 265.74 377.27H266.11C266.35 377.27 266.44 377.62 266.54 377.82C266.64 378.02 266.64 378.03 266.68 378.12L266.76 378.26V377.91C266.76 377.75 266.77 377.54 266.78 377.45Z\" fill=\"#FFE3BB\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 75\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_31_2\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_32\" style=\"mix-blend-mode:overlay\">\n<path d=\"M271.33 377.66C271.33 377.45 271.4 377.41 271.46 377.41C271.606 377.4 271.753 377.4 271.9 377.41C271.99 377.41 272.02 377.46 272.01 377.51C272.014 377.557 272.014 377.603 272.01 377.65C272.01 377.8 271.92 378.16 271.88 378.76V379.27C271.88 379.72 271.88 380.12 271.88 380.27C271.88 380.42 271.88 380.78 271.88 381.01C271.887 381.056 271.887 381.104 271.88 381.15C271.874 381.2 271.874 381.25 271.88 381.3C271.88 381.48 271.88 381.74 271.88 381.84C271.88 381.94 271.79 381.96 271.7 381.96H271.2C271.07 381.96 271.08 381.87 271.08 381.76C271.08 381.65 271.13 381.45 271.14 381.22C271.15 380.99 271.29 379.89 271.3 379.72C271.31 379.55 271.38 378.67 271.38 378.52C271.38 378.37 271.38 378.3 271.38 378.18V377.95L271.33 377.66Z\" fill=\"#FFE3BB\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 76\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_32_2\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_33\" style=\"mix-blend-mode:overlay\">\n<path d=\"M274.92 381.7C274.954 381.755 274.978 381.816 274.99 381.88C274.99 381.93 274.94 381.88 274.88 381.88H274.25C274.16 381.88 274.16 381.72 274.04 381.43C273.92 381.14 273.84 380.91 273.7 380.57L273.46 379.94C273.46 380.24 273.46 380.51 273.46 380.76C273.46 381.18 273.46 381.63 273.46 381.7V381.76C273.46 381.86 273.4 381.89 273.3 381.87C273.2 381.85 272.72 381.92 272.58 381.92C272.44 381.92 272.46 381.87 272.46 381.78C272.46 381.69 272.46 381.69 272.46 381.63C272.46 381.57 272.46 380.63 272.46 380.12C272.46 379.96 272.46 379.84 272.46 379.77C272.505 379.475 272.532 379.178 272.54 378.88C272.54 378.42 272.54 377.88 272.54 377.72V377.58C272.54 377.36 272.62 377.39 272.68 377.39C272.922 377.353 273.166 377.329 273.41 377.32C273.58 377.306 273.75 377.331 273.908 377.395C274.067 377.458 274.208 377.557 274.321 377.684C274.435 377.811 274.517 377.962 274.562 378.126C274.607 378.291 274.613 378.463 274.58 378.63C274.557 378.947 274.454 379.254 274.28 379.52C274.198 379.639 274.104 379.749 274 379.85L274.35 380.65C274.66 381.13 274.85 381.57 274.92 381.7ZM273.62 379.12C273.71 379.12 273.78 378.99 273.8 378.79C273.82 378.59 273.73 378.43 273.64 378.43C273.598 378.432 273.559 378.45 273.53 378.48C273.53 378.48 273.53 378.68 273.53 378.83C273.522 378.903 273.522 378.977 273.53 379.05C273.525 379.07 273.525 379.09 273.53 379.11V379.16C273.562 379.153 273.593 379.139 273.62 379.12Z\" fill=\"#FFE3BB\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 77\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_33_2\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_34\" style=\"mix-blend-mode:overlay\">\n<path d=\"M275.64 379.43C275.64 378.94 275.64 378.9 275.64 378.52C275.64 378.14 275.64 377.76 275.71 377.59C275.78 377.42 275.71 377.45 275.82 377.45H275.9C275.99 377.45 276.08 377.45 276.33 377.45C276.58 377.45 276.95 377.4 277.17 377.4H277.78C277.89 377.4 277.89 377.46 277.89 377.58C277.89 377.7 277.89 377.86 277.89 378.06C277.902 378.136 277.902 378.214 277.89 378.29C277.89 378.37 277.89 378.39 277.81 378.39H277.69C277.53 378.376 277.37 378.376 277.21 378.39H276C275.94 378.39 275.94 378.39 275.94 378.51C275.94 378.63 275.94 378.9 275.89 379.12V379.5C275.885 379.567 275.885 379.633 275.89 379.7H276.43H277.02H277.29C277.35 379.7 277.36 379.7 277.36 379.78C277.354 379.847 277.354 379.913 277.36 379.98C277.36 380.1 277.36 380.15 277.36 380.31C277.36 380.47 277.36 380.41 277.31 380.41H277.21H276.65C276.433 380.414 276.216 380.431 276 380.46H275.89V381.09H276.76H277.46H277.69C277.78 381.09 277.8 381.15 277.79 381.22C277.78 381.29 277.79 381.31 277.79 381.35C277.79 381.39 277.79 381.61 277.79 381.79C277.79 381.97 277.69 381.93 277.52 381.93H276.52H275.65C275.65 381.93 275.65 381.88 275.65 381.82C275.65 381.76 275.65 381.66 275.65 381.59C275.65 381.52 275.65 381.45 275.65 381.32V380.45C275.56 380 275.61 379.92 275.64 379.43Z\" fill=\"#FFE3BB\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 78\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_34_2\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_35\" style=\"mix-blend-mode:overlay\">\n<path d=\"M281.31 382.65C281.31 382.55 281.31 382.54 281.38 382.54H281.57H282.28H283.43C283.52 382.54 283.54 382.54 283.55 382.62V382.73L283.66 383.49V383.81V383.86C283.66 383.93 283.66 383.95 283.58 383.95H283H282.15H282.03C282.03 383.95 282.03 384.02 282.03 384.06V384.28C282.034 384.34 282.034 384.4 282.03 384.46V384.54H282.8H283.33C283.43 384.54 283.45 384.54 283.46 384.62C283.464 384.68 283.464 384.74 283.46 384.8C283.46 384.88 283.46 384.88 283.39 384.88H282.1L282.18 385.51C282.18 385.84 282.26 386.17 282.26 386.27C282.26 386.37 282.26 386.47 282.26 386.6C282.26 386.73 282.26 386.92 282.31 386.98C282.36 387.04 282.31 387.08 282.19 387.08H281.8C281.7 387.08 281.72 386.99 281.69 386.85C281.66 386.71 281.69 386.68 281.64 386.54C281.59 386.4 281.64 386.14 281.57 386C281.5 385.86 281.47 385.05 281.45 384.91C281.43 384.77 281.39 384.62 281.36 384.34C281.33 384.06 281.36 383.95 281.3 383.77L281.22 383.19C281.34 383 281.33 382.77 281.31 382.65Z\" fill=\"#FFE3BB\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 79\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_35_2\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_36\" style=\"mix-blend-mode:overlay\">\n<path d=\"M287 386.83C287.049 386.886 287.086 386.95 287.11 387.02C287.11 387.02 287.11 387.02 287.01 387.02H286.36C286.26 387.02 286.23 386.86 286.05 386.55L285.54 385.68L285.17 385.04C285.22 385.34 285.27 385.62 285.32 385.87C285.39 386.3 285.48 386.76 285.5 386.87C285.52 386.98 285.5 386.87 285.5 386.93C285.5 386.99 285.5 387.06 285.35 387.04C285.2 387.02 284.76 387.1 284.61 387.1C284.46 387.1 284.48 387.04 284.47 386.95C284.46 386.86 284.47 386.86 284.47 386.8C284.47 386.74 284.29 385.8 284.23 385.26C284.213 385.141 284.213 385.019 284.23 384.9C284.23 384.77 284.23 384.4 284.14 383.99C284.05 383.58 283.99 382.99 283.96 382.81C283.957 382.76 283.957 382.71 283.96 382.66C283.96 382.44 284.01 382.46 284.06 382.46C284.11 382.46 284.47 382.4 284.81 382.4C285.182 382.386 285.544 382.519 285.819 382.77C286.094 383.02 286.259 383.369 286.28 383.74C286.32 384.048 286.268 384.361 286.13 384.64C286.071 384.762 285.997 384.876 285.91 384.98L286.42 385.8C286.66 386.25 287 386.7 287 386.83ZM285.17 384.2C285.25 384.15 285.31 384.06 285.28 383.85C285.25 383.64 285.14 383.49 285.05 383.49C285.031 383.49 285.011 383.494 284.994 383.503C284.976 383.511 284.961 383.524 284.95 383.54C284.95 383.54 284.95 383.74 285 383.9C284.99 383.976 284.99 384.054 285 384.13C285 384.13 285 384.13 285 384.18C285 384.23 285 384.18 285 384.24C285.073 384.25 285.146 384.236 285.21 384.2H285.17Z\" fill=\"#FFE3BB\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 80\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_36_2\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_37\" style=\"mix-blend-mode:overlay\">\n<path d=\"M288 382.37C288 382.3 288 382.29 288.07 382.32C288.14 382.35 288.14 382.43 288.17 382.5C288.2 382.57 288.47 383.08 288.58 383.28C288.69 383.48 288.8 383.71 288.92 383.97C289.04 384.23 289.4 384.89 289.56 385.2C289.72 385.51 290.1 386.13 290.2 386.3C290.301 386.502 290.418 386.696 290.55 386.88C290.554 386.91 290.554 386.94 290.55 386.97C290.55 386.97 290.5 386.97 290.45 386.97H290.04C289.99 386.97 289.95 386.85 289.9 386.75C289.85 386.65 289.63 386.19 289.59 386.09C289.55 385.99 289.45 385.82 289.39 385.72C289.33 385.62 289.32 385.59 289.27 385.59H289.05C288.96 385.59 288.59 385.59 288.44 385.59H288C287.95 385.59 287.95 385.66 287.94 385.73C287.93 385.8 287.94 386.2 287.94 386.32V386.6V386.79C287.94 386.89 287.94 386.91 287.88 386.91H287.55C287.546 386.88 287.546 386.85 287.55 386.82C287.55 386.76 287.55 386.74 287.55 386.57C287.55 386.4 287.66 385.79 287.67 385.57C287.683 385.291 287.716 385.014 287.77 384.74C287.77 384.52 287.77 384.42 287.84 384.12C287.91 383.82 287.91 383.5 287.94 383.27L288.02 382.75C287.94 382.58 288 382.44 288 382.37ZM288.89 384.72C288.89 384.72 288.89 384.72 288.89 384.66C288.754 384.423 288.631 384.179 288.52 383.93C288.42 383.73 288.35 383.56 288.33 383.53C288.31 383.5 288.26 383.4 288.24 383.4C288.22 383.4 288.24 383.52 288.24 383.64C288.24 383.76 288.18 384.09 288.16 384.21C288.145 384.355 288.121 384.498 288.09 384.64V384.74C288.09 384.74 288.09 384.74 288.15 384.74C288.21 384.74 288.73 384.74 288.83 384.74C288.93 384.74 288.88 384.75 288.87 384.72H288.89Z\" fill=\"#FFE3BB\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 81\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_37_2\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_38\" style=\"mix-blend-mode:overlay\">\n<path d=\"M292 382.48C292 382.3 292.15 382.31 292.27 382.31C292.478 382.307 292.685 382.29 292.89 382.26C293.05 382.26 293.07 382.35 293.07 382.55C293.07 382.75 293.15 383.23 293.23 383.84C293.31 384.45 293.39 385.08 293.42 385.3C293.49 385.85 293.71 387.21 293.67 386.92C293.67 386.99 293.67 387.02 293.59 387.02H293.43H292.99C292.84 387.02 292.78 386.95 292.69 386.78C292.6 386.61 292.38 386.21 292.17 385.88C292.06 385.72 291.86 385.39 291.69 385.1L291.36 384.56V384.81C291.36 384.96 291.36 385.11 291.42 385.26C291.48 385.41 291.6 386.62 291.65 386.79C291.648 386.817 291.648 386.843 291.65 386.87C291.65 386.97 291.65 386.97 291.55 386.96H291.11C290.99 386.96 290.97 386.96 290.95 386.73C290.93 386.5 290.77 385.62 290.65 384.84C290.58 384.29 290.51 383.57 290.45 383.09C290.434 382.946 290.411 382.802 290.38 382.66C290.371 382.61 290.371 382.56 290.38 382.51C290.38 382.33 290.38 382.3 290.5 382.31C290.609 382.335 290.721 382.335 290.83 382.31H291.22C291.46 382.31 291.63 382.67 291.77 382.87C291.91 383.07 291.91 383.09 291.97 383.18L292.08 383.33L292.03 382.97C292 382.79 292 382.58 292 382.48Z\" fill=\"#FFE3BB\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 82\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_38_2\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_39\" style=\"mix-blend-mode:overlay\">\n<path d=\"M296.76 386.08C296.765 386.103 296.765 386.127 296.76 386.15C296.688 386.361 296.554 386.545 296.376 386.679C296.197 386.813 295.983 386.89 295.76 386.9H295.64C295.595 386.982 295.562 387.069 295.54 387.16C295.61 387.16 295.63 387.16 295.81 387.16C295.99 387.16 296.18 387.25 296.23 387.61C296.238 387.674 296.231 387.74 296.208 387.801C296.186 387.862 296.149 387.917 296.1 387.96L296 388C295.892 388.055 295.77 388.076 295.65 388.06C295.47 388.06 295.26 388.06 295.25 387.94C295.24 387.834 295.24 387.726 295.25 387.62C295.25 387.62 295.32 387.62 295.4 387.7C295.476 387.716 295.554 387.716 295.63 387.7C295.77 387.7 295.83 387.7 295.84 387.53C295.85 387.36 295.78 387.32 295.67 387.32C295.56 387.32 295.54 387.41 295.5 387.41C295.46 387.41 295.32 387.41 295.31 387.41C295.3 387.334 295.3 387.256 295.31 387.18C295.303 387.08 295.303 386.98 295.31 386.88C295.019 386.743 294.765 386.537 294.57 386.28C294.212 385.803 293.985 385.241 293.91 384.65C293.846 384.135 293.925 383.612 294.14 383.14C294.209 382.971 294.322 382.823 294.468 382.714C294.615 382.605 294.788 382.538 294.97 382.52C295.181 382.526 295.388 382.579 295.576 382.674C295.765 382.769 295.93 382.904 296.06 383.07C296.096 383.111 296.123 383.158 296.14 383.21C296.139 383.229 296.134 383.248 296.125 383.265C296.117 383.282 296.105 383.298 296.09 383.31C295.964 383.433 295.853 383.571 295.76 383.72C295.71 383.81 295.66 383.89 295.61 383.89C295.56 383.89 295.55 383.89 295.51 383.82C295.47 383.75 295.27 383.55 295.13 383.55C294.99 383.55 294.86 383.64 294.76 383.85C294.653 384.172 294.622 384.514 294.67 384.85C294.79 385.77 295.35 386.08 295.51 386.05C295.67 386.02 295.82 385.87 295.88 385.8C295.94 385.73 295.88 385.72 295.95 385.72H296.02L296.55 386.02C296.67 386 296.75 386 296.76 386.08Z\" fill=\"#FFE3BB\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 83\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_39_2\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_40\" style=\"mix-blend-mode:overlay\">\n<path d=\"M299.67 382.7C299.67 382.49 299.67 382.44 299.75 382.44H299.8C299.9 382.44 300.08 382.44 300.25 382.44C300.42 382.44 300.38 382.44 300.39 382.54C300.395 382.587 300.395 382.633 300.39 382.68C300.396 383.061 300.423 383.442 300.47 383.82L300.53 384.33C300.59 384.79 300.66 385.21 300.67 385.33C300.68 385.45 300.76 385.85 300.79 386.08C300.79 386.15 300.79 386.21 300.79 386.23C300.781 386.28 300.781 386.33 300.79 386.38C300.79 386.56 300.86 386.83 300.87 386.93C300.88 387.03 300.8 387.06 300.72 387.05H300.2C300.06 387.05 300.05 386.96 300.03 386.85C300.01 386.74 300.03 386.53 300.03 386.3C300.03 386.07 299.93 384.94 299.91 384.76C299.89 384.58 299.79 383.7 299.77 383.54C299.75 383.38 299.77 383.31 299.77 383.19V382.96L299.67 382.7Z\" fill=\"#FFE3BB\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 84\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_40_2\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_41\" style=\"mix-blend-mode:overlay\">\n<path d=\"M302.3 382.81C301.74 382.81 301.54 383.14 301.59 383.53C301.637 383.712 301.727 383.881 301.852 384.022C301.978 384.163 302.134 384.272 302.31 384.34C302.662 384.42 302.984 384.601 303.236 384.86C303.488 385.119 303.66 385.445 303.73 385.8C303.87 386.92 302.97 387.07 302.47 387.07C302.095 387.039 301.742 386.88 301.47 386.62C301.458 386.604 301.451 386.585 301.451 386.565C301.451 386.545 301.458 386.526 301.47 386.51C301.47 386.51 301.52 386.31 301.57 386.31C301.57 386.31 301.57 386.31 301.7 386.42C301.902 386.574 302.139 386.674 302.39 386.71C302.6 386.71 303.24 386.71 303.15 385.95C303.1 385.58 302.62 385.39 302.15 385.1C301.887 384.975 301.658 384.787 301.484 384.554C301.31 384.32 301.195 384.048 301.15 383.76C301.125 383.596 301.137 383.428 301.183 383.269C301.23 383.11 301.311 382.962 301.42 382.838C301.53 382.713 301.665 382.614 301.817 382.547C301.969 382.48 302.134 382.447 302.3 382.45C302.673 382.489 303.023 382.647 303.3 382.9C303.35 382.9 303.37 382.96 303.37 382.99C303.374 382.999 303.377 383.01 303.377 383.02C303.377 383.03 303.374 383.041 303.37 383.05C303.37 383.05 303.29 383.24 303.24 383.24H303.16C302.922 383.015 302.623 382.865 302.3 382.81Z\" fill=\"#FFE3BB\"\/>\n<\/g>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Group 8\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector5656231 85\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_41_2\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_42\" style=\"mix-blend-mode:overlay\">\n<path d=\"M247 393.6C247.48 393.6 248.51 394.06 248.2 396.5C247.9 398.76 246.43 398.85 246.2 398.85H245.49C245.41 398.85 245.41 398.73 245.42 398.59C245.425 398.527 245.425 398.463 245.42 398.4C245.42 398.22 245.48 397.84 245.5 397.68C245.52 397.52 245.5 397.16 245.62 396.57C245.74 395.98 245.79 395.57 245.87 395C245.95 394.43 246 393.88 246.02 393.72C246.04 393.56 246.26 393.61 246.39 393.61H246.58L247 393.6ZM246.83 396.99C247.032 396.744 247.161 396.446 247.2 396.13C247.227 396 247.227 395.865 247.202 395.735C247.176 395.604 247.124 395.48 247.05 395.37C246.991 395.294 246.916 395.232 246.83 395.19C246.83 395.27 246.83 395.35 246.83 395.44C246.83 395.71 246.73 395.99 246.7 396.23C246.67 396.47 246.64 396.65 246.61 396.87L246.55 397.26C246.659 397.189 246.757 397.101 246.84 397L246.83 396.99Z\" fill=\"#FFEBD4\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 86\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_42_2\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_43\" style=\"mix-blend-mode:overlay\">\n<path d=\"M248.87 396.51C248.87 396.68 248.87 396.75 248.87 396.93L248.76 397.82C248.76 397.95 248.76 398.09 248.71 398.2C248.701 398.263 248.701 398.327 248.71 398.39H249.24H249.79H250.29H250.62C250.68 398.39 250.68 398.39 250.62 398.51C250.56 398.63 250.62 398.66 250.62 398.74C250.62 398.82 250.62 398.83 250.5 398.83H250.41C250.224 398.815 250.036 398.815 249.85 398.83H249.18H248.5C248.4 398.83 248.39 398.83 248.4 398.72C248.396 398.68 248.396 398.64 248.4 398.6C248.404 398.577 248.404 398.553 248.4 398.53C248.4 398.53 248.4 398.44 248.4 398.1C248.4 397.76 248.51 397.1 248.58 396.55C248.65 396 248.78 395.3 248.82 394.99C248.86 394.68 248.93 394.12 248.95 393.84C248.97 393.56 249.22 393.69 249.38 393.69C249.54 393.69 249.98 393.69 250.26 393.69H251.16C251.27 393.69 251.24 393.81 251.23 393.89V393.98C251.23 394.05 251.23 394.15 251.23 394.15C251.23 394.15 251.17 394.15 251.07 394.15H249.59H249.36H249.24V394.35C249.24 394.46 249.24 394.59 249.19 394.7C249.14 394.81 249.19 395.11 249.13 395.28V395.58C249.134 395.643 249.134 395.707 249.13 395.77H249.48C249.57 395.77 249.68 395.77 249.84 395.77C250 395.77 250.18 395.77 250.24 395.77H250.52H250.87H250.98C251.04 395.77 251.04 395.83 250.98 395.86C250.92 395.89 250.98 396.07 250.98 396.13C250.98 396.19 250.98 396.22 250.89 396.22C250.8 396.22 250.38 396.13 250.18 396.13C249.964 396.115 249.746 396.115 249.53 396.13C249.427 396.14 249.323 396.14 249.22 396.13H249.08V396.25C249.001 396.329 248.931 396.416 248.87 396.51Z\" fill=\"#FFEBD4\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 87\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_43_2\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_44\" style=\"mix-blend-mode:overlay\">\n<path d=\"M251.57 396.7C251.45 397.58 251.62 398.22 251.96 398.22C252.3 398.22 252.44 397.83 252.46 397.63C252.48 397.43 252.64 396.48 252.71 395.92C252.71 395.53 252.88 394.87 252.94 394.39C252.966 394.218 252.983 394.044 252.99 393.87C252.98 393.824 252.98 393.776 252.99 393.73C252.99 393.54 253.11 393.58 253.15 393.58H253.52C253.64 393.58 253.62 393.64 253.61 393.76C253.6 393.88 253.61 394 253.61 394.16C253.616 394.24 253.616 394.32 253.61 394.4C253.56 394.67 253.51 395.59 253.31 397.01C253.11 398.43 252.51 398.85 252 398.85C251.49 398.85 251.35 398.21 251.32 397.85C251.317 397.418 251.347 396.987 251.41 396.56C251.41 396.3 251.48 396.08 251.5 395.99C251.52 395.9 251.56 395.61 251.6 395.29C251.67 394.77 251.74 394.13 251.76 393.92C251.76 393.87 251.76 393.83 251.76 393.8C251.76 393.58 251.85 393.6 251.88 393.62H251.94H252.03C252.03 393.62 252.03 393.62 252.03 393.71C252.05 393.12 251.71 395.59 251.57 396.7Z\" fill=\"#FFEBD4\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 88\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_44_2\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_45\" style=\"mix-blend-mode:overlay\">\n<path d=\"M255.82 396.57C255.74 397.19 255.68 398.3 255.64 398.57C255.6 398.84 255.46 398.8 255.16 398.8H253.99C253.94 398.8 253.94 398.74 253.99 398.65C254.04 398.56 254.06 398.34 254.08 398.15C254.1 397.96 254.08 397.8 254.16 397.46C254.26 396.68 254.43 395.46 254.53 394.94C254.53 394.75 254.59 394.57 254.61 394.41C254.63 394.25 254.66 393.99 254.67 393.86H254.58H254.15C254.15 393.86 254.15 393.8 254.15 393.74V393.57C254.15 393.49 254.15 393.47 254.22 393.47H254.34H255.45H256.79C256.9 393.47 256.86 393.58 256.84 393.71C256.82 393.84 256.78 393.88 256.69 393.88C256.543 393.887 256.397 393.887 256.25 393.88C256.12 394.41 255.89 396.05 255.82 396.57Z\" fill=\"#FFEBD4\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 89\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_45_2\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_46\" style=\"mix-blend-mode:overlay\">\n<path d=\"M259.57 394.29C259.575 394.313 259.575 394.337 259.57 394.36C259.575 394.396 259.575 394.434 259.57 394.47C259.52 394.53 259.4 394.75 259.34 394.84C259.28 394.93 259.27 394.97 259.21 394.97C259.15 394.97 258.79 394.19 258.41 394.19C258.27 394.19 258.07 394.19 258.01 394.71C257.989 394.886 258.026 395.063 258.114 395.216C258.202 395.37 258.338 395.49 258.5 395.56C258.73 395.72 259.45 396.08 259.25 397.56C259.245 397.761 259.199 397.959 259.116 398.142C259.033 398.325 258.913 398.489 258.764 398.624C258.616 398.76 258.441 398.864 258.252 398.93C258.062 398.996 257.861 399.024 257.66 399.01C257.415 399.007 257.178 398.922 256.987 398.767C256.797 398.613 256.664 398.399 256.61 398.16C256.602 398.134 256.602 398.106 256.61 398.08C256.627 398.045 256.647 398.011 256.67 397.98C256.744 397.869 256.824 397.762 256.91 397.66C256.91 397.66 256.97 397.74 257 397.8C257.056 397.926 257.145 398.034 257.258 398.114C257.37 398.193 257.503 398.24 257.64 398.25C257.712 398.256 257.783 398.246 257.851 398.223C257.919 398.199 257.981 398.161 258.034 398.113C258.086 398.064 258.128 398.005 258.157 397.939C258.186 397.873 258.2 397.802 258.2 397.73C258.209 397.526 258.177 397.323 258.104 397.132C258.032 396.941 257.922 396.767 257.78 396.62C257.524 396.453 257.319 396.22 257.187 395.945C257.055 395.67 257.001 395.364 257.03 395.06C257.071 394.692 257.221 394.344 257.462 394.063C257.703 393.781 258.023 393.578 258.38 393.48C258.631 393.501 258.873 393.586 259.082 393.728C259.29 393.87 259.459 394.064 259.57 394.29Z\" fill=\"#FFEBD4\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 90\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_46_2\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_47\" style=\"mix-blend-mode:overlay\">\n<path d=\"M262.43 394.31C262.447 394.359 262.447 394.411 262.43 394.46C262.43 394.53 262.36 394.57 262.3 394.62C262.24 394.67 261.9 395.03 261.81 395.09C261.75 395.09 261.74 395 261.71 394.95C261.68 394.9 261.62 394.67 261.43 394.67C261.24 394.67 261.07 394.93 260.93 396.01C260.79 397.09 260.93 397.42 261.09 397.42C261.25 397.42 261.3 397.36 261.39 397.1C261.48 396.84 261.49 396.91 261.55 396.91C261.59 396.904 261.63 396.904 261.67 396.91C261.859 396.987 262.053 397.054 262.25 397.11C262.3 397.11 262.31 397.2 262.3 397.29C262.29 397.38 262.3 397.36 262.3 397.4C262.28 397.492 262.253 397.582 262.22 397.67C262.07 398.08 261.7 398.92 260.9 398.92C260.36 398.92 259.58 398.28 259.9 396C260.22 393.72 261.06 393.39 261.54 393.39C262.24 393.45 262.35 394.1 262.43 394.31Z\" fill=\"#FFEBD4\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 91\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_47_2\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_48\" style=\"mix-blend-mode:overlay\">\n<path d=\"M264.51 395.94H265.51V395.71C265.51 395.58 265.51 395.42 265.56 395.3C265.61 395.18 265.8 393.69 265.81 393.59C265.82 393.49 265.81 393.53 265.88 393.53H266.01C266.039 393.519 266.071 393.519 266.1 393.53C266.109 393.539 266.114 393.552 266.114 393.565C266.114 393.578 266.109 393.591 266.1 393.6C266.104 393.62 266.104 393.64 266.1 393.66C266.1 393.75 266.04 393.97 265.97 394.31C265.9 394.65 265.68 396.26 265.64 396.59L265.4 398.19V398.49C265.396 398.563 265.396 398.637 265.4 398.71C265.4 398.77 265.4 398.76 265.34 398.76H265.15C265.15 398.76 265.15 398.76 265.15 398.68C265.15 398.89 265.24 397.99 265.29 397.58L265.4 396.78L265.47 396.22H265.05H263.65C263.66 396.283 263.66 396.347 263.65 396.41C263.65 396.53 263.65 396.7 263.58 396.87C263.51 397.04 263.51 397.37 263.47 397.69C263.43 398.01 263.39 398.32 263.39 398.47V398.58C263.39 398.76 263.27 398.73 263.19 398.73C263.05 398.716 262.91 398.716 262.77 398.73C262.62 398.73 262.67 398.58 262.71 398.26C262.75 397.94 262.98 396.11 263.04 395.66C263.1 395.21 263.28 393.89 263.31 393.71C263.34 393.53 263.38 393.47 263.44 393.47H263.55H263.67H264C264.1 393.47 264.06 393.61 264.05 393.7C264.04 393.79 263.98 394.18 263.91 394.59L263.79 395.34L263.72 395.78H264.03L264.51 395.94Z\" fill=\"#FFEBD4\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 92\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_48_2\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_49\" style=\"mix-blend-mode:overlay\">\n<path d=\"M246.21 403.3C246.21 403.2 246.21 402.85 246.21 402.68C246.21 402.51 246.29 401.93 246.3 401.79C246.31 401.65 246.36 401.41 246.41 401.41C246.46 401.41 246.41 401.41 246.5 401.51C246.59 401.61 246.5 401.63 246.58 401.75C246.66 401.87 246.84 402.29 246.93 402.46L247.14 402.85L247.26 403.08C247.259 403.063 247.259 403.047 247.26 403.03V402.88C247.26 402.76 247.26 402.51 247.26 402.29C247.26 402.07 247.32 401.77 247.26 401.63C247.2 401.49 247.26 401.43 247.34 401.43H247.51H247.57H247.63C247.636 401.453 247.636 401.477 247.63 401.5C247.63 401.6 247.63 401.72 247.63 401.9C247.63 402.08 247.63 402.79 247.57 402.99C247.51 403.19 247.57 403.65 247.57 403.71C247.589 403.819 247.589 403.931 247.57 404.04C247.57 404.23 247.57 405.18 247.57 405.24C247.57 405.3 247.57 405.42 247.57 405.42C247.57 405.42 247.5 405.42 247.45 405.29C247.343 405.112 247.246 404.929 247.16 404.74L246.85 404.07C246.809 403.956 246.759 403.846 246.7 403.74L246.6 403.53V403.69C246.6 403.77 246.6 403.98 246.52 404.23C246.44 404.48 246.47 405.16 246.47 405.23C246.47 405.3 246.47 405.44 246.41 405.44C246.35 405.44 246.33 405.38 246.3 405.31C246.27 405.24 246.06 404.62 245.98 404.46C245.9 404.3 245.77 403.96 245.71 403.8C245.65 403.64 245.26 402.69 245.18 402.48C245.1 402.27 244.9 401.74 244.84 401.6C244.831 401.564 244.831 401.526 244.84 401.49H245.14C245.21 401.49 245.23 401.49 245.27 401.65C245.31 401.81 245.54 402.35 245.75 402.76C245.84 402.97 245.93 403.17 246.01 403.33L246.13 403.58V403.5L246.21 403.3Z\" fill=\"#FFEBD4\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 93\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_49_2\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_50\" style=\"mix-blend-mode:overlay\">\n<path d=\"M251.05 403.39C251.11 403.79 251.31 405.5 250.05 405.5C249.41 405.5 249.05 404.95 248.75 404.39C248.596 404.033 248.479 403.661 248.4 403.28C248.23 402.28 248.67 401.28 249.29 401.28C249.52 401.25 249.755 401.291 249.96 401.4C250.529 401.928 250.911 402.626 251.05 403.39ZM248.93 401.3C248.845 401.291 248.767 401.254 248.706 401.194C248.646 401.134 248.609 401.055 248.6 400.97C248.6 400.81 248.65 400.65 248.8 400.65C248.885 400.653 248.967 400.684 249.032 400.738C249.097 400.792 249.142 400.867 249.16 400.95C249.17 400.988 249.172 401.028 249.166 401.067C249.16 401.106 249.145 401.144 249.124 401.177C249.102 401.21 249.073 401.238 249.04 401.259C249.007 401.28 248.969 401.294 248.93 401.3ZM250.66 403.39C250.5 402.46 250 401.65 249.44 401.65C249.27 401.65 249.14 401.65 249.03 401.81C248.877 402.03 248.769 402.28 248.714 402.542C248.659 402.805 248.658 403.077 248.71 403.34C248.87 404.24 249.27 405.18 249.97 405.18C250.67 405.18 250.81 404.34 250.66 403.39ZM249.96 400.61C250.09 400.61 250.19 400.79 250.22 400.97C250.231 401.007 250.234 401.046 250.227 401.083C250.22 401.121 250.204 401.157 250.18 401.187C250.157 401.218 250.126 401.242 250.091 401.258C250.057 401.274 250.018 401.282 249.98 401.28C249.78 401.28 249.7 401.11 249.67 400.97C249.62 400.65 249.83 400.61 250 400.61H249.96Z\" fill=\"#FFEBD4\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 94\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_50_2\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_51\" style=\"mix-blend-mode:overlay\">\n<path d=\"M251.65 403.54C251.71 403.8 251.96 405.22 251.98 405.36C252 405.5 251.88 405.5 251.82 405.5C251.76 405.5 251.75 405.41 251.74 405.34C251.711 405.252 251.691 405.162 251.68 405.07C251.675 405.013 251.675 404.957 251.68 404.9C251.68 404.77 251.44 403.35 251.28 402.43C251.22 402.03 251.16 401.73 251.14 401.66C251.137 401.62 251.137 401.58 251.14 401.54C251.14 401.42 251.14 401.41 251.2 401.41H251.9C252.09 401.41 252.8 401.48 252.9 401.98C253.02 402.66 252.26 402.76 252.02 402.76H251.95C252.01 402.81 253.67 404.99 253.87 405.19C254.07 405.39 254.03 405.37 254.04 405.41C253.971 405.426 253.899 405.426 253.83 405.41C253.64 405.41 253.65 405.41 253.58 405.26C253.51 405.11 252.98 404.5 252.69 404.1C252.54 403.9 252.28 403.58 252.06 403.31L251.65 402.82V403.05C251.6 403.26 251.63 403.42 251.65 403.54ZM251.73 402.54C251.87 402.555 252.01 402.555 252.15 402.54C252.39 402.48 252.56 402.41 252.52 402.16C252.48 401.91 252.07 401.79 251.88 401.79H251.39L251.5 402.6L251.73 402.54Z\" fill=\"#FFEBD4\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 95\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_51_2\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_52\" style=\"mix-blend-mode:overlay\">\n<path d=\"M254.66 401.4H255.48H255.66C255.83 401.4 255.87 401.5 255.87 401.55C255.87 401.6 255.87 401.74 255.93 401.98C255.99 402.22 256 402.33 256.02 402.42C256.04 402.51 256.02 402.57 255.88 402.57H255.06L255.15 403.17C255.15 403.26 255.15 403.44 255.22 403.65C255.33 404.29 255.5 405.24 255.52 405.33C255.52 405.41 255.52 405.4 255.46 405.4H255.15C255.06 405.4 255.06 405.4 255.04 405.2C255.02 405 254.81 403.6 254.76 403.3C254.71 403 254.65 402.7 254.62 402.54H253.8C253.783 402.54 253.767 402.537 253.752 402.53C253.736 402.523 253.723 402.514 253.711 402.501C253.7 402.489 253.692 402.475 253.686 402.459C253.681 402.443 253.679 402.427 253.68 402.41C253.68 402.36 253.61 401.91 253.57 401.65C253.57 401.57 253.57 401.51 253.57 401.48C253.57 401.39 253.57 401.4 253.64 401.4H254.1H254.66Z\" fill=\"#FFEBD4\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 96\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_52_2\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_53\" style=\"mix-blend-mode:overlay\">\n<path d=\"M256.57 403.22C256.5 402.77 256.47 402.73 256.41 402.39C256.35 402.05 256.3 401.71 256.28 401.54C256.26 401.37 256.28 401.42 256.35 401.42H256.42C256.49 401.42 256.58 401.42 256.79 401.42C257 401.42 257.3 401.37 257.48 401.37H258.01C258.1 401.37 258.12 401.37 258.13 401.53C258.14 401.69 258.2 401.79 258.23 401.97C258.26 402.15 258.23 402.08 258.23 402.18C258.23 402.28 258.23 402.27 258.18 402.27C258.144 402.276 258.106 402.276 258.07 402.27C257.934 402.256 257.796 402.256 257.66 402.27H256.66C256.6 402.27 256.61 402.27 256.66 402.39C256.71 402.51 256.66 402.74 256.74 402.94L256.79 403.28C256.785 403.34 256.785 403.4 256.79 403.46H257.25H257.74H257.97C258.03 403.46 258.04 403.46 258.05 403.53C258.043 403.586 258.043 403.644 258.05 403.7C258.05 403.81 258.05 403.87 258.1 404.01C258.15 404.15 258.1 404.1 258.1 404.1H258.01H257.54C257.356 404.104 257.172 404.121 256.99 404.15H257L257.1 404.72H257.83H258.42H258.62C258.7 404.72 258.72 404.77 258.73 404.84C258.74 404.91 258.73 404.92 258.73 404.96C258.73 405 258.73 405.19 258.79 405.36C258.85 405.53 258.74 405.48 258.59 405.48H257.76H257.02C257.02 405.48 257.02 405.48 257.02 405.38C257.02 405.28 257.02 405.24 257.02 405.17C257.02 405.1 257.02 405.04 256.97 404.92L256.84 404.14C256.63 403.76 256.64 403.66 256.57 403.22Z\" fill=\"#FFEBD4\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 97\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_53_2\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_54\" style=\"mix-blend-mode:overlay\">\n<path d=\"M259.3 403.54C259.36 403.8 259.6 405.22 259.63 405.36C259.66 405.5 259.52 405.5 259.46 405.5C259.4 405.5 259.39 405.41 259.38 405.34C259.37 405.27 259.38 405.19 259.32 405.07C259.315 405.013 259.315 404.957 259.32 404.9C259.32 404.77 259.08 403.35 258.93 402.43C258.893 402.171 258.843 401.914 258.78 401.66C258.78 401.61 258.78 401.57 258.78 401.54C258.78 401.51 258.78 401.41 258.84 401.41H259.54C259.74 401.41 260.44 401.48 260.54 401.98C260.65 402.66 259.89 402.76 259.65 402.76H259.59C259.59 402.81 261.3 404.99 261.51 405.19C261.72 405.39 261.66 405.37 261.67 405.41C261.604 405.426 261.536 405.426 261.47 405.41C261.27 405.41 261.28 405.41 261.21 405.26C261.14 405.11 260.61 404.5 260.32 404.1C260.17 403.9 259.91 403.58 259.69 403.31L259.29 402.82V403.05C259.271 403.213 259.275 403.378 259.3 403.54ZM259.38 402.54C259.516 402.555 259.654 402.555 259.79 402.54C260.03 402.48 260.21 402.41 260.16 402.16C260.11 401.91 259.71 401.79 259.52 401.79H259L259.1 402.6L259.38 402.54Z\" fill=\"#FFEBD4\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 98\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_54_2\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_55\" style=\"mix-blend-mode:overlay\">\n<path d=\"M263.86 404.69C263.99 405.51 263.07 405.46 262.86 405.46H262.12C262.01 405.46 261.97 405.36 261.95 405.24L261.75 403.97C261.75 403.86 261.75 403.78 261.75 403.69C261.724 403.558 261.707 403.424 261.7 403.29C261.7 402.97 261.51 402.09 261.5 401.93C261.49 401.77 261.5 401.83 261.5 401.77C261.5 401.71 261.45 401.51 261.44 401.48C261.44 401.48 261.44 401.48 261.44 401.42C261.64 401.374 261.845 401.347 262.05 401.34C262.55 401.34 263.05 401.5 263.19 402.39C263.227 402.535 263.234 402.685 263.212 402.833C263.19 402.981 263.138 403.123 263.06 403.25C263.003 403.334 262.923 403.4 262.83 403.44C263.092 403.546 263.324 403.716 263.503 403.934C263.683 404.153 263.806 404.412 263.86 404.69ZM262.25 403.31V403.37C262.363 403.368 262.474 403.34 262.575 403.289C262.676 403.237 262.763 403.163 262.831 403.072C262.899 402.981 262.945 402.876 262.965 402.765C262.986 402.654 262.981 402.539 262.95 402.43C262.8 401.55 262.37 401.51 261.95 401.51V401.88C261.95 402.09 262.02 402.33 262.04 402.49L262.15 403.15C262.192 403.198 262.225 403.252 262.25 403.31ZM263.56 404.69C263.539 404.468 263.462 404.255 263.336 404.072C263.21 403.888 263.039 403.739 262.84 403.64C262.667 403.566 262.479 403.531 262.29 403.54C262.29 403.54 262.29 403.61 262.29 403.68C262.29 403.75 262.4 404.25 262.42 404.35C262.44 404.45 262.42 404.48 262.42 404.62C262.42 404.76 262.53 405.12 262.54 405.22C262.55 405.32 262.61 405.31 262.7 405.31C263.38 405.35 263.62 405.08 263.56 404.69Z\" fill=\"#FFEBD4\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 99\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_55_2\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_56\" style=\"mix-blend-mode:overlay\">\n<path d=\"M265.39 404.2C265.67 404.2 265.64 403.84 265.61 403.66C265.58 403.48 265.52 403.02 265.46 402.66C265.467 402.59 265.467 402.52 265.46 402.45C265.41 402.17 265.3 401.65 265.28 401.52C265.26 401.39 265.28 401.33 265.36 401.33H266C266.06 401.33 266.11 401.33 266.15 401.5C266.19 401.67 266.22 401.87 266.27 402.18C266.32 402.49 266.44 403.18 266.48 403.41C266.52 403.64 266.72 405.41 265.61 405.41C265.256 405.398 264.917 405.259 264.657 405.019C264.396 404.778 264.231 404.452 264.19 404.1C264.183 404.024 264.183 403.946 264.19 403.87C264.12 403.46 264.03 402.77 263.97 402.47C263.91 402.17 263.81 401.63 263.8 401.47C263.79 401.31 263.74 401.26 263.87 401.26H264.11H264.26H264.62C264.68 401.26 264.69 401.26 264.71 401.38L265.1 403.68C265.06 403.87 265.1 404.2 265.39 404.2Z\" fill=\"#FFEBD4\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 100\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_56_2\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_57\" style=\"mix-blend-mode:overlay\">\n<path d=\"M268.79 402C268.79 402.05 268.85 402.08 268.85 402.11C268.85 402.14 268.85 402.2 268.77 402.24C268.69 402.28 268.51 402.55 268.44 402.6C268.39 402.6 268.36 402.53 268.32 402.49C268.28 402.45 268.17 402.28 268 402.28C267.83 402.28 267.73 402.48 267.87 403.28C268.01 404.08 268.25 404.36 268.37 404.36C268.49 404.36 268.54 404.31 268.56 404.11C268.58 403.91 268.61 403.97 268.65 403.97C268.69 403.97 268.74 403.97 268.78 403.97C268.82 403.97 269.21 404.09 269.35 404.12C269.49 404.15 269.42 404.19 269.44 404.26V404.35C269.45 404.416 269.45 404.484 269.44 404.55C269.452 404.674 269.439 404.8 269.401 404.919C269.363 405.038 269.3 405.148 269.218 405.242C269.135 405.335 269.034 405.411 268.921 405.464C268.808 405.517 268.685 405.546 268.56 405.55C268.07 405.55 267.21 405.06 266.91 403.32C266.61 401.58 267.33 401.32 267.75 401.32C267.967 401.334 268.177 401.404 268.36 401.523C268.542 401.642 268.69 401.806 268.79 402Z\" fill=\"#FFEBD4\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 101\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_57_2\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_58\" style=\"mix-blend-mode:overlay\">\n<path d=\"M271.07 403.21H272V403.04C272 402.94 272 402.82 271.94 402.73L271.75 401.43C271.75 401.38 271.75 401.38 271.75 401.38H272C272.015 401.382 272.029 401.389 272.04 401.4C272.051 401.411 272.058 401.425 272.06 401.44C272.06 401.5 272.06 401.68 272.06 401.94C272.06 402.2 272.27 403.42 272.32 403.68C272.37 403.94 272.47 404.79 272.49 404.89C272.51 404.99 272.49 405.04 272.49 405.12C272.49 405.2 272.49 405.25 272.49 405.29H272.33C272.33 405.29 272.28 405.29 272.28 405.23C272.28 405.38 272.2 404.7 272.14 404.39C272.14 404.27 272.08 404.01 272.04 403.78L271.97 403.35H270.33C270.33 403.4 270.33 403.45 270.33 403.5C270.33 403.55 270.33 403.72 270.38 403.85L270.48 404.47C270.507 404.672 270.547 404.873 270.6 405.07V405.16C270.6 405.29 270.52 405.27 270.45 405.27C270.327 405.261 270.203 405.261 270.08 405.27C269.95 405.27 269.95 405.15 269.91 404.91C269.87 404.67 269.62 403.27 269.57 402.91C269.52 402.55 269.35 401.56 269.32 401.42C269.29 401.28 269.32 401.24 269.38 401.24H270C270.09 401.24 270.09 401.35 270.1 401.42C270.11 401.49 270.16 401.78 270.2 402.1L270.27 402.67L270.32 403.01H270.6L271.07 403.21Z\" fill=\"#FFEBD4\"\/>\n<\/g>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Group 9\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector5656231 102\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_58_2\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_59\" style=\"mix-blend-mode:overlay\">\n<path d=\"M277.69 367H279.52V369.76H279.18V369.42H277.69V371.37H277.35V369.42H275.87V369.79H275.55V367H277.35V365.93H277.79C277.784 365.952 277.771 365.972 277.753 365.986C277.735 366 277.713 366.009 277.69 366.01V367ZM275.87 369H277.35V367.4H275.87V369ZM277.69 369H279.18V367.4H277.69V369Z\" fill=\"#FFEBD4\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 103\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_59_2\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_60\" style=\"mix-blend-mode:overlay\">\n<path d=\"M280.37 366.22H284.5V371.41H284.17V371.12H280.69V371.41H280.37V366.22ZM280.69 370.76H284.17V366.58H280.69V370.76ZM280.93 369.86L282.44 369.53V369.79L281.08 370.14C281.08 370.159 281.074 370.178 281.063 370.194C281.053 370.21 281.038 370.222 281.02 370.23L280.93 369.86ZM282.81 367.71C282.848 368.197 282.915 368.681 283.01 369.16C283.194 368.797 283.325 368.41 283.4 368.01L283.75 368.11C283.75 368.11 283.75 368.17 283.65 368.17C283.541 368.653 283.362 369.118 283.12 369.55C283.24 369.9 283.4 370.16 283.57 370.16C283.74 370.16 283.69 369.91 283.73 369.53C283.79 369.604 283.861 369.668 283.94 369.72C283.89 370.26 283.77 370.51 283.58 370.51H283.48C283.24 370.45 283.07 370.22 282.92 369.87C282.731 370.15 282.494 370.394 282.22 370.59C282.172 370.501 282.112 370.42 282.04 370.35C282.35 370.136 282.612 369.86 282.81 369.54C282.667 368.945 282.574 368.34 282.53 367.73H281V367.43H282.53C282.53 367.21 282.53 366.99 282.53 366.76H282.92C282.92 366.76 282.92 366.83 282.82 366.84V367.4H283.94V367.7L282.81 367.71ZM281.16 368.11H282.27V369.27H281.16V368.11ZM282.02 369.01V368.37H281.4V369L282.02 369.01ZM283.22 366.69C283.424 366.793 283.609 366.928 283.77 367.09L283.61 367.31C283.448 367.142 283.263 366.997 283.06 366.88L283.22 366.69Z\" fill=\"#FFEBD4\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 104\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_60_2\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_61\" style=\"mix-blend-mode:overlay\">\n<path d=\"M285.05 367.26V366.94H286.87V367.26H285.05ZM286.73 369.33V371.05H285.56V371.32H285.27V369.32L286.73 369.33ZM286.73 367.73V368.06H285.29V367.73H286.73ZM285.29 368.85V368.53H286.73V368.85H285.29ZM286.71 366.16V366.48H285.31V366.16H286.71ZM286.44 369.66H285.57V370.66H286.44V369.66ZM289.44 366.25V370.84C289.44 371.36 289.26 371.39 288.33 371.39C288.303 371.247 288.262 371.106 288.21 370.97H289C289.09 370.97 289.12 370.97 289.12 370.82V366.6H287V366.24L289.44 366.25ZM288.74 367.25V367.6H287V367.25H288.74ZM288.55 370.05H287.45V370.49H287.15V368.16H288.55V370.05ZM288.26 368.51H287.45V369.7H288.26V368.51Z\" fill=\"#FFEBD4\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 105\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_61_2\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_62\" style=\"mix-blend-mode:overlay\">\n<path d=\"M294 369.61H294.46V370H290V369.62H290.5V366.68H291.57V365.94H291.98C291.971 365.96 291.957 365.978 291.94 365.992C291.922 366.006 291.902 366.016 291.88 366.02V366.64H292.66V365.9H293.07C293.066 365.921 293.055 365.941 293.038 365.955C293.022 365.97 293.002 365.978 292.98 365.98V366.61H294V369.61ZM291.76 370.36C291.744 370.367 291.727 370.371 291.71 370.371C291.693 370.371 291.676 370.367 291.66 370.36C291.235 370.766 290.749 371.103 290.22 371.36C290.144 371.251 290.057 371.15 289.96 371.06C290.494 370.813 290.982 370.474 291.4 370.06L291.76 370.36ZM291.48 367.04H290.73V368.14H291.48V367.04ZM290.73 368.51V369.61H291.48V368.51H290.73ZM292.57 367.04H291.79V368.14H292.57V367.04ZM292.57 369.61V368.51H291.79V369.61H292.57ZM294.1 371.39C293.656 371.022 293.184 370.688 292.69 370.39L292.93 370.12C293.445 370.414 293.937 370.749 294.4 371.12L294.1 371.39ZM293.67 367.04H292.89V368.14H293.67V367.04ZM292.89 368.51V369.61H293.67V368.51H292.89Z\" fill=\"#FFEBD4\"\/>\n<\/g>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 106\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_62_2\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_63\" style=\"mix-blend-mode:overlay\">\n<path d=\"M269.83 366.4H258.19C257.849 367.583 257.849 368.837 258.19 370.02H269.83C269.445 368.844 269.445 367.576 269.83 366.4Z\" fill=\"#FFEBD4\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 107\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_63_2\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_64\" style=\"mix-blend-mode:overlay\">\n<path d=\"M273.73 368.19C273.73 367.942 273.656 367.7 273.519 367.494C273.381 367.289 273.185 367.129 272.956 367.034C272.727 366.94 272.475 366.916 272.232 366.965C271.99 367.014 271.767 367.134 271.593 367.31C271.418 367.486 271.3 367.709 271.253 367.952C271.206 368.195 271.232 368.447 271.328 368.675C271.424 368.904 271.586 369.098 271.793 369.234C272 369.37 272.242 369.442 272.49 369.44C272.82 369.437 273.135 369.304 273.367 369.07C273.6 368.836 273.73 368.52 273.73 368.19Z\" fill=\"#FFEBD4\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 108\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_64_2\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_65\" style=\"mix-blend-mode:overlay\">\n<path d=\"M312.83 370H301.18C300.845 368.817 300.845 367.563 301.18 366.38H312.83C312.44 367.555 312.44 368.825 312.83 370Z\" fill=\"#FFEBD4\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 109\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_65_2\" style=\"mix-blend-mode:overlay\">\n<g id=\"Vector_66\" style=\"mix-blend-mode:overlay\">\n<path d=\"M296.79 368.23C296.786 368.48 296.857 368.725 296.994 368.934C297.131 369.143 297.327 369.306 297.557 369.402C297.788 369.499 298.042 369.524 298.286 369.475C298.531 369.426 298.756 369.304 298.931 369.126C299.106 368.948 299.224 368.721 299.269 368.476C299.314 368.23 299.285 367.977 299.185 367.748C299.085 367.519 298.918 367.326 298.707 367.192C298.496 367.059 298.25 366.992 298 367C297.678 367.008 297.372 367.14 297.146 367.37C296.92 367.6 296.793 367.908 296.79 368.23Z\" fill=\"#FFEBD4\"\/>\n<\/g>\n<\/g>\n<\/g>\n<path id=\"Vector5656231 110\" d=\"M98.18 384.87C98.18 387.21 97.0667 389.543 94.84 391.87V382C97.0667 379.66 98.18 377.327 98.18 375V384.87Z\" fill=\"#C61C6F\"\/>\n<path id=\"Vector5656231 111\" d=\"M94.84 381.96V391.89L87.92 389.42V379.49L94.84 381.96Z\" fill=\"#EB6D79\"\/>\n<path id=\"Vector5656231 112\" d=\"M90.41 373C90.4987 373.346 90.5424 373.703 90.54 374.06C90.54 375.68 89.69 377.44 87.99 379.36C87.1846 378.681 86.3175 378.078 85.4 377.56C82.1322 375.662 78.492 374.496 74.73 374.14C71.0166 373.776 67.2677 374.115 63.68 375.14C60.3262 376.078 57.0991 377.422 54.07 379.14C51.3465 380.616 48.8782 382.52 46.76 384.78C46.0241 383.987 45.4289 383.073 45 382.08C44.691 381.384 44.5309 380.631 44.53 379.87C44.587 378.333 45.1533 376.859 46.14 375.68C48.3627 373.028 51.0798 370.834 54.14 369.22C57.1691 367.502 60.3962 366.158 63.75 365.22C67.3377 364.195 71.0866 363.856 74.8 364.22C78.562 364.576 82.2022 365.742 85.47 367.64C88.29 369.32 89.9367 371.107 90.41 373Z\" fill=\"#CE5F6B\"\/>\n<path id=\"Vector5656231 113\" d=\"M79.4 314.82C79.4486 313.316 78.9513 311.846 78 310.68C77.4983 310.087 76.8694 309.616 76.16 309.3C75.4713 308.997 74.7389 308.804 73.99 308.73C70.9968 308.622 68.0011 308.854 65.06 309.42L53.32 311.23V326.23L66.02 324.23C68.5445 323.924 71.0287 323.347 73.43 322.51C77 321.09 79.4 318.63 79.4 314.82ZM81.84 336.22C81.9007 334.535 81.2974 332.894 80.16 331.65C79.7172 331.181 79.2045 330.783 78.64 330.47C77.6654 329.934 76.5953 329.594 75.49 329.47C72.6171 329.264 69.7296 329.432 66.9 329.97L53.32 332.07V349.14C68.21 346.83 71.22 346.44 73.23 345.82C74.8184 345.359 76.331 344.668 77.72 343.77C78.9521 342.939 79.9782 341.838 80.72 340.55C81.4755 339.233 81.8624 337.738 81.84 336.22ZM89.9 335C89.8911 337.363 89.293 339.686 88.16 341.76C87.0989 343.784 85.6317 345.568 83.85 347C79.54 350.4 73.36 351.91 67.94 352.74L45.54 356.21V306.58L67.54 303.17C71.1019 302.478 74.7581 302.42 78.34 303C80.82 303.454 83.0689 304.746 84.71 306.66C85.2766 307.336 85.7539 308.082 86.13 308.88C87.68 312.17 87.13 315.88 84.97 319.17C84.5679 319.786 84.1164 320.368 83.62 320.91C82.2186 322.404 80.5923 323.669 78.8 324.66C82.3467 324.987 85.0767 326.067 86.99 327.9C87.8203 328.666 88.4987 329.582 88.99 330.6C89.6147 331.981 89.9255 333.484 89.9 335Z\" fill=\"#5198BF\"\/>\n<path id=\"Vector5656231 114\" d=\"M85.91 324C86.9433 326.207 87.97 328.417 88.99 330.63C88.4987 329.612 87.8202 328.696 86.99 327.93C85.0833 326.097 82.3533 325.017 78.8 324.69C80.5923 323.699 82.2186 322.434 83.62 320.94C84.5459 321.76 85.2945 322.76 85.82 323.88L85.91 324Z\" fill=\"#437F9F\"\/>\n<path id=\"Vector5656231 115\" d=\"M44.48 379.87C44.4809 380.631 44.641 381.384 44.95 382.08C45.3931 383.081 46.0054 383.997 46.76 384.79C47.7804 385.844 48.9495 386.744 50.23 387.46C53.5483 389.34 57.269 390.396 61.08 390.54C65.4052 390.715 69.7196 389.989 73.75 388.41L78 392.53C72.5161 394.491 66.6945 395.33 60.88 395C55.5867 394.708 50.434 393.188 45.83 390.56C41.1633 387.893 38.3367 385.173 37.35 382.4C37.0221 381.517 36.8528 380.582 36.85 379.64C36.9201 377.538 37.6436 375.511 38.92 373.84C41.3879 370.535 44.5439 367.806 48.17 365.84C56.9795 360.709 67.2926 358.784 77.36 360.39C81.9283 361.109 86.3311 362.64 90.36 364.91C94.66 367.403 97.1833 370.127 97.93 373.08C98.0858 373.684 98.1631 374.306 98.16 374.93C98.16 377.27 97.0467 379.603 94.82 381.93L87.9 379.46L87.97 379.37C89.67 377.45 90.52 375.69 90.52 374.07C90.5224 373.713 90.4787 373.356 90.39 373.01C89.9233 371.09 88.2567 369.3 85.39 367.64C82.1222 365.742 78.482 364.576 74.72 364.22C71.0066 363.856 67.2577 364.195 63.67 365.22C60.3162 366.158 57.0891 367.502 54.06 369.22C50.9998 370.834 48.2828 373.028 46.06 375.68C45.0842 376.863 44.5285 378.337 44.48 379.87Z\" fill=\"#EFA3AE\"\/>\n<path id=\"Vector5656231 116\" d=\"M83.05 302.14L86.17 308.88C85.7939 308.082 85.3166 307.336 84.75 306.66C83.1088 304.746 80.86 303.454 78.38 303C74.7981 302.42 71.1419 302.478 67.58 303.17L45.58 306.58L42.4 299.8L64.4 296.39C67.9619 295.698 71.6181 295.64 75.2 296.22C77.68 296.674 79.9288 297.966 81.57 299.88C82.1592 300.566 82.6567 301.326 83.05 302.14Z\" fill=\"#407C96\"\/>\n<path id=\"Vector5656231 117\" d=\"M81.84 336.22C81.8556 337.752 81.4547 339.259 80.68 340.58C79.9382 341.868 78.9121 342.969 77.68 343.8C76.291 344.698 74.7784 345.389 73.19 345.85C71.19 346.47 68.19 346.85 53.28 349.17V341.9C64.93 340.1 68.08 339.68 70.04 339.07C71.644 338.608 73.1707 337.91 74.57 337C75.804 336.175 76.8307 335.077 77.57 333.79C78.1757 332.773 78.5544 331.637 78.68 330.46C79.2445 330.773 79.7572 331.171 80.2 331.64C81.3254 332.893 81.9142 334.537 81.84 336.22Z\" fill=\"#437F9F\"\/>\n<path id=\"Vector5656231 118\" d=\"M78 310.68C78.9513 311.846 79.4487 313.316 79.4001 314.82C79.4001 318.63 76.9801 321.09 73.4001 322.55C71.002 323.386 68.5211 323.963 66 324.27L53.3 326.27V319L62.85 317.52C65.374 317.211 67.8581 316.635 70.2601 315.8C73.2601 314.56 75.64 312.53 76.14 309.33C76.8536 309.634 77.4895 310.096 78 310.68Z\" fill=\"#437F9F\"\/>\n<path id=\"Vector5656231 119\" d=\"M36.85 389.55V379.62C36.8528 380.562 37.0221 381.497 37.35 382.38C38.37 385.147 41.1967 387.867 45.83 390.54C50.4323 393.175 55.5851 394.702 60.88 395C66.6945 395.33 72.5161 394.491 78 392.53V402.46C72.5159 404.419 66.6933 405.252 60.88 404.91C55.5883 404.617 50.4366 403.101 45.83 400.48C41.1633 397.813 38.3367 395.09 37.35 392.31C37.0221 391.427 36.8528 390.492 36.85 389.55Z\" fill=\"#EB6D79\"\/>\n<path id=\"Vector5656231 120\" d=\"M42.4 312.54V299.8L45.54 306.58V356.23L42.4 349.45V338.18V312.54Z\" fill=\"#33647D\"\/>\n<path id=\"Vector5656231 121\" d=\"M42.4 312.54V338.18L40.24 339.42L22.64 279.61L31.24 274.64L42.4 312.54Z\" fill=\"#CE5F6B\"\/>\n<path id=\"Vector5656231 122\" d=\"M23.74 299.57C23.24 297.76 22.79 296.12 22.38 294.57C21.05 289.64 20.14 286.11 19.45 282.93C18.9273 285.712 18.1507 288.44 17.13 291.08C15.5833 295.08 14.01 299.027 12.41 302.92L27 311.37C25.72 306.76 24.65 302.89 23.74 299.57ZM22.64 279.57L40.24 339.39L33.76 335.65L28.76 317.71L16.26 310.49L10.77 307.33L6 319.67L0 316.18L16.51 276.07L22.64 279.57Z\" fill=\"#EB6D79\"\/>\n<path id=\"Vector5656231 123\" d=\"M31.24 274.64L22.64 279.61L16.51 276.06L25.11 271.1L31.24 274.64Z\" fill=\"#EFA3AE\"\/>\n<path id=\"Vector5656231 124\" d=\"M27 311.37L12.41 303L21.01 298L23.74 299.58C24.65 302.89 25.72 306.76 27 311.37Z\" fill=\"#EFA3AE\"\/>\n<path id=\"Vector5656231 125\" d=\"M19.45 283C20.14 286.18 21.05 289.71 22.38 294.64C21.93 295.77 21.47 296.9 21.01 298.02L12.41 303.02C14.01 299.1 15.5833 295.153 17.13 291.18C18.1525 288.53 18.9291 285.792 19.45 283Z\" fill=\"#C61C6F\"\/>\n<path id=\"Vector5656231 126\" d=\"M16.2501 310.52L14.6401 314.71L6.04004 319.67L10.7601 307.36L16.2501 310.52Z\" fill=\"#C61C6F\"\/>\n<g id=\"Group 10\" style=\"mix-blend-mode:multiply\">\n<g id=\"Vector5656231 127\" style=\"mix-blend-mode:multiply\" opacity=\"0.36\">\n<g id=\"Vector_66_2\" style=\"mix-blend-mode:multiply\" opacity=\"0.36\">\n<g id=\"Vector_67\" style=\"mix-blend-mode:multiply\" opacity=\"0.36\">\n<path d=\"M83.66 320.91C85.55 322.41 86.3 324.74 87.21 326.72C87.77 327.92 88.15 328.86 88.73 330.05C89.4544 331.582 89.8517 333.248 89.8964 334.943C89.9412 336.637 89.6325 338.322 88.99 339.89C88.4945 340.99 87.9438 342.065 87.34 343.11C88.16 343.03 88.8 342.94 89.44 342.91C92.05 342.79 94.65 342.67 97.26 342.59C98.16 342.59 99.08 342.49 99.72 343.44C99.88 343.68 100.56 343.63 101 343.61C104.21 343.45 107.43 343.28 110.64 343.06C111.119 342.991 111.607 343.097 112.013 343.36C112.42 343.623 112.717 344.025 112.85 344.49C113.64 346.36 114.53 348.2 115.46 350.25C114.931 350.481 114.386 350.674 113.83 350.83C110.47 351.47 107.12 352.13 103.74 352.68C98.15 353.58 92.54 354.39 86.94 355.28C83.2201 355.95 79.4497 356.302 75.67 356.33C66.25 356.23 45.54 356.23 45.54 356.23V306.58L53.92 305.28C53.92 305.28 63.63 303.66 70.16 302.74C73.73 302.6 76.61 302.22 79.7 303.39C80.9832 303.76 82.1798 304.382 83.22 305.22C84.33 306.047 85.2443 307.108 85.8976 308.328C86.5509 309.549 86.9273 310.898 87 312.28C87.12 314.46 86.75 316.11 85 319.17C84.63 319.7 84.13 320.25 83.66 320.91ZM53.32 341.91C53.32 341.91 60.71 342.75 64.37 342.07C67.18 341.56 70.04 341.24 72.68 340.07C74.3392 339.426 75.7903 338.34 76.8762 336.929C77.9621 335.519 78.6412 333.839 78.84 332.07C79.03 330.69 78.93 330.5 77.64 330.01C75.3004 329.345 72.8462 329.185 70.44 329.54C65.28 330.18 53.32 332.1 53.32 332.1V341.91ZM53.32 318.98C53.32 318.98 62.65 319.39 67.02 318.32C69.2428 317.926 71.3564 317.064 73.22 315.79C74.8859 314.561 75.9999 312.725 76.32 310.68C76.51 309.57 76.32 309.21 75.2 308.89C74.7574 308.764 74.3001 308.697 73.84 308.69C72.4568 308.62 71.0706 308.64 69.69 308.75C65.04 309.35 53.32 311.24 53.32 311.24V318.98Z\" fill=\"#5198BF\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 128\" style=\"mix-blend-mode:multiply\">\n<g id=\"Vector_67_2\" style=\"mix-blend-mode:multiply\">\n<g id=\"Vector_68\" style=\"mix-blend-mode:multiply\">\n<path d=\"M51.5501 388.14C48.7801 386.81 46.4901 385.21 45.0601 382.32C44.0601 380.37 44.4001 378.78 45.3201 376.81C46.2839 375.187 47.5541 373.768 49.0601 372.63C54.5627 368.144 61.1958 365.261 68.2301 364.3C70.1304 364.109 72.0413 364.046 73.9501 364.11C73.9501 365.7 73.9501 367.61 73.8601 369.26C73.7701 370.91 75.0201 372.64 75.2101 374.26C73.2701 374.75 71.2101 374.94 69.4501 375.46C64.9021 376.781 60.6372 378.93 56.8701 381.8C54.528 383.362 52.682 385.562 51.5501 388.14Z\" fill=\"#B4A8C3\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 129\" style=\"mix-blend-mode:multiply\">\n<g id=\"Vector_68_2\" style=\"mix-blend-mode:multiply\">\n<g id=\"Vector_69\" style=\"mix-blend-mode:multiply\">\n<path d=\"M10.7601 307.36L16.2501 310.52C16.1001 311.14 15.7401 311.78 15.5601 312.52C15.97 312.67 16.3914 312.787 16.8201 312.87C19.9656 313.315 22.9872 314.397 25.7001 316.05C27.9701 317.29 28.8901 318.87 29.7701 321.33C29.7701 321.33 30.3701 323.49 30.8701 325.33C30.9901 325.76 31.6801 328.02 31.8201 328.74C30.4301 328 29.0001 327 27.9001 326.34C26.2501 325.39 24.5701 324.5 22.9701 323.47C21.8222 322.8 20.5496 322.371 19.2301 322.21C14.9901 321.48 10.7501 320.71 6.51004 319.94C6.41004 319.94 6.33004 319.86 6.04004 319.71C7.51004 315.68 9.09004 311.47 10.7601 307.36Z\" fill=\"#B4A8C3\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 130\" style=\"mix-blend-mode:multiply\">\n<g id=\"Vector_69_2\" style=\"mix-blend-mode:multiply\">\n<g id=\"Vector_70\" style=\"mix-blend-mode:multiply\">\n<path d=\"M60.71 395C66.5772 395.34 72.4537 394.514 78 392.57V398.17C78.3888 398.271 78.7883 398.325 79.19 398.33C79.7195 398.26 80.2582 398.332 80.7504 398.539C81.2427 398.747 81.6706 399.082 81.99 399.51C82.84 400.51 83.79 401.39 84.78 402.4C76.97 405.47 68.92 405.03 60.78 404.9C60.58 401.6 60.66 398.43 60.71 395Z\" fill=\"#B4A8C3\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 131\" style=\"mix-blend-mode:multiply\">\n<g id=\"Vector_70_2\" style=\"mix-blend-mode:multiply\">\n<g id=\"Vector_71\" style=\"mix-blend-mode:multiply\">\n<path d=\"M94.8401 391.89V382C96.7937 380.169 97.9862 377.67 98.1801 375C98.5501 375.15 98.6901 375.81 98.9501 376C100.506 376.969 101.892 378.189 103.05 379.61C104.168 380.915 104.836 382.546 104.955 384.261C105.074 385.975 104.637 387.683 103.71 389.13C103.5 389.47 103.26 389.8 103.04 390.13C102.734 390.74 102.244 391.238 101.639 391.554C101.034 391.87 100.345 391.988 99.6701 391.89C98.0618 391.786 96.4484 391.786 94.8401 391.89Z\" fill=\"#B4A8C3\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 132\" style=\"mix-blend-mode:multiply\">\n<g id=\"Vector_71_2\" style=\"mix-blend-mode:multiply\">\n<g id=\"Vector_72\" style=\"mix-blend-mode:multiply\">\n<path d=\"M21.0001 298C21.7401 298.45 23.1701 299.16 23.7401 299.59C23.7797 299.834 23.8365 300.074 23.9101 300.31C24.4001 301.87 24.7701 303.47 25.2501 305.31C20.8801 304.64 16.7301 303.84 12.4401 303.01C14.6601 296.51 18.3301 289.85 19.4401 283.01C19.6701 283.92 20.0301 285.7 20.2701 286.61C20.8001 288.7 21.7501 292.61 22.3701 294.61C22.1981 295.125 21.9805 295.624 21.7201 296.1C21.4475 296.72 21.2071 297.355 21.0001 298Z\" fill=\"#B4A8C3\"\/>\n<\/g>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"shadows\" style=\"mix-blend-mode:multiply\" filter=\"url(#filter0_d)\">\n<g id=\"Vector5656231 133\" style=\"mix-blend-mode:multiply\" opacity=\"0.15\">\n<g id=\"Vector_72_2\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\" filter=\"url(#filter1_d)\">\n<g id=\"Vector_73\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\">\n<path d=\"M123.58 181.61C95.3599 186.23 79.7699 149.61 78.4199 143.52C79.0799 141.2 83.7899 135.86 86.9099 139.86C104.28 162.22 108.2 158.8 121.57 163.06C134.64 167.23 131.78 180.26 123.58 181.61Z\" fill=\"black\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 134\" style=\"mix-blend-mode:multiply\" opacity=\"0.15\">\n<g id=\"Vector_73_2\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\" filter=\"url(#filter2_d)\">\n<g id=\"Vector_74\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\">\n<path d=\"M167.18 156.56C169 153.95 162.95 142.05 159.7 143.56C137.87 153.77 131.62 160.83 114.39 160.69C103.53 160.6 110.59 176.11 115.01 180.96C129.72 187.87 159 168.28 167.18 156.56Z\" fill=\"black\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 135\" style=\"mix-blend-mode:multiply\" opacity=\"0.15\">\n<g id=\"Vector_74_2\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\" filter=\"url(#filter3_d)\">\n<g id=\"Vector_75\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\">\n<path d=\"M114.52 178.4C96.1599 173.2 87.0899 158.4 78.6899 142.84C78.5834 143.06 78.4932 143.287 78.4199 143.52C79.7699 149.58 95.3599 186.23 123.58 181.61C125.429 181.301 127.115 180.361 128.35 178.95C123.745 179.605 119.059 179.418 114.52 178.4Z\" fill=\"black\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 136\" style=\"mix-blend-mode:multiply\" opacity=\"0.15\">\n<g id=\"Vector_75_2\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\" filter=\"url(#filter4_d)\">\n<g id=\"Vector_76\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\">\n<path d=\"M114.52 178.4C113.89 178.22 113.3 178 112.7 177.79C113.37 178.926 114.139 180.001 115 181C129.71 187.91 159 168.32 167.17 156.6C167.54 156.07 164.76 147.53 164.57 146.42C150.92 161.17 136 179 114.52 178.4Z\" fill=\"black\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 137\" style=\"mix-blend-mode:multiply\" opacity=\"0.15\">\n<g id=\"Vector_76_2\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\" filter=\"url(#filter5_d)\">\n<g id=\"Vector_77\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\">\n<path d=\"M231.17 163.09C258.02 173.23 280.07 140.34 282.52 134.66C282.29 132.25 278.65 126.07 274.86 129.38C253.69 147.89 250.47 143.76 236.56 145.29C223 146.79 223.37 160.15 231.17 163.09Z\" fill=\"black\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 138\" style=\"mix-blend-mode:multiply\" opacity=\"0.15\">\n<g id=\"Vector_77_2\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\" filter=\"url(#filter6_d)\">\n<g id=\"Vector_78\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\">\n<path d=\"M238.62 159.75C237.25 158.33 238.98 151.56 238.34 145.12C237.76 145.12 237.17 145.22 236.56 145.29C222.96 146.79 223.37 160.15 231.17 163.09C258.02 173.23 280.07 140.34 282.52 134.66C282.52 134.53 282.52 134.38 282.45 134.23C267.16 143.71 256.6 164.83 238.62 159.75Z\" fill=\"black\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 139\" style=\"mix-blend-mode:multiply\" opacity=\"0.15\">\n<g id=\"Vector_78_2\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\" filter=\"url(#filter7_d)\">\n<g id=\"Vector_79\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\">\n<path d=\"M284.24 121.45C285.85 120.9 288.43 120.37 289.52 121.45C290.12 122.03 289.6 123.45 288.59 123.7C288.043 123.82 287.534 124.075 287.11 124.44C286.363 125.234 285.718 126.117 285.19 127.07L289.71 128.3L293.71 128.23C295.051 127.526 296.344 126.735 297.58 125.86C298.63 124.86 300.77 125.48 300.58 125.92C300.232 126.87 299.683 127.733 298.97 128.45C299.996 127.957 300.948 127.324 301.8 126.57C302.54 125.86 305.36 126.36 303.91 128.57C304.85 129.22 304.8 129.52 304.04 130.57C303.209 131.464 302.227 132.205 301.14 132.76C301.926 132.297 302.796 131.994 303.7 131.87C304.7 131.79 304.61 133.32 303.96 134.1C301.4 137.1 294.77 138.75 292.12 139.1C285.62 139.86 278.47 137.1 278.47 137.1L272.38 132.65C272.38 132.65 274.47 128.65 275.38 127.35C277.68 124.16 281.75 122.3 284.24 121.45Z\" fill=\"black\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 140\" style=\"mix-blend-mode:multiply\" opacity=\"0.15\">\n<g id=\"Vector_79_2\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\" filter=\"url(#filter8_d)\">\n<g id=\"Vector_80\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\">\n<path d=\"M196.69 284.79C194.46 309.79 198.96 344.79 202.69 360.7C206.42 376.61 212.69 363.52 213.58 359.7C216.01 349.15 218.09 296.15 218.27 286.7C218.53 271.4 197.11 280.18 196.69 284.79Z\" fill=\"black\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 141\" style=\"mix-blend-mode:multiply\" opacity=\"0.15\">\n<g id=\"Vector_80_2\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\" filter=\"url(#filter9_d)\">\n<g id=\"Vector_81\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\">\n<path d=\"M214.49 353.75C214.49 353.75 220.31 362.87 221.01 366.87C223.28 379.68 194.87 372.77 195.51 370.2C196.65 365.59 200.3 357.08 201.35 354.43C205.691 355.61 210.294 355.371 214.49 353.75Z\" fill=\"black\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 142\" style=\"mix-blend-mode:multiply\" opacity=\"0.15\">\n<g id=\"Vector_81_2\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\" filter=\"url(#filter10_d)\">\n<g id=\"Vector_82\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\">\n<path d=\"M195.48 368.68C196.36 365.44 198.88 360.47 199.99 356.84C199.99 357.42 199.11 362.64 200.85 364.02C205.49 362.37 210.18 363.18 214.79 363.02C216.15 361.45 215.6 357.09 215.31 355.46C215.31 355.46 219.85 363.31 221.01 366.86C223.41 374.15 222.42 375.69 220.91 377.86C220.91 379.03 220.46 379.13 220.46 379.13C220.46 379.13 217.13 379.6 208.01 379.8C203.12 379.91 195.68 379.92 195.68 379.92V378.42C193.63 376.12 194.83 371 195.48 368.68Z\" fill=\"black\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 143\" style=\"mix-blend-mode:multiply\" opacity=\"0.15\">\n<g id=\"Vector_82_2\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\" filter=\"url(#filter11_d)\">\n<g id=\"Vector_83\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\">\n<path d=\"M215.3 362.05C215.96 360.1 215.55 356.84 215.3 355.47C215.3 355.47 219.84 363.32 221 366.87C223.4 374.16 222.41 375.7 220.9 377.87C220.9 379.04 220.45 379.14 220.45 379.14C220.45 379.14 219.15 379.32 215.98 379.51C217.388 373.741 217.153 367.692 215.3 362.05Z\" fill=\"black\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 144\" style=\"mix-blend-mode:multiply\" opacity=\"0.15\">\n<g id=\"Vector_83_2\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\" filter=\"url(#filter12_d)\">\n<g id=\"Vector_84\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\">\n<path d=\"M200.16 378.51C204.65 378.51 209.16 378.8 213.68 378.38C215.59 378.19 218.68 378.24 221.1 377.56C221.042 377.657 220.979 377.751 220.91 377.84C220.91 379.01 220.46 379.11 220.46 379.11C220.46 379.11 217.13 379.58 208.01 379.78C203.12 379.89 195.68 379.9 195.68 379.9V378.42C197.17 378.537 198.666 378.567 200.16 378.51Z\" fill=\"black\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 145\" style=\"mix-blend-mode:multiply\" opacity=\"0.15\">\n<g id=\"Vector_84_2\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\" filter=\"url(#filter13_d)\">\n<g id=\"Vector_85\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\">\n<path d=\"M202.36 368.63C202.46 368.626 202.559 368.602 202.65 368.56C206.87 366.38 210.83 366.24 214.42 368.15C214.498 368.191 214.583 368.215 214.67 368.222C214.758 368.229 214.846 368.218 214.929 368.19C215.012 368.162 215.089 368.117 215.154 368.059C215.22 368.001 215.273 367.929 215.31 367.85C215.392 367.688 215.407 367.5 215.353 367.326C215.299 367.153 215.18 367.007 215.02 366.92C211.02 364.8 206.68 364.92 202.02 367.32C201.86 367.407 201.74 367.552 201.685 367.725C201.629 367.898 201.641 368.086 201.72 368.25C201.777 368.37 201.868 368.469 201.982 368.537C202.096 368.605 202.228 368.637 202.36 368.63Z\" fill=\"black\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 146\" style=\"mix-blend-mode:multiply\" opacity=\"0.15\">\n<g id=\"Vector_85_2\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\" filter=\"url(#filter14_d)\">\n<g id=\"Vector_86\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\">\n<path d=\"M205.74 371.14C205.862 371.139 205.98 371.103 206.083 371.038C206.185 370.973 206.268 370.88 206.32 370.77C206.63 370.55 209.99 369.53 211.9 370.51C211.979 370.55 212.065 370.574 212.154 370.579C212.242 370.585 212.331 370.572 212.414 370.542C212.497 370.512 212.574 370.465 212.638 370.405C212.703 370.344 212.755 370.271 212.79 370.19C212.871 370.028 212.884 369.841 212.828 369.669C212.772 369.496 212.651 369.353 212.49 369.27C210.03 368.01 205.63 369.12 205.13 370.14C205.048 370.302 205.033 370.49 205.087 370.664C205.141 370.837 205.26 370.983 205.42 371.07C205.518 371.123 205.629 371.147 205.74 371.14Z\" fill=\"black\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 147\" style=\"mix-blend-mode:multiply\" opacity=\"0.15\">\n<g id=\"Vector_86_2\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\" filter=\"url(#filter15_d)\">\n<g id=\"Vector_87\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\">\n<path d=\"M173.78 291.17C173.13 285.92 154.33 271.07 153.14 287.17C151.41 310.41 152.94 361.07 154.43 367.47C155.92 373.87 161.21 371.52 162.68 368.58C164.15 365.64 178.37 328.46 173.78 291.17Z\" fill=\"black\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 148\" style=\"mix-blend-mode:multiply\" opacity=\"0.15\">\n<g id=\"Vector_87_2\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\" filter=\"url(#filter16_d)\">\n<g id=\"Vector_88\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\">\n<path d=\"M167.58 353.79C167.58 353.79 169.22 362.35 168.71 366.08C168.2 369.81 146 367.27 146 367.27C146 367.27 149.38 360.27 154 356.83C165.67 357.09 167.58 353.79 167.58 353.79Z\" fill=\"black\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 149\" style=\"mix-blend-mode:multiply\" opacity=\"0.15\">\n<g id=\"Vector_88_2\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\" filter=\"url(#filter17_d)\">\n<g id=\"Vector_89\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\">\n<path d=\"M168 355.18C167.91 355.6 167.8 356.02 167.68 356.46C166.49 360.92 162.2 361.9 159.32 362.34C155.52 361.7 151.41 360.15 150.24 360.23C143.97 365.84 142.24 365.29 137.53 368.92C134 371.66 134.04 374.81 133.77 376.92C133.35 380.28 136.6 380.15 145.05 380.22C152.16 380.28 168.05 379.67 169.67 378.13C169.952 377.35 169.997 376.505 169.8 375.7C173.06 370.83 168.94 358.53 168 355.18Z\" fill=\"black\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 150\" style=\"mix-blend-mode:multiply\" opacity=\"0.15\">\n<g id=\"Vector_89_2\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\" filter=\"url(#filter18_d)\">\n<g id=\"Vector_90\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\">\n<path d=\"M159.38 374C162.013 370.224 163.467 365.752 163.56 361.15C164.561 360.734 165.451 360.09 166.161 359.271C166.87 358.452 167.38 357.48 167.65 356.43C167.77 355.99 167.88 355.57 167.97 355.15C168.97 358.5 173.06 370.8 169.77 375.71C169.967 376.515 169.922 377.36 169.64 378.14C168.43 379.28 159.4 379.91 151.91 380.14C154.891 378.776 157.465 376.66 159.38 374Z\" fill=\"black\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 151\" style=\"mix-blend-mode:multiply\" opacity=\"0.15\">\n<g id=\"Vector_90_2\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\" filter=\"url(#filter19_d)\">\n<g id=\"Vector_91\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\">\n<path d=\"M133.77 376.48C138.18 378.65 144.03 378.81 153.63 378.48C158.57 378.31 165.63 378.76 169.79 375.69C169.965 376.69 169.907 377.716 169.62 378.69C167.99 380.23 152.09 380.2 144.98 380.09C134.76 379.94 133.32 380.35 133.74 376.99C133.761 376.821 133.771 376.65 133.77 376.48Z\" fill=\"black\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 152\" style=\"mix-blend-mode:multiply\" opacity=\"0.15\">\n<g id=\"Vector_91_2\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\" filter=\"url(#filter20_d)\">\n<g id=\"Vector_92\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\">\n<path d=\"M156.24 368.44C156.333 368.439 156.426 368.418 156.51 368.378C156.595 368.339 156.67 368.281 156.73 368.21C156.857 368.075 156.928 367.896 156.928 367.71C156.928 367.524 156.857 367.345 156.73 367.21C153.35 364.04 148.95 362.91 143.67 363.86C143.491 363.896 143.333 364.001 143.23 364.153C143.127 364.304 143.088 364.49 143.12 364.67C143.132 364.761 143.162 364.848 143.209 364.927C143.256 365.005 143.318 365.074 143.392 365.128C143.465 365.182 143.549 365.221 143.638 365.242C143.727 365.263 143.82 365.266 143.91 365.25C148.75 364.38 152.76 365.39 155.82 368.25C155.932 368.363 156.081 368.43 156.24 368.44Z\" fill=\"black\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 153\" style=\"mix-blend-mode:multiply\" opacity=\"0.15\">\n<g id=\"Vector_92_2\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\" filter=\"url(#filter21_d)\">\n<g id=\"Vector_93\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\">\n<path d=\"M149.4 369.72C149.495 369.716 149.589 369.693 149.675 369.652C149.761 369.61 149.837 369.552 149.9 369.48C150.019 369.337 150.08 369.154 150.069 368.968C150.057 368.782 149.976 368.608 149.84 368.48C147.79 366.62 143.04 366.38 142.28 367.19C142.153 367.325 142.082 367.504 142.082 367.69C142.082 367.876 142.153 368.055 142.28 368.19C142.341 368.263 142.417 368.323 142.504 368.363C142.59 368.404 142.685 368.425 142.78 368.425C142.875 368.425 142.97 368.404 143.056 368.363C143.143 368.323 143.219 368.263 143.28 368.19C143.77 368.02 147.38 368.1 148.97 369.55C149.09 369.654 149.242 369.714 149.4 369.72Z\" fill=\"black\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 154\" style=\"mix-blend-mode:multiply\" opacity=\"0.15\">\n<g id=\"Vector_93_2\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\" filter=\"url(#filter22_d)\">\n<g id=\"Vector_94\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\">\n<path d=\"M215.43 223.67C222.88 265.11 219.78 268.58 220.63 299.67C220.99 312.4 219.63 340.78 218.4 347.72C209.4 355.72 194.74 348.93 194.74 348.93C194.74 348.93 190.01 312.93 188.42 300.99C186.62 287.34 178.6 227.76 178.6 227.76L215.43 223.67Z\" fill=\"black\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 155\" style=\"mix-blend-mode:multiply\" opacity=\"0.15\">\n<g id=\"Vector_94_2\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\" filter=\"url(#filter23_d)\">\n<g id=\"Vector_95\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\">\n<path d=\"M220.63 299.62C219.78 268.62 222.88 265.11 215.43 223.62L178.6 227.62L182 253.16C191.8 252.87 201.71 251.86 211.62 251.16C209.96 283.92 214.43 318.28 210.85 351.29C213.647 350.825 216.257 349.58 218.38 347.7C219.59 340.73 221 312.35 220.63 299.62Z\" fill=\"black\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 156\" style=\"mix-blend-mode:multiply\" opacity=\"0.15\">\n<g id=\"Vector_95_2\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\" filter=\"url(#filter24_d)\">\n<g id=\"Vector_96\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\">\n<path d=\"M210.73 253.24C204.64 251.37 203.27 243.97 202.73 238.38C202.73 238.29 202.694 238.203 202.63 238.14C202.567 238.076 202.48 238.04 202.39 238.04C202.3 238.04 202.213 238.076 202.15 238.14C202.086 238.203 202.05 238.29 202.05 238.38C201.39 245.46 201.91 251.89 208.49 255.61C210.31 256.612 212.327 257.204 214.399 257.346C216.472 257.488 218.551 257.175 220.49 256.43C220.403 255.343 220.259 254.262 220.06 253.19C217.016 254.083 213.783 254.1 210.73 253.24Z\" fill=\"black\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 157\" style=\"mix-blend-mode:multiply\" opacity=\"0.15\">\n<g id=\"Vector_96_2\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\" filter=\"url(#filter25_d)\">\n<g id=\"Vector_97\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\">\n<path d=\"M150.72 223.94C150.72 223.94 145.1 266.05 145.1 287.49C145.1 310.97 151.84 352.3 151.84 352.3C151.84 352.3 166.84 354.94 171.17 350.44C173.07 345.55 174.33 307.03 175.67 294.02C177.01 281.01 186.84 228.45 186.84 228.45L150.72 223.94Z\" fill=\"black\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 158\" style=\"mix-blend-mode:multiply\" opacity=\"0.15\">\n<g id=\"Vector_97_2\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\" filter=\"url(#filter26_d)\">\n<g id=\"Vector_98\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\">\n<path d=\"M165.78 352.72C167.769 352.534 169.652 351.738 171.17 350.44C173.07 345.55 174.33 307.03 175.67 294.02C176.3 287.9 178.78 273.23 181.23 259.32C164.67 286.84 169.34 321.68 165.78 352.72Z\" fill=\"black\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 159\" style=\"mix-blend-mode:multiply\" opacity=\"0.15\">\n<g id=\"Vector_98_2\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\" filter=\"url(#filter27_d)\">\n<g id=\"Vector_99\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\">\n<path d=\"M150.72 223.94C150.72 223.94 149.2 235.37 147.72 249.35C158.98 252.83 170.57 253.52 182.32 253.15C184.72 239.74 186.83 228.45 186.83 228.45L150.72 223.94Z\" fill=\"black\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 160\" style=\"mix-blend-mode:multiply\" opacity=\"0.15\">\n<g id=\"Vector_99_2\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\" filter=\"url(#filter28_d)\">\n<g id=\"Vector_100\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\">\n<path d=\"M157.9 240.19C157.82 239.96 157.43 239.97 157.46 240.25C158.07 245.3 155.32 250.17 152.2 253.83C150.919 255.469 149.051 256.545 146.99 256.83C146.9 257.99 146.89 259.18 146.89 260.36C154.41 259.78 160.58 247.47 157.9 240.19Z\" fill=\"black\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 161\" style=\"mix-blend-mode:multiply\" opacity=\"0.15\">\n<g id=\"Vector_100_2\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\" filter=\"url(#filter29_d)\">\n<g id=\"Vector_101\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\">\n<path d=\"M233.67 142.73C233.67 142.73 230.76 172.57 228.27 172.57C225.78 172.57 187 162.57 187.14 155.57C189.23 150.42 191.7 132.07 199.95 133.42C212.76 135.5 221.29 138.66 233.67 142.73Z\" fill=\"black\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 162\" style=\"mix-blend-mode:multiply\" opacity=\"0.15\">\n<g id=\"Vector_101_2\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\" filter=\"url(#filter30_d)\">\n<g id=\"Vector_102\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\">\n<path d=\"M129.58 155.55C129.58 155.55 136.67 182.72 139.03 181.89C141.39 181.06 171.36 167.89 169.08 161.3C172.97 148.87 171.7 133.39 160.98 135.5C152.57 137.16 139.93 149.49 129.58 155.55Z\" fill=\"black\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 163\" style=\"mix-blend-mode:multiply\" opacity=\"0.15\">\n<g id=\"Vector_102_2\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\" filter=\"url(#filter31_d)\">\n<g id=\"Vector_103\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\">\n<path d=\"M211 137.68C211 135.54 193 130.32 180.46 130.53C166.65 130.76 153.91 138.13 153.8 140.16C152.58 162.32 149.6 219.16 145.63 240.31C161.11 249.92 194.54 250.12 219.79 238.69C213.14 216 211 156.64 211 137.68Z\" fill=\"black\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 164\" style=\"mix-blend-mode:multiply\" opacity=\"0.15\">\n<g id=\"Vector_103_2\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\" filter=\"url(#filter32_d)\">\n<g id=\"Vector_104\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\">\n<path d=\"M219.78 238.69C213.14 216.01 211.04 156.64 210.99 137.69C210.99 136.69 207.16 135.07 201.82 133.6C206.63 173.55 204.82 220.66 176.4 247.4C190.55 247.57 206.33 244.78 219.78 238.69Z\" fill=\"black\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 165\" style=\"mix-blend-mode:multiply\" opacity=\"0.15\">\n<g id=\"Vector_104_2\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\" filter=\"url(#filter33_d)\">\n<g id=\"Vector_105\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\">\n<path d=\"M175.11 143C173.307 140.397 171.921 137.529 171 134.5C170.71 133.55 170.55 132.5 170.31 131.42C173.655 130.887 177.033 130.59 180.42 130.53C184.171 130.468 187.924 130.608 191.66 130.95C190.71 138 181.23 152 175.11 143Z\" fill=\"black\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 166\" style=\"mix-blend-mode:multiply\" opacity=\"0.15\">\n<g id=\"Vector_105_2\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\" filter=\"url(#filter34_d)\">\n<g id=\"Vector_106\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\">\n<path d=\"M181.49 23.3699C170.25 18.6299 161.24 19.6699 153.71 25.1299C152.79 25.7199 151.86 26.3099 150.9 26.8899C146.859 29.4334 142.558 31.5386 138.07 33.1699C136.56 33.6799 141.41 37.0199 143.19 36.8399C141.99 38.7199 140.83 40.7199 139.7 42.8399C137.7 46.6999 132.37 58.9799 130.36 62.0699C129.51 63.3699 135.63 63.4599 137.14 62.5099C139.14 69.5099 143.34 77.4299 144.2 93.5099C144.2 93.5099 213.72 106.68 215.84 90.7099C217.23 80.1699 222.13 75.1699 224.53 64.9199C230.52 34.1699 196.78 16.5299 181.49 23.3699Z\" fill=\"black\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 167\" style=\"mix-blend-mode:multiply\" opacity=\"0.15\">\n<g id=\"Vector_106_2\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\" filter=\"url(#filter35_d)\">\n<g id=\"Vector_107\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\">\n<path d=\"M188.9 118.2L188.91 133.19L171.8 134.17L172.05 121.71L188.9 118.2Z\" fill=\"black\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 168\" style=\"mix-blend-mode:multiply\" opacity=\"0.15\">\n<g id=\"Vector_107_2\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\" filter=\"url(#filter36_d)\">\n<g id=\"Vector_108\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\">\n<path d=\"M171.93 127.81L172.05 121.71L188.89 118.2V127.2C181.19 130.09 173.49 128.49 171.93 127.81Z\" fill=\"black\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 169\" style=\"mix-blend-mode:multiply\" opacity=\"0.15\">\n<g id=\"Vector_108_2\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\" filter=\"url(#filter37_d)\">\n<g id=\"Vector_109\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\">\n<path d=\"M227.54 74.8699C223.54 71.8699 219.07 74.5899 216.69 78.2399C212.51 81.2399 209.03 87.4599 211.78 91.7199C215.1 96.8399 223.15 93.5399 226.62 90.3199C230.82 86.4199 232.81 78.8199 227.54 74.8699Z\" fill=\"black\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 170\" style=\"mix-blend-mode:multiply\" opacity=\"0.15\">\n<g id=\"Vector_109_2\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\" filter=\"url(#filter38_d)\">\n<g id=\"Vector_110\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\">\n<path d=\"M225.53 78C223.99 77.83 222.08 79.43 221.63 80.78C221.31 81.7988 221.31 82.8912 221.63 83.91C221.98 85.19 222.27 86.69 220.54 87.24C220.284 87.349 220.078 87.5484 219.96 87.8C219.923 87.8638 219.904 87.9363 219.904 88.01C219.904 88.0837 219.923 88.1562 219.96 88.22C220.01 88.31 220.05 88.4 220.09 88.49C220.203 88.6407 220.36 88.7519 220.54 88.8076C220.719 88.8633 220.912 88.8606 221.09 88.8C221.577 88.6541 222.028 88.4066 222.412 88.0739C222.797 87.7412 223.106 87.3308 223.321 86.8698C223.535 86.4088 223.65 85.9075 223.657 85.3991C223.663 84.8906 223.562 84.3866 223.36 83.92C222.78 82.19 222.72 81.04 224.22 79.79C224.81 79.31 225.59 78.89 225.55 78.1C225.556 78.0831 225.557 78.0648 225.554 78.0473C225.55 78.0297 225.542 78.0133 225.53 78Z\" fill=\"black\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 171\" style=\"mix-blend-mode:multiply\" opacity=\"0.15\">\n<g id=\"Vector_110_2\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\" filter=\"url(#filter39_d)\">\n<g id=\"Vector_111\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\">\n<path d=\"M136.17 80.45C139.29 76.79 143.43 78.7301 145.89 81.9101C149.81 84.1701 153.5 89.69 151.6 94.36C149.32 99.96 142.03 98.09 138.69 95.5C134.64 92.38 132.08 85.24 136.17 80.45Z\" fill=\"black\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 172\" style=\"mix-blend-mode:multiply\" opacity=\"0.15\">\n<g id=\"Vector_111_2\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\" filter=\"url(#filter40_d)\">\n<g id=\"Vector_112\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\">\n<path d=\"M138.25 83.1501C139.56 82.7301 141.38 83.9701 141.92 85.2201C142.293 86.205 142.4 87.2706 142.23 88.31C142.07 89.64 141.98 91.1601 143.53 91.4001C143.8 91.4001 143.94 91.6601 144.1 91.8601C144.132 91.9255 144.148 91.9972 144.148 92.07C144.148 92.1427 144.132 92.2146 144.1 92.28C144.1 92.38 144.04 92.47 144.02 92.56C143.955 92.7191 143.84 92.8526 143.692 92.9394C143.543 93.0262 143.37 93.0616 143.2 93.0401C141.2 92.7301 140.35 90.7301 140.71 88.6201C141.01 86.8201 140.94 85.62 139.5 84.7C138.95 84.33 138.23 84.05 138.17 83.27C138.167 83.2437 138.173 83.2171 138.188 83.195C138.202 83.173 138.224 83.1571 138.25 83.1501Z\" fill=\"black\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 173\" style=\"mix-blend-mode:multiply\" opacity=\"0.15\">\n<g id=\"Vector_112_2\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\" filter=\"url(#filter41_d)\">\n<g id=\"Vector_113\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\">\n<path d=\"M146.16 50.15C144.679 63.0959 143.991 76.1202 144.1 89.15C144.31 101.54 150.81 113.92 159.41 120.08C174.88 131.16 195.74 124.17 204.49 115.17C218 101.3 220.8 84.81 214.88 50.79C212.66 49 146.16 50.15 146.16 50.15Z\" fill=\"black\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 174\" style=\"mix-blend-mode:multiply\" opacity=\"0.15\">\n<g id=\"Vector_113_2\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\" filter=\"url(#filter42_d)\">\n<g id=\"Vector_114\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\">\n<path d=\"M196.4 115.58C205.49 108.77 211.1 100.1 211.66 86.18C212.11 74.64 211.89 61.88 205.95 50.01C211 50.16 214.41 50.41 214.88 50.79C220.8 84.79 217.98 101.3 204.49 115.17C195.74 124.17 174.88 131.17 159.41 120.08C158.69 119.57 157.98 118.98 157.29 118.38C170.16 123.18 184.82 124.26 196.4 115.58Z\" fill=\"black\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 175\" style=\"mix-blend-mode:multiply\" opacity=\"0.15\">\n<g id=\"Vector_114_2\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\" filter=\"url(#filter43_d)\">\n<g id=\"Vector_115\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\">\n<path d=\"M203.53 87.4201C203.848 87.2425 204.085 86.9486 204.192 86.5999C204.298 86.2513 204.265 85.875 204.1 85.5501C203.517 84.2414 202.573 83.1254 201.38 82.3323C200.187 81.5391 198.793 81.1014 197.36 81.0701C194.57 81.1701 192.57 83.1801 191.18 85.8301C191.006 86.1508 190.964 86.5267 191.063 86.8778C191.162 87.2289 191.394 87.5276 191.71 87.7101C192.36 88.0701 193.61 83.9501 197.89 84.2701C201.07 84.5101 203.37 87.5001 203.53 87.4201Z\" fill=\"black\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 176\" style=\"mix-blend-mode:multiply\" opacity=\"0.15\">\n<g id=\"Vector_115_2\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\" filter=\"url(#filter44_d)\">\n<g id=\"Vector_116\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\">\n<path d=\"M164.52 88.1999C164.688 88.1887 164.852 88.1409 165 88.0599C165.32 87.8841 165.559 87.5902 165.665 87.2409C165.772 86.8915 165.738 86.5144 165.57 86.1899C165.006 84.8806 164.081 83.7587 162.904 82.9549C161.726 82.151 160.345 81.6985 158.92 81.6499C156.11 81.7499 154.06 83.8099 152.66 86.4699C152.489 86.7896 152.449 87.1631 152.548 87.5119C152.646 87.8606 152.877 88.1575 153.19 88.3399C153.83 88.7099 154.95 85.1499 159.36 84.9099C163.53 84.6799 164 88.2599 164.52 88.1999Z\" fill=\"black\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 177\" style=\"mix-blend-mode:multiply\" opacity=\"0.15\">\n<g id=\"Vector_116_2\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\" filter=\"url(#filter45_d)\">\n<g id=\"Vector_117\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\">\n<path d=\"M198 72.23C199.67 72.11 202.17 73.47 202.63 75.35C202.63 75.54 202.5 75.75 202.3 75.68C201.15 75.25 200.01 74.52 198.72 74.6C198.15 74.6 195.99 74.77 195.65 75.33C195.31 75.89 193.94 76.2 193.82 75.33C193.57 73.43 196.74 72.32 198 72.23Z\" fill=\"black\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 178\" style=\"mix-blend-mode:multiply\" opacity=\"0.15\">\n<g id=\"Vector_117_2\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\" filter=\"url(#filter46_d)\">\n<g id=\"Vector_118\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\">\n<path d=\"M155 74.5101C158.14 72.6301 162.29 73.3701 163.34 77.0401C163.356 77.0933 163.358 77.15 163.345 77.2042C163.332 77.2584 163.305 77.3081 163.266 77.348C163.227 77.3879 163.178 77.4166 163.124 77.431C163.07 77.4455 163.014 77.4452 162.96 77.4301C161.65 77.0201 160.62 76.2401 159.21 76.0501C157.8 75.8601 156.81 77.0501 155.54 76.9301C155.278 76.8852 155.035 76.7634 154.843 76.5802C154.65 76.397 154.516 76.1606 154.458 75.9012C154.401 75.6417 154.421 75.371 154.518 75.1232C154.614 74.8755 154.782 74.6621 155 74.5101Z\" fill=\"black\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 179\" style=\"mix-blend-mode:multiply\" opacity=\"0.15\">\n<g id=\"Vector_118_2\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\" filter=\"url(#filter47_d)\">\n<g id=\"Vector_119\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\">\n<path d=\"M168 104.86C168 104.86 170.06 113.12 176 113.69C186.46 114.69 187.23 104.69 187.23 104.69L168 104.86Z\" fill=\"black\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 180\" style=\"mix-blend-mode:multiply\" opacity=\"0.15\">\n<g id=\"Vector_119_2\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\" filter=\"url(#filter48_d)\">\n<g id=\"Vector_120\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\">\n<path d=\"M184.61 107.4C185.202 107.146 185.738 106.778 186.188 106.316C186.637 105.854 186.992 105.309 187.23 104.71L170.42 104.85C173.74 108.73 178.36 109.56 184.61 107.4Z\" fill=\"black\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 181\" style=\"mix-blend-mode:multiply\" opacity=\"0.15\">\n<g id=\"Vector_120_2\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\" filter=\"url(#filter49_d)\">\n<g id=\"Vector_121\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\">\n<path d=\"M184.17 111.26C181.55 110.72 177.99 110.89 176.02 112.26C175.526 112.582 175.095 112.992 174.75 113.47C175.157 113.599 175.576 113.686 176 113.73C179.94 114.06 182.5 112.87 184.17 111.26Z\" fill=\"black\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 182\" style=\"mix-blend-mode:multiply\" opacity=\"0.15\">\n<g id=\"Vector_121_2\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\" filter=\"url(#filter50_d)\">\n<g id=\"Vector_122\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\">\n<path d=\"M176.87 83.28C176.87 83.28 176.61 88.1 174.7 89.74C172.79 91.38 171.83 92.14 171.98 94.74C172.06 96.1 174.26 98.01 176.4 98.01C172.69 98.82 171.01 96.72 170.9 94.94C170.71 92.1 171.29 91.13 173.9 88.76C175.54 87.28 176.87 83.28 176.87 83.28Z\" fill=\"black\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 183\" style=\"mix-blend-mode:multiply\" opacity=\"0.15\">\n<g id=\"Vector_122_2\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\" filter=\"url(#filter51_d)\">\n<g id=\"Vector_123\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\">\n<path d=\"M216.81 46.68C207.94 32.81 152.69 36.96 148.44 40.13C132.73 51.81 134.87 71.52 137.68 77.69C137.68 74.69 142.92 71.3 147.79 69.3C149.267 68.6947 150.78 68.1804 152.32 67.76C150.5 70.23 149.14 72.95 149.14 75.59C155.51 71.49 166.74 70.79 172.26 68.18C172.965 71.4739 174.326 74.5923 176.26 77.35C176.05 74.01 179.33 68.9 188.36 67.13C186.67 69.72 185.29 72.24 185.8 72.56C193.36 71.19 204.85 69.15 208.2 65.63C210.99 68.19 213.49 70.04 213.38 77.54C225.66 70.31 221.49 53.65 216.81 46.68Z\" fill=\"black\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 184\" style=\"mix-blend-mode:multiply\" opacity=\"0.15\">\n<g id=\"Vector_123_2\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\" filter=\"url(#filter52_d)\">\n<g id=\"Vector_124\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\">\n<path d=\"M181.53 47C176.4 49.66 172.98 56.08 174.58 62C174.603 62.1155 174.666 62.2194 174.757 62.2941C174.848 62.3687 174.962 62.4095 175.08 62.4095C175.198 62.4095 175.312 62.3687 175.403 62.2941C175.494 62.2194 175.557 62.1155 175.58 62C176.71 56.44 177.51 51.41 181.89 47.46C182.12 47.21 181.8 46.84 181.53 47Z\" fill=\"black\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 185\" style=\"mix-blend-mode:multiply\" opacity=\"0.15\">\n<g id=\"Vector_124_2\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\" filter=\"url(#filter53_d)\">\n<g id=\"Vector_125\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\">\n<path d=\"M170.25 45.2701C167.42 54.0501 160.47 59.5901 154.49 65.9801C154.442 66.0294 154.414 66.0941 154.409 66.1625C154.405 66.231 154.425 66.2988 154.465 66.354C154.506 66.4091 154.565 66.4481 154.632 66.4638C154.699 66.4796 154.769 66.4712 154.83 66.4401C158.805 64.2288 162.284 61.2234 165.048 57.6107C167.813 53.998 169.805 49.8553 170.9 45.4401C170.92 45.3951 170.929 45.3464 170.928 45.2973C170.927 45.2482 170.916 45.2 170.894 45.1558C170.873 45.1117 170.842 45.0727 170.804 45.0415C170.766 45.0104 170.722 44.9878 170.674 44.9754C170.627 44.963 170.577 44.961 170.529 44.9696C170.481 44.9782 170.435 44.9971 170.394 45.0251C170.354 45.0531 170.32 45.0895 170.295 45.1318C170.27 45.1741 170.255 45.2213 170.25 45.2701Z\" fill=\"black\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 186\" style=\"mix-blend-mode:multiply\" opacity=\"0.15\">\n<g id=\"Vector_125_2\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\" filter=\"url(#filter54_d)\">\n<g id=\"Vector_126\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\">\n<path d=\"M161.39 51.7699C160.11 54.5699 157.8 56.3399 156.1 58.7699C155.88 59.0899 156.25 59.5899 156.61 59.4499C159.61 58.2599 161.11 54.9599 161.8 51.9099C161.86 51.7099 161.5 51.5299 161.39 51.7699Z\" fill=\"black\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 187\" style=\"mix-blend-mode:multiply\" opacity=\"0.15\">\n<g id=\"Vector_126_2\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\" filter=\"url(#filter55_d)\">\n<g id=\"Vector_127\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\">\n<path d=\"M203.09 37.8201C203.064 37.7885 203.028 37.7671 202.988 37.7598C202.948 37.7526 202.907 37.7599 202.872 37.7804C202.837 37.801 202.81 37.8335 202.797 37.8719C202.784 37.9104 202.785 37.9523 202.8 37.9901C204.697 41.4486 205.749 45.3071 205.87 49.2501C206.03 53.2501 204.34 56.7801 203 60.4401C202.79 61.0301 203.56 61.3601 203.95 61.0101C210.32 55.1801 207.25 44.0001 203.09 37.8201Z\" fill=\"black\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 188\" style=\"mix-blend-mode:multiply\" opacity=\"0.15\">\n<g id=\"Vector_127_2\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\" filter=\"url(#filter56_d)\">\n<g id=\"Vector_128\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\">\n<path d=\"M201.29 46.5199C201.2 46.3599 200.91 46.4599 200.98 46.6499C201.771 48.6174 201.88 50.7931 201.29 52.8299C200.86 54.5199 199.96 56.0099 199.57 57.6899C199.546 57.7743 199.55 57.8642 199.582 57.9459C199.614 58.0275 199.672 58.0964 199.747 58.1419C199.822 58.1874 199.91 58.2069 199.997 58.1975C200.085 58.1881 200.166 58.1503 200.23 58.0899C203.42 55.2299 203.44 49.9999 201.29 46.5199Z\" fill=\"black\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 189\" style=\"mix-blend-mode:multiply\" opacity=\"0.15\">\n<g id=\"Vector_128_2\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\" filter=\"url(#filter57_d)\">\n<g id=\"Vector_129\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\">\n<path d=\"M174.25 24.57C167.13 23.04 158.75 27.52 154.33 33.18C154 33.61 154.45 34.39 154.95 34.01C160.65 29.67 167 25.88 174.17 25.14C174.47 25.11 174.58 24.64 174.25 24.57Z\" fill=\"black\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 190\" style=\"mix-blend-mode:multiply\" opacity=\"0.15\">\n<g id=\"Vector_129_2\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\" filter=\"url(#filter58_d)\">\n<g id=\"Vector_130\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\">\n<path d=\"M217.83 47.4199C217.72 47.1899 217.32 47.3599 217.42 47.5999C220.01 54.2199 219.53 60.5299 217.86 67.3199C217.75 67.7599 218.39 68.0799 218.57 67.6399C221.38 60.8499 220.93 54.0499 217.83 47.4199Z\" fill=\"black\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 191\" style=\"mix-blend-mode:multiply\" opacity=\"0.15\">\n<g id=\"Vector_130_2\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\" filter=\"url(#filter59_d)\">\n<g id=\"Vector_131\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\">\n<path d=\"M147.93 47.0601C141.57 53.1201 136.23 65.1801 139.11 74.1301C139.155 74.2692 139.247 74.3881 139.371 74.4657C139.495 74.5434 139.642 74.5748 139.787 74.5545C139.931 74.5342 140.064 74.4634 140.162 74.3546C140.259 74.2459 140.315 74.1061 140.32 73.9601C141.07 64.5501 141.97 54.8601 148.25 47.4001C148.44 47.1701 148.15 46.8601 147.93 47.0601Z\" fill=\"black\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 192\" style=\"mix-blend-mode:multiply\" opacity=\"0.15\">\n<g id=\"Vector_131_2\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\" filter=\"url(#filter60_d)\">\n<g id=\"Vector_132\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\">\n<path d=\"M74.55 130.64C74.55 130.64 85.77 140.41 85.4 142.64C84.97 145.26 82.8199 148.95 80.6799 148.79C78.5399 148.63 71.8099 148.98 70.8399 147.63C69.8699 146.28 67.9099 130.29 69.5399 129.63C71.1699 128.97 74.55 130.64 74.55 130.64Z\" fill=\"black\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 193\" style=\"mix-blend-mode:multiply\" opacity=\"0.15\">\n<g id=\"Vector_132_2\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\" filter=\"url(#filter61_d)\">\n<g id=\"Vector_133\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\">\n<path d=\"M82.7799 145C81.2099 145.28 78.1799 142.28 77.4199 140.84C76.2974 138.766 75.7032 136.448 75.6899 134.09C75.6899 134.09 74.8899 132.43 69.4799 131.58C65.6099 130.97 65.7199 125.94 67.1499 126.2C73.3699 127.36 75.7499 126.83 78.0599 128.66C80.3699 130.49 85.3199 136.8 85.7799 141.74C85.9999 143.69 84.6599 144.64 82.7799 145Z\" fill=\"black\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 194\" style=\"mix-blend-mode:multiply\" opacity=\"0.15\">\n<g id=\"Vector_133_2\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\" filter=\"url(#filter62_d)\">\n<g id=\"Vector_134\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\">\n<path d=\"M192.64 131C192.585 130.783 192.467 130.588 192.301 130.438C192.134 130.289 191.926 130.194 191.705 130.163C191.483 130.133 191.258 130.17 191.057 130.269C190.857 130.369 190.69 130.526 190.58 130.72C188.14 135.37 187.05 140.31 182.33 143.34C176.02 147.34 170.51 134.79 170.05 130.22C170.057 130.186 170.057 130.152 170.049 130.119C170.041 130.085 170.025 130.054 170.004 130.028C169.982 130.001 169.955 129.979 169.924 129.965C169.893 129.95 169.859 129.942 169.825 129.942C169.791 129.942 169.757 129.95 169.726 129.965C169.695 129.979 169.668 130.001 169.646 130.028C169.625 130.054 169.609 130.085 169.601 130.119C169.593 130.152 169.593 130.186 169.6 130.22C169.04 137.52 172.93 145.77 180.6 146.5C186.42 147.05 193.33 136.25 192.64 131Z\" fill=\"black\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 195\" style=\"mix-blend-mode:multiply\" opacity=\"0.15\">\n<g id=\"Vector_134_2\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\" filter=\"url(#filter63_d)\">\n<g id=\"Vector_135\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\">\n<path d=\"M140.34 179.53C132.06 174.14 133.5 161.44 129.16 153.7C129.131 153.642 129.083 153.597 129.025 153.57C128.966 153.544 128.9 153.538 128.838 153.555C128.776 153.571 128.721 153.608 128.683 153.66C128.645 153.712 128.627 153.776 128.63 153.84C128.01 158.84 130.28 165.34 131.56 170.08C132.84 174.82 134.62 179.8 138.47 182.85C140.33 184.33 142.4 180.88 140.34 179.53Z\" fill=\"black\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 196\" style=\"mix-blend-mode:multiply\" opacity=\"0.15\">\n<g id=\"Vector_135_2\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\" filter=\"url(#filter64_d)\">\n<g id=\"Vector_136\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\">\n<path d=\"M233.37 140.7C233.31 140.6 233.13 140.57 233.08 140.7C231.53 144.45 231.95 149.04 231.53 153.05C230.88 159.34 229.92 165.35 226.87 170.93C225.73 173.02 228.87 174.93 229.98 172.81C232.592 167.835 234.215 162.402 234.76 156.81C235.31 151.92 236.11 145 233.37 140.7Z\" fill=\"black\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 197\" style=\"mix-blend-mode:multiply\" opacity=\"0.15\">\n<g id=\"Vector_136_2\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\" filter=\"url(#filter65_d)\">\n<g id=\"Vector_137\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\">\n<path d=\"M173.05 272C171.25 286 169.05 300 167.26 314C165.68 326.51 163.64 340 165.35 352.62C165.42 353.18 166.19 352.98 166.23 352.5C167.38 339.67 167.36 326.84 168.88 314C170.55 300 172.62 286.12 173.5 272C173.52 271.65 173.08 271.67 173.05 272Z\" fill=\"black\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 198\" style=\"mix-blend-mode:multiply\" opacity=\"0.15\">\n<g id=\"Vector_137_2\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\" filter=\"url(#filter66_d)\">\n<g id=\"Vector_138\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\">\n<path d=\"M215.74 310.58C215.93 295.86 215.62 281.35 214.5 266.67C214.5 266.45 214.16 266.44 214.17 266.67C215.69 294.67 213.98 322.13 212.17 349.97C212.17 350.39 212.7 350.4 212.83 350.06C217.48 338.07 215.58 323.23 215.74 310.58Z\" fill=\"black\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 199\" style=\"mix-blend-mode:multiply\" opacity=\"0.15\">\n<g id=\"Vector_138_2\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\" filter=\"url(#filter67_d)\">\n<g id=\"Vector_139\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\">\n<path d=\"M352.03 37.7H284.13V129.8H352.03V37.7Z\" fill=\"black\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 200\" style=\"mix-blend-mode:multiply\" opacity=\"0.15\">\n<g id=\"Vector_139_2\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\" filter=\"url(#filter68_d)\">\n<g id=\"Vector_140\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\">\n<path d=\"M68.015 53.179L64.7457 53.4438L72.863 153.676L76.1323 153.411L68.015 53.179Z\" fill=\"black\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 201\" style=\"mix-blend-mode:multiply\" opacity=\"0.15\">\n<g id=\"Vector_140_2\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\" filter=\"url(#filter69_d)\">\n<g id=\"Vector_141\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\">\n<path d=\"M62.37 80.18C60.6982 80.1795 59.0282 80.0726 57.37 79.86C57.1777 79.8348 57.0033 79.7343 56.8852 79.5805C56.767 79.4267 56.7148 79.2323 56.74 79.04C56.7652 78.8477 56.8658 78.6733 57.0195 78.5552C57.1733 78.437 57.3677 78.3848 57.56 78.41C59.1486 78.6135 60.7484 78.717 62.35 78.72C62.4472 78.7187 62.5437 78.7365 62.634 78.7725C62.7243 78.8085 62.8066 78.8619 62.8762 78.9297C62.9459 78.9974 63.0015 79.0783 63.0399 79.1676C63.0783 79.2569 63.0987 79.3528 63.1 79.45C63.1014 79.5462 63.0834 79.6418 63.0472 79.7309C63.011 79.8201 62.9573 79.9011 62.8892 79.9692C62.8211 80.0372 62.7401 80.091 62.651 80.1272C62.5618 80.1634 62.4662 80.1814 62.37 80.18ZM67.29 79.86C67.1116 79.8592 66.9395 79.7941 66.8054 79.6765C66.6713 79.5589 66.5841 79.3968 66.56 79.22C66.5474 79.1248 66.5537 79.028 66.5785 78.9352C66.6033 78.8424 66.6463 78.7554 66.7048 78.6792C66.7633 78.6031 66.8363 78.5392 66.9196 78.4913C67.0028 78.4433 67.0947 78.4123 67.19 78.4C68.7917 78.188 70.3783 77.874 71.94 77.46C72.0326 77.4351 72.1292 77.4286 72.2243 77.441C72.3193 77.4533 72.4111 77.4843 72.4942 77.5322C72.5773 77.58 72.6502 77.6437 72.7086 77.7197C72.7671 77.7957 72.8101 77.8824 72.835 77.975C72.86 78.0676 72.8664 78.1642 72.854 78.2593C72.8417 78.3543 72.8107 78.4461 72.7629 78.5292C72.715 78.6123 72.6513 78.6851 72.5753 78.7436C72.4994 78.8021 72.4126 78.8451 72.32 78.87C70.6963 79.3079 69.0462 79.6419 67.38 79.87L67.29 79.86ZM52.61 78.92C52.547 78.9296 52.483 78.9296 52.42 78.92C50.7996 78.4888 49.2095 77.9509 47.66 77.31C47.5661 77.2777 47.4798 77.2266 47.4063 77.1598C47.3329 77.093 47.2738 77.012 47.2327 76.9216C47.1917 76.8312 47.1695 76.7334 47.1675 76.6341C47.1656 76.5348 47.1839 76.4362 47.2213 76.3443C47.2588 76.2523 47.3146 76.169 47.3854 76.0993C47.4562 76.0297 47.5404 75.9752 47.6329 75.9393C47.7255 75.9033 47.8244 75.8866 47.9236 75.8902C48.0228 75.8937 48.1203 75.9175 48.21 75.96C49.7067 76.5706 51.2396 77.0882 52.8 77.51C52.9868 77.5593 53.1465 77.6807 53.2439 77.8475C53.3414 78.0144 53.3688 78.213 53.32 78.4C53.2729 78.5513 53.1785 78.6834 53.0507 78.777C52.9229 78.8706 52.7684 78.9207 52.61 78.92ZM76.8 77.31C76.655 77.3098 76.5133 77.2671 76.3924 77.1871C76.2715 77.1071 76.1768 76.9934 76.12 76.86C76.0758 76.7694 76.0508 76.6706 76.0467 76.5698C76.0425 76.469 76.0593 76.3685 76.0959 76.2746C76.1326 76.1806 76.1883 76.0953 76.2596 76.0239C76.3308 75.9526 76.4161 75.8968 76.51 75.86C77.9974 75.2396 79.4437 74.5248 80.84 73.72C80.924 73.6714 81.0168 73.6399 81.1131 73.6271C81.2093 73.6144 81.3071 73.6208 81.4009 73.6458C81.4947 73.6709 81.5826 73.7142 81.6597 73.7733C81.7368 73.8323 81.8014 73.906 81.85 73.99C81.8986 74.0741 81.9302 74.1668 81.9429 74.2631C81.9556 74.3593 81.9493 74.4571 81.9242 74.5509C81.8991 74.6447 81.8558 74.7326 81.7968 74.8097C81.7377 74.8868 81.6641 74.9514 81.58 75C80.1303 75.8407 78.6271 76.5857 77.08 77.23C76.9929 77.275 76.8977 77.3021 76.8 77.31ZM43.51 75.16C43.3798 75.1612 43.2518 75.1266 43.14 75.06C41.7033 74.2171 40.3206 73.2853 39 72.27C38.9101 72.2168 38.8325 72.1453 38.7723 72.06C38.7121 71.9747 38.6706 71.8776 38.6505 71.7751C38.6305 71.6727 38.6324 71.5671 38.656 71.4654C38.6797 71.3637 38.7246 71.2682 38.7878 71.1851C38.851 71.102 38.9311 71.0332 39.0228 70.9833C39.1145 70.9333 39.2157 70.9033 39.3198 70.8953C39.4239 70.8873 39.5285 70.9013 39.6268 70.9366C39.7251 70.9719 39.8148 71.0276 39.89 71.1C41.1634 72.0827 42.4996 72.9812 43.89 73.79C43.9736 73.8377 44.047 73.9015 44.1059 73.9776C44.1648 74.0538 44.208 74.1409 44.2331 74.2338C44.2582 74.3268 44.2646 74.4238 44.2521 74.5192C44.2396 74.6147 44.2083 74.7067 44.16 74.79C44.0968 74.9061 44.0025 75.0022 43.8877 75.0675C43.7728 75.1329 43.642 75.1649 43.51 75.16ZM85.31 72.38C85.1974 72.3804 85.0862 72.3544 84.9855 72.304C84.8848 72.2536 84.7973 72.1803 84.73 72.09C84.6189 71.9386 84.5704 71.7502 84.5946 71.564C84.6188 71.3777 84.7139 71.208 84.86 71.09C86.1389 70.1077 87.3515 69.042 88.49 67.9C88.6275 67.777 88.8055 67.709 88.99 67.709C89.1745 67.709 89.3525 67.777 89.49 67.9C89.6173 68.0354 89.6881 68.2142 89.6881 68.4C89.6881 68.5858 89.6173 68.7646 89.49 68.9C88.3037 70.0878 87.041 71.1969 85.71 72.22C85.5958 72.3124 85.4564 72.3681 85.31 72.38ZM35.69 69.17C35.4991 69.1694 35.316 69.094 35.18 68.96C33.9915 67.7743 32.8824 66.5116 31.86 65.18C31.7489 65.0286 31.7004 64.8402 31.7246 64.654C31.7488 64.4677 31.8439 64.298 31.99 64.18C32.1434 64.0724 32.332 64.027 32.5176 64.053C32.7032 64.0789 32.872 64.1744 32.99 64.32C33.9749 65.5968 35.0404 66.8092 36.18 67.95C36.3095 68.0842 36.3819 68.2635 36.3819 68.45C36.3819 68.6365 36.3095 68.8158 36.18 68.95C36.1168 69.0171 36.041 69.0711 35.9569 69.1089C35.8729 69.1466 35.7821 69.1674 35.69 69.17ZM92.26 65.41C92.1001 65.4141 91.9441 65.3609 91.82 65.26C91.6723 65.1435 91.5753 64.9744 91.5492 64.7881C91.5231 64.6018 91.57 64.4126 91.68 64.26C92.6627 62.9866 93.5612 61.6504 94.37 60.26C94.4668 60.0916 94.6266 59.9685 94.8141 59.9179C95.0016 59.8673 95.2016 59.8932 95.37 59.99C95.5384 60.0868 95.6615 60.2466 95.7121 60.4341C95.7627 60.6216 95.7368 60.8216 95.64 60.99C94.7985 62.4404 93.8667 63.8365 92.85 65.17C92.7757 65.2514 92.6842 65.3152 92.5822 65.3567C92.4801 65.3983 92.37 65.4165 92.26 65.41ZM29.69 61.41C29.5607 61.4079 29.434 61.3728 29.322 61.3081C29.21 61.2433 29.1164 61.1511 29.05 61.04C28.2073 59.5913 27.4623 58.088 26.82 56.54C26.7773 56.4491 26.7535 56.3505 26.7501 56.2502C26.7467 56.1498 26.7638 56.0498 26.8002 55.9563C26.8367 55.8627 26.8919 55.7776 26.9623 55.706C27.0328 55.6344 27.117 55.578 27.21 55.54C27.3013 55.496 27.4007 55.4715 27.5019 55.468C27.6032 55.4646 27.704 55.4822 27.7981 55.5198C27.8921 55.5574 27.9773 55.6142 28.0483 55.6866C28.1192 55.7589 28.1743 55.8452 28.21 55.94C28.8318 57.4286 29.55 58.875 30.36 60.27C30.4548 60.4389 30.4796 60.6382 30.4291 60.8251C30.3787 61.0121 30.2569 61.1718 30.09 61.27C29.969 61.3421 29.8308 61.3801 29.69 61.38V61.41ZM97.19 56.92C97.0972 56.9343 97.0028 56.9343 96.91 56.92C96.8171 56.8819 96.7327 56.8255 96.662 56.7541C96.5913 56.6828 96.5356 56.598 96.4983 56.5047C96.461 56.4114 96.4428 56.3116 96.4448 56.2112C96.4468 56.1107 96.469 56.0117 96.51 55.92C97.1282 54.4286 97.6493 52.8987 98.07 51.34C98.0944 51.2464 98.1371 51.1586 98.1957 51.0817C98.2542 51.0047 98.3275 50.9402 98.4113 50.8918C98.495 50.8434 98.5875 50.8122 98.6834 50.7998C98.7794 50.7875 98.8768 50.7944 98.97 50.82C99.0623 50.8443 99.1489 50.8868 99.2246 50.9448C99.3004 51.0029 99.3638 51.0755 99.4113 51.1583C99.4587 51.2411 99.4892 51.3325 99.501 51.4272C99.5128 51.522 99.5057 51.6181 99.48 51.71C99.0488 53.3337 98.511 54.9271 97.87 56.48C97.8073 56.6059 97.7101 56.7113 97.5897 56.7839C97.4692 56.8566 97.3306 56.8933 97.19 56.89V56.92ZM25.9 52.29C25.7399 52.2906 25.5841 52.2379 25.4574 52.1401C25.3306 52.0423 25.24 51.905 25.2 51.75C24.7564 50.131 24.4224 48.4839 24.2 46.82C24.1748 46.6277 24.227 46.4333 24.3452 46.2795C24.4633 46.1258 24.6377 46.0252 24.83 46C25.0223 45.9748 25.2167 46.027 25.3705 46.1452C25.5243 46.2633 25.6248 46.4377 25.65 46.63C25.8615 48.2293 26.1789 49.8128 26.6 51.37C26.649 51.5583 26.6219 51.7582 26.5246 51.9267C26.4273 52.0951 26.2676 52.2185 26.08 52.27C26.0214 52.2861 25.9607 52.2928 25.9 52.29ZM99.73 47.38H99.64C99.5447 47.3677 99.4528 47.3367 99.3696 47.2888C99.2863 47.2409 99.2133 47.177 99.1548 47.1008C99.0963 47.0246 99.0533 46.9376 99.0285 46.8448C99.0037 46.752 98.9974 46.6552 99.01 46.56C99.2135 44.9614 99.317 43.3516 99.32 41.74V41.58C99.32 41.3864 99.3969 41.2007 99.5338 41.0638C99.6707 40.9269 99.8564 40.85 100.05 40.85C100.244 40.85 100.429 40.9269 100.566 41.0638C100.703 41.2007 100.78 41.3864 100.78 41.58V41.72C100.778 43.3917 100.671 45.0617 100.46 46.72C100.443 46.9012 100.358 47.0694 100.223 47.1915C100.088 47.3136 99.9121 47.3809 99.73 47.38ZM24.61 42.5C24.5161 42.5055 24.422 42.4917 24.3337 42.4594C24.2453 42.4272 24.1644 42.3772 24.096 42.3126C24.0277 42.248 23.9732 42.1701 23.9361 42.0836C23.8989 41.9972 23.8798 41.9041 23.88 41.81H24.61L23.88 41.74C23.8756 40.0684 23.9791 38.3983 24.19 36.74C24.2152 36.5477 24.3157 36.3733 24.4695 36.2552C24.6233 36.137 24.8177 36.0848 25.01 36.11C25.2023 36.1352 25.3767 36.2358 25.4948 36.3895C25.613 36.5433 25.6652 36.7377 25.64 36.93C25.4396 38.5054 25.3394 40.0919 25.34 41.68C25.3468 41.782 25.3332 41.8843 25.3 41.9809C25.2668 42.0776 25.2148 42.1666 25.1468 42.243C25.0789 42.3193 24.9964 42.3813 24.9042 42.4254C24.8121 42.4696 24.7121 42.4949 24.61 42.5ZM99.71 37.38C99.5337 37.3814 99.363 37.318 99.2302 37.2019C99.0975 37.0858 99.012 36.925 98.99 36.75C98.7618 35.1472 98.4311 33.5606 98 32C97.9742 31.9074 97.9669 31.8107 97.9786 31.7153C97.9903 31.6199 98.0207 31.5277 98.0681 31.4441C98.1155 31.3605 98.1789 31.287 98.2547 31.228C98.3306 31.1689 98.4173 31.1254 98.51 31.1C98.6033 31.0729 98.701 31.065 98.7974 31.0767C98.8938 31.0884 98.9868 31.1195 99.0709 31.168C99.155 31.2166 99.2284 31.2817 99.2867 31.3594C99.3449 31.437 99.3869 31.5257 99.41 31.62C99.8525 33.2359 100.187 34.8796 100.41 36.54C100.433 36.733 100.38 36.9274 100.263 37.0823C100.145 37.2371 99.9721 37.3403 99.78 37.37L99.71 37.38ZM25.86 32.78C25.8004 32.7895 25.7396 32.7895 25.68 32.78C25.5866 32.7567 25.4987 32.7151 25.4215 32.6576C25.3442 32.6002 25.2791 32.528 25.2298 32.4453C25.1805 32.3626 25.1481 32.2709 25.1344 32.1756C25.1207 32.0803 25.126 31.9833 25.15 31.89C25.5812 30.2663 26.1191 28.6729 26.76 27.12C26.797 27.0262 26.8527 26.9409 26.9239 26.8694C26.995 26.7979 27.08 26.7416 27.1737 26.7042C27.2673 26.6667 27.3676 26.6488 27.4685 26.6515C27.5693 26.6542 27.6685 26.6776 27.76 26.72C27.8539 26.7568 27.9392 26.8126 28.0105 26.8839C28.0817 26.9553 28.1374 27.0406 28.1741 27.1346C28.2107 27.2285 28.2275 27.3291 28.2234 27.4298C28.2192 27.5306 28.1942 27.6294 28.15 27.72C27.5368 29.2113 27.0224 30.7412 26.61 32.3C26.554 32.4506 26.4506 32.5789 26.3153 32.6654C26.18 32.752 26.0202 32.7922 25.86 32.78ZM97.13 27.89C96.9868 27.8879 96.8472 27.8443 96.7283 27.7644C96.6093 27.6845 96.5161 27.5718 96.46 27.44C95.8348 25.9513 95.1133 24.5049 94.3 23.11C94.2513 23.0273 94.2195 22.9358 94.2062 22.8408C94.1929 22.7457 94.1985 22.649 94.2227 22.5561C94.2468 22.4632 94.289 22.376 94.3469 22.2995C94.4048 22.2229 94.4772 22.1585 94.56 22.11C94.7282 22.0169 94.9258 21.992 95.1119 22.0403C95.298 22.0887 95.4584 22.2067 95.56 22.37C96.4 23.8217 97.1482 25.3247 97.8 26.87C97.8442 26.9606 97.8692 27.0594 97.8734 27.1602C97.8775 27.261 97.8607 27.3615 97.8241 27.4555C97.7874 27.5494 97.7317 27.6348 97.6605 27.7061C97.5892 27.7775 97.5039 27.8333 97.41 27.87C97.3188 27.8942 97.2238 27.901 97.13 27.89ZM29.61 23.67C29.483 23.6709 29.3583 23.6363 29.25 23.57C29.1664 23.5223 29.093 23.4585 29.0341 23.3824C28.9753 23.3062 28.932 23.2191 28.9069 23.1262C28.8818 23.0332 28.8754 22.9363 28.8879 22.8408C28.9005 22.7453 28.9318 22.6533 28.98 22.57C29.8179 21.1174 30.7499 19.721 31.77 18.39C31.8865 18.2423 32.0556 18.1453 32.2419 18.1192C32.4282 18.0931 32.6174 18.14 32.77 18.25C32.9156 18.368 33.0111 18.5368 33.0371 18.7224C33.0631 18.908 33.0176 19.0966 32.91 19.25C31.9308 20.5237 31.0355 21.8599 30.23 23.25C30.1742 23.3695 30.0871 23.4716 29.978 23.5456C29.8688 23.6195 29.7416 23.6625 29.61 23.67ZM92.18 19.39C92.0674 19.3904 91.9562 19.3644 91.8555 19.314C91.7548 19.2636 91.6673 19.1903 91.6 19.1C90.6078 17.8265 89.5357 16.6174 88.39 15.48C88.3161 15.3402 88.289 15.1804 88.3126 15.024C88.3361 14.8676 88.4092 14.7229 88.521 14.611C88.6329 14.4992 88.7776 14.4261 88.934 14.4026C89.0903 14.379 89.2502 14.4061 89.39 14.48C90.5753 15.6652 91.6842 16.9244 92.71 18.25C92.7941 18.3574 92.8464 18.4863 92.861 18.622C92.8756 18.7576 92.8519 18.8947 92.7925 19.0175C92.7332 19.1404 92.6406 19.2442 92.5253 19.3171C92.4099 19.39 92.2765 19.4291 92.14 19.43L92.18 19.39ZM35.59 15.85C35.4953 15.8508 35.4014 15.8326 35.3138 15.7966C35.2262 15.7605 35.1467 15.7073 35.08 15.64C34.9549 15.5035 34.8855 15.3251 34.8855 15.14C34.8855 14.9549 34.9549 14.7765 35.08 14.64C36.2652 13.4547 37.5244 12.3458 38.85 11.32C38.9262 11.2609 39.0132 11.2174 39.1062 11.192C39.1992 11.1665 39.2963 11.1596 39.3919 11.1717C39.4876 11.1838 39.5799 11.2146 39.6636 11.2623C39.7474 11.3101 39.8209 11.3738 39.88 11.45C39.9391 11.5262 39.9826 11.6132 40.0081 11.7062C40.0335 11.7992 40.0404 11.8963 40.0283 11.9919C40.0163 12.0876 39.9855 12.1799 39.9377 12.2637C39.89 12.3474 39.8262 12.4209 39.75 12.48C38.4733 13.4649 37.2608 14.5304 36.12 15.67C36.0488 15.7349 35.965 15.7843 35.8738 15.8153C35.7826 15.8463 35.686 15.8581 35.59 15.85ZM85.19 12.45C85.0309 12.4493 84.8764 12.3966 84.75 12.3C83.4736 11.3275 82.1377 10.4358 80.75 9.62998C80.5831 9.53177 80.4614 9.37205 80.4109 9.1851C80.3604 8.99814 80.3852 8.79885 80.48 8.62998C80.5267 8.54535 80.59 8.47099 80.666 8.41134C80.7421 8.35168 80.8294 8.30795 80.9227 8.28276C81.016 8.25756 81.1135 8.25141 81.2092 8.26468C81.305 8.27795 81.3971 8.31036 81.48 8.35998C82.9372 9.19201 84.337 10.1208 85.67 11.14C85.8162 11.258 85.9112 11.4277 85.9354 11.614C85.9596 11.8002 85.9111 11.9886 85.8 12.14C85.7308 12.237 85.6392 12.3158 85.533 12.3698C85.4268 12.4237 85.3091 12.4513 85.19 12.45ZM43.38 9.83998C43.2513 9.84119 43.1247 9.80741 43.0138 9.74224C42.9028 9.67706 42.8116 9.58296 42.75 9.46998C42.7 9.38763 42.667 9.29608 42.653 9.20075C42.639 9.10542 42.6443 9.00825 42.6685 8.915C42.6928 8.82175 42.7355 8.73431 42.7941 8.65787C42.8528 8.58143 42.9262 8.51754 43.01 8.46998C44.4617 7.62996 45.9646 6.88183 47.51 6.22998C47.6015 6.18752 47.7007 6.16421 47.8015 6.16149C47.9024 6.15877 48.0027 6.17669 48.0963 6.21415C48.19 6.25161 48.275 6.30782 48.3461 6.37933C48.4173 6.45084 48.473 6.53614 48.51 6.62998C48.5542 6.72061 48.5792 6.81942 48.5834 6.92018C48.5875 7.02094 48.5707 7.12147 48.5341 7.21542C48.4974 7.30938 48.4417 7.39472 48.3705 7.46607C48.2992 7.53742 48.2139 7.59323 48.12 7.62998C46.6304 8.25314 45.1838 8.97474 43.79 9.78998C43.6598 9.84136 43.5187 9.85857 43.38 9.83998ZM76.65 7.54998C76.5571 7.56311 76.4629 7.56311 76.37 7.54998C74.879 6.93339 73.349 6.4156 71.79 5.99998C71.6017 5.95092 71.4406 5.82906 71.3421 5.66121C71.2437 5.49337 71.2159 5.29328 71.265 5.10498C71.3141 4.91668 71.4359 4.75558 71.6038 4.65712C71.7716 4.55866 71.9717 4.53092 72.16 4.57998C73.7821 5.01234 75.3753 5.54673 76.93 6.17998C77.0898 6.24226 77.2225 6.3588 77.305 6.50917C77.3874 6.65953 77.4143 6.83412 77.3809 7.00232C77.3475 7.17052 77.2559 7.32159 77.1223 7.42904C76.9887 7.5365 76.8215 7.59347 76.65 7.58998V7.54998ZM52.46 5.99998C52.2986 6.00112 52.1414 5.94874 52.0129 5.85104C51.8845 5.75334 51.792 5.61582 51.75 5.45998C51.701 5.27173 51.7281 5.07175 51.8254 4.90331C51.9227 4.73488 52.0824 4.61154 52.27 4.55998C53.8902 4.1212 55.5369 3.78718 57.2 3.55998C57.3919 3.53714 57.5851 3.59026 57.7383 3.70799C57.8915 3.82571 57.9926 3.9987 58.02 4.18998C58.043 4.383 57.9902 4.57742 57.8727 4.73225C57.7552 4.88709 57.5821 4.99025 57.39 5.01998C55.7899 5.24039 54.2063 5.56779 52.65 5.99998H52.46ZM67.13 4.99998H67C65.438 4.79985 63.8648 4.69965 62.29 4.69998H62.17C61.9898 4.67893 61.8237 4.59244 61.7031 4.45694C61.5825 4.32144 61.5159 4.14637 61.5159 3.96498C61.5159 3.78359 61.5825 3.60852 61.7031 3.47302C61.8237 3.33752 61.9898 3.25103 62.17 3.22998H62.28C63.9215 3.23267 65.5612 3.3362 67.19 3.53998C67.3836 3.54794 67.5661 3.63248 67.6974 3.77501C67.8287 3.91753 67.898 4.10637 67.89 4.29998C67.8821 4.49359 67.7975 4.67611 67.655 4.80738C67.5125 4.93866 67.3236 5.00794 67.13 4.99998Z\" fill=\"black\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 202\" style=\"mix-blend-mode:multiply\" opacity=\"0.15\">\n<g id=\"Vector_141_2\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\" filter=\"url(#filter70_d)\">\n<g id=\"Vector_142\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\">\n<path d=\"M62.33 72.17C79.1415 72.17 92.77 58.5416 92.77 41.73C92.77 24.9185 79.1415 11.29 62.33 11.29C45.5185 11.29 31.89 24.9185 31.89 41.73C31.89 58.5416 45.5185 72.17 62.33 72.17Z\" fill=\"black\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 203\" style=\"mix-blend-mode:multiply\" opacity=\"0.15\">\n<g id=\"Vector_142_2\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\" filter=\"url(#filter71_d)\">\n<g id=\"Vector_143\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\">\n<path d=\"M37.48 32.1199C37.08 33.8699 37.1 35.2099 36.19 36.9099C35.3618 38.1575 34.9456 39.6334 35 41.1299C35 43.5599 34.26 50.8299 38.55 49.6999C42.1 48.7699 40.16 44.0999 42.68 42.0599C43.87 41.0599 45.42 41.4699 46.15 39.9299C46.88 38.3899 45.94 37.0099 47.15 35.7099C49.23 33.3899 53.56 34.3699 55.15 31.5799C52.61 30.0999 49.75 28.8399 51.15 25.0099C51.68 23.5899 53.38 22.4299 53.36 20.7499C53.36 18.5299 51.76 20.1099 50.3 18.9799C49.09 18.0399 50.3 16.2799 49.21 15.4699C48.9502 15.342 48.6645 15.2754 48.375 15.2754C48.0854 15.2754 47.7998 15.342 47.54 15.4699C43.157 17.5275 39.4872 20.8456 37 24.9999C40.86 24.4699 37.82 30.6699 37.48 32.1199Z\" fill=\"black\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 204\" style=\"mix-blend-mode:multiply\" opacity=\"0.15\">\n<g id=\"Vector_143_2\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\" filter=\"url(#filter72_d)\">\n<g id=\"Vector_144\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\">\n<path d=\"M48.4 42.3299C47.5 43.1699 46.25 42.3299 45.3 43.1199C44.91 43.4499 44.39 46.6699 44.76 47.2199C46 49.0999 48.94 43.6599 49 42.4399C48.9207 42.3666 48.8222 42.3174 48.716 42.2979C48.6097 42.2784 48.5002 42.2895 48.4 42.3299Z\" fill=\"black\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 205\" style=\"mix-blend-mode:multiply\" opacity=\"0.15\">\n<g id=\"Vector_144_2\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\" filter=\"url(#filter73_d)\">\n<g id=\"Vector_145\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\">\n<path d=\"M87.11 59.3999C86.8259 58.8178 86.4513 58.2845 86 57.8199C85.6653 57.5772 85.2717 57.4287 84.8601 57.39C84.4485 57.3514 84.034 57.4238 83.66 57.5999L80.43 58.9999C78.43 59.8699 75.91 59.2699 73.79 60.2099C70.51 61.6599 65.18 67.5499 72.26 66.1199C73.13 65.9499 74.26 65.2599 75.03 65.7499C75.0937 66.9557 75.0937 68.1641 75.03 69.3699C79.8554 67.154 84.0192 63.7175 87.11 59.3999Z\" fill=\"black\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 206\" style=\"mix-blend-mode:multiply\" opacity=\"0.15\">\n<g id=\"Vector_145_2\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\" filter=\"url(#filter74_d)\">\n<g id=\"Vector_146\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\">\n<path d=\"M87.23 58.1901C87.4545 58.0827 87.6531 57.9278 87.8119 57.7361C87.9708 57.5445 88.0861 57.3207 88.15 57.0801C87.85 57.4601 87.54 57.8201 87.23 58.1801V58.1901Z\" fill=\"black\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 207\" style=\"mix-blend-mode:multiply\" opacity=\"0.15\">\n<g id=\"Vector_146_2\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\" filter=\"url(#filter75_d)\">\n<g id=\"Vector_147\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\">\n<path d=\"M86.8399 53.7801C85.8999 55.1401 87.2799 56.6401 87.2299 58.1801C87.5399 57.8201 87.8499 57.4601 88.1499 57.0801C88.6399 55.6701 88.2699 53.5201 86.8399 53.7801Z\" fill=\"black\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 208\" style=\"mix-blend-mode:multiply\" opacity=\"0.15\">\n<g id=\"Vector_147_2\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\" filter=\"url(#filter76_d)\">\n<g id=\"Vector_148\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\">\n<path d=\"M84.26 49.46C83.09 50.39 81.4 49.85 80.26 50.77C79.9961 50.988 79.7953 51.2725 79.6783 51.5941C79.5613 51.9158 79.5324 52.2628 79.5946 52.5994C79.6568 52.9359 79.8079 53.2497 80.0321 53.5083C80.2564 53.7669 80.5456 53.9608 80.87 54.07C83.27 55.07 83.18 52.68 83.87 51.34C84.17 50.75 85.35 50.13 85.31 49.45C85.25 48.33 84.75 49.07 84.26 49.46Z\" fill=\"black\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 209\" style=\"mix-blend-mode:multiply\" opacity=\"0.15\">\n<g id=\"Vector_148_2\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\" filter=\"url(#filter77_d)\">\n<g id=\"Vector_149\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\">\n<path d=\"M74.23 47.1501C74.23 48.2301 74.86 49.3901 74.85 50.5001C74.85 51.2701 74.28 55.2101 76.16 52.6001C76.86 51.6001 76.26 47.4401 75.16 46.4101C74.74 46.0501 74.23 46.8701 74.23 47.1501Z\" fill=\"black\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 210\" style=\"mix-blend-mode:multiply\" opacity=\"0.15\">\n<g id=\"Vector_149_2\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\" filter=\"url(#filter78_d)\">\n<g id=\"Vector_150\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\">\n<path d=\"M88.54 43.5399C88.3 42.9699 87.03 42.7699 87.12 43.6799C87.29 46.2899 85.34 47.2099 87.12 49.7599C87.94 48.9299 87.96 48.0199 88.12 46.8599C88.12 46.5099 87.92 45.7899 87.94 45.3999C88 44.7299 88.7 44.3999 88.54 43.5399Z\" fill=\"black\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 211\" style=\"mix-blend-mode:multiply\" opacity=\"0.15\">\n<g id=\"Vector_150_2\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\" filter=\"url(#filter79_d)\">\n<g id=\"Vector_151\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\">\n<path d=\"M60.3999 26.9299C59.7499 25.9999 59.6799 26.2199 59.4999 25.0099C59.2899 23.6399 59.7799 22.3999 59.0099 21.2399C58.5863 20.6455 58.0138 20.173 57.3499 19.8699C57.1707 19.777 56.9718 19.7285 56.7699 19.7285C56.568 19.7285 56.3691 19.777 56.1899 19.8699C55.0899 19.8699 53.9199 19.9499 53.4099 20.9599C52.9899 21.7999 53.1899 23.9599 52.9799 25.0399C52.1299 29.2899 54.8199 29.3099 58.2599 29.3099C59.4499 29.3099 61.6099 29.8899 61.4599 28.2299C61.4099 27.6599 60.6699 27.3299 60.3999 26.9299Z\" fill=\"black\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 212\" style=\"mix-blend-mode:multiply\" opacity=\"0.15\">\n<g id=\"Vector_151_2\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\" filter=\"url(#filter80_d)\">\n<g id=\"Vector_152\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\">\n<path d=\"M87.38 39.9299C89.26 38.9299 87.1 38.2799 86.88 37.2299C86.6 35.8999 88.15 34.9499 87.58 33.5299C89.58 32.4099 89.51 35.6999 89.58 36.8799C91.42 36.8799 89.69 34.1199 89.51 33.2199C89.21 31.6899 90.07 30.6099 89.88 29.0999C89.88 28.8799 89.8 28.6399 89.76 28.3999C87.3194 23.4373 83.5804 19.2283 78.94 16.2199C78.8631 16.2607 78.7895 16.3075 78.72 16.3599C76.72 18.0499 79.21 18.5299 78.87 19.8699C78.67 20.6599 77.65 20.4599 77.07 20.5899C77.2 20.5899 74.84 20.8699 75.17 20.9799C75.1583 21.019 75.1322 21.0522 75.0968 21.0726C75.0615 21.0931 75.0197 21.0993 74.98 21.0899C74.85 19.4099 73.24 17.7899 71.62 18.9499C70.09 17.3599 72.62 16.1599 72.79 14.5699C71.88 14.5199 70.79 14.3499 70.02 14.9299C69.02 15.6999 69.52 16.6199 68.24 16.9899C68.06 17.0399 67.38 16.4899 66.96 16.6599C66.32 16.9099 66.3 17.5699 65.96 18.0899C65.4538 19.0389 64.847 19.9307 64.15 20.7499C63.33 21.4699 62.85 22.1599 62.33 20.7499C61.81 19.3399 63.39 19.2899 63.61 18.0799C63.93 16.3799 60.28 15.5199 60.61 18.2399C59.29 18.3399 58.29 17.0199 56.73 17.2399C54.64 17.4899 55.29 18.0799 57.08 18.6599C60.68 19.8299 60.36 21.3199 61.21 24.4799C62.14 27.9599 65.85 26.3699 65.96 29.8499C66.02 31.6099 66.55 32.0499 67.16 33.5799C67.77 35.1099 67.23 35.9199 66.84 37.4699C66.57 38.5599 65.84 40.4699 67.2 40.6799C68.61 39.9699 69.66 39.7699 70.4 38.1899C70.77 37.4099 70.25 37.0899 71.11 36.5499C71.97 36.0099 72.72 36.6699 73.42 36.5999C74.71 36.4899 75.91 35.3499 77.14 36.2299C78.85 37.4499 77.42 38.9199 77.68 40.3199C77.94 41.7199 79.86 42.0399 80.22 43.3199C80.58 44.5999 78.22 45.3199 78.56 46.5599C79.18 49.1299 80.25 45.3199 80.56 45.0899C81.01 44.6999 82.07 45.0899 82.4 44.6599C82.73 44.2299 82.58 42.9799 82.53 42.4699C82.39 41.0599 81.62 40.1499 83.41 39.6299C84.57 39.1999 86.19 40.5499 87.38 39.9299Z\" fill=\"black\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 213\" style=\"mix-blend-mode:multiply\" opacity=\"0.15\">\n<g id=\"Vector_152_2\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\" filter=\"url(#filter81_d)\">\n<g id=\"Vector_153\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\">\n<path d=\"M62.12 11.65C62.0214 11.5262 61.9145 11.4093 61.8 11.3C59.5008 11.3363 57.2131 11.6315 54.98 12.18C55.1395 12.2265 55.2877 12.3056 55.4151 12.4123C55.5425 12.519 55.6463 12.651 55.72 12.8C56.35 13.91 54.61 15.58 56.21 16.04C57.15 16.31 57.21 15.16 57.97 14.98C58.5438 14.8764 59.1281 14.8428 59.71 14.88C60.95 14.88 62 15.75 62.81 14.29C62.6046 14.1122 62.3874 13.9485 62.16 13.8C62.25 12.8 62.77 12.47 62.12 11.65Z\" fill=\"black\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 214\" style=\"mix-blend-mode:multiply\" opacity=\"0.15\">\n<g id=\"Vector_153_2\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\" filter=\"url(#filter82_d)\">\n<g id=\"Vector_154\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\">\n<path d=\"M48.86 42.4299C35.93 42.4299 25.46 50.1499 25.46 59.6699C25.5164 63.1322 26.8439 66.453 29.19 68.9999L21.36 80.4099L36.05 74.0899C40.0546 75.9783 44.4326 76.9421 48.86 76.9099C61.78 76.9099 72.26 69.1899 72.26 59.6699C72.26 50.1499 61.78 42.4299 48.86 42.4299Z\" fill=\"black\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 215\" style=\"mix-blend-mode:multiply\" opacity=\"0.15\">\n<g id=\"Vector_154_2\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\" filter=\"url(#filter83_d)\">\n<g id=\"Vector_155\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\">\n<path d=\"M52.9299 63.61H43.9999L42.3799 67.46H38.7999L46.7999 49.25H50.3999L58.2899 67.46H54.5399L52.9299 63.61ZM51.6799 60.61L48.4999 53L45.2799 60.65L51.6799 60.61Z\" fill=\"black\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 216\" style=\"mix-blend-mode:multiply\" opacity=\"0.15\">\n<g id=\"Vector_155_2\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\" filter=\"url(#filter84_d)\">\n<g id=\"Vector_156\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\">\n<path d=\"M83.53 0C94.87 0 104.06 6.78 104.06 15.13C104.01 18.1702 102.842 21.0854 100.78 23.32L107.65 33.32L94.76 27.79C91.2498 29.4478 87.4119 30.2954 83.53 30.27C72.18 30.27 63 23.49 63 15.13C63 6.77 72.18 0 83.53 0Z\" fill=\"black\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 217\" style=\"mix-blend-mode:multiply\" opacity=\"0.15\">\n<g id=\"Vector_156_2\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\" filter=\"url(#filter85_d)\">\n<g id=\"Vector_157\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\">\n<path d=\"M88.74 7.93994V9.79994L80.61 19.4499H88.84V21.7599H77V19.8899L85.14 10.2499H77.24V7.93994H88.74Z\" fill=\"black\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 218\" style=\"mix-blend-mode:multiply\" opacity=\"0.15\">\n<g id=\"Vector_157_2\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\" filter=\"url(#filter86_d)\">\n<g id=\"Vector_158\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\">\n<path d=\"M71.75 132.91C72.35 135.67 70.18 136.96 67.96 137.21C65.74 137.46 64.09 135.37 63.74 133.82C63.39 132.27 64.9 130.82 67.11 130.55C69.32 130.28 71.19 130.39 71.75 132.91Z\" fill=\"black\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 219\" style=\"mix-blend-mode:multiply\" opacity=\"0.15\">\n<g id=\"Vector_158_2\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\" filter=\"url(#filter87_d)\">\n<g id=\"Vector_159\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\">\n<path d=\"M74 137.55C74.44 140.17 71.3 141.23 68.63 141.55C68.1571 141.643 67.6704 141.641 67.1982 141.545C66.726 141.448 66.2775 141.259 65.8787 140.989C65.4798 140.718 65.1385 140.371 64.8744 139.968C64.6103 139.565 64.4287 139.114 64.34 138.64C63.99 137.09 65.87 135.64 68.53 135.29C71.19 134.94 73.6 135.05 74 137.55Z\" fill=\"black\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 220\" style=\"mix-blend-mode:multiply\" opacity=\"0.15\">\n<g id=\"Vector_159_2\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\" filter=\"url(#filter88_d)\">\n<g id=\"Vector_160\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\">\n<path d=\"M73.9099 142.2C74.3299 144.81 72.5599 145.2 70.0999 145.51C67.6399 145.82 65.3799 144.76 65.0299 143.2C64.6799 141.64 66.3899 140.2 68.8399 139.89C71.2899 139.58 73.5099 139.68 73.9099 142.2Z\" fill=\"black\"\/>\n<\/g>\n<\/g>\n<\/g>\n<g id=\"Vector5656231 221\" style=\"mix-blend-mode:multiply\" opacity=\"0.15\">\n<g id=\"Vector_160_2\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\" filter=\"url(#filter89_d)\">\n<g id=\"Vector_161\" style=\"mix-blend-mode:overlay\" opacity=\"0.15\">\n<path d=\"M72.6 146.21C72.85 147.6 71.68 148.51 69.95 148.71C68.22 148.91 66.6 148.1 66.33 146.91C66.06 145.72 67.25 144.6 68.98 144.41C70.71 144.22 72.2 143.92 72.6 146.21Z\" fill=\"black\"\/>\n<\/g>\n<\/g>\n<\/g>\n<\/g>\n<path id=\"Vector5656231 222\" d=\"M113.31 187.61C85.09 192.23 69.5 155.61 68.15 149.52C68.81 147.2 73.52 141.86 76.64 145.86C94 168.22 97.93 164.8 111.3 169.06C124.37 173.23 121.51 186.26 113.31 187.61Z\" fill=\"#B57D68\"\/>\n<path id=\"Vector5656231 223\" d=\"M156.91 162.56C158.73 159.95 152.68 148.05 149.43 149.56C127.6 159.77 121.35 166.83 104.12 166.69C93.26 166.6 100.32 182.11 104.74 186.96C119.45 193.87 148.73 174.28 156.91 162.56Z\" fill=\"#B57D68\"\/>\n<path id=\"Vector5656231 224\" d=\"M104.25 184.4C85.89 179.2 76.82 164.4 68.42 148.84C68.3135 149.06 68.2233 149.287 68.15 149.52C69.5 155.58 85.09 192.23 113.31 187.61C115.159 187.301 116.845 186.361 118.08 184.95C113.475 185.605 108.789 185.418 104.25 184.4Z\" fill=\"#9E5B44\"\/>\n<path id=\"Vector5656231 225\" d=\"M104.25 184.4C103.62 184.22 103.03 184 102.43 183.79C103.105 184.913 103.878 185.974 104.74 186.96C119.45 193.87 148.74 174.28 156.91 162.56C157.28 162.03 154.5 153.49 154.31 152.38C140.65 167.17 125.69 185 104.25 184.4Z\" fill=\"#9E5B44\"\/>\n<path id=\"Vector5656231 226\" d=\"M220.9 169.09C247.75 179.23 269.8 146.34 272.25 140.66C272.02 138.25 268.38 132.07 264.59 135.38C243.42 153.89 240.2 149.76 226.29 151.29C212.69 152.79 213.1 166.15 220.9 169.09Z\" fill=\"#B57D68\"\/>\n<path id=\"Vector5656231 227\" d=\"M228.35 165.75C226.98 164.33 228.71 157.56 228.07 151.12C227.49 151.12 226.9 151.22 226.29 151.29C212.69 152.79 213.1 166.15 220.9 169.09C247.75 179.23 269.8 146.34 272.25 140.66C272.25 140.53 272.25 140.38 272.18 140.23C256.89 149.71 246.33 170.83 228.35 165.75Z\" fill=\"#9E5B44\"\/>\n<path id=\"Vector5656231 228\" d=\"M274 127.45C275.61 126.9 278.19 126.37 279.28 127.45C279.88 128.03 279.36 129.5 278.35 129.7C277.803 129.82 277.294 130.075 276.87 130.44C276.123 131.234 275.478 132.117 274.95 133.07L279.47 134.3L283.47 134.23C284.814 133.527 286.111 132.735 287.35 131.86C288.4 130.86 290.54 131.48 290.35 131.92C290.002 132.87 289.453 133.733 288.74 134.45C289.766 133.957 290.718 133.324 291.57 132.57C292.31 131.86 295.13 132.36 293.68 134.57C294.62 135.22 294.57 135.52 293.81 136.57C292.979 137.464 291.997 138.205 290.91 138.76C291.696 138.297 292.566 137.994 293.47 137.87C294.47 137.79 294.38 139.32 293.73 140.1C291.16 143.1 284.54 144.75 281.89 145.1C275.39 145.86 268.24 143.1 268.24 143.1L262.15 138.65C262.15 138.65 264.24 134.65 265.15 133.35C267.41 130.16 271.48 128.3 274 127.45Z\" fill=\"#B57D68\"\/>\n<path id=\"Vector5656231 229\" d=\"M186.42 290.79C184.18 315.79 188.69 350.79 192.42 366.7C196.15 382.61 202.42 369.52 203.31 365.7C205.74 355.15 207.82 302.15 208 292.7C208.26 277.4 186.84 286.18 186.42 290.79Z\" fill=\"#B57D68\"\/>\n<path id=\"Vector5656231 230\" d=\"M204.22 359.75C204.22 359.75 210.04 368.87 210.74 372.87C213.01 385.68 184.6 378.77 185.24 376.2C186.38 371.59 190.03 363.08 191.08 360.43C195.421 361.61 200.024 361.371 204.22 359.75Z\" fill=\"#B57D68\"\/>\n<path id=\"Vector5656231 231\" d=\"M185.21 374.68C186.09 371.44 188.61 366.47 189.72 362.84C189.72 363.42 188.84 368.64 190.58 370.02C195.22 368.37 199.91 369.18 204.52 369.02C205.88 367.45 205.33 363.09 205.04 361.46C205.04 361.46 209.58 369.31 210.74 372.86C213.14 380.15 212.15 381.69 210.63 383.86C210.63 385.03 210.18 385.13 210.18 385.13C206.047 385.561 201.895 385.785 197.74 385.8C192.85 385.91 185.41 385.92 185.41 385.92V384.42C183.36 382.12 184.56 377 185.21 374.68Z\" fill=\"#68333E\"\/>\n<path id=\"Vector5656231 232\" d=\"M205 368.05C205.67 366.1 205.26 362.84 205 361.47C205 361.47 209.54 369.32 210.7 372.87C213.1 380.16 212.11 381.7 210.59 383.87C210.59 385.04 210.14 385.14 210.14 385.14C210.14 385.14 208.85 385.32 205.68 385.51C207.093 379.741 206.858 373.691 205 368.05Z\" fill=\"#5B222D\"\/>\n<path id=\"Vector5656231 233\" d=\"M189.89 384.51C194.38 384.51 198.89 384.8 203.41 384.38C205.32 384.19 208.41 384.24 210.83 383.56C210.769 383.657 210.702 383.751 210.63 383.84C210.63 385.01 210.18 385.11 210.18 385.11C206.047 385.541 201.895 385.765 197.74 385.78C192.85 385.89 185.41 385.9 185.41 385.9V384.42C186.9 384.537 188.396 384.567 189.89 384.51Z\" fill=\"#5F2037\"\/>\n<path id=\"Vector5656231 234\" d=\"M192.09 374.63C192.19 374.626 192.289 374.602 192.38 374.56C196.6 372.38 200.56 372.24 204.15 374.15C204.228 374.191 204.313 374.215 204.4 374.222C204.488 374.229 204.576 374.218 204.659 374.19C204.742 374.162 204.819 374.117 204.884 374.059C204.95 374.001 205.003 373.929 205.04 373.85C205.122 373.688 205.137 373.5 205.083 373.326C205.029 373.153 204.91 373.007 204.75 372.92C200.75 370.8 196.41 370.92 191.75 373.32C191.59 373.407 191.47 373.552 191.415 373.725C191.359 373.898 191.371 374.086 191.45 374.25C191.507 374.37 191.598 374.469 191.712 374.537C191.826 374.605 191.958 374.637 192.09 374.63Z\" fill=\"#E2C0AE\"\/>\n<path id=\"Vector5656231 235\" d=\"M195.47 377.14C195.592 377.139 195.71 377.103 195.813 377.038C195.915 376.973 195.998 376.88 196.05 376.77C196.36 376.55 199.72 375.53 201.63 376.51C201.709 376.55 201.795 376.574 201.884 376.579C201.972 376.585 202.061 376.572 202.144 376.542C202.227 376.512 202.304 376.465 202.368 376.405C202.433 376.344 202.485 376.271 202.52 376.19C202.601 376.028 202.614 375.841 202.558 375.669C202.502 375.496 202.381 375.353 202.22 375.27C199.76 374.01 195.36 375.12 194.86 376.14C194.778 376.302 194.763 376.49 194.817 376.664C194.871 376.837 194.99 376.983 195.15 377.07C195.248 377.123 195.359 377.147 195.47 377.14Z\" fill=\"#E2C0AE\"\/>\n<path id=\"Vector5656231 236\" d=\"M163.51 297.17C162.86 291.92 144.06 277.07 142.87 293.17C141.14 316.41 142.67 367.07 144.16 373.47C145.65 379.87 150.93 377.52 152.41 374.58C153.89 371.64 168.1 334.46 163.51 297.17Z\" fill=\"#B57D68\"\/>\n<path id=\"Vector5656231 237\" d=\"M157.31 359.79C157.31 359.79 158.95 368.35 158.44 372.08C157.93 375.81 135.7 373.27 135.7 373.27C135.7 373.27 139.08 366.27 143.7 362.83C155.4 363.09 157.31 359.79 157.31 359.79Z\" fill=\"#B57D68\"\/>\n<path id=\"Vector5656231 238\" d=\"M157.7 361.18C157.61 361.6 157.5 362.02 157.38 362.46C156.19 366.92 151.9 367.9 149.02 368.34C145.22 367.7 141.11 366.15 139.94 366.23C133.67 371.84 131.94 371.29 127.23 374.92C123.7 377.66 123.74 380.81 123.47 382.92C123.05 386.28 126.3 386.15 134.75 386.22C141.86 386.28 157.75 385.67 159.37 384.13C159.652 383.35 159.697 382.505 159.5 381.7C162.79 376.83 158.67 364.53 157.7 361.18Z\" fill=\"#68333E\"\/>\n<path id=\"Vector5656231 239\" d=\"M149.11 380C151.743 376.224 153.197 371.752 153.29 367.15C154.291 366.734 155.181 366.09 155.891 365.271C156.6 364.452 157.11 363.48 157.38 362.43C157.5 361.99 157.61 361.57 157.7 361.15C158.7 364.5 162.79 376.8 159.5 381.71C159.697 382.515 159.652 383.36 159.37 384.14C158.16 385.28 149.13 385.91 141.64 386.14C144.621 384.776 147.195 382.66 149.11 380Z\" fill=\"#5B222D\"\/>\n<path id=\"Vector5656231 240\" d=\"M123.5 382.48C127.91 384.65 133.76 384.81 143.36 384.48C148.3 384.31 155.36 384.76 159.52 381.69C159.695 382.69 159.637 383.716 159.35 384.69C157.72 386.23 141.82 386.2 134.71 386.09C124.49 385.94 123.05 386.35 123.47 382.99C123.491 382.821 123.501 382.65 123.5 382.48Z\" fill=\"#5F2037\"\/>\n<path id=\"Vector5656231 241\" d=\"M146 374.44C146.093 374.439 146.186 374.418 146.27 374.378C146.355 374.339 146.43 374.281 146.49 374.21C146.611 374.068 146.673 373.886 146.663 373.7C146.654 373.514 146.574 373.339 146.44 373.21C143.06 370.04 138.66 368.91 133.38 369.86C133.201 369.896 133.043 370.001 132.94 370.153C132.837 370.304 132.798 370.49 132.83 370.67C132.842 370.761 132.872 370.848 132.919 370.927C132.966 371.005 133.028 371.074 133.102 371.128C133.175 371.182 133.259 371.221 133.348 371.242C133.437 371.263 133.53 371.266 133.62 371.25C138.46 370.38 142.47 371.39 145.53 374.25C145.592 374.312 145.665 374.36 145.746 374.393C145.826 374.425 145.913 374.441 146 374.44Z\" fill=\"#E2C0AE\"\/>\n<path id=\"Vector5656231 242\" d=\"M139.13 375.72C139.225 375.716 139.319 375.693 139.405 375.652C139.491 375.61 139.567 375.552 139.63 375.48C139.749 375.337 139.81 375.154 139.799 374.968C139.787 374.782 139.706 374.608 139.57 374.48C137.57 372.62 132.77 372.38 132.01 373.19C131.883 373.325 131.812 373.504 131.812 373.69C131.812 373.876 131.883 374.055 132.01 374.19C132.071 374.263 132.147 374.323 132.234 374.363C132.32 374.404 132.415 374.425 132.51 374.425C132.605 374.425 132.7 374.404 132.786 374.363C132.873 374.323 132.949 374.263 133.01 374.19C133.5 374.02 137.11 374.1 138.7 375.55C138.82 375.654 138.972 375.714 139.13 375.72Z\" fill=\"#E2C0AE\"\/>\n<path id=\"Vector5656231 243\" d=\"M205.16 229.67C212.61 271.11 209.51 274.58 210.36 305.67C210.72 318.4 209.36 346.78 208.13 353.72C199.13 361.72 184.47 354.93 184.47 354.93C184.47 354.93 179.74 318.93 178.15 306.99C176.35 293.34 168.33 233.76 168.33 233.76L205.16 229.67Z\" fill=\"#5F432E\"\/>\n<path id=\"Vector5656231 244\" d=\"M210.36 305.62C209.51 274.62 212.61 271.11 205.16 229.62L168.33 233.62L171.75 259.07C181.55 258.78 191.46 257.77 201.37 257.07C199.71 289.83 204.18 324.19 200.6 357.2C203.397 356.735 206.007 355.49 208.13 353.61C209.32 346.73 210.72 318.35 210.36 305.62Z\" fill=\"#5A3F2C\"\/>\n<path id=\"Vector5656231 245\" d=\"M200.46 259.24C194.37 257.37 192.99 249.97 192.46 244.38C192.46 244.29 192.424 244.203 192.36 244.14C192.297 244.076 192.21 244.04 192.12 244.04C192.03 244.04 191.943 244.076 191.88 244.14C191.816 244.203 191.78 244.29 191.78 244.38C191.12 251.46 191.64 257.89 198.22 261.61C200.039 262.613 202.056 263.206 204.129 263.348C206.202 263.49 208.281 263.176 210.22 262.43C210.141 261.343 210.001 260.261 209.8 259.19C206.753 260.085 203.516 260.102 200.46 259.24Z\" fill=\"#4B3321\"\/>\n<path id=\"Vector5656231 246\" d=\"M140.45 229.94C140.45 229.94 134.83 272.05 134.83 293.49C134.83 316.97 141.57 358.3 141.57 358.3C141.57 358.3 156.57 360.94 160.9 356.44C162.8 351.55 164.06 313.03 165.4 300.02C166.74 287.01 176.57 234.45 176.57 234.45L140.45 229.94Z\" fill=\"#5F432E\"\/>\n<path id=\"Vector5656231 247\" d=\"M155.51 358.72C157.499 358.534 159.382 357.738 160.9 356.44C162.8 351.55 164.06 313.03 165.4 300.02C166.03 293.9 168.51 279.23 170.96 265.32C154.4 292.84 159.07 327.68 155.51 358.72Z\" fill=\"#5A3F2C\"\/>\n<path id=\"Vector5656231 248\" d=\"M140.45 229.94C140.45 229.94 138.93 241.37 137.45 255.35C148.71 258.83 160.3 259.52 172.05 259.15C174.45 245.74 176.56 234.45 176.56 234.45L140.45 229.94Z\" fill=\"#5A3F2C\"\/>\n<path id=\"Vector5656231 249\" d=\"M147.63 246.19C147.55 245.96 147.16 245.97 147.19 246.25C147.79 251.3 145.05 256.17 141.93 259.83C140.649 261.469 138.781 262.545 136.72 262.83C136.63 263.99 136.62 265.18 136.62 266.36C144.13 265.78 150.31 253.47 147.63 246.19Z\" fill=\"#4B3321\"\/>\n<path id=\"Vector5656231 250\" d=\"M223.4 148.73C223.4 148.73 220.49 178.57 218 178.57C215.51 178.57 176.73 168.57 176.86 161.57C178.95 156.42 181.43 138.07 189.68 139.42C202.49 141.5 211 144.66 223.4 148.73Z\" fill=\"#CA5D69\"\/>\n<path id=\"Vector5656231 251\" d=\"M119.31 161.55C119.31 161.55 126.4 188.72 128.76 187.89C131.12 187.06 161.09 173.89 158.81 167.3C162.7 154.87 161.43 139.39 150.71 141.5C142.3 143.16 129.66 155.49 119.31 161.55Z\" fill=\"#CA5D69\"\/>\n<path id=\"Vector5656231 252\" d=\"M200.72 143.68C200.72 141.54 182.72 136.32 170.18 136.53C156.37 136.76 143.63 144.13 143.52 146.16C142.3 168.32 139.32 225.16 135.35 246.31C150.83 255.92 184.26 256.12 209.51 244.69C202.87 222 200.77 162.64 200.72 143.68Z\" fill=\"#EB6D79\"\/>\n<path id=\"Vector5656231 253\" d=\"M209.51 244.69C202.87 222.01 200.77 162.64 200.72 143.69C200.72 142.69 196.89 141.07 191.55 139.6C196.36 179.55 194.55 226.66 166.13 253.4C180.28 253.57 196.06 250.78 209.51 244.69Z\" fill=\"#CA5D69\"\/>\n<path id=\"Vector5656231 254\" d=\"M164.84 149C163.049 146.398 161.672 143.534 160.76 140.51C160.47 139.56 160.31 138.51 160.07 137.43C163.415 136.897 166.793 136.6 170.18 136.54C173.931 136.478 177.684 136.618 181.42 136.96C180.44 144 171 158 164.84 149Z\" fill=\"#B57D68\"\/>\n<path id=\"Vector5656231 255\" d=\"M171.22 29.3699C160 24.6299 151 25.6699 143.44 31.1299C142.52 31.7199 141.59 32.3099 140.62 32.8899C136.583 35.4352 132.285 37.5406 127.8 39.1699C126.29 39.6799 131.14 43.0199 132.92 42.8399C131.72 44.7199 130.56 46.7199 129.43 48.8399C127.43 52.6999 122.1 64.9799 120.09 68.0699C119.24 69.3699 125.36 69.4599 126.87 68.5099C128.87 75.5099 133.07 83.4299 133.93 99.5099C133.93 99.5099 203.45 112.68 205.57 96.7099C207 86.1999 211.86 81.1999 214.26 70.9999C220.25 40.1699 186.51 22.5299 171.22 29.3699Z\" fill=\"#231F20\"\/>\n<path id=\"Vector5656231 256\" d=\"M178.62 124.2L178.63 139.19L161.53 140.17L161.78 127.71L178.62 124.2Z\" fill=\"#B57D68\"\/>\n<path id=\"Vector5656231 257\" d=\"M161.66 133.81L161.78 127.71L178.62 124.2V133.2C170.92 136.09 163.22 134.49 161.66 133.81Z\" fill=\"#9E5B44\"\/>\n<path id=\"Vector5656231 258\" d=\"M217.27 80.8699C213.27 77.8699 208.8 80.5899 206.42 84.2399C202.24 87.2399 198.75 93.4599 201.51 97.7199C204.83 102.84 212.87 99.5399 216.35 96.3199C220.55 92.4199 222.54 84.8199 217.27 80.8699Z\" fill=\"#9E5B44\"\/>\n<path id=\"Vector5656231 259\" d=\"M215.26 84C213.72 83.83 211.81 85.43 211.36 86.78C211.04 87.7988 211.04 88.8912 211.36 89.91C211.71 91.19 212 92.69 210.27 93.24C210.014 93.349 209.808 93.5484 209.69 93.8C209.653 93.8638 209.634 93.9363 209.634 94.01C209.634 94.0837 209.653 94.1562 209.69 94.22C209.74 94.31 209.78 94.4 209.82 94.49C209.933 94.6407 210.09 94.7519 210.27 94.8076C210.449 94.8633 210.642 94.8606 210.82 94.8C211.307 94.6541 211.758 94.4066 212.142 94.0739C212.527 93.7412 212.837 93.3308 213.051 92.8698C213.265 92.4088 213.38 91.9075 213.387 91.3991C213.393 90.8906 213.292 90.3866 213.09 89.92C212.51 88.19 212.45 87.04 213.95 85.79C214.54 85.31 215.32 84.89 215.28 84.1C215.286 84.0831 215.287 84.0648 215.284 84.0473C215.28 84.0297 215.272 84.0133 215.26 84Z\" fill=\"#B57D68\"\/>\n<path id=\"Vector5656231 260\" d=\"M125.9 86.45C129.02 82.79 133.16 84.7301 135.62 87.9101C139.54 90.1701 143.23 95.69 141.33 100.36C139.05 105.96 131.76 104.09 128.42 101.5C124.37 98.38 121.81 91.24 125.9 86.45Z\" fill=\"#9E5B44\"\/>\n<path id=\"Vector5656231 261\" d=\"M128 89.1501C129.31 88.7301 131.13 89.9701 131.67 91.2201C132.043 92.205 132.15 93.2706 131.98 94.31C131.82 95.64 131.73 97.1601 133.28 97.4001C133.55 97.4001 133.69 97.6601 133.84 97.8601C133.874 97.9248 133.892 97.9968 133.892 98.07C133.892 98.1432 133.874 98.2153 133.84 98.28C133.84 98.38 133.78 98.47 133.76 98.56C133.695 98.7191 133.58 98.8526 133.432 98.9394C133.283 99.0261 133.11 99.0616 132.94 99.0401C130.94 98.7301 130.09 96.7301 130.45 94.6201C130.75 92.8201 130.68 91.62 129.24 90.7C128.69 90.33 127.97 90.05 127.91 89.27C127.907 89.2423 127.915 89.2145 127.931 89.1923C127.948 89.17 127.973 89.155 128 89.1501Z\" fill=\"#B57D68\"\/>\n<path id=\"Vector5656231 262\" d=\"M135.89 56.15C134.409 69.096 133.718 82.12 133.82 95.15C134.04 107.54 140.54 119.92 149.14 126.08C164.61 137.16 185.47 130.17 194.22 121.17C207.71 107.3 210.53 90.81 204.61 56.79C202.39 55 135.89 56.15 135.89 56.15Z\" fill=\"#B57D68\"\/>\n<path id=\"Vector5656231 263\" d=\"M186.13 121.58C195.22 114.77 200.83 106.1 201.39 92.18C201.84 80.64 201.62 67.88 195.68 56.01C200.68 56.16 204.14 56.41 204.61 56.79C210.53 90.79 207.71 107.3 194.22 121.17C185.47 130.17 164.61 137.17 149.14 126.08C148.42 125.57 147.71 124.98 147.02 124.38C159.89 129.18 174.55 130.26 186.13 121.58Z\" fill=\"#9E5B44\"\/>\n<path id=\"Vector5656231 264\" d=\"M193.26 93.4201C193.578 93.2425 193.815 92.9486 193.922 92.5999C194.028 92.2513 193.995 91.875 193.83 91.5501C193.247 90.2414 192.303 89.1254 191.11 88.3323C189.917 87.5391 188.523 87.1014 187.09 87.0701C184.3 87.1701 182.3 89.1801 180.91 91.8301C180.736 92.1508 180.694 92.5267 180.793 92.8778C180.892 93.2289 181.124 93.5276 181.44 93.7101C182.09 94.0701 183.34 89.9501 187.62 90.2701C190.8 90.5101 193.1 93.5001 193.26 93.4201Z\" fill=\"#1F0601\"\/>\n<path id=\"Vector5656231 265\" d=\"M154.25 94.1999C154.418 94.1887 154.582 94.1409 154.73 94.0599C155.048 93.8823 155.285 93.5884 155.392 93.2397C155.498 92.8911 155.465 92.5148 155.3 92.1899C154.736 90.8806 153.811 89.7587 152.634 88.9549C151.456 88.151 150.075 87.6985 148.65 87.6499C145.84 87.7499 143.79 89.8099 142.39 92.4699C142.219 92.7896 142.179 93.1631 142.278 93.5119C142.376 93.8606 142.607 94.1575 142.92 94.3399C143.56 94.7099 144.68 91.1499 149.09 90.9099C153.26 90.6799 153.73 94.2599 154.25 94.1999Z\" fill=\"#1F0601\"\/>\n<path id=\"Vector5656231 266\" d=\"M187.76 78.23C189.43 78.11 191.93 79.47 192.39 81.35C192.39 81.54 192.26 81.75 192.06 81.68C190.9 81.25 189.77 80.52 188.48 80.6C187.91 80.6 185.75 80.77 185.41 81.33C185.07 81.89 183.7 82.2 183.58 81.33C183.3 79.43 186.47 78.32 187.76 78.23Z\" fill=\"#37201C\"\/>\n<path id=\"Vector5656231 267\" d=\"M144.73 80.5101C147.87 78.6301 152.02 79.3701 153.07 83.0401C153.086 83.0933 153.088 83.15 153.075 83.2042C153.062 83.2584 153.035 83.3081 152.996 83.348C152.957 83.3879 152.908 83.4166 152.854 83.431C152.8 83.4455 152.744 83.4452 152.69 83.4301C151.38 83.0201 150.35 82.2401 148.94 82.0501C147.53 81.8601 146.54 83.0501 145.27 82.9301C145.008 82.8852 144.765 82.7634 144.573 82.5802C144.38 82.397 144.246 82.1606 144.188 81.9012C144.131 81.6417 144.151 81.371 144.248 81.1232C144.344 80.8755 144.512 80.6621 144.73 80.5101Z\" fill=\"#37201C\"\/>\n<path id=\"Vector5656231 268\" d=\"M157.7 110.86C157.7 110.86 159.75 119.12 165.7 119.69C176.16 120.69 176.93 110.69 176.93 110.69L157.7 110.86Z\" fill=\"#A72231\"\/>\n<path id=\"Vector5656231 269\" d=\"M174.34 113.4C174.932 113.146 175.468 112.778 175.918 112.316C176.367 111.854 176.722 111.309 176.96 110.71L160.15 110.85C163.47 114.73 168.09 115.56 174.34 113.4Z\" fill=\"white\"\/>\n<path id=\"Vector5656231 270\" d=\"M173.9 117.26C171.28 116.72 167.72 116.89 165.75 118.26C165.256 118.582 164.825 118.992 164.48 119.47C164.887 119.599 165.306 119.686 165.73 119.73C169.67 120.06 172.23 118.87 173.9 117.26Z\" fill=\"#FA4B51\"\/>\n<path id=\"Vector5656231 271\" d=\"M166.6 89.28C166.6 89.28 166.34 94.1 164.43 95.74C162.52 97.38 161.56 98.14 161.71 100.74C161.79 102.1 163.99 104.01 166.13 104.01C162.42 104.82 160.74 102.72 160.63 100.94C160.44 98.1 161.02 97.13 163.63 94.76C165.27 93.28 166.6 89.28 166.6 89.28Z\" fill=\"#37201C\"\/>\n<path id=\"Vector5656231 272\" d=\"M206.54 52.68C197.67 38.81 142.42 42.96 138.17 46.13C122.46 57.81 124.6 77.52 127.41 83.69C127.41 80.69 132.65 77.3 137.52 75.3C138.997 74.6947 140.51 74.1804 142.05 73.76C140.23 76.23 138.87 78.95 138.87 81.59C145.24 77.49 156.47 76.79 161.99 74.18C162.695 77.4739 164.056 80.5923 165.99 83.35C165.78 80.01 169.06 74.9 178.09 73.13C176.4 75.72 175.02 78.24 175.53 78.56C183.09 77.19 194.53 75.15 197.93 71.63C200.72 74.19 203.22 76.04 203.11 83.54C215.39 76.31 211.22 59.65 206.54 52.68Z\" fill=\"#231F20\"\/>\n<path id=\"Vector5656231 273\" d=\"M171.25 53C166.13 55.66 162.71 62.08 164.31 68C164.333 68.1155 164.396 68.2194 164.487 68.2941C164.578 68.3687 164.692 68.4095 164.81 68.4095C164.928 68.4095 165.042 68.3687 165.133 68.2941C165.224 68.2194 165.287 68.1155 165.31 68C166.44 62.44 167.24 57.41 171.62 53.46C171.85 53.21 171.53 52.84 171.25 53Z\" fill=\"#1F0601\"\/>\n<path id=\"Vector5656231 274\" d=\"M160 51.2701C157.17 60.0501 150.22 65.5901 144.24 71.9801C144.192 72.0294 144.164 72.0941 144.159 72.1625C144.155 72.231 144.175 72.2988 144.215 72.354C144.256 72.4091 144.315 72.4481 144.382 72.4638C144.449 72.4796 144.519 72.4712 144.58 72.4401C148.555 70.2288 152.034 67.2234 154.798 63.6107C157.563 59.998 159.555 55.8553 160.65 51.4401C160.67 51.3951 160.679 51.3464 160.678 51.2973C160.677 51.2482 160.666 51.2 160.644 51.1558C160.623 51.1117 160.592 51.0727 160.554 51.0415C160.516 51.0104 160.472 50.9878 160.424 50.9754C160.377 50.963 160.327 50.961 160.279 50.9696C160.231 50.9782 160.185 50.9971 160.144 51.0251C160.104 51.0531 160.07 51.0895 160.045 51.1318C160.02 51.1741 160.005 51.2213 160 51.2701Z\" fill=\"#1F0601\"\/>\n<path id=\"Vector5656231 275\" d=\"M151.12 57.7699C149.84 60.5699 147.53 62.3399 145.83 64.7699C145.61 65.0899 145.98 65.5899 146.34 65.4499C149.34 64.2599 150.84 60.9599 151.53 57.9099C151.59 57.7099 151.23 57.5299 151.12 57.7699Z\" fill=\"#1F0601\"\/>\n<path id=\"Vector5656231 276\" d=\"M192.82 43.8201C192.794 43.7885 192.758 43.7671 192.718 43.7598C192.678 43.7526 192.637 43.7599 192.602 43.7804C192.567 43.801 192.54 43.8335 192.527 43.8719C192.514 43.9104 192.515 43.9523 192.53 43.9901C194.427 47.4486 195.479 51.3071 195.6 55.2501C195.76 59.2501 194.07 62.7801 192.73 66.4401C192.52 67.0301 193.29 67.3601 193.73 67.0101C200.05 61.1801 197 50.0001 192.82 43.8201Z\" fill=\"#1F0601\"\/>\n<path id=\"Vector5656231 277\" d=\"M191 52.5199C190.91 52.3599 190.62 52.4599 190.69 52.6499C191.481 54.6174 191.59 56.7931 191 58.8299C190.57 60.5199 189.67 62.0099 189.28 63.6899C189.256 63.7743 189.26 63.8642 189.292 63.9459C189.324 64.0275 189.382 64.0964 189.457 64.1419C189.532 64.1874 189.62 64.2069 189.707 64.1975C189.795 64.1881 189.876 64.1503 189.94 64.0899C193.15 61.2299 193.17 55.9999 191 52.5199Z\" fill=\"#1F0601\"\/>\n<path id=\"Vector5656231 278\" d=\"M164 30.5699C156.88 29.0399 148.5 33.5699 144.08 39.1799C143.75 39.6099 144.2 40.3899 144.7 40.0099C150.4 35.6699 156.7 31.8799 163.92 31.1399C164.2 31.1099 164.31 30.6399 164 30.5699Z\" fill=\"#1F0601\"\/>\n<path id=\"Vector5656231 279\" d=\"M207.56 53.4199C207.45 53.1899 207.05 53.3599 207.15 53.5999C209.74 60.2199 209.26 66.5299 207.59 73.3199C207.48 73.7599 208.12 74.0799 208.3 73.6399C211.11 66.8499 210.66 60.0499 207.56 53.4199Z\" fill=\"#1F0601\"\/>\n<path id=\"Vector5656231 280\" d=\"M137.66 53.0601C131.3 59.1201 125.96 71.1801 128.84 80.1301C128.885 80.2692 128.977 80.3881 129.101 80.4657C129.225 80.5434 129.372 80.5748 129.517 80.5545C129.661 80.5342 129.794 80.4634 129.892 80.3546C129.989 80.2459 130.045 80.1061 130.05 79.9601C130.8 70.5501 131.7 60.8601 137.98 53.4001C138.17 53.1701 137.88 52.8601 137.66 53.0601Z\" fill=\"#1F0601\"\/>\n<path id=\"Vector5656231 281\" d=\"M64.28 136.64C64.28 136.64 75.5 146.41 75.13 148.64C74.7 151.26 72.5501 154.95 70.4101 154.79C68.2701 154.63 61.5401 154.98 60.5701 153.63C59.6001 152.28 57.6401 136.29 59.2701 135.63C60.9001 134.97 64.28 136.64 64.28 136.64Z\" fill=\"#9E5B44\"\/>\n<path id=\"Vector5656231 282\" d=\"M72.51 151C70.94 151.28 67.91 148.28 67.15 146.84C66.0275 144.766 65.4333 142.448 65.42 140.09C65.42 140.09 64.62 138.43 59.21 137.58C55.34 136.97 55.45 131.94 56.87 132.2C63.1 133.36 65.48 132.83 67.79 134.66C70.1 136.49 75.05 142.8 75.51 147.74C75.69 149.69 74.39 150.64 72.51 151Z\" fill=\"#B57D68\"\/>\n<path id=\"Vector5656231 283\" d=\"M182.37 137C182.315 136.783 182.197 136.588 182.031 136.438C181.864 136.289 181.656 136.194 181.435 136.163C181.213 136.133 180.988 136.17 180.787 136.269C180.587 136.369 180.42 136.526 180.31 136.72C177.87 141.37 176.78 146.31 172.06 149.34C165.75 153.34 160.24 140.79 159.78 136.22C159.787 136.186 159.787 136.152 159.779 136.119C159.771 136.085 159.755 136.054 159.734 136.028C159.712 136.001 159.685 135.979 159.654 135.965C159.623 135.95 159.589 135.942 159.555 135.942C159.521 135.942 159.487 135.95 159.456 135.965C159.425 135.979 159.398 136.001 159.376 136.028C159.355 136.054 159.339 136.085 159.331 136.119C159.323 136.152 159.323 136.186 159.33 136.22C158.77 143.52 162.66 151.77 170.33 152.5C176.15 153.05 183.06 142.25 182.37 137Z\" fill=\"#B5535E\"\/>\n<path id=\"Vector5656231 284\" d=\"M130.07 185.53C121.79 180.14 123.23 167.44 118.89 159.7C118.861 159.642 118.813 159.597 118.755 159.57C118.696 159.544 118.63 159.538 118.568 159.555C118.506 159.571 118.451 159.608 118.413 159.66C118.375 159.712 118.357 159.776 118.36 159.84C117.74 164.84 120.01 171.34 121.29 176.08C122.57 180.82 124.35 185.8 128.2 188.85C130.06 190.33 132.13 186.88 130.07 185.53Z\" fill=\"#B5535E\"\/>\n<path id=\"Vector5656231 285\" d=\"M223.1 146.7C223.04 146.6 222.86 146.57 222.81 146.7C221.26 150.45 221.68 155.04 221.26 159.05C220.61 165.34 219.65 171.35 216.6 176.93C215.46 179.02 218.6 180.93 219.71 178.81C222.322 173.835 223.945 168.402 224.49 162.81C225 157.92 225.84 151 223.1 146.7Z\" fill=\"#B5535E\"\/>\n<path id=\"Vector5656231 286\" d=\"M162.78 278C160.98 292 158.78 306 156.99 320C155.41 332.51 153.37 346 155.08 358.62C155.15 359.18 155.92 358.98 155.96 358.5C157.11 345.67 157.09 332.84 158.61 320C160.27 306 162.35 292.12 163.23 278C163.25 277.65 162.81 277.67 162.78 278Z\" fill=\"#4B3321\"\/>\n<path id=\"Vector5656231 287\" d=\"M205.47 316.58C205.66 301.86 205.35 287.35 204.23 272.67C204.23 272.45 203.89 272.44 203.9 272.67C205.42 300.67 203.71 328.13 201.9 355.97C201.9 356.39 202.43 356.4 202.56 356.06C207.21 344.07 205.31 329.23 205.47 316.58Z\" fill=\"#4B3321\"\/>\n<path id=\"Vector5656231 288\" d=\"M341.76 43.7H273.86V135.8H341.76V43.7Z\" fill=\"#F7E8B4\"\/>\n<g id=\"fourmsg\">\n<g id=\"msg fade\">\n<path id=\"Vector5656231 289\" d=\"M359.53 101.83H313.74C311.362 101.843 309.085 102.797 307.408 104.484C305.731 106.17 304.79 108.452 304.79 110.83V111C304.797 112.835 305.365 114.624 306.418 116.127C307.471 117.63 308.958 118.776 310.68 119.41L305.74 128.58L317.22 119.95H359.53C361.917 119.95 364.206 119.002 365.894 117.314C367.582 115.626 368.53 113.337 368.53 110.95V110.77C368.514 108.393 367.559 106.12 365.873 104.445C364.187 102.77 361.907 101.83 359.53 101.83Z\" fill=\"#8CD0C4\"\/>\n<path id=\"Vector5656231 290\" d=\"M319.13 115L317.92 113H316.09V115H314.75V108H317.67C319.48 108 320.5 108.87 320.5 110.4C320.538 110.875 320.424 111.35 320.177 111.758C319.929 112.165 319.559 112.485 319.12 112.67L320.65 114.99L319.13 115ZM316.13 111.76H317.71C318.71 111.76 319.27 111.33 319.27 110.45C319.27 109.57 318.71 109.18 317.71 109.18H316.13V111.76Z\" fill=\"white\"\/>\n<path id=\"Vector5656231 291\" d=\"M327.09 108.05V109.22H323.31V110.94H326.7V112.11H323.31V113.87H327.21V115H322V108L327.09 108.05Z\" fill=\"white\"\/>\n<path id=\"Vector5656231 292\" d=\"M333.12 113.56H329.71L329.09 115.04H327.7L330.76 108.04H332.15L335.15 115.04H333.71L333.12 113.56ZM332.64 112.41L331.42 109.48L330.19 112.41H332.64Z\" fill=\"white\"\/>\n<path id=\"Vector5656231 293\" d=\"M342.57 111.54C342.577 112.018 342.484 112.492 342.299 112.932C342.113 113.372 341.838 113.769 341.491 114.098C341.145 114.427 340.734 114.68 340.284 114.842C339.835 115.005 339.357 115.072 338.88 115.04H336V108.04H338.91C339.385 108.008 339.862 108.075 340.31 108.238C340.758 108.4 341.167 108.654 341.511 108.983C341.856 109.313 342.128 109.71 342.31 110.15C342.492 110.59 342.581 111.064 342.57 111.54ZM341.21 111.54C341.223 111.234 341.172 110.928 341.061 110.642C340.95 110.356 340.781 110.097 340.566 109.879C340.35 109.661 340.091 109.49 339.806 109.377C339.522 109.264 339.216 109.21 338.91 109.22H337.36V113.85H339C339.298 113.852 339.594 113.793 339.869 113.676C340.144 113.56 340.392 113.389 340.599 113.174C340.805 112.959 340.966 112.704 341.071 112.425C341.176 112.146 341.224 111.848 341.21 111.55V111.54Z\" fill=\"white\"\/>\n<path id=\"Vector5656231 294\" d=\"M345.08 108.05V115.05H343.74V108.05H345.08Z\" fill=\"white\"\/>\n<path id=\"Vector5656231 295\" d=\"M348.06 108.05L351.67 112.83V108.05H353V115.05H351.7L348.1 110.27V115H346.79V108L348.06 108.05Z\" fill=\"white\"\/>\n<path id=\"Vector5656231 296\" d=\"M359.42 111.56H360.59V114.19C359.78 114.767 358.814 115.085 357.82 115.1C357.339 115.12 356.858 115.041 356.409 114.869C355.959 114.697 355.548 114.435 355.203 114.1C354.857 113.764 354.584 113.362 354.398 112.917C354.213 112.472 354.121 111.995 354.126 111.513C354.132 111.031 354.235 110.556 354.43 110.115C354.625 109.675 354.908 109.279 355.261 108.951C355.614 108.623 356.03 108.371 356.484 108.209C356.937 108.047 357.419 107.98 357.9 108.01C358.902 108.014 359.871 108.368 360.64 109.01L359.88 110.01C359.332 109.512 358.62 109.234 357.88 109.23C357.257 109.23 356.659 109.478 356.218 109.918C355.778 110.359 355.53 110.957 355.53 111.58C355.53 112.203 355.778 112.801 356.218 113.242C356.659 113.682 357.257 113.93 357.88 113.93C358.412 113.91 358.931 113.759 359.39 113.49L359.42 111.56Z\" fill=\"white\"\/>\n<\/g>\n<g id=\"msg fade 2\">\n<path id=\"Vector5656231 297\" d=\"M254.35 86.0901H300.13C302.508 86.1033 304.785 87.0574 306.462 88.7438C308.139 90.4301 309.08 92.7118 309.08 95.0901V95.2701C309.073 97.1052 308.505 98.8943 307.452 100.397C306.399 101.9 304.912 103.046 303.19 103.68L308.13 112.85L296.65 104.22H254.35C251.963 104.22 249.674 103.272 247.986 101.584C246.298 99.8962 245.35 97.607 245.35 95.2201V95.0001C245.374 92.6288 246.332 90.3626 248.018 88.6942C249.703 87.0258 251.979 86.09 254.35 86.0901Z\" fill=\"#FF8059\"\/>\n<path id=\"Vector5656231 298\" d=\"M256.92 91.9001L258.52 97.4001L260.12 91.9001H261.44L263.04 97.4001L264.63 91.9001H266L263.68 98.9001H262.3L260.74 93.6601L259.16 98.9001H257.78L255.47 91.9001H256.92Z\" fill=\"white\"\/>\n<path id=\"Vector5656231 299\" d=\"M271.15 98.8801L269.94 96.8201H268.11V98.8201H266.78V91.8201H269.69C271.5 91.8201 272.53 92.6901 272.53 94.2201C272.565 94.6964 272.45 95.1717 272.201 95.579C271.951 95.9863 271.58 96.305 271.14 96.4901L272.68 98.8001L271.15 98.8801ZM268.15 95.6501H269.73C270.73 95.6501 271.29 95.2201 271.29 94.3401C271.29 93.4601 270.73 93.0601 269.73 93.0601H268.15V95.6501Z\" fill=\"white\"\/>\n<path id=\"Vector5656231 300\" d=\"M275.33 91.9001V98.9001H274V91.9001H275.33Z\" fill=\"white\"\/>\n<path id=\"Vector5656231 301\" d=\"M282 91.9001V93.0801H279.82V98.8801H278.47V93.0801H276.3V91.9001H282Z\" fill=\"white\"\/>\n<path id=\"Vector5656231 302\" d=\"M284.25 91.9001V98.9001H282.92V91.9001H284.25Z\" fill=\"white\"\/>\n<path id=\"Vector5656231 303\" d=\"M287.24 91.9001L290.84 96.6801V91.9001H292.14V98.9001H290.87L287.28 94.1301V98.9001H286V91.9001H287.24Z\" fill=\"white\"\/>\n<path id=\"Vector5656231 304\" d=\"M298.6 95.4101H299.77V98.0001C298.959 98.5739 297.993 98.8878 297 98.9001C296.513 98.9308 296.024 98.8606 295.565 98.6939C295.106 98.5272 294.686 98.2676 294.332 97.9313C293.978 97.595 293.697 97.1892 293.507 96.7394C293.317 96.2896 293.221 95.8054 293.227 95.317C293.233 94.8287 293.339 94.3467 293.539 93.9013C293.739 93.4559 294.029 93.0566 294.391 92.7284C294.753 92.4001 295.178 92.1501 295.641 91.9938C296.103 91.8375 296.593 91.7784 297.08 91.8201C298.082 91.824 299.051 92.1777 299.82 92.8201L299.06 93.8201C298.514 93.3187 297.801 93.0372 297.06 93.0301C296.738 93.0091 296.415 93.0544 296.111 93.1633C295.807 93.2721 295.528 93.4422 295.293 93.6629C295.057 93.8836 294.869 94.1504 294.741 94.4466C294.613 94.7428 294.546 95.0622 294.546 95.3851C294.546 95.708 294.613 96.0274 294.741 96.3236C294.869 96.6198 295.057 96.8866 295.293 97.1073C295.528 97.328 295.807 97.4981 296.111 97.6069C296.415 97.7158 296.738 97.7611 297.06 97.7401C297.592 97.7201 298.111 97.5689 298.57 97.3001L298.6 95.4101Z\" fill=\"white\"\/>\n<\/g>\n<g id=\"msg fade 3\">\n<path id=\"Vector5656231 305\" d=\"M362.19 67.09H316.41C315.226 67.082 314.052 67.3094 312.956 67.7588C311.861 68.2083 310.866 68.8709 310.028 69.7083C309.191 70.5457 308.528 71.5409 308.079 72.6364C307.629 73.732 307.402 74.9059 307.41 76.09V76.27C307.409 78.1071 307.973 79.9002 309.027 81.405C310.081 82.9098 311.573 84.0533 313.3 84.6801L308.3 93.85L319.79 85.2201H362.09C364.468 85.2069 366.745 84.2528 368.422 82.5664C370.099 80.88 371.04 78.5984 371.04 76.2201V76.0001C371.017 73.6545 370.079 71.4107 368.426 69.7464C366.773 68.0822 364.535 67.129 362.19 67.09Z\" fill=\"#F3B756\"\/>\n<path id=\"Vector5656231 306\" d=\"M316.49 74C315.86 74 315.49 74.23 315.49 74.66C315.49 76.08 319.25 75.31 319.24 77.81C319.24 79.12 318.1 79.88 316.56 79.88C315.474 79.8732 314.427 79.4756 313.61 78.76L314.17 77.63C314.834 78.2308 315.685 78.5841 316.58 78.63C317.33 78.63 317.78 78.35 317.78 77.86C317.78 76.41 314.03 77.23 314.03 74.75C314.03 73.53 315.03 72.75 316.64 72.75C317.536 72.7536 318.413 73.0101 319.17 73.49L318.63 74.65C317.983 74.2559 317.247 74.0323 316.49 74Z\" fill=\"white\"\/>\n<path id=\"Vector5656231 307\" d=\"M326.09 75.2C326.09 76.8 325.09 77.72 323.33 77.72H321.8V79.78H320.46V72.78H323.33C325.09 72.79 326.09 73.66 326.09 75.2ZM324.83 75.2C324.83 74.34 324.26 73.92 323.26 73.92H321.8V76.51H323.26C324.26 76.55 324.83 76.12 324.83 75.24V75.2Z\" fill=\"white\"\/>\n<path id=\"Vector5656231 308\" d=\"M332.32 72.79V74H328.54V75.73H331.93V76.9H328.54V78.65H332.44V79.82H327.2V72.82L332.32 72.79Z\" fill=\"white\"\/>\n<path id=\"Vector5656231 309\" d=\"M338.35 78.3H334.94L334.32 79.78H332.93L335.99 72.78H337.38L340.38 79.78H339L338.35 78.3ZM337.87 77.15L336.65 74.22L335.42 77.15H337.87Z\" fill=\"white\"\/>\n<path id=\"Vector5656231 310\" d=\"M345.89 79.78L343.71 76.78L342.59 78V79.76H341.25V72.76H342.59V76.18L345.76 72.76H347.31L344.65 75.76L347.5 79.76L345.89 79.78Z\" fill=\"white\"\/>\n<path id=\"Vector5656231 311\" d=\"M349.84 72.79V79.79H348.5V72.79H349.84Z\" fill=\"white\"\/>\n<path id=\"Vector5656231 312\" d=\"M352.82 72.79L356.43 77.57V72.79H357.72V79.79H356.46L352.86 75V79.77H351.55V72.77L352.82 72.79Z\" fill=\"white\"\/>\n<path id=\"Vector5656231 313\" d=\"M364.18 76.31H365.35V78.93C364.54 79.5074 363.574 79.8248 362.58 79.84C362.099 79.8595 361.618 79.7809 361.169 79.609C360.719 79.437 360.308 79.1752 359.963 78.8397C359.617 78.5041 359.344 78.1017 359.158 77.657C358.973 77.2123 358.881 76.7345 358.886 76.2529C358.892 75.7712 358.995 75.2957 359.19 74.8553C359.385 74.4148 359.668 74.0187 360.021 73.691C360.374 73.3633 360.79 73.1109 361.244 72.9491C361.697 72.7874 362.179 72.7196 362.66 72.75C363.662 72.7539 364.631 73.1076 365.4 73.75L364.64 74.75C364.094 74.2486 363.381 73.9671 362.64 73.96C362.017 73.96 361.419 74.2076 360.978 74.6483C360.538 75.089 360.29 75.6867 360.29 76.31C360.29 76.9333 360.538 77.531 360.978 77.9717C361.419 78.4124 362.017 78.66 362.64 78.66C363.172 78.64 363.691 78.4888 364.15 78.22L364.18 76.31Z\" fill=\"white\"\/>\n<\/g>\n<g id=\"msg fade 4\">\n<path id=\"Vector5656231 314\" d=\"M256.14 51.8401H301.93C304.3 51.8532 306.568 52.8004 308.244 54.476C309.92 56.1516 310.867 58.4205 310.88 60.7901V61.0001C310.881 62.8384 310.314 64.6323 309.259 66.1372C308.203 67.6421 306.709 68.785 304.98 69.4101L309.93 78.5801L298.45 69.9501H256.14C253.762 69.9369 251.485 68.9828 249.808 67.2964C248.131 65.61 247.19 63.3284 247.19 60.9501V60.7701C247.208 58.4039 248.158 56.1402 249.833 54.4689C251.508 52.7976 253.774 51.8532 256.14 51.8401Z\" fill=\"#5198BF\"\/>\n<path id=\"Vector5656231 315\" d=\"M254.54 57.6001V63.3801H257.54V64.5901H253.2V57.5901L254.54 57.6001Z\" fill=\"white\"\/>\n<path id=\"Vector5656231 316\" d=\"M259.94 57.6001V64.6001H258.6V57.6001H259.94Z\" fill=\"white\"\/>\n<path id=\"Vector5656231 317\" d=\"M264 58.76C263.37 58.76 263 58.99 263 59.42C263 60.84 266.76 60.07 266.75 62.57C266.75 63.88 265.61 64.64 264.07 64.64C262.967 64.6453 261.9 64.2469 261.07 63.52L261.63 62.39C262.294 62.9908 263.146 63.3441 264.04 63.39C264.79 63.39 265.24 63.11 265.24 62.62C265.24 61.16 261.49 61.99 261.49 59.51C261.49 58.29 262.49 57.51 264.1 57.51C264.996 57.5136 265.873 57.7701 266.63 58.25L266.09 59.41C265.458 59.0239 264.74 58.8005 264 58.76Z\" fill=\"white\"\/>\n<path id=\"Vector5656231 318\" d=\"M272.85 57.6001V58.7901H270.67V64.5901H269.32V58.7901H267.15V57.6001H272.85Z\" fill=\"white\"\/>\n<path id=\"Vector5656231 319\" d=\"M278.91 57.6001V58.7701H275.13V60.5001H278.52V61.6601H275.13V63.4201H279V64.5901H273.76V57.5901L278.91 57.6001Z\" fill=\"white\"\/>\n<path id=\"Vector5656231 320\" d=\"M281.66 57.6001L285.26 62.3801V57.6001H286.56V64.6001H285.29L281.7 59.8301V64.6001H280.39V57.6001H281.66Z\" fill=\"white\"\/>\n<path id=\"Vector5656231 321\" d=\"M289.61 57.6001V64.6001H288.28V57.6001H289.61Z\" fill=\"white\"\/>\n<path id=\"Vector5656231 322\" d=\"M292.6 57.6001L296.2 62.3801V57.6001H297.5V64.6001H296.23L292.64 59.8301V64.6001H291.33V57.6001H292.6Z\" fill=\"white\"\/>\n<path id=\"Vector5656231 323\" d=\"M304 61.1101H305.16V63.7401C304.355 64.3184 303.391 64.636 302.4 64.6501C301.919 64.6696 301.438 64.591 300.989 64.4191C300.539 64.2471 300.128 63.9853 299.783 63.6498C299.437 63.3142 299.164 62.9118 298.978 62.4671C298.793 62.0224 298.701 61.5446 298.706 61.063C298.712 60.5813 298.815 60.1058 299.01 59.6654C299.205 59.2249 299.488 58.8288 299.841 58.5011C300.194 58.1734 300.61 57.921 301.064 57.7592C301.517 57.5974 301.999 57.5297 302.48 57.5601C303.479 57.5621 304.446 57.9162 305.21 58.5601L304.46 59.5601C303.914 59.0587 303.201 58.7772 302.46 58.7701C301.837 58.7701 301.239 59.0177 300.798 59.4584C300.358 59.8991 300.11 60.4968 300.11 61.1201C300.11 61.7434 300.358 62.3411 300.798 62.7818C301.239 63.2225 301.837 63.4701 302.46 63.4701C303.005 63.4459 303.535 63.2842 304 63.0001V61.1101Z\" fill=\"white\"\/>\n<\/g>\n<\/g>\n<path id=\"Vector5656231 324\" d=\"M57.7431 59.1785L54.4738 59.4433L62.5911 159.675L65.8603 159.41L57.7431 59.1785Z\" fill=\"#1EB1FA\"\/>\n<path id=\"worlddot\" d=\"M52.1 86.18C50.4282 86.1795 48.7582 86.0726 47.1 85.86C46.9077 85.8348 46.7333 85.7343 46.6152 85.5805C46.497 85.4267 46.4448 85.2323 46.47 85.04C46.4952 84.8477 46.5957 84.6733 46.7495 84.5552C46.9033 84.437 47.0977 84.3848 47.29 84.41C48.8786 84.6135 50.4784 84.717 52.08 84.72C52.1772 84.7187 52.2737 84.7365 52.364 84.7725C52.4542 84.8085 52.5366 84.8619 52.6062 84.9297C52.6759 84.9974 52.7315 85.0783 52.7699 85.1676C52.8083 85.2569 52.8287 85.3528 52.83 85.45C52.8313 85.5462 52.8134 85.6418 52.7772 85.731C52.741 85.8201 52.6872 85.9011 52.6192 85.9692C52.5511 86.0372 52.4701 86.091 52.3809 86.1272C52.2918 86.1634 52.1962 86.1814 52.1 86.18ZM57 85.86C56.8216 85.8592 56.6495 85.7941 56.5154 85.6765C56.3812 85.5589 56.2941 85.3968 56.27 85.22C56.2574 85.1248 56.2636 85.028 56.2885 84.9352C56.3133 84.8424 56.3563 84.7554 56.4148 84.6792C56.4733 84.6031 56.5463 84.5392 56.6296 84.4913C56.7128 84.4433 56.8047 84.4123 56.9 84.4C58.5017 84.188 60.0883 83.874 61.65 83.46C61.837 83.4096 62.0363 83.4356 62.2042 83.5322C62.372 83.6287 62.4946 83.788 62.545 83.975C62.5954 84.162 62.5694 84.3613 62.4729 84.5292C62.3763 84.697 62.217 84.8196 62.03 84.87C60.4062 85.3079 58.7562 85.6419 57.09 85.87L57 85.86ZM42.32 84.92C42.257 84.9296 42.193 84.9296 42.13 84.92C40.5068 84.4873 38.9134 83.9495 37.36 83.31C37.2714 83.2732 37.1908 83.2194 37.123 83.1515C37.0552 83.0836 37.0014 83.003 36.9647 82.9143C36.928 82.8256 36.9092 82.7306 36.9092 82.6346C36.9093 82.5387 36.9282 82.4437 36.965 82.355C37.0018 82.2664 37.0556 82.1858 37.1235 82.118C37.1914 82.0502 37.272 81.9964 37.3607 81.9597C37.4494 81.9231 37.5444 81.9042 37.6404 81.9042C37.7363 81.9043 37.8314 81.9232 37.92 81.96C39.4167 82.5706 40.9496 83.0882 42.51 83.51C42.6968 83.5593 42.8565 83.6807 42.9539 83.8475C43.0514 84.0144 43.0788 84.213 43.03 84.4C42.984 84.548 42.8926 84.6779 42.7688 84.7712C42.645 84.8645 42.495 84.9165 42.34 84.92H42.32ZM66.51 83.31C66.365 83.3099 66.2233 83.2671 66.1024 83.1871C65.9815 83.1071 65.8868 82.9934 65.83 82.86C65.7858 82.7694 65.7608 82.6706 65.7566 82.5698C65.7525 82.469 65.7693 82.3685 65.8059 82.2746C65.8426 82.1806 65.8983 82.0953 65.9695 82.0239C66.0408 81.9526 66.1261 81.8968 66.22 81.86C67.7074 81.2396 69.1537 80.5248 70.55 79.72C70.634 79.6701 70.7271 79.6372 70.8238 79.6233C70.9206 79.6094 71.0191 79.6146 71.1138 79.6388C71.2086 79.6629 71.2976 79.7055 71.3759 79.764C71.4541 79.8226 71.5201 79.896 71.57 79.98C71.6199 80.0641 71.6528 80.1571 71.6667 80.2539C71.6806 80.3506 71.6754 80.4491 71.6513 80.5439C71.6271 80.6386 71.5845 80.7276 71.526 80.8059C71.4674 80.8841 71.394 80.9501 71.31 81C69.8603 81.8407 68.3571 82.5857 66.81 83.23C66.7229 83.275 66.6277 83.3022 66.53 83.31H66.51ZM33.24 81.16C33.1098 81.1612 32.9818 81.1266 32.87 81.06C31.4196 80.2185 30.0235 79.2867 28.69 78.27C28.6001 78.2168 28.5225 78.1453 28.4623 78.06C28.4021 77.9747 28.3606 77.8776 28.3405 77.7751C28.3205 77.6727 28.3224 77.5671 28.346 77.4654C28.3697 77.3637 28.4146 77.2682 28.4778 77.1851C28.541 77.102 28.6211 77.0332 28.7128 76.9833C28.8045 76.9333 28.9057 76.9033 29.0098 76.8953C29.1139 76.8873 29.2185 76.9013 29.3168 76.9366C29.4151 76.9719 29.5048 77.0276 29.58 77.1C30.8534 78.0827 32.1896 78.9812 33.58 79.79C33.6636 79.8377 33.737 79.9015 33.7959 79.9776C33.8548 80.0538 33.898 80.1409 33.9231 80.2338C33.9482 80.3268 33.9546 80.4238 33.9421 80.5192C33.9296 80.6147 33.8983 80.7067 33.85 80.79C33.79 80.9 33.702 80.9922 33.5949 81.0572C33.4877 81.1222 33.3653 81.1577 33.24 81.16ZM75 78.38C74.8874 78.3804 74.7762 78.3544 74.6755 78.304C74.5748 78.2536 74.4873 78.1803 74.42 78.09C74.3089 77.9386 74.2604 77.7502 74.2846 77.564C74.3088 77.3777 74.4039 77.208 74.55 77.09C75.8289 76.1077 77.0415 75.042 78.18 73.9C78.3175 73.777 78.4955 73.709 78.68 73.709C78.8645 73.709 79.0425 73.777 79.18 73.9C79.3073 74.0354 79.3781 74.2142 79.3781 74.4C79.3781 74.5858 79.3073 74.7646 79.18 74.9C77.9937 76.0878 76.731 77.1969 75.4 78.22C75.2858 78.3124 75.1464 78.3681 75 78.38ZM25.42 75.17C25.2291 75.1694 25.046 75.094 24.91 74.96C23.7215 73.7743 22.6124 72.5116 21.59 71.18C21.4789 71.0286 21.4304 70.8402 21.4546 70.654C21.4788 70.4677 21.5739 70.298 21.72 70.18C21.8734 70.0724 22.062 70.027 22.2476 70.053C22.4332 70.0789 22.602 70.1744 22.72 70.32C23.7049 71.5968 24.7704 72.8092 25.91 73.95C26.0395 74.0842 26.1119 74.2635 26.1119 74.45C26.1119 74.6365 26.0395 74.8158 25.91 74.95C25.8468 75.0171 25.771 75.0711 25.6869 75.1089C25.6029 75.1466 25.5121 75.1674 25.42 75.17ZM82 71.41C81.8401 71.4141 81.6841 71.3609 81.56 71.26C81.4123 71.1435 81.3153 70.9744 81.2892 70.7881C81.2631 70.6018 81.31 70.4126 81.42 70.26C82.4027 68.9866 83.3012 67.6504 84.11 66.26C84.1579 66.1766 84.2218 66.1035 84.298 66.0448C84.3742 65.9861 84.4612 65.943 84.5541 65.9179C84.6469 65.8928 84.7438 65.8863 84.8392 65.8987C84.9346 65.911 85.0266 65.9421 85.11 65.99C85.1934 66.0379 85.2665 66.1018 85.3252 66.178C85.3839 66.2542 85.427 66.3412 85.4521 66.4341C85.4772 66.527 85.4837 66.6238 85.4713 66.7192C85.459 66.8146 85.4279 66.9066 85.38 66.99C84.5385 68.4404 83.6067 69.8365 82.59 71.17C82.5157 71.2514 82.4242 71.3152 82.3221 71.3567C82.2201 71.3983 82.11 71.4165 82 71.41ZM19.43 67.41C19.3007 67.4079 19.174 67.3728 19.062 67.3081C18.95 67.2433 18.8564 67.1511 18.79 67.04C17.9473 65.5913 17.2023 64.088 16.56 62.54C16.5072 62.4495 16.4746 62.3487 16.4642 62.2444C16.4538 62.1402 16.466 62.0349 16.5 61.9358C16.5339 61.8367 16.5888 61.746 16.6609 61.67C16.733 61.594 16.8206 61.5344 16.9178 61.4952C17.0149 61.456 17.1194 61.4383 17.2241 61.4431C17.3287 61.4479 17.4311 61.4751 17.5243 61.523C17.6175 61.5709 17.6993 61.6383 17.7641 61.7206C17.8289 61.8029 17.8753 61.8982 17.9 62C18.5218 63.4886 19.24 64.935 20.05 66.33C20.1448 66.4989 20.1696 66.6982 20.1191 66.8851C20.0687 67.0721 19.9469 67.2318 19.78 67.33C19.6656 67.3748 19.5423 67.3919 19.42 67.38L19.43 67.41ZM86.93 62.92C86.8372 62.9343 86.7428 62.9343 86.65 62.92C86.5571 62.8819 86.4727 62.8255 86.402 62.7541C86.3313 62.6828 86.2756 62.598 86.2383 62.5047C86.201 62.4114 86.1828 62.3116 86.1848 62.2112C86.1868 62.1107 86.209 62.0117 86.25 61.92C86.8664 60.4153 87.3842 58.872 87.8 57.3C87.8493 57.1132 87.9707 56.9536 88.1375 56.8561C88.3044 56.7586 88.503 56.7313 88.69 56.78C88.7839 56.802 88.8724 56.8428 88.95 56.9001C89.0276 56.9574 89.0927 57.0299 89.1414 57.1132C89.19 57.1965 89.2212 57.2888 89.233 57.3845C89.2448 57.4803 89.237 57.5774 89.21 57.67C88.7788 59.2937 88.2409 60.8871 87.6 62.44C87.5432 62.5734 87.4485 62.6871 87.3276 62.7671C87.2067 62.8471 87.065 62.8899 86.92 62.89L86.93 62.92ZM15.64 58.32C15.4799 58.3206 15.3241 58.2679 15.1974 58.1701C15.0706 58.0723 14.98 57.935 14.94 57.78C14.4964 56.161 14.1623 54.5139 13.94 52.85C13.9148 52.6577 13.967 52.4633 14.0852 52.3095C14.2033 52.1558 14.3777 52.0552 14.57 52.03C14.7623 52.0048 14.9567 52.057 15.1105 52.1752C15.2643 52.2933 15.3648 52.4677 15.39 52.66C15.6015 54.2593 15.9189 55.8428 16.34 57.4C16.389 57.5883 16.3619 57.7882 16.2646 57.9567C16.1673 58.1251 16.0076 58.2485 15.82 58.3C15.7565 58.3072 15.6924 58.3038 15.63 58.29L15.64 58.32ZM89.47 53.41H89.38C89.2847 53.3977 89.1928 53.3667 89.1096 53.3188C89.0263 53.2708 88.9533 53.207 88.8948 53.1308C88.8362 53.0546 88.7933 52.9676 88.7685 52.8748C88.7436 52.782 88.7374 52.6852 88.75 52.59C88.9535 50.9914 89.057 49.3816 89.06 47.77V47.61C89.06 47.4164 89.1369 47.2307 89.2738 47.0938C89.4107 46.9569 89.5964 46.88 89.79 46.88C89.9836 46.88 90.1693 46.9569 90.3062 47.0938C90.4431 47.2307 90.52 47.4164 90.52 47.61V47.75C90.5179 49.4217 90.411 51.0917 90.2 52.75C90.1755 52.9276 90.0865 53.0899 89.9501 53.2061C89.8136 53.3222 89.6392 53.3842 89.46 53.38L89.47 53.41ZM14.34 48.5C14.2461 48.5055 14.152 48.4917 14.0636 48.4594C13.9753 48.4272 13.8944 48.3772 13.826 48.3126C13.7577 48.248 13.7032 48.1701 13.6661 48.0836C13.6289 47.9972 13.6098 47.9041 13.61 47.81H14.34L13.61 47.74C13.6055 46.0684 13.7091 44.3983 13.92 42.74C13.9452 42.5477 14.0457 42.3733 14.1995 42.2552C14.3533 42.137 14.5477 42.0848 14.74 42.11C14.9323 42.1352 15.1067 42.2358 15.2248 42.3895C15.343 42.5433 15.3952 42.7377 15.37 42.93C15.1695 44.5054 15.0693 46.0919 15.07 47.68C15.0768 47.782 15.0632 47.8843 15.03 47.9809C14.9968 48.0776 14.9448 48.1666 14.8768 48.243C14.8089 48.3193 14.7264 48.3813 14.6342 48.4254C14.5421 48.4696 14.4421 48.4949 14.34 48.5ZM89.44 43.38C89.2637 43.3814 89.0929 43.318 88.9602 43.2019C88.8275 43.0858 88.742 42.925 88.72 42.75C88.4881 41.1503 88.1541 39.5671 87.72 38.01C87.6942 37.9174 87.6869 37.8207 87.6986 37.7253C87.7103 37.6299 87.7407 37.5377 87.7881 37.4541C87.8355 37.3705 87.8989 37.297 87.9747 37.238C88.0506 37.1789 88.1373 37.1354 88.23 37.11C88.3233 37.0829 88.421 37.075 88.5174 37.0867C88.6138 37.0984 88.7068 37.1295 88.7909 37.178C88.875 37.2266 88.9484 37.2917 89.0066 37.3694C89.0649 37.447 89.1069 37.5357 89.13 37.63C89.5725 39.2459 89.9066 40.8896 90.13 42.55C90.153 42.743 90.1002 42.9374 89.9827 43.0923C89.8652 43.2471 89.6921 43.3503 89.5 43.38H89.44ZM15.59 38.78H15.4C15.2132 38.7307 15.0536 38.6093 14.9561 38.4425C14.8586 38.2756 14.8312 38.077 14.88 37.89C15.3112 36.2663 15.8491 34.6729 16.49 33.12C16.527 33.0262 16.5827 32.9409 16.6539 32.8694C16.725 32.7979 16.81 32.7416 16.9037 32.7042C16.9973 32.6667 17.0976 32.6488 17.1985 32.6515C17.2993 32.6542 17.3985 32.6776 17.49 32.72C17.5839 32.7568 17.6692 32.8126 17.7405 32.8839C17.8117 32.9553 17.8674 33.0406 17.9041 33.1346C17.9407 33.2285 17.9575 33.3291 17.9534 33.4298C17.9492 33.5306 17.9242 33.6294 17.88 33.72C17.2668 35.2113 16.7524 36.7412 16.34 38.3C16.284 38.4506 16.1806 38.5789 16.0453 38.6654C15.91 38.752 15.7502 38.7922 15.59 38.78ZM86.86 33.89C86.7161 33.8905 86.5754 33.8479 86.456 33.7677C86.3366 33.6875 86.2439 33.5734 86.19 33.44C85.5551 31.9505 84.8235 30.5041 84 29.11C83.9513 29.0273 83.9194 28.9358 83.9062 28.8408C83.8929 28.7457 83.8985 28.649 83.9226 28.5561C83.9468 28.4632 83.989 28.376 84.0469 28.2995C84.1048 28.2229 84.1772 28.1585 84.26 28.11C84.4282 28.0169 84.6258 27.992 84.8119 28.0403C84.998 28.0887 85.1584 28.2067 85.26 28.37C86.1 29.8217 86.8482 31.3247 87.5 32.87C87.5427 32.9609 87.5665 33.0595 87.5699 33.1599C87.5733 33.2602 87.5562 33.3602 87.5198 33.4538C87.4833 33.5473 87.4281 33.6325 87.3577 33.704C87.2872 33.7756 87.203 33.8321 87.11 33.87C87.0284 33.8907 86.9439 33.8974 86.86 33.89ZM19.34 29.67C19.213 29.6709 19.0883 29.6363 18.98 29.57C18.8964 29.5223 18.823 29.4585 18.7641 29.3824C18.7052 29.3062 18.662 29.2191 18.6369 29.1262C18.6118 29.0332 18.6054 28.9363 18.6179 28.8408C18.6304 28.7453 18.6617 28.6533 18.71 28.57C19.5479 27.1174 20.4799 25.721 21.5 24.39C21.6165 24.2423 21.7856 24.1453 21.9719 24.1192C22.1582 24.0931 22.3474 24.14 22.5 24.25C22.6456 24.368 22.7411 24.5368 22.7671 24.7224C22.793 24.908 22.7476 25.0966 22.64 25.25C21.6608 26.5237 20.7655 27.8599 19.96 29.25C19.9042 29.3695 19.8171 29.4716 19.708 29.5456C19.5988 29.6195 19.4716 29.6625 19.34 29.67ZM81.91 25.39C81.7974 25.3904 81.6862 25.3644 81.5855 25.314C81.4848 25.2636 81.3973 25.1903 81.33 25.1C80.3378 23.8265 79.2657 22.6174 78.12 21.48C77.9927 21.3446 77.9219 21.1658 77.9219 20.98C77.9219 20.7942 77.9927 20.6154 78.12 20.48C78.2565 20.3549 78.4349 20.2855 78.62 20.2855C78.8051 20.2855 78.9835 20.3549 79.12 20.48C80.3053 21.6652 81.4142 22.9244 82.44 24.25C82.5241 24.3574 82.5764 24.4863 82.591 24.622C82.6056 24.7576 82.5819 24.8947 82.5225 25.0175C82.4632 25.1404 82.3706 25.2442 82.2552 25.3171C82.1399 25.39 82.0064 25.4291 81.87 25.43L81.91 25.39ZM25.32 21.85C25.2253 21.8508 25.1314 21.8326 25.0438 21.7966C24.9562 21.7605 24.8767 21.7073 24.81 21.64C24.6849 21.5035 24.6155 21.3251 24.6155 21.14C24.6155 20.9549 24.6849 20.7765 24.81 20.64C25.9952 19.4547 27.2544 18.3458 28.58 17.32C28.6562 17.2609 28.7432 17.2174 28.8362 17.192C28.9292 17.1665 29.0263 17.1596 29.1219 17.1717C29.2176 17.1838 29.3099 17.2146 29.3936 17.2623C29.4774 17.3101 29.5509 17.3738 29.61 17.45C29.6691 17.5262 29.7126 17.6132 29.7381 17.7062C29.7635 17.7992 29.7704 17.8963 29.7583 17.9919C29.7463 18.0876 29.7155 18.1799 29.6677 18.2637C29.6199 18.3474 29.5562 18.4209 29.48 18.48C28.2033 19.4649 26.9908 20.5304 25.85 21.67C25.7788 21.7349 25.695 21.7843 25.6038 21.8153C25.5126 21.8463 25.416 21.8581 25.32 21.85ZM74.92 18.45C74.7609 18.4493 74.6064 18.3966 74.48 18.3C73.2036 17.3275 71.8677 16.4358 70.48 15.63C70.3131 15.5318 70.1913 15.3721 70.1409 15.1851C70.0904 14.9982 70.1152 14.7989 70.21 14.63C70.2567 14.5454 70.32 14.471 70.396 14.4114C70.4721 14.3517 70.5594 14.308 70.6527 14.2828C70.746 14.2576 70.8435 14.2514 70.9392 14.2647C71.0349 14.278 71.127 14.3104 71.21 14.36C72.6672 15.192 74.067 16.1208 75.4 17.14C75.5461 17.258 75.6412 17.4277 75.6654 17.614C75.6896 17.8002 75.6411 17.9886 75.53 18.14C75.4608 18.237 75.3692 18.3158 75.263 18.3698C75.1568 18.4237 75.0391 18.4513 74.92 18.45ZM33.11 15.84C32.9813 15.8412 32.8547 15.8074 32.7438 15.7423C32.6328 15.6771 32.5416 15.583 32.48 15.47C32.43 15.3877 32.397 15.2961 32.383 15.2008C32.369 15.1054 32.3743 15.0083 32.3985 14.915C32.4228 14.8218 32.4655 14.7343 32.5241 14.6579C32.5828 14.5815 32.6562 14.5176 32.74 14.47C34.1917 13.63 35.6946 12.8819 37.24 12.23C37.3315 12.1876 37.4307 12.1642 37.5315 12.1615C37.6324 12.1588 37.7327 12.1767 37.8263 12.2142C37.92 12.2516 38.005 12.3079 38.0761 12.3794C38.1473 12.4509 38.203 12.5362 38.24 12.63C38.2773 12.7185 38.2966 12.8136 38.2966 12.9096C38.2967 13.0057 38.2775 13.1008 38.2402 13.1893C38.2029 13.2778 38.1483 13.358 38.0796 13.4251C38.0109 13.4922 37.9294 13.5449 37.84 13.58C36.3545 14.2052 34.9114 14.9267 33.52 15.74C33.3944 15.8085 33.2531 15.843 33.11 15.84ZM66.38 13.55C66.2848 13.5468 66.1905 13.5299 66.1 13.5C64.6078 12.9004 63.0778 12.3993 61.52 12C61.3317 11.9509 61.1706 11.8291 61.0721 11.6612C60.9737 11.4934 60.9459 11.2933 60.995 11.105C61.0441 10.9167 61.1659 10.7556 61.3338 10.6572C61.5016 10.5587 61.7017 10.5309 61.89 10.58C63.5121 11.0124 65.1053 11.5468 66.66 12.18C66.8198 12.2423 66.9525 12.3588 67.035 12.5092C67.1174 12.6596 67.1443 12.8342 67.1109 13.0024C67.0775 13.1705 66.9859 13.3216 66.8523 13.4291C66.7187 13.5365 66.5514 13.5935 66.38 13.59V13.55ZM42.19 12C42.0286 12.0012 41.8714 11.9488 41.7429 11.8511C41.6145 11.7534 41.522 11.6158 41.48 11.46C41.431 11.2718 41.4581 11.0718 41.5554 10.9033C41.6527 10.7349 41.8124 10.6116 42 10.56C43.6202 10.1212 45.2669 9.78718 46.93 9.55998C47.1131 9.55496 47.2916 9.61805 47.431 9.73706C47.5703 9.85607 47.6605 10.0226 47.6841 10.2042C47.7078 10.3859 47.6632 10.5699 47.5589 10.7206C47.4547 10.8713 47.2983 10.978 47.12 11.02C45.5206 11.2306 43.937 11.5479 42.38 11.97L42.19 12ZM56.86 11H56.77C55.208 10.7999 53.6348 10.6997 52.06 10.7H51.94C51.7598 10.679 51.5937 10.5925 51.4731 10.457C51.3525 10.3215 51.2859 10.1464 51.2859 9.96498C51.2859 9.78359 51.3525 9.60852 51.4731 9.47302C51.5937 9.33752 51.7598 9.25103 51.94 9.22998H52.05C53.7056 9.24429 55.3588 9.36118 57 9.57998C57.1936 9.59324 57.374 9.68287 57.5015 9.82915C57.6291 9.97543 57.6933 10.1664 57.68 10.36C57.6667 10.5536 57.5771 10.734 57.4308 10.8616C57.2846 10.9891 57.0936 11.0533 56.9 11.04L56.86 11Z\" fill=\"#1EB1FA\"\/>\n<path id=\"Vector5656231 325\" d=\"M52.06 78.17C68.8715 78.17 82.5 64.5416 82.5 47.73C82.5 30.9185 68.8715 17.29 52.06 17.29C35.2484 17.29 21.62 30.9185 21.62 47.73C21.62 64.5416 35.2484 78.17 52.06 78.17Z\" fill=\"#75DDFF\"\/>\n<path id=\"Vector5656231 326\" d=\"M27.21 38.1199C26.81 39.8699 26.83 41.2099 25.92 42.9099C25.0918 44.1575 24.6756 45.6334 24.73 47.1299C24.73 49.5599 23.99 56.8299 28.28 55.6999C31.83 54.7699 29.89 50.0999 32.41 48.0599C33.6 47.0599 35.15 47.4699 35.88 45.9299C36.61 44.3899 35.67 43.0099 36.88 41.7099C38.96 39.3899 43.29 40.3699 44.88 37.5799C42.34 36.0999 39.48 34.8399 40.88 31.0099C41.41 29.5899 43.11 28.4299 43.09 26.7499C43.09 24.5299 41.49 26.1099 40.03 24.9799C38.82 24.0399 40.03 22.2799 38.94 21.4699C38.6802 21.342 38.3946 21.2754 38.105 21.2754C37.8155 21.2754 37.5298 21.342 37.27 21.4699C32.8685 23.5193 29.1805 26.8381 26.68 30.9999C30.59 30.4699 27.55 36.6699 27.21 38.1199Z\" fill=\"#00B298\"\/>\n<path id=\"Vector5656231 327\" d=\"M38.13 48.3301C37.23 49.1701 35.98 48.3301 35.03 49.1201C34.64 49.4501 34.12 52.6701 34.49 53.2201C35.75 55.1001 38.67 49.6601 38.72 48.4401C38.6416 48.3687 38.5449 48.3206 38.4406 48.3012C38.3364 48.2817 38.2288 48.2918 38.13 48.3301Z\" fill=\"#00B298\"\/>\n<path id=\"Vector5656231 328\" d=\"M76.84 65.3999C76.5681 64.8205 76.2071 64.2874 75.77 63.8199C75.4353 63.5772 75.0417 63.4287 74.6301 63.39C74.2185 63.3514 73.804 63.4238 73.43 63.5999L70.16 64.9999C68.16 65.8699 65.64 65.2699 63.52 66.2099C60.24 67.6599 54.91 73.5499 61.99 72.1199C62.86 71.9499 63.99 71.2599 64.76 71.7499C64.8238 72.9557 64.8238 74.1641 64.76 75.3699C69.5854 73.154 73.7492 69.7175 76.84 65.3999Z\" fill=\"#00B298\"\/>\n<path id=\"Vector5656231 329\" d=\"M77 64.1901C77.2245 64.0827 77.4231 63.9278 77.5819 63.7361C77.7407 63.5445 77.8561 63.3207 77.92 63.0801C77.62 63.4601 77.31 63.8201 77 64.1801V64.1901Z\" fill=\"#00B298\"\/>\n<path id=\"Vector5656231 330\" d=\"M76.57 59.7801C75.63 61.1401 77.01 62.6401 76.96 64.1801C77.27 63.8201 77.58 63.4601 77.88 63.0801C78.37 61.6701 78 59.5201 76.57 59.7801Z\" fill=\"#00B298\"\/>\n<path id=\"Vector5656231 331\" d=\"M74 55.46C72.83 56.39 71.14 55.85 70 56.77C69.7361 56.988 69.5353 57.2725 69.4183 57.5941C69.3013 57.9158 69.2724 58.2628 69.3346 58.5994C69.3969 58.9359 69.5479 59.2497 69.7721 59.5083C69.9964 59.7669 70.2856 59.9608 70.61 60.07C73.01 61.07 72.92 58.68 73.61 57.34C73.91 56.75 75.09 56.13 75.05 55.45C75 54.33 74.48 55.07 74 55.46Z\" fill=\"#00B298\"\/>\n<path id=\"Vector5656231 332\" d=\"M64 53.1501C64 54.2301 64.63 55.3901 64.62 56.5001C64.62 57.2701 64.04 61.2101 65.93 58.6001C66.63 57.6001 66.03 53.4401 64.93 52.4101C64.47 52.0501 64 52.8701 64 53.1501Z\" fill=\"#00B298\"\/>\n<path id=\"Vector5656231 333\" d=\"M78.27 49.5399C78.03 48.9699 76.76 48.7699 76.85 49.6799C77.02 52.2899 75.07 53.2099 76.85 55.7599C77.67 54.9299 77.69 54.0199 77.85 52.8599C77.85 52.5099 77.65 51.7899 77.67 51.3999C77.76 50.7299 78.43 50.3999 78.27 49.5399Z\" fill=\"#00B298\"\/>\n<path id=\"Vector5656231 334\" d=\"M50.13 32.9299C49.48 31.9999 49.41 32.2199 49.23 31.0099C49.02 29.6399 49.51 28.3999 48.74 27.2399C48.3164 26.6455 47.7439 26.173 47.08 25.8699C46.9008 25.777 46.7019 25.7285 46.5 25.7285C46.2981 25.7285 46.0992 25.777 45.92 25.8699C44.82 25.8699 43.65 25.9499 43.14 26.9599C42.72 27.7999 42.92 29.9599 42.7 31.0399C41.86 35.2899 44.55 35.3099 47.99 35.3099C49.18 35.3099 51.34 35.8899 51.19 34.2299C51.14 33.6599 50.4 33.3299 50.13 32.9299Z\" fill=\"#00B298\"\/>\n<path id=\"Vector5656231 335\" d=\"M77.11 45.9299C78.99 44.9299 76.83 44.2799 76.61 43.2299C76.33 41.8999 77.88 40.9499 77.31 39.5299C79.31 38.4099 79.24 41.6999 79.31 42.8799C81.15 42.8799 79.42 40.1199 79.24 39.2199C78.94 37.6899 79.8 36.6099 79.61 35.0999C79.61 34.8799 79.53 34.6399 79.48 34.3999C77.0464 29.4357 73.31 25.2259 68.67 22.2199C68.5931 22.2607 68.5195 22.3075 68.45 22.3599C66.45 24.0499 68.94 24.5299 68.6 25.8699C68.39 26.6599 67.38 26.4599 66.8 26.5899C66.93 26.5899 64.57 26.8699 64.9 26.9799C64.8883 27.019 64.8622 27.0522 64.8268 27.0726C64.7915 27.0931 64.7497 27.0993 64.71 27.0899C64.58 25.4099 62.97 23.7899 61.35 24.9499C59.82 23.3599 62.35 22.1599 62.52 20.5699C61.61 20.5199 60.52 20.3499 59.75 20.9299C58.75 21.6999 59.25 22.6199 57.97 22.9899C57.79 23.0399 57.11 22.4899 56.69 22.6599C56.05 22.9099 56.03 23.5699 55.69 24.0899C55.1838 25.0389 54.577 25.9307 53.88 26.7499C53.06 27.4699 52.58 28.1599 52.06 26.7499C51.54 25.3399 53.06 25.2899 53.34 24.0799C53.66 22.3799 50.01 21.5199 50.34 24.2399C49.02 24.3399 48.02 23.0199 46.46 23.2399C44.37 23.4899 45.02 24.0799 46.81 24.6599C50.41 25.8299 50.09 27.3199 50.94 30.4799C51.87 33.9599 55.58 32.3699 55.69 35.8499C55.75 37.6099 56.28 38.0499 56.89 39.5799C57.5 41.1099 56.96 41.9199 56.57 43.4699C56.3 44.5599 55.57 46.4699 56.93 46.6799C58.34 45.9699 59.39 45.7699 60.13 44.1899C60.49 43.4099 59.98 43.0899 60.84 42.5499C61.7 42.0099 62.45 42.6699 63.15 42.5999C64.44 42.4899 65.64 41.3499 66.87 42.2299C68.58 43.4499 67.15 44.9199 67.41 46.3199C67.67 47.7199 69.59 48.0399 69.95 49.3199C70.31 50.5999 67.95 51.3199 68.29 52.5599C68.91 55.1299 69.98 51.3199 70.29 51.0899C70.73 50.6999 71.8 51.0899 72.13 50.6599C72.46 50.2299 72.31 48.9799 72.26 48.4699C72 46.9999 71.23 46.0899 73 45.5699C74.3 45.1999 75.92 46.5499 77.11 45.9299Z\" fill=\"#00B298\"\/>\n<path id=\"Vector5656231 336\" d=\"M51.85 17.65C51.7514 17.5262 51.6445 17.4093 51.53 17.3C49.2308 17.3363 46.9431 17.6315 44.71 18.18C44.8695 18.2265 45.0177 18.3056 45.1451 18.4123C45.2725 18.519 45.3763 18.651 45.45 18.8C46.08 19.91 44.34 21.5801 45.94 22.0401C46.88 22.3101 46.94 21.16 47.7 20.98C48.2738 20.8764 48.8581 20.8428 49.44 20.88C50.68 20.88 51.73 21.7501 52.54 20.2901C52.3346 20.1123 52.1174 19.9485 51.89 19.8C52 18.8 52.5 18.47 51.85 17.65Z\" fill=\"#00B298\"\/>\n<path id=\"Vector5656231 337\" d=\"M38.59 48.4299C25.66 48.4299 15.19 56.1499 15.19 65.6699C15.2463 69.1322 16.5739 72.453 18.92 74.9999L11.09 86.4099L25.78 80.0899C29.7846 81.9783 34.1626 82.9421 38.59 82.9099C51.51 82.9099 61.99 75.1899 61.99 65.6699C61.99 56.1499 51.51 48.4299 38.59 48.4299Z\" fill=\"#F3B756\"\/>\n<path id=\"Vector5656231 338\" d=\"M42.66 69.61H33.76L32.14 73.46H28.53L36.53 55.25H40.15L48 73.46H44.27L42.66 69.61ZM41.41 66.61L38.23 59L35 66.62L41.41 66.61Z\" fill=\"white\"\/>\n<path id=\"Vector5656231 339\" d=\"M73.26 6C84.6 6 93.79 12.78 93.79 21.13C93.7395 24.1702 92.572 27.0854 90.51 29.32L97.38 39.32L84.49 33.79C80.9798 35.4478 77.1419 36.2954 73.26 36.27C61.91 36.27 52.72 29.49 52.72 21.13C52.72 12.77 61.91 6 73.26 6Z\" fill=\"#EB6D79\"\/>\n<path id=\"Vector5656231 340\" d=\"M78.47 13.9399V15.7999L70.34 25.4499H78.57V27.7599H66.76V25.8899L74.9 16.2499H67V13.9399H78.47Z\" fill=\"white\"\/>\n<path id=\"Vector5656231 341\" d=\"M61.48 138.91C62.08 141.67 59.91 142.96 57.69 143.21C55.47 143.46 53.82 141.37 53.47 139.82C53.12 138.27 54.63 136.82 56.84 136.55C59.05 136.28 60.92 136.39 61.48 138.91Z\" fill=\"#B57D68\"\/>\n<path id=\"Vector5656231 342\" d=\"M63.76 143.55C64.2 146.17 61.05 147.23 58.39 147.55C57.9171 147.643 57.4304 147.641 56.9582 147.545C56.486 147.448 56.0375 147.259 55.6387 146.989C55.2398 146.718 54.8985 146.371 54.6344 145.968C54.3703 145.565 54.1887 145.114 54.1 144.64C53.75 143.09 55.63 141.64 58.29 141.29C60.95 140.94 63.33 141.05 63.76 143.55Z\" fill=\"#B57D68\"\/>\n<path id=\"Vector5656231 343\" d=\"M63.64 148.2C64.06 150.81 62.29 151.2 59.83 151.51C57.37 151.82 55.11 150.76 54.76 149.2C54.41 147.64 56.12 146.2 58.57 145.89C61.02 145.58 63.24 145.68 63.64 148.2Z\" fill=\"#B57D68\"\/>\n<path id=\"Vector5656231 344\" d=\"M62.3301 152.21C62.5801 153.6 61.4101 154.51 59.6801 154.71C57.9501 154.91 56.3301 154.1 56.0601 152.91C55.7901 151.72 56.9801 150.6 58.7101 150.41C60.4401 150.22 61.9301 149.92 62.3301 152.21Z\" fill=\"#B57D68\"\/>\n<\/g>\n<\/g>\n<\/g>\n<\/g>\n<\/g>\n<defs>\n<filter id=\"filter0_d\" x=\"17.36\" y=\"0\" width=\"338.67\" height=\"388.224\" filterUnits=\"userSpaceOnUse\" color-interpolation-filters=\"sRGB\">\n<feFlood flood-opacity=\"0\" result=\"BackgroundImageFix\"\/>\n<feColorMatrix in=\"SourceAlpha\" type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\"\/>\n<feOffset dy=\"4\"\/>\n<feGaussianBlur stdDeviation=\"2\"\/>\n<feColorMatrix type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\"\/>\n<feBlend mode=\"normal\" in2=\"BackgroundImageFix\" result=\"effect1_dropShadow\"\/>\n<feBlend mode=\"normal\" in=\"SourceGraphic\" in2=\"effect1_dropShadow\" result=\"shape\"\/>\n<\/filter>\n<filter id=\"filter1_d\" x=\"74.4199\" y=\"138.417\" width=\"60.1344\" height=\"51.595\" filterUnits=\"userSpaceOnUse\" color-interpolation-filters=\"sRGB\">\n<feFlood flood-opacity=\"0\" result=\"BackgroundImageFix\"\/>\n<feColorMatrix in=\"SourceAlpha\" type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\"\/>\n<feOffset dy=\"4\"\/>\n<feGaussianBlur stdDeviation=\"2\"\/>\n<feColorMatrix type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\"\/>\n<feBlend mode=\"normal\" in2=\"BackgroundImageFix\" result=\"effect1_dropShadow\"\/>\n<feBlend mode=\"normal\" in=\"SourceGraphic\" in2=\"effect1_dropShadow\" result=\"shape\"\/>\n<\/filter>\n<filter id=\"filter2_d\" x=\"104.641\" y=\"143.428\" width=\"66.8734\" height=\"46.9711\" filterUnits=\"userSpaceOnUse\" color-interpolation-filters=\"sRGB\">\n<feFlood flood-opacity=\"0\" result=\"BackgroundImageFix\"\/>\n<feColorMatrix in=\"SourceAlpha\" type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\"\/>\n<feOffset dy=\"4\"\/>\n<feGaussianBlur stdDeviation=\"2\"\/>\n<feColorMatrix type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\"\/>\n<feBlend mode=\"normal\" in2=\"BackgroundImageFix\" result=\"effect1_dropShadow\"\/>\n<feBlend mode=\"normal\" in=\"SourceGraphic\" in2=\"effect1_dropShadow\" result=\"shape\"\/>\n<\/filter>\n<filter id=\"filter3_d\" x=\"74.4199\" y=\"142.84\" width=\"57.93\" height=\"47.1715\" filterUnits=\"userSpaceOnUse\" color-interpolation-filters=\"sRGB\">\n<feFlood flood-opacity=\"0\" result=\"BackgroundImageFix\"\/>\n<feColorMatrix in=\"SourceAlpha\" type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\"\/>\n<feOffset dy=\"4\"\/>\n<feGaussianBlur stdDeviation=\"2\"\/>\n<feColorMatrix type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\"\/>\n<feBlend mode=\"normal\" in2=\"BackgroundImageFix\" result=\"effect1_dropShadow\"\/>\n<feBlend mode=\"normal\" in=\"SourceGraphic\" in2=\"effect1_dropShadow\" result=\"shape\"\/>\n<\/filter>\n<filter id=\"filter4_d\" x=\"108.7\" y=\"146.42\" width=\"62.5039\" height=\"44.0192\" filterUnits=\"userSpaceOnUse\" color-interpolation-filters=\"sRGB\">\n<feFlood flood-opacity=\"0\" result=\"BackgroundImageFix\"\/>\n<feColorMatrix in=\"SourceAlpha\" type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\"\/>\n<feOffset dy=\"4\"\/>\n<feGaussianBlur stdDeviation=\"2\"\/>\n<feColorMatrix type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\"\/>\n<feBlend mode=\"normal\" in2=\"BackgroundImageFix\" result=\"effect1_dropShadow\"\/>\n<feBlend mode=\"normal\" in=\"SourceGraphic\" in2=\"effect1_dropShadow\" result=\"shape\"\/>\n<\/filter>\n<filter id=\"filter5_d\" x=\"221.743\" y=\"128.427\" width=\"64.777\" height=\"44.5912\" filterUnits=\"userSpaceOnUse\" color-interpolation-filters=\"sRGB\">\n<feFlood flood-opacity=\"0\" result=\"BackgroundImageFix\"\/>\n<feColorMatrix in=\"SourceAlpha\" type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\"\/>\n<feOffset dy=\"4\"\/>\n<feGaussianBlur stdDeviation=\"2\"\/>\n<feColorMatrix type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\"\/>\n<feBlend mode=\"normal\" in2=\"BackgroundImageFix\" result=\"effect1_dropShadow\"\/>\n<feBlend mode=\"normal\" in=\"SourceGraphic\" in2=\"effect1_dropShadow\" result=\"shape\"\/>\n<\/filter>\n<filter id=\"filter6_d\" x=\"221.73\" y=\"134.23\" width=\"64.79\" height=\"38.7877\" filterUnits=\"userSpaceOnUse\" color-interpolation-filters=\"sRGB\">\n<feFlood flood-opacity=\"0\" result=\"BackgroundImageFix\"\/>\n<feColorMatrix in=\"SourceAlpha\" type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\"\/>\n<feOffset dy=\"4\"\/>\n<feGaussianBlur stdDeviation=\"2\"\/>\n<feColorMatrix type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\"\/>\n<feBlend mode=\"normal\" in2=\"BackgroundImageFix\" result=\"effect1_dropShadow\"\/>\n<feBlend mode=\"normal\" in=\"SourceGraphic\" in2=\"effect1_dropShadow\" result=\"shape\"\/>\n<\/filter>\n<filter id=\"filter7_d\" x=\"268.38\" y=\"120.823\" width=\"40.2329\" height=\"26.409\" filterUnits=\"userSpaceOnUse\" color-interpolation-filters=\"sRGB\">\n<feFlood flood-opacity=\"0\" result=\"BackgroundImageFix\"\/>\n<feColorMatrix in=\"SourceAlpha\" type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\"\/>\n<feOffset dy=\"4\"\/>\n<feGaussianBlur stdDeviation=\"2\"\/>\n<feColorMatrix type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\"\/>\n<feBlend mode=\"normal\" in2=\"BackgroundImageFix\" result=\"effect1_dropShadow\"\/>\n<feBlend mode=\"normal\" in=\"SourceGraphic\" in2=\"effect1_dropShadow\" result=\"shape\"\/>\n<\/filter>\n<filter id=\"filter8_d\" x=\"192.096\" y=\"278.072\" width=\"30.1765\" height=\"98.3212\" filterUnits=\"userSpaceOnUse\" color-interpolation-filters=\"sRGB\">\n<feFlood flood-opacity=\"0\" result=\"BackgroundImageFix\"\/>\n<feColorMatrix in=\"SourceAlpha\" type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\"\/>\n<feOffset dy=\"4\"\/>\n<feGaussianBlur stdDeviation=\"2\"\/>\n<feColorMatrix type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\"\/>\n<feBlend mode=\"normal\" in2=\"BackgroundImageFix\" result=\"effect1_dropShadow\"\/>\n<feBlend mode=\"normal\" in=\"SourceGraphic\" in2=\"effect1_dropShadow\" result=\"shape\"\/>\n<\/filter>\n<filter id=\"filter9_d\" x=\"191.499\" y=\"353.75\" width=\"33.6398\" height=\"28.6264\" filterUnits=\"userSpaceOnUse\" color-interpolation-filters=\"sRGB\">\n<feFlood flood-opacity=\"0\" result=\"BackgroundImageFix\"\/>\n<feColorMatrix in=\"SourceAlpha\" type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\"\/>\n<feOffset dy=\"4\"\/>\n<feGaussianBlur stdDeviation=\"2\"\/>\n<feColorMatrix type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\"\/>\n<feBlend mode=\"normal\" in2=\"BackgroundImageFix\" result=\"effect1_dropShadow\"\/>\n<feBlend mode=\"normal\" in=\"SourceGraphic\" in2=\"effect1_dropShadow\" result=\"shape\"\/>\n<\/filter>\n<filter id=\"filter10_d\" x=\"190.535\" y=\"355.46\" width=\"35.9185\" height=\"32.46\" filterUnits=\"userSpaceOnUse\" color-interpolation-filters=\"sRGB\">\n<feFlood flood-opacity=\"0\" result=\"BackgroundImageFix\"\/>\n<feColorMatrix in=\"SourceAlpha\" type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\"\/>\n<feOffset dy=\"4\"\/>\n<feGaussianBlur stdDeviation=\"2\"\/>\n<feColorMatrix type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\"\/>\n<feBlend mode=\"normal\" in2=\"BackgroundImageFix\" result=\"effect1_dropShadow\"\/>\n<feBlend mode=\"normal\" in=\"SourceGraphic\" in2=\"effect1_dropShadow\" result=\"shape\"\/>\n<\/filter>\n<filter id=\"filter11_d\" x=\"211.3\" y=\"355.47\" width=\"15.1438\" height=\"32.04\" filterUnits=\"userSpaceOnUse\" color-interpolation-filters=\"sRGB\">\n<feFlood flood-opacity=\"0\" result=\"BackgroundImageFix\"\/>\n<feColorMatrix in=\"SourceAlpha\" type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\"\/>\n<feOffset dy=\"4\"\/>\n<feGaussianBlur stdDeviation=\"2\"\/>\n<feColorMatrix type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\"\/>\n<feBlend mode=\"normal\" in2=\"BackgroundImageFix\" result=\"effect1_dropShadow\"\/>\n<feBlend mode=\"normal\" in=\"SourceGraphic\" in2=\"effect1_dropShadow\" result=\"shape\"\/>\n<\/filter>\n<filter id=\"filter12_d\" x=\"191.68\" y=\"377.56\" width=\"33.42\" height=\"10.34\" filterUnits=\"userSpaceOnUse\" color-interpolation-filters=\"sRGB\">\n<feFlood flood-opacity=\"0\" result=\"BackgroundImageFix\"\/>\n<feColorMatrix in=\"SourceAlpha\" type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\"\/>\n<feOffset dy=\"4\"\/>\n<feGaussianBlur stdDeviation=\"2\"\/>\n<feColorMatrix type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\"\/>\n<feBlend mode=\"normal\" in2=\"BackgroundImageFix\" result=\"effect1_dropShadow\"\/>\n<feBlend mode=\"normal\" in=\"SourceGraphic\" in2=\"effect1_dropShadow\" result=\"shape\"\/>\n<\/filter>\n<filter id=\"filter13_d\" x=\"197.65\" y=\"365.419\" width=\"21.7345\" height=\"11.2115\" filterUnits=\"userSpaceOnUse\" color-interpolation-filters=\"sRGB\">\n<feFlood flood-opacity=\"0\" result=\"BackgroundImageFix\"\/>\n<feColorMatrix in=\"SourceAlpha\" type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\"\/>\n<feOffset dy=\"4\"\/>\n<feGaussianBlur stdDeviation=\"2\"\/>\n<feColorMatrix type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\"\/>\n<feBlend mode=\"normal\" in2=\"BackgroundImageFix\" result=\"effect1_dropShadow\"\/>\n<feBlend mode=\"normal\" in=\"SourceGraphic\" in2=\"effect1_dropShadow\" result=\"shape\"\/>\n<\/filter>\n<filter id=\"filter14_d\" x=\"201.055\" y=\"368.708\" width=\"15.807\" height=\"10.4334\" filterUnits=\"userSpaceOnUse\" color-interpolation-filters=\"sRGB\">\n<feFlood flood-opacity=\"0\" result=\"BackgroundImageFix\"\/>\n<feColorMatrix in=\"SourceAlpha\" type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\"\/>\n<feOffset dy=\"4\"\/>\n<feGaussianBlur stdDeviation=\"2\"\/>\n<feColorMatrix type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\"\/>\n<feBlend mode=\"normal\" in2=\"BackgroundImageFix\" result=\"effect1_dropShadow\"\/>\n<feBlend mode=\"normal\" in=\"SourceGraphic\" in2=\"effect1_dropShadow\" result=\"shape\"\/>\n<\/filter>\n<filter id=\"filter15_d\" x=\"148.372\" y=\"279.885\" width=\"30.3161\" height=\"99.6578\" filterUnits=\"userSpaceOnUse\" color-interpolation-filters=\"sRGB\">\n<feFlood flood-opacity=\"0\" result=\"BackgroundImageFix\"\/>\n<feColorMatrix in=\"SourceAlpha\" type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\"\/>\n<feOffset dy=\"4\"\/>\n<feGaussianBlur stdDeviation=\"2\"\/>\n<feColorMatrix type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\"\/>\n<feBlend mode=\"normal\" in2=\"BackgroundImageFix\" result=\"effect1_dropShadow\"\/>\n<feBlend mode=\"normal\" in=\"SourceGraphic\" in2=\"effect1_dropShadow\" result=\"shape\"\/>\n<\/filter>\n<filter id=\"filter16_d\" x=\"142\" y=\"353.79\" width=\"30.8083\" height=\"22.3245\" filterUnits=\"userSpaceOnUse\" color-interpolation-filters=\"sRGB\">\n<feFlood flood-opacity=\"0\" result=\"BackgroundImageFix\"\/>\n<feColorMatrix in=\"SourceAlpha\" type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\"\/>\n<feOffset dy=\"4\"\/>\n<feGaussianBlur stdDeviation=\"2\"\/>\n<feColorMatrix type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\"\/>\n<feBlend mode=\"normal\" in2=\"BackgroundImageFix\" result=\"effect1_dropShadow\"\/>\n<feBlend mode=\"normal\" in=\"SourceGraphic\" in2=\"effect1_dropShadow\" result=\"shape\"\/>\n<\/filter>\n<filter id=\"filter17_d\" x=\"129.734\" y=\"355.18\" width=\"45.3005\" height=\"33.044\" filterUnits=\"userSpaceOnUse\" color-interpolation-filters=\"sRGB\">\n<feFlood flood-opacity=\"0\" result=\"BackgroundImageFix\"\/>\n<feColorMatrix in=\"SourceAlpha\" type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\"\/>\n<feOffset dy=\"4\"\/>\n<feGaussianBlur stdDeviation=\"2\"\/>\n<feColorMatrix type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\"\/>\n<feBlend mode=\"normal\" in2=\"BackgroundImageFix\" result=\"effect1_dropShadow\"\/>\n<feBlend mode=\"normal\" in=\"SourceGraphic\" in2=\"effect1_dropShadow\" result=\"shape\"\/>\n<\/filter>\n<filter id=\"filter18_d\" x=\"147.91\" y=\"355.15\" width=\"27.1177\" height=\"32.99\" filterUnits=\"userSpaceOnUse\" color-interpolation-filters=\"sRGB\">\n<feFlood flood-opacity=\"0\" result=\"BackgroundImageFix\"\/>\n<feColorMatrix in=\"SourceAlpha\" type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\"\/>\n<feOffset dy=\"4\"\/>\n<feGaussianBlur stdDeviation=\"2\"\/>\n<feColorMatrix type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\"\/>\n<feBlend mode=\"normal\" in2=\"BackgroundImageFix\" result=\"effect1_dropShadow\"\/>\n<feBlend mode=\"normal\" in=\"SourceGraphic\" in2=\"effect1_dropShadow\" result=\"shape\"\/>\n<\/filter>\n<filter id=\"filter19_d\" x=\"129.677\" y=\"375.69\" width=\"44.2122\" height=\"12.4451\" filterUnits=\"userSpaceOnUse\" color-interpolation-filters=\"sRGB\">\n<feFlood flood-opacity=\"0\" result=\"BackgroundImageFix\"\/>\n<feColorMatrix in=\"SourceAlpha\" type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\"\/>\n<feOffset dy=\"4\"\/>\n<feGaussianBlur stdDeviation=\"2\"\/>\n<feColorMatrix type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\"\/>\n<feBlend mode=\"normal\" in2=\"BackgroundImageFix\" result=\"effect1_dropShadow\"\/>\n<feBlend mode=\"normal\" in=\"SourceGraphic\" in2=\"effect1_dropShadow\" result=\"shape\"\/>\n<\/filter>\n<filter id=\"filter20_d\" x=\"139.109\" y=\"363.534\" width=\"21.8189\" height=\"12.9059\" filterUnits=\"userSpaceOnUse\" color-interpolation-filters=\"sRGB\">\n<feFlood flood-opacity=\"0\" result=\"BackgroundImageFix\"\/>\n<feColorMatrix in=\"SourceAlpha\" type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\"\/>\n<feOffset dy=\"4\"\/>\n<feGaussianBlur stdDeviation=\"2\"\/>\n<feColorMatrix type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\"\/>\n<feBlend mode=\"normal\" in2=\"BackgroundImageFix\" result=\"effect1_dropShadow\"\/>\n<feBlend mode=\"normal\" in=\"SourceGraphic\" in2=\"effect1_dropShadow\" result=\"shape\"\/>\n<\/filter>\n<filter id=\"filter21_d\" x=\"138.082\" y=\"366.75\" width=\"15.9883\" height=\"10.9702\" filterUnits=\"userSpaceOnUse\" color-interpolation-filters=\"sRGB\">\n<feFlood flood-opacity=\"0\" result=\"BackgroundImageFix\"\/>\n<feColorMatrix in=\"SourceAlpha\" type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\"\/>\n<feOffset dy=\"4\"\/>\n<feGaussianBlur stdDeviation=\"2\"\/>\n<feColorMatrix type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\"\/>\n<feBlend mode=\"normal\" in2=\"BackgroundImageFix\" result=\"effect1_dropShadow\"\/>\n<feBlend mode=\"normal\" in=\"SourceGraphic\" in2=\"effect1_dropShadow\" result=\"shape\"\/>\n<\/filter>\n<filter id=\"filter22_d\" x=\"174.6\" y=\"223.67\" width=\"50.0888\" height=\"135.949\" filterUnits=\"userSpaceOnUse\" color-interpolation-filters=\"sRGB\">\n<feFlood flood-opacity=\"0\" result=\"BackgroundImageFix\"\/>\n<feColorMatrix in=\"SourceAlpha\" type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\"\/>\n<feOffset dy=\"4\"\/>\n<feGaussianBlur stdDeviation=\"2\"\/>\n<feColorMatrix type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\"\/>\n<feBlend mode=\"normal\" in2=\"BackgroundImageFix\" result=\"effect1_dropShadow\"\/>\n<feBlend mode=\"normal\" in=\"SourceGraphic\" in2=\"effect1_dropShadow\" result=\"shape\"\/>\n<\/filter>\n<filter id=\"filter23_d\" x=\"174.6\" y=\"223.62\" width=\"50.0901\" height=\"135.67\" filterUnits=\"userSpaceOnUse\" color-interpolation-filters=\"sRGB\">\n<feFlood flood-opacity=\"0\" result=\"BackgroundImageFix\"\/>\n<feColorMatrix in=\"SourceAlpha\" type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\"\/>\n<feOffset dy=\"4\"\/>\n<feGaussianBlur stdDeviation=\"2\"\/>\n<feColorMatrix type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\"\/>\n<feBlend mode=\"normal\" in2=\"BackgroundImageFix\" result=\"effect1_dropShadow\"\/>\n<feBlend mode=\"normal\" in=\"SourceGraphic\" in2=\"effect1_dropShadow\" result=\"shape\"\/>\n<\/filter>\n<filter id=\"filter24_d\" x=\"197.835\" y=\"238.04\" width=\"26.6554\" height=\"27.3393\" filterUnits=\"userSpaceOnUse\" color-interpolation-filters=\"sRGB\">\n<feFlood flood-opacity=\"0\" result=\"BackgroundImageFix\"\/>\n<feColorMatrix in=\"SourceAlpha\" type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\"\/>\n<feOffset dy=\"4\"\/>\n<feGaussianBlur stdDeviation=\"2\"\/>\n<feColorMatrix type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\"\/>\n<feBlend mode=\"normal\" in2=\"BackgroundImageFix\" result=\"effect1_dropShadow\"\/>\n<feBlend mode=\"normal\" in=\"SourceGraphic\" in2=\"effect1_dropShadow\" result=\"shape\"\/>\n<\/filter>\n<filter id=\"filter25_d\" x=\"141.1\" y=\"223.94\" width=\"49.74\" height=\"137.129\" filterUnits=\"userSpaceOnUse\" color-interpolation-filters=\"sRGB\">\n<feFlood flood-opacity=\"0\" result=\"BackgroundImageFix\"\/>\n<feColorMatrix in=\"SourceAlpha\" type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\"\/>\n<feOffset dy=\"4\"\/>\n<feGaussianBlur stdDeviation=\"2\"\/>\n<feColorMatrix type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\"\/>\n<feBlend mode=\"normal\" in2=\"BackgroundImageFix\" result=\"effect1_dropShadow\"\/>\n<feBlend mode=\"normal\" in=\"SourceGraphic\" in2=\"effect1_dropShadow\" result=\"shape\"\/>\n<\/filter>\n<filter id=\"filter26_d\" x=\"161.78\" y=\"259.32\" width=\"23.45\" height=\"101.4\" filterUnits=\"userSpaceOnUse\" color-interpolation-filters=\"sRGB\">\n<feFlood flood-opacity=\"0\" result=\"BackgroundImageFix\"\/>\n<feColorMatrix in=\"SourceAlpha\" type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\"\/>\n<feOffset dy=\"4\"\/>\n<feGaussianBlur stdDeviation=\"2\"\/>\n<feColorMatrix type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\"\/>\n<feBlend mode=\"normal\" in2=\"BackgroundImageFix\" result=\"effect1_dropShadow\"\/>\n<feBlend mode=\"normal\" in=\"SourceGraphic\" in2=\"effect1_dropShadow\" result=\"shape\"\/>\n<\/filter>\n<filter id=\"filter27_d\" x=\"143.72\" y=\"223.94\" width=\"47.11\" height=\"37.2992\" filterUnits=\"userSpaceOnUse\" color-interpolation-filters=\"sRGB\">\n<feFlood flood-opacity=\"0\" result=\"BackgroundImageFix\"\/>\n<feColorMatrix in=\"SourceAlpha\" type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\"\/>\n<feOffset dy=\"4\"\/>\n<feGaussianBlur stdDeviation=\"2\"\/>\n<feColorMatrix type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\"\/>\n<feBlend mode=\"normal\" in2=\"BackgroundImageFix\" result=\"effect1_dropShadow\"\/>\n<feBlend mode=\"normal\" in=\"SourceGraphic\" in2=\"effect1_dropShadow\" result=\"shape\"\/>\n<\/filter>\n<filter id=\"filter28_d\" x=\"142.89\" y=\"240.028\" width=\"19.6476\" height=\"28.3321\" filterUnits=\"userSpaceOnUse\" color-interpolation-filters=\"sRGB\">\n<feFlood flood-opacity=\"0\" result=\"BackgroundImageFix\"\/>\n<feColorMatrix in=\"SourceAlpha\" type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\"\/>\n<feOffset dy=\"4\"\/>\n<feGaussianBlur stdDeviation=\"2\"\/>\n<feColorMatrix type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\"\/>\n<feBlend mode=\"normal\" in2=\"BackgroundImageFix\" result=\"effect1_dropShadow\"\/>\n<feBlend mode=\"normal\" in=\"SourceGraphic\" in2=\"effect1_dropShadow\" result=\"shape\"\/>\n<\/filter>\n<filter id=\"filter29_d\" x=\"183.14\" y=\"133.349\" width=\"54.5304\" height=\"47.2208\" filterUnits=\"userSpaceOnUse\" color-interpolation-filters=\"sRGB\">\n<feFlood flood-opacity=\"0\" result=\"BackgroundImageFix\"\/>\n<feColorMatrix in=\"SourceAlpha\" type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\"\/>\n<feOffset dy=\"4\"\/>\n<feGaussianBlur stdDeviation=\"2\"\/>\n<feColorMatrix type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\"\/>\n<feBlend mode=\"normal\" in2=\"BackgroundImageFix\" result=\"effect1_dropShadow\"\/>\n<feBlend mode=\"normal\" in=\"SourceGraphic\" in2=\"effect1_dropShadow\" result=\"shape\"\/>\n<\/filter>\n<filter id=\"filter30_d\" x=\"125.58\" y=\"135.305\" width=\"49.5112\" height=\"54.6032\" filterUnits=\"userSpaceOnUse\" color-interpolation-filters=\"sRGB\">\n<feFlood flood-opacity=\"0\" result=\"BackgroundImageFix\"\/>\n<feColorMatrix in=\"SourceAlpha\" type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\"\/>\n<feOffset dy=\"4\"\/>\n<feGaussianBlur stdDeviation=\"2\"\/>\n<feColorMatrix type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\"\/>\n<feBlend mode=\"normal\" in2=\"BackgroundImageFix\" result=\"effect1_dropShadow\"\/>\n<feBlend mode=\"normal\" in=\"SourceGraphic\" in2=\"effect1_dropShadow\" result=\"shape\"\/>\n<\/filter>\n<filter id=\"filter31_d\" x=\"141.63\" y=\"130.524\" width=\"82.16\" height=\"124.875\" filterUnits=\"userSpaceOnUse\" color-interpolation-filters=\"sRGB\">\n<feFlood flood-opacity=\"0\" result=\"BackgroundImageFix\"\/>\n<feColorMatrix in=\"SourceAlpha\" type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\"\/>\n<feOffset dy=\"4\"\/>\n<feGaussianBlur stdDeviation=\"2\"\/>\n<feColorMatrix type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\"\/>\n<feBlend mode=\"normal\" in2=\"BackgroundImageFix\" result=\"effect1_dropShadow\"\/>\n<feBlend mode=\"normal\" in=\"SourceGraphic\" in2=\"effect1_dropShadow\" result=\"shape\"\/>\n<\/filter>\n<filter id=\"filter32_d\" x=\"172.4\" y=\"133.6\" width=\"51.38\" height=\"121.807\" filterUnits=\"userSpaceOnUse\" color-interpolation-filters=\"sRGB\">\n<feFlood flood-opacity=\"0\" result=\"BackgroundImageFix\"\/>\n<feColorMatrix in=\"SourceAlpha\" type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\"\/>\n<feOffset dy=\"4\"\/>\n<feGaussianBlur stdDeviation=\"2\"\/>\n<feColorMatrix type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\"\/>\n<feBlend mode=\"normal\" in2=\"BackgroundImageFix\" result=\"effect1_dropShadow\"\/>\n<feBlend mode=\"normal\" in=\"SourceGraphic\" in2=\"effect1_dropShadow\" result=\"shape\"\/>\n<\/filter>\n<filter id=\"filter33_d\" x=\"166.31\" y=\"130.516\" width=\"29.35\" height=\"23.4086\" filterUnits=\"userSpaceOnUse\" color-interpolation-filters=\"sRGB\">\n<feFlood flood-opacity=\"0\" result=\"BackgroundImageFix\"\/>\n<feColorMatrix in=\"SourceAlpha\" type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\"\/>\n<feOffset dy=\"4\"\/>\n<feGaussianBlur stdDeviation=\"2\"\/>\n<feColorMatrix type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\"\/>\n<feBlend mode=\"normal\" in2=\"BackgroundImageFix\" result=\"effect1_dropShadow\"\/>\n<feBlend mode=\"normal\" in=\"SourceGraphic\" in2=\"effect1_dropShadow\" result=\"shape\"\/>\n<\/filter>\n<filter id=\"filter34_d\" x=\"126.279\" y=\"20.3533\" width=\"102.955\" height=\"86.2609\" filterUnits=\"userSpaceOnUse\" color-interpolation-filters=\"sRGB\">\n<feFlood flood-opacity=\"0\" result=\"BackgroundImageFix\"\/>\n<feColorMatrix in=\"SourceAlpha\" type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\"\/>\n<feOffset dy=\"4\"\/>\n<feGaussianBlur stdDeviation=\"2\"\/>\n<feColorMatrix type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\"\/>\n<feBlend mode=\"normal\" in2=\"BackgroundImageFix\" result=\"effect1_dropShadow\"\/>\n<feBlend mode=\"normal\" in=\"SourceGraphic\" in2=\"effect1_dropShadow\" result=\"shape\"\/>\n<\/filter>\n<filter id=\"filter35_d\" x=\"167.8\" y=\"118.2\" width=\"25.11\" height=\"23.97\" filterUnits=\"userSpaceOnUse\" color-interpolation-filters=\"sRGB\">\n<feFlood flood-opacity=\"0\" result=\"BackgroundImageFix\"\/>\n<feColorMatrix in=\"SourceAlpha\" type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\"\/>\n<feOffset dy=\"4\"\/>\n<feGaussianBlur stdDeviation=\"2\"\/>\n<feColorMatrix type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\"\/>\n<feBlend mode=\"normal\" in2=\"BackgroundImageFix\" result=\"effect1_dropShadow\"\/>\n<feBlend mode=\"normal\" in=\"SourceGraphic\" in2=\"effect1_dropShadow\" result=\"shape\"\/>\n<\/filter>\n<filter id=\"filter36_d\" x=\"167.93\" y=\"118.2\" width=\"24.96\" height=\"18.6679\" filterUnits=\"userSpaceOnUse\" color-interpolation-filters=\"sRGB\">\n<feFlood flood-opacity=\"0\" result=\"BackgroundImageFix\"\/>\n<feColorMatrix in=\"SourceAlpha\" type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\"\/>\n<feOffset dy=\"4\"\/>\n<feGaussianBlur stdDeviation=\"2\"\/>\n<feColorMatrix type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\"\/>\n<feBlend mode=\"normal\" in2=\"BackgroundImageFix\" result=\"effect1_dropShadow\"\/>\n<feBlend mode=\"normal\" in=\"SourceGraphic\" in2=\"effect1_dropShadow\" result=\"shape\"\/>\n<\/filter>\n<filter id=\"filter37_d\" x=\"206.799\" y=\"73.585\" width=\"27.9138\" height=\"28.791\" filterUnits=\"userSpaceOnUse\" color-interpolation-filters=\"sRGB\">\n<feFlood flood-opacity=\"0\" result=\"BackgroundImageFix\"\/>\n<feColorMatrix in=\"SourceAlpha\" type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\"\/>\n<feOffset dy=\"4\"\/>\n<feGaussianBlur stdDeviation=\"2\"\/>\n<feColorMatrix type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\"\/>\n<feBlend mode=\"normal\" in2=\"BackgroundImageFix\" result=\"effect1_dropShadow\"\/>\n<feBlend mode=\"normal\" in=\"SourceGraphic\" in2=\"effect1_dropShadow\" result=\"shape\"\/>\n<\/filter>\n<filter id=\"filter38_d\" x=\"215.904\" y=\"77.9875\" width=\"13.6516\" height=\"18.86\" filterUnits=\"userSpaceOnUse\" color-interpolation-filters=\"sRGB\">\n<feFlood flood-opacity=\"0\" result=\"BackgroundImageFix\"\/>\n<feColorMatrix in=\"SourceAlpha\" type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\"\/>\n<feOffset dy=\"4\"\/>\n<feGaussianBlur stdDeviation=\"2\"\/>\n<feColorMatrix type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\"\/>\n<feBlend mode=\"normal\" in2=\"BackgroundImageFix\" result=\"effect1_dropShadow\"\/>\n<feBlend mode=\"normal\" in=\"SourceGraphic\" in2=\"effect1_dropShadow\" result=\"shape\"\/>\n<\/filter>\n<filter id=\"filter39_d\" x=\"130.097\" y=\"78.4641\" width=\"26.0171\" height=\"27.5432\" filterUnits=\"userSpaceOnUse\" color-interpolation-filters=\"sRGB\">\n<feFlood flood-opacity=\"0\" result=\"BackgroundImageFix\"\/>\n<feColorMatrix in=\"SourceAlpha\" type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\"\/>\n<feOffset dy=\"4\"\/>\n<feGaussianBlur stdDeviation=\"2\"\/>\n<feColorMatrix type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\"\/>\n<feBlend mode=\"normal\" in2=\"BackgroundImageFix\" result=\"effect1_dropShadow\"\/>\n<feBlend mode=\"normal\" in=\"SourceGraphic\" in2=\"effect1_dropShadow\" result=\"shape\"\/>\n<\/filter>\n<filter id=\"filter40_d\" x=\"134.169\" y=\"83.0667\" width=\"13.9787\" height=\"17.9795\" filterUnits=\"userSpaceOnUse\" color-interpolation-filters=\"sRGB\">\n<feFlood flood-opacity=\"0\" result=\"BackgroundImageFix\"\/>\n<feColorMatrix in=\"SourceAlpha\" type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\"\/>\n<feOffset dy=\"4\"\/>\n<feGaussianBlur stdDeviation=\"2\"\/>\n<feColorMatrix type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\"\/>\n<feBlend mode=\"normal\" in2=\"BackgroundImageFix\" result=\"effect1_dropShadow\"\/>\n<feBlend mode=\"normal\" in=\"SourceGraphic\" in2=\"effect1_dropShadow\" result=\"shape\"\/>\n<\/filter>\n<filter id=\"filter41_d\" x=\"140.089\" y=\"49.7864\" width=\"81.7319\" height=\"83.9851\" filterUnits=\"userSpaceOnUse\" color-interpolation-filters=\"sRGB\">\n<feFlood flood-opacity=\"0\" result=\"BackgroundImageFix\"\/>\n<feColorMatrix in=\"SourceAlpha\" type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\"\/>\n<feOffset dy=\"4\"\/>\n<feGaussianBlur stdDeviation=\"2\"\/>\n<feColorMatrix type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\"\/>\n<feBlend mode=\"normal\" in2=\"BackgroundImageFix\" result=\"effect1_dropShadow\"\/>\n<feBlend mode=\"normal\" in=\"SourceGraphic\" in2=\"effect1_dropShadow\" result=\"shape\"\/>\n<\/filter>\n<filter id=\"filter42_d\" x=\"153.29\" y=\"50.01\" width=\"68.5264\" height=\"83.7659\" filterUnits=\"userSpaceOnUse\" color-interpolation-filters=\"sRGB\">\n<feFlood flood-opacity=\"0\" result=\"BackgroundImageFix\"\/>\n<feColorMatrix in=\"SourceAlpha\" type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\"\/>\n<feOffset dy=\"4\"\/>\n<feGaussianBlur stdDeviation=\"2\"\/>\n<feColorMatrix type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\"\/>\n<feBlend mode=\"normal\" in2=\"BackgroundImageFix\" result=\"effect1_dropShadow\"\/>\n<feBlend mode=\"normal\" in=\"SourceGraphic\" in2=\"effect1_dropShadow\" result=\"shape\"\/>\n<\/filter>\n<filter id=\"filter43_d\" x=\"187.01\" y=\"81.0701\" width=\"21.2426\" height=\"14.6623\" filterUnits=\"userSpaceOnUse\" color-interpolation-filters=\"sRGB\">\n<feFlood flood-opacity=\"0\" result=\"BackgroundImageFix\"\/>\n<feColorMatrix in=\"SourceAlpha\" type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\"\/>\n<feOffset dy=\"4\"\/>\n<feGaussianBlur stdDeviation=\"2\"\/>\n<feColorMatrix type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\"\/>\n<feBlend mode=\"normal\" in2=\"BackgroundImageFix\" result=\"effect1_dropShadow\"\/>\n<feBlend mode=\"normal\" in=\"SourceGraphic\" in2=\"effect1_dropShadow\" result=\"shape\"\/>\n<\/filter>\n<filter id=\"filter44_d\" x=\"148.495\" y=\"81.6499\" width=\"21.2315\" height=\"14.7169\" filterUnits=\"userSpaceOnUse\" color-interpolation-filters=\"sRGB\">\n<feFlood flood-opacity=\"0\" result=\"BackgroundImageFix\"\/>\n<feColorMatrix in=\"SourceAlpha\" type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\"\/>\n<feOffset dy=\"4\"\/>\n<feGaussianBlur stdDeviation=\"2\"\/>\n<feColorMatrix type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\"\/>\n<feBlend mode=\"normal\" in2=\"BackgroundImageFix\" result=\"effect1_dropShadow\"\/>\n<feBlend mode=\"normal\" in=\"SourceGraphic\" in2=\"effect1_dropShadow\" result=\"shape\"\/>\n<\/filter>\n<filter id=\"filter45_d\" x=\"189.806\" y=\"72.2227\" width=\"16.824\" height=\"11.6498\" filterUnits=\"userSpaceOnUse\" color-interpolation-filters=\"sRGB\">\n<feFlood flood-opacity=\"0\" result=\"BackgroundImageFix\"\/>\n<feColorMatrix in=\"SourceAlpha\" type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\"\/>\n<feOffset dy=\"4\"\/>\n<feGaussianBlur stdDeviation=\"2\"\/>\n<feColorMatrix type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\"\/>\n<feBlend mode=\"normal\" in2=\"BackgroundImageFix\" result=\"effect1_dropShadow\"\/>\n<feBlend mode=\"normal\" in=\"SourceGraphic\" in2=\"effect1_dropShadow\" result=\"shape\"\/>\n<\/filter>\n<filter id=\"filter46_d\" x=\"150.426\" y=\"73.5122\" width=\"16.9272\" height=\"11.9294\" filterUnits=\"userSpaceOnUse\" color-interpolation-filters=\"sRGB\">\n<feFlood flood-opacity=\"0\" result=\"BackgroundImageFix\"\/>\n<feColorMatrix in=\"SourceAlpha\" type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\"\/>\n<feOffset dy=\"4\"\/>\n<feGaussianBlur stdDeviation=\"2\"\/>\n<feColorMatrix type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\"\/>\n<feBlend mode=\"normal\" in2=\"BackgroundImageFix\" result=\"effect1_dropShadow\"\/>\n<feBlend mode=\"normal\" in=\"SourceGraphic\" in2=\"effect1_dropShadow\" result=\"shape\"\/>\n<\/filter>\n<filter id=\"filter47_d\" x=\"164\" y=\"104.69\" width=\"27.23\" height=\"17.0703\" filterUnits=\"userSpaceOnUse\" color-interpolation-filters=\"sRGB\">\n<feFlood flood-opacity=\"0\" result=\"BackgroundImageFix\"\/>\n<feColorMatrix in=\"SourceAlpha\" type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\"\/>\n<feOffset dy=\"4\"\/>\n<feGaussianBlur stdDeviation=\"2\"\/>\n<feColorMatrix type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\"\/>\n<feBlend mode=\"normal\" in2=\"BackgroundImageFix\" result=\"effect1_dropShadow\"\/>\n<feBlend mode=\"normal\" in=\"SourceGraphic\" in2=\"effect1_dropShadow\" result=\"shape\"\/>\n<\/filter>\n<filter id=\"filter48_d\" x=\"166.42\" y=\"104.71\" width=\"24.81\" height=\"11.8575\" filterUnits=\"userSpaceOnUse\" color-interpolation-filters=\"sRGB\">\n<feFlood flood-opacity=\"0\" result=\"BackgroundImageFix\"\/>\n<feColorMatrix in=\"SourceAlpha\" type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\"\/>\n<feOffset dy=\"4\"\/>\n<feGaussianBlur stdDeviation=\"2\"\/>\n<feColorMatrix type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\"\/>\n<feBlend mode=\"normal\" in2=\"BackgroundImageFix\" result=\"effect1_dropShadow\"\/>\n<feBlend mode=\"normal\" in=\"SourceGraphic\" in2=\"effect1_dropShadow\" result=\"shape\"\/>\n<\/filter>\n<filter id=\"filter49_d\" x=\"170.75\" y=\"110.975\" width=\"17.42\" height=\"10.8105\" filterUnits=\"userSpaceOnUse\" color-interpolation-filters=\"sRGB\">\n<feFlood flood-opacity=\"0\" result=\"BackgroundImageFix\"\/>\n<feColorMatrix in=\"SourceAlpha\" type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\"\/>\n<feOffset dy=\"4\"\/>\n<feGaussianBlur stdDeviation=\"2\"\/>\n<feColorMatrix type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\"\/>\n<feBlend mode=\"normal\" in2=\"BackgroundImageFix\" result=\"effect1_dropShadow\"\/>\n<feBlend mode=\"normal\" in=\"SourceGraphic\" in2=\"effect1_dropShadow\" result=\"shape\"\/>\n<\/filter>\n<filter id=\"filter50_d\" x=\"166.867\" y=\"83.28\" width=\"14.0031\" height=\"22.909\" filterUnits=\"userSpaceOnUse\" color-interpolation-filters=\"sRGB\">\n<feFlood flood-opacity=\"0\" result=\"BackgroundImageFix\"\/>\n<feColorMatrix in=\"SourceAlpha\" type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\"\/>\n<feOffset dy=\"4\"\/>\n<feGaussianBlur stdDeviation=\"2\"\/>\n<feColorMatrix type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\"\/>\n<feBlend mode=\"normal\" in2=\"BackgroundImageFix\" result=\"effect1_dropShadow\"\/>\n<feBlend mode=\"normal\" in=\"SourceGraphic\" in2=\"effect1_dropShadow\" result=\"shape\"\/>\n<\/filter>\n<filter id=\"filter51_d\" x=\"131.706\" y=\"36.9824\" width=\"93.7519\" height=\"48.7076\" filterUnits=\"userSpaceOnUse\" color-interpolation-filters=\"sRGB\">\n<feFlood flood-opacity=\"0\" result=\"BackgroundImageFix\"\/>\n<feColorMatrix in=\"SourceAlpha\" type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\"\/>\n<feOffset dy=\"4\"\/>\n<feGaussianBlur stdDeviation=\"2\"\/>\n<feColorMatrix type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\"\/>\n<feBlend mode=\"normal\" in2=\"BackgroundImageFix\" result=\"effect1_dropShadow\"\/>\n<feBlend mode=\"normal\" in=\"SourceGraphic\" in2=\"effect1_dropShadow\" result=\"shape\"\/>\n<\/filter>\n<filter id=\"filter52_d\" x=\"170.183\" y=\"46.9612\" width=\"15.7859\" height=\"23.4483\" filterUnits=\"userSpaceOnUse\" color-interpolation-filters=\"sRGB\">\n<feFlood flood-opacity=\"0\" result=\"BackgroundImageFix\"\/>\n<feColorMatrix in=\"SourceAlpha\" type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\"\/>\n<feOffset dy=\"4\"\/>\n<feGaussianBlur stdDeviation=\"2\"\/>\n<feColorMatrix type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\"\/>\n<feBlend mode=\"normal\" in2=\"BackgroundImageFix\" result=\"effect1_dropShadow\"\/>\n<feBlend mode=\"normal\" in=\"SourceGraphic\" in2=\"effect1_dropShadow\" result=\"shape\"\/>\n<\/filter>\n<filter id=\"filter53_d\" x=\"150.408\" y=\"44.9644\" width=\"24.5196\" height=\"29.5072\" filterUnits=\"userSpaceOnUse\" color-interpolation-filters=\"sRGB\">\n<feFlood flood-opacity=\"0\" result=\"BackgroundImageFix\"\/>\n<feColorMatrix in=\"SourceAlpha\" type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\"\/>\n<feOffset dy=\"4\"\/>\n<feGaussianBlur stdDeviation=\"2\"\/>\n<feColorMatrix type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\"\/>\n<feBlend mode=\"normal\" in2=\"BackgroundImageFix\" result=\"effect1_dropShadow\"\/>\n<feBlend mode=\"normal\" in=\"SourceGraphic\" in2=\"effect1_dropShadow\" result=\"shape\"\/>\n<\/filter>\n<filter id=\"filter54_d\" x=\"152.034\" y=\"51.655\" width=\"13.7728\" height=\"15.819\" filterUnits=\"userSpaceOnUse\" color-interpolation-filters=\"sRGB\">\n<feFlood flood-opacity=\"0\" result=\"BackgroundImageFix\"\/>\n<feColorMatrix in=\"SourceAlpha\" type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\"\/>\n<feOffset dy=\"4\"\/>\n<feGaussianBlur stdDeviation=\"2\"\/>\n<feColorMatrix type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\"\/>\n<feBlend mode=\"normal\" in2=\"BackgroundImageFix\" result=\"effect1_dropShadow\"\/>\n<feBlend mode=\"normal\" in=\"SourceGraphic\" in2=\"effect1_dropShadow\" result=\"shape\"\/>\n<\/filter>\n<filter id=\"filter55_d\" x=\"198.788\" y=\"37.7571\" width=\"12.8122\" height=\"31.3963\" filterUnits=\"userSpaceOnUse\" color-interpolation-filters=\"sRGB\">\n<feFlood flood-opacity=\"0\" result=\"BackgroundImageFix\"\/>\n<feColorMatrix in=\"SourceAlpha\" type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\"\/>\n<feOffset dy=\"4\"\/>\n<feGaussianBlur stdDeviation=\"2\"\/>\n<feColorMatrix type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\"\/>\n<feBlend mode=\"normal\" in2=\"BackgroundImageFix\" result=\"effect1_dropShadow\"\/>\n<feBlend mode=\"normal\" in=\"SourceGraphic\" in2=\"effect1_dropShadow\" result=\"shape\"\/>\n<\/filter>\n<filter id=\"filter56_d\" x=\"195.555\" y=\"46.4402\" width=\"11.2285\" height=\"19.7596\" filterUnits=\"userSpaceOnUse\" color-interpolation-filters=\"sRGB\">\n<feFlood flood-opacity=\"0\" result=\"BackgroundImageFix\"\/>\n<feColorMatrix in=\"SourceAlpha\" type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\"\/>\n<feOffset dy=\"4\"\/>\n<feGaussianBlur stdDeviation=\"2\"\/>\n<feColorMatrix type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\"\/>\n<feBlend mode=\"normal\" in2=\"BackgroundImageFix\" result=\"effect1_dropShadow\"\/>\n<feBlend mode=\"normal\" in=\"SourceGraphic\" in2=\"effect1_dropShadow\" result=\"shape\"\/>\n<\/filter>\n<filter id=\"filter57_d\" x=\"150.217\" y=\"24.2671\" width=\"28.2344\" height=\"17.8443\" filterUnits=\"userSpaceOnUse\" color-interpolation-filters=\"sRGB\">\n<feFlood flood-opacity=\"0\" result=\"BackgroundImageFix\"\/>\n<feColorMatrix in=\"SourceAlpha\" type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\"\/>\n<feOffset dy=\"4\"\/>\n<feGaussianBlur stdDeviation=\"2\"\/>\n<feColorMatrix type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\"\/>\n<feBlend mode=\"normal\" in2=\"BackgroundImageFix\" result=\"effect1_dropShadow\"\/>\n<feBlend mode=\"normal\" in=\"SourceGraphic\" in2=\"effect1_dropShadow\" result=\"shape\"\/>\n<\/filter>\n<filter id=\"filter58_d\" x=\"213.404\" y=\"47.311\" width=\"11.0345\" height=\"28.5393\" filterUnits=\"userSpaceOnUse\" color-interpolation-filters=\"sRGB\">\n<feFlood flood-opacity=\"0\" result=\"BackgroundImageFix\"\/>\n<feColorMatrix in=\"SourceAlpha\" type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\"\/>\n<feOffset dy=\"4\"\/>\n<feGaussianBlur stdDeviation=\"2\"\/>\n<feColorMatrix type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\"\/>\n<feBlend mode=\"normal\" in2=\"BackgroundImageFix\" result=\"effect1_dropShadow\"\/>\n<feBlend mode=\"normal\" in=\"SourceGraphic\" in2=\"effect1_dropShadow\" result=\"shape\"\/>\n<\/filter>\n<filter id=\"filter59_d\" x=\"134.309\" y=\"46.9958\" width=\"18.0024\" height=\"35.5647\" filterUnits=\"userSpaceOnUse\" color-interpolation-filters=\"sRGB\">\n<feFlood flood-opacity=\"0\" result=\"BackgroundImageFix\"\/>\n<feColorMatrix in=\"SourceAlpha\" type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\"\/>\n<feOffset dy=\"4\"\/>\n<feGaussianBlur stdDeviation=\"2\"\/>\n<feColorMatrix type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\"\/>\n<feBlend mode=\"normal\" in2=\"BackgroundImageFix\" result=\"effect1_dropShadow\"\/>\n<feBlend mode=\"normal\" in=\"SourceGraphic\" in2=\"effect1_dropShadow\" result=\"shape\"\/>\n<\/filter>\n<filter id=\"filter60_d\" x=\"64.9144\" y=\"129.476\" width=\"24.4945\" height=\"27.3194\" filterUnits=\"userSpaceOnUse\" color-interpolation-filters=\"sRGB\">\n<feFlood flood-opacity=\"0\" result=\"BackgroundImageFix\"\/>\n<feColorMatrix in=\"SourceAlpha\" type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\"\/>\n<feOffset dy=\"4\"\/>\n<feGaussianBlur stdDeviation=\"2\"\/>\n<feColorMatrix type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\"\/>\n<feBlend mode=\"normal\" in2=\"BackgroundImageFix\" result=\"effect1_dropShadow\"\/>\n<feBlend mode=\"normal\" in=\"SourceGraphic\" in2=\"effect1_dropShadow\" result=\"shape\"\/>\n<\/filter>\n<filter id=\"filter61_d\" x=\"62.2369\" y=\"126.19\" width=\"27.5666\" height=\"26.8281\" filterUnits=\"userSpaceOnUse\" color-interpolation-filters=\"sRGB\">\n<feFlood flood-opacity=\"0\" result=\"BackgroundImageFix\"\/>\n<feColorMatrix in=\"SourceAlpha\" type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\"\/>\n<feOffset dy=\"4\"\/>\n<feGaussianBlur stdDeviation=\"2\"\/>\n<feColorMatrix type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\"\/>\n<feBlend mode=\"normal\" in2=\"BackgroundImageFix\" result=\"effect1_dropShadow\"\/>\n<feBlend mode=\"normal\" in=\"SourceGraphic\" in2=\"effect1_dropShadow\" result=\"shape\"\/>\n<\/filter>\n<filter id=\"filter62_d\" x=\"165.547\" y=\"129.942\" width=\"31.1408\" height=\"24.5782\" filterUnits=\"userSpaceOnUse\" color-interpolation-filters=\"sRGB\">\n<feFlood flood-opacity=\"0\" result=\"BackgroundImageFix\"\/>\n<feColorMatrix in=\"SourceAlpha\" type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\"\/>\n<feOffset dy=\"4\"\/>\n<feGaussianBlur stdDeviation=\"2\"\/>\n<feColorMatrix type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\"\/>\n<feBlend mode=\"normal\" in2=\"BackgroundImageFix\" result=\"effect1_dropShadow\"\/>\n<feBlend mode=\"normal\" in=\"SourceGraphic\" in2=\"effect1_dropShadow\" result=\"shape\"\/>\n<\/filter>\n<filter id=\"filter63_d\" x=\"124.525\" y=\"153.545\" width=\"20.6714\" height=\"37.6665\" filterUnits=\"userSpaceOnUse\" color-interpolation-filters=\"sRGB\">\n<feFlood flood-opacity=\"0\" result=\"BackgroundImageFix\"\/>\n<feColorMatrix in=\"SourceAlpha\" type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\"\/>\n<feOffset dy=\"4\"\/>\n<feGaussianBlur stdDeviation=\"2\"\/>\n<feColorMatrix type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\"\/>\n<feBlend mode=\"normal\" in2=\"BackgroundImageFix\" result=\"effect1_dropShadow\"\/>\n<feBlend mode=\"normal\" in=\"SourceGraphic\" in2=\"effect1_dropShadow\" result=\"shape\"\/>\n<\/filter>\n<filter id=\"filter64_d\" x=\"222.625\" y=\"140.613\" width=\"16.6844\" height=\"41.1211\" filterUnits=\"userSpaceOnUse\" color-interpolation-filters=\"sRGB\">\n<feFlood flood-opacity=\"0\" result=\"BackgroundImageFix\"\/>\n<feColorMatrix in=\"SourceAlpha\" type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\"\/>\n<feOffset dy=\"4\"\/>\n<feGaussianBlur stdDeviation=\"2\"\/>\n<feColorMatrix type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\"\/>\n<feBlend mode=\"normal\" in2=\"BackgroundImageFix\" result=\"effect1_dropShadow\"\/>\n<feBlend mode=\"normal\" in=\"SourceGraphic\" in2=\"effect1_dropShadow\" result=\"shape\"\/>\n<\/filter>\n<filter id=\"filter65_d\" x=\"160.702\" y=\"271.745\" width=\"16.7985\" height=\"89.2141\" filterUnits=\"userSpaceOnUse\" color-interpolation-filters=\"sRGB\">\n<feFlood flood-opacity=\"0\" result=\"BackgroundImageFix\"\/>\n<feColorMatrix in=\"SourceAlpha\" type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\"\/>\n<feOffset dy=\"4\"\/>\n<feGaussianBlur stdDeviation=\"2\"\/>\n<feColorMatrix type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\"\/>\n<feBlend mode=\"normal\" in2=\"BackgroundImageFix\" result=\"effect1_dropShadow\"\/>\n<feBlend mode=\"normal\" in=\"SourceGraphic\" in2=\"effect1_dropShadow\" result=\"shape\"\/>\n<\/filter>\n<filter id=\"filter66_d\" x=\"208.17\" y=\"266.501\" width=\"11.8219\" height=\"91.8\" filterUnits=\"userSpaceOnUse\" color-interpolation-filters=\"sRGB\">\n<feFlood flood-opacity=\"0\" result=\"BackgroundImageFix\"\/>\n<feColorMatrix in=\"SourceAlpha\" type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\"\/>\n<feOffset dy=\"4\"\/>\n<feGaussianBlur stdDeviation=\"2\"\/>\n<feColorMatrix type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\"\/>\n<feBlend mode=\"normal\" in2=\"BackgroundImageFix\" result=\"effect1_dropShadow\"\/>\n<feBlend mode=\"normal\" in=\"SourceGraphic\" in2=\"effect1_dropShadow\" result=\"shape\"\/>\n<\/filter>\n<filter id=\"filter67_d\" x=\"280.13\" y=\"37.7\" width=\"75.9\" height=\"100.1\" filterUnits=\"userSpaceOnUse\" color-interpolation-filters=\"sRGB\">\n<feFlood flood-opacity=\"0\" result=\"BackgroundImageFix\"\/>\n<feColorMatrix in=\"SourceAlpha\" type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\"\/>\n<feOffset dy=\"4\"\/>\n<feGaussianBlur stdDeviation=\"2\"\/>\n<feColorMatrix type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\"\/>\n<feBlend mode=\"normal\" in2=\"BackgroundImageFix\" result=\"effect1_dropShadow\"\/>\n<feBlend mode=\"normal\" in=\"SourceGraphic\" in2=\"effect1_dropShadow\" result=\"shape\"\/>\n<\/filter>\n<filter id=\"filter68_d\" x=\"60.7457\" y=\"53.179\" width=\"19.3866\" height=\"108.497\" filterUnits=\"userSpaceOnUse\" color-interpolation-filters=\"sRGB\">\n<feFlood flood-opacity=\"0\" result=\"BackgroundImageFix\"\/>\n<feColorMatrix in=\"SourceAlpha\" type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\"\/>\n<feOffset dy=\"4\"\/>\n<feGaussianBlur stdDeviation=\"2\"\/>\n<feColorMatrix type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\"\/>\n<feBlend mode=\"normal\" in2=\"BackgroundImageFix\" result=\"effect1_dropShadow\"\/>\n<feBlend mode=\"normal\" in=\"SourceGraphic\" in2=\"effect1_dropShadow\" result=\"shape\"\/>\n<\/filter>\n<filter id=\"filter69_d\" x=\"19.8799\" y=\"3.22998\" width=\"84.9001\" height=\"84.9501\" filterUnits=\"userSpaceOnUse\" color-interpolation-filters=\"sRGB\">\n<feFlood flood-opacity=\"0\" result=\"BackgroundImageFix\"\/>\n<feColorMatrix in=\"SourceAlpha\" type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\"\/>\n<feOffset dy=\"4\"\/>\n<feGaussianBlur stdDeviation=\"2\"\/>\n<feColorMatrix type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\"\/>\n<feBlend mode=\"normal\" in2=\"BackgroundImageFix\" result=\"effect1_dropShadow\"\/>\n<feBlend mode=\"normal\" in=\"SourceGraphic\" in2=\"effect1_dropShadow\" result=\"shape\"\/>\n<\/filter>\n<filter id=\"filter70_d\" x=\"27.89\" y=\"11.29\" width=\"68.88\" height=\"68.88\" filterUnits=\"userSpaceOnUse\" color-interpolation-filters=\"sRGB\">\n<feFlood flood-opacity=\"0\" result=\"BackgroundImageFix\"\/>\n<feColorMatrix in=\"SourceAlpha\" type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\"\/>\n<feOffset dy=\"4\"\/>\n<feGaussianBlur stdDeviation=\"2\"\/>\n<feColorMatrix type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\"\/>\n<feBlend mode=\"normal\" in2=\"BackgroundImageFix\" result=\"effect1_dropShadow\"\/>\n<feBlend mode=\"normal\" in=\"SourceGraphic\" in2=\"effect1_dropShadow\" result=\"shape\"\/>\n<\/filter>\n<filter id=\"filter71_d\" x=\"30.9513\" y=\"15.2754\" width=\"28.1987\" height=\"42.5429\" filterUnits=\"userSpaceOnUse\" color-interpolation-filters=\"sRGB\">\n<feFlood flood-opacity=\"0\" result=\"BackgroundImageFix\"\/>\n<feColorMatrix in=\"SourceAlpha\" type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\"\/>\n<feOffset dy=\"4\"\/>\n<feGaussianBlur stdDeviation=\"2\"\/>\n<feColorMatrix type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\"\/>\n<feBlend mode=\"normal\" in2=\"BackgroundImageFix\" result=\"effect1_dropShadow\"\/>\n<feBlend mode=\"normal\" in=\"SourceGraphic\" in2=\"effect1_dropShadow\" result=\"shape\"\/>\n<\/filter>\n<filter id=\"filter72_d\" x=\"40.6333\" y=\"42.2886\" width=\"12.3667\" height=\"13.3226\" filterUnits=\"userSpaceOnUse\" color-interpolation-filters=\"sRGB\">\n<feFlood flood-opacity=\"0\" result=\"BackgroundImageFix\"\/>\n<feColorMatrix in=\"SourceAlpha\" type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\"\/>\n<feOffset dy=\"4\"\/>\n<feGaussianBlur stdDeviation=\"2\"\/>\n<feColorMatrix type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\"\/>\n<feBlend mode=\"normal\" in2=\"BackgroundImageFix\" result=\"effect1_dropShadow\"\/>\n<feBlend mode=\"normal\" in=\"SourceGraphic\" in2=\"effect1_dropShadow\" result=\"shape\"\/>\n<\/filter>\n<filter id=\"filter73_d\" x=\"64.7639\" y=\"57.3799\" width=\"26.3461\" height=\"19.99\" filterUnits=\"userSpaceOnUse\" color-interpolation-filters=\"sRGB\">\n<feFlood flood-opacity=\"0\" result=\"BackgroundImageFix\"\/>\n<feColorMatrix in=\"SourceAlpha\" type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\"\/>\n<feOffset dy=\"4\"\/>\n<feGaussianBlur stdDeviation=\"2\"\/>\n<feColorMatrix type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\"\/>\n<feBlend mode=\"normal\" in2=\"BackgroundImageFix\" result=\"effect1_dropShadow\"\/>\n<feBlend mode=\"normal\" in=\"SourceGraphic\" in2=\"effect1_dropShadow\" result=\"shape\"\/>\n<\/filter>\n<filter id=\"filter74_d\" x=\"83.23\" y=\"57.0801\" width=\"8.92\" height=\"9.11\" filterUnits=\"userSpaceOnUse\" color-interpolation-filters=\"sRGB\">\n<feFlood flood-opacity=\"0\" result=\"BackgroundImageFix\"\/>\n<feColorMatrix in=\"SourceAlpha\" type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\"\/>\n<feOffset dy=\"4\"\/>\n<feGaussianBlur stdDeviation=\"2\"\/>\n<feColorMatrix type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\"\/>\n<feBlend mode=\"normal\" in2=\"BackgroundImageFix\" result=\"effect1_dropShadow\"\/>\n<feBlend mode=\"normal\" in=\"SourceGraphic\" in2=\"effect1_dropShadow\" result=\"shape\"\/>\n<\/filter>\n<filter id=\"filter75_d\" x=\"82.5112\" y=\"53.7585\" width=\"9.84369\" height=\"12.4216\" filterUnits=\"userSpaceOnUse\" color-interpolation-filters=\"sRGB\">\n<feFlood flood-opacity=\"0\" result=\"BackgroundImageFix\"\/>\n<feColorMatrix in=\"SourceAlpha\" type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\"\/>\n<feOffset dy=\"4\"\/>\n<feGaussianBlur stdDeviation=\"2\"\/>\n<feColorMatrix type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\"\/>\n<feBlend mode=\"normal\" in2=\"BackgroundImageFix\" result=\"effect1_dropShadow\"\/>\n<feBlend mode=\"normal\" in=\"SourceGraphic\" in2=\"effect1_dropShadow\" result=\"shape\"\/>\n<\/filter>\n<filter id=\"filter76_d\" x=\"75.5626\" y=\"48.8572\" width=\"13.7484\" height=\"13.4509\" filterUnits=\"userSpaceOnUse\" color-interpolation-filters=\"sRGB\">\n<feFlood flood-opacity=\"0\" result=\"BackgroundImageFix\"\/>\n<feColorMatrix in=\"SourceAlpha\" type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\"\/>\n<feOffset dy=\"4\"\/>\n<feGaussianBlur stdDeviation=\"2\"\/>\n<feColorMatrix type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\"\/>\n<feBlend mode=\"normal\" in2=\"BackgroundImageFix\" result=\"effect1_dropShadow\"\/>\n<feBlend mode=\"normal\" in=\"SourceGraphic\" in2=\"effect1_dropShadow\" result=\"shape\"\/>\n<\/filter>\n<filter id=\"filter77_d\" x=\"70.23\" y=\"46.3203\" width=\"10.2306\" height=\"15.1617\" filterUnits=\"userSpaceOnUse\" color-interpolation-filters=\"sRGB\">\n<feFlood flood-opacity=\"0\" result=\"BackgroundImageFix\"\/>\n<feColorMatrix in=\"SourceAlpha\" type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\"\/>\n<feOffset dy=\"4\"\/>\n<feGaussianBlur stdDeviation=\"2\"\/>\n<feColorMatrix type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\"\/>\n<feBlend mode=\"normal\" in2=\"BackgroundImageFix\" result=\"effect1_dropShadow\"\/>\n<feBlend mode=\"normal\" in=\"SourceGraphic\" in2=\"effect1_dropShadow\" result=\"shape\"\/>\n<\/filter>\n<filter id=\"filter78_d\" x=\"82.3654\" y=\"43.0547\" width=\"10.1984\" height=\"14.7052\" filterUnits=\"userSpaceOnUse\" color-interpolation-filters=\"sRGB\">\n<feFlood flood-opacity=\"0\" result=\"BackgroundImageFix\"\/>\n<feColorMatrix in=\"SourceAlpha\" type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\"\/>\n<feOffset dy=\"4\"\/>\n<feGaussianBlur stdDeviation=\"2\"\/>\n<feColorMatrix type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\"\/>\n<feBlend mode=\"normal\" in2=\"BackgroundImageFix\" result=\"effect1_dropShadow\"\/>\n<feBlend mode=\"normal\" in=\"SourceGraphic\" in2=\"effect1_dropShadow\" result=\"shape\"\/>\n<\/filter>\n<filter id=\"filter79_d\" x=\"48.8217\" y=\"19.7285\" width=\"16.6457\" height=\"17.6795\" filterUnits=\"userSpaceOnUse\" color-interpolation-filters=\"sRGB\">\n<feFlood flood-opacity=\"0\" result=\"BackgroundImageFix\"\/>\n<feColorMatrix in=\"SourceAlpha\" type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\"\/>\n<feOffset dy=\"4\"\/>\n<feGaussianBlur stdDeviation=\"2\"\/>\n<feColorMatrix type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\"\/>\n<feBlend mode=\"normal\" in2=\"BackgroundImageFix\" result=\"effect1_dropShadow\"\/>\n<feBlend mode=\"normal\" in=\"SourceGraphic\" in2=\"effect1_dropShadow\" result=\"shape\"\/>\n<\/filter>\n<filter id=\"filter80_d\" x=\"51.4263\" y=\"14.5078\" width=\"42.9937\" height=\"40.9389\" filterUnits=\"userSpaceOnUse\" color-interpolation-filters=\"sRGB\">\n<feFlood flood-opacity=\"0\" result=\"BackgroundImageFix\"\/>\n<feColorMatrix in=\"SourceAlpha\" type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\"\/>\n<feOffset dy=\"4\"\/>\n<feGaussianBlur stdDeviation=\"2\"\/>\n<feColorMatrix type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\"\/>\n<feBlend mode=\"normal\" in2=\"BackgroundImageFix\" result=\"effect1_dropShadow\"\/>\n<feBlend mode=\"normal\" in=\"SourceGraphic\" in2=\"effect1_dropShadow\" result=\"shape\"\/>\n<\/filter>\n<filter id=\"filter81_d\" x=\"50.98\" y=\"11.3\" width=\"15.83\" height=\"12.7809\" filterUnits=\"userSpaceOnUse\" color-interpolation-filters=\"sRGB\">\n<feFlood flood-opacity=\"0\" result=\"BackgroundImageFix\"\/>\n<feColorMatrix in=\"SourceAlpha\" type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\"\/>\n<feOffset dy=\"4\"\/>\n<feGaussianBlur stdDeviation=\"2\"\/>\n<feColorMatrix type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\"\/>\n<feBlend mode=\"normal\" in2=\"BackgroundImageFix\" result=\"effect1_dropShadow\"\/>\n<feBlend mode=\"normal\" in=\"SourceGraphic\" in2=\"effect1_dropShadow\" result=\"shape\"\/>\n<\/filter>\n<filter id=\"filter82_d\" x=\"17.36\" y=\"42.4299\" width=\"58.9\" height=\"45.98\" filterUnits=\"userSpaceOnUse\" color-interpolation-filters=\"sRGB\">\n<feFlood flood-opacity=\"0\" result=\"BackgroundImageFix\"\/>\n<feColorMatrix in=\"SourceAlpha\" type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\"\/>\n<feOffset dy=\"4\"\/>\n<feGaussianBlur stdDeviation=\"2\"\/>\n<feColorMatrix type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\"\/>\n<feBlend mode=\"normal\" in2=\"BackgroundImageFix\" result=\"effect1_dropShadow\"\/>\n<feBlend mode=\"normal\" in=\"SourceGraphic\" in2=\"effect1_dropShadow\" result=\"shape\"\/>\n<\/filter>\n<filter id=\"filter83_d\" x=\"34.7999\" y=\"49.25\" width=\"27.49\" height=\"26.21\" filterUnits=\"userSpaceOnUse\" color-interpolation-filters=\"sRGB\">\n<feFlood flood-opacity=\"0\" result=\"BackgroundImageFix\"\/>\n<feColorMatrix in=\"SourceAlpha\" type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\"\/>\n<feOffset dy=\"4\"\/>\n<feGaussianBlur stdDeviation=\"2\"\/>\n<feColorMatrix type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\"\/>\n<feBlend mode=\"normal\" in2=\"BackgroundImageFix\" result=\"effect1_dropShadow\"\/>\n<feBlend mode=\"normal\" in=\"SourceGraphic\" in2=\"effect1_dropShadow\" result=\"shape\"\/>\n<\/filter>\n<filter id=\"filter84_d\" x=\"59\" y=\"0\" width=\"52.65\" height=\"41.32\" filterUnits=\"userSpaceOnUse\" color-interpolation-filters=\"sRGB\">\n<feFlood flood-opacity=\"0\" result=\"BackgroundImageFix\"\/>\n<feColorMatrix in=\"SourceAlpha\" type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\"\/>\n<feOffset dy=\"4\"\/>\n<feGaussianBlur stdDeviation=\"2\"\/>\n<feColorMatrix type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\"\/>\n<feBlend mode=\"normal\" in2=\"BackgroundImageFix\" result=\"effect1_dropShadow\"\/>\n<feBlend mode=\"normal\" in=\"SourceGraphic\" in2=\"effect1_dropShadow\" result=\"shape\"\/>\n<\/filter>\n<filter id=\"filter85_d\" x=\"73\" y=\"7.93994\" width=\"19.84\" height=\"21.82\" filterUnits=\"userSpaceOnUse\" color-interpolation-filters=\"sRGB\">\n<feFlood flood-opacity=\"0\" result=\"BackgroundImageFix\"\/>\n<feColorMatrix in=\"SourceAlpha\" type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\"\/>\n<feOffset dy=\"4\"\/>\n<feGaussianBlur stdDeviation=\"2\"\/>\n<feColorMatrix type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\"\/>\n<feBlend mode=\"normal\" in2=\"BackgroundImageFix\" result=\"effect1_dropShadow\"\/>\n<feBlend mode=\"normal\" in=\"SourceGraphic\" in2=\"effect1_dropShadow\" result=\"shape\"\/>\n<\/filter>\n<filter id=\"filter86_d\" x=\"59.6896\" y=\"130.448\" width=\"16.1616\" height=\"14.7819\" filterUnits=\"userSpaceOnUse\" color-interpolation-filters=\"sRGB\">\n<feFlood flood-opacity=\"0\" result=\"BackgroundImageFix\"\/>\n<feColorMatrix in=\"SourceAlpha\" type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\"\/>\n<feOffset dy=\"4\"\/>\n<feGaussianBlur stdDeviation=\"2\"\/>\n<feColorMatrix type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\"\/>\n<feBlend mode=\"normal\" in2=\"BackgroundImageFix\" result=\"effect1_dropShadow\"\/>\n<feBlend mode=\"normal\" in=\"SourceGraphic\" in2=\"effect1_dropShadow\" result=\"shape\"\/>\n<\/filter>\n<filter id=\"filter87_d\" x=\"60.2981\" y=\"135.144\" width=\"17.7435\" height=\"14.4745\" filterUnits=\"userSpaceOnUse\" color-interpolation-filters=\"sRGB\">\n<feFlood flood-opacity=\"0\" result=\"BackgroundImageFix\"\/>\n<feColorMatrix in=\"SourceAlpha\" type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\"\/>\n<feOffset dy=\"4\"\/>\n<feGaussianBlur stdDeviation=\"2\"\/>\n<feColorMatrix type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\"\/>\n<feBlend mode=\"normal\" in2=\"BackgroundImageFix\" result=\"effect1_dropShadow\"\/>\n<feBlend mode=\"normal\" in=\"SourceGraphic\" in2=\"effect1_dropShadow\" result=\"shape\"\/>\n<\/filter>\n<filter id=\"filter88_d\" x=\"60.9845\" y=\"139.765\" width=\"16.9873\" height=\"13.7985\" filterUnits=\"userSpaceOnUse\" color-interpolation-filters=\"sRGB\">\n<feFlood flood-opacity=\"0\" result=\"BackgroundImageFix\"\/>\n<feColorMatrix in=\"SourceAlpha\" type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\"\/>\n<feOffset dy=\"4\"\/>\n<feGaussianBlur stdDeviation=\"2\"\/>\n<feColorMatrix type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\"\/>\n<feBlend mode=\"normal\" in2=\"BackgroundImageFix\" result=\"effect1_dropShadow\"\/>\n<feBlend mode=\"normal\" in=\"SourceGraphic\" in2=\"effect1_dropShadow\" result=\"shape\"\/>\n<\/filter>\n<filter id=\"filter89_d\" x=\"62.2917\" y=\"144.282\" width=\"14.3418\" height=\"12.4583\" filterUnits=\"userSpaceOnUse\" color-interpolation-filters=\"sRGB\">\n<feFlood flood-opacity=\"0\" result=\"BackgroundImageFix\"\/>\n<feColorMatrix in=\"SourceAlpha\" type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\"\/>\n<feOffset dy=\"4\"\/>\n<feGaussianBlur stdDeviation=\"2\"\/>\n<feColorMatrix type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\"\/>\n<feBlend mode=\"normal\" in2=\"BackgroundImageFix\" result=\"effect1_dropShadow\"\/>\n<feBlend mode=\"normal\" in=\"SourceGraphic\" in2=\"effect1_dropShadow\" result=\"shape\"\/>\n<\/filter>\n<\/defs>\n<\/svg>\n<\/div>\n<p><img decoding=\"async\" src=\"\/wp-content\/uploads\/2021\/05\/Ladder1.svg\" alt=\"\"><\/p>\n<div><a class=\"\" href=\"#bsec\" uk-scroll><br \/>\n    <span class=\"arro-hero uk-icon-button\" uk-icon=\"icon: arrow-down; ratio: 3;\"><\/span><\/a><\/div>\n<div>\n<div><svg width=\"409\" height=\"409\" viewBox=\"0 0 409 409\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n<g id=\"about-svg 1\">\n<g id=\"Layer 2\">\n<g id=\"Layer 1\">\n<path id=\"Vector13326\" d=\"M204.5 409C317.442 409 409 317.442 409 204.5C409 91.5578 317.442 0 204.5 0C91.5578 0 0 91.5578 0 204.5C0 317.442 91.5578 409 204.5 409Z\" fill=\"#F4F4F4\"\/>\n<path id=\"cog-abouts\" d=\"M112.5 298.79C114.055 298.819 115.599 299.057 117.09 299.5L120.09 296.4L126.18 300.09L124.81 304.17C125.893 305.285 126.819 306.543 127.56 307.91L131.86 307.83L133.55 314.74L129.7 316.66C129.671 318.211 129.435 319.751 129 321.24L132.09 324.24L128.4 330.32L124.3 329C123.186 330.08 121.931 331.005 120.57 331.75L120.64 336.04L113.73 337.74L111.81 333.89C110.258 333.862 108.717 333.623 107.23 333.18L104.23 336.28L98.15 332.59L99.51 328.51C98.4332 327.392 97.5116 326.134 96.77 324.77L92.47 324.85L90.78 317.94L94.63 316C94.6627 314.449 94.9015 312.908 95.34 311.42L92.25 308.42L95.93 302.34L100.01 303.7C101.13 302.625 102.388 301.704 103.75 300.96L103.67 296.66L110.58 294.97L112.5 298.81V298.79ZM110.66 308.79C109.194 309.148 107.866 309.933 106.846 311.046C105.826 312.159 105.159 313.549 104.93 315.041C104.7 316.533 104.918 318.06 105.556 319.428C106.195 320.796 107.224 321.944 108.515 322.727C109.806 323.509 111.3 323.891 112.808 323.825C114.316 323.758 115.77 323.245 116.987 322.352C118.204 321.458 119.128 320.224 119.643 318.805C120.158 317.386 120.241 315.846 119.88 314.38C119.391 312.423 118.146 310.74 116.417 309.699C114.689 308.659 112.619 308.346 110.66 308.83V308.79Z\" fill=\"#5198BF\"\/>\n<path id=\"Vector13326_2\" d=\"M80.61 223.88C80.61 223.88 34.31 150.42 118.61 113.88\" stroke=\"#1A2E35\" stroke-width=\"0.43\" stroke-miterlimit=\"10\" stroke-dasharray=\"2.59 2.59\"\/>\n<path id=\"Vector13326_3\" d=\"M319.78 167.46H114.65V305.36H319.78V167.46Z\" fill=\"#8CD0C4\"\/>\n<path id=\"Vector13326_4\" d=\"M114.65 181H319.78\" stroke=\"#231F20\" stroke-miterlimit=\"10\"\/>\n<path id=\"Vector13326_5\" d=\"M123.27 177.81C125.175 177.81 126.72 176.265 126.72 174.36C126.72 172.455 125.175 170.91 123.27 170.91C121.365 170.91 119.82 172.455 119.82 174.36C119.82 176.265 121.365 177.81 123.27 177.81Z\" fill=\"#D7ECF4\" stroke=\"#231F20\" stroke-miterlimit=\"10\"\/>\n<path id=\"Vector13326_6\" d=\"M133.61 177.81C135.515 177.81 137.06 176.265 137.06 174.36C137.06 172.455 135.515 170.91 133.61 170.91C131.705 170.91 130.16 172.455 130.16 174.36C130.16 176.265 131.705 177.81 133.61 177.81Z\" fill=\"#D7ECF4\" stroke=\"#231F20\" stroke-miterlimit=\"10\"\/>\n<path id=\"Vector13326_7\" d=\"M143.96 177.81C145.865 177.81 147.41 176.265 147.41 174.36C147.41 172.455 145.865 170.91 143.96 170.91C142.055 170.91 140.51 172.455 140.51 174.36C140.51 176.265 142.055 177.81 143.96 177.81Z\" fill=\"#D7ECF4\" stroke=\"#231F20\" stroke-miterlimit=\"10\"\/>\n<g id=\"box-about\">\n<path id=\"Vector13326_8\" d=\"M311.01 267.87H286.04V293.54H311.01V267.87Z\" fill=\"#EB6D79\"\/>\n<path id=\"Vector13326_9\" d=\"M301.28 267.87H275.8V293.62H301.28V267.87Z\" fill=\"#F3B756\"\/>\n<path id=\"Vector13326_10\" d=\"M252 180.5H276.88C276.88 180.5 276.88 159.62 298.58 159.24C309.86 159.05 315.7 166.43 318.08 172.09C319.394 175.35 319.919 178.875 319.611 182.377C319.303 185.879 318.172 189.259 316.31 192.24C312.09 199.24 303 206.19 286.23 203.24L286.07 258.67H310.67V225.8C310.67 225.8 345.18 216.88 345.18 178.86C345.18 142.48 315.76 134.62 299.95 134.12C291.15 133.84 287.95 133.46 277.08 135C263.24 137 251.73 153.07 252 180.5Z\" fill=\"#EB6D79\"\/>\n<path id=\"Vector13326_11\" d=\"M241.72 180.5H266.6C266.6 180.5 266.6 159.62 288.31 159.24C299.58 159.05 305.43 166.43 307.8 172.09C309.112 175.352 309.633 178.879 309.32 182.381C309.007 185.884 307.87 189.262 306 192.24C301.78 199.24 292.54 205.52 275.77 202.57V258.66H300.37V225.8C300.37 225.8 334.87 216.88 334.87 178.86C334.87 142.48 302.25 134.03 288.28 134.03C277.63 134 241.25 136.61 241.72 180.5Z\" fill=\"#F3B756\"\/>\n<\/g>\n<path id=\"box-about_2\" d=\"M252.61 267.51H226.86V293.26H252.61V267.51Z\" fill=\"#F3B756\"\/>\n<path id=\"box-about_3\" d=\"M205.91 267.51H180.16V293.26H205.91V267.51Z\" fill=\"#F3B756\"\/>\n<path id=\"box-about_4\" d=\"M159.2 267.51H133.45V293.26H159.2V267.51Z\" fill=\"#F3B756\"\/>\n<path id=\"cog-about\" d=\"M87.42 214.68C90.5054 214.739 93.5691 215.21 96.53 216.08L102.47 209.93L114.56 217.26L111.85 225.37C113.992 227.593 115.828 230.092 117.31 232.8L125.85 232.65L129.22 246.39L121.57 250.2C121.516 253.289 121.045 256.357 120.17 259.32L126.32 265.26L119 277.35L110.89 274.64C108.667 276.782 106.168 278.618 103.46 280.1L103.61 288.64L89.86 292L86.05 284.35C82.9612 284.291 79.8942 283.82 76.93 282.95L71 289.11L58.9 281.77L61.61 273.67C59.468 271.449 57.6348 268.95 56.16 266.24L47.61 266.39L44.25 252.65L51.89 248.83C51.9495 245.745 52.4203 242.681 53.29 239.72L47.14 233.78L54.48 221.69L62.58 224.4C64.7985 222.257 67.294 220.421 70 218.94L69.85 210.4L83.6 207L87.42 214.65V214.68ZM83.75 234.63C80.8356 235.343 78.198 236.904 76.1708 239.116C74.1437 241.328 72.818 244.092 72.3614 247.057C71.9048 250.022 72.3378 253.057 73.6057 255.776C74.8736 258.495 76.9194 260.778 79.4844 262.334C82.0494 263.891 85.0184 264.652 88.0159 264.521C91.0134 264.39 93.9048 263.374 96.3245 261.6C98.7442 259.825 100.583 257.374 101.61 254.554C102.636 251.735 102.803 248.674 102.09 245.76C101.131 241.854 98.6616 238.487 95.2229 236.4C91.7842 234.314 87.6578 233.677 83.75 234.63V234.63Z\" fill=\"#5198BF\"\/>\n<path id=\"Vector13326_12\" d=\"M311.77 82.7C314.405 78.1677 315.775 73.011 315.737 67.7684C315.699 62.5258 314.253 57.3897 311.552 52.8964C308.851 48.4031 304.993 44.7176 300.381 42.2246C295.769 39.7316 290.572 38.5227 285.333 38.7241C280.094 38.9255 275.005 40.5299 270.598 43.3696C266.191 46.2093 262.627 50.1802 260.279 54.8676C257.931 59.555 256.884 64.787 257.249 70.017C257.613 75.2471 259.375 80.2834 262.35 84.6L258.64 91L280.83 103.91C280.83 103.91 283.04 100.4 284.95 97.23C290.324 97.5075 295.671 96.2982 300.402 93.7348C305.134 91.1714 309.067 87.3533 311.77 82.7V82.7Z\" fill=\"#FCD545\"\/>\n<path id=\"Vector13326_13\" d=\"M272.86 99.12L273.07 98.83L273.7 97.97C274.27 97.23 275.1 96.13 276.21 94.74C277.32 93.35 278.69 91.67 280.41 89.82C282.352 87.7128 284.496 85.8004 286.81 84.11C288.158 83.1285 289.59 82.2684 291.09 81.54C291.909 81.1347 292.817 80.9453 293.73 80.99C294.214 81.0275 294.681 81.1817 295.092 81.4395C295.503 81.6972 295.846 82.0509 296.09 82.47C296.343 82.9121 296.418 83.4344 296.3 83.93C296.186 84.4398 295.878 84.8848 295.44 85.17C294.565 85.709 293.521 85.9049 292.51 85.72C291.457 85.5044 290.459 85.0789 289.574 84.469C288.69 83.8591 287.937 83.0772 287.361 82.1701C286.785 81.2629 286.398 80.249 286.223 79.189C286.047 78.1289 286.087 77.0443 286.34 76C286.569 74.8757 287.105 73.837 287.89 73C288.309 72.5531 288.87 72.2658 289.478 72.1874C290.085 72.109 290.701 72.2442 291.22 72.57C291.473 72.7574 291.677 73.004 291.812 73.2881C291.948 73.5722 292.013 73.8853 292 74.2C291.964 74.8252 291.714 75.4188 291.29 75.88C290.38 76.7129 289.227 77.2317 288 77.36C286.793 77.5698 285.556 77.5251 284.368 77.2289C283.18 76.9327 282.067 76.3915 281.1 75.64C280.147 74.8613 279.397 73.8631 278.915 72.731C278.432 71.5989 278.232 70.3667 278.33 69.14C278.377 68.5299 278.55 67.9362 278.838 67.3959C279.125 66.8556 279.521 66.3804 280 66C280.244 65.8022 280.526 65.6581 280.83 65.5771C281.133 65.4961 281.45 65.48 281.76 65.53C282.063 65.5839 282.351 65.7008 282.606 65.873C282.861 66.0453 283.077 66.2691 283.24 66.53C283.552 67.0509 283.698 67.6541 283.66 68.26C283.617 68.8446 283.461 69.4152 283.2 69.94C282.698 70.9613 281.994 71.8698 281.13 72.61C279.48 74.0715 277.333 74.8477 275.13 74.78C273.031 74.7034 271.027 73.8808 269.48 72.46C268.686 71.812 268.13 70.9185 267.9 69.92C267.799 69.4172 267.87 68.895 268.102 68.4377C268.335 67.9805 268.714 67.6149 269.18 67.4C269.662 67.2446 270.186 67.284 270.64 67.51C271.076 67.719 271.447 68.0442 271.71 68.45C272.174 69.2434 272.364 70.1678 272.25 71.08C272.09 72.83 271.82 74.46 271.6 76.08C270.66 82.36 269.6 87.4 268.91 90.87C268.55 92.61 268.24 93.95 268.03 94.87C267.92 95.31 267.84 95.65 267.78 95.87L267.69 96.22C267.703 96.099 267.723 95.9788 267.75 95.86L267.96 94.86C268.15 93.93 268.42 92.58 268.78 90.86C269.47 87.38 270.44 82.33 271.35 76.06C271.56 74.49 271.82 72.83 271.97 71.13C272.072 70.2776 271.896 69.4151 271.47 68.67C271.303 68.2364 270.97 67.8869 270.546 67.6984C270.121 67.5099 269.639 67.4979 269.205 67.665C268.771 67.8321 268.422 68.1646 268.233 68.5894C268.045 69.0141 268.033 69.4964 268.2 69.93C268.431 70.8561 268.953 71.6835 269.69 72.29C271.192 73.6493 273.125 74.4354 275.15 74.51C277.279 74.5756 279.352 73.8284 280.95 72.42C281.783 71.7107 282.463 70.8398 282.95 69.86C283.219 69.3934 283.366 68.8663 283.376 68.3277C283.387 67.7891 283.261 67.2567 283.01 66.78C282.878 66.552 282.7 66.3546 282.486 66.2012C282.272 66.0477 282.028 65.9416 281.77 65.89C281.508 65.851 281.241 65.8673 280.986 65.9379C280.731 66.0085 280.494 66.1319 280.29 66.3C279.854 66.6546 279.498 67.0971 279.245 67.5984C278.992 68.0998 278.847 68.6489 278.82 69.21C278.727 70.3783 278.918 71.5518 279.378 72.6299C279.838 73.7079 280.552 74.6585 281.46 75.4C282.38 76.1044 283.437 76.6103 284.562 76.8857C285.688 77.1611 286.858 77.2 288 77C289.118 76.8715 290.167 76.3958 291 75.64C291.369 75.2403 291.585 74.7233 291.61 74.18C291.63 73.9223 291.583 73.6637 291.475 73.4291C291.366 73.1944 291.199 72.9916 290.99 72.84C290.548 72.5473 290.014 72.4296 289.49 72.51C288.967 72.6034 288.486 72.8547 288.11 73.23C287.373 74.0204 286.871 75.0004 286.66 76.06C286.421 77.0605 286.384 78.0987 286.552 79.1137C286.719 80.1286 287.087 81.1 287.635 81.9708C288.183 82.8416 288.898 83.5943 289.741 84.1849C290.583 84.7754 291.535 85.192 292.54 85.41C293.473 85.5826 294.437 85.4083 295.25 84.92C295.619 84.6778 295.882 84.3037 295.984 83.8743C296.086 83.4448 296.02 82.9925 295.8 82.61C295.579 82.2342 295.272 81.9171 294.903 81.6856C294.534 81.4541 294.114 81.315 293.68 81.28C292.817 81.238 291.957 81.4134 291.18 81.79C289.715 82.5089 288.316 83.3555 287 84.32C284.688 85.9868 282.544 87.8758 280.6 89.96C278.87 91.79 277.48 93.46 276.36 94.83C275.24 96.2 274.36 97.28 273.8 98.02L273.14 98.85C273 99 272.86 99.12 272.86 99.12Z\" fill=\"#1A2E35\"\/>\n<path id=\"Vector13326_14\" d=\"M276.73 107L257.68 95.93C257.492 95.8213 257.327 95.6766 257.195 95.5041C257.063 95.3315 256.966 95.1346 256.91 94.9246C256.855 94.7147 256.841 94.4957 256.87 94.2804C256.899 94.0651 256.97 93.8577 257.08 93.67V93.67C257.189 93.4819 257.333 93.3171 257.506 93.185C257.678 93.053 257.875 92.9563 258.085 92.9006C258.295 92.8448 258.514 92.8311 258.729 92.8602C258.945 92.8893 259.152 92.9606 259.34 93.07L278.39 104.15C278.578 104.259 278.743 104.403 278.875 104.576C279.007 104.748 279.104 104.945 279.159 105.155C279.215 105.365 279.229 105.584 279.2 105.8C279.171 106.015 279.099 106.222 278.99 106.41V106.41C278.88 106.597 278.735 106.761 278.562 106.892C278.389 107.023 278.192 107.119 277.982 107.174C277.772 107.229 277.554 107.241 277.339 107.212C277.124 107.182 276.917 107.11 276.73 107V107Z\" fill=\"#1A2E35\"\/>\n<path id=\"Vector13326_15\" d=\"M276 108.26L257 97.18C256.621 96.9598 256.17 96.8994 255.746 97.0119C255.322 97.1244 254.96 97.4007 254.74 97.78C254.52 98.1592 254.459 98.6104 254.572 99.0342C254.684 99.4581 254.961 99.8198 255.34 100.04L257.43 101.25L257.13 108.15C257.116 108.537 257.208 108.921 257.394 109.261C257.581 109.601 257.856 109.884 258.19 110.08L264.99 114.08C265.323 114.286 265.708 114.396 266.1 114.396C266.492 114.396 266.877 114.286 267.21 114.08L272.97 110.38L274.39 111.21C274.578 111.319 274.785 111.39 275 111.419C275.216 111.448 275.434 111.434 275.644 111.378C275.854 111.322 276.051 111.226 276.224 111.094C276.396 110.962 276.541 110.798 276.65 110.61C276.759 110.422 276.83 110.215 276.859 110C276.888 109.784 276.874 109.566 276.818 109.356C276.762 109.146 276.666 108.949 276.534 108.776C276.402 108.604 276.238 108.459 276.05 108.35L276 108.26Z\" fill=\"#1A2E35\"\/>\n<g id=\"Group\" opacity=\"0.2\">\n<path id=\"Vector13326_16\" opacity=\"0.2\" d=\"M279.58 42.39C281.874 41.8647 284.239 41.7194 286.58 41.96C288.148 42.1097 289.686 42.494 291.14 43.1C292.14 43.56 292.65 43.97 292.58 44.2C292.42 44.72 290.1 44.29 286.51 44.51C281.891 44.6858 277.42 46.1856 273.629 48.8309C269.839 51.4761 266.889 55.1552 265.13 59.43C263.69 62.73 263.3 65.05 262.75 65.02C262.51 65.02 262.3 64.4 262.22 63.29C262.148 61.7169 262.317 60.1421 262.72 58.62C263.301 56.3272 264.254 54.1451 265.54 52.16C267.118 49.7006 269.155 47.5684 271.54 45.88\" fill=\"white\"\/>\n<\/g>\n<g id=\"Group_2\" opacity=\"0.2\">\n<path id=\"Vector13326_17\" opacity=\"0.2\" d=\"M298.06 48.83C296.46 47.88 295.3 46.62 295.63 45.67C295.81 45.21 296.36 44.94 297.15 44.92C298.114 44.9634 299.053 45.2421 299.884 45.732C300.716 46.2218 301.415 46.9078 301.92 47.73C302.098 47.9727 302.201 48.2624 302.215 48.563C302.229 48.8636 302.154 49.1617 302 49.42\" fill=\"white\"\/>\n<\/g>\n<path id=\"Vector13326_18\" d=\"M266.54 114.23C266.162 113.863 265.805 113.476 265.47 113.07C263.71 111.236 261.426 109.992 258.93 109.51C258.405 109.45 257.885 109.359 257.37 109.24C257.899 109.145 258.441 109.145 258.97 109.24C260.258 109.418 261.505 109.824 262.65 110.44C263.789 111.065 264.806 111.892 265.65 112.88C266.031 113.268 266.333 113.727 266.54 114.23V114.23Z\" fill=\"#375A64\"\/>\n<path id=\"Vector13326_19\" d=\"M272.92 110.38C272.87 110.47 269.39 108.53 265.14 106.06C260.89 103.59 257.49 101.52 257.54 101.43C257.59 101.34 261.07 103.28 265.32 105.75C269.57 108.22 273 110.29 272.92 110.38Z\" fill=\"#375A64\"\/>\n<path id=\"Vector13326_20\" d=\"M270.41 112C269.719 111.756 269.05 111.455 268.41 111.1C267.2 110.49 265.56 109.63 263.77 108.62C261.98 107.61 260.38 106.62 259.24 105.94C258.608 105.579 258.006 105.168 257.44 104.71C258.111 104.986 258.757 105.321 259.37 105.71L263.95 108.29L268.53 110.86C269.19 111.183 269.819 111.564 270.41 112V112Z\" fill=\"#375A64\"\/>\n<path id=\"Vector13326_21\" d=\"M189.58 197.51H267.81\" stroke=\"#231F20\" stroke-miterlimit=\"10\"\/>\n<path id=\"Vector13326_22\" d=\"M189.58 207.66H267.81\" stroke=\"#231F20\" stroke-miterlimit=\"10\"\/>\n<path id=\"Vector13326_23\" d=\"M189.58 217.8H267.81\" stroke=\"#231F20\" stroke-miterlimit=\"10\"\/>\n<path id=\"Vector13326_24\" d=\"M189.58 227.95H267.81\" stroke=\"#231F20\" stroke-miterlimit=\"10\"\/>\n<path id=\"Vector13326_25\" d=\"M189.58 238.1H267.81\" stroke=\"#231F20\" stroke-miterlimit=\"10\"\/>\n<path id=\"Vector13326_26\" d=\"M189.58 248.24H267.81\" stroke=\"#231F20\" stroke-miterlimit=\"10\"\/>\n<path id=\"Vector13326_27\" d=\"M189.58 258.39H267.81\" stroke=\"#231F20\" stroke-miterlimit=\"10\"\/>\n<path id=\"Vector13326_28\" d=\"M172.83 157.12C204.006 157.12 229.28 131.846 229.28 100.67C229.28 69.4935 204.006 44.22 172.83 44.22C141.653 44.22 116.38 69.4935 116.38 100.67C116.38 131.846 141.653 157.12 172.83 157.12Z\" fill=\"#8AD5F2\"\/>\n<path id=\"Vector13326_29\" d=\"M172.83 139.02C194.01 139.02 211.18 121.85 211.18 100.67C211.18 79.4898 194.01 62.3199 172.83 62.3199C151.65 62.3199 134.48 79.4898 134.48 100.67C134.48 121.85 151.65 139.02 172.83 139.02Z\" fill=\"#FFB616\"\/>\n<path id=\"Vector13326_30\" d=\"M172.83 119.2C183.064 119.2 191.36 110.904 191.36 100.67C191.36 90.4362 183.064 82.14 172.83 82.14C162.596 82.14 154.3 90.4362 154.3 100.67C154.3 110.904 162.596 119.2 172.83 119.2Z\" fill=\"#EB6D79\"\/>\n<path id=\"Vector13326_31\" d=\"M233 59.65C213.56 73.21 192.48 86.65 173 100.2Z\" fill=\"#F5F5F5\"\/>\n<path id=\"Vector13326_32\" d=\"M173 100.2C172.9 100.05 186.23 90.84 202.79 79.65C219.35 68.46 232.85 59.5 232.95 59.65C233.05 59.8 219.76 69 203.2 80.2C186.64 91.4 173.14 100.35 173 100.2Z\" fill=\"#1A2E35\"\/>\n<path id=\"Vector13326_33\" d=\"M226.39 63.5699C226.39 63.3899 229.51 63.3499 233.39 63.4899C237.27 63.6299 240.33 63.8899 240.32 64.0799C240.31 64.2699 237.2 64.3 233.32 64.16C229.44 64.02 226.38 63.7599 226.39 63.5699Z\" fill=\"#1A2E35\"\/>\n<path id=\"Vector13326_34\" d=\"M228.75 54.45C228.93 54.45 228.62 56.61 228.06 59.2C227.5 61.79 226.91 63.86 226.73 63.82C226.55 63.78 226.85 61.65 227.41 59.06C227.97 56.47 228.57 54.41 228.75 54.45Z\" fill=\"#1A2E35\"\/>\n<path id=\"Vector13326_35\" d=\"M225.35 55.52C225.53 55.52 225.28 57.77 224.8 60.52C224.32 63.27 223.8 65.4 223.58 65.37C223.36 65.34 223.65 63.11 224.14 60.37C224.63 57.63 225.17 55.48 225.35 55.52Z\" fill=\"#1A2E35\"\/>\n<path id=\"Vector13326_36\" d=\"M233.33 67.5799C233.33 67.7599 231.13 67.3999 228.5 66.7799C225.87 66.1599 223.78 65.5199 223.83 65.3399C223.88 65.1599 226.03 65.5099 228.66 66.1299C231.29 66.7499 233.37 67.3999 233.33 67.5799Z\" fill=\"#1A2E35\"\/>\n<\/g>\n<\/g>\n<\/g>\n    <\/svg><\/div>\n<\/div>\n<h1><strong>Sul progetto<\/strong><\/h1>\n<div>\n<p>L&#8217;inclusione di studentesse e studenti migranti nei sistemi educativi europei \u00e8 una priorit\u00e0 per i responsabili delle politiche nell&#8217;Unione europea, poich\u00e9 ci sono ancora molte sfide al riguardo.<\/p>\n<p>Il progetto FEINAMC si concentra sulla diffusione e l&#8217;approfondimento di buone pratiche (un programma di mentoring e uno strumento di valutazione dell&#8217;apprendimento precedente) per favorire l&#8217;inclusione dei bambini migranti appena arrivati nei sistemi educativi formali in Austria, Cipro, Grecia, Italia e Spagna e nei paesi dell\u2019UE<\/p>\n<\/div>\n<p>\n    <a href=\"\/it\/about\">Scopri di pi\u00f9 ><\/a>\n<\/p>\n<h2>Obiettivi<\/h2>\n<h2>Risorse<\/h2>\n<h2>Metodologia<\/h2>\n<h1><strong>NEWS<\/strong><\/h1>\n<div>\n\n    <div id=\"wk-grid2e5\" class=\"uk-child-width-1-1 uk-child-width-1-2@s uk-child-width-1-2@m uk-child-width-1-3@l uk-child-width-1-3@xl uk-grid-match uk-text-left widget-home\" uk-height-match=\"target: > div > .uk-panel, > div > .uk-card; row: true\" uk-grid >\n\n    \n        <div >\n            <div class=\"uk-card uk-card-default uk-card-hover\">\n\n                                <a class=\"uk-position-cover uk-position-z-index\" href=\"https:\/\/feinamc.eu\/it\/2023\/03\/28\/feinamc-un-progetto-sulle-esigenze-educativo-formative-dei-nuovi-migranti\/\" title=\"Feinamc, un progetto sulle esigenze educativo-formative dei nuovi migranti\"><\/a>\n                \n                \n                \n                \n                                        <div class=\"uk-card-body\">\n                    \n                                                <div class=\"uk-margin uk-text-center\"><img decoding=\"async\" src=\"https:\/\/feinamc.eu\/wp-content\/uploads\/2021\/05\/news1.png\" alt=\"Feinamc, un progetto sulle esigenze educativo-formative dei nuovi migranti\"><\/div>\n                        \n                                                <h3 class=\"uk-panel uk-margin-remove-top\">\n\n                                                            <a class=\"uk-link-reset\" href=\"https:\/\/feinamc.eu\/it\/2023\/03\/28\/feinamc-un-progetto-sulle-esigenze-educativo-formative-dei-nuovi-migranti\/\">Feinamc, un progetto sulle esigenze educativo-formative dei nuovi migranti<\/a>\n                            \n                            \n                        <\/h3>\n                        \n                        \n                        \n                        \n                        \n                        \n                                        <\/div>\n                    \n                \n            <\/div>\n        <\/div>\n\n    \n        <div >\n            <div class=\"uk-card uk-card-default uk-card-hover\">\n\n                                <a class=\"uk-position-cover uk-position-z-index\" href=\"https:\/\/feinamc.eu\/it\/2023\/01\/02\/4th-newsletter\/\" title=\"Newsletter N\u00b04\"><\/a>\n                \n                \n                \n                \n                                        <div class=\"uk-card-body\">\n                    \n                                                <div class=\"uk-margin uk-text-center\"><img decoding=\"async\" src=\"https:\/\/feinamc.eu\/wp-content\/uploads\/2021\/05\/news1.png\" alt=\"Newsletter N\u00b04\"><\/div>\n                        \n                                                <h3 class=\"uk-panel uk-margin-remove-top\">\n\n                                                            <a class=\"uk-link-reset\" href=\"https:\/\/feinamc.eu\/it\/2023\/01\/02\/4th-newsletter\/\">Newsletter N\u00b04<\/a>\n                            \n                            \n                        <\/h3>\n                        \n                        \n                        \n                                                <div class=\"uk-margin\">In questi ultimi mesi, la partnership di FEINAMC ha l&#8217;opportunit\u00e0 di presentare i risultati del progetto a diverse autorit\u00e0 educative...<\/div>\n                        \n                        \n                        \n                                        <\/div>\n                    \n                \n            <\/div>\n        <\/div>\n\n    \n        <div >\n            <div class=\"uk-card uk-card-default uk-card-hover\">\n\n                                <a class=\"uk-position-cover uk-position-z-index\" href=\"https:\/\/feinamc.eu\/it\/2022\/09\/20\/3rd-newsletter\/\" title=\"Newsletter N\u00b03\"><\/a>\n                \n                \n                \n                \n                                        <div class=\"uk-card-body\">\n                    \n                                                <div class=\"uk-margin uk-text-center\"><img decoding=\"async\" src=\"https:\/\/feinamc.eu\/wp-content\/uploads\/2021\/05\/news1.png\" alt=\"Newsletter N\u00b03\"><\/div>\n                        \n                                                <h3 class=\"uk-panel uk-margin-remove-top\">\n\n                                                            <a class=\"uk-link-reset\" href=\"https:\/\/feinamc.eu\/it\/2022\/09\/20\/3rd-newsletter\/\">Newsletter N\u00b03<\/a>\n                            \n                            \n                        <\/h3>\n                        \n                        \n                        \n                                                <div class=\"uk-margin\">Nonostante tutte le sfide imposte dalla pandemia di Covid-19, siamo riuscit\u0437 a completare l&#8217;attuazione del programma di mentoring. L\u0437 student\u0437...<\/div>\n                        \n                        \n                        \n                                        <\/div>\n                    \n                \n            <\/div>\n        <\/div>\n\n    \n    <\/div>\n\n<\/div>\n<p>\n    <a href=\"\/it\/news\">Leggi tutte le news<\/a>\n<\/p>\n<h1><strong>Contattaci<\/strong><\/h1>\n<div>[contact-form-7 id=&#8221;153&#8243; title=&#8221;Contact form 1&#8243;]<\/div>\n<p><img decoding=\"async\" src=\"\/wp-content\/uploads\/2021\/05\/contact-home.png\" alt=\"\"><\/p>\n<p><!--more--><br \/>\n<!-- {\"type\":\"layout\",\"children\":[{\"type\":\"section\",\"props\":{\"style\":\"default\",\"width\":\"\",\"vertical_align\":\"\",\"title_position\":\"top-left\",\"title_rotation\":\"left\",\"title_breakpoint\":\"xl\",\"image_position\":\"center-center\",\"css\":\"@media only screen and (min-width:1024px){\\n    .el-section{position:relative;background-color:#8CD0C4;height:100vh;}}\\n\\n\\n@media only screen and (max-width:1023px){\\n.el-section{position:relative;background-color:#8CD0C4;height:70vh;}\\n}\",\"height\":\"full\",\"header_transparent\":\"light\",\"header_transparent_noplaceholder\":true,\"padding_remove_top\":true,\"padding_remove_bottom\":false,\"padding\":\"small\"},\"children\":[{\"type\":\"row\",\"children\":[{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"media_overlay_gradient\":\"\"},\"children\":[{\"type\":\"text\",\"props\":{\"margin\":\"default\",\"column_breakpoint\":\"m\",\"content\":\"<svg width=\\\"1622\\\" height=\\\"1010\\\" viewBox=\\\"0 0 1622 1010\\\" fill=\\\"none\\\" xmlns=\\\"http:\\\/\\\/www.w3.org\\\/2000\\\/svg\\\">\\n<g id=\\\"whiteBackground 1\\\" clip-path=\\\"url(#clip0)\\\">\\n<g id=\\\"Group\\\">\\n<g id=\\\"Layer 2\\\">\\n<g id=\\\"Layer 1\\\">\\n<g id=\\\"Group_2\\\" style=\\\"mix-blend-mode:multiply\\\" opacity=\\\"0.8\\\">\\n<g id=\\\"Vector\\\" style=\\\"mix-blend-mode:multiply\\\" opacity=\\\"0.15\\\">\\n<path d=\\\"M1621.12 936L64.5199 1009.4L18.4399 18.44H1573.44L1621.12 936Z\\\" fill=\\\"#332D2D\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<path id=\\\"Vector_2\\\" d=\\\"M1602.68 917.56L46.08 990.97L0 0H1555L1602.68 917.56Z\\\" fill=\\\"white\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<defs>\\n<clipPath id=\\\"clip0\\\">\\n<rect width=\\\"1621.12\\\" height=\\\"1009.4\\\" fill=\\\"white\\\"\\\/>\\n<\\\/clipPath>\\n<\\\/defs>\\n<\\\/svg>\\n\",\"text_align\":\"center\",\"css\":\"svg {height:95vh;}\\n\\n@media only screen and (max-width:1023px){.el-element{display:none;}}\"}},{\"type\":\"headline\",\"props\":{\"title_element\":\"h1\",\"css\":\"@media only screen and (min-width:1024px){\\n.el-element{    top: 27%;\\n    left: 50%;\\n    transform: translate(-50%,-50%);\\n    width: max-content;\\n    max-width: 100%;\\n    box-sizing: border-box;\\n    position:absolute;\\n    width:40%;\\n    text-align:center;\\n}\\n}\\n@media only screen and (max-width:1023px){.el-element{color:#fff; width:100%; font-size:20px;padding-left:5%;padding-right:5%;padding-top:20%;}}\",\"content\":\"<strong>Diffondere ed approfondire buone pratiche per promuovere l\\u2019inclusione educativa di migranti appena arrivati<\\\/strong>\",\"maxwidth\":\"medium\",\"class\":\"color-primary this-text\",\"title_style\":\"h2\"}},{\"type\":\"text\",\"props\":{\"margin\":\"default\",\"column_breakpoint\":\"m\",\"content\":\"<svg width=\\\"1207\\\" height=\\\"540\\\" viewBox=\\\"0 0 1207 540\\\" fill=\\\"none\\\" xmlns=\\\"http:\\\/\\\/www.w3.org\\\/2000\\\/svg\\\">\\n<g id=\\\"no-children 1\\\">\\n<g id=\\\"children 2\\\">\\n<g id=\\\"children 1\\\">\\n<g id=\\\"Group\\\">\\n<g id=\\\"Layer 2\\\">\\n<g id=\\\"Layer 1\\\">\\n<path id=\\\"Vector689132\\\" d=\\\"M1009 48.47C1009 50.93 998.49 52.93 985.53 52.93C972.57 52.93 962.05 50.93 962.05 48.47\\\" stroke=\\\"#EB6D79\\\" stroke-width=\\\"2\\\" stroke-miterlimit=\\\"10\\\"\\\/>\\n<path id=\\\"Vector689132 2\\\" d=\\\"M962.06 48.47C962.06 46 972.57 44 985.54 44C998.51 44 1009 46 1009 48.47\\\" stroke=\\\"#EB6D79\\\" stroke-width=\\\"2\\\" stroke-miterlimit=\\\"10\\\"\\\/>\\n<path id=\\\"Vector689132 3\\\" d=\\\"M1009 101.53C1009 104 998.49 106 985.53 106C972.57 106 962.05 104 962.05 101.53\\\" stroke=\\\"#EB6D79\\\" stroke-width=\\\"2\\\" stroke-miterlimit=\\\"10\\\"\\\/>\\n<path id=\\\"Vector689132 4\\\" d=\\\"M962.06 101.53C962.06 99.07 972.57 97.07 985.54 97.07C998.51 97.07 1009.01 99.07 1009.01 101.53\\\" stroke=\\\"#EB6D79\\\" stroke-width=\\\"2\\\" stroke-miterlimit=\\\"10\\\"\\\/>\\n<path id=\\\"Vector689132 5\\\" d=\\\"M962.06 48.73V101.53\\\" stroke=\\\"#EB6D79\\\" stroke-width=\\\"2\\\" stroke-miterlimit=\\\"10\\\"\\\/>\\n<path id=\\\"Vector689132 6\\\" d=\\\"M1009.01 48.73V101.53\\\" stroke=\\\"#EB6D79\\\" stroke-width=\\\"2\\\" stroke-miterlimit=\\\"10\\\"\\\/>\\n<path id=\\\"Vector689132 7\\\" d=\\\"M955.96 45.5601V104.58\\\" stroke=\\\"#EB6D79\\\" stroke-width=\\\"2\\\" stroke-miterlimit=\\\"10\\\"\\\/>\\n<path id=\\\"Vector689132 8\\\" d=\\\"M954.3 45.42H957.63\\\" stroke=\\\"#EB6D79\\\" stroke-width=\\\"2\\\" stroke-miterlimit=\\\"10\\\"\\\/>\\n<path id=\\\"Vector689132 9\\\" d=\\\"M954.3 104.58H957.63\\\" stroke=\\\"#EB6D79\\\" stroke-width=\\\"2\\\" stroke-miterlimit=\\\"10\\\"\\\/>\\n<path id=\\\"b-move\\\" d=\\\"M952.423 72.668C952.423 74.4626 952.01 75.9062 951.185 76.9989C950.36 78.0844 949.253 78.6271 947.864 78.6271C946.38 78.6271 945.233 78.1025 944.423 77.0532L944.325 78.41H942.48V61.7375H944.488V67.9571C945.298 66.9513 946.416 66.4484 947.842 66.4484C949.268 66.4484 950.386 66.9875 951.196 68.0657C952.014 69.1439 952.423 70.6201 952.423 72.4943V72.668ZM950.414 72.44C950.414 71.0724 950.15 70.0159 949.622 69.2705C949.094 68.5252 948.334 68.1525 947.343 68.1525C946.018 68.1525 945.067 68.7676 944.488 69.9978V75.0777C945.103 76.3079 946.062 76.9229 947.364 76.9229C948.327 76.9229 949.076 76.5503 949.611 75.8049C950.147 75.0596 950.414 73.938 950.414 72.44Z\\\" fill=\\\"#EB6D79\\\"\\\/>\\n<path id=\\\"Vector689132 156\\\" d=\\\"M608.62 205.4H397.43\\\" stroke=\\\"#EB6D79\\\" stroke-width=\\\"2\\\" stroke-miterlimit=\\\"10\\\"\\\/>\\n<path id=\\\"abnormal\\\" d=\\\"M567.42 221.4C567.42 221.4 567.22 180.09 556.08 179.48C544.94 178.87 547.78 231.72 532.59 234.76C517.4 237.8 538.08 138.18 503.59 138.18C469.1 138.18 499.22 251 467.31 251C435.4 251 452.11 176.28 434.39 174.46C416.67 172.64 433.89 235.46 414.14 235.46\\\" stroke=\\\"#EB6D79\\\" stroke-width=\\\"2\\\" stroke-miterlimit=\\\"10\\\"\\\/>\\n<path id=\\\"Vector689132 158\\\" d=\\\"M503.03 101.12V274.85\\\" stroke=\\\"#EB6D79\\\" stroke-width=\\\"2\\\" stroke-miterlimit=\\\"10\\\"\\\/>\\n<path id=\\\"x\\\" d=\\\"M391.089 197.155L395.454 189.97H399.383L392.944 199.701L399.583 209.65H395.691L391.143 202.284L386.596 209.65H382.686L389.325 199.701L382.886 189.97H386.778L391.089 197.155Z\\\" fill=\\\"#EB6D79\\\"\\\/>\\n<path id=\\\"y\\\" d=\\\"M503.305 85.0609L507.889 70.3101H511.49L503.578 93.0275C502.353 96.3014 500.407 97.9384 497.74 97.9384L497.103 97.8838L495.848 97.6473V94.9191L496.757 94.9918C497.897 94.9918 498.782 94.7614 499.413 94.3007C500.056 93.8399 500.583 92.9972 500.995 91.7725L501.741 89.7717L494.72 70.3101H498.394L503.305 85.0609Z\\\" fill=\\\"#EB6D79\\\"\\\/>\\n<g id=\\\"circlea\\\">\\n<path id=\\\"a\\\" d=\\\"M182.816 179.49C182.622 179.102 182.465 178.411 182.344 177.417C180.779 179.041 178.912 179.854 176.741 179.854C174.801 179.854 173.207 179.308 171.958 178.217C170.721 177.113 170.103 175.719 170.103 174.033C170.103 171.984 170.879 170.396 172.431 169.268C173.995 168.128 176.19 167.558 179.015 167.558H182.289V166.012C182.289 164.836 181.937 163.902 181.234 163.211C180.531 162.508 179.494 162.156 178.124 162.156C176.923 162.156 175.917 162.46 175.104 163.066C174.292 163.672 173.886 164.406 173.886 165.267H170.503C170.503 164.284 170.848 163.339 171.54 162.429C172.243 161.508 173.189 160.78 174.377 160.247C175.577 159.713 176.893 159.446 178.324 159.446C180.591 159.446 182.368 160.016 183.653 161.156C184.938 162.284 185.605 163.842 185.654 165.83V174.888C185.654 176.695 185.884 178.132 186.345 179.199V179.49H182.816ZM177.233 176.925C178.287 176.925 179.288 176.653 180.234 176.107C181.179 175.561 181.865 174.852 182.289 173.979V169.941H179.652C175.529 169.941 173.468 171.148 173.468 173.561C173.468 174.615 173.819 175.44 174.522 176.034C175.226 176.628 176.129 176.925 177.233 176.925Z\\\" fill=\\\"#5198BF\\\"\\\/>\\n<path id=\\\"Vector689132 501\\\" d=\\\"M159.84 216.47C140.84 198.8 136.45 170 149.9 147.83C155.204 138.827 163.106 131.639 172.57 127.21C187.29 120.56 205.64 121.36 220.74 130.49C235.84 139.62 247 157.24 247.74 175C248.019 182.464 246.591 189.893 243.563 196.721C240.536 203.549 235.989 209.596 230.27 214.4C219.27 223.59 204.9 227.73 190.32 228.06C185.22 228.18 169.32 225.21 160.25 216.88L159.84 216.47Z\\\" stroke=\\\"#5198BF\\\" stroke-width=\\\"2\\\" stroke-miterlimit=\\\"10\\\"\\\/>\\n<\\\/g>\\n<g id=\\\"circleb\\\">\\n<path id=\\\"Vector689132 502\\\" d=\\\"M215.47 233.79C200.19 219.57 196.77 196.29 207.77 178.56C211.996 171.543 218.217 165.944 225.64 162.48C231.795 159.794 238.506 158.629 245.205 159.085C251.905 159.541 258.396 161.604 264.13 165.1C276.19 172.39 285.13 186.47 285.73 200.66C285.947 206.627 284.798 212.564 282.372 218.02C279.946 223.475 276.306 228.305 271.73 232.14C262.96 239.48 251.46 242.79 239.81 243.05C235.73 243.15 223.05 240.77 215.81 234.12L215.47 233.79Z\\\" stroke=\\\"#5198BF\\\" stroke-width=\\\"2\\\" stroke-miterlimit=\\\"10\\\"\\\/>\\n<path id=\\\"b 2\\\" d=\\\"M269.667 204.028C269.667 207.035 268.976 209.455 267.594 211.285C266.211 213.104 264.356 214.014 262.028 214.014C259.542 214.014 257.62 213.135 256.262 211.376L256.099 213.65H253.006V185.712H256.371V196.134C257.729 194.449 259.603 193.606 261.992 193.606C264.38 193.606 266.254 194.51 267.612 196.316C268.982 198.123 269.667 200.597 269.667 203.737V204.028ZM266.302 203.646C266.302 201.355 265.86 199.584 264.974 198.335C264.089 197.086 262.816 196.462 261.155 196.462C258.936 196.462 257.341 197.493 256.371 199.554V208.066C257.402 210.127 259.009 211.158 261.191 211.158C262.804 211.158 264.059 210.534 264.956 209.285C265.854 208.036 266.302 206.156 266.302 203.646Z\\\" fill=\\\"#5198BF\\\"\\\/>\\n<\\\/g>\\n<g id=\\\"circlec\\\">\\n<path id=\\\"Vector689132 503\\\" d=\\\"M261.11 99.8C277.03 108.06 286.38 125.45 283.44 141.35C282.312 147.012 279.839 152.32 276.23 156.826C272.62 161.332 267.98 164.904 262.7 167.24C251.63 172.17 237.32 171.56 226.99 165.03C222.67 162.262 219.038 158.544 216.373 154.16C213.707 149.775 212.078 144.84 211.61 139.73C210.74 129.94 214.04 120.19 219.61 111.84C221.55 108.91 229.45 101.12 237.71 99.26C251.49 96.14 261.11 99.8 261.11 99.8Z\\\" stroke=\\\"#5198BF\\\" stroke-width=\\\"2\\\" stroke-miterlimit=\\\"10\\\"\\\/>\\n<path id=\\\"c\\\" d=\\\"M258.99 135.327C260.191 135.327 261.24 134.964 262.137 134.236C263.034 133.508 263.531 132.599 263.628 131.508H266.811C266.751 132.635 266.363 133.709 265.647 134.727C264.932 135.746 263.974 136.558 262.773 137.164C261.585 137.771 260.324 138.074 258.99 138.074C256.31 138.074 254.176 137.183 252.588 135.4C251.012 133.605 250.223 131.156 250.223 128.052V127.488C250.223 125.572 250.575 123.869 251.278 122.377C251.982 120.886 252.988 119.728 254.298 118.903C255.619 118.079 257.177 117.666 258.972 117.666C261.179 117.666 263.01 118.327 264.465 119.649C265.932 120.971 266.714 122.686 266.811 124.796H263.628C263.531 123.523 263.046 122.48 262.173 121.668C261.312 120.843 260.245 120.431 258.972 120.431C257.262 120.431 255.935 121.049 254.989 122.286C254.055 123.511 253.588 125.287 253.588 127.615V128.252C253.588 130.519 254.055 132.266 254.989 133.49C255.922 134.715 257.256 135.327 258.99 135.327Z\\\" fill=\\\"#5198BF\\\"\\\/>\\n<\\\/g>\\n<path id=\\\"Vector689132 915\\\" d=\\\"M202.56 283.63L200.07 368.08L177.73 358.66L202.56 283.66V283.63ZM205 270L175.29 359.78L202 371.06L205 270Z\\\" fill=\\\"#5198BF\\\"\\\/>\\n<path id=\\\"Vector689132 916\\\" d=\\\"M205.74 270L238.31 362.29L201.98 371.06\\\" stroke=\\\"#5198BF\\\" stroke-width=\\\"2\\\" stroke-miterlimit=\\\"10\\\"\\\/>\\n<path id=\\\"Vector689132 917\\\" d=\\\"M175.25 359.78L177.22 359.43\\\" stroke=\\\"#5198BF\\\" stroke-width=\\\"2\\\" stroke-miterlimit=\\\"10\\\"\\\/>\\n<path id=\\\"Vector689132 919\\\" d=\\\"M215.46 352.62L217.43 352.27L217.13 350.29\\\" stroke=\\\"#5198BF\\\" stroke-width=\\\"2\\\" stroke-miterlimit=\\\"10\\\"\\\/>\\n<path id=\\\"Vector689132 921\\\" d=\\\"M205.26 271.98L204.96 270\\\" stroke=\\\"#5198BF\\\" stroke-width=\\\"2\\\" stroke-miterlimit=\\\"10\\\"\\\/>\\n<g id=\\\"dotted\\\">\\n<path id=\\\"Vector689132 918\\\" d=\\\"M181.47 358.68L213.34 353\\\" stroke=\\\"#5198BF\\\" stroke-width=\\\"2\\\" stroke-miterlimit=\\\"10\\\" stroke-dasharray=\\\"4.32 4.32\\\"\\\/>\\n<path id=\\\"Vector689132 920\\\" d=\\\"M216.51 346.17L205.57 274.04\\\" stroke=\\\"#5198BF\\\" stroke-width=\\\"2\\\" stroke-miterlimit=\\\"10\\\" stroke-dasharray=\\\"4.17 4.17\\\"\\\/>\\n<path id=\\\"Vector689132 922\\\" d=\\\"M238.31 362.29L217.43 352.27\\\" stroke=\\\"#5198BF\\\" stroke-width=\\\"2\\\" stroke-miterlimit=\\\"10\\\" stroke-dasharray=\\\"4 4\\\"\\\/>\\n<\\\/g>\\n<path id=\\\"poseid\\\" d=\\\"M563.42 100.22C563.42 100.22 571.58 103.31 571.33 86.81C571.21 78.93 571.21 71.11 571.23 65.09C571.23 57.09 579.86 51.77 586.76 55.72C587.92 56.3215 588.891 57.2321 589.565 58.351C590.239 59.47 590.59 60.7537 590.58 62.06C590.83 73.06 577.58 71.56 577.58 71.56C577.58 71.56 592.58 71.31 592.58 83.31C592.58 95.31 574.75 94.64 574.75 89.22\\\" stroke=\\\"#EB6D79\\\" stroke-width=\\\"2\\\" stroke-miterlimit=\\\"10\\\"\\\/>\\n<path id=\\\"poseid\\\" d=\\\"M1025.63 6.33002C1025.63 6.33002 1031.63 2.67002 1032.63 8.67002C1033.63 14.67 1025.63 38 1037.63 38C1049.63 38 1038 9.33002 1041 6.33002C1044 3.33002 1049.67 6.67002 1049.67 6.67002\\\" stroke=\\\"#EB6D79\\\" stroke-width=\\\"2\\\" stroke-miterlimit=\\\"10\\\"\\\/>\\n<path id=\\\"poseid\\\" d=\\\"M1036.96 0V51\\\" stroke=\\\"#EB6D79\\\" stroke-width=\\\"2\\\" stroke-miterlimit=\\\"10\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<\\\/svg>\\n\",\"text_align\":\"center\",\"class\":\"uk-position-bottom-center this-element\",\"css\":\"@media only screen and (max-width:1023px) {.el-element{display:none;}}\"}}]}]},{\"type\":\"row\",\"props\":{\"layout\":\"1-5,1-5,1-5,1-5,1-5|1-2,1-2,1-3,1-3,1-3\",\"class\":\"this-col\"},\"children\":[{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"media_overlay_gradient\":\"\",\"width_medium\":\"1-5\",\"width_small\":\"1-2\"},\"children\":[{\"type\":\"image\",\"props\":{\"margin\":\"default\",\"image_svg_color\":\"emphasis\",\"image\":\"wp-content\\\/uploads\\\/2021\\\/05\\\/boy11.svg\",\"class\":\"uk-position-bottom\",\"id\":\"boy1\",\"css\":\"@media only screen and (max-width:1023px) {.el-element{display:none;}}\"}}]},{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"media_overlay_gradient\":\"\",\"width_medium\":\"1-5\",\"width_small\":\"1-2\"},\"children\":[{\"type\":\"text\",\"props\":{\"margin\":\"default\",\"column_breakpoint\":\"m\",\"content\":\"<img src=\\\"\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/girl-img.svg\\\">\",\"id\":\"girl2\",\"class\":\"uk-position-bottom\",\"css\":\"@media only screen and (max-width:1023px) {.el-element{display:none;}}\"}}]},{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"media_overlay_gradient\":\"\",\"width_medium\":\"1-5\",\"width_small\":\"1-3\"},\"children\":[{\"type\":\"image\",\"props\":{\"margin\":\"default\",\"image_svg_color\":\"emphasis\",\"image\":\"wp-content\\\/uploads\\\/2021\\\/05\\\/girl11.svg\",\"class\":\"uk-position-bottom\",\"id\":\"girl1\",\"css\":\"@media only screen and (max-width:1023px) {.el-element{display:none;}}\"}}]},{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"media_overlay_gradient\":\"\",\"width_medium\":\"1-5\",\"width_small\":\"1-3\"},\"children\":[{\"type\":\"text\",\"props\":{\"margin\":\"default\",\"column_breakpoint\":\"m\",\"content\":\"<svg width=\\\"372\\\" height=\\\"409\\\" viewBox=\\\"0 0 372 409\\\" fill=\\\"none\\\" xmlns=\\\"http:\\\/\\\/www.w3.org\\\/2000\\\/svg\\\">\\n<g id=\\\"standing-boy 1\\\">\\n<g id=\\\"Standingboy 1\\\">\\n<g id=\\\"Group\\\">\\n<g id=\\\"Layer 2\\\">\\n<g id=\\\"Layer 1\\\">\\n<path id=\\\"Vector5656231\\\" d=\\\"M305.26 356.95H307.89V349.13H305.26V356.95Z\\\" fill=\\\"#AB805B\\\"\\\/>\\n<path id=\\\"Vector5656231 2\\\" d=\\\"M285.23 361.45L306.57 356.42L327.9 361.45V363.39H285.23V361.45Z\\\" fill=\\\"#AB805B\\\"\\\/>\\n<path id=\\\"Vector5656231 3\\\" d=\\\"M327.74 361.41L327.9 361.45V363.39H285.23V361.45L285.4 361.41H327.74Z\\\" fill=\\\"#FFB640\\\"\\\/>\\n<path id=\\\"Vector5656231 4\\\" d=\\\"M263.47 270.11L265.47 272.25C260.313 279.876 257.405 288.799 257.08 298C256.19 325.47 278.75 347.74 307.46 347.74C315.281 347.742 323.011 346.068 330.13 342.83L332.13 344.97C321.879 350.905 309.908 353.162 298.199 351.367C286.491 349.573 275.746 343.835 267.742 335.102C259.739 326.37 254.956 315.166 254.187 303.346C253.417 291.525 256.706 279.797 263.51 270.1L263.47 270.11Z\\\" fill=\\\"#AB805B\\\"\\\/>\\n<g id=\\\"worldrota\\\">\\n<path id=\\\"Vector5656231 5\\\" d=\\\"M307.03 345.54C333.413 345.54 354.8 324.153 354.8 297.77C354.8 271.387 333.413 250 307.03 250C280.647 250 259.26 271.387 259.26 297.77C259.26 324.153 280.647 345.54 307.03 345.54Z\\\" fill=\\\"#47AAD1\\\"\\\/>\\n<path id=\\\"Vector5656231 6\\\" d=\\\"M295.88 340.06C295.602 340.012 295.338 339.904 295.107 339.744C294.875 339.583 294.682 339.373 294.54 339.13C294.186 338.239 294.123 337.259 294.36 336.33C294.428 335.927 294.458 335.519 294.45 335.11C294.293 334.233 294.007 333.383 293.6 332.59C292.973 330.962 291.919 329.532 290.55 328.45C289.857 328.033 289.119 327.698 288.35 327.45L287.43 327.11C285.48 326.352 283.686 325.24 282.14 323.83C281.757 323.521 281.478 323.102 281.34 322.63C281.251 322.177 281.279 321.709 281.42 321.27C282.136 318.449 282.046 315.483 281.16 312.71C281.036 312.421 280.973 312.11 280.973 311.795C280.973 311.48 281.036 311.169 281.16 310.88C281.245 310.727 281.349 310.586 281.47 310.46C281.431 310.397 281.38 310.343 281.32 310.3C280.97 310.055 280.693 309.721 280.517 309.332C280.341 308.943 280.273 308.514 280.32 308.09C280.454 307.565 280.778 307.109 281.23 306.81C282.109 306.196 283.064 305.699 284.07 305.33C284.655 305.101 285.226 304.838 285.78 304.54C286.283 304.249 286.77 303.932 287.24 303.59C287.74 303.24 288.24 302.88 288.77 302.59C289.83 302.02 290.942 301.551 292.09 301.19L295.17 300.11C296.188 299.712 297.248 299.433 298.33 299.28C300.175 299.179 302.023 299.437 303.77 300.04C304.497 300.205 305.194 300.478 305.84 300.85C306.08 301 306.31 301.18 306.54 301.35C306.77 301.52 306.87 301.61 307.05 301.73C307.733 302.085 308.502 302.244 309.27 302.19L310.35 302.08V302.13H310.6L310.73 304.13H310.42C309.945 304.2 309.508 304.429 309.18 304.78C308.984 304.993 308.803 305.221 308.64 305.46L307.95 306.46C308.67 308.06 309.17 309.85 308.3 311.46C307.899 312.135 307.356 312.714 306.71 313.16C306.333 313.415 305.996 313.725 305.71 314.08C305.575 314.286 305.451 314.5 305.34 314.72C305.057 315.424 304.56 316.022 303.92 316.43L303.59 316.59C303.676 316.791 303.794 316.977 303.94 317.14L305.58 319.02L303.3 318.84C303.22 318.97 303.12 319.17 303.05 319.31C302.923 319.617 302.762 319.909 302.57 320.18C302.371 320.448 302.139 320.69 301.88 320.9C301.776 320.978 301.679 321.065 301.59 321.16C301.268 321.569 301.049 322.049 300.95 322.56C300.51 324.93 300.51 327.36 300.95 329.73L301.1 330.95C301.296 332.346 301.296 333.764 301.1 335.16C300.899 336.714 300.13 338.139 298.94 339.16C298.083 339.814 297.016 340.134 295.94 340.06H295.88ZM301.94 315.21C302.208 314.953 302.529 314.759 302.88 314.64C303.139 314.398 303.341 314.1 303.47 313.77C303.62 313.474 303.787 313.187 303.97 312.91C304.363 312.393 304.832 311.938 305.36 311.56C305.781 311.275 306.145 310.911 306.43 310.49C306.96 309.49 306.43 308.05 305.79 306.78L305.52 306.23L306.95 304.23L307.15 303.95C306.717 303.827 306.303 303.645 305.92 303.41C305.68 303.26 305.45 303.08 305.23 302.91C305.01 302.74 304.9 302.65 304.72 302.53C304.241 302.272 303.73 302.08 303.2 301.96C301.713 301.445 300.143 301.211 298.57 301.27C297.64 301.419 296.728 301.668 295.85 302.01L292.76 303.09C291.724 303.411 290.72 303.826 289.76 304.33C289.29 304.61 288.84 304.93 288.39 305.24C287.864 305.628 287.317 305.985 286.75 306.31C286.128 306.645 285.487 306.942 284.83 307.2C283.986 307.511 283.183 307.924 282.44 308.43L282.36 308.49C282.42 308.54 282.5 308.63 282.64 308.75C283.03 309.017 283.32 309.408 283.461 309.86C283.602 310.312 283.588 310.798 283.42 311.24C283.332 311.433 283.194 311.598 283.02 311.72C283.042 311.846 283.075 311.97 283.12 312.09C284.123 315.232 284.23 318.591 283.43 321.79C283.43 321.91 283.35 322.09 283.34 322.11C283.395 322.178 283.455 322.242 283.52 322.3C284.875 323.531 286.444 324.504 288.15 325.17L289.01 325.49C289.939 325.779 290.83 326.182 291.66 326.69C293.366 327.975 294.684 329.705 295.47 331.69C295.953 332.673 296.29 333.72 296.47 334.8C296.512 335.391 296.481 335.986 296.38 336.57C296.32 337.05 296.22 337.85 296.19 337.96C296.706 337.966 297.208 337.801 297.62 337.49C298.396 336.781 298.89 335.815 299.01 334.77C299.181 333.563 299.181 332.337 299.01 331.13L298.86 329.94C298.365 327.316 298.365 324.624 298.86 322C299.032 321.15 299.425 320.36 300 319.71C300.139 319.566 300.286 319.429 300.44 319.3C300.574 319.199 300.695 319.081 300.8 318.95C300.92 318.771 301.02 318.58 301.1 318.38C301.254 318.048 301.442 317.733 301.66 317.44C301.478 317.083 301.407 316.68 301.457 316.282C301.507 315.884 301.675 315.511 301.94 315.21Z\\\" fill=\\\"#4880AA\\\"\\\/>\\n<path id=\\\"Vector5656231 7\\\" d=\\\"M308.25 303.42V303.16C308.255 302.945 308.176 302.737 308.03 302.58C307.96 302.51 307.89 302.46 307.83 302.47H305.94L310.14 296.12L310.94 296.48C311.18 296.57 311.73 296.57 312.94 295.31C313.191 295.099 313.39 294.832 313.52 294.53C313.536 294.449 313.532 294.364 313.51 294.285C313.487 294.205 313.446 294.131 313.39 294.07C313.186 293.828 312.895 293.674 312.58 293.64C312.04 293.664 311.507 293.772 311 293.96C310.573 294.098 310.139 294.211 309.7 294.3L306.33 294.89L308.77 292.58C308.841 292.462 308.883 292.329 308.891 292.191C308.9 292.054 308.876 291.916 308.82 291.79C308.614 291.367 308.308 291 307.93 290.72C307.193 290.093 306.396 289.54 305.55 289.07C305.025 288.837 304.61 288.411 304.39 287.88C304.297 287.555 304.26 287.217 304.28 286.88C304.28 286.64 303.93 286.44 303.64 286.37C303.383 286.316 303.122 286.283 302.86 286.27C302.399 286.248 301.943 286.171 301.5 286.04C300.222 285.506 299.138 284.596 298.39 283.43L296.53 281.03C296.241 280.687 296.076 280.258 296.06 279.81C296.095 279.36 296.291 278.938 296.61 278.62L299.61 275.17C301.46 273.07 303.32 271.17 305.84 270.77C306.771 270.633 307.722 270.722 308.611 271.03C309.501 271.338 310.303 271.856 310.95 272.54L311.25 272.86L311.08 275.49C311.388 275.646 311.725 275.735 312.07 275.751C312.415 275.766 312.759 275.708 313.08 275.58C313.21 275.483 313.319 275.36 313.4 275.219C313.481 275.078 313.532 274.922 313.55 274.76C313.577 274.626 313.552 274.486 313.48 274.37L310.39 271.25L314.12 272.62C314.038 272.336 313.906 272.068 313.73 271.83L313.47 271.4C313.202 270.994 313.054 270.52 313.043 270.034C313.032 269.547 313.16 269.067 313.41 268.65L313.75 268.2L314.32 268.26C316.508 268.42 318.673 268.808 320.78 269.42C321.801 269.777 322.802 270.187 323.78 270.65C325.78 271.54 327.67 272.39 329.62 272.26H330.28C331.53 272.14 333.2 271.98 334.28 273.13C337.42 273.53 340.505 274.278 343.48 275.36L343.78 275.47L343.96 275.72C345.844 278.21 347.459 280.891 348.78 283.72L349.18 284.59L348.35 285L347.75 285.31C347.446 285.54 347.109 285.722 346.75 285.85C346.005 286.073 345.207 286.045 344.48 285.77C343.444 285.434 342.46 284.953 341.56 284.34L341.25 284.12C340.61 283.67 339.94 283.2 339.5 283.33C339.174 283.471 338.878 283.675 338.63 283.93L338.37 284.16C337.734 284.669 337.066 285.137 336.37 285.56C335.215 286.152 334.226 287.021 333.49 288.09C333.38 288.29 333.29 288.49 333.2 288.7C333.11 288.91 332.97 289.19 332.84 289.42C332.47 290.051 332.031 290.638 331.53 291.17L326.1 297.43C325.492 298.241 324.701 298.895 323.79 299.34C323.647 299.399 323.5 299.449 323.35 299.49C323.185 299.534 323.026 299.601 322.88 299.69C322.749 299.856 322.644 300.042 322.57 300.24C322.441 300.599 322.259 300.936 322.03 301.24C321.03 302.46 319.43 302.24 318.28 302.07C316.345 301.805 314.374 302.061 312.57 302.81C311.886 303.46 311.08 303.97 310.2 304.31C309.948 304.405 309.691 304.485 309.43 304.55L308 305L308.25 303.42ZM342.49 282.42L342.78 282.62C343.502 283.118 344.294 283.505 345.13 283.77C345.444 283.909 345.793 283.947 346.13 283.88C346.308 283.801 346.476 283.7 346.63 283.58C345.501 281.285 344.162 279.099 342.63 277.05C339.765 276.026 336.792 275.331 333.77 274.98L333.29 274.93L333.01 274.53C332.66 274.01 331.83 274.05 330.59 274.17L329.87 274.23C327.41 274.39 325.18 273.39 323.03 272.44C322.111 272.003 321.17 271.616 320.21 271.28C318.583 270.771 316.907 270.436 315.21 270.28C315.21 270.33 315.26 270.39 315.3 270.45L315.51 270.79C315.848 271.273 316.08 271.821 316.19 272.4C316.23 272.722 316.198 273.049 316.096 273.357C315.994 273.665 315.825 273.946 315.6 274.18C315.635 274.449 315.635 274.721 315.6 274.99C315.55 275.446 315.398 275.884 315.155 276.274C314.913 276.663 314.587 276.993 314.2 277.24C313.605 277.53 312.952 277.681 312.29 277.681C311.628 277.681 310.975 277.53 310.38 277.24C309.907 277.091 309.509 276.765 309.27 276.33C309.123 275.997 309.064 275.632 309.1 275.27L309.2 273.5C308.79 273.152 308.31 272.895 307.793 272.747C307.275 272.599 306.732 272.562 306.2 272.64C304.35 272.93 302.77 274.58 301.2 276.4L298.2 279.83L300.02 282.18C300.507 282.974 301.198 283.623 302.02 284.06C302.319 284.131 302.623 284.178 302.93 284.2C303.294 284.219 303.655 284.269 304.01 284.35C304.581 284.455 305.105 284.734 305.509 285.15C305.914 285.566 306.18 286.097 306.27 286.67C306.301 286.815 306.301 286.965 306.27 287.11L306.52 287.26C307.492 287.799 308.407 288.435 309.25 289.16C309.892 289.658 310.401 290.307 310.73 291.05C310.822 291.291 310.883 291.543 310.91 291.8C311.458 291.636 312.028 291.558 312.6 291.57C313.064 291.598 313.518 291.723 313.931 291.937C314.344 292.15 314.708 292.448 315 292.81C315.246 293.108 315.421 293.459 315.509 293.835C315.598 294.212 315.598 294.603 315.51 294.98C315.312 295.629 314.938 296.21 314.43 296.66C313.87 297.22 312.54 298.57 310.98 298.47L309.3 301.02C309.358 301.065 309.412 301.115 309.46 301.17C309.696 301.408 309.889 301.686 310.03 301.99C310.506 301.736 310.944 301.416 311.33 301.04L311.64 300.82C313.866 299.863 316.313 299.541 318.71 299.89C319.6 300.01 320.24 300.07 320.52 299.74C320.63 299.578 320.721 299.403 320.79 299.22C320.96 298.774 321.223 298.368 321.56 298.03C321.909 297.737 322.319 297.525 322.76 297.41L323.06 297.31C323.674 296.961 324.209 296.487 324.63 295.92L330.08 289.66C330.484 289.228 330.843 288.756 331.15 288.25C331.25 288.06 331.35 287.86 331.44 287.65C331.53 287.44 331.67 287.16 331.8 286.92C332.674 285.562 333.888 284.456 335.32 283.71C335.943 283.333 336.541 282.915 337.11 282.46L337.34 282.26C337.797 281.798 338.36 281.455 338.98 281.26C339.358 281.171 339.752 281.171 340.13 281.26C340.992 281.454 341.799 281.84 342.49 282.39V282.42Z\\\" fill=\\\"#4880AA\\\"\\\/>\\n<path id=\\\"Vector5656231 8\\\" d=\\\"M289.19 270.15C288.8 269.82 288.42 269.49 288.03 269.21C287.64 268.93 287.17 268.63 286.73 268.35C285.425 267.679 284.305 266.697 283.47 265.49L282.99 264.7L283.75 264.19C287.743 261.516 292.158 259.535 296.81 258.33L297.07 258.26L297.33 258.33C299.66 258.91 311.39 261.86 314.06 263.26L316.27 264.42L313.9 265.06C312.664 265.401 311.408 265.665 310.14 265.85C309.55 265.94 308.96 266.01 308.36 266.08C306.535 266.194 304.737 266.585 303.03 267.24L302.77 267.36C302.228 267.645 301.638 267.828 301.03 267.9C300.784 267.92 300.536 267.92 300.29 267.9C300.111 267.868 299.929 267.868 299.75 267.9C299.43 268 299.2 268.56 298.97 269.11C298.849 269.41 298.712 269.704 298.56 269.99C298.173 270.622 297.655 271.164 297.041 271.58C296.427 271.996 295.731 272.275 295 272.4C294.415 272.55 293.806 272.577 293.21 272.48C291.683 272.083 290.293 271.278 289.19 270.15ZM309.78 263.9H310.11C306.87 262.9 301.83 261.51 297.11 260.35C293.107 261.415 289.29 263.084 285.79 265.3C286.403 265.85 287.074 266.333 287.79 266.74C288.28 267.05 288.79 267.35 289.22 267.69C289.65 268.03 290.07 268.37 290.5 268.69C292.06 270.02 293.1 270.81 294.38 270.49C294.854 270.427 295.308 270.262 295.712 270.006C296.116 269.751 296.46 269.411 296.72 269.01C296.842 268.791 296.949 268.564 297.04 268.33C297.18 267.822 297.432 267.353 297.778 266.956C298.125 266.56 298.556 266.247 299.04 266.04C299.477 265.909 299.937 265.871 300.39 265.93C300.906 265.995 301.428 265.871 301.86 265.58L302.15 265.45C304.042 264.713 306.034 264.267 308.06 264.13C308.64 264.07 309.21 264 309.79 263.91L309.78 263.9Z\\\" fill=\\\"#4880AA\\\"\\\/>\\n<path id=\\\"Vector5656231 9\\\" d=\\\"M309.49 302.83H310.18C309.746 302.833 309.317 302.924 308.919 303.095C308.52 303.267 308.16 303.517 307.86 303.83C307.621 304.091 307.401 304.369 307.2 304.66C306.84 305.16 306.48 305.66 306.11 306.17C306.84 307.68 307.58 309.54 306.77 311.03C306.16 312.17 304.86 312.63 304.13 313.68C303.62 314.4 303.36 315.42 302.62 315.82C302.359 315.911 302.115 316.047 301.9 316.22C301.39 316.75 301.9 317.66 302.35 318.22C301.56 318.16 301.35 319.4 300.84 320.09C300.547 320.413 300.233 320.717 299.9 321C299.427 321.556 299.104 322.224 298.96 322.94C298.21 325.94 298.78 329.08 299.14 332.15C299.33 333.52 299.33 334.91 299.14 336.28C298.966 337.645 298.301 338.899 297.27 339.81C296.63 340.32 294.79 341.04 294.27 340.08C293.82 339.32 294.45 337.23 294.32 336.26C294.135 335.217 293.798 334.206 293.32 333.26C292.58 331.357 291.331 329.693 289.71 328.45C288.602 327.833 287.432 327.334 286.22 326.96C284.302 326.203 282.537 325.105 281.01 323.72C280.775 323.538 280.597 323.291 280.5 323.01C280.456 322.704 280.487 322.392 280.59 322.1C281.38 318.94 281.273 315.622 280.28 312.52C280.119 312.175 280.094 311.782 280.21 311.42C280.33 311.2 280.54 311.06 280.65 310.84C280.89 310.36 280.49 309.84 280.11 309.5C279.73 309.16 279.28 308.74 279.39 308.21C279.483 307.916 279.678 307.664 279.94 307.5C281.36 306.44 283.08 306.04 284.6 305.19C285.69 304.58 286.67 303.75 287.75 303.12C288.807 302.554 289.916 302.089 291.06 301.73L294.29 300.6C295.287 300.213 296.323 299.935 297.38 299.77C299.176 299.684 300.971 299.942 302.67 300.53C303.332 300.682 303.968 300.928 304.56 301.26C305 301.54 305.39 301.91 305.83 302.18C306.726 302.678 307.747 302.907 308.77 302.84C308.775 302.903 308.775 302.967 308.77 303.03C309.015 302.985 309.256 302.918 309.49 302.83Z\\\" fill=\\\"#C7D14A\\\"\\\/>\\n<path id=\\\"Vector5656231 10\\\" d=\\\"M347.91 283.49C347.343 283.639 346.743 283.6 346.2 283.38C345.213 283.073 344.279 282.618 343.43 282.03C342.48 281.38 341.43 280.52 340.36 280.81C339.764 281.052 339.226 281.416 338.78 281.88C337 283.39 334.62 284.18 333.44 286.3C333.18 286.75 333 287.24 332.75 287.7C332.391 288.295 331.972 288.851 331.5 289.36L325.78 295.93C325.253 296.651 324.569 297.242 323.78 297.66C323.329 297.771 322.901 297.964 322.52 298.23C322.04 298.66 321.93 299.42 321.52 299.92C320.82 300.78 319.59 300.58 318.52 300.43C316.227 300.113 313.891 300.434 311.77 301.36C311.124 302.003 310.351 302.504 309.5 302.83C309.277 302.923 309.046 302.996 308.81 303.05C308.815 302.987 308.815 302.923 308.81 302.86C308.836 302.415 308.693 301.977 308.409 301.634C308.125 301.29 307.722 301.067 307.28 301.01C308.23 299.57 309.18 298.14 310.12 296.7C311.29 297.23 312.53 296.2 313.47 295.26C313.868 294.914 314.168 294.469 314.34 293.97C314.63 292.79 313.43 291.75 312.34 291.7C311.228 291.82 310.132 292.058 309.07 292.41C309.309 292.142 309.464 291.81 309.517 291.455C309.571 291.099 309.52 290.737 309.37 290.41C309.093 289.797 308.667 289.264 308.13 288.86C307.301 288.145 306.399 287.518 305.44 286.99C305.134 286.859 304.883 286.626 304.73 286.33C304.68 286.066 304.66 285.798 304.67 285.53C304.602 285.155 304.42 284.81 304.147 284.543C303.875 284.276 303.527 284.1 303.15 284.04C302.43 283.87 301.68 283.93 300.97 283.71C299.851 283.212 298.907 282.39 298.26 281.35L296.26 278.83C296.103 278.664 296.008 278.448 295.99 278.22C296.019 277.982 296.132 277.762 296.31 277.6L299.49 273.98C301.17 272.07 303.03 270.05 305.41 269.69C306.212 269.575 307.031 269.654 307.796 269.92C308.562 270.186 309.252 270.632 309.81 271.22C309.81 272 309.72 272.78 309.68 273.57C309.653 273.769 309.677 273.973 309.75 274.16C309.877 274.37 310.082 274.521 310.32 274.58C310.8 274.807 311.324 274.925 311.855 274.925C312.386 274.925 312.91 274.807 313.39 274.58C313.628 274.439 313.834 274.25 313.995 274.025C314.157 273.8 314.27 273.545 314.327 273.274C314.384 273.003 314.385 272.724 314.329 272.453C314.272 272.182 314.16 271.925 314 271.7C314.55 271.91 315.06 271.14 315 270.5C314.835 269.893 314.557 269.323 314.18 268.82C313.998 268.559 313.891 268.254 313.87 267.937C313.849 267.62 313.915 267.303 314.06 267.02C316.282 267.178 318.481 267.57 320.62 268.19C323.87 269.27 326.95 271.45 330.34 271.24C331.86 271.14 333.72 270.7 334.63 272.03C338 272.42 341.313 273.205 344.5 274.37C346.432 276.914 348.088 279.656 349.44 282.55C349.276 282.613 349.115 282.687 348.96 282.77C348.637 283.047 348.285 283.288 347.91 283.49Z\\\" fill=\\\"#C7D14A\\\"\\\/>\\n<path id=\\\"Vector5656231 11\\\" d=\\\"M310.2 263.82C307.6 264.2 304.9 264.28 302.45 265.36C301.907 265.657 301.319 265.863 300.71 265.97C300.172 265.9 299.628 265.9 299.09 265.97C298.03 266.33 297.79 267.72 297.27 268.63C296.925 269.167 296.469 269.623 295.933 269.968C295.396 270.313 294.791 270.539 294.16 270.63C291.58 271.28 289.73 268.88 287.8 267.46C286.25 266.32 284.29 265.53 283.29 263.87C287.392 261.133 291.925 259.104 296.7 257.87C302.26 259.26 311.78 261.78 314.02 262.96C312.766 263.327 311.49 263.615 310.2 263.82Z\\\" fill=\\\"#C7D14A\\\"\\\/>\\n<\\\/g>\\n<g id=\\\"Vector5656231 12\\\" style=\\\"mix-blend-mode:multiply\\\" opacity=\\\"0.5\\\">\\n<g id=\\\"Vector\\\" style=\\\"mix-blend-mode:multiply\\\" opacity=\\\"0.5\\\">\\n<g id=\\\"Vector_2\\\" style=\\\"mix-blend-mode:multiply\\\" opacity=\\\"0.5\\\">\\n<path d=\\\"M299.8 339.4C309.186 339.409 318.367 336.652 326.196 331.473C334.024 326.294 340.153 318.924 343.817 310.282C347.481 301.64 348.517 292.11 346.796 282.883C345.075 273.656 340.673 265.14 334.14 258.4C339.6 262.201 344.207 267.1 347.664 272.784C351.121 278.467 353.353 284.811 354.216 291.407C355.08 298.004 354.556 304.708 352.678 311.09C350.801 317.472 347.611 323.392 343.313 328.47C339.015 333.548 333.703 337.672 327.719 340.578C321.734 343.485 315.209 345.109 308.561 345.347C301.912 345.585 295.287 344.432 289.11 341.962C282.933 339.491 277.34 335.757 272.69 331C280.663 336.49 290.12 339.421 299.8 339.4Z\\\" fill=\\\"#2E90B7\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 13\\\" style=\\\"mix-blend-mode:multiply\\\" opacity=\\\"0.5\\\">\\n<g id=\\\"Vector_2_2\\\" style=\\\"mix-blend-mode:multiply\\\" opacity=\\\"0.5\\\">\\n<g id=\\\"Vector_3\\\" style=\\\"mix-blend-mode:multiply\\\" opacity=\\\"0.5\\\">\\n<path d=\\\"M306.16 343.79C314.217 343.79 322.142 341.752 329.2 337.866C336.257 333.98 342.217 328.372 346.525 321.564C350.833 314.756 353.35 306.969 353.84 298.928C354.33 290.886 352.779 282.851 349.33 275.57C354.67 285.713 356.183 297.439 353.594 308.605C351.005 319.772 344.487 329.635 335.228 336.394C325.97 343.152 314.589 346.356 303.165 345.419C291.74 344.482 281.034 339.467 273 331.29L273.67 331.04C282.493 339.253 294.106 343.81 306.16 343.79Z\\\" fill=\\\"#2E90B7\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<path id=\\\"Vector5656231 14\\\" d=\\\"M307 250C316.166 249.989 325.139 252.629 332.84 257.6C322.077 251.229 309.245 249.333 297.1 252.32C284.954 255.307 274.465 262.937 267.884 273.573C261.303 284.209 259.156 297.002 261.904 309.203C264.652 321.405 272.075 332.042 282.58 338.83C273.586 333.482 266.597 325.329 262.686 315.624C258.775 305.918 258.159 295.197 260.933 285.107C263.707 275.018 269.716 266.118 278.039 259.776C286.361 253.433 296.536 249.999 307 250Z\\\" fill=\\\"#77D1ED\\\"\\\/>\\n<path id=\\\"Vector5656231 15\\\" d=\\\"M339.71 363.79H319.25C314.66 363.79 314.66 373.63 319.25 373.63H339.71V363.79Z\\\" fill=\\\"#EAC5A2\\\"\\\/>\\n<path id=\\\"Vector5656231 16\\\" d=\\\"M336.16 365.68H320.66C317.18 365.68 317.18 371.97 320.66 371.97H336.16V365.68Z\\\" fill=\\\"#FFEBD4\\\"\\\/>\\n<path id=\\\"Vector5656231 17\\\" d=\\\"M320.8 372.55H336.31C339.79 372.55 337.91 365.03 334.43 365.03H318.92L320.8 372.55Z\\\" fill=\\\"#EAC5A2\\\"\\\/>\\n<path id=\\\"Vector5656231 18\\\" d=\\\"M320 373.31C315.4 373.31 315.4 364.24 320 364.24H341.15V362.82H317C311.89 362.82 311.89 374.59 317 374.59H341.1V373.31H320Z\\\" fill=\\\"#9B902C\\\"\\\/>\\n<path id=\\\"Vector5656231 19\\\" d=\\\"M317.45 362.9V362.82H257.65C253.15 362.82 253.15 374.57 257.65 374.57H317.45V374.5C313.67 373.65 313.67 363.77 317.45 362.9Z\\\" fill=\\\"#C4C439\\\"\\\/>\\n<path id=\\\"Vector5656231 20\\\" d=\\\"M315.4 372.62H255.06C255.252 373.168 255.599 373.649 256.058 374.004C256.518 374.359 257.071 374.573 257.65 374.62H317.45V374.55C316.983 374.408 316.555 374.16 316.199 373.825C315.843 373.49 315.57 373.078 315.4 372.62Z\\\" fill=\\\"#B5B133\\\"\\\/>\\n<path id=\\\"Vector5656231 21\\\" d=\\\"M329.75 375.27H318.51C312.78 375.27 312.78 389.43 318.51 389.43H329.75V375.27Z\\\" fill=\\\"#EAC5A2\\\"\\\/>\\n<path id=\\\"Vector5656231 22\\\" d=\\\"M332.93 377.35H321.69C315.96 377.35 316.4 387.98 322.12 387.98H333.36L332.93 377.35Z\\\" fill=\\\"#FFEBD4\\\"\\\/>\\n<path id=\\\"Vector5656231 23\\\" d=\\\"M324.18 388.63H335.43C341.15 388.63 338.55 376.7 332.82 376.7H321.58L324.18 388.63Z\\\" fill=\\\"#EAC5A2\\\"\\\/>\\n<path id=\\\"Vector5656231 24\\\" d=\\\"M318.71 383.46L326.56 383.97L336.2 383.46H318.71Z\\\" fill=\\\"#EAC5A2\\\"\\\/>\\n<path id=\\\"Vector5656231 25\\\" d=\\\"M319.39 389C313.67 389 313.67 375.94 319.39 375.94H333V373.94H315.71C309.35 373.94 309.35 390.88 315.71 390.88H333V389H319.39Z\\\" fill=\\\"#FF9945\\\"\\\/>\\n<path id=\\\"Vector5656231 26\\\" d=\\\"M316.26 374V373.89H241.72C236.12 373.89 236.12 390.79 241.72 390.79H316.27V390.69C310.84 390.7 310.84 374 316.26 374Z\\\" fill=\\\"#FFB255\\\"\\\/>\\n<path id=\\\"Vector5656231 27\\\" d=\\\"M302 373.88H241.68C236.08 373.88 236.08 390.78 241.68 390.78H265.29C269.82 382.75 284.29 375.75 302 373.88Z\\\" fill=\\\"#FFC05A\\\"\\\/>\\n<path id=\\\"Vector5656231 28\\\" d=\\\"M314.19 389.68H239.49C239.753 390.021 240.089 390.298 240.473 390.492C240.857 390.686 241.28 390.791 241.71 390.8H316.26V390.7C315.862 390.691 315.47 390.595 315.112 390.419C314.755 390.242 314.44 389.99 314.19 389.68Z\\\" fill=\\\"#FFB048\\\"\\\/>\\n<path id=\\\"Vector5656231 29\\\" d=\\\"M339.07 392.26H283.68C277.83 392.26 277.83 407.12 283.68 407.12H339.07V392.26Z\\\" fill=\\\"#EAC5A2\\\"\\\/>\\n<path id=\\\"Vector5656231 30\\\" d=\\\"M339.07 395.18H288C282.6 395.18 282.6 405.66 288 405.66H339.09L339.07 395.18Z\\\" fill=\\\"#FFEBD4\\\"\\\/>\\n<path id=\\\"Vector5656231 31\\\" d=\\\"M338.44 392.82H322.39L325.57 406.9H341.63L338.44 392.82Z\\\" fill=\\\"#EAC5A2\\\"\\\/>\\n<path id=\\\"Vector5656231 32\\\" d=\\\"M284.12 390.7H245.42C238.91 390.7 238.91 408.48 245.42 408.48H284.12C277.08 402.44 278 396.53 284.12 390.7Z\\\" fill=\\\"#EB6D79\\\"\\\/>\\n<path id=\\\"Vector5656231 33\\\" d=\\\"M282.59 407H242.59C242.918 407.438 243.341 407.796 243.828 408.046C244.315 408.295 244.853 408.43 245.4 408.44H284.1C283.553 407.987 283.05 407.507 282.59 407Z\\\" fill=\\\"#EA3F50\\\"\\\/>\\n<path id=\\\"Vector5656231 34\\\" d=\\\"M284.94 406.54C279.09 406.54 279.09 392.84 284.94 392.84H343.86V390.7H282.27C275.76 390.7 275.76 408.48 282.27 408.48H343.86V406.54H284.94Z\\\" fill=\\\"#B5535E\\\"\\\/>\\n<path id=\\\"Vector5656231 35\\\" d=\\\"M347.17 351.75H320.06L333.67 407.92H360.79L347.17 351.75Z\\\" fill=\\\"#AF37AF\\\"\\\/>\\n<path id=\\\"Vector5656231 36\\\" d=\\\"M346.27 352.31H319.16L332.77 408.48H359.88L360.76 407.92L346.27 352.31Z\\\" fill=\\\"#4988AB\\\"\\\/>\\n<path id=\\\"Vector5656231 37\\\" d=\\\"M347.9 351.39H320.79L334.4 407.56H358.93L366.86 403.49L347.9 351.39Z\\\" fill=\\\"#EAC5A2\\\"\\\/>\\n<path id=\\\"Vector5656231 38\\\" d=\\\"M354.96 348.13H327.84L340.96 404.29H367.69L368.77 403.66L354.96 348.13Z\\\" fill=\\\"#4988AB\\\"\\\/>\\n<path id=\\\"Vector5656231 39\\\" d=\\\"M329.09 347.77C325.09 348.53 322.17 349.6 320.17 351.94L333.8 408.31C336.016 406.023 338.928 404.536 342.08 404.08L342.56 400.97L329.09 347.77Z\\\" fill=\\\"#4988AB\\\"\\\/>\\n<path id=\\\"Vector5656231 40\\\" d=\\\"M328 347.49C324 348.25 321 349.77 319 352.11L332.63 408.48C335.006 405.912 338.175 404.215 341.63 403.66L341.43 401.14L328 347.49Z\\\" fill=\\\"#5198BF\\\"\\\/>\\n<path id=\\\"Vector5656231 41\\\" d=\\\"M355.16 347.49H328.04L341.65 403.66H368.77L355.16 347.49Z\\\" fill=\\\"#5198BF\\\"\\\/>\\n<path id=\\\"Vector5656231 42\\\" d=\\\"M355.16 347.49H328.04L354.1 349.48L368.77 403.66L355.16 347.49Z\\\" fill=\\\"#4988AB\\\"\\\/>\\n<g id=\\\"Group 2\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector5656231 43\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_3_2\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_4\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<path d=\\\"M367.73 402.77H342.12L342.07 402.55L329.25 349.16H354.86L354.91 349.38L367.73 402.77ZM342.58 402.19H367L354.4 349.74H330L342.58 402.19Z\\\" fill=\\\"#5B6E9B\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Group 3\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector5656231 44\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_4_2\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_5\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<path d=\\\"M323.28 363.22L321 353.93L321.09 353.82C321.713 353.005 322.501 352.33 323.402 351.839C324.303 351.348 325.297 351.052 326.32 350.97H326.57L329.04 360.97H328.72C326.868 361.153 325.103 361.845 323.62 362.97L323.28 363.22ZM321.64 354.07L323.64 362.2C325.047 361.251 326.656 360.644 328.34 360.43L326.15 351.57C324.375 351.775 322.754 352.674 321.64 354.07Z\\\" fill=\\\"#5B6E9B\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 45\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_5_2\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_6\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<path d=\\\"M333.11 403.47L329.11 387L329.2 386.89C329.875 386.113 330.721 385.503 331.672 385.109C332.623 384.715 333.653 384.548 334.68 384.62H334.94L338.88 400.53H338.56C336.12 400.81 334.56 401.53 333.5 402.94L333.11 403.47ZM329.72 387.15L333.39 402.15C334.669 400.889 336.358 400.13 338.15 400.01L334.47 385.17C333.582 385.133 332.696 385.291 331.875 385.633C331.054 385.975 330.319 386.493 329.72 387.15Z\\\" fill=\\\"#5B6E9B\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<path id=\\\"Vector5656231 46\\\" d=\\\"M309.46 389.27H243.25L243.16 389.17C241.16 386.67 241.16 378 243.16 375.52L243.25 375.41H309.42V375.98L309.23 376.06C308.67 376.3 308.08 378.41 308.05 381.99C308.05 385.77 308.64 388.39 309.24 388.65L309.41 388.73L309.46 389.27ZM243.53 388.7H308.53C307.53 387.11 307.53 382.56 307.53 381.98C307.53 380.8 307.64 377.32 308.53 375.98H243.53C241.76 378.38 241.75 386.29 243.53 388.7Z\\\" fill=\\\"#FFE3BB\\\"\\\/>\\n<path id=\\\"Vector5656231 47\\\" d=\\\"M291.59 401.47L303.38 401.97L317.84 401.47H291.59Z\\\" fill=\\\"#EAC5A2\\\"\\\/>\\n<path id=\\\"Vector5656231 48\\\" d=\\\"M301.93 397.35L313.72 397.85L328.18 397.35H301.93Z\\\" fill=\\\"#EAC5A2\\\"\\\/>\\n<g id=\\\"Group 4\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector5656231 49\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_6_2\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_7\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<path d=\\\"M277.68 407.83H246.82C243.75 407.83 242.35 403.56 242.35 399.59C242.35 395.62 243.75 391.35 246.82 391.35H277.82V391.93C275.82 392.24 274.82 396.58 274.97 400.6C275.09 404.45 276.16 407.12 277.62 407.26L277.68 407.83ZM246.82 391.93C244.27 391.93 242.93 395.78 242.93 399.59C242.93 403.4 244.27 407.26 246.82 407.26H276.41C275.12 406.06 274.56 403.26 274.47 400.62C274.35 397.07 275.08 393.35 276.66 391.93H246.82Z\\\" fill=\\\"#FFEBD4\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<path id=\\\"Vector5656231 50\\\" d=\\\"M279.06 365C292.36 365 303.99 364.13 310.37 362.82H257.65C257.241 362.828 256.839 362.934 256.479 363.129C256.119 363.324 255.811 363.602 255.58 363.94C261.92 364.61 270.11 365 279.06 365Z\\\" fill=\\\"#DBD749\\\"\\\/>\\n<g id=\\\"Group 5\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector5656231 51\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_7_2\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_8\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<path d=\\\"M336.88 367.56C336.88 367.73 336.96 367.8 337 367.96L337.23 368.8C337.23 368.92 337.23 369.05 337.31 369.16C337.39 369.27 337.31 369.28 337.31 369.34H338.54H339.09H339.47C339.53 369.34 339.54 369.34 339.56 369.45C339.58 369.56 339.56 369.59 339.56 369.67C339.56 369.75 339.56 369.76 339.46 369.76H339.35C339.137 369.747 338.923 369.747 338.71 369.76H337.2C337.164 369.766 337.128 369.758 337.098 369.737C337.068 369.717 337.047 369.685 337.04 369.65C337.04 369.65 337.04 369.58 337.04 369.54C337.04 369.5 337.04 369.54 337.04 369.47C337.04 369.4 337.04 369.38 336.92 369.07C336.8 368.76 336.64 368.07 336.52 367.61C336.4 367.15 336.26 366.43 336.18 366.14C336.1 365.85 335.97 365.32 335.89 365.06C335.81 364.8 336.13 364.91 336.31 364.91C336.49 364.91 336.96 364.91 337.31 364.91H338.31C338.44 364.91 338.44 365.03 338.46 365.1V365.18C338.46 365.25 338.51 365.34 338.46 365.34C338.41 365.34 338.38 365.34 338.27 365.34H336.7H336.44H336.31V365.53C336.31 365.64 336.31 365.76 336.39 365.87C336.47 365.98 336.51 366.25 336.55 366.41L336.62 366.7C336.637 366.758 336.657 366.814 336.68 366.87H337.07C337.17 366.87 337.28 366.87 337.46 366.87C337.64 366.87 337.85 366.87 337.92 366.87H338.22H338.63H338.75C338.773 366.872 338.795 366.882 338.811 366.899C338.828 366.915 338.838 366.937 338.84 366.96C338.84 366.96 338.89 367.16 338.89 367.21C338.89 367.26 338.89 367.29 338.83 367.29C338.77 367.29 338.23 367.21 338 367.21C337.77 367.21 337.51 367.21 337.28 367.21C337.167 367.225 337.053 367.225 336.94 367.21H336.78V367.33C336.84 367.4 336.86 367.48 336.88 367.56Z\\\" fill=\\\"#FFEBD4\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 52\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_8_2\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_9\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<path d=\\\"M340.61 364.83C340.56 364.62 340.74 364.63 340.86 364.63C341.068 364.627 341.275 364.61 341.48 364.58C341.64 364.58 341.67 364.68 341.71 364.9C341.75 365.12 341.89 365.64 342.06 366.31L342.47 367.91C342.63 368.51 343.05 370 342.97 369.68C342.97 369.77 342.97 369.8 342.91 369.8H342.74H342.3C342.14 369.8 342.07 369.72 341.95 369.54C341.83 369.36 341.56 368.91 341.29 368.54C341.16 368.37 340.91 368 340.68 367.68L340.28 367.1L340.35 367.37L340.47 367.86C340.56 368.18 340.87 369.35 340.94 369.54C340.946 369.57 340.946 369.6 340.94 369.63C340.94 369.73 340.94 369.73 340.86 369.73H340.41C340.3 369.73 340.27 369.73 340.21 369.47C340.15 369.21 339.87 368.26 339.63 367.4C339.48 366.8 339.3 366.01 339.17 365.49L339.03 365.01C339.007 364.958 338.987 364.904 338.97 364.85C338.92 364.65 338.97 364.62 339.07 364.63C339.179 364.656 339.291 364.656 339.4 364.63H339.52C339.59 364.63 339.63 364.63 339.8 364.63C339.97 364.63 340.26 365.02 340.43 365.24C340.51 365.358 340.597 365.472 340.69 365.58L340.82 365.74L340.72 365.35C340.69 365.17 340.63 364.93 340.61 364.83Z\\\" fill=\\\"#FFEBD4\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 53\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_9_2\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_10\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<path d=\\\"M344.61 367.67C344.5 367.67 344.48 367.61 344.47 367.57C344.46 367.477 344.46 367.383 344.47 367.29C344.47 367.12 344.52 367.14 344.58 367.14C344.64 367.14 344.84 367.19 345.08 367.21C345.32 367.23 345.68 367.33 345.86 367.34C345.897 367.341 345.933 367.353 345.963 367.375C345.993 367.396 346.016 367.426 346.03 367.46C346.034 367.5 346.034 367.54 346.03 367.58C346.43 369.49 345.72 369.89 345.22 369.89C344.72 369.89 343.53 369.53 342.98 367.39C342.34 364.93 343.43 364.69 343.85 364.69C344.156 364.732 344.447 364.844 344.702 365.018C344.957 365.191 345.169 365.421 345.32 365.69C345.37 365.76 345.44 365.91 345.48 365.97C345.52 366.03 345.48 365.97 345.48 365.97C345.48 365.97 345.48 365.97 345.4 366.07L345.04 366.33L344.79 366.58C344.765 366.618 344.735 366.651 344.7 366.68C344.7 366.68 344.63 366.6 344.58 366.55C344.53 366.5 344.42 366.31 344.27 366.31C344.12 366.31 344.06 366.92 344.16 367.31C344.26 367.7 344.42 368.39 344.81 368.39C344.99 368.39 345.04 368.21 345.04 368.04C345.041 367.918 345.024 367.797 344.99 367.68H344.87L344.61 367.67Z\\\" fill=\\\"#FFEBD4\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 54\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_10_2\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_11\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<path d=\\\"M350.15 369.71C350.15 369.76 350.15 369.76 350.03 369.76H348.87H347.94H347.26C347.13 369.76 347.15 369.76 347.12 369.58C347.09 369.4 346.86 368.47 346.82 368.31C346.78 368.15 346.63 367.69 346.57 367.45C346.66 367.79 346.34 366.28 346.28 366.07L346.07 365.27L345.94 364.81C345.94 364.72 346.02 364.76 346.07 364.76H346.35C346.35 364.76 346.35 364.76 346.4 364.81C346.45 364.86 346.69 366.1 346.74 366.3L347 367.3C347 367.41 347.13 367.74 347.18 367.96C347.185 368.02 347.185 368.08 347.18 368.14C347.176 368.183 347.176 368.227 347.18 368.27H347.32H348.71H349.6C349.65 368.27 349.67 368.27 349.67 368.27C349.676 368.296 349.676 368.324 349.67 368.35L349.76 368.67C349.92 369 350.13 369.63 350.15 369.71Z\\\" fill=\\\"#FFEBD4\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 55\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_11_2\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_12\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<path d=\\\"M349.81 365.85C349.91 366.24 350.18 367.45 350.27 367.85C350.36 368.25 350.71 369.46 350.77 369.64C350.773 369.673 350.773 369.707 350.77 369.74C350.77 369.82 350.77 369.83 350.77 369.85C350.77 369.87 350.67 369.85 350.6 369.85C350.53 369.85 350.47 369.85 350.38 369.55C350.29 369.25 349.9 367.55 349.78 367.13C349.66 366.71 349.36 365.29 349.3 365.13C349.24 364.97 349.3 365.03 349.3 364.98C349.3 364.93 349.3 364.8 349.3 364.8H349.52C349.57 364.8 349.59 364.85 349.6 364.9C349.61 364.95 349.6 365.02 349.6 365.07C349.6 365.12 349.72 365.46 349.81 365.85Z\\\" fill=\\\"#FFEBD4\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 56\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_12_2\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_13\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<path d=\\\"M353 365.48V365.54C353 365.54 353 365.6 353 365.64C353 365.68 352.93 365.91 352.89 366C352.85 366.09 352.89 366.12 352.8 366.12C352.71 366.12 352.02 365.39 351.59 365.39C351.44 365.39 351.22 365.39 351.35 365.88C351.48 366.37 351.93 366.54 352.24 366.68C352.648 366.835 353.01 367.091 353.293 367.423C353.576 367.755 353.771 368.153 353.86 368.58C354.1 369.51 353.58 369.94 352.64 369.94C352.345 369.926 352.056 369.848 351.795 369.709C351.534 369.571 351.307 369.377 351.13 369.14C351.126 369.117 351.126 369.093 351.13 369.07C351.124 369.037 351.124 369.003 351.13 368.97C351.166 368.865 351.213 368.765 351.27 368.67C351.27 368.67 351.36 368.75 351.42 368.81C351.661 369.045 351.975 369.19 352.31 369.22C352.52 369.22 352.85 369.17 352.73 368.73C352.543 368.31 352.228 367.96 351.83 367.73C351.51 367.5 350.63 367.18 350.39 366.26C350.337 366.104 350.319 365.939 350.336 365.775C350.354 365.612 350.406 365.454 350.491 365.313C350.576 365.172 350.69 365.052 350.827 364.96C350.963 364.867 351.118 364.806 351.28 364.78C351.918 364.801 352.528 365.049 353 365.48Z\\\" fill=\\\"#FFEBD4\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 57\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_13_2\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_14\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<path d=\\\"M355.36 366.75H355.58H355.82H355.95V366.53L355.88 366.19C355.83 366.02 355.61 365.08 355.58 364.95C355.55 364.82 355.58 364.78 355.63 364.77C355.737 364.777 355.843 364.777 355.95 364.77H356.12H356.43C356.55 364.77 356.53 364.82 356.58 364.94C356.63 365.06 356.75 365.77 356.81 366C356.87 366.23 357.01 367 357.08 367.29C357.15 367.58 357.38 368.41 357.45 368.7C357.52 368.99 357.67 369.54 357.73 369.7C357.73 369.84 357.73 369.81 357.64 369.81H357.37C357.197 369.819 357.023 369.819 356.85 369.81C356.75 369.81 356.75 369.74 356.73 369.64C356.71 369.54 356.53 368.89 356.44 368.64C356.35 368.39 356.34 368.3 356.3 368.12C356.264 368.012 356.234 367.902 356.21 367.79H355.43L355.53 368.24C355.53 368.49 355.64 368.75 355.67 368.89C355.7 369.03 355.73 369.12 355.77 369.25C355.81 369.38 355.87 369.63 355.9 369.71C355.93 369.79 355.9 369.83 355.77 369.83H355.43C355.33 369.83 355.1 369.83 354.97 369.83C354.84 369.83 354.81 369.73 354.78 369.63L354.6 368.85C354.6 368.71 354.43 368.15 354.32 367.73C354.32 367.58 354.25 367.45 354.22 367.37C354.168 367.233 354.125 367.093 354.09 366.95C354.03 366.68 353.96 366.4 353.92 366.24C353.88 366.08 353.67 365.06 353.63 364.93C353.59 364.8 353.63 364.83 353.68 364.83H353.76C353.906 364.842 354.054 364.842 354.2 364.83H354.62C354.67 364.83 354.68 364.9 354.7 364.96C354.72 365.02 354.83 365.44 354.93 365.81C354.98 366.01 355.03 366.23 355.07 366.42L355.15 366.75H355.36Z\\\" fill=\\\"#FFEBD4\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Group 6\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector5656231 58\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_14_2\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_15\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<path d=\\\"M338.52 375.55V375.4L338.17 374.13C338.09 373.78 337.97 373.31 337.91 373.13C337.85 372.95 337.72 372.46 337.68 372.32C337.64 372.18 337.63 372.11 337.68 372.11H338.12H338.56C338.67 372.11 338.86 372.11 339.34 372.51C339.747 372.904 340.023 373.414 340.13 373.97C340.271 374.446 340.225 374.957 340 375.4C339.735 375.59 339.416 375.692 339.09 375.69H338.66C338.53 375.64 338.51 375.59 338.52 375.55ZM338.66 373.48C338.74 373.79 338.84 374.05 338.89 374.28C338.94 374.51 339 374.68 339.06 374.94C339.12 375.2 339.14 375.26 339.19 375.44C339.367 375.463 339.546 375.416 339.69 375.31C339.91 375.15 340.08 374.75 339.87 373.92C339.769 373.344 339.446 372.83 338.97 372.49C338.796 372.38 338.596 372.317 338.39 372.31L338.5 372.78C338.55 373 338.63 373.33 338.66 373.48Z\\\" fill=\\\"#FFEBD4\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 59\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_15_2\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_16\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<path d=\\\"M340.05 372.19C340.05 372.02 340.05 371.99 340.05 371.99C340.12 371.99 340.26 371.99 340.39 371.99C340.52 371.99 340.49 371.99 340.5 372.07C340.51 372.15 340.5 372.14 340.5 372.18C340.54 372.487 340.6 372.791 340.68 373.09L340.78 373.5C340.88 373.87 340.97 374.2 340.99 374.29C341.01 374.38 341.12 374.71 341.16 374.9C341.166 374.94 341.166 374.98 341.16 375.02C341.155 375.06 341.155 375.1 341.16 375.14C341.16 375.28 341.26 375.5 341.28 375.58C341.3 375.66 341.28 375.68 341.18 375.67H340.79C340.7 375.67 340.67 375.6 340.65 375.51C340.63 375.42 340.65 375.25 340.56 375.07C340.47 374.89 340.33 373.98 340.3 373.84C340.27 373.7 340.09 372.99 340.06 372.84C340.03 372.69 340.06 372.66 340 372.56V372.37L340.05 372.19Z\\\" fill=\\\"#FFEBD4\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 60\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_16_2\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_17\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<path d=\\\"M343.65 375.05V375.11C343.626 375.276 343.543 375.428 343.416 375.538C343.29 375.648 343.128 375.709 342.96 375.71C342.4 375.71 341.66 374.89 341.38 373.81C341.1 372.73 341.43 372 341.91 372C342.076 372.009 342.239 372.052 342.387 372.128C342.535 372.204 342.666 372.31 342.77 372.44C342.806 372.469 342.834 372.507 342.85 372.55C342.85 372.55 342.85 372.6 342.85 372.63C342.775 372.733 342.711 372.843 342.66 372.96C342.66 373.03 342.6 373.09 342.56 373.09C342.52 373.09 342.56 373.09 342.48 373.09C342.4 373.09 342.28 372.87 342.17 372.87C342.06 372.87 341.78 373.14 342 373.99C342.22 374.84 342.64 374.99 342.76 374.99C342.88 374.99 342.97 374.84 343.01 374.79C343.05 374.74 343.01 374.72 343.01 374.72H343.07L343.49 374.96C343.58 375 343.64 375 343.65 375.05Z\\\" fill=\\\"#FFEBD4\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 61\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_17_2\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_18\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<path d=\\\"M345.38 374.06C345.49 374.49 345.75 375.25 345.8 375.45C345.85 375.65 345.72 375.61 345.47 375.61H344.47C344.47 375.61 344.41 375.61 344.4 375.51C344.39 375.41 344.4 375.29 344.32 375.16C344.24 375.03 344.25 374.92 344.19 374.69C344.06 374.15 343.85 373.32 343.78 372.95C343.76 372.829 343.734 372.708 343.7 372.59C343.7 372.43 343.62 372.3 343.59 372.21H343.16C343.16 372.21 343.16 372.21 343.1 372.13C343.105 372.093 343.105 372.057 343.1 372.02C343.1 371.96 343.1 371.95 343.1 371.95H345.2C345.29 371.95 345.29 372.03 345.31 372.11C345.33 372.19 345.31 372.23 345.24 372.23H344.86C345 372.58 345.28 373.7 345.38 374.06Z\\\" fill=\\\"#FFEBD4\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 62\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_18_2\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_19\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<path d=\\\"M346.13 372.77C346.2 373.05 346.39 373.93 346.46 374.2C346.53 374.47 346.78 375.37 346.82 375.5C346.824 375.527 346.824 375.553 346.82 375.58C346.82 375.63 346.82 375.64 346.82 375.66C346.82 375.68 346.74 375.66 346.69 375.66C346.64 375.66 346.59 375.66 346.53 375.44C346.47 375.22 346.18 374.02 346.09 373.68C346 373.34 345.79 372.33 345.74 372.2V372.09C345.74 372.02 345.74 371.96 345.74 371.96H345.9C345.9 371.96 345.9 371.96 345.96 372.03C346.02 372.1 345.96 372.11 345.96 372.15C346.005 372.36 346.062 372.567 346.13 372.77Z\\\" fill=\\\"#FFEBD4\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 63\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_19_2\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_20\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<path d=\\\"M349.11 373.8C349.21 374.15 349.53 375.7 348.38 375.7C347.81 375.7 347.38 375.2 347.12 374.7C346.954 374.379 346.817 374.045 346.71 373.7C346.47 372.76 346.8 371.92 347.36 371.92C347.57 371.891 347.783 371.93 347.97 372.03C348.521 372.49 348.919 373.108 349.11 373.8ZM348.76 373.8C348.54 372.95 348.03 372.22 347.52 372.22C347.37 372.22 347.24 372.22 347.17 372.37C347.04 372.572 346.957 372.802 346.927 373.041C346.898 373.279 346.923 373.522 347 373.75C347.21 374.57 347.65 375.41 348.29 375.41C348.93 375.41 349 374.65 348.76 373.8Z\\\" fill=\\\"#FFEBD4\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 64\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_20_2\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_21\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<path d=\\\"M350.42 373.82C350.51 374.18 350.72 374.93 350.76 375.08C350.8 375.23 350.89 375.5 350.91 375.58C350.91 375.65 350.91 375.66 350.85 375.66H350.57H350.16C350.05 375.66 350.04 375.58 350.01 375.51C349.98 375.44 350.01 375.41 349.93 375.28L349.88 375.07C349.81 374.77 349.65 374.16 349.62 373.93C349.59 373.7 349.4 372.8 349.34 372.59C349.28 372.38 349.24 372.18 349.2 371.98C349.16 371.78 349.2 371.84 349.28 371.84H349.75C349.796 371.834 349.843 371.841 349.886 371.861C349.928 371.88 349.964 371.911 349.99 371.95L350.43 372.64L351.22 373.89C351.31 374.02 351.45 374.21 351.57 374.4L351.78 374.71L351.7 374.41L351.55 373.9C351.545 373.85 351.545 373.8 351.55 373.75C351.49 373.53 351.44 373.32 351.41 373.17C351.38 373.02 351.25 372.62 351.21 372.43L351.09 371.93C351.09 371.87 351.09 371.85 351.14 371.85H351.23H351.38C351.38 371.85 351.44 371.85 351.45 371.85C351.446 371.887 351.446 371.923 351.45 371.96C351.45 372.06 351.76 373.18 351.83 373.45V373.6C351.91 373.9 352.05 374.34 352.1 374.53C352.15 374.72 352.33 375.34 352.35 375.44C352.35 375.53 352.35 375.54 352.3 375.53H352.1C352.05 375.53 352.05 375.53 351.98 375.43C351.91 375.33 351.5 374.62 351.37 374.43C351.24 374.24 350.73 373.43 350.57 373.18C350.41 372.93 350.37 372.88 350.27 372.73L350.07 372.46L350.21 372.95C350.29 373.34 350.38 373.64 350.42 373.82Z\\\" fill=\\\"#FFEBD4\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 65\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_21_2\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_22\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<path d=\\\"M352.69 375C352.683 374.873 352.683 374.747 352.69 374.62C352.69 374.48 352.69 374.18 352.69 374.03C352.69 373.88 352.69 373.65 352.69 373.54C352.69 373.43 352.69 373.16 352.69 373C352.684 372.88 352.684 372.76 352.69 372.64C352.69 372.56 352.69 372.27 352.69 372.13C352.69 371.99 352.69 371.88 352.77 371.88C352.85 371.88 352.87 372 352.95 372.14C353.03 372.28 353.23 372.7 353.27 372.78C353.31 372.86 353.65 373.48 353.7 373.57C353.75 373.66 354.04 374.18 354.12 374.31C354.2 374.44 354.39 374.82 354.46 374.98C354.53 375.14 354.74 375.47 354.78 375.54C354.776 375.556 354.776 375.574 354.78 375.59C354.78 375.59 354.78 375.59 354.73 375.59H354.5C354.5 375.59 354.5 375.59 354.44 375.59L354.34 375.4L354.23 375.17C354.18 375.045 354.12 374.925 354.05 374.81C354.005 374.739 353.965 374.666 353.93 374.59L353.85 374.44C353.8 374.36 353.79 374.36 353.76 374.36H352.87C352.87 374.36 352.87 374.36 352.87 374.42V374.57C352.87 374.65 352.87 375.05 352.87 375.1C352.875 375.157 352.875 375.213 352.87 375.27V375.43C352.865 375.477 352.865 375.523 352.87 375.57H352.79C352.79 375.57 352.79 375.57 352.79 375.51C352.785 375.487 352.785 375.463 352.79 375.44V375.25C352.762 375.165 352.728 375.081 352.69 375ZM353.56 374C353.546 373.957 353.526 373.917 353.5 373.88C353.45 373.79 353.29 373.45 353.2 373.3C353.11 373.15 352.92 372.74 352.89 372.65C352.846 372.555 352.792 372.464 352.73 372.38C352.73 372.38 352.73 372.51 352.73 372.63C352.73 372.75 352.73 373.21 352.73 373.34C352.73 373.47 352.73 373.85 352.73 373.96C352.73 374.02 352.82 374.01 352.86 374.01H353.48C353.48 374.01 353.57 374 353.56 374Z\\\" fill=\\\"#FFEBD4\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 66\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_22_2\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_23\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<path d=\\\"M354.83 373.93C354.91 374.16 355.24 375.44 355.27 375.57C355.3 375.7 355.19 375.7 355.14 375.7C355.09 375.7 355.07 375.61 355.05 375.55C355.022 375.472 354.998 375.391 354.98 375.31C354.975 375.26 354.975 375.21 354.98 375.16C354.98 375.04 354.64 373.76 354.43 372.93C354.34 372.57 354.26 372.3 354.24 372.23C354.236 372.193 354.236 372.157 354.24 372.12C354.24 372.02 354.24 372.01 354.24 372.01H354.87C355.05 372.01 355.69 372.07 355.81 372.52C355.97 373.14 355.29 373.23 355.08 373.23H355C355.06 373.23 356.74 375.23 356.94 375.43C357.14 375.63 357.1 375.59 357.1 375.62C357.1 375.65 357.1 375.62 357.1 375.62C357.041 375.635 356.979 375.635 356.92 375.62C356.74 375.62 356.75 375.62 356.67 375.48C356.59 375.34 356.07 374.8 355.77 374.48C355.62 374.3 355.36 374.01 355.14 373.77L354.74 373.32V373.53C354.76 373.68 354.8 373.82 354.83 373.93ZM354.83 373.02C354.953 373.035 355.077 373.035 355.2 373.02C355.41 372.97 355.57 372.91 355.51 372.68C355.45 372.45 355.07 372.35 354.9 372.35H354.46L354.62 373.08L354.83 373.02Z\\\" fill=\\\"#FFEBD4\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 67\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_23_2\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_24\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<path d=\\\"M357.87 375.65H357.71C357.71 375.65 357.71 375.65 357.65 375.65V375.59C357.65 375.54 357.65 375.17 357.65 375.09C357.65 375.01 357.65 374.8 357.65 374.7C357.65 374.6 357.65 374.57 357.65 374.51C357.65 374.45 357.49 374.18 357.42 374.06C357.35 373.94 357.26 373.75 357.17 373.59C357.08 373.43 356.61 372.59 356.54 372.43C356.47 372.27 356.4 372.21 356.39 372.16C356.38 372.11 356.39 372.09 356.5 372.09H356.84C356.92 372.09 356.9 372.14 356.93 372.2L357.15 372.63C357.22 372.76 357.33 372.98 357.41 373.12C357.49 373.26 357.56 373.37 357.63 373.51C357.7 373.65 357.72 373.67 357.76 373.76V373.63C357.755 373.557 357.755 373.483 357.76 373.41V373.12C357.757 373.073 357.757 373.027 357.76 372.98C357.754 372.93 357.754 372.88 357.76 372.83C357.775 372.634 357.775 372.436 357.76 372.24C357.76 372.06 357.83 372.09 357.89 372.09H358.15C358.23 372.09 358.25 372.09 358.26 372.14V372.19C358.26 372.25 358.26 372.6 358.26 372.79C358.26 372.98 358.2 373.73 358.19 373.95C358.18 374.17 358.11 375.1 358.12 375.19C358.11 375.316 358.11 375.444 358.12 375.57C358.12 375.64 358.12 375.67 358.12 375.67H357.84L357.87 375.65Z\\\" fill=\\\"#FFEBD4\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Group 7\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector5656231 68\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_24_2\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_25\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<path d=\\\"M249.63 377.66C249.63 377.45 249.69 377.41 249.75 377.41H249.8C249.943 377.4 250.087 377.4 250.23 377.41C250.33 377.41 250.35 377.46 250.35 377.51C250.354 377.557 250.354 377.603 250.35 377.65C250.35 377.8 250.27 378.16 250.23 378.76C250.23 378.92 250.23 379.1 250.23 379.27C250.23 379.72 250.23 380.12 250.23 380.27C250.23 380.42 250.23 380.78 250.23 381.01C250.234 381.057 250.234 381.103 250.23 381.15C250.23 381.15 250.23 381.24 250.23 381.3C250.23 381.36 250.23 381.74 250.23 381.84C250.23 381.94 250.14 381.96 250.06 381.96H249.55C249.43 381.96 249.43 381.87 249.43 381.76C249.43 381.65 249.48 381.45 249.5 381.22C249.52 380.99 249.64 379.89 249.65 379.72C249.66 379.55 249.73 378.67 249.74 378.52C249.75 378.37 249.74 378.3 249.74 378.18V377.95L249.63 377.66Z\\\" fill=\\\"#FFE3BB\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 69\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_25_2\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_26\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<path d=\\\"M253.16 381.16V381.23C253.055 381.452 252.891 381.64 252.687 381.776C252.483 381.912 252.245 381.989 252 382C251.27 382 250.64 381 250.71 379.69C250.78 378.38 251.51 377.47 252.13 377.47C252.331 377.46 252.531 377.507 252.708 377.604C252.884 377.701 253.03 377.845 253.13 378.02C253.142 378.063 253.142 378.107 253.13 378.15C253.121 378.191 253.096 378.227 253.06 378.25C252.921 378.371 252.794 378.505 252.68 378.65C252.61 378.74 252.55 378.81 252.5 378.81C252.481 378.808 252.463 378.801 252.448 378.791C252.432 378.78 252.419 378.766 252.41 378.75C252.31 378.62 252.23 378.48 252.09 378.48C251.95 378.48 251.48 378.81 251.42 379.85C251.36 380.89 251.85 381.08 252 381.08C252.15 381.08 252.34 380.9 252.41 380.83C252.48 380.76 252.47 380.76 252.49 380.76C252.513 380.752 252.537 380.752 252.56 380.76L253.01 381.06C253.09 381.07 253.16 381.09 253.16 381.16Z\\\" fill=\\\"#FFE3BB\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 70\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_26_2\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_27\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<path d=\\\"M255.81 379.94C255.81 380.47 255.81 381.4 255.81 381.64C255.81 381.88 255.64 381.84 255.31 381.84H254.06C254.01 381.84 254.01 381.79 254.01 381.72C254.01 381.65 254.01 381.45 254.06 381.29C254.11 381.13 254.06 381 254.06 380.72C254.06 380.06 254.17 379.05 254.22 378.6C254.22 378.43 254.22 378.29 254.22 378.15C254.22 378.01 254.22 377.79 254.22 377.69H253.66C253.66 377.69 253.66 377.69 253.66 377.59C253.66 377.49 253.66 377.5 253.66 377.45C253.66 377.4 253.66 377.37 253.73 377.37H255.04H256.47C256.59 377.37 256.56 377.46 256.55 377.57C256.54 377.68 256.55 377.72 256.41 377.72H256C255.93 378.13 255.84 379.5 255.81 379.94Z\\\" fill=\\\"#FFE3BB\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 71\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_27_2\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_28\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<path d=\\\"M257.31 378.37C257.31 378.71 257.19 379.79 257.17 380.11C257.15 380.43 257.11 381.55 257.11 381.71C257.115 381.74 257.115 381.77 257.11 381.8C257.11 381.87 257.11 381.88 257.04 381.9C256.984 381.912 256.926 381.912 256.87 381.9C256.69 381.9 256.74 381.9 256.75 381.64C256.76 381.38 256.87 379.9 256.89 379.48C256.91 379.06 257.04 377.83 257.03 377.68V377.55C257.03 377.46 257.03 377.38 257.13 377.38H257.34C257.34 377.38 257.34 377.38 257.34 377.47C257.334 377.52 257.334 377.57 257.34 377.62C257.35 377.78 257.34 378 257.31 378.37Z\\\" fill=\\\"#FFE3BB\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 72\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_28_2\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_29\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<path d=\\\"M260.79 379.62C260.79 380.05 260.56 381.95 259.07 381.95C258.32 381.95 257.99 381.34 257.83 380.73C257.733 380.328 257.689 379.914 257.7 379.5C257.76 378.36 258.53 377.33 259.26 377.33C259.518 377.289 259.781 377.334 260.01 377.46C260.278 377.749 260.486 378.09 260.62 378.461C260.754 378.832 260.812 379.226 260.79 379.62ZM260.33 379.62C260.39 378.62 260.01 377.7 259.33 377.7C259.13 377.7 258.97 377.7 258.81 377.88C258.341 378.321 258.062 378.927 258.03 379.57C257.98 380.57 258.21 381.57 259.03 381.57C259.85 381.57 260.27 380.66 260.33 379.62Z\\\" fill=\\\"#FFE3BB\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 73\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_29_2\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_30\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<path d=\\\"M262.48 379.66C262.48 380.09 262.43 381 262.42 381.19C262.41 381.38 262.42 381.7 262.42 381.8C262.42 381.89 262.36 381.91 262.31 381.91H261.93H261.4C261.25 381.91 261.26 381.82 261.25 381.74C261.243 381.647 261.243 381.553 261.25 381.46C261.25 381.39 261.25 381.31 261.25 381.2C261.25 380.84 261.33 380.08 261.37 379.8C261.41 379.52 261.54 378.42 261.55 378.17C261.56 377.92 261.55 377.67 261.61 377.42C261.67 377.17 261.7 377.25 261.78 377.25H262.39C262.55 377.25 262.62 377.25 262.66 377.37C262.7 377.49 262.84 377.9 262.95 378.22C263.06 378.54 263.37 379.44 263.48 379.75L263.73 380.37L263.88 380.75V379.57C263.88 379.3 263.88 379.05 263.88 378.87C263.88 378.69 263.88 378.19 263.88 377.96L263.93 377.35C263.93 377.28 263.98 377.26 264.02 377.26H264.13C264.193 377.271 264.257 377.271 264.32 377.26C264.38 377.26 264.39 377.26 264.39 377.32C264.393 377.36 264.393 377.4 264.39 377.44C264.39 377.56 264.3 378.94 264.28 379.27C264.28 379.27 264.28 379.38 264.28 379.45C264.28 379.82 264.28 380.35 264.28 380.59C264.28 380.83 264.28 381.59 264.28 381.7C264.28 381.81 264.22 381.82 264.17 381.81H264.1C264.037 381.815 263.973 381.815 263.91 381.81C263.85 381.81 263.85 381.81 263.79 381.69C263.73 381.57 263.5 380.69 263.41 380.45C263.32 380.21 262.97 379.22 262.87 378.92C262.82 378.77 262.73 378.55 262.66 378.37L262.51 378.04V378.64C262.5 379.06 262.49 379.43 262.48 379.66Z\\\" fill=\\\"#FFE3BB\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 74\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_30_2\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_31\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<path d=\\\"M266.78 377.45C266.78 377.26 266.95 377.28 267.07 377.28C267.273 377.294 267.477 377.294 267.68 377.28C267.84 377.28 267.83 377.36 267.8 377.56C267.77 377.76 267.75 378.23 267.72 378.82C267.69 379.41 267.65 380.04 267.64 380.25C267.64 380.79 267.58 382.12 267.59 381.83C267.59 381.91 267.59 381.93 267.5 381.93H267.34H266.92C266.77 381.93 266.72 381.86 266.66 381.69C266.6 381.52 266.47 381.14 266.32 380.81L266 380L265.78 379.47V379.71C265.78 379.86 265.78 380.01 265.78 380.15C265.78 380.29 265.71 381.48 265.73 381.65V381.73C265.73 381.83 265.68 381.83 265.62 381.82H265.18C265.07 381.82 265.05 381.82 265.07 381.59C265.09 381.36 265.07 380.51 265.13 379.74C265.13 379.2 265.22 378.5 265.25 378.03C265.25 377.85 265.25 377.7 265.25 377.61C265.245 377.56 265.245 377.51 265.25 377.46C265.25 377.29 265.33 377.26 265.41 377.27C265.519 377.285 265.63 377.285 265.74 377.27H266.11C266.35 377.27 266.44 377.62 266.54 377.82C266.64 378.02 266.64 378.03 266.68 378.12L266.76 378.26V377.91C266.76 377.75 266.77 377.54 266.78 377.45Z\\\" fill=\\\"#FFE3BB\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 75\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_31_2\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_32\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<path d=\\\"M271.33 377.66C271.33 377.45 271.4 377.41 271.46 377.41C271.606 377.4 271.753 377.4 271.9 377.41C271.99 377.41 272.02 377.46 272.01 377.51C272.014 377.557 272.014 377.603 272.01 377.65C272.01 377.8 271.92 378.16 271.88 378.76V379.27C271.88 379.72 271.88 380.12 271.88 380.27C271.88 380.42 271.88 380.78 271.88 381.01C271.887 381.056 271.887 381.104 271.88 381.15C271.874 381.2 271.874 381.25 271.88 381.3C271.88 381.48 271.88 381.74 271.88 381.84C271.88 381.94 271.79 381.96 271.7 381.96H271.2C271.07 381.96 271.08 381.87 271.08 381.76C271.08 381.65 271.13 381.45 271.14 381.22C271.15 380.99 271.29 379.89 271.3 379.72C271.31 379.55 271.38 378.67 271.38 378.52C271.38 378.37 271.38 378.3 271.38 378.18V377.95L271.33 377.66Z\\\" fill=\\\"#FFE3BB\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 76\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_32_2\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_33\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<path d=\\\"M274.92 381.7C274.954 381.755 274.978 381.816 274.99 381.88C274.99 381.93 274.94 381.88 274.88 381.88H274.25C274.16 381.88 274.16 381.72 274.04 381.43C273.92 381.14 273.84 380.91 273.7 380.57L273.46 379.94C273.46 380.24 273.46 380.51 273.46 380.76C273.46 381.18 273.46 381.63 273.46 381.7V381.76C273.46 381.86 273.4 381.89 273.3 381.87C273.2 381.85 272.72 381.92 272.58 381.92C272.44 381.92 272.46 381.87 272.46 381.78C272.46 381.69 272.46 381.69 272.46 381.63C272.46 381.57 272.46 380.63 272.46 380.12C272.46 379.96 272.46 379.84 272.46 379.77C272.505 379.475 272.532 379.178 272.54 378.88C272.54 378.42 272.54 377.88 272.54 377.72V377.58C272.54 377.36 272.62 377.39 272.68 377.39C272.922 377.353 273.166 377.329 273.41 377.32C273.58 377.306 273.75 377.331 273.908 377.395C274.067 377.458 274.208 377.557 274.321 377.684C274.435 377.811 274.517 377.962 274.562 378.126C274.607 378.291 274.613 378.463 274.58 378.63C274.557 378.947 274.454 379.254 274.28 379.52C274.198 379.639 274.104 379.749 274 379.85L274.35 380.65C274.66 381.13 274.85 381.57 274.92 381.7ZM273.62 379.12C273.71 379.12 273.78 378.99 273.8 378.79C273.82 378.59 273.73 378.43 273.64 378.43C273.598 378.432 273.559 378.45 273.53 378.48C273.53 378.48 273.53 378.68 273.53 378.83C273.522 378.903 273.522 378.977 273.53 379.05C273.525 379.07 273.525 379.09 273.53 379.11V379.16C273.562 379.153 273.593 379.139 273.62 379.12Z\\\" fill=\\\"#FFE3BB\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 77\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_33_2\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_34\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<path d=\\\"M275.64 379.43C275.64 378.94 275.64 378.9 275.64 378.52C275.64 378.14 275.64 377.76 275.71 377.59C275.78 377.42 275.71 377.45 275.82 377.45H275.9C275.99 377.45 276.08 377.45 276.33 377.45C276.58 377.45 276.95 377.4 277.17 377.4H277.78C277.89 377.4 277.89 377.46 277.89 377.58C277.89 377.7 277.89 377.86 277.89 378.06C277.902 378.136 277.902 378.214 277.89 378.29C277.89 378.37 277.89 378.39 277.81 378.39H277.69C277.53 378.376 277.37 378.376 277.21 378.39H276C275.94 378.39 275.94 378.39 275.94 378.51C275.94 378.63 275.94 378.9 275.89 379.12V379.5C275.885 379.567 275.885 379.633 275.89 379.7H276.43H277.02H277.29C277.35 379.7 277.36 379.7 277.36 379.78C277.354 379.847 277.354 379.913 277.36 379.98C277.36 380.1 277.36 380.15 277.36 380.31C277.36 380.47 277.36 380.41 277.31 380.41H277.21H276.65C276.433 380.414 276.216 380.431 276 380.46H275.89V381.09H276.76H277.46H277.69C277.78 381.09 277.8 381.15 277.79 381.22C277.78 381.29 277.79 381.31 277.79 381.35C277.79 381.39 277.79 381.61 277.79 381.79C277.79 381.97 277.69 381.93 277.52 381.93H276.52H275.65C275.65 381.93 275.65 381.88 275.65 381.82C275.65 381.76 275.65 381.66 275.65 381.59C275.65 381.52 275.65 381.45 275.65 381.32V380.45C275.56 380 275.61 379.92 275.64 379.43Z\\\" fill=\\\"#FFE3BB\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 78\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_34_2\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_35\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<path d=\\\"M281.31 382.65C281.31 382.55 281.31 382.54 281.38 382.54H281.57H282.28H283.43C283.52 382.54 283.54 382.54 283.55 382.62V382.73L283.66 383.49V383.81V383.86C283.66 383.93 283.66 383.95 283.58 383.95H283H282.15H282.03C282.03 383.95 282.03 384.02 282.03 384.06V384.28C282.034 384.34 282.034 384.4 282.03 384.46V384.54H282.8H283.33C283.43 384.54 283.45 384.54 283.46 384.62C283.464 384.68 283.464 384.74 283.46 384.8C283.46 384.88 283.46 384.88 283.39 384.88H282.1L282.18 385.51C282.18 385.84 282.26 386.17 282.26 386.27C282.26 386.37 282.26 386.47 282.26 386.6C282.26 386.73 282.26 386.92 282.31 386.98C282.36 387.04 282.31 387.08 282.19 387.08H281.8C281.7 387.08 281.72 386.99 281.69 386.85C281.66 386.71 281.69 386.68 281.64 386.54C281.59 386.4 281.64 386.14 281.57 386C281.5 385.86 281.47 385.05 281.45 384.91C281.43 384.77 281.39 384.62 281.36 384.34C281.33 384.06 281.36 383.95 281.3 383.77L281.22 383.19C281.34 383 281.33 382.77 281.31 382.65Z\\\" fill=\\\"#FFE3BB\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 79\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_35_2\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_36\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<path d=\\\"M287 386.83C287.049 386.886 287.086 386.95 287.11 387.02C287.11 387.02 287.11 387.02 287.01 387.02H286.36C286.26 387.02 286.23 386.86 286.05 386.55L285.54 385.68L285.17 385.04C285.22 385.34 285.27 385.62 285.32 385.87C285.39 386.3 285.48 386.76 285.5 386.87C285.52 386.98 285.5 386.87 285.5 386.93C285.5 386.99 285.5 387.06 285.35 387.04C285.2 387.02 284.76 387.1 284.61 387.1C284.46 387.1 284.48 387.04 284.47 386.95C284.46 386.86 284.47 386.86 284.47 386.8C284.47 386.74 284.29 385.8 284.23 385.26C284.213 385.141 284.213 385.019 284.23 384.9C284.23 384.77 284.23 384.4 284.14 383.99C284.05 383.58 283.99 382.99 283.96 382.81C283.957 382.76 283.957 382.71 283.96 382.66C283.96 382.44 284.01 382.46 284.06 382.46C284.11 382.46 284.47 382.4 284.81 382.4C285.182 382.386 285.544 382.519 285.819 382.77C286.094 383.02 286.259 383.369 286.28 383.74C286.32 384.048 286.268 384.361 286.13 384.64C286.071 384.762 285.997 384.876 285.91 384.98L286.42 385.8C286.66 386.25 287 386.7 287 386.83ZM285.17 384.2C285.25 384.15 285.31 384.06 285.28 383.85C285.25 383.64 285.14 383.49 285.05 383.49C285.031 383.49 285.011 383.494 284.994 383.503C284.976 383.511 284.961 383.524 284.95 383.54C284.95 383.54 284.95 383.74 285 383.9C284.99 383.976 284.99 384.054 285 384.13C285 384.13 285 384.13 285 384.18C285 384.23 285 384.18 285 384.24C285.073 384.25 285.146 384.236 285.21 384.2H285.17Z\\\" fill=\\\"#FFE3BB\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 80\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_36_2\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_37\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<path d=\\\"M288 382.37C288 382.3 288 382.29 288.07 382.32C288.14 382.35 288.14 382.43 288.17 382.5C288.2 382.57 288.47 383.08 288.58 383.28C288.69 383.48 288.8 383.71 288.92 383.97C289.04 384.23 289.4 384.89 289.56 385.2C289.72 385.51 290.1 386.13 290.2 386.3C290.301 386.502 290.418 386.696 290.55 386.88C290.554 386.91 290.554 386.94 290.55 386.97C290.55 386.97 290.5 386.97 290.45 386.97H290.04C289.99 386.97 289.95 386.85 289.9 386.75C289.85 386.65 289.63 386.19 289.59 386.09C289.55 385.99 289.45 385.82 289.39 385.72C289.33 385.62 289.32 385.59 289.27 385.59H289.05C288.96 385.59 288.59 385.59 288.44 385.59H288C287.95 385.59 287.95 385.66 287.94 385.73C287.93 385.8 287.94 386.2 287.94 386.32V386.6V386.79C287.94 386.89 287.94 386.91 287.88 386.91H287.55C287.546 386.88 287.546 386.85 287.55 386.82C287.55 386.76 287.55 386.74 287.55 386.57C287.55 386.4 287.66 385.79 287.67 385.57C287.683 385.291 287.716 385.014 287.77 384.74C287.77 384.52 287.77 384.42 287.84 384.12C287.91 383.82 287.91 383.5 287.94 383.27L288.02 382.75C287.94 382.58 288 382.44 288 382.37ZM288.89 384.72C288.89 384.72 288.89 384.72 288.89 384.66C288.754 384.423 288.631 384.179 288.52 383.93C288.42 383.73 288.35 383.56 288.33 383.53C288.31 383.5 288.26 383.4 288.24 383.4C288.22 383.4 288.24 383.52 288.24 383.64C288.24 383.76 288.18 384.09 288.16 384.21C288.145 384.355 288.121 384.498 288.09 384.64V384.74C288.09 384.74 288.09 384.74 288.15 384.74C288.21 384.74 288.73 384.74 288.83 384.74C288.93 384.74 288.88 384.75 288.87 384.72H288.89Z\\\" fill=\\\"#FFE3BB\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 81\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_37_2\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_38\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<path d=\\\"M292 382.48C292 382.3 292.15 382.31 292.27 382.31C292.478 382.307 292.685 382.29 292.89 382.26C293.05 382.26 293.07 382.35 293.07 382.55C293.07 382.75 293.15 383.23 293.23 383.84C293.31 384.45 293.39 385.08 293.42 385.3C293.49 385.85 293.71 387.21 293.67 386.92C293.67 386.99 293.67 387.02 293.59 387.02H293.43H292.99C292.84 387.02 292.78 386.95 292.69 386.78C292.6 386.61 292.38 386.21 292.17 385.88C292.06 385.72 291.86 385.39 291.69 385.1L291.36 384.56V384.81C291.36 384.96 291.36 385.11 291.42 385.26C291.48 385.41 291.6 386.62 291.65 386.79C291.648 386.817 291.648 386.843 291.65 386.87C291.65 386.97 291.65 386.97 291.55 386.96H291.11C290.99 386.96 290.97 386.96 290.95 386.73C290.93 386.5 290.77 385.62 290.65 384.84C290.58 384.29 290.51 383.57 290.45 383.09C290.434 382.946 290.411 382.802 290.38 382.66C290.371 382.61 290.371 382.56 290.38 382.51C290.38 382.33 290.38 382.3 290.5 382.31C290.609 382.335 290.721 382.335 290.83 382.31H291.22C291.46 382.31 291.63 382.67 291.77 382.87C291.91 383.07 291.91 383.09 291.97 383.18L292.08 383.33L292.03 382.97C292 382.79 292 382.58 292 382.48Z\\\" fill=\\\"#FFE3BB\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 82\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_38_2\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_39\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<path d=\\\"M296.76 386.08C296.765 386.103 296.765 386.127 296.76 386.15C296.688 386.361 296.554 386.545 296.376 386.679C296.197 386.813 295.983 386.89 295.76 386.9H295.64C295.595 386.982 295.562 387.069 295.54 387.16C295.61 387.16 295.63 387.16 295.81 387.16C295.99 387.16 296.18 387.25 296.23 387.61C296.238 387.674 296.231 387.74 296.208 387.801C296.186 387.862 296.149 387.917 296.1 387.96L296 388C295.892 388.055 295.77 388.076 295.65 388.06C295.47 388.06 295.26 388.06 295.25 387.94C295.24 387.834 295.24 387.726 295.25 387.62C295.25 387.62 295.32 387.62 295.4 387.7C295.476 387.716 295.554 387.716 295.63 387.7C295.77 387.7 295.83 387.7 295.84 387.53C295.85 387.36 295.78 387.32 295.67 387.32C295.56 387.32 295.54 387.41 295.5 387.41C295.46 387.41 295.32 387.41 295.31 387.41C295.3 387.334 295.3 387.256 295.31 387.18C295.303 387.08 295.303 386.98 295.31 386.88C295.019 386.743 294.765 386.537 294.57 386.28C294.212 385.803 293.985 385.241 293.91 384.65C293.846 384.135 293.925 383.612 294.14 383.14C294.209 382.971 294.322 382.823 294.468 382.714C294.615 382.605 294.788 382.538 294.97 382.52C295.181 382.526 295.388 382.579 295.576 382.674C295.765 382.769 295.93 382.904 296.06 383.07C296.096 383.111 296.123 383.158 296.14 383.21C296.139 383.229 296.134 383.248 296.125 383.265C296.117 383.282 296.105 383.298 296.09 383.31C295.964 383.433 295.853 383.571 295.76 383.72C295.71 383.81 295.66 383.89 295.61 383.89C295.56 383.89 295.55 383.89 295.51 383.82C295.47 383.75 295.27 383.55 295.13 383.55C294.99 383.55 294.86 383.64 294.76 383.85C294.653 384.172 294.622 384.514 294.67 384.85C294.79 385.77 295.35 386.08 295.51 386.05C295.67 386.02 295.82 385.87 295.88 385.8C295.94 385.73 295.88 385.72 295.95 385.72H296.02L296.55 386.02C296.67 386 296.75 386 296.76 386.08Z\\\" fill=\\\"#FFE3BB\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 83\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_39_2\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_40\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<path d=\\\"M299.67 382.7C299.67 382.49 299.67 382.44 299.75 382.44H299.8C299.9 382.44 300.08 382.44 300.25 382.44C300.42 382.44 300.38 382.44 300.39 382.54C300.395 382.587 300.395 382.633 300.39 382.68C300.396 383.061 300.423 383.442 300.47 383.82L300.53 384.33C300.59 384.79 300.66 385.21 300.67 385.33C300.68 385.45 300.76 385.85 300.79 386.08C300.79 386.15 300.79 386.21 300.79 386.23C300.781 386.28 300.781 386.33 300.79 386.38C300.79 386.56 300.86 386.83 300.87 386.93C300.88 387.03 300.8 387.06 300.72 387.05H300.2C300.06 387.05 300.05 386.96 300.03 386.85C300.01 386.74 300.03 386.53 300.03 386.3C300.03 386.07 299.93 384.94 299.91 384.76C299.89 384.58 299.79 383.7 299.77 383.54C299.75 383.38 299.77 383.31 299.77 383.19V382.96L299.67 382.7Z\\\" fill=\\\"#FFE3BB\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 84\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_40_2\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_41\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<path d=\\\"M302.3 382.81C301.74 382.81 301.54 383.14 301.59 383.53C301.637 383.712 301.727 383.881 301.852 384.022C301.978 384.163 302.134 384.272 302.31 384.34C302.662 384.42 302.984 384.601 303.236 384.86C303.488 385.119 303.66 385.445 303.73 385.8C303.87 386.92 302.97 387.07 302.47 387.07C302.095 387.039 301.742 386.88 301.47 386.62C301.458 386.604 301.451 386.585 301.451 386.565C301.451 386.545 301.458 386.526 301.47 386.51C301.47 386.51 301.52 386.31 301.57 386.31C301.57 386.31 301.57 386.31 301.7 386.42C301.902 386.574 302.139 386.674 302.39 386.71C302.6 386.71 303.24 386.71 303.15 385.95C303.1 385.58 302.62 385.39 302.15 385.1C301.887 384.975 301.658 384.787 301.484 384.554C301.31 384.32 301.195 384.048 301.15 383.76C301.125 383.596 301.137 383.428 301.183 383.269C301.23 383.11 301.311 382.962 301.42 382.838C301.53 382.713 301.665 382.614 301.817 382.547C301.969 382.48 302.134 382.447 302.3 382.45C302.673 382.489 303.023 382.647 303.3 382.9C303.35 382.9 303.37 382.96 303.37 382.99C303.374 382.999 303.377 383.01 303.377 383.02C303.377 383.03 303.374 383.041 303.37 383.05C303.37 383.05 303.29 383.24 303.24 383.24H303.16C302.922 383.015 302.623 382.865 302.3 382.81Z\\\" fill=\\\"#FFE3BB\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Group 8\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector5656231 85\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_41_2\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_42\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<path d=\\\"M247 393.6C247.48 393.6 248.51 394.06 248.2 396.5C247.9 398.76 246.43 398.85 246.2 398.85H245.49C245.41 398.85 245.41 398.73 245.42 398.59C245.425 398.527 245.425 398.463 245.42 398.4C245.42 398.22 245.48 397.84 245.5 397.68C245.52 397.52 245.5 397.16 245.62 396.57C245.74 395.98 245.79 395.57 245.87 395C245.95 394.43 246 393.88 246.02 393.72C246.04 393.56 246.26 393.61 246.39 393.61H246.58L247 393.6ZM246.83 396.99C247.032 396.744 247.161 396.446 247.2 396.13C247.227 396 247.227 395.865 247.202 395.735C247.176 395.604 247.124 395.48 247.05 395.37C246.991 395.294 246.916 395.232 246.83 395.19C246.83 395.27 246.83 395.35 246.83 395.44C246.83 395.71 246.73 395.99 246.7 396.23C246.67 396.47 246.64 396.65 246.61 396.87L246.55 397.26C246.659 397.189 246.757 397.101 246.84 397L246.83 396.99Z\\\" fill=\\\"#FFEBD4\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 86\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_42_2\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_43\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<path d=\\\"M248.87 396.51C248.87 396.68 248.87 396.75 248.87 396.93L248.76 397.82C248.76 397.95 248.76 398.09 248.71 398.2C248.701 398.263 248.701 398.327 248.71 398.39H249.24H249.79H250.29H250.62C250.68 398.39 250.68 398.39 250.62 398.51C250.56 398.63 250.62 398.66 250.62 398.74C250.62 398.82 250.62 398.83 250.5 398.83H250.41C250.224 398.815 250.036 398.815 249.85 398.83H249.18H248.5C248.4 398.83 248.39 398.83 248.4 398.72C248.396 398.68 248.396 398.64 248.4 398.6C248.404 398.577 248.404 398.553 248.4 398.53C248.4 398.53 248.4 398.44 248.4 398.1C248.4 397.76 248.51 397.1 248.58 396.55C248.65 396 248.78 395.3 248.82 394.99C248.86 394.68 248.93 394.12 248.95 393.84C248.97 393.56 249.22 393.69 249.38 393.69C249.54 393.69 249.98 393.69 250.26 393.69H251.16C251.27 393.69 251.24 393.81 251.23 393.89V393.98C251.23 394.05 251.23 394.15 251.23 394.15C251.23 394.15 251.17 394.15 251.07 394.15H249.59H249.36H249.24V394.35C249.24 394.46 249.24 394.59 249.19 394.7C249.14 394.81 249.19 395.11 249.13 395.28V395.58C249.134 395.643 249.134 395.707 249.13 395.77H249.48C249.57 395.77 249.68 395.77 249.84 395.77C250 395.77 250.18 395.77 250.24 395.77H250.52H250.87H250.98C251.04 395.77 251.04 395.83 250.98 395.86C250.92 395.89 250.98 396.07 250.98 396.13C250.98 396.19 250.98 396.22 250.89 396.22C250.8 396.22 250.38 396.13 250.18 396.13C249.964 396.115 249.746 396.115 249.53 396.13C249.427 396.14 249.323 396.14 249.22 396.13H249.08V396.25C249.001 396.329 248.931 396.416 248.87 396.51Z\\\" fill=\\\"#FFEBD4\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 87\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_43_2\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_44\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<path d=\\\"M251.57 396.7C251.45 397.58 251.62 398.22 251.96 398.22C252.3 398.22 252.44 397.83 252.46 397.63C252.48 397.43 252.64 396.48 252.71 395.92C252.71 395.53 252.88 394.87 252.94 394.39C252.966 394.218 252.983 394.044 252.99 393.87C252.98 393.824 252.98 393.776 252.99 393.73C252.99 393.54 253.11 393.58 253.15 393.58H253.52C253.64 393.58 253.62 393.64 253.61 393.76C253.6 393.88 253.61 394 253.61 394.16C253.616 394.24 253.616 394.32 253.61 394.4C253.56 394.67 253.51 395.59 253.31 397.01C253.11 398.43 252.51 398.85 252 398.85C251.49 398.85 251.35 398.21 251.32 397.85C251.317 397.418 251.347 396.987 251.41 396.56C251.41 396.3 251.48 396.08 251.5 395.99C251.52 395.9 251.56 395.61 251.6 395.29C251.67 394.77 251.74 394.13 251.76 393.92C251.76 393.87 251.76 393.83 251.76 393.8C251.76 393.58 251.85 393.6 251.88 393.62H251.94H252.03C252.03 393.62 252.03 393.62 252.03 393.71C252.05 393.12 251.71 395.59 251.57 396.7Z\\\" fill=\\\"#FFEBD4\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 88\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_44_2\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_45\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<path d=\\\"M255.82 396.57C255.74 397.19 255.68 398.3 255.64 398.57C255.6 398.84 255.46 398.8 255.16 398.8H253.99C253.94 398.8 253.94 398.74 253.99 398.65C254.04 398.56 254.06 398.34 254.08 398.15C254.1 397.96 254.08 397.8 254.16 397.46C254.26 396.68 254.43 395.46 254.53 394.94C254.53 394.75 254.59 394.57 254.61 394.41C254.63 394.25 254.66 393.99 254.67 393.86H254.58H254.15C254.15 393.86 254.15 393.8 254.15 393.74V393.57C254.15 393.49 254.15 393.47 254.22 393.47H254.34H255.45H256.79C256.9 393.47 256.86 393.58 256.84 393.71C256.82 393.84 256.78 393.88 256.69 393.88C256.543 393.887 256.397 393.887 256.25 393.88C256.12 394.41 255.89 396.05 255.82 396.57Z\\\" fill=\\\"#FFEBD4\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 89\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_45_2\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_46\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<path d=\\\"M259.57 394.29C259.575 394.313 259.575 394.337 259.57 394.36C259.575 394.396 259.575 394.434 259.57 394.47C259.52 394.53 259.4 394.75 259.34 394.84C259.28 394.93 259.27 394.97 259.21 394.97C259.15 394.97 258.79 394.19 258.41 394.19C258.27 394.19 258.07 394.19 258.01 394.71C257.989 394.886 258.026 395.063 258.114 395.216C258.202 395.37 258.338 395.49 258.5 395.56C258.73 395.72 259.45 396.08 259.25 397.56C259.245 397.761 259.199 397.959 259.116 398.142C259.033 398.325 258.913 398.489 258.764 398.624C258.616 398.76 258.441 398.864 258.252 398.93C258.062 398.996 257.861 399.024 257.66 399.01C257.415 399.007 257.178 398.922 256.987 398.767C256.797 398.613 256.664 398.399 256.61 398.16C256.602 398.134 256.602 398.106 256.61 398.08C256.627 398.045 256.647 398.011 256.67 397.98C256.744 397.869 256.824 397.762 256.91 397.66C256.91 397.66 256.97 397.74 257 397.8C257.056 397.926 257.145 398.034 257.258 398.114C257.37 398.193 257.503 398.24 257.64 398.25C257.712 398.256 257.783 398.246 257.851 398.223C257.919 398.199 257.981 398.161 258.034 398.113C258.086 398.064 258.128 398.005 258.157 397.939C258.186 397.873 258.2 397.802 258.2 397.73C258.209 397.526 258.177 397.323 258.104 397.132C258.032 396.941 257.922 396.767 257.78 396.62C257.524 396.453 257.319 396.22 257.187 395.945C257.055 395.67 257.001 395.364 257.03 395.06C257.071 394.692 257.221 394.344 257.462 394.063C257.703 393.781 258.023 393.578 258.38 393.48C258.631 393.501 258.873 393.586 259.082 393.728C259.29 393.87 259.459 394.064 259.57 394.29Z\\\" fill=\\\"#FFEBD4\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 90\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_46_2\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_47\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<path d=\\\"M262.43 394.31C262.447 394.359 262.447 394.411 262.43 394.46C262.43 394.53 262.36 394.57 262.3 394.62C262.24 394.67 261.9 395.03 261.81 395.09C261.75 395.09 261.74 395 261.71 394.95C261.68 394.9 261.62 394.67 261.43 394.67C261.24 394.67 261.07 394.93 260.93 396.01C260.79 397.09 260.93 397.42 261.09 397.42C261.25 397.42 261.3 397.36 261.39 397.1C261.48 396.84 261.49 396.91 261.55 396.91C261.59 396.904 261.63 396.904 261.67 396.91C261.859 396.987 262.053 397.054 262.25 397.11C262.3 397.11 262.31 397.2 262.3 397.29C262.29 397.38 262.3 397.36 262.3 397.4C262.28 397.492 262.253 397.582 262.22 397.67C262.07 398.08 261.7 398.92 260.9 398.92C260.36 398.92 259.58 398.28 259.9 396C260.22 393.72 261.06 393.39 261.54 393.39C262.24 393.45 262.35 394.1 262.43 394.31Z\\\" fill=\\\"#FFEBD4\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 91\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_47_2\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_48\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<path d=\\\"M264.51 395.94H265.51V395.71C265.51 395.58 265.51 395.42 265.56 395.3C265.61 395.18 265.8 393.69 265.81 393.59C265.82 393.49 265.81 393.53 265.88 393.53H266.01C266.039 393.519 266.071 393.519 266.1 393.53C266.109 393.539 266.114 393.552 266.114 393.565C266.114 393.578 266.109 393.591 266.1 393.6C266.104 393.62 266.104 393.64 266.1 393.66C266.1 393.75 266.04 393.97 265.97 394.31C265.9 394.65 265.68 396.26 265.64 396.59L265.4 398.19V398.49C265.396 398.563 265.396 398.637 265.4 398.71C265.4 398.77 265.4 398.76 265.34 398.76H265.15C265.15 398.76 265.15 398.76 265.15 398.68C265.15 398.89 265.24 397.99 265.29 397.58L265.4 396.78L265.47 396.22H265.05H263.65C263.66 396.283 263.66 396.347 263.65 396.41C263.65 396.53 263.65 396.7 263.58 396.87C263.51 397.04 263.51 397.37 263.47 397.69C263.43 398.01 263.39 398.32 263.39 398.47V398.58C263.39 398.76 263.27 398.73 263.19 398.73C263.05 398.716 262.91 398.716 262.77 398.73C262.62 398.73 262.67 398.58 262.71 398.26C262.75 397.94 262.98 396.11 263.04 395.66C263.1 395.21 263.28 393.89 263.31 393.71C263.34 393.53 263.38 393.47 263.44 393.47H263.55H263.67H264C264.1 393.47 264.06 393.61 264.05 393.7C264.04 393.79 263.98 394.18 263.91 394.59L263.79 395.34L263.72 395.78H264.03L264.51 395.94Z\\\" fill=\\\"#FFEBD4\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 92\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_48_2\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_49\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<path d=\\\"M246.21 403.3C246.21 403.2 246.21 402.85 246.21 402.68C246.21 402.51 246.29 401.93 246.3 401.79C246.31 401.65 246.36 401.41 246.41 401.41C246.46 401.41 246.41 401.41 246.5 401.51C246.59 401.61 246.5 401.63 246.58 401.75C246.66 401.87 246.84 402.29 246.93 402.46L247.14 402.85L247.26 403.08C247.259 403.063 247.259 403.047 247.26 403.03V402.88C247.26 402.76 247.26 402.51 247.26 402.29C247.26 402.07 247.32 401.77 247.26 401.63C247.2 401.49 247.26 401.43 247.34 401.43H247.51H247.57H247.63C247.636 401.453 247.636 401.477 247.63 401.5C247.63 401.6 247.63 401.72 247.63 401.9C247.63 402.08 247.63 402.79 247.57 402.99C247.51 403.19 247.57 403.65 247.57 403.71C247.589 403.819 247.589 403.931 247.57 404.04C247.57 404.23 247.57 405.18 247.57 405.24C247.57 405.3 247.57 405.42 247.57 405.42C247.57 405.42 247.5 405.42 247.45 405.29C247.343 405.112 247.246 404.929 247.16 404.74L246.85 404.07C246.809 403.956 246.759 403.846 246.7 403.74L246.6 403.53V403.69C246.6 403.77 246.6 403.98 246.52 404.23C246.44 404.48 246.47 405.16 246.47 405.23C246.47 405.3 246.47 405.44 246.41 405.44C246.35 405.44 246.33 405.38 246.3 405.31C246.27 405.24 246.06 404.62 245.98 404.46C245.9 404.3 245.77 403.96 245.71 403.8C245.65 403.64 245.26 402.69 245.18 402.48C245.1 402.27 244.9 401.74 244.84 401.6C244.831 401.564 244.831 401.526 244.84 401.49H245.14C245.21 401.49 245.23 401.49 245.27 401.65C245.31 401.81 245.54 402.35 245.75 402.76C245.84 402.97 245.93 403.17 246.01 403.33L246.13 403.58V403.5L246.21 403.3Z\\\" fill=\\\"#FFEBD4\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 93\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_49_2\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_50\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<path d=\\\"M251.05 403.39C251.11 403.79 251.31 405.5 250.05 405.5C249.41 405.5 249.05 404.95 248.75 404.39C248.596 404.033 248.479 403.661 248.4 403.28C248.23 402.28 248.67 401.28 249.29 401.28C249.52 401.25 249.755 401.291 249.96 401.4C250.529 401.928 250.911 402.626 251.05 403.39ZM248.93 401.3C248.845 401.291 248.767 401.254 248.706 401.194C248.646 401.134 248.609 401.055 248.6 400.97C248.6 400.81 248.65 400.65 248.8 400.65C248.885 400.653 248.967 400.684 249.032 400.738C249.097 400.792 249.142 400.867 249.16 400.95C249.17 400.988 249.172 401.028 249.166 401.067C249.16 401.106 249.145 401.144 249.124 401.177C249.102 401.21 249.073 401.238 249.04 401.259C249.007 401.28 248.969 401.294 248.93 401.3ZM250.66 403.39C250.5 402.46 250 401.65 249.44 401.65C249.27 401.65 249.14 401.65 249.03 401.81C248.877 402.03 248.769 402.28 248.714 402.542C248.659 402.805 248.658 403.077 248.71 403.34C248.87 404.24 249.27 405.18 249.97 405.18C250.67 405.18 250.81 404.34 250.66 403.39ZM249.96 400.61C250.09 400.61 250.19 400.79 250.22 400.97C250.231 401.007 250.234 401.046 250.227 401.083C250.22 401.121 250.204 401.157 250.18 401.187C250.157 401.218 250.126 401.242 250.091 401.258C250.057 401.274 250.018 401.282 249.98 401.28C249.78 401.28 249.7 401.11 249.67 400.97C249.62 400.65 249.83 400.61 250 400.61H249.96Z\\\" fill=\\\"#FFEBD4\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 94\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_50_2\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_51\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<path d=\\\"M251.65 403.54C251.71 403.8 251.96 405.22 251.98 405.36C252 405.5 251.88 405.5 251.82 405.5C251.76 405.5 251.75 405.41 251.74 405.34C251.711 405.252 251.691 405.162 251.68 405.07C251.675 405.013 251.675 404.957 251.68 404.9C251.68 404.77 251.44 403.35 251.28 402.43C251.22 402.03 251.16 401.73 251.14 401.66C251.137 401.62 251.137 401.58 251.14 401.54C251.14 401.42 251.14 401.41 251.2 401.41H251.9C252.09 401.41 252.8 401.48 252.9 401.98C253.02 402.66 252.26 402.76 252.02 402.76H251.95C252.01 402.81 253.67 404.99 253.87 405.19C254.07 405.39 254.03 405.37 254.04 405.41C253.971 405.426 253.899 405.426 253.83 405.41C253.64 405.41 253.65 405.41 253.58 405.26C253.51 405.11 252.98 404.5 252.69 404.1C252.54 403.9 252.28 403.58 252.06 403.31L251.65 402.82V403.05C251.6 403.26 251.63 403.42 251.65 403.54ZM251.73 402.54C251.87 402.555 252.01 402.555 252.15 402.54C252.39 402.48 252.56 402.41 252.52 402.16C252.48 401.91 252.07 401.79 251.88 401.79H251.39L251.5 402.6L251.73 402.54Z\\\" fill=\\\"#FFEBD4\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 95\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_51_2\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_52\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<path d=\\\"M254.66 401.4H255.48H255.66C255.83 401.4 255.87 401.5 255.87 401.55C255.87 401.6 255.87 401.74 255.93 401.98C255.99 402.22 256 402.33 256.02 402.42C256.04 402.51 256.02 402.57 255.88 402.57H255.06L255.15 403.17C255.15 403.26 255.15 403.44 255.22 403.65C255.33 404.29 255.5 405.24 255.52 405.33C255.52 405.41 255.52 405.4 255.46 405.4H255.15C255.06 405.4 255.06 405.4 255.04 405.2C255.02 405 254.81 403.6 254.76 403.3C254.71 403 254.65 402.7 254.62 402.54H253.8C253.783 402.54 253.767 402.537 253.752 402.53C253.736 402.523 253.723 402.514 253.711 402.501C253.7 402.489 253.692 402.475 253.686 402.459C253.681 402.443 253.679 402.427 253.68 402.41C253.68 402.36 253.61 401.91 253.57 401.65C253.57 401.57 253.57 401.51 253.57 401.48C253.57 401.39 253.57 401.4 253.64 401.4H254.1H254.66Z\\\" fill=\\\"#FFEBD4\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 96\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_52_2\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_53\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<path d=\\\"M256.57 403.22C256.5 402.77 256.47 402.73 256.41 402.39C256.35 402.05 256.3 401.71 256.28 401.54C256.26 401.37 256.28 401.42 256.35 401.42H256.42C256.49 401.42 256.58 401.42 256.79 401.42C257 401.42 257.3 401.37 257.48 401.37H258.01C258.1 401.37 258.12 401.37 258.13 401.53C258.14 401.69 258.2 401.79 258.23 401.97C258.26 402.15 258.23 402.08 258.23 402.18C258.23 402.28 258.23 402.27 258.18 402.27C258.144 402.276 258.106 402.276 258.07 402.27C257.934 402.256 257.796 402.256 257.66 402.27H256.66C256.6 402.27 256.61 402.27 256.66 402.39C256.71 402.51 256.66 402.74 256.74 402.94L256.79 403.28C256.785 403.34 256.785 403.4 256.79 403.46H257.25H257.74H257.97C258.03 403.46 258.04 403.46 258.05 403.53C258.043 403.586 258.043 403.644 258.05 403.7C258.05 403.81 258.05 403.87 258.1 404.01C258.15 404.15 258.1 404.1 258.1 404.1H258.01H257.54C257.356 404.104 257.172 404.121 256.99 404.15H257L257.1 404.72H257.83H258.42H258.62C258.7 404.72 258.72 404.77 258.73 404.84C258.74 404.91 258.73 404.92 258.73 404.96C258.73 405 258.73 405.19 258.79 405.36C258.85 405.53 258.74 405.48 258.59 405.48H257.76H257.02C257.02 405.48 257.02 405.48 257.02 405.38C257.02 405.28 257.02 405.24 257.02 405.17C257.02 405.1 257.02 405.04 256.97 404.92L256.84 404.14C256.63 403.76 256.64 403.66 256.57 403.22Z\\\" fill=\\\"#FFEBD4\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 97\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_53_2\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_54\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<path d=\\\"M259.3 403.54C259.36 403.8 259.6 405.22 259.63 405.36C259.66 405.5 259.52 405.5 259.46 405.5C259.4 405.5 259.39 405.41 259.38 405.34C259.37 405.27 259.38 405.19 259.32 405.07C259.315 405.013 259.315 404.957 259.32 404.9C259.32 404.77 259.08 403.35 258.93 402.43C258.893 402.171 258.843 401.914 258.78 401.66C258.78 401.61 258.78 401.57 258.78 401.54C258.78 401.51 258.78 401.41 258.84 401.41H259.54C259.74 401.41 260.44 401.48 260.54 401.98C260.65 402.66 259.89 402.76 259.65 402.76H259.59C259.59 402.81 261.3 404.99 261.51 405.19C261.72 405.39 261.66 405.37 261.67 405.41C261.604 405.426 261.536 405.426 261.47 405.41C261.27 405.41 261.28 405.41 261.21 405.26C261.14 405.11 260.61 404.5 260.32 404.1C260.17 403.9 259.91 403.58 259.69 403.31L259.29 402.82V403.05C259.271 403.213 259.275 403.378 259.3 403.54ZM259.38 402.54C259.516 402.555 259.654 402.555 259.79 402.54C260.03 402.48 260.21 402.41 260.16 402.16C260.11 401.91 259.71 401.79 259.52 401.79H259L259.1 402.6L259.38 402.54Z\\\" fill=\\\"#FFEBD4\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 98\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_54_2\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_55\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<path d=\\\"M263.86 404.69C263.99 405.51 263.07 405.46 262.86 405.46H262.12C262.01 405.46 261.97 405.36 261.95 405.24L261.75 403.97C261.75 403.86 261.75 403.78 261.75 403.69C261.724 403.558 261.707 403.424 261.7 403.29C261.7 402.97 261.51 402.09 261.5 401.93C261.49 401.77 261.5 401.83 261.5 401.77C261.5 401.71 261.45 401.51 261.44 401.48C261.44 401.48 261.44 401.48 261.44 401.42C261.64 401.374 261.845 401.347 262.05 401.34C262.55 401.34 263.05 401.5 263.19 402.39C263.227 402.535 263.234 402.685 263.212 402.833C263.19 402.981 263.138 403.123 263.06 403.25C263.003 403.334 262.923 403.4 262.83 403.44C263.092 403.546 263.324 403.716 263.503 403.934C263.683 404.153 263.806 404.412 263.86 404.69ZM262.25 403.31V403.37C262.363 403.368 262.474 403.34 262.575 403.289C262.676 403.237 262.763 403.163 262.831 403.072C262.899 402.981 262.945 402.876 262.965 402.765C262.986 402.654 262.981 402.539 262.95 402.43C262.8 401.55 262.37 401.51 261.95 401.51V401.88C261.95 402.09 262.02 402.33 262.04 402.49L262.15 403.15C262.192 403.198 262.225 403.252 262.25 403.31ZM263.56 404.69C263.539 404.468 263.462 404.255 263.336 404.072C263.21 403.888 263.039 403.739 262.84 403.64C262.667 403.566 262.479 403.531 262.29 403.54C262.29 403.54 262.29 403.61 262.29 403.68C262.29 403.75 262.4 404.25 262.42 404.35C262.44 404.45 262.42 404.48 262.42 404.62C262.42 404.76 262.53 405.12 262.54 405.22C262.55 405.32 262.61 405.31 262.7 405.31C263.38 405.35 263.62 405.08 263.56 404.69Z\\\" fill=\\\"#FFEBD4\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 99\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_55_2\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_56\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<path d=\\\"M265.39 404.2C265.67 404.2 265.64 403.84 265.61 403.66C265.58 403.48 265.52 403.02 265.46 402.66C265.467 402.59 265.467 402.52 265.46 402.45C265.41 402.17 265.3 401.65 265.28 401.52C265.26 401.39 265.28 401.33 265.36 401.33H266C266.06 401.33 266.11 401.33 266.15 401.5C266.19 401.67 266.22 401.87 266.27 402.18C266.32 402.49 266.44 403.18 266.48 403.41C266.52 403.64 266.72 405.41 265.61 405.41C265.256 405.398 264.917 405.259 264.657 405.019C264.396 404.778 264.231 404.452 264.19 404.1C264.183 404.024 264.183 403.946 264.19 403.87C264.12 403.46 264.03 402.77 263.97 402.47C263.91 402.17 263.81 401.63 263.8 401.47C263.79 401.31 263.74 401.26 263.87 401.26H264.11H264.26H264.62C264.68 401.26 264.69 401.26 264.71 401.38L265.1 403.68C265.06 403.87 265.1 404.2 265.39 404.2Z\\\" fill=\\\"#FFEBD4\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 100\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_56_2\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_57\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<path d=\\\"M268.79 402C268.79 402.05 268.85 402.08 268.85 402.11C268.85 402.14 268.85 402.2 268.77 402.24C268.69 402.28 268.51 402.55 268.44 402.6C268.39 402.6 268.36 402.53 268.32 402.49C268.28 402.45 268.17 402.28 268 402.28C267.83 402.28 267.73 402.48 267.87 403.28C268.01 404.08 268.25 404.36 268.37 404.36C268.49 404.36 268.54 404.31 268.56 404.11C268.58 403.91 268.61 403.97 268.65 403.97C268.69 403.97 268.74 403.97 268.78 403.97C268.82 403.97 269.21 404.09 269.35 404.12C269.49 404.15 269.42 404.19 269.44 404.26V404.35C269.45 404.416 269.45 404.484 269.44 404.55C269.452 404.674 269.439 404.8 269.401 404.919C269.363 405.038 269.3 405.148 269.218 405.242C269.135 405.335 269.034 405.411 268.921 405.464C268.808 405.517 268.685 405.546 268.56 405.55C268.07 405.55 267.21 405.06 266.91 403.32C266.61 401.58 267.33 401.32 267.75 401.32C267.967 401.334 268.177 401.404 268.36 401.523C268.542 401.642 268.69 401.806 268.79 402Z\\\" fill=\\\"#FFEBD4\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 101\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_57_2\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_58\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<path d=\\\"M271.07 403.21H272V403.04C272 402.94 272 402.82 271.94 402.73L271.75 401.43C271.75 401.38 271.75 401.38 271.75 401.38H272C272.015 401.382 272.029 401.389 272.04 401.4C272.051 401.411 272.058 401.425 272.06 401.44C272.06 401.5 272.06 401.68 272.06 401.94C272.06 402.2 272.27 403.42 272.32 403.68C272.37 403.94 272.47 404.79 272.49 404.89C272.51 404.99 272.49 405.04 272.49 405.12C272.49 405.2 272.49 405.25 272.49 405.29H272.33C272.33 405.29 272.28 405.29 272.28 405.23C272.28 405.38 272.2 404.7 272.14 404.39C272.14 404.27 272.08 404.01 272.04 403.78L271.97 403.35H270.33C270.33 403.4 270.33 403.45 270.33 403.5C270.33 403.55 270.33 403.72 270.38 403.85L270.48 404.47C270.507 404.672 270.547 404.873 270.6 405.07V405.16C270.6 405.29 270.52 405.27 270.45 405.27C270.327 405.261 270.203 405.261 270.08 405.27C269.95 405.27 269.95 405.15 269.91 404.91C269.87 404.67 269.62 403.27 269.57 402.91C269.52 402.55 269.35 401.56 269.32 401.42C269.29 401.28 269.32 401.24 269.38 401.24H270C270.09 401.24 270.09 401.35 270.1 401.42C270.11 401.49 270.16 401.78 270.2 402.1L270.27 402.67L270.32 403.01H270.6L271.07 403.21Z\\\" fill=\\\"#FFEBD4\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Group 9\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector5656231 102\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_58_2\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_59\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<path d=\\\"M277.69 367H279.52V369.76H279.18V369.42H277.69V371.37H277.35V369.42H275.87V369.79H275.55V367H277.35V365.93H277.79C277.784 365.952 277.771 365.972 277.753 365.986C277.735 366 277.713 366.009 277.69 366.01V367ZM275.87 369H277.35V367.4H275.87V369ZM277.69 369H279.18V367.4H277.69V369Z\\\" fill=\\\"#FFEBD4\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 103\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_59_2\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_60\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<path d=\\\"M280.37 366.22H284.5V371.41H284.17V371.12H280.69V371.41H280.37V366.22ZM280.69 370.76H284.17V366.58H280.69V370.76ZM280.93 369.86L282.44 369.53V369.79L281.08 370.14C281.08 370.159 281.074 370.178 281.063 370.194C281.053 370.21 281.038 370.222 281.02 370.23L280.93 369.86ZM282.81 367.71C282.848 368.197 282.915 368.681 283.01 369.16C283.194 368.797 283.325 368.41 283.4 368.01L283.75 368.11C283.75 368.11 283.75 368.17 283.65 368.17C283.541 368.653 283.362 369.118 283.12 369.55C283.24 369.9 283.4 370.16 283.57 370.16C283.74 370.16 283.69 369.91 283.73 369.53C283.79 369.604 283.861 369.668 283.94 369.72C283.89 370.26 283.77 370.51 283.58 370.51H283.48C283.24 370.45 283.07 370.22 282.92 369.87C282.731 370.15 282.494 370.394 282.22 370.59C282.172 370.501 282.112 370.42 282.04 370.35C282.35 370.136 282.612 369.86 282.81 369.54C282.667 368.945 282.574 368.34 282.53 367.73H281V367.43H282.53C282.53 367.21 282.53 366.99 282.53 366.76H282.92C282.92 366.76 282.92 366.83 282.82 366.84V367.4H283.94V367.7L282.81 367.71ZM281.16 368.11H282.27V369.27H281.16V368.11ZM282.02 369.01V368.37H281.4V369L282.02 369.01ZM283.22 366.69C283.424 366.793 283.609 366.928 283.77 367.09L283.61 367.31C283.448 367.142 283.263 366.997 283.06 366.88L283.22 366.69Z\\\" fill=\\\"#FFEBD4\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 104\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_60_2\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_61\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<path d=\\\"M285.05 367.26V366.94H286.87V367.26H285.05ZM286.73 369.33V371.05H285.56V371.32H285.27V369.32L286.73 369.33ZM286.73 367.73V368.06H285.29V367.73H286.73ZM285.29 368.85V368.53H286.73V368.85H285.29ZM286.71 366.16V366.48H285.31V366.16H286.71ZM286.44 369.66H285.57V370.66H286.44V369.66ZM289.44 366.25V370.84C289.44 371.36 289.26 371.39 288.33 371.39C288.303 371.247 288.262 371.106 288.21 370.97H289C289.09 370.97 289.12 370.97 289.12 370.82V366.6H287V366.24L289.44 366.25ZM288.74 367.25V367.6H287V367.25H288.74ZM288.55 370.05H287.45V370.49H287.15V368.16H288.55V370.05ZM288.26 368.51H287.45V369.7H288.26V368.51Z\\\" fill=\\\"#FFEBD4\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 105\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_61_2\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_62\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<path d=\\\"M294 369.61H294.46V370H290V369.62H290.5V366.68H291.57V365.94H291.98C291.971 365.96 291.957 365.978 291.94 365.992C291.922 366.006 291.902 366.016 291.88 366.02V366.64H292.66V365.9H293.07C293.066 365.921 293.055 365.941 293.038 365.955C293.022 365.97 293.002 365.978 292.98 365.98V366.61H294V369.61ZM291.76 370.36C291.744 370.367 291.727 370.371 291.71 370.371C291.693 370.371 291.676 370.367 291.66 370.36C291.235 370.766 290.749 371.103 290.22 371.36C290.144 371.251 290.057 371.15 289.96 371.06C290.494 370.813 290.982 370.474 291.4 370.06L291.76 370.36ZM291.48 367.04H290.73V368.14H291.48V367.04ZM290.73 368.51V369.61H291.48V368.51H290.73ZM292.57 367.04H291.79V368.14H292.57V367.04ZM292.57 369.61V368.51H291.79V369.61H292.57ZM294.1 371.39C293.656 371.022 293.184 370.688 292.69 370.39L292.93 370.12C293.445 370.414 293.937 370.749 294.4 371.12L294.1 371.39ZM293.67 367.04H292.89V368.14H293.67V367.04ZM292.89 368.51V369.61H293.67V368.51H292.89Z\\\" fill=\\\"#FFEBD4\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 106\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_62_2\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_63\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<path d=\\\"M269.83 366.4H258.19C257.849 367.583 257.849 368.837 258.19 370.02H269.83C269.445 368.844 269.445 367.576 269.83 366.4Z\\\" fill=\\\"#FFEBD4\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 107\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_63_2\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_64\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<path d=\\\"M273.73 368.19C273.73 367.942 273.656 367.7 273.519 367.494C273.381 367.289 273.185 367.129 272.956 367.034C272.727 366.94 272.475 366.916 272.232 366.965C271.99 367.014 271.767 367.134 271.593 367.31C271.418 367.486 271.3 367.709 271.253 367.952C271.206 368.195 271.232 368.447 271.328 368.675C271.424 368.904 271.586 369.098 271.793 369.234C272 369.37 272.242 369.442 272.49 369.44C272.82 369.437 273.135 369.304 273.367 369.07C273.6 368.836 273.73 368.52 273.73 368.19Z\\\" fill=\\\"#FFEBD4\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 108\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_64_2\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_65\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<path d=\\\"M312.83 370H301.18C300.845 368.817 300.845 367.563 301.18 366.38H312.83C312.44 367.555 312.44 368.825 312.83 370Z\\\" fill=\\\"#FFEBD4\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 109\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_65_2\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<g id=\\\"Vector_66\\\" style=\\\"mix-blend-mode:overlay\\\">\\n<path d=\\\"M296.79 368.23C296.786 368.48 296.857 368.725 296.994 368.934C297.131 369.143 297.327 369.306 297.557 369.402C297.788 369.499 298.042 369.524 298.286 369.475C298.531 369.426 298.756 369.304 298.931 369.126C299.106 368.948 299.224 368.721 299.269 368.476C299.314 368.23 299.285 367.977 299.185 367.748C299.085 367.519 298.918 367.326 298.707 367.192C298.496 367.059 298.25 366.992 298 367C297.678 367.008 297.372 367.14 297.146 367.37C296.92 367.6 296.793 367.908 296.79 368.23Z\\\" fill=\\\"#FFEBD4\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<path id=\\\"Vector5656231 110\\\" d=\\\"M98.18 384.87C98.18 387.21 97.0667 389.543 94.84 391.87V382C97.0667 379.66 98.18 377.327 98.18 375V384.87Z\\\" fill=\\\"#C61C6F\\\"\\\/>\\n<path id=\\\"Vector5656231 111\\\" d=\\\"M94.84 381.96V391.89L87.92 389.42V379.49L94.84 381.96Z\\\" fill=\\\"#EB6D79\\\"\\\/>\\n<path id=\\\"Vector5656231 112\\\" d=\\\"M90.41 373C90.4987 373.346 90.5424 373.703 90.54 374.06C90.54 375.68 89.69 377.44 87.99 379.36C87.1846 378.681 86.3175 378.078 85.4 377.56C82.1322 375.662 78.492 374.496 74.73 374.14C71.0166 373.776 67.2677 374.115 63.68 375.14C60.3262 376.078 57.0991 377.422 54.07 379.14C51.3465 380.616 48.8782 382.52 46.76 384.78C46.0241 383.987 45.4289 383.073 45 382.08C44.691 381.384 44.5309 380.631 44.53 379.87C44.587 378.333 45.1533 376.859 46.14 375.68C48.3627 373.028 51.0798 370.834 54.14 369.22C57.1691 367.502 60.3962 366.158 63.75 365.22C67.3377 364.195 71.0866 363.856 74.8 364.22C78.562 364.576 82.2022 365.742 85.47 367.64C88.29 369.32 89.9367 371.107 90.41 373Z\\\" fill=\\\"#CE5F6B\\\"\\\/>\\n<path id=\\\"Vector5656231 113\\\" d=\\\"M79.4 314.82C79.4486 313.316 78.9513 311.846 78 310.68C77.4983 310.087 76.8694 309.616 76.16 309.3C75.4713 308.997 74.7389 308.804 73.99 308.73C70.9968 308.622 68.0011 308.854 65.06 309.42L53.32 311.23V326.23L66.02 324.23C68.5445 323.924 71.0287 323.347 73.43 322.51C77 321.09 79.4 318.63 79.4 314.82ZM81.84 336.22C81.9007 334.535 81.2974 332.894 80.16 331.65C79.7172 331.181 79.2045 330.783 78.64 330.47C77.6654 329.934 76.5953 329.594 75.49 329.47C72.6171 329.264 69.7296 329.432 66.9 329.97L53.32 332.07V349.14C68.21 346.83 71.22 346.44 73.23 345.82C74.8184 345.359 76.331 344.668 77.72 343.77C78.9521 342.939 79.9782 341.838 80.72 340.55C81.4755 339.233 81.8624 337.738 81.84 336.22ZM89.9 335C89.8911 337.363 89.293 339.686 88.16 341.76C87.0989 343.784 85.6317 345.568 83.85 347C79.54 350.4 73.36 351.91 67.94 352.74L45.54 356.21V306.58L67.54 303.17C71.1019 302.478 74.7581 302.42 78.34 303C80.82 303.454 83.0689 304.746 84.71 306.66C85.2766 307.336 85.7539 308.082 86.13 308.88C87.68 312.17 87.13 315.88 84.97 319.17C84.5679 319.786 84.1164 320.368 83.62 320.91C82.2186 322.404 80.5923 323.669 78.8 324.66C82.3467 324.987 85.0767 326.067 86.99 327.9C87.8203 328.666 88.4987 329.582 88.99 330.6C89.6147 331.981 89.9255 333.484 89.9 335Z\\\" fill=\\\"#5198BF\\\"\\\/>\\n<path id=\\\"Vector5656231 114\\\" d=\\\"M85.91 324C86.9433 326.207 87.97 328.417 88.99 330.63C88.4987 329.612 87.8202 328.696 86.99 327.93C85.0833 326.097 82.3533 325.017 78.8 324.69C80.5923 323.699 82.2186 322.434 83.62 320.94C84.5459 321.76 85.2945 322.76 85.82 323.88L85.91 324Z\\\" fill=\\\"#437F9F\\\"\\\/>\\n<path id=\\\"Vector5656231 115\\\" d=\\\"M44.48 379.87C44.4809 380.631 44.641 381.384 44.95 382.08C45.3931 383.081 46.0054 383.997 46.76 384.79C47.7804 385.844 48.9495 386.744 50.23 387.46C53.5483 389.34 57.269 390.396 61.08 390.54C65.4052 390.715 69.7196 389.989 73.75 388.41L78 392.53C72.5161 394.491 66.6945 395.33 60.88 395C55.5867 394.708 50.434 393.188 45.83 390.56C41.1633 387.893 38.3367 385.173 37.35 382.4C37.0221 381.517 36.8528 380.582 36.85 379.64C36.9201 377.538 37.6436 375.511 38.92 373.84C41.3879 370.535 44.5439 367.806 48.17 365.84C56.9795 360.709 67.2926 358.784 77.36 360.39C81.9283 361.109 86.3311 362.64 90.36 364.91C94.66 367.403 97.1833 370.127 97.93 373.08C98.0858 373.684 98.1631 374.306 98.16 374.93C98.16 377.27 97.0467 379.603 94.82 381.93L87.9 379.46L87.97 379.37C89.67 377.45 90.52 375.69 90.52 374.07C90.5224 373.713 90.4787 373.356 90.39 373.01C89.9233 371.09 88.2567 369.3 85.39 367.64C82.1222 365.742 78.482 364.576 74.72 364.22C71.0066 363.856 67.2577 364.195 63.67 365.22C60.3162 366.158 57.0891 367.502 54.06 369.22C50.9998 370.834 48.2828 373.028 46.06 375.68C45.0842 376.863 44.5285 378.337 44.48 379.87Z\\\" fill=\\\"#EFA3AE\\\"\\\/>\\n<path id=\\\"Vector5656231 116\\\" d=\\\"M83.05 302.14L86.17 308.88C85.7939 308.082 85.3166 307.336 84.75 306.66C83.1088 304.746 80.86 303.454 78.38 303C74.7981 302.42 71.1419 302.478 67.58 303.17L45.58 306.58L42.4 299.8L64.4 296.39C67.9619 295.698 71.6181 295.64 75.2 296.22C77.68 296.674 79.9288 297.966 81.57 299.88C82.1592 300.566 82.6567 301.326 83.05 302.14Z\\\" fill=\\\"#407C96\\\"\\\/>\\n<path id=\\\"Vector5656231 117\\\" d=\\\"M81.84 336.22C81.8556 337.752 81.4547 339.259 80.68 340.58C79.9382 341.868 78.9121 342.969 77.68 343.8C76.291 344.698 74.7784 345.389 73.19 345.85C71.19 346.47 68.19 346.85 53.28 349.17V341.9C64.93 340.1 68.08 339.68 70.04 339.07C71.644 338.608 73.1707 337.91 74.57 337C75.804 336.175 76.8307 335.077 77.57 333.79C78.1757 332.773 78.5544 331.637 78.68 330.46C79.2445 330.773 79.7572 331.171 80.2 331.64C81.3254 332.893 81.9142 334.537 81.84 336.22Z\\\" fill=\\\"#437F9F\\\"\\\/>\\n<path id=\\\"Vector5656231 118\\\" d=\\\"M78 310.68C78.9513 311.846 79.4487 313.316 79.4001 314.82C79.4001 318.63 76.9801 321.09 73.4001 322.55C71.002 323.386 68.5211 323.963 66 324.27L53.3 326.27V319L62.85 317.52C65.374 317.211 67.8581 316.635 70.2601 315.8C73.2601 314.56 75.64 312.53 76.14 309.33C76.8536 309.634 77.4895 310.096 78 310.68Z\\\" fill=\\\"#437F9F\\\"\\\/>\\n<path id=\\\"Vector5656231 119\\\" d=\\\"M36.85 389.55V379.62C36.8528 380.562 37.0221 381.497 37.35 382.38C38.37 385.147 41.1967 387.867 45.83 390.54C50.4323 393.175 55.5851 394.702 60.88 395C66.6945 395.33 72.5161 394.491 78 392.53V402.46C72.5159 404.419 66.6933 405.252 60.88 404.91C55.5883 404.617 50.4366 403.101 45.83 400.48C41.1633 397.813 38.3367 395.09 37.35 392.31C37.0221 391.427 36.8528 390.492 36.85 389.55Z\\\" fill=\\\"#EB6D79\\\"\\\/>\\n<path id=\\\"Vector5656231 120\\\" d=\\\"M42.4 312.54V299.8L45.54 306.58V356.23L42.4 349.45V338.18V312.54Z\\\" fill=\\\"#33647D\\\"\\\/>\\n<path id=\\\"Vector5656231 121\\\" d=\\\"M42.4 312.54V338.18L40.24 339.42L22.64 279.61L31.24 274.64L42.4 312.54Z\\\" fill=\\\"#CE5F6B\\\"\\\/>\\n<path id=\\\"Vector5656231 122\\\" d=\\\"M23.74 299.57C23.24 297.76 22.79 296.12 22.38 294.57C21.05 289.64 20.14 286.11 19.45 282.93C18.9273 285.712 18.1507 288.44 17.13 291.08C15.5833 295.08 14.01 299.027 12.41 302.92L27 311.37C25.72 306.76 24.65 302.89 23.74 299.57ZM22.64 279.57L40.24 339.39L33.76 335.65L28.76 317.71L16.26 310.49L10.77 307.33L6 319.67L0 316.18L16.51 276.07L22.64 279.57Z\\\" fill=\\\"#EB6D79\\\"\\\/>\\n<path id=\\\"Vector5656231 123\\\" d=\\\"M31.24 274.64L22.64 279.61L16.51 276.06L25.11 271.1L31.24 274.64Z\\\" fill=\\\"#EFA3AE\\\"\\\/>\\n<path id=\\\"Vector5656231 124\\\" d=\\\"M27 311.37L12.41 303L21.01 298L23.74 299.58C24.65 302.89 25.72 306.76 27 311.37Z\\\" fill=\\\"#EFA3AE\\\"\\\/>\\n<path id=\\\"Vector5656231 125\\\" d=\\\"M19.45 283C20.14 286.18 21.05 289.71 22.38 294.64C21.93 295.77 21.47 296.9 21.01 298.02L12.41 303.02C14.01 299.1 15.5833 295.153 17.13 291.18C18.1525 288.53 18.9291 285.792 19.45 283Z\\\" fill=\\\"#C61C6F\\\"\\\/>\\n<path id=\\\"Vector5656231 126\\\" d=\\\"M16.2501 310.52L14.6401 314.71L6.04004 319.67L10.7601 307.36L16.2501 310.52Z\\\" fill=\\\"#C61C6F\\\"\\\/>\\n<g id=\\\"Group 10\\\" style=\\\"mix-blend-mode:multiply\\\">\\n<g id=\\\"Vector5656231 127\\\" style=\\\"mix-blend-mode:multiply\\\" opacity=\\\"0.36\\\">\\n<g id=\\\"Vector_66_2\\\" style=\\\"mix-blend-mode:multiply\\\" opacity=\\\"0.36\\\">\\n<g id=\\\"Vector_67\\\" style=\\\"mix-blend-mode:multiply\\\" opacity=\\\"0.36\\\">\\n<path d=\\\"M83.66 320.91C85.55 322.41 86.3 324.74 87.21 326.72C87.77 327.92 88.15 328.86 88.73 330.05C89.4544 331.582 89.8517 333.248 89.8964 334.943C89.9412 336.637 89.6325 338.322 88.99 339.89C88.4945 340.99 87.9438 342.065 87.34 343.11C88.16 343.03 88.8 342.94 89.44 342.91C92.05 342.79 94.65 342.67 97.26 342.59C98.16 342.59 99.08 342.49 99.72 343.44C99.88 343.68 100.56 343.63 101 343.61C104.21 343.45 107.43 343.28 110.64 343.06C111.119 342.991 111.607 343.097 112.013 343.36C112.42 343.623 112.717 344.025 112.85 344.49C113.64 346.36 114.53 348.2 115.46 350.25C114.931 350.481 114.386 350.674 113.83 350.83C110.47 351.47 107.12 352.13 103.74 352.68C98.15 353.58 92.54 354.39 86.94 355.28C83.2201 355.95 79.4497 356.302 75.67 356.33C66.25 356.23 45.54 356.23 45.54 356.23V306.58L53.92 305.28C53.92 305.28 63.63 303.66 70.16 302.74C73.73 302.6 76.61 302.22 79.7 303.39C80.9832 303.76 82.1798 304.382 83.22 305.22C84.33 306.047 85.2443 307.108 85.8976 308.328C86.5509 309.549 86.9273 310.898 87 312.28C87.12 314.46 86.75 316.11 85 319.17C84.63 319.7 84.13 320.25 83.66 320.91ZM53.32 341.91C53.32 341.91 60.71 342.75 64.37 342.07C67.18 341.56 70.04 341.24 72.68 340.07C74.3392 339.426 75.7903 338.34 76.8762 336.929C77.9621 335.519 78.6412 333.839 78.84 332.07C79.03 330.69 78.93 330.5 77.64 330.01C75.3004 329.345 72.8462 329.185 70.44 329.54C65.28 330.18 53.32 332.1 53.32 332.1V341.91ZM53.32 318.98C53.32 318.98 62.65 319.39 67.02 318.32C69.2428 317.926 71.3564 317.064 73.22 315.79C74.8859 314.561 75.9999 312.725 76.32 310.68C76.51 309.57 76.32 309.21 75.2 308.89C74.7574 308.764 74.3001 308.697 73.84 308.69C72.4568 308.62 71.0706 308.64 69.69 308.75C65.04 309.35 53.32 311.24 53.32 311.24V318.98Z\\\" fill=\\\"#5198BF\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 128\\\" style=\\\"mix-blend-mode:multiply\\\">\\n<g id=\\\"Vector_67_2\\\" style=\\\"mix-blend-mode:multiply\\\">\\n<g id=\\\"Vector_68\\\" style=\\\"mix-blend-mode:multiply\\\">\\n<path d=\\\"M51.5501 388.14C48.7801 386.81 46.4901 385.21 45.0601 382.32C44.0601 380.37 44.4001 378.78 45.3201 376.81C46.2839 375.187 47.5541 373.768 49.0601 372.63C54.5627 368.144 61.1958 365.261 68.2301 364.3C70.1304 364.109 72.0413 364.046 73.9501 364.11C73.9501 365.7 73.9501 367.61 73.8601 369.26C73.7701 370.91 75.0201 372.64 75.2101 374.26C73.2701 374.75 71.2101 374.94 69.4501 375.46C64.9021 376.781 60.6372 378.93 56.8701 381.8C54.528 383.362 52.682 385.562 51.5501 388.14Z\\\" fill=\\\"#B4A8C3\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 129\\\" style=\\\"mix-blend-mode:multiply\\\">\\n<g id=\\\"Vector_68_2\\\" style=\\\"mix-blend-mode:multiply\\\">\\n<g id=\\\"Vector_69\\\" style=\\\"mix-blend-mode:multiply\\\">\\n<path d=\\\"M10.7601 307.36L16.2501 310.52C16.1001 311.14 15.7401 311.78 15.5601 312.52C15.97 312.67 16.3914 312.787 16.8201 312.87C19.9656 313.315 22.9872 314.397 25.7001 316.05C27.9701 317.29 28.8901 318.87 29.7701 321.33C29.7701 321.33 30.3701 323.49 30.8701 325.33C30.9901 325.76 31.6801 328.02 31.8201 328.74C30.4301 328 29.0001 327 27.9001 326.34C26.2501 325.39 24.5701 324.5 22.9701 323.47C21.8222 322.8 20.5496 322.371 19.2301 322.21C14.9901 321.48 10.7501 320.71 6.51004 319.94C6.41004 319.94 6.33004 319.86 6.04004 319.71C7.51004 315.68 9.09004 311.47 10.7601 307.36Z\\\" fill=\\\"#B4A8C3\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 130\\\" style=\\\"mix-blend-mode:multiply\\\">\\n<g id=\\\"Vector_69_2\\\" style=\\\"mix-blend-mode:multiply\\\">\\n<g id=\\\"Vector_70\\\" style=\\\"mix-blend-mode:multiply\\\">\\n<path d=\\\"M60.71 395C66.5772 395.34 72.4537 394.514 78 392.57V398.17C78.3888 398.271 78.7883 398.325 79.19 398.33C79.7195 398.26 80.2582 398.332 80.7504 398.539C81.2427 398.747 81.6706 399.082 81.99 399.51C82.84 400.51 83.79 401.39 84.78 402.4C76.97 405.47 68.92 405.03 60.78 404.9C60.58 401.6 60.66 398.43 60.71 395Z\\\" fill=\\\"#B4A8C3\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 131\\\" style=\\\"mix-blend-mode:multiply\\\">\\n<g id=\\\"Vector_70_2\\\" style=\\\"mix-blend-mode:multiply\\\">\\n<g id=\\\"Vector_71\\\" style=\\\"mix-blend-mode:multiply\\\">\\n<path d=\\\"M94.8401 391.89V382C96.7937 380.169 97.9862 377.67 98.1801 375C98.5501 375.15 98.6901 375.81 98.9501 376C100.506 376.969 101.892 378.189 103.05 379.61C104.168 380.915 104.836 382.546 104.955 384.261C105.074 385.975 104.637 387.683 103.71 389.13C103.5 389.47 103.26 389.8 103.04 390.13C102.734 390.74 102.244 391.238 101.639 391.554C101.034 391.87 100.345 391.988 99.6701 391.89C98.0618 391.786 96.4484 391.786 94.8401 391.89Z\\\" fill=\\\"#B4A8C3\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 132\\\" style=\\\"mix-blend-mode:multiply\\\">\\n<g id=\\\"Vector_71_2\\\" style=\\\"mix-blend-mode:multiply\\\">\\n<g id=\\\"Vector_72\\\" style=\\\"mix-blend-mode:multiply\\\">\\n<path d=\\\"M21.0001 298C21.7401 298.45 23.1701 299.16 23.7401 299.59C23.7797 299.834 23.8365 300.074 23.9101 300.31C24.4001 301.87 24.7701 303.47 25.2501 305.31C20.8801 304.64 16.7301 303.84 12.4401 303.01C14.6601 296.51 18.3301 289.85 19.4401 283.01C19.6701 283.92 20.0301 285.7 20.2701 286.61C20.8001 288.7 21.7501 292.61 22.3701 294.61C22.1981 295.125 21.9805 295.624 21.7201 296.1C21.4475 296.72 21.2071 297.355 21.0001 298Z\\\" fill=\\\"#B4A8C3\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"shadows\\\" style=\\\"mix-blend-mode:multiply\\\" filter=\\\"url(#filter0_d)\\\">\\n<g id=\\\"Vector5656231 133\\\" style=\\\"mix-blend-mode:multiply\\\" opacity=\\\"0.15\\\">\\n<g id=\\\"Vector_72_2\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\" filter=\\\"url(#filter1_d)\\\">\\n<g id=\\\"Vector_73\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\">\\n<path d=\\\"M123.58 181.61C95.3599 186.23 79.7699 149.61 78.4199 143.52C79.0799 141.2 83.7899 135.86 86.9099 139.86C104.28 162.22 108.2 158.8 121.57 163.06C134.64 167.23 131.78 180.26 123.58 181.61Z\\\" fill=\\\"black\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 134\\\" style=\\\"mix-blend-mode:multiply\\\" opacity=\\\"0.15\\\">\\n<g id=\\\"Vector_73_2\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\" filter=\\\"url(#filter2_d)\\\">\\n<g id=\\\"Vector_74\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\">\\n<path d=\\\"M167.18 156.56C169 153.95 162.95 142.05 159.7 143.56C137.87 153.77 131.62 160.83 114.39 160.69C103.53 160.6 110.59 176.11 115.01 180.96C129.72 187.87 159 168.28 167.18 156.56Z\\\" fill=\\\"black\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 135\\\" style=\\\"mix-blend-mode:multiply\\\" opacity=\\\"0.15\\\">\\n<g id=\\\"Vector_74_2\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\" filter=\\\"url(#filter3_d)\\\">\\n<g id=\\\"Vector_75\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\">\\n<path d=\\\"M114.52 178.4C96.1599 173.2 87.0899 158.4 78.6899 142.84C78.5834 143.06 78.4932 143.287 78.4199 143.52C79.7699 149.58 95.3599 186.23 123.58 181.61C125.429 181.301 127.115 180.361 128.35 178.95C123.745 179.605 119.059 179.418 114.52 178.4Z\\\" fill=\\\"black\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 136\\\" style=\\\"mix-blend-mode:multiply\\\" opacity=\\\"0.15\\\">\\n<g id=\\\"Vector_75_2\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\" filter=\\\"url(#filter4_d)\\\">\\n<g id=\\\"Vector_76\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\">\\n<path d=\\\"M114.52 178.4C113.89 178.22 113.3 178 112.7 177.79C113.37 178.926 114.139 180.001 115 181C129.71 187.91 159 168.32 167.17 156.6C167.54 156.07 164.76 147.53 164.57 146.42C150.92 161.17 136 179 114.52 178.4Z\\\" fill=\\\"black\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 137\\\" style=\\\"mix-blend-mode:multiply\\\" opacity=\\\"0.15\\\">\\n<g id=\\\"Vector_76_2\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\" filter=\\\"url(#filter5_d)\\\">\\n<g id=\\\"Vector_77\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\">\\n<path d=\\\"M231.17 163.09C258.02 173.23 280.07 140.34 282.52 134.66C282.29 132.25 278.65 126.07 274.86 129.38C253.69 147.89 250.47 143.76 236.56 145.29C223 146.79 223.37 160.15 231.17 163.09Z\\\" fill=\\\"black\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 138\\\" style=\\\"mix-blend-mode:multiply\\\" opacity=\\\"0.15\\\">\\n<g id=\\\"Vector_77_2\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\" filter=\\\"url(#filter6_d)\\\">\\n<g id=\\\"Vector_78\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\">\\n<path d=\\\"M238.62 159.75C237.25 158.33 238.98 151.56 238.34 145.12C237.76 145.12 237.17 145.22 236.56 145.29C222.96 146.79 223.37 160.15 231.17 163.09C258.02 173.23 280.07 140.34 282.52 134.66C282.52 134.53 282.52 134.38 282.45 134.23C267.16 143.71 256.6 164.83 238.62 159.75Z\\\" fill=\\\"black\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 139\\\" style=\\\"mix-blend-mode:multiply\\\" opacity=\\\"0.15\\\">\\n<g id=\\\"Vector_78_2\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\" filter=\\\"url(#filter7_d)\\\">\\n<g id=\\\"Vector_79\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\">\\n<path d=\\\"M284.24 121.45C285.85 120.9 288.43 120.37 289.52 121.45C290.12 122.03 289.6 123.45 288.59 123.7C288.043 123.82 287.534 124.075 287.11 124.44C286.363 125.234 285.718 126.117 285.19 127.07L289.71 128.3L293.71 128.23C295.051 127.526 296.344 126.735 297.58 125.86C298.63 124.86 300.77 125.48 300.58 125.92C300.232 126.87 299.683 127.733 298.97 128.45C299.996 127.957 300.948 127.324 301.8 126.57C302.54 125.86 305.36 126.36 303.91 128.57C304.85 129.22 304.8 129.52 304.04 130.57C303.209 131.464 302.227 132.205 301.14 132.76C301.926 132.297 302.796 131.994 303.7 131.87C304.7 131.79 304.61 133.32 303.96 134.1C301.4 137.1 294.77 138.75 292.12 139.1C285.62 139.86 278.47 137.1 278.47 137.1L272.38 132.65C272.38 132.65 274.47 128.65 275.38 127.35C277.68 124.16 281.75 122.3 284.24 121.45Z\\\" fill=\\\"black\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 140\\\" style=\\\"mix-blend-mode:multiply\\\" opacity=\\\"0.15\\\">\\n<g id=\\\"Vector_79_2\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\" filter=\\\"url(#filter8_d)\\\">\\n<g id=\\\"Vector_80\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\">\\n<path d=\\\"M196.69 284.79C194.46 309.79 198.96 344.79 202.69 360.7C206.42 376.61 212.69 363.52 213.58 359.7C216.01 349.15 218.09 296.15 218.27 286.7C218.53 271.4 197.11 280.18 196.69 284.79Z\\\" fill=\\\"black\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 141\\\" style=\\\"mix-blend-mode:multiply\\\" opacity=\\\"0.15\\\">\\n<g id=\\\"Vector_80_2\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\" filter=\\\"url(#filter9_d)\\\">\\n<g id=\\\"Vector_81\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\">\\n<path d=\\\"M214.49 353.75C214.49 353.75 220.31 362.87 221.01 366.87C223.28 379.68 194.87 372.77 195.51 370.2C196.65 365.59 200.3 357.08 201.35 354.43C205.691 355.61 210.294 355.371 214.49 353.75Z\\\" fill=\\\"black\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 142\\\" style=\\\"mix-blend-mode:multiply\\\" opacity=\\\"0.15\\\">\\n<g id=\\\"Vector_81_2\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\" filter=\\\"url(#filter10_d)\\\">\\n<g id=\\\"Vector_82\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\">\\n<path d=\\\"M195.48 368.68C196.36 365.44 198.88 360.47 199.99 356.84C199.99 357.42 199.11 362.64 200.85 364.02C205.49 362.37 210.18 363.18 214.79 363.02C216.15 361.45 215.6 357.09 215.31 355.46C215.31 355.46 219.85 363.31 221.01 366.86C223.41 374.15 222.42 375.69 220.91 377.86C220.91 379.03 220.46 379.13 220.46 379.13C220.46 379.13 217.13 379.6 208.01 379.8C203.12 379.91 195.68 379.92 195.68 379.92V378.42C193.63 376.12 194.83 371 195.48 368.68Z\\\" fill=\\\"black\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 143\\\" style=\\\"mix-blend-mode:multiply\\\" opacity=\\\"0.15\\\">\\n<g id=\\\"Vector_82_2\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\" filter=\\\"url(#filter11_d)\\\">\\n<g id=\\\"Vector_83\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\">\\n<path d=\\\"M215.3 362.05C215.96 360.1 215.55 356.84 215.3 355.47C215.3 355.47 219.84 363.32 221 366.87C223.4 374.16 222.41 375.7 220.9 377.87C220.9 379.04 220.45 379.14 220.45 379.14C220.45 379.14 219.15 379.32 215.98 379.51C217.388 373.741 217.153 367.692 215.3 362.05Z\\\" fill=\\\"black\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 144\\\" style=\\\"mix-blend-mode:multiply\\\" opacity=\\\"0.15\\\">\\n<g id=\\\"Vector_83_2\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\" filter=\\\"url(#filter12_d)\\\">\\n<g id=\\\"Vector_84\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\">\\n<path d=\\\"M200.16 378.51C204.65 378.51 209.16 378.8 213.68 378.38C215.59 378.19 218.68 378.24 221.1 377.56C221.042 377.657 220.979 377.751 220.91 377.84C220.91 379.01 220.46 379.11 220.46 379.11C220.46 379.11 217.13 379.58 208.01 379.78C203.12 379.89 195.68 379.9 195.68 379.9V378.42C197.17 378.537 198.666 378.567 200.16 378.51Z\\\" fill=\\\"black\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 145\\\" style=\\\"mix-blend-mode:multiply\\\" opacity=\\\"0.15\\\">\\n<g id=\\\"Vector_84_2\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\" filter=\\\"url(#filter13_d)\\\">\\n<g id=\\\"Vector_85\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\">\\n<path d=\\\"M202.36 368.63C202.46 368.626 202.559 368.602 202.65 368.56C206.87 366.38 210.83 366.24 214.42 368.15C214.498 368.191 214.583 368.215 214.67 368.222C214.758 368.229 214.846 368.218 214.929 368.19C215.012 368.162 215.089 368.117 215.154 368.059C215.22 368.001 215.273 367.929 215.31 367.85C215.392 367.688 215.407 367.5 215.353 367.326C215.299 367.153 215.18 367.007 215.02 366.92C211.02 364.8 206.68 364.92 202.02 367.32C201.86 367.407 201.74 367.552 201.685 367.725C201.629 367.898 201.641 368.086 201.72 368.25C201.777 368.37 201.868 368.469 201.982 368.537C202.096 368.605 202.228 368.637 202.36 368.63Z\\\" fill=\\\"black\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 146\\\" style=\\\"mix-blend-mode:multiply\\\" opacity=\\\"0.15\\\">\\n<g id=\\\"Vector_85_2\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\" filter=\\\"url(#filter14_d)\\\">\\n<g id=\\\"Vector_86\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\">\\n<path d=\\\"M205.74 371.14C205.862 371.139 205.98 371.103 206.083 371.038C206.185 370.973 206.268 370.88 206.32 370.77C206.63 370.55 209.99 369.53 211.9 370.51C211.979 370.55 212.065 370.574 212.154 370.579C212.242 370.585 212.331 370.572 212.414 370.542C212.497 370.512 212.574 370.465 212.638 370.405C212.703 370.344 212.755 370.271 212.79 370.19C212.871 370.028 212.884 369.841 212.828 369.669C212.772 369.496 212.651 369.353 212.49 369.27C210.03 368.01 205.63 369.12 205.13 370.14C205.048 370.302 205.033 370.49 205.087 370.664C205.141 370.837 205.26 370.983 205.42 371.07C205.518 371.123 205.629 371.147 205.74 371.14Z\\\" fill=\\\"black\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 147\\\" style=\\\"mix-blend-mode:multiply\\\" opacity=\\\"0.15\\\">\\n<g id=\\\"Vector_86_2\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\" filter=\\\"url(#filter15_d)\\\">\\n<g id=\\\"Vector_87\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\">\\n<path d=\\\"M173.78 291.17C173.13 285.92 154.33 271.07 153.14 287.17C151.41 310.41 152.94 361.07 154.43 367.47C155.92 373.87 161.21 371.52 162.68 368.58C164.15 365.64 178.37 328.46 173.78 291.17Z\\\" fill=\\\"black\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 148\\\" style=\\\"mix-blend-mode:multiply\\\" opacity=\\\"0.15\\\">\\n<g id=\\\"Vector_87_2\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\" filter=\\\"url(#filter16_d)\\\">\\n<g id=\\\"Vector_88\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\">\\n<path d=\\\"M167.58 353.79C167.58 353.79 169.22 362.35 168.71 366.08C168.2 369.81 146 367.27 146 367.27C146 367.27 149.38 360.27 154 356.83C165.67 357.09 167.58 353.79 167.58 353.79Z\\\" fill=\\\"black\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 149\\\" style=\\\"mix-blend-mode:multiply\\\" opacity=\\\"0.15\\\">\\n<g id=\\\"Vector_88_2\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\" filter=\\\"url(#filter17_d)\\\">\\n<g id=\\\"Vector_89\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\">\\n<path d=\\\"M168 355.18C167.91 355.6 167.8 356.02 167.68 356.46C166.49 360.92 162.2 361.9 159.32 362.34C155.52 361.7 151.41 360.15 150.24 360.23C143.97 365.84 142.24 365.29 137.53 368.92C134 371.66 134.04 374.81 133.77 376.92C133.35 380.28 136.6 380.15 145.05 380.22C152.16 380.28 168.05 379.67 169.67 378.13C169.952 377.35 169.997 376.505 169.8 375.7C173.06 370.83 168.94 358.53 168 355.18Z\\\" fill=\\\"black\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 150\\\" style=\\\"mix-blend-mode:multiply\\\" opacity=\\\"0.15\\\">\\n<g id=\\\"Vector_89_2\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\" filter=\\\"url(#filter18_d)\\\">\\n<g id=\\\"Vector_90\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\">\\n<path d=\\\"M159.38 374C162.013 370.224 163.467 365.752 163.56 361.15C164.561 360.734 165.451 360.09 166.161 359.271C166.87 358.452 167.38 357.48 167.65 356.43C167.77 355.99 167.88 355.57 167.97 355.15C168.97 358.5 173.06 370.8 169.77 375.71C169.967 376.515 169.922 377.36 169.64 378.14C168.43 379.28 159.4 379.91 151.91 380.14C154.891 378.776 157.465 376.66 159.38 374Z\\\" fill=\\\"black\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 151\\\" style=\\\"mix-blend-mode:multiply\\\" opacity=\\\"0.15\\\">\\n<g id=\\\"Vector_90_2\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\" filter=\\\"url(#filter19_d)\\\">\\n<g id=\\\"Vector_91\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\">\\n<path d=\\\"M133.77 376.48C138.18 378.65 144.03 378.81 153.63 378.48C158.57 378.31 165.63 378.76 169.79 375.69C169.965 376.69 169.907 377.716 169.62 378.69C167.99 380.23 152.09 380.2 144.98 380.09C134.76 379.94 133.32 380.35 133.74 376.99C133.761 376.821 133.771 376.65 133.77 376.48Z\\\" fill=\\\"black\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 152\\\" style=\\\"mix-blend-mode:multiply\\\" opacity=\\\"0.15\\\">\\n<g id=\\\"Vector_91_2\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\" filter=\\\"url(#filter20_d)\\\">\\n<g id=\\\"Vector_92\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\">\\n<path d=\\\"M156.24 368.44C156.333 368.439 156.426 368.418 156.51 368.378C156.595 368.339 156.67 368.281 156.73 368.21C156.857 368.075 156.928 367.896 156.928 367.71C156.928 367.524 156.857 367.345 156.73 367.21C153.35 364.04 148.95 362.91 143.67 363.86C143.491 363.896 143.333 364.001 143.23 364.153C143.127 364.304 143.088 364.49 143.12 364.67C143.132 364.761 143.162 364.848 143.209 364.927C143.256 365.005 143.318 365.074 143.392 365.128C143.465 365.182 143.549 365.221 143.638 365.242C143.727 365.263 143.82 365.266 143.91 365.25C148.75 364.38 152.76 365.39 155.82 368.25C155.932 368.363 156.081 368.43 156.24 368.44Z\\\" fill=\\\"black\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 153\\\" style=\\\"mix-blend-mode:multiply\\\" opacity=\\\"0.15\\\">\\n<g id=\\\"Vector_92_2\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\" filter=\\\"url(#filter21_d)\\\">\\n<g id=\\\"Vector_93\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\">\\n<path d=\\\"M149.4 369.72C149.495 369.716 149.589 369.693 149.675 369.652C149.761 369.61 149.837 369.552 149.9 369.48C150.019 369.337 150.08 369.154 150.069 368.968C150.057 368.782 149.976 368.608 149.84 368.48C147.79 366.62 143.04 366.38 142.28 367.19C142.153 367.325 142.082 367.504 142.082 367.69C142.082 367.876 142.153 368.055 142.28 368.19C142.341 368.263 142.417 368.323 142.504 368.363C142.59 368.404 142.685 368.425 142.78 368.425C142.875 368.425 142.97 368.404 143.056 368.363C143.143 368.323 143.219 368.263 143.28 368.19C143.77 368.02 147.38 368.1 148.97 369.55C149.09 369.654 149.242 369.714 149.4 369.72Z\\\" fill=\\\"black\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 154\\\" style=\\\"mix-blend-mode:multiply\\\" opacity=\\\"0.15\\\">\\n<g id=\\\"Vector_93_2\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\" filter=\\\"url(#filter22_d)\\\">\\n<g id=\\\"Vector_94\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\">\\n<path d=\\\"M215.43 223.67C222.88 265.11 219.78 268.58 220.63 299.67C220.99 312.4 219.63 340.78 218.4 347.72C209.4 355.72 194.74 348.93 194.74 348.93C194.74 348.93 190.01 312.93 188.42 300.99C186.62 287.34 178.6 227.76 178.6 227.76L215.43 223.67Z\\\" fill=\\\"black\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 155\\\" style=\\\"mix-blend-mode:multiply\\\" opacity=\\\"0.15\\\">\\n<g id=\\\"Vector_94_2\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\" filter=\\\"url(#filter23_d)\\\">\\n<g id=\\\"Vector_95\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\">\\n<path d=\\\"M220.63 299.62C219.78 268.62 222.88 265.11 215.43 223.62L178.6 227.62L182 253.16C191.8 252.87 201.71 251.86 211.62 251.16C209.96 283.92 214.43 318.28 210.85 351.29C213.647 350.825 216.257 349.58 218.38 347.7C219.59 340.73 221 312.35 220.63 299.62Z\\\" fill=\\\"black\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 156\\\" style=\\\"mix-blend-mode:multiply\\\" opacity=\\\"0.15\\\">\\n<g id=\\\"Vector_95_2\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\" filter=\\\"url(#filter24_d)\\\">\\n<g id=\\\"Vector_96\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\">\\n<path d=\\\"M210.73 253.24C204.64 251.37 203.27 243.97 202.73 238.38C202.73 238.29 202.694 238.203 202.63 238.14C202.567 238.076 202.48 238.04 202.39 238.04C202.3 238.04 202.213 238.076 202.15 238.14C202.086 238.203 202.05 238.29 202.05 238.38C201.39 245.46 201.91 251.89 208.49 255.61C210.31 256.612 212.327 257.204 214.399 257.346C216.472 257.488 218.551 257.175 220.49 256.43C220.403 255.343 220.259 254.262 220.06 253.19C217.016 254.083 213.783 254.1 210.73 253.24Z\\\" fill=\\\"black\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 157\\\" style=\\\"mix-blend-mode:multiply\\\" opacity=\\\"0.15\\\">\\n<g id=\\\"Vector_96_2\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\" filter=\\\"url(#filter25_d)\\\">\\n<g id=\\\"Vector_97\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\">\\n<path d=\\\"M150.72 223.94C150.72 223.94 145.1 266.05 145.1 287.49C145.1 310.97 151.84 352.3 151.84 352.3C151.84 352.3 166.84 354.94 171.17 350.44C173.07 345.55 174.33 307.03 175.67 294.02C177.01 281.01 186.84 228.45 186.84 228.45L150.72 223.94Z\\\" fill=\\\"black\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 158\\\" style=\\\"mix-blend-mode:multiply\\\" opacity=\\\"0.15\\\">\\n<g id=\\\"Vector_97_2\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\" filter=\\\"url(#filter26_d)\\\">\\n<g id=\\\"Vector_98\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\">\\n<path d=\\\"M165.78 352.72C167.769 352.534 169.652 351.738 171.17 350.44C173.07 345.55 174.33 307.03 175.67 294.02C176.3 287.9 178.78 273.23 181.23 259.32C164.67 286.84 169.34 321.68 165.78 352.72Z\\\" fill=\\\"black\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 159\\\" style=\\\"mix-blend-mode:multiply\\\" opacity=\\\"0.15\\\">\\n<g id=\\\"Vector_98_2\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\" filter=\\\"url(#filter27_d)\\\">\\n<g id=\\\"Vector_99\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\">\\n<path d=\\\"M150.72 223.94C150.72 223.94 149.2 235.37 147.72 249.35C158.98 252.83 170.57 253.52 182.32 253.15C184.72 239.74 186.83 228.45 186.83 228.45L150.72 223.94Z\\\" fill=\\\"black\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 160\\\" style=\\\"mix-blend-mode:multiply\\\" opacity=\\\"0.15\\\">\\n<g id=\\\"Vector_99_2\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\" filter=\\\"url(#filter28_d)\\\">\\n<g id=\\\"Vector_100\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\">\\n<path d=\\\"M157.9 240.19C157.82 239.96 157.43 239.97 157.46 240.25C158.07 245.3 155.32 250.17 152.2 253.83C150.919 255.469 149.051 256.545 146.99 256.83C146.9 257.99 146.89 259.18 146.89 260.36C154.41 259.78 160.58 247.47 157.9 240.19Z\\\" fill=\\\"black\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 161\\\" style=\\\"mix-blend-mode:multiply\\\" opacity=\\\"0.15\\\">\\n<g id=\\\"Vector_100_2\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\" filter=\\\"url(#filter29_d)\\\">\\n<g id=\\\"Vector_101\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\">\\n<path d=\\\"M233.67 142.73C233.67 142.73 230.76 172.57 228.27 172.57C225.78 172.57 187 162.57 187.14 155.57C189.23 150.42 191.7 132.07 199.95 133.42C212.76 135.5 221.29 138.66 233.67 142.73Z\\\" fill=\\\"black\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 162\\\" style=\\\"mix-blend-mode:multiply\\\" opacity=\\\"0.15\\\">\\n<g id=\\\"Vector_101_2\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\" filter=\\\"url(#filter30_d)\\\">\\n<g id=\\\"Vector_102\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\">\\n<path d=\\\"M129.58 155.55C129.58 155.55 136.67 182.72 139.03 181.89C141.39 181.06 171.36 167.89 169.08 161.3C172.97 148.87 171.7 133.39 160.98 135.5C152.57 137.16 139.93 149.49 129.58 155.55Z\\\" fill=\\\"black\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 163\\\" style=\\\"mix-blend-mode:multiply\\\" opacity=\\\"0.15\\\">\\n<g id=\\\"Vector_102_2\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\" filter=\\\"url(#filter31_d)\\\">\\n<g id=\\\"Vector_103\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\">\\n<path d=\\\"M211 137.68C211 135.54 193 130.32 180.46 130.53C166.65 130.76 153.91 138.13 153.8 140.16C152.58 162.32 149.6 219.16 145.63 240.31C161.11 249.92 194.54 250.12 219.79 238.69C213.14 216 211 156.64 211 137.68Z\\\" fill=\\\"black\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 164\\\" style=\\\"mix-blend-mode:multiply\\\" opacity=\\\"0.15\\\">\\n<g id=\\\"Vector_103_2\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\" filter=\\\"url(#filter32_d)\\\">\\n<g id=\\\"Vector_104\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\">\\n<path d=\\\"M219.78 238.69C213.14 216.01 211.04 156.64 210.99 137.69C210.99 136.69 207.16 135.07 201.82 133.6C206.63 173.55 204.82 220.66 176.4 247.4C190.55 247.57 206.33 244.78 219.78 238.69Z\\\" fill=\\\"black\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 165\\\" style=\\\"mix-blend-mode:multiply\\\" opacity=\\\"0.15\\\">\\n<g id=\\\"Vector_104_2\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\" filter=\\\"url(#filter33_d)\\\">\\n<g id=\\\"Vector_105\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\">\\n<path d=\\\"M175.11 143C173.307 140.397 171.921 137.529 171 134.5C170.71 133.55 170.55 132.5 170.31 131.42C173.655 130.887 177.033 130.59 180.42 130.53C184.171 130.468 187.924 130.608 191.66 130.95C190.71 138 181.23 152 175.11 143Z\\\" fill=\\\"black\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 166\\\" style=\\\"mix-blend-mode:multiply\\\" opacity=\\\"0.15\\\">\\n<g id=\\\"Vector_105_2\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\" filter=\\\"url(#filter34_d)\\\">\\n<g id=\\\"Vector_106\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\">\\n<path d=\\\"M181.49 23.3699C170.25 18.6299 161.24 19.6699 153.71 25.1299C152.79 25.7199 151.86 26.3099 150.9 26.8899C146.859 29.4334 142.558 31.5386 138.07 33.1699C136.56 33.6799 141.41 37.0199 143.19 36.8399C141.99 38.7199 140.83 40.7199 139.7 42.8399C137.7 46.6999 132.37 58.9799 130.36 62.0699C129.51 63.3699 135.63 63.4599 137.14 62.5099C139.14 69.5099 143.34 77.4299 144.2 93.5099C144.2 93.5099 213.72 106.68 215.84 90.7099C217.23 80.1699 222.13 75.1699 224.53 64.9199C230.52 34.1699 196.78 16.5299 181.49 23.3699Z\\\" fill=\\\"black\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 167\\\" style=\\\"mix-blend-mode:multiply\\\" opacity=\\\"0.15\\\">\\n<g id=\\\"Vector_106_2\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\" filter=\\\"url(#filter35_d)\\\">\\n<g id=\\\"Vector_107\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\">\\n<path d=\\\"M188.9 118.2L188.91 133.19L171.8 134.17L172.05 121.71L188.9 118.2Z\\\" fill=\\\"black\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 168\\\" style=\\\"mix-blend-mode:multiply\\\" opacity=\\\"0.15\\\">\\n<g id=\\\"Vector_107_2\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\" filter=\\\"url(#filter36_d)\\\">\\n<g id=\\\"Vector_108\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\">\\n<path d=\\\"M171.93 127.81L172.05 121.71L188.89 118.2V127.2C181.19 130.09 173.49 128.49 171.93 127.81Z\\\" fill=\\\"black\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 169\\\" style=\\\"mix-blend-mode:multiply\\\" opacity=\\\"0.15\\\">\\n<g id=\\\"Vector_108_2\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\" filter=\\\"url(#filter37_d)\\\">\\n<g id=\\\"Vector_109\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\">\\n<path d=\\\"M227.54 74.8699C223.54 71.8699 219.07 74.5899 216.69 78.2399C212.51 81.2399 209.03 87.4599 211.78 91.7199C215.1 96.8399 223.15 93.5399 226.62 90.3199C230.82 86.4199 232.81 78.8199 227.54 74.8699Z\\\" fill=\\\"black\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 170\\\" style=\\\"mix-blend-mode:multiply\\\" opacity=\\\"0.15\\\">\\n<g id=\\\"Vector_109_2\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\" filter=\\\"url(#filter38_d)\\\">\\n<g id=\\\"Vector_110\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\">\\n<path d=\\\"M225.53 78C223.99 77.83 222.08 79.43 221.63 80.78C221.31 81.7988 221.31 82.8912 221.63 83.91C221.98 85.19 222.27 86.69 220.54 87.24C220.284 87.349 220.078 87.5484 219.96 87.8C219.923 87.8638 219.904 87.9363 219.904 88.01C219.904 88.0837 219.923 88.1562 219.96 88.22C220.01 88.31 220.05 88.4 220.09 88.49C220.203 88.6407 220.36 88.7519 220.54 88.8076C220.719 88.8633 220.912 88.8606 221.09 88.8C221.577 88.6541 222.028 88.4066 222.412 88.0739C222.797 87.7412 223.106 87.3308 223.321 86.8698C223.535 86.4088 223.65 85.9075 223.657 85.3991C223.663 84.8906 223.562 84.3866 223.36 83.92C222.78 82.19 222.72 81.04 224.22 79.79C224.81 79.31 225.59 78.89 225.55 78.1C225.556 78.0831 225.557 78.0648 225.554 78.0473C225.55 78.0297 225.542 78.0133 225.53 78Z\\\" fill=\\\"black\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 171\\\" style=\\\"mix-blend-mode:multiply\\\" opacity=\\\"0.15\\\">\\n<g id=\\\"Vector_110_2\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\" filter=\\\"url(#filter39_d)\\\">\\n<g id=\\\"Vector_111\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\">\\n<path d=\\\"M136.17 80.45C139.29 76.79 143.43 78.7301 145.89 81.9101C149.81 84.1701 153.5 89.69 151.6 94.36C149.32 99.96 142.03 98.09 138.69 95.5C134.64 92.38 132.08 85.24 136.17 80.45Z\\\" fill=\\\"black\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 172\\\" style=\\\"mix-blend-mode:multiply\\\" opacity=\\\"0.15\\\">\\n<g id=\\\"Vector_111_2\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\" filter=\\\"url(#filter40_d)\\\">\\n<g id=\\\"Vector_112\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\">\\n<path d=\\\"M138.25 83.1501C139.56 82.7301 141.38 83.9701 141.92 85.2201C142.293 86.205 142.4 87.2706 142.23 88.31C142.07 89.64 141.98 91.1601 143.53 91.4001C143.8 91.4001 143.94 91.6601 144.1 91.8601C144.132 91.9255 144.148 91.9972 144.148 92.07C144.148 92.1427 144.132 92.2146 144.1 92.28C144.1 92.38 144.04 92.47 144.02 92.56C143.955 92.7191 143.84 92.8526 143.692 92.9394C143.543 93.0262 143.37 93.0616 143.2 93.0401C141.2 92.7301 140.35 90.7301 140.71 88.6201C141.01 86.8201 140.94 85.62 139.5 84.7C138.95 84.33 138.23 84.05 138.17 83.27C138.167 83.2437 138.173 83.2171 138.188 83.195C138.202 83.173 138.224 83.1571 138.25 83.1501Z\\\" fill=\\\"black\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 173\\\" style=\\\"mix-blend-mode:multiply\\\" opacity=\\\"0.15\\\">\\n<g id=\\\"Vector_112_2\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\" filter=\\\"url(#filter41_d)\\\">\\n<g id=\\\"Vector_113\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\">\\n<path d=\\\"M146.16 50.15C144.679 63.0959 143.991 76.1202 144.1 89.15C144.31 101.54 150.81 113.92 159.41 120.08C174.88 131.16 195.74 124.17 204.49 115.17C218 101.3 220.8 84.81 214.88 50.79C212.66 49 146.16 50.15 146.16 50.15Z\\\" fill=\\\"black\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 174\\\" style=\\\"mix-blend-mode:multiply\\\" opacity=\\\"0.15\\\">\\n<g id=\\\"Vector_113_2\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\" filter=\\\"url(#filter42_d)\\\">\\n<g id=\\\"Vector_114\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\">\\n<path d=\\\"M196.4 115.58C205.49 108.77 211.1 100.1 211.66 86.18C212.11 74.64 211.89 61.88 205.95 50.01C211 50.16 214.41 50.41 214.88 50.79C220.8 84.79 217.98 101.3 204.49 115.17C195.74 124.17 174.88 131.17 159.41 120.08C158.69 119.57 157.98 118.98 157.29 118.38C170.16 123.18 184.82 124.26 196.4 115.58Z\\\" fill=\\\"black\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 175\\\" style=\\\"mix-blend-mode:multiply\\\" opacity=\\\"0.15\\\">\\n<g id=\\\"Vector_114_2\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\" filter=\\\"url(#filter43_d)\\\">\\n<g id=\\\"Vector_115\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\">\\n<path d=\\\"M203.53 87.4201C203.848 87.2425 204.085 86.9486 204.192 86.5999C204.298 86.2513 204.265 85.875 204.1 85.5501C203.517 84.2414 202.573 83.1254 201.38 82.3323C200.187 81.5391 198.793 81.1014 197.36 81.0701C194.57 81.1701 192.57 83.1801 191.18 85.8301C191.006 86.1508 190.964 86.5267 191.063 86.8778C191.162 87.2289 191.394 87.5276 191.71 87.7101C192.36 88.0701 193.61 83.9501 197.89 84.2701C201.07 84.5101 203.37 87.5001 203.53 87.4201Z\\\" fill=\\\"black\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 176\\\" style=\\\"mix-blend-mode:multiply\\\" opacity=\\\"0.15\\\">\\n<g id=\\\"Vector_115_2\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\" filter=\\\"url(#filter44_d)\\\">\\n<g id=\\\"Vector_116\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\">\\n<path d=\\\"M164.52 88.1999C164.688 88.1887 164.852 88.1409 165 88.0599C165.32 87.8841 165.559 87.5902 165.665 87.2409C165.772 86.8915 165.738 86.5144 165.57 86.1899C165.006 84.8806 164.081 83.7587 162.904 82.9549C161.726 82.151 160.345 81.6985 158.92 81.6499C156.11 81.7499 154.06 83.8099 152.66 86.4699C152.489 86.7896 152.449 87.1631 152.548 87.5119C152.646 87.8606 152.877 88.1575 153.19 88.3399C153.83 88.7099 154.95 85.1499 159.36 84.9099C163.53 84.6799 164 88.2599 164.52 88.1999Z\\\" fill=\\\"black\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 177\\\" style=\\\"mix-blend-mode:multiply\\\" opacity=\\\"0.15\\\">\\n<g id=\\\"Vector_116_2\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\" filter=\\\"url(#filter45_d)\\\">\\n<g id=\\\"Vector_117\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\">\\n<path d=\\\"M198 72.23C199.67 72.11 202.17 73.47 202.63 75.35C202.63 75.54 202.5 75.75 202.3 75.68C201.15 75.25 200.01 74.52 198.72 74.6C198.15 74.6 195.99 74.77 195.65 75.33C195.31 75.89 193.94 76.2 193.82 75.33C193.57 73.43 196.74 72.32 198 72.23Z\\\" fill=\\\"black\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 178\\\" style=\\\"mix-blend-mode:multiply\\\" opacity=\\\"0.15\\\">\\n<g id=\\\"Vector_117_2\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\" filter=\\\"url(#filter46_d)\\\">\\n<g id=\\\"Vector_118\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\">\\n<path d=\\\"M155 74.5101C158.14 72.6301 162.29 73.3701 163.34 77.0401C163.356 77.0933 163.358 77.15 163.345 77.2042C163.332 77.2584 163.305 77.3081 163.266 77.348C163.227 77.3879 163.178 77.4166 163.124 77.431C163.07 77.4455 163.014 77.4452 162.96 77.4301C161.65 77.0201 160.62 76.2401 159.21 76.0501C157.8 75.8601 156.81 77.0501 155.54 76.9301C155.278 76.8852 155.035 76.7634 154.843 76.5802C154.65 76.397 154.516 76.1606 154.458 75.9012C154.401 75.6417 154.421 75.371 154.518 75.1232C154.614 74.8755 154.782 74.6621 155 74.5101Z\\\" fill=\\\"black\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 179\\\" style=\\\"mix-blend-mode:multiply\\\" opacity=\\\"0.15\\\">\\n<g id=\\\"Vector_118_2\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\" filter=\\\"url(#filter47_d)\\\">\\n<g id=\\\"Vector_119\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\">\\n<path d=\\\"M168 104.86C168 104.86 170.06 113.12 176 113.69C186.46 114.69 187.23 104.69 187.23 104.69L168 104.86Z\\\" fill=\\\"black\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 180\\\" style=\\\"mix-blend-mode:multiply\\\" opacity=\\\"0.15\\\">\\n<g id=\\\"Vector_119_2\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\" filter=\\\"url(#filter48_d)\\\">\\n<g id=\\\"Vector_120\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\">\\n<path d=\\\"M184.61 107.4C185.202 107.146 185.738 106.778 186.188 106.316C186.637 105.854 186.992 105.309 187.23 104.71L170.42 104.85C173.74 108.73 178.36 109.56 184.61 107.4Z\\\" fill=\\\"black\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 181\\\" style=\\\"mix-blend-mode:multiply\\\" opacity=\\\"0.15\\\">\\n<g id=\\\"Vector_120_2\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\" filter=\\\"url(#filter49_d)\\\">\\n<g id=\\\"Vector_121\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\">\\n<path d=\\\"M184.17 111.26C181.55 110.72 177.99 110.89 176.02 112.26C175.526 112.582 175.095 112.992 174.75 113.47C175.157 113.599 175.576 113.686 176 113.73C179.94 114.06 182.5 112.87 184.17 111.26Z\\\" fill=\\\"black\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 182\\\" style=\\\"mix-blend-mode:multiply\\\" opacity=\\\"0.15\\\">\\n<g id=\\\"Vector_121_2\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\" filter=\\\"url(#filter50_d)\\\">\\n<g id=\\\"Vector_122\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\">\\n<path d=\\\"M176.87 83.28C176.87 83.28 176.61 88.1 174.7 89.74C172.79 91.38 171.83 92.14 171.98 94.74C172.06 96.1 174.26 98.01 176.4 98.01C172.69 98.82 171.01 96.72 170.9 94.94C170.71 92.1 171.29 91.13 173.9 88.76C175.54 87.28 176.87 83.28 176.87 83.28Z\\\" fill=\\\"black\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 183\\\" style=\\\"mix-blend-mode:multiply\\\" opacity=\\\"0.15\\\">\\n<g id=\\\"Vector_122_2\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\" filter=\\\"url(#filter51_d)\\\">\\n<g id=\\\"Vector_123\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\">\\n<path d=\\\"M216.81 46.68C207.94 32.81 152.69 36.96 148.44 40.13C132.73 51.81 134.87 71.52 137.68 77.69C137.68 74.69 142.92 71.3 147.79 69.3C149.267 68.6947 150.78 68.1804 152.32 67.76C150.5 70.23 149.14 72.95 149.14 75.59C155.51 71.49 166.74 70.79 172.26 68.18C172.965 71.4739 174.326 74.5923 176.26 77.35C176.05 74.01 179.33 68.9 188.36 67.13C186.67 69.72 185.29 72.24 185.8 72.56C193.36 71.19 204.85 69.15 208.2 65.63C210.99 68.19 213.49 70.04 213.38 77.54C225.66 70.31 221.49 53.65 216.81 46.68Z\\\" fill=\\\"black\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 184\\\" style=\\\"mix-blend-mode:multiply\\\" opacity=\\\"0.15\\\">\\n<g id=\\\"Vector_123_2\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\" filter=\\\"url(#filter52_d)\\\">\\n<g id=\\\"Vector_124\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\">\\n<path d=\\\"M181.53 47C176.4 49.66 172.98 56.08 174.58 62C174.603 62.1155 174.666 62.2194 174.757 62.2941C174.848 62.3687 174.962 62.4095 175.08 62.4095C175.198 62.4095 175.312 62.3687 175.403 62.2941C175.494 62.2194 175.557 62.1155 175.58 62C176.71 56.44 177.51 51.41 181.89 47.46C182.12 47.21 181.8 46.84 181.53 47Z\\\" fill=\\\"black\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 185\\\" style=\\\"mix-blend-mode:multiply\\\" opacity=\\\"0.15\\\">\\n<g id=\\\"Vector_124_2\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\" filter=\\\"url(#filter53_d)\\\">\\n<g id=\\\"Vector_125\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\">\\n<path d=\\\"M170.25 45.2701C167.42 54.0501 160.47 59.5901 154.49 65.9801C154.442 66.0294 154.414 66.0941 154.409 66.1625C154.405 66.231 154.425 66.2988 154.465 66.354C154.506 66.4091 154.565 66.4481 154.632 66.4638C154.699 66.4796 154.769 66.4712 154.83 66.4401C158.805 64.2288 162.284 61.2234 165.048 57.6107C167.813 53.998 169.805 49.8553 170.9 45.4401C170.92 45.3951 170.929 45.3464 170.928 45.2973C170.927 45.2482 170.916 45.2 170.894 45.1558C170.873 45.1117 170.842 45.0727 170.804 45.0415C170.766 45.0104 170.722 44.9878 170.674 44.9754C170.627 44.963 170.577 44.961 170.529 44.9696C170.481 44.9782 170.435 44.9971 170.394 45.0251C170.354 45.0531 170.32 45.0895 170.295 45.1318C170.27 45.1741 170.255 45.2213 170.25 45.2701Z\\\" fill=\\\"black\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 186\\\" style=\\\"mix-blend-mode:multiply\\\" opacity=\\\"0.15\\\">\\n<g id=\\\"Vector_125_2\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\" filter=\\\"url(#filter54_d)\\\">\\n<g id=\\\"Vector_126\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\">\\n<path d=\\\"M161.39 51.7699C160.11 54.5699 157.8 56.3399 156.1 58.7699C155.88 59.0899 156.25 59.5899 156.61 59.4499C159.61 58.2599 161.11 54.9599 161.8 51.9099C161.86 51.7099 161.5 51.5299 161.39 51.7699Z\\\" fill=\\\"black\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 187\\\" style=\\\"mix-blend-mode:multiply\\\" opacity=\\\"0.15\\\">\\n<g id=\\\"Vector_126_2\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\" filter=\\\"url(#filter55_d)\\\">\\n<g id=\\\"Vector_127\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\">\\n<path d=\\\"M203.09 37.8201C203.064 37.7885 203.028 37.7671 202.988 37.7598C202.948 37.7526 202.907 37.7599 202.872 37.7804C202.837 37.801 202.81 37.8335 202.797 37.8719C202.784 37.9104 202.785 37.9523 202.8 37.9901C204.697 41.4486 205.749 45.3071 205.87 49.2501C206.03 53.2501 204.34 56.7801 203 60.4401C202.79 61.0301 203.56 61.3601 203.95 61.0101C210.32 55.1801 207.25 44.0001 203.09 37.8201Z\\\" fill=\\\"black\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 188\\\" style=\\\"mix-blend-mode:multiply\\\" opacity=\\\"0.15\\\">\\n<g id=\\\"Vector_127_2\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\" filter=\\\"url(#filter56_d)\\\">\\n<g id=\\\"Vector_128\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\">\\n<path d=\\\"M201.29 46.5199C201.2 46.3599 200.91 46.4599 200.98 46.6499C201.771 48.6174 201.88 50.7931 201.29 52.8299C200.86 54.5199 199.96 56.0099 199.57 57.6899C199.546 57.7743 199.55 57.8642 199.582 57.9459C199.614 58.0275 199.672 58.0964 199.747 58.1419C199.822 58.1874 199.91 58.2069 199.997 58.1975C200.085 58.1881 200.166 58.1503 200.23 58.0899C203.42 55.2299 203.44 49.9999 201.29 46.5199Z\\\" fill=\\\"black\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 189\\\" style=\\\"mix-blend-mode:multiply\\\" opacity=\\\"0.15\\\">\\n<g id=\\\"Vector_128_2\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\" filter=\\\"url(#filter57_d)\\\">\\n<g id=\\\"Vector_129\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\">\\n<path d=\\\"M174.25 24.57C167.13 23.04 158.75 27.52 154.33 33.18C154 33.61 154.45 34.39 154.95 34.01C160.65 29.67 167 25.88 174.17 25.14C174.47 25.11 174.58 24.64 174.25 24.57Z\\\" fill=\\\"black\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 190\\\" style=\\\"mix-blend-mode:multiply\\\" opacity=\\\"0.15\\\">\\n<g id=\\\"Vector_129_2\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\" filter=\\\"url(#filter58_d)\\\">\\n<g id=\\\"Vector_130\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\">\\n<path d=\\\"M217.83 47.4199C217.72 47.1899 217.32 47.3599 217.42 47.5999C220.01 54.2199 219.53 60.5299 217.86 67.3199C217.75 67.7599 218.39 68.0799 218.57 67.6399C221.38 60.8499 220.93 54.0499 217.83 47.4199Z\\\" fill=\\\"black\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 191\\\" style=\\\"mix-blend-mode:multiply\\\" opacity=\\\"0.15\\\">\\n<g id=\\\"Vector_130_2\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\" filter=\\\"url(#filter59_d)\\\">\\n<g id=\\\"Vector_131\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\">\\n<path d=\\\"M147.93 47.0601C141.57 53.1201 136.23 65.1801 139.11 74.1301C139.155 74.2692 139.247 74.3881 139.371 74.4657C139.495 74.5434 139.642 74.5748 139.787 74.5545C139.931 74.5342 140.064 74.4634 140.162 74.3546C140.259 74.2459 140.315 74.1061 140.32 73.9601C141.07 64.5501 141.97 54.8601 148.25 47.4001C148.44 47.1701 148.15 46.8601 147.93 47.0601Z\\\" fill=\\\"black\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 192\\\" style=\\\"mix-blend-mode:multiply\\\" opacity=\\\"0.15\\\">\\n<g id=\\\"Vector_131_2\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\" filter=\\\"url(#filter60_d)\\\">\\n<g id=\\\"Vector_132\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\">\\n<path d=\\\"M74.55 130.64C74.55 130.64 85.77 140.41 85.4 142.64C84.97 145.26 82.8199 148.95 80.6799 148.79C78.5399 148.63 71.8099 148.98 70.8399 147.63C69.8699 146.28 67.9099 130.29 69.5399 129.63C71.1699 128.97 74.55 130.64 74.55 130.64Z\\\" fill=\\\"black\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 193\\\" style=\\\"mix-blend-mode:multiply\\\" opacity=\\\"0.15\\\">\\n<g id=\\\"Vector_132_2\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\" filter=\\\"url(#filter61_d)\\\">\\n<g id=\\\"Vector_133\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\">\\n<path d=\\\"M82.7799 145C81.2099 145.28 78.1799 142.28 77.4199 140.84C76.2974 138.766 75.7032 136.448 75.6899 134.09C75.6899 134.09 74.8899 132.43 69.4799 131.58C65.6099 130.97 65.7199 125.94 67.1499 126.2C73.3699 127.36 75.7499 126.83 78.0599 128.66C80.3699 130.49 85.3199 136.8 85.7799 141.74C85.9999 143.69 84.6599 144.64 82.7799 145Z\\\" fill=\\\"black\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 194\\\" style=\\\"mix-blend-mode:multiply\\\" opacity=\\\"0.15\\\">\\n<g id=\\\"Vector_133_2\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\" filter=\\\"url(#filter62_d)\\\">\\n<g id=\\\"Vector_134\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\">\\n<path d=\\\"M192.64 131C192.585 130.783 192.467 130.588 192.301 130.438C192.134 130.289 191.926 130.194 191.705 130.163C191.483 130.133 191.258 130.17 191.057 130.269C190.857 130.369 190.69 130.526 190.58 130.72C188.14 135.37 187.05 140.31 182.33 143.34C176.02 147.34 170.51 134.79 170.05 130.22C170.057 130.186 170.057 130.152 170.049 130.119C170.041 130.085 170.025 130.054 170.004 130.028C169.982 130.001 169.955 129.979 169.924 129.965C169.893 129.95 169.859 129.942 169.825 129.942C169.791 129.942 169.757 129.95 169.726 129.965C169.695 129.979 169.668 130.001 169.646 130.028C169.625 130.054 169.609 130.085 169.601 130.119C169.593 130.152 169.593 130.186 169.6 130.22C169.04 137.52 172.93 145.77 180.6 146.5C186.42 147.05 193.33 136.25 192.64 131Z\\\" fill=\\\"black\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 195\\\" style=\\\"mix-blend-mode:multiply\\\" opacity=\\\"0.15\\\">\\n<g id=\\\"Vector_134_2\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\" filter=\\\"url(#filter63_d)\\\">\\n<g id=\\\"Vector_135\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\">\\n<path d=\\\"M140.34 179.53C132.06 174.14 133.5 161.44 129.16 153.7C129.131 153.642 129.083 153.597 129.025 153.57C128.966 153.544 128.9 153.538 128.838 153.555C128.776 153.571 128.721 153.608 128.683 153.66C128.645 153.712 128.627 153.776 128.63 153.84C128.01 158.84 130.28 165.34 131.56 170.08C132.84 174.82 134.62 179.8 138.47 182.85C140.33 184.33 142.4 180.88 140.34 179.53Z\\\" fill=\\\"black\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 196\\\" style=\\\"mix-blend-mode:multiply\\\" opacity=\\\"0.15\\\">\\n<g id=\\\"Vector_135_2\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\" filter=\\\"url(#filter64_d)\\\">\\n<g id=\\\"Vector_136\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\">\\n<path d=\\\"M233.37 140.7C233.31 140.6 233.13 140.57 233.08 140.7C231.53 144.45 231.95 149.04 231.53 153.05C230.88 159.34 229.92 165.35 226.87 170.93C225.73 173.02 228.87 174.93 229.98 172.81C232.592 167.835 234.215 162.402 234.76 156.81C235.31 151.92 236.11 145 233.37 140.7Z\\\" fill=\\\"black\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 197\\\" style=\\\"mix-blend-mode:multiply\\\" opacity=\\\"0.15\\\">\\n<g id=\\\"Vector_136_2\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\" filter=\\\"url(#filter65_d)\\\">\\n<g id=\\\"Vector_137\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\">\\n<path d=\\\"M173.05 272C171.25 286 169.05 300 167.26 314C165.68 326.51 163.64 340 165.35 352.62C165.42 353.18 166.19 352.98 166.23 352.5C167.38 339.67 167.36 326.84 168.88 314C170.55 300 172.62 286.12 173.5 272C173.52 271.65 173.08 271.67 173.05 272Z\\\" fill=\\\"black\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 198\\\" style=\\\"mix-blend-mode:multiply\\\" opacity=\\\"0.15\\\">\\n<g id=\\\"Vector_137_2\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\" filter=\\\"url(#filter66_d)\\\">\\n<g id=\\\"Vector_138\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\">\\n<path d=\\\"M215.74 310.58C215.93 295.86 215.62 281.35 214.5 266.67C214.5 266.45 214.16 266.44 214.17 266.67C215.69 294.67 213.98 322.13 212.17 349.97C212.17 350.39 212.7 350.4 212.83 350.06C217.48 338.07 215.58 323.23 215.74 310.58Z\\\" fill=\\\"black\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 199\\\" style=\\\"mix-blend-mode:multiply\\\" opacity=\\\"0.15\\\">\\n<g id=\\\"Vector_138_2\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\" filter=\\\"url(#filter67_d)\\\">\\n<g id=\\\"Vector_139\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\">\\n<path d=\\\"M352.03 37.7H284.13V129.8H352.03V37.7Z\\\" fill=\\\"black\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 200\\\" style=\\\"mix-blend-mode:multiply\\\" opacity=\\\"0.15\\\">\\n<g id=\\\"Vector_139_2\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\" filter=\\\"url(#filter68_d)\\\">\\n<g id=\\\"Vector_140\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\">\\n<path d=\\\"M68.015 53.179L64.7457 53.4438L72.863 153.676L76.1323 153.411L68.015 53.179Z\\\" fill=\\\"black\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 201\\\" style=\\\"mix-blend-mode:multiply\\\" opacity=\\\"0.15\\\">\\n<g id=\\\"Vector_140_2\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\" filter=\\\"url(#filter69_d)\\\">\\n<g id=\\\"Vector_141\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\">\\n<path d=\\\"M62.37 80.18C60.6982 80.1795 59.0282 80.0726 57.37 79.86C57.1777 79.8348 57.0033 79.7343 56.8852 79.5805C56.767 79.4267 56.7148 79.2323 56.74 79.04C56.7652 78.8477 56.8658 78.6733 57.0195 78.5552C57.1733 78.437 57.3677 78.3848 57.56 78.41C59.1486 78.6135 60.7484 78.717 62.35 78.72C62.4472 78.7187 62.5437 78.7365 62.634 78.7725C62.7243 78.8085 62.8066 78.8619 62.8762 78.9297C62.9459 78.9974 63.0015 79.0783 63.0399 79.1676C63.0783 79.2569 63.0987 79.3528 63.1 79.45C63.1014 79.5462 63.0834 79.6418 63.0472 79.7309C63.011 79.8201 62.9573 79.9011 62.8892 79.9692C62.8211 80.0372 62.7401 80.091 62.651 80.1272C62.5618 80.1634 62.4662 80.1814 62.37 80.18ZM67.29 79.86C67.1116 79.8592 66.9395 79.7941 66.8054 79.6765C66.6713 79.5589 66.5841 79.3968 66.56 79.22C66.5474 79.1248 66.5537 79.028 66.5785 78.9352C66.6033 78.8424 66.6463 78.7554 66.7048 78.6792C66.7633 78.6031 66.8363 78.5392 66.9196 78.4913C67.0028 78.4433 67.0947 78.4123 67.19 78.4C68.7917 78.188 70.3783 77.874 71.94 77.46C72.0326 77.4351 72.1292 77.4286 72.2243 77.441C72.3193 77.4533 72.4111 77.4843 72.4942 77.5322C72.5773 77.58 72.6502 77.6437 72.7086 77.7197C72.7671 77.7957 72.8101 77.8824 72.835 77.975C72.86 78.0676 72.8664 78.1642 72.854 78.2593C72.8417 78.3543 72.8107 78.4461 72.7629 78.5292C72.715 78.6123 72.6513 78.6851 72.5753 78.7436C72.4994 78.8021 72.4126 78.8451 72.32 78.87C70.6963 79.3079 69.0462 79.6419 67.38 79.87L67.29 79.86ZM52.61 78.92C52.547 78.9296 52.483 78.9296 52.42 78.92C50.7996 78.4888 49.2095 77.9509 47.66 77.31C47.5661 77.2777 47.4798 77.2266 47.4063 77.1598C47.3329 77.093 47.2738 77.012 47.2327 76.9216C47.1917 76.8312 47.1695 76.7334 47.1675 76.6341C47.1656 76.5348 47.1839 76.4362 47.2213 76.3443C47.2588 76.2523 47.3146 76.169 47.3854 76.0993C47.4562 76.0297 47.5404 75.9752 47.6329 75.9393C47.7255 75.9033 47.8244 75.8866 47.9236 75.8902C48.0228 75.8937 48.1203 75.9175 48.21 75.96C49.7067 76.5706 51.2396 77.0882 52.8 77.51C52.9868 77.5593 53.1465 77.6807 53.2439 77.8475C53.3414 78.0144 53.3688 78.213 53.32 78.4C53.2729 78.5513 53.1785 78.6834 53.0507 78.777C52.9229 78.8706 52.7684 78.9207 52.61 78.92ZM76.8 77.31C76.655 77.3098 76.5133 77.2671 76.3924 77.1871C76.2715 77.1071 76.1768 76.9934 76.12 76.86C76.0758 76.7694 76.0508 76.6706 76.0467 76.5698C76.0425 76.469 76.0593 76.3685 76.0959 76.2746C76.1326 76.1806 76.1883 76.0953 76.2596 76.0239C76.3308 75.9526 76.4161 75.8968 76.51 75.86C77.9974 75.2396 79.4437 74.5248 80.84 73.72C80.924 73.6714 81.0168 73.6399 81.1131 73.6271C81.2093 73.6144 81.3071 73.6208 81.4009 73.6458C81.4947 73.6709 81.5826 73.7142 81.6597 73.7733C81.7368 73.8323 81.8014 73.906 81.85 73.99C81.8986 74.0741 81.9302 74.1668 81.9429 74.2631C81.9556 74.3593 81.9493 74.4571 81.9242 74.5509C81.8991 74.6447 81.8558 74.7326 81.7968 74.8097C81.7377 74.8868 81.6641 74.9514 81.58 75C80.1303 75.8407 78.6271 76.5857 77.08 77.23C76.9929 77.275 76.8977 77.3021 76.8 77.31ZM43.51 75.16C43.3798 75.1612 43.2518 75.1266 43.14 75.06C41.7033 74.2171 40.3206 73.2853 39 72.27C38.9101 72.2168 38.8325 72.1453 38.7723 72.06C38.7121 71.9747 38.6706 71.8776 38.6505 71.7751C38.6305 71.6727 38.6324 71.5671 38.656 71.4654C38.6797 71.3637 38.7246 71.2682 38.7878 71.1851C38.851 71.102 38.9311 71.0332 39.0228 70.9833C39.1145 70.9333 39.2157 70.9033 39.3198 70.8953C39.4239 70.8873 39.5285 70.9013 39.6268 70.9366C39.7251 70.9719 39.8148 71.0276 39.89 71.1C41.1634 72.0827 42.4996 72.9812 43.89 73.79C43.9736 73.8377 44.047 73.9015 44.1059 73.9776C44.1648 74.0538 44.208 74.1409 44.2331 74.2338C44.2582 74.3268 44.2646 74.4238 44.2521 74.5192C44.2396 74.6147 44.2083 74.7067 44.16 74.79C44.0968 74.9061 44.0025 75.0022 43.8877 75.0675C43.7728 75.1329 43.642 75.1649 43.51 75.16ZM85.31 72.38C85.1974 72.3804 85.0862 72.3544 84.9855 72.304C84.8848 72.2536 84.7973 72.1803 84.73 72.09C84.6189 71.9386 84.5704 71.7502 84.5946 71.564C84.6188 71.3777 84.7139 71.208 84.86 71.09C86.1389 70.1077 87.3515 69.042 88.49 67.9C88.6275 67.777 88.8055 67.709 88.99 67.709C89.1745 67.709 89.3525 67.777 89.49 67.9C89.6173 68.0354 89.6881 68.2142 89.6881 68.4C89.6881 68.5858 89.6173 68.7646 89.49 68.9C88.3037 70.0878 87.041 71.1969 85.71 72.22C85.5958 72.3124 85.4564 72.3681 85.31 72.38ZM35.69 69.17C35.4991 69.1694 35.316 69.094 35.18 68.96C33.9915 67.7743 32.8824 66.5116 31.86 65.18C31.7489 65.0286 31.7004 64.8402 31.7246 64.654C31.7488 64.4677 31.8439 64.298 31.99 64.18C32.1434 64.0724 32.332 64.027 32.5176 64.053C32.7032 64.0789 32.872 64.1744 32.99 64.32C33.9749 65.5968 35.0404 66.8092 36.18 67.95C36.3095 68.0842 36.3819 68.2635 36.3819 68.45C36.3819 68.6365 36.3095 68.8158 36.18 68.95C36.1168 69.0171 36.041 69.0711 35.9569 69.1089C35.8729 69.1466 35.7821 69.1674 35.69 69.17ZM92.26 65.41C92.1001 65.4141 91.9441 65.3609 91.82 65.26C91.6723 65.1435 91.5753 64.9744 91.5492 64.7881C91.5231 64.6018 91.57 64.4126 91.68 64.26C92.6627 62.9866 93.5612 61.6504 94.37 60.26C94.4668 60.0916 94.6266 59.9685 94.8141 59.9179C95.0016 59.8673 95.2016 59.8932 95.37 59.99C95.5384 60.0868 95.6615 60.2466 95.7121 60.4341C95.7627 60.6216 95.7368 60.8216 95.64 60.99C94.7985 62.4404 93.8667 63.8365 92.85 65.17C92.7757 65.2514 92.6842 65.3152 92.5822 65.3567C92.4801 65.3983 92.37 65.4165 92.26 65.41ZM29.69 61.41C29.5607 61.4079 29.434 61.3728 29.322 61.3081C29.21 61.2433 29.1164 61.1511 29.05 61.04C28.2073 59.5913 27.4623 58.088 26.82 56.54C26.7773 56.4491 26.7535 56.3505 26.7501 56.2502C26.7467 56.1498 26.7638 56.0498 26.8002 55.9563C26.8367 55.8627 26.8919 55.7776 26.9623 55.706C27.0328 55.6344 27.117 55.578 27.21 55.54C27.3013 55.496 27.4007 55.4715 27.5019 55.468C27.6032 55.4646 27.704 55.4822 27.7981 55.5198C27.8921 55.5574 27.9773 55.6142 28.0483 55.6866C28.1192 55.7589 28.1743 55.8452 28.21 55.94C28.8318 57.4286 29.55 58.875 30.36 60.27C30.4548 60.4389 30.4796 60.6382 30.4291 60.8251C30.3787 61.0121 30.2569 61.1718 30.09 61.27C29.969 61.3421 29.8308 61.3801 29.69 61.38V61.41ZM97.19 56.92C97.0972 56.9343 97.0028 56.9343 96.91 56.92C96.8171 56.8819 96.7327 56.8255 96.662 56.7541C96.5913 56.6828 96.5356 56.598 96.4983 56.5047C96.461 56.4114 96.4428 56.3116 96.4448 56.2112C96.4468 56.1107 96.469 56.0117 96.51 55.92C97.1282 54.4286 97.6493 52.8987 98.07 51.34C98.0944 51.2464 98.1371 51.1586 98.1957 51.0817C98.2542 51.0047 98.3275 50.9402 98.4113 50.8918C98.495 50.8434 98.5875 50.8122 98.6834 50.7998C98.7794 50.7875 98.8768 50.7944 98.97 50.82C99.0623 50.8443 99.1489 50.8868 99.2246 50.9448C99.3004 51.0029 99.3638 51.0755 99.4113 51.1583C99.4587 51.2411 99.4892 51.3325 99.501 51.4272C99.5128 51.522 99.5057 51.6181 99.48 51.71C99.0488 53.3337 98.511 54.9271 97.87 56.48C97.8073 56.6059 97.7101 56.7113 97.5897 56.7839C97.4692 56.8566 97.3306 56.8933 97.19 56.89V56.92ZM25.9 52.29C25.7399 52.2906 25.5841 52.2379 25.4574 52.1401C25.3306 52.0423 25.24 51.905 25.2 51.75C24.7564 50.131 24.4224 48.4839 24.2 46.82C24.1748 46.6277 24.227 46.4333 24.3452 46.2795C24.4633 46.1258 24.6377 46.0252 24.83 46C25.0223 45.9748 25.2167 46.027 25.3705 46.1452C25.5243 46.2633 25.6248 46.4377 25.65 46.63C25.8615 48.2293 26.1789 49.8128 26.6 51.37C26.649 51.5583 26.6219 51.7582 26.5246 51.9267C26.4273 52.0951 26.2676 52.2185 26.08 52.27C26.0214 52.2861 25.9607 52.2928 25.9 52.29ZM99.73 47.38H99.64C99.5447 47.3677 99.4528 47.3367 99.3696 47.2888C99.2863 47.2409 99.2133 47.177 99.1548 47.1008C99.0963 47.0246 99.0533 46.9376 99.0285 46.8448C99.0037 46.752 98.9974 46.6552 99.01 46.56C99.2135 44.9614 99.317 43.3516 99.32 41.74V41.58C99.32 41.3864 99.3969 41.2007 99.5338 41.0638C99.6707 40.9269 99.8564 40.85 100.05 40.85C100.244 40.85 100.429 40.9269 100.566 41.0638C100.703 41.2007 100.78 41.3864 100.78 41.58V41.72C100.778 43.3917 100.671 45.0617 100.46 46.72C100.443 46.9012 100.358 47.0694 100.223 47.1915C100.088 47.3136 99.9121 47.3809 99.73 47.38ZM24.61 42.5C24.5161 42.5055 24.422 42.4917 24.3337 42.4594C24.2453 42.4272 24.1644 42.3772 24.096 42.3126C24.0277 42.248 23.9732 42.1701 23.9361 42.0836C23.8989 41.9972 23.8798 41.9041 23.88 41.81H24.61L23.88 41.74C23.8756 40.0684 23.9791 38.3983 24.19 36.74C24.2152 36.5477 24.3157 36.3733 24.4695 36.2552C24.6233 36.137 24.8177 36.0848 25.01 36.11C25.2023 36.1352 25.3767 36.2358 25.4948 36.3895C25.613 36.5433 25.6652 36.7377 25.64 36.93C25.4396 38.5054 25.3394 40.0919 25.34 41.68C25.3468 41.782 25.3332 41.8843 25.3 41.9809C25.2668 42.0776 25.2148 42.1666 25.1468 42.243C25.0789 42.3193 24.9964 42.3813 24.9042 42.4254C24.8121 42.4696 24.7121 42.4949 24.61 42.5ZM99.71 37.38C99.5337 37.3814 99.363 37.318 99.2302 37.2019C99.0975 37.0858 99.012 36.925 98.99 36.75C98.7618 35.1472 98.4311 33.5606 98 32C97.9742 31.9074 97.9669 31.8107 97.9786 31.7153C97.9903 31.6199 98.0207 31.5277 98.0681 31.4441C98.1155 31.3605 98.1789 31.287 98.2547 31.228C98.3306 31.1689 98.4173 31.1254 98.51 31.1C98.6033 31.0729 98.701 31.065 98.7974 31.0767C98.8938 31.0884 98.9868 31.1195 99.0709 31.168C99.155 31.2166 99.2284 31.2817 99.2867 31.3594C99.3449 31.437 99.3869 31.5257 99.41 31.62C99.8525 33.2359 100.187 34.8796 100.41 36.54C100.433 36.733 100.38 36.9274 100.263 37.0823C100.145 37.2371 99.9721 37.3403 99.78 37.37L99.71 37.38ZM25.86 32.78C25.8004 32.7895 25.7396 32.7895 25.68 32.78C25.5866 32.7567 25.4987 32.7151 25.4215 32.6576C25.3442 32.6002 25.2791 32.528 25.2298 32.4453C25.1805 32.3626 25.1481 32.2709 25.1344 32.1756C25.1207 32.0803 25.126 31.9833 25.15 31.89C25.5812 30.2663 26.1191 28.6729 26.76 27.12C26.797 27.0262 26.8527 26.9409 26.9239 26.8694C26.995 26.7979 27.08 26.7416 27.1737 26.7042C27.2673 26.6667 27.3676 26.6488 27.4685 26.6515C27.5693 26.6542 27.6685 26.6776 27.76 26.72C27.8539 26.7568 27.9392 26.8126 28.0105 26.8839C28.0817 26.9553 28.1374 27.0406 28.1741 27.1346C28.2107 27.2285 28.2275 27.3291 28.2234 27.4298C28.2192 27.5306 28.1942 27.6294 28.15 27.72C27.5368 29.2113 27.0224 30.7412 26.61 32.3C26.554 32.4506 26.4506 32.5789 26.3153 32.6654C26.18 32.752 26.0202 32.7922 25.86 32.78ZM97.13 27.89C96.9868 27.8879 96.8472 27.8443 96.7283 27.7644C96.6093 27.6845 96.5161 27.5718 96.46 27.44C95.8348 25.9513 95.1133 24.5049 94.3 23.11C94.2513 23.0273 94.2195 22.9358 94.2062 22.8408C94.1929 22.7457 94.1985 22.649 94.2227 22.5561C94.2468 22.4632 94.289 22.376 94.3469 22.2995C94.4048 22.2229 94.4772 22.1585 94.56 22.11C94.7282 22.0169 94.9258 21.992 95.1119 22.0403C95.298 22.0887 95.4584 22.2067 95.56 22.37C96.4 23.8217 97.1482 25.3247 97.8 26.87C97.8442 26.9606 97.8692 27.0594 97.8734 27.1602C97.8775 27.261 97.8607 27.3615 97.8241 27.4555C97.7874 27.5494 97.7317 27.6348 97.6605 27.7061C97.5892 27.7775 97.5039 27.8333 97.41 27.87C97.3188 27.8942 97.2238 27.901 97.13 27.89ZM29.61 23.67C29.483 23.6709 29.3583 23.6363 29.25 23.57C29.1664 23.5223 29.093 23.4585 29.0341 23.3824C28.9753 23.3062 28.932 23.2191 28.9069 23.1262C28.8818 23.0332 28.8754 22.9363 28.8879 22.8408C28.9005 22.7453 28.9318 22.6533 28.98 22.57C29.8179 21.1174 30.7499 19.721 31.77 18.39C31.8865 18.2423 32.0556 18.1453 32.2419 18.1192C32.4282 18.0931 32.6174 18.14 32.77 18.25C32.9156 18.368 33.0111 18.5368 33.0371 18.7224C33.0631 18.908 33.0176 19.0966 32.91 19.25C31.9308 20.5237 31.0355 21.8599 30.23 23.25C30.1742 23.3695 30.0871 23.4716 29.978 23.5456C29.8688 23.6195 29.7416 23.6625 29.61 23.67ZM92.18 19.39C92.0674 19.3904 91.9562 19.3644 91.8555 19.314C91.7548 19.2636 91.6673 19.1903 91.6 19.1C90.6078 17.8265 89.5357 16.6174 88.39 15.48C88.3161 15.3402 88.289 15.1804 88.3126 15.024C88.3361 14.8676 88.4092 14.7229 88.521 14.611C88.6329 14.4992 88.7776 14.4261 88.934 14.4026C89.0903 14.379 89.2502 14.4061 89.39 14.48C90.5753 15.6652 91.6842 16.9244 92.71 18.25C92.7941 18.3574 92.8464 18.4863 92.861 18.622C92.8756 18.7576 92.8519 18.8947 92.7925 19.0175C92.7332 19.1404 92.6406 19.2442 92.5253 19.3171C92.4099 19.39 92.2765 19.4291 92.14 19.43L92.18 19.39ZM35.59 15.85C35.4953 15.8508 35.4014 15.8326 35.3138 15.7966C35.2262 15.7605 35.1467 15.7073 35.08 15.64C34.9549 15.5035 34.8855 15.3251 34.8855 15.14C34.8855 14.9549 34.9549 14.7765 35.08 14.64C36.2652 13.4547 37.5244 12.3458 38.85 11.32C38.9262 11.2609 39.0132 11.2174 39.1062 11.192C39.1992 11.1665 39.2963 11.1596 39.3919 11.1717C39.4876 11.1838 39.5799 11.2146 39.6636 11.2623C39.7474 11.3101 39.8209 11.3738 39.88 11.45C39.9391 11.5262 39.9826 11.6132 40.0081 11.7062C40.0335 11.7992 40.0404 11.8963 40.0283 11.9919C40.0163 12.0876 39.9855 12.1799 39.9377 12.2637C39.89 12.3474 39.8262 12.4209 39.75 12.48C38.4733 13.4649 37.2608 14.5304 36.12 15.67C36.0488 15.7349 35.965 15.7843 35.8738 15.8153C35.7826 15.8463 35.686 15.8581 35.59 15.85ZM85.19 12.45C85.0309 12.4493 84.8764 12.3966 84.75 12.3C83.4736 11.3275 82.1377 10.4358 80.75 9.62998C80.5831 9.53177 80.4614 9.37205 80.4109 9.1851C80.3604 8.99814 80.3852 8.79885 80.48 8.62998C80.5267 8.54535 80.59 8.47099 80.666 8.41134C80.7421 8.35168 80.8294 8.30795 80.9227 8.28276C81.016 8.25756 81.1135 8.25141 81.2092 8.26468C81.305 8.27795 81.3971 8.31036 81.48 8.35998C82.9372 9.19201 84.337 10.1208 85.67 11.14C85.8162 11.258 85.9112 11.4277 85.9354 11.614C85.9596 11.8002 85.9111 11.9886 85.8 12.14C85.7308 12.237 85.6392 12.3158 85.533 12.3698C85.4268 12.4237 85.3091 12.4513 85.19 12.45ZM43.38 9.83998C43.2513 9.84119 43.1247 9.80741 43.0138 9.74224C42.9028 9.67706 42.8116 9.58296 42.75 9.46998C42.7 9.38763 42.667 9.29608 42.653 9.20075C42.639 9.10542 42.6443 9.00825 42.6685 8.915C42.6928 8.82175 42.7355 8.73431 42.7941 8.65787C42.8528 8.58143 42.9262 8.51754 43.01 8.46998C44.4617 7.62996 45.9646 6.88183 47.51 6.22998C47.6015 6.18752 47.7007 6.16421 47.8015 6.16149C47.9024 6.15877 48.0027 6.17669 48.0963 6.21415C48.19 6.25161 48.275 6.30782 48.3461 6.37933C48.4173 6.45084 48.473 6.53614 48.51 6.62998C48.5542 6.72061 48.5792 6.81942 48.5834 6.92018C48.5875 7.02094 48.5707 7.12147 48.5341 7.21542C48.4974 7.30938 48.4417 7.39472 48.3705 7.46607C48.2992 7.53742 48.2139 7.59323 48.12 7.62998C46.6304 8.25314 45.1838 8.97474 43.79 9.78998C43.6598 9.84136 43.5187 9.85857 43.38 9.83998ZM76.65 7.54998C76.5571 7.56311 76.4629 7.56311 76.37 7.54998C74.879 6.93339 73.349 6.4156 71.79 5.99998C71.6017 5.95092 71.4406 5.82906 71.3421 5.66121C71.2437 5.49337 71.2159 5.29328 71.265 5.10498C71.3141 4.91668 71.4359 4.75558 71.6038 4.65712C71.7716 4.55866 71.9717 4.53092 72.16 4.57998C73.7821 5.01234 75.3753 5.54673 76.93 6.17998C77.0898 6.24226 77.2225 6.3588 77.305 6.50917C77.3874 6.65953 77.4143 6.83412 77.3809 7.00232C77.3475 7.17052 77.2559 7.32159 77.1223 7.42904C76.9887 7.5365 76.8215 7.59347 76.65 7.58998V7.54998ZM52.46 5.99998C52.2986 6.00112 52.1414 5.94874 52.0129 5.85104C51.8845 5.75334 51.792 5.61582 51.75 5.45998C51.701 5.27173 51.7281 5.07175 51.8254 4.90331C51.9227 4.73488 52.0824 4.61154 52.27 4.55998C53.8902 4.1212 55.5369 3.78718 57.2 3.55998C57.3919 3.53714 57.5851 3.59026 57.7383 3.70799C57.8915 3.82571 57.9926 3.9987 58.02 4.18998C58.043 4.383 57.9902 4.57742 57.8727 4.73225C57.7552 4.88709 57.5821 4.99025 57.39 5.01998C55.7899 5.24039 54.2063 5.56779 52.65 5.99998H52.46ZM67.13 4.99998H67C65.438 4.79985 63.8648 4.69965 62.29 4.69998H62.17C61.9898 4.67893 61.8237 4.59244 61.7031 4.45694C61.5825 4.32144 61.5159 4.14637 61.5159 3.96498C61.5159 3.78359 61.5825 3.60852 61.7031 3.47302C61.8237 3.33752 61.9898 3.25103 62.17 3.22998H62.28C63.9215 3.23267 65.5612 3.3362 67.19 3.53998C67.3836 3.54794 67.5661 3.63248 67.6974 3.77501C67.8287 3.91753 67.898 4.10637 67.89 4.29998C67.8821 4.49359 67.7975 4.67611 67.655 4.80738C67.5125 4.93866 67.3236 5.00794 67.13 4.99998Z\\\" fill=\\\"black\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 202\\\" style=\\\"mix-blend-mode:multiply\\\" opacity=\\\"0.15\\\">\\n<g id=\\\"Vector_141_2\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\" filter=\\\"url(#filter70_d)\\\">\\n<g id=\\\"Vector_142\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\">\\n<path d=\\\"M62.33 72.17C79.1415 72.17 92.77 58.5416 92.77 41.73C92.77 24.9185 79.1415 11.29 62.33 11.29C45.5185 11.29 31.89 24.9185 31.89 41.73C31.89 58.5416 45.5185 72.17 62.33 72.17Z\\\" fill=\\\"black\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 203\\\" style=\\\"mix-blend-mode:multiply\\\" opacity=\\\"0.15\\\">\\n<g id=\\\"Vector_142_2\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\" filter=\\\"url(#filter71_d)\\\">\\n<g id=\\\"Vector_143\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\">\\n<path d=\\\"M37.48 32.1199C37.08 33.8699 37.1 35.2099 36.19 36.9099C35.3618 38.1575 34.9456 39.6334 35 41.1299C35 43.5599 34.26 50.8299 38.55 49.6999C42.1 48.7699 40.16 44.0999 42.68 42.0599C43.87 41.0599 45.42 41.4699 46.15 39.9299C46.88 38.3899 45.94 37.0099 47.15 35.7099C49.23 33.3899 53.56 34.3699 55.15 31.5799C52.61 30.0999 49.75 28.8399 51.15 25.0099C51.68 23.5899 53.38 22.4299 53.36 20.7499C53.36 18.5299 51.76 20.1099 50.3 18.9799C49.09 18.0399 50.3 16.2799 49.21 15.4699C48.9502 15.342 48.6645 15.2754 48.375 15.2754C48.0854 15.2754 47.7998 15.342 47.54 15.4699C43.157 17.5275 39.4872 20.8456 37 24.9999C40.86 24.4699 37.82 30.6699 37.48 32.1199Z\\\" fill=\\\"black\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 204\\\" style=\\\"mix-blend-mode:multiply\\\" opacity=\\\"0.15\\\">\\n<g id=\\\"Vector_143_2\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\" filter=\\\"url(#filter72_d)\\\">\\n<g id=\\\"Vector_144\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\">\\n<path d=\\\"M48.4 42.3299C47.5 43.1699 46.25 42.3299 45.3 43.1199C44.91 43.4499 44.39 46.6699 44.76 47.2199C46 49.0999 48.94 43.6599 49 42.4399C48.9207 42.3666 48.8222 42.3174 48.716 42.2979C48.6097 42.2784 48.5002 42.2895 48.4 42.3299Z\\\" fill=\\\"black\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 205\\\" style=\\\"mix-blend-mode:multiply\\\" opacity=\\\"0.15\\\">\\n<g id=\\\"Vector_144_2\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\" filter=\\\"url(#filter73_d)\\\">\\n<g id=\\\"Vector_145\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\">\\n<path d=\\\"M87.11 59.3999C86.8259 58.8178 86.4513 58.2845 86 57.8199C85.6653 57.5772 85.2717 57.4287 84.8601 57.39C84.4485 57.3514 84.034 57.4238 83.66 57.5999L80.43 58.9999C78.43 59.8699 75.91 59.2699 73.79 60.2099C70.51 61.6599 65.18 67.5499 72.26 66.1199C73.13 65.9499 74.26 65.2599 75.03 65.7499C75.0937 66.9557 75.0937 68.1641 75.03 69.3699C79.8554 67.154 84.0192 63.7175 87.11 59.3999Z\\\" fill=\\\"black\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 206\\\" style=\\\"mix-blend-mode:multiply\\\" opacity=\\\"0.15\\\">\\n<g id=\\\"Vector_145_2\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\" filter=\\\"url(#filter74_d)\\\">\\n<g id=\\\"Vector_146\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\">\\n<path d=\\\"M87.23 58.1901C87.4545 58.0827 87.6531 57.9278 87.8119 57.7361C87.9708 57.5445 88.0861 57.3207 88.15 57.0801C87.85 57.4601 87.54 57.8201 87.23 58.1801V58.1901Z\\\" fill=\\\"black\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 207\\\" style=\\\"mix-blend-mode:multiply\\\" opacity=\\\"0.15\\\">\\n<g id=\\\"Vector_146_2\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\" filter=\\\"url(#filter75_d)\\\">\\n<g id=\\\"Vector_147\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\">\\n<path d=\\\"M86.8399 53.7801C85.8999 55.1401 87.2799 56.6401 87.2299 58.1801C87.5399 57.8201 87.8499 57.4601 88.1499 57.0801C88.6399 55.6701 88.2699 53.5201 86.8399 53.7801Z\\\" fill=\\\"black\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 208\\\" style=\\\"mix-blend-mode:multiply\\\" opacity=\\\"0.15\\\">\\n<g id=\\\"Vector_147_2\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\" filter=\\\"url(#filter76_d)\\\">\\n<g id=\\\"Vector_148\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\">\\n<path d=\\\"M84.26 49.46C83.09 50.39 81.4 49.85 80.26 50.77C79.9961 50.988 79.7953 51.2725 79.6783 51.5941C79.5613 51.9158 79.5324 52.2628 79.5946 52.5994C79.6568 52.9359 79.8079 53.2497 80.0321 53.5083C80.2564 53.7669 80.5456 53.9608 80.87 54.07C83.27 55.07 83.18 52.68 83.87 51.34C84.17 50.75 85.35 50.13 85.31 49.45C85.25 48.33 84.75 49.07 84.26 49.46Z\\\" fill=\\\"black\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 209\\\" style=\\\"mix-blend-mode:multiply\\\" opacity=\\\"0.15\\\">\\n<g id=\\\"Vector_148_2\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\" filter=\\\"url(#filter77_d)\\\">\\n<g id=\\\"Vector_149\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\">\\n<path d=\\\"M74.23 47.1501C74.23 48.2301 74.86 49.3901 74.85 50.5001C74.85 51.2701 74.28 55.2101 76.16 52.6001C76.86 51.6001 76.26 47.4401 75.16 46.4101C74.74 46.0501 74.23 46.8701 74.23 47.1501Z\\\" fill=\\\"black\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 210\\\" style=\\\"mix-blend-mode:multiply\\\" opacity=\\\"0.15\\\">\\n<g id=\\\"Vector_149_2\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\" filter=\\\"url(#filter78_d)\\\">\\n<g id=\\\"Vector_150\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\">\\n<path d=\\\"M88.54 43.5399C88.3 42.9699 87.03 42.7699 87.12 43.6799C87.29 46.2899 85.34 47.2099 87.12 49.7599C87.94 48.9299 87.96 48.0199 88.12 46.8599C88.12 46.5099 87.92 45.7899 87.94 45.3999C88 44.7299 88.7 44.3999 88.54 43.5399Z\\\" fill=\\\"black\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 211\\\" style=\\\"mix-blend-mode:multiply\\\" opacity=\\\"0.15\\\">\\n<g id=\\\"Vector_150_2\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\" filter=\\\"url(#filter79_d)\\\">\\n<g id=\\\"Vector_151\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\">\\n<path d=\\\"M60.3999 26.9299C59.7499 25.9999 59.6799 26.2199 59.4999 25.0099C59.2899 23.6399 59.7799 22.3999 59.0099 21.2399C58.5863 20.6455 58.0138 20.173 57.3499 19.8699C57.1707 19.777 56.9718 19.7285 56.7699 19.7285C56.568 19.7285 56.3691 19.777 56.1899 19.8699C55.0899 19.8699 53.9199 19.9499 53.4099 20.9599C52.9899 21.7999 53.1899 23.9599 52.9799 25.0399C52.1299 29.2899 54.8199 29.3099 58.2599 29.3099C59.4499 29.3099 61.6099 29.8899 61.4599 28.2299C61.4099 27.6599 60.6699 27.3299 60.3999 26.9299Z\\\" fill=\\\"black\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 212\\\" style=\\\"mix-blend-mode:multiply\\\" opacity=\\\"0.15\\\">\\n<g id=\\\"Vector_151_2\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\" filter=\\\"url(#filter80_d)\\\">\\n<g id=\\\"Vector_152\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\">\\n<path d=\\\"M87.38 39.9299C89.26 38.9299 87.1 38.2799 86.88 37.2299C86.6 35.8999 88.15 34.9499 87.58 33.5299C89.58 32.4099 89.51 35.6999 89.58 36.8799C91.42 36.8799 89.69 34.1199 89.51 33.2199C89.21 31.6899 90.07 30.6099 89.88 29.0999C89.88 28.8799 89.8 28.6399 89.76 28.3999C87.3194 23.4373 83.5804 19.2283 78.94 16.2199C78.8631 16.2607 78.7895 16.3075 78.72 16.3599C76.72 18.0499 79.21 18.5299 78.87 19.8699C78.67 20.6599 77.65 20.4599 77.07 20.5899C77.2 20.5899 74.84 20.8699 75.17 20.9799C75.1583 21.019 75.1322 21.0522 75.0968 21.0726C75.0615 21.0931 75.0197 21.0993 74.98 21.0899C74.85 19.4099 73.24 17.7899 71.62 18.9499C70.09 17.3599 72.62 16.1599 72.79 14.5699C71.88 14.5199 70.79 14.3499 70.02 14.9299C69.02 15.6999 69.52 16.6199 68.24 16.9899C68.06 17.0399 67.38 16.4899 66.96 16.6599C66.32 16.9099 66.3 17.5699 65.96 18.0899C65.4538 19.0389 64.847 19.9307 64.15 20.7499C63.33 21.4699 62.85 22.1599 62.33 20.7499C61.81 19.3399 63.39 19.2899 63.61 18.0799C63.93 16.3799 60.28 15.5199 60.61 18.2399C59.29 18.3399 58.29 17.0199 56.73 17.2399C54.64 17.4899 55.29 18.0799 57.08 18.6599C60.68 19.8299 60.36 21.3199 61.21 24.4799C62.14 27.9599 65.85 26.3699 65.96 29.8499C66.02 31.6099 66.55 32.0499 67.16 33.5799C67.77 35.1099 67.23 35.9199 66.84 37.4699C66.57 38.5599 65.84 40.4699 67.2 40.6799C68.61 39.9699 69.66 39.7699 70.4 38.1899C70.77 37.4099 70.25 37.0899 71.11 36.5499C71.97 36.0099 72.72 36.6699 73.42 36.5999C74.71 36.4899 75.91 35.3499 77.14 36.2299C78.85 37.4499 77.42 38.9199 77.68 40.3199C77.94 41.7199 79.86 42.0399 80.22 43.3199C80.58 44.5999 78.22 45.3199 78.56 46.5599C79.18 49.1299 80.25 45.3199 80.56 45.0899C81.01 44.6999 82.07 45.0899 82.4 44.6599C82.73 44.2299 82.58 42.9799 82.53 42.4699C82.39 41.0599 81.62 40.1499 83.41 39.6299C84.57 39.1999 86.19 40.5499 87.38 39.9299Z\\\" fill=\\\"black\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 213\\\" style=\\\"mix-blend-mode:multiply\\\" opacity=\\\"0.15\\\">\\n<g id=\\\"Vector_152_2\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\" filter=\\\"url(#filter81_d)\\\">\\n<g id=\\\"Vector_153\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\">\\n<path d=\\\"M62.12 11.65C62.0214 11.5262 61.9145 11.4093 61.8 11.3C59.5008 11.3363 57.2131 11.6315 54.98 12.18C55.1395 12.2265 55.2877 12.3056 55.4151 12.4123C55.5425 12.519 55.6463 12.651 55.72 12.8C56.35 13.91 54.61 15.58 56.21 16.04C57.15 16.31 57.21 15.16 57.97 14.98C58.5438 14.8764 59.1281 14.8428 59.71 14.88C60.95 14.88 62 15.75 62.81 14.29C62.6046 14.1122 62.3874 13.9485 62.16 13.8C62.25 12.8 62.77 12.47 62.12 11.65Z\\\" fill=\\\"black\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 214\\\" style=\\\"mix-blend-mode:multiply\\\" opacity=\\\"0.15\\\">\\n<g id=\\\"Vector_153_2\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\" filter=\\\"url(#filter82_d)\\\">\\n<g id=\\\"Vector_154\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\">\\n<path d=\\\"M48.86 42.4299C35.93 42.4299 25.46 50.1499 25.46 59.6699C25.5164 63.1322 26.8439 66.453 29.19 68.9999L21.36 80.4099L36.05 74.0899C40.0546 75.9783 44.4326 76.9421 48.86 76.9099C61.78 76.9099 72.26 69.1899 72.26 59.6699C72.26 50.1499 61.78 42.4299 48.86 42.4299Z\\\" fill=\\\"black\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 215\\\" style=\\\"mix-blend-mode:multiply\\\" opacity=\\\"0.15\\\">\\n<g id=\\\"Vector_154_2\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\" filter=\\\"url(#filter83_d)\\\">\\n<g id=\\\"Vector_155\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\">\\n<path d=\\\"M52.9299 63.61H43.9999L42.3799 67.46H38.7999L46.7999 49.25H50.3999L58.2899 67.46H54.5399L52.9299 63.61ZM51.6799 60.61L48.4999 53L45.2799 60.65L51.6799 60.61Z\\\" fill=\\\"black\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 216\\\" style=\\\"mix-blend-mode:multiply\\\" opacity=\\\"0.15\\\">\\n<g id=\\\"Vector_155_2\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\" filter=\\\"url(#filter84_d)\\\">\\n<g id=\\\"Vector_156\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\">\\n<path d=\\\"M83.53 0C94.87 0 104.06 6.78 104.06 15.13C104.01 18.1702 102.842 21.0854 100.78 23.32L107.65 33.32L94.76 27.79C91.2498 29.4478 87.4119 30.2954 83.53 30.27C72.18 30.27 63 23.49 63 15.13C63 6.77 72.18 0 83.53 0Z\\\" fill=\\\"black\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 217\\\" style=\\\"mix-blend-mode:multiply\\\" opacity=\\\"0.15\\\">\\n<g id=\\\"Vector_156_2\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\" filter=\\\"url(#filter85_d)\\\">\\n<g id=\\\"Vector_157\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\">\\n<path d=\\\"M88.74 7.93994V9.79994L80.61 19.4499H88.84V21.7599H77V19.8899L85.14 10.2499H77.24V7.93994H88.74Z\\\" fill=\\\"black\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 218\\\" style=\\\"mix-blend-mode:multiply\\\" opacity=\\\"0.15\\\">\\n<g id=\\\"Vector_157_2\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\" filter=\\\"url(#filter86_d)\\\">\\n<g id=\\\"Vector_158\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\">\\n<path d=\\\"M71.75 132.91C72.35 135.67 70.18 136.96 67.96 137.21C65.74 137.46 64.09 135.37 63.74 133.82C63.39 132.27 64.9 130.82 67.11 130.55C69.32 130.28 71.19 130.39 71.75 132.91Z\\\" fill=\\\"black\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 219\\\" style=\\\"mix-blend-mode:multiply\\\" opacity=\\\"0.15\\\">\\n<g id=\\\"Vector_158_2\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\" filter=\\\"url(#filter87_d)\\\">\\n<g id=\\\"Vector_159\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\">\\n<path d=\\\"M74 137.55C74.44 140.17 71.3 141.23 68.63 141.55C68.1571 141.643 67.6704 141.641 67.1982 141.545C66.726 141.448 66.2775 141.259 65.8787 140.989C65.4798 140.718 65.1385 140.371 64.8744 139.968C64.6103 139.565 64.4287 139.114 64.34 138.64C63.99 137.09 65.87 135.64 68.53 135.29C71.19 134.94 73.6 135.05 74 137.55Z\\\" fill=\\\"black\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 220\\\" style=\\\"mix-blend-mode:multiply\\\" opacity=\\\"0.15\\\">\\n<g id=\\\"Vector_159_2\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\" filter=\\\"url(#filter88_d)\\\">\\n<g id=\\\"Vector_160\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\">\\n<path d=\\\"M73.9099 142.2C74.3299 144.81 72.5599 145.2 70.0999 145.51C67.6399 145.82 65.3799 144.76 65.0299 143.2C64.6799 141.64 66.3899 140.2 68.8399 139.89C71.2899 139.58 73.5099 139.68 73.9099 142.2Z\\\" fill=\\\"black\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<g id=\\\"Vector5656231 221\\\" style=\\\"mix-blend-mode:multiply\\\" opacity=\\\"0.15\\\">\\n<g id=\\\"Vector_160_2\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\" filter=\\\"url(#filter89_d)\\\">\\n<g id=\\\"Vector_161\\\" style=\\\"mix-blend-mode:overlay\\\" opacity=\\\"0.15\\\">\\n<path d=\\\"M72.6 146.21C72.85 147.6 71.68 148.51 69.95 148.71C68.22 148.91 66.6 148.1 66.33 146.91C66.06 145.72 67.25 144.6 68.98 144.41C70.71 144.22 72.2 143.92 72.6 146.21Z\\\" fill=\\\"black\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<path id=\\\"Vector5656231 222\\\" d=\\\"M113.31 187.61C85.09 192.23 69.5 155.61 68.15 149.52C68.81 147.2 73.52 141.86 76.64 145.86C94 168.22 97.93 164.8 111.3 169.06C124.37 173.23 121.51 186.26 113.31 187.61Z\\\" fill=\\\"#B57D68\\\"\\\/>\\n<path id=\\\"Vector5656231 223\\\" d=\\\"M156.91 162.56C158.73 159.95 152.68 148.05 149.43 149.56C127.6 159.77 121.35 166.83 104.12 166.69C93.26 166.6 100.32 182.11 104.74 186.96C119.45 193.87 148.73 174.28 156.91 162.56Z\\\" fill=\\\"#B57D68\\\"\\\/>\\n<path id=\\\"Vector5656231 224\\\" d=\\\"M104.25 184.4C85.89 179.2 76.82 164.4 68.42 148.84C68.3135 149.06 68.2233 149.287 68.15 149.52C69.5 155.58 85.09 192.23 113.31 187.61C115.159 187.301 116.845 186.361 118.08 184.95C113.475 185.605 108.789 185.418 104.25 184.4Z\\\" fill=\\\"#9E5B44\\\"\\\/>\\n<path id=\\\"Vector5656231 225\\\" d=\\\"M104.25 184.4C103.62 184.22 103.03 184 102.43 183.79C103.105 184.913 103.878 185.974 104.74 186.96C119.45 193.87 148.74 174.28 156.91 162.56C157.28 162.03 154.5 153.49 154.31 152.38C140.65 167.17 125.69 185 104.25 184.4Z\\\" fill=\\\"#9E5B44\\\"\\\/>\\n<path id=\\\"Vector5656231 226\\\" d=\\\"M220.9 169.09C247.75 179.23 269.8 146.34 272.25 140.66C272.02 138.25 268.38 132.07 264.59 135.38C243.42 153.89 240.2 149.76 226.29 151.29C212.69 152.79 213.1 166.15 220.9 169.09Z\\\" fill=\\\"#B57D68\\\"\\\/>\\n<path id=\\\"Vector5656231 227\\\" d=\\\"M228.35 165.75C226.98 164.33 228.71 157.56 228.07 151.12C227.49 151.12 226.9 151.22 226.29 151.29C212.69 152.79 213.1 166.15 220.9 169.09C247.75 179.23 269.8 146.34 272.25 140.66C272.25 140.53 272.25 140.38 272.18 140.23C256.89 149.71 246.33 170.83 228.35 165.75Z\\\" fill=\\\"#9E5B44\\\"\\\/>\\n<path id=\\\"Vector5656231 228\\\" d=\\\"M274 127.45C275.61 126.9 278.19 126.37 279.28 127.45C279.88 128.03 279.36 129.5 278.35 129.7C277.803 129.82 277.294 130.075 276.87 130.44C276.123 131.234 275.478 132.117 274.95 133.07L279.47 134.3L283.47 134.23C284.814 133.527 286.111 132.735 287.35 131.86C288.4 130.86 290.54 131.48 290.35 131.92C290.002 132.87 289.453 133.733 288.74 134.45C289.766 133.957 290.718 133.324 291.57 132.57C292.31 131.86 295.13 132.36 293.68 134.57C294.62 135.22 294.57 135.52 293.81 136.57C292.979 137.464 291.997 138.205 290.91 138.76C291.696 138.297 292.566 137.994 293.47 137.87C294.47 137.79 294.38 139.32 293.73 140.1C291.16 143.1 284.54 144.75 281.89 145.1C275.39 145.86 268.24 143.1 268.24 143.1L262.15 138.65C262.15 138.65 264.24 134.65 265.15 133.35C267.41 130.16 271.48 128.3 274 127.45Z\\\" fill=\\\"#B57D68\\\"\\\/>\\n<path id=\\\"Vector5656231 229\\\" d=\\\"M186.42 290.79C184.18 315.79 188.69 350.79 192.42 366.7C196.15 382.61 202.42 369.52 203.31 365.7C205.74 355.15 207.82 302.15 208 292.7C208.26 277.4 186.84 286.18 186.42 290.79Z\\\" fill=\\\"#B57D68\\\"\\\/>\\n<path id=\\\"Vector5656231 230\\\" d=\\\"M204.22 359.75C204.22 359.75 210.04 368.87 210.74 372.87C213.01 385.68 184.6 378.77 185.24 376.2C186.38 371.59 190.03 363.08 191.08 360.43C195.421 361.61 200.024 361.371 204.22 359.75Z\\\" fill=\\\"#B57D68\\\"\\\/>\\n<path id=\\\"Vector5656231 231\\\" d=\\\"M185.21 374.68C186.09 371.44 188.61 366.47 189.72 362.84C189.72 363.42 188.84 368.64 190.58 370.02C195.22 368.37 199.91 369.18 204.52 369.02C205.88 367.45 205.33 363.09 205.04 361.46C205.04 361.46 209.58 369.31 210.74 372.86C213.14 380.15 212.15 381.69 210.63 383.86C210.63 385.03 210.18 385.13 210.18 385.13C206.047 385.561 201.895 385.785 197.74 385.8C192.85 385.91 185.41 385.92 185.41 385.92V384.42C183.36 382.12 184.56 377 185.21 374.68Z\\\" fill=\\\"#68333E\\\"\\\/>\\n<path id=\\\"Vector5656231 232\\\" d=\\\"M205 368.05C205.67 366.1 205.26 362.84 205 361.47C205 361.47 209.54 369.32 210.7 372.87C213.1 380.16 212.11 381.7 210.59 383.87C210.59 385.04 210.14 385.14 210.14 385.14C210.14 385.14 208.85 385.32 205.68 385.51C207.093 379.741 206.858 373.691 205 368.05Z\\\" fill=\\\"#5B222D\\\"\\\/>\\n<path id=\\\"Vector5656231 233\\\" d=\\\"M189.89 384.51C194.38 384.51 198.89 384.8 203.41 384.38C205.32 384.19 208.41 384.24 210.83 383.56C210.769 383.657 210.702 383.751 210.63 383.84C210.63 385.01 210.18 385.11 210.18 385.11C206.047 385.541 201.895 385.765 197.74 385.78C192.85 385.89 185.41 385.9 185.41 385.9V384.42C186.9 384.537 188.396 384.567 189.89 384.51Z\\\" fill=\\\"#5F2037\\\"\\\/>\\n<path id=\\\"Vector5656231 234\\\" d=\\\"M192.09 374.63C192.19 374.626 192.289 374.602 192.38 374.56C196.6 372.38 200.56 372.24 204.15 374.15C204.228 374.191 204.313 374.215 204.4 374.222C204.488 374.229 204.576 374.218 204.659 374.19C204.742 374.162 204.819 374.117 204.884 374.059C204.95 374.001 205.003 373.929 205.04 373.85C205.122 373.688 205.137 373.5 205.083 373.326C205.029 373.153 204.91 373.007 204.75 372.92C200.75 370.8 196.41 370.92 191.75 373.32C191.59 373.407 191.47 373.552 191.415 373.725C191.359 373.898 191.371 374.086 191.45 374.25C191.507 374.37 191.598 374.469 191.712 374.537C191.826 374.605 191.958 374.637 192.09 374.63Z\\\" fill=\\\"#E2C0AE\\\"\\\/>\\n<path id=\\\"Vector5656231 235\\\" d=\\\"M195.47 377.14C195.592 377.139 195.71 377.103 195.813 377.038C195.915 376.973 195.998 376.88 196.05 376.77C196.36 376.55 199.72 375.53 201.63 376.51C201.709 376.55 201.795 376.574 201.884 376.579C201.972 376.585 202.061 376.572 202.144 376.542C202.227 376.512 202.304 376.465 202.368 376.405C202.433 376.344 202.485 376.271 202.52 376.19C202.601 376.028 202.614 375.841 202.558 375.669C202.502 375.496 202.381 375.353 202.22 375.27C199.76 374.01 195.36 375.12 194.86 376.14C194.778 376.302 194.763 376.49 194.817 376.664C194.871 376.837 194.99 376.983 195.15 377.07C195.248 377.123 195.359 377.147 195.47 377.14Z\\\" fill=\\\"#E2C0AE\\\"\\\/>\\n<path id=\\\"Vector5656231 236\\\" d=\\\"M163.51 297.17C162.86 291.92 144.06 277.07 142.87 293.17C141.14 316.41 142.67 367.07 144.16 373.47C145.65 379.87 150.93 377.52 152.41 374.58C153.89 371.64 168.1 334.46 163.51 297.17Z\\\" fill=\\\"#B57D68\\\"\\\/>\\n<path id=\\\"Vector5656231 237\\\" d=\\\"M157.31 359.79C157.31 359.79 158.95 368.35 158.44 372.08C157.93 375.81 135.7 373.27 135.7 373.27C135.7 373.27 139.08 366.27 143.7 362.83C155.4 363.09 157.31 359.79 157.31 359.79Z\\\" fill=\\\"#B57D68\\\"\\\/>\\n<path id=\\\"Vector5656231 238\\\" d=\\\"M157.7 361.18C157.61 361.6 157.5 362.02 157.38 362.46C156.19 366.92 151.9 367.9 149.02 368.34C145.22 367.7 141.11 366.15 139.94 366.23C133.67 371.84 131.94 371.29 127.23 374.92C123.7 377.66 123.74 380.81 123.47 382.92C123.05 386.28 126.3 386.15 134.75 386.22C141.86 386.28 157.75 385.67 159.37 384.13C159.652 383.35 159.697 382.505 159.5 381.7C162.79 376.83 158.67 364.53 157.7 361.18Z\\\" fill=\\\"#68333E\\\"\\\/>\\n<path id=\\\"Vector5656231 239\\\" d=\\\"M149.11 380C151.743 376.224 153.197 371.752 153.29 367.15C154.291 366.734 155.181 366.09 155.891 365.271C156.6 364.452 157.11 363.48 157.38 362.43C157.5 361.99 157.61 361.57 157.7 361.15C158.7 364.5 162.79 376.8 159.5 381.71C159.697 382.515 159.652 383.36 159.37 384.14C158.16 385.28 149.13 385.91 141.64 386.14C144.621 384.776 147.195 382.66 149.11 380Z\\\" fill=\\\"#5B222D\\\"\\\/>\\n<path id=\\\"Vector5656231 240\\\" d=\\\"M123.5 382.48C127.91 384.65 133.76 384.81 143.36 384.48C148.3 384.31 155.36 384.76 159.52 381.69C159.695 382.69 159.637 383.716 159.35 384.69C157.72 386.23 141.82 386.2 134.71 386.09C124.49 385.94 123.05 386.35 123.47 382.99C123.491 382.821 123.501 382.65 123.5 382.48Z\\\" fill=\\\"#5F2037\\\"\\\/>\\n<path id=\\\"Vector5656231 241\\\" d=\\\"M146 374.44C146.093 374.439 146.186 374.418 146.27 374.378C146.355 374.339 146.43 374.281 146.49 374.21C146.611 374.068 146.673 373.886 146.663 373.7C146.654 373.514 146.574 373.339 146.44 373.21C143.06 370.04 138.66 368.91 133.38 369.86C133.201 369.896 133.043 370.001 132.94 370.153C132.837 370.304 132.798 370.49 132.83 370.67C132.842 370.761 132.872 370.848 132.919 370.927C132.966 371.005 133.028 371.074 133.102 371.128C133.175 371.182 133.259 371.221 133.348 371.242C133.437 371.263 133.53 371.266 133.62 371.25C138.46 370.38 142.47 371.39 145.53 374.25C145.592 374.312 145.665 374.36 145.746 374.393C145.826 374.425 145.913 374.441 146 374.44Z\\\" fill=\\\"#E2C0AE\\\"\\\/>\\n<path id=\\\"Vector5656231 242\\\" d=\\\"M139.13 375.72C139.225 375.716 139.319 375.693 139.405 375.652C139.491 375.61 139.567 375.552 139.63 375.48C139.749 375.337 139.81 375.154 139.799 374.968C139.787 374.782 139.706 374.608 139.57 374.48C137.57 372.62 132.77 372.38 132.01 373.19C131.883 373.325 131.812 373.504 131.812 373.69C131.812 373.876 131.883 374.055 132.01 374.19C132.071 374.263 132.147 374.323 132.234 374.363C132.32 374.404 132.415 374.425 132.51 374.425C132.605 374.425 132.7 374.404 132.786 374.363C132.873 374.323 132.949 374.263 133.01 374.19C133.5 374.02 137.11 374.1 138.7 375.55C138.82 375.654 138.972 375.714 139.13 375.72Z\\\" fill=\\\"#E2C0AE\\\"\\\/>\\n<path id=\\\"Vector5656231 243\\\" d=\\\"M205.16 229.67C212.61 271.11 209.51 274.58 210.36 305.67C210.72 318.4 209.36 346.78 208.13 353.72C199.13 361.72 184.47 354.93 184.47 354.93C184.47 354.93 179.74 318.93 178.15 306.99C176.35 293.34 168.33 233.76 168.33 233.76L205.16 229.67Z\\\" fill=\\\"#5F432E\\\"\\\/>\\n<path id=\\\"Vector5656231 244\\\" d=\\\"M210.36 305.62C209.51 274.62 212.61 271.11 205.16 229.62L168.33 233.62L171.75 259.07C181.55 258.78 191.46 257.77 201.37 257.07C199.71 289.83 204.18 324.19 200.6 357.2C203.397 356.735 206.007 355.49 208.13 353.61C209.32 346.73 210.72 318.35 210.36 305.62Z\\\" fill=\\\"#5A3F2C\\\"\\\/>\\n<path id=\\\"Vector5656231 245\\\" d=\\\"M200.46 259.24C194.37 257.37 192.99 249.97 192.46 244.38C192.46 244.29 192.424 244.203 192.36 244.14C192.297 244.076 192.21 244.04 192.12 244.04C192.03 244.04 191.943 244.076 191.88 244.14C191.816 244.203 191.78 244.29 191.78 244.38C191.12 251.46 191.64 257.89 198.22 261.61C200.039 262.613 202.056 263.206 204.129 263.348C206.202 263.49 208.281 263.176 210.22 262.43C210.141 261.343 210.001 260.261 209.8 259.19C206.753 260.085 203.516 260.102 200.46 259.24Z\\\" fill=\\\"#4B3321\\\"\\\/>\\n<path id=\\\"Vector5656231 246\\\" d=\\\"M140.45 229.94C140.45 229.94 134.83 272.05 134.83 293.49C134.83 316.97 141.57 358.3 141.57 358.3C141.57 358.3 156.57 360.94 160.9 356.44C162.8 351.55 164.06 313.03 165.4 300.02C166.74 287.01 176.57 234.45 176.57 234.45L140.45 229.94Z\\\" fill=\\\"#5F432E\\\"\\\/>\\n<path id=\\\"Vector5656231 247\\\" d=\\\"M155.51 358.72C157.499 358.534 159.382 357.738 160.9 356.44C162.8 351.55 164.06 313.03 165.4 300.02C166.03 293.9 168.51 279.23 170.96 265.32C154.4 292.84 159.07 327.68 155.51 358.72Z\\\" fill=\\\"#5A3F2C\\\"\\\/>\\n<path id=\\\"Vector5656231 248\\\" d=\\\"M140.45 229.94C140.45 229.94 138.93 241.37 137.45 255.35C148.71 258.83 160.3 259.52 172.05 259.15C174.45 245.74 176.56 234.45 176.56 234.45L140.45 229.94Z\\\" fill=\\\"#5A3F2C\\\"\\\/>\\n<path id=\\\"Vector5656231 249\\\" d=\\\"M147.63 246.19C147.55 245.96 147.16 245.97 147.19 246.25C147.79 251.3 145.05 256.17 141.93 259.83C140.649 261.469 138.781 262.545 136.72 262.83C136.63 263.99 136.62 265.18 136.62 266.36C144.13 265.78 150.31 253.47 147.63 246.19Z\\\" fill=\\\"#4B3321\\\"\\\/>\\n<path id=\\\"Vector5656231 250\\\" d=\\\"M223.4 148.73C223.4 148.73 220.49 178.57 218 178.57C215.51 178.57 176.73 168.57 176.86 161.57C178.95 156.42 181.43 138.07 189.68 139.42C202.49 141.5 211 144.66 223.4 148.73Z\\\" fill=\\\"#CA5D69\\\"\\\/>\\n<path id=\\\"Vector5656231 251\\\" d=\\\"M119.31 161.55C119.31 161.55 126.4 188.72 128.76 187.89C131.12 187.06 161.09 173.89 158.81 167.3C162.7 154.87 161.43 139.39 150.71 141.5C142.3 143.16 129.66 155.49 119.31 161.55Z\\\" fill=\\\"#CA5D69\\\"\\\/>\\n<path id=\\\"Vector5656231 252\\\" d=\\\"M200.72 143.68C200.72 141.54 182.72 136.32 170.18 136.53C156.37 136.76 143.63 144.13 143.52 146.16C142.3 168.32 139.32 225.16 135.35 246.31C150.83 255.92 184.26 256.12 209.51 244.69C202.87 222 200.77 162.64 200.72 143.68Z\\\" fill=\\\"#EB6D79\\\"\\\/>\\n<path id=\\\"Vector5656231 253\\\" d=\\\"M209.51 244.69C202.87 222.01 200.77 162.64 200.72 143.69C200.72 142.69 196.89 141.07 191.55 139.6C196.36 179.55 194.55 226.66 166.13 253.4C180.28 253.57 196.06 250.78 209.51 244.69Z\\\" fill=\\\"#CA5D69\\\"\\\/>\\n<path id=\\\"Vector5656231 254\\\" d=\\\"M164.84 149C163.049 146.398 161.672 143.534 160.76 140.51C160.47 139.56 160.31 138.51 160.07 137.43C163.415 136.897 166.793 136.6 170.18 136.54C173.931 136.478 177.684 136.618 181.42 136.96C180.44 144 171 158 164.84 149Z\\\" fill=\\\"#B57D68\\\"\\\/>\\n<path id=\\\"Vector5656231 255\\\" d=\\\"M171.22 29.3699C160 24.6299 151 25.6699 143.44 31.1299C142.52 31.7199 141.59 32.3099 140.62 32.8899C136.583 35.4352 132.285 37.5406 127.8 39.1699C126.29 39.6799 131.14 43.0199 132.92 42.8399C131.72 44.7199 130.56 46.7199 129.43 48.8399C127.43 52.6999 122.1 64.9799 120.09 68.0699C119.24 69.3699 125.36 69.4599 126.87 68.5099C128.87 75.5099 133.07 83.4299 133.93 99.5099C133.93 99.5099 203.45 112.68 205.57 96.7099C207 86.1999 211.86 81.1999 214.26 70.9999C220.25 40.1699 186.51 22.5299 171.22 29.3699Z\\\" fill=\\\"#231F20\\\"\\\/>\\n<path id=\\\"Vector5656231 256\\\" d=\\\"M178.62 124.2L178.63 139.19L161.53 140.17L161.78 127.71L178.62 124.2Z\\\" fill=\\\"#B57D68\\\"\\\/>\\n<path id=\\\"Vector5656231 257\\\" d=\\\"M161.66 133.81L161.78 127.71L178.62 124.2V133.2C170.92 136.09 163.22 134.49 161.66 133.81Z\\\" fill=\\\"#9E5B44\\\"\\\/>\\n<path id=\\\"Vector5656231 258\\\" d=\\\"M217.27 80.8699C213.27 77.8699 208.8 80.5899 206.42 84.2399C202.24 87.2399 198.75 93.4599 201.51 97.7199C204.83 102.84 212.87 99.5399 216.35 96.3199C220.55 92.4199 222.54 84.8199 217.27 80.8699Z\\\" fill=\\\"#9E5B44\\\"\\\/>\\n<path id=\\\"Vector5656231 259\\\" d=\\\"M215.26 84C213.72 83.83 211.81 85.43 211.36 86.78C211.04 87.7988 211.04 88.8912 211.36 89.91C211.71 91.19 212 92.69 210.27 93.24C210.014 93.349 209.808 93.5484 209.69 93.8C209.653 93.8638 209.634 93.9363 209.634 94.01C209.634 94.0837 209.653 94.1562 209.69 94.22C209.74 94.31 209.78 94.4 209.82 94.49C209.933 94.6407 210.09 94.7519 210.27 94.8076C210.449 94.8633 210.642 94.8606 210.82 94.8C211.307 94.6541 211.758 94.4066 212.142 94.0739C212.527 93.7412 212.837 93.3308 213.051 92.8698C213.265 92.4088 213.38 91.9075 213.387 91.3991C213.393 90.8906 213.292 90.3866 213.09 89.92C212.51 88.19 212.45 87.04 213.95 85.79C214.54 85.31 215.32 84.89 215.28 84.1C215.286 84.0831 215.287 84.0648 215.284 84.0473C215.28 84.0297 215.272 84.0133 215.26 84Z\\\" fill=\\\"#B57D68\\\"\\\/>\\n<path id=\\\"Vector5656231 260\\\" d=\\\"M125.9 86.45C129.02 82.79 133.16 84.7301 135.62 87.9101C139.54 90.1701 143.23 95.69 141.33 100.36C139.05 105.96 131.76 104.09 128.42 101.5C124.37 98.38 121.81 91.24 125.9 86.45Z\\\" fill=\\\"#9E5B44\\\"\\\/>\\n<path id=\\\"Vector5656231 261\\\" d=\\\"M128 89.1501C129.31 88.7301 131.13 89.9701 131.67 91.2201C132.043 92.205 132.15 93.2706 131.98 94.31C131.82 95.64 131.73 97.1601 133.28 97.4001C133.55 97.4001 133.69 97.6601 133.84 97.8601C133.874 97.9248 133.892 97.9968 133.892 98.07C133.892 98.1432 133.874 98.2153 133.84 98.28C133.84 98.38 133.78 98.47 133.76 98.56C133.695 98.7191 133.58 98.8526 133.432 98.9394C133.283 99.0261 133.11 99.0616 132.94 99.0401C130.94 98.7301 130.09 96.7301 130.45 94.6201C130.75 92.8201 130.68 91.62 129.24 90.7C128.69 90.33 127.97 90.05 127.91 89.27C127.907 89.2423 127.915 89.2145 127.931 89.1923C127.948 89.17 127.973 89.155 128 89.1501Z\\\" fill=\\\"#B57D68\\\"\\\/>\\n<path id=\\\"Vector5656231 262\\\" d=\\\"M135.89 56.15C134.409 69.096 133.718 82.12 133.82 95.15C134.04 107.54 140.54 119.92 149.14 126.08C164.61 137.16 185.47 130.17 194.22 121.17C207.71 107.3 210.53 90.81 204.61 56.79C202.39 55 135.89 56.15 135.89 56.15Z\\\" fill=\\\"#B57D68\\\"\\\/>\\n<path id=\\\"Vector5656231 263\\\" d=\\\"M186.13 121.58C195.22 114.77 200.83 106.1 201.39 92.18C201.84 80.64 201.62 67.88 195.68 56.01C200.68 56.16 204.14 56.41 204.61 56.79C210.53 90.79 207.71 107.3 194.22 121.17C185.47 130.17 164.61 137.17 149.14 126.08C148.42 125.57 147.71 124.98 147.02 124.38C159.89 129.18 174.55 130.26 186.13 121.58Z\\\" fill=\\\"#9E5B44\\\"\\\/>\\n<path id=\\\"Vector5656231 264\\\" d=\\\"M193.26 93.4201C193.578 93.2425 193.815 92.9486 193.922 92.5999C194.028 92.2513 193.995 91.875 193.83 91.5501C193.247 90.2414 192.303 89.1254 191.11 88.3323C189.917 87.5391 188.523 87.1014 187.09 87.0701C184.3 87.1701 182.3 89.1801 180.91 91.8301C180.736 92.1508 180.694 92.5267 180.793 92.8778C180.892 93.2289 181.124 93.5276 181.44 93.7101C182.09 94.0701 183.34 89.9501 187.62 90.2701C190.8 90.5101 193.1 93.5001 193.26 93.4201Z\\\" fill=\\\"#1F0601\\\"\\\/>\\n<path id=\\\"Vector5656231 265\\\" d=\\\"M154.25 94.1999C154.418 94.1887 154.582 94.1409 154.73 94.0599C155.048 93.8823 155.285 93.5884 155.392 93.2397C155.498 92.8911 155.465 92.5148 155.3 92.1899C154.736 90.8806 153.811 89.7587 152.634 88.9549C151.456 88.151 150.075 87.6985 148.65 87.6499C145.84 87.7499 143.79 89.8099 142.39 92.4699C142.219 92.7896 142.179 93.1631 142.278 93.5119C142.376 93.8606 142.607 94.1575 142.92 94.3399C143.56 94.7099 144.68 91.1499 149.09 90.9099C153.26 90.6799 153.73 94.2599 154.25 94.1999Z\\\" fill=\\\"#1F0601\\\"\\\/>\\n<path id=\\\"Vector5656231 266\\\" d=\\\"M187.76 78.23C189.43 78.11 191.93 79.47 192.39 81.35C192.39 81.54 192.26 81.75 192.06 81.68C190.9 81.25 189.77 80.52 188.48 80.6C187.91 80.6 185.75 80.77 185.41 81.33C185.07 81.89 183.7 82.2 183.58 81.33C183.3 79.43 186.47 78.32 187.76 78.23Z\\\" fill=\\\"#37201C\\\"\\\/>\\n<path id=\\\"Vector5656231 267\\\" d=\\\"M144.73 80.5101C147.87 78.6301 152.02 79.3701 153.07 83.0401C153.086 83.0933 153.088 83.15 153.075 83.2042C153.062 83.2584 153.035 83.3081 152.996 83.348C152.957 83.3879 152.908 83.4166 152.854 83.431C152.8 83.4455 152.744 83.4452 152.69 83.4301C151.38 83.0201 150.35 82.2401 148.94 82.0501C147.53 81.8601 146.54 83.0501 145.27 82.9301C145.008 82.8852 144.765 82.7634 144.573 82.5802C144.38 82.397 144.246 82.1606 144.188 81.9012C144.131 81.6417 144.151 81.371 144.248 81.1232C144.344 80.8755 144.512 80.6621 144.73 80.5101Z\\\" fill=\\\"#37201C\\\"\\\/>\\n<path id=\\\"Vector5656231 268\\\" d=\\\"M157.7 110.86C157.7 110.86 159.75 119.12 165.7 119.69C176.16 120.69 176.93 110.69 176.93 110.69L157.7 110.86Z\\\" fill=\\\"#A72231\\\"\\\/>\\n<path id=\\\"Vector5656231 269\\\" d=\\\"M174.34 113.4C174.932 113.146 175.468 112.778 175.918 112.316C176.367 111.854 176.722 111.309 176.96 110.71L160.15 110.85C163.47 114.73 168.09 115.56 174.34 113.4Z\\\" fill=\\\"white\\\"\\\/>\\n<path id=\\\"Vector5656231 270\\\" d=\\\"M173.9 117.26C171.28 116.72 167.72 116.89 165.75 118.26C165.256 118.582 164.825 118.992 164.48 119.47C164.887 119.599 165.306 119.686 165.73 119.73C169.67 120.06 172.23 118.87 173.9 117.26Z\\\" fill=\\\"#FA4B51\\\"\\\/>\\n<path id=\\\"Vector5656231 271\\\" d=\\\"M166.6 89.28C166.6 89.28 166.34 94.1 164.43 95.74C162.52 97.38 161.56 98.14 161.71 100.74C161.79 102.1 163.99 104.01 166.13 104.01C162.42 104.82 160.74 102.72 160.63 100.94C160.44 98.1 161.02 97.13 163.63 94.76C165.27 93.28 166.6 89.28 166.6 89.28Z\\\" fill=\\\"#37201C\\\"\\\/>\\n<path id=\\\"Vector5656231 272\\\" d=\\\"M206.54 52.68C197.67 38.81 142.42 42.96 138.17 46.13C122.46 57.81 124.6 77.52 127.41 83.69C127.41 80.69 132.65 77.3 137.52 75.3C138.997 74.6947 140.51 74.1804 142.05 73.76C140.23 76.23 138.87 78.95 138.87 81.59C145.24 77.49 156.47 76.79 161.99 74.18C162.695 77.4739 164.056 80.5923 165.99 83.35C165.78 80.01 169.06 74.9 178.09 73.13C176.4 75.72 175.02 78.24 175.53 78.56C183.09 77.19 194.53 75.15 197.93 71.63C200.72 74.19 203.22 76.04 203.11 83.54C215.39 76.31 211.22 59.65 206.54 52.68Z\\\" fill=\\\"#231F20\\\"\\\/>\\n<path id=\\\"Vector5656231 273\\\" d=\\\"M171.25 53C166.13 55.66 162.71 62.08 164.31 68C164.333 68.1155 164.396 68.2194 164.487 68.2941C164.578 68.3687 164.692 68.4095 164.81 68.4095C164.928 68.4095 165.042 68.3687 165.133 68.2941C165.224 68.2194 165.287 68.1155 165.31 68C166.44 62.44 167.24 57.41 171.62 53.46C171.85 53.21 171.53 52.84 171.25 53Z\\\" fill=\\\"#1F0601\\\"\\\/>\\n<path id=\\\"Vector5656231 274\\\" d=\\\"M160 51.2701C157.17 60.0501 150.22 65.5901 144.24 71.9801C144.192 72.0294 144.164 72.0941 144.159 72.1625C144.155 72.231 144.175 72.2988 144.215 72.354C144.256 72.4091 144.315 72.4481 144.382 72.4638C144.449 72.4796 144.519 72.4712 144.58 72.4401C148.555 70.2288 152.034 67.2234 154.798 63.6107C157.563 59.998 159.555 55.8553 160.65 51.4401C160.67 51.3951 160.679 51.3464 160.678 51.2973C160.677 51.2482 160.666 51.2 160.644 51.1558C160.623 51.1117 160.592 51.0727 160.554 51.0415C160.516 51.0104 160.472 50.9878 160.424 50.9754C160.377 50.963 160.327 50.961 160.279 50.9696C160.231 50.9782 160.185 50.9971 160.144 51.0251C160.104 51.0531 160.07 51.0895 160.045 51.1318C160.02 51.1741 160.005 51.2213 160 51.2701Z\\\" fill=\\\"#1F0601\\\"\\\/>\\n<path id=\\\"Vector5656231 275\\\" d=\\\"M151.12 57.7699C149.84 60.5699 147.53 62.3399 145.83 64.7699C145.61 65.0899 145.98 65.5899 146.34 65.4499C149.34 64.2599 150.84 60.9599 151.53 57.9099C151.59 57.7099 151.23 57.5299 151.12 57.7699Z\\\" fill=\\\"#1F0601\\\"\\\/>\\n<path id=\\\"Vector5656231 276\\\" d=\\\"M192.82 43.8201C192.794 43.7885 192.758 43.7671 192.718 43.7598C192.678 43.7526 192.637 43.7599 192.602 43.7804C192.567 43.801 192.54 43.8335 192.527 43.8719C192.514 43.9104 192.515 43.9523 192.53 43.9901C194.427 47.4486 195.479 51.3071 195.6 55.2501C195.76 59.2501 194.07 62.7801 192.73 66.4401C192.52 67.0301 193.29 67.3601 193.73 67.0101C200.05 61.1801 197 50.0001 192.82 43.8201Z\\\" fill=\\\"#1F0601\\\"\\\/>\\n<path id=\\\"Vector5656231 277\\\" d=\\\"M191 52.5199C190.91 52.3599 190.62 52.4599 190.69 52.6499C191.481 54.6174 191.59 56.7931 191 58.8299C190.57 60.5199 189.67 62.0099 189.28 63.6899C189.256 63.7743 189.26 63.8642 189.292 63.9459C189.324 64.0275 189.382 64.0964 189.457 64.1419C189.532 64.1874 189.62 64.2069 189.707 64.1975C189.795 64.1881 189.876 64.1503 189.94 64.0899C193.15 61.2299 193.17 55.9999 191 52.5199Z\\\" fill=\\\"#1F0601\\\"\\\/>\\n<path id=\\\"Vector5656231 278\\\" d=\\\"M164 30.5699C156.88 29.0399 148.5 33.5699 144.08 39.1799C143.75 39.6099 144.2 40.3899 144.7 40.0099C150.4 35.6699 156.7 31.8799 163.92 31.1399C164.2 31.1099 164.31 30.6399 164 30.5699Z\\\" fill=\\\"#1F0601\\\"\\\/>\\n<path id=\\\"Vector5656231 279\\\" d=\\\"M207.56 53.4199C207.45 53.1899 207.05 53.3599 207.15 53.5999C209.74 60.2199 209.26 66.5299 207.59 73.3199C207.48 73.7599 208.12 74.0799 208.3 73.6399C211.11 66.8499 210.66 60.0499 207.56 53.4199Z\\\" fill=\\\"#1F0601\\\"\\\/>\\n<path id=\\\"Vector5656231 280\\\" d=\\\"M137.66 53.0601C131.3 59.1201 125.96 71.1801 128.84 80.1301C128.885 80.2692 128.977 80.3881 129.101 80.4657C129.225 80.5434 129.372 80.5748 129.517 80.5545C129.661 80.5342 129.794 80.4634 129.892 80.3546C129.989 80.2459 130.045 80.1061 130.05 79.9601C130.8 70.5501 131.7 60.8601 137.98 53.4001C138.17 53.1701 137.88 52.8601 137.66 53.0601Z\\\" fill=\\\"#1F0601\\\"\\\/>\\n<path id=\\\"Vector5656231 281\\\" d=\\\"M64.28 136.64C64.28 136.64 75.5 146.41 75.13 148.64C74.7 151.26 72.5501 154.95 70.4101 154.79C68.2701 154.63 61.5401 154.98 60.5701 153.63C59.6001 152.28 57.6401 136.29 59.2701 135.63C60.9001 134.97 64.28 136.64 64.28 136.64Z\\\" fill=\\\"#9E5B44\\\"\\\/>\\n<path id=\\\"Vector5656231 282\\\" d=\\\"M72.51 151C70.94 151.28 67.91 148.28 67.15 146.84C66.0275 144.766 65.4333 142.448 65.42 140.09C65.42 140.09 64.62 138.43 59.21 137.58C55.34 136.97 55.45 131.94 56.87 132.2C63.1 133.36 65.48 132.83 67.79 134.66C70.1 136.49 75.05 142.8 75.51 147.74C75.69 149.69 74.39 150.64 72.51 151Z\\\" fill=\\\"#B57D68\\\"\\\/>\\n<path id=\\\"Vector5656231 283\\\" d=\\\"M182.37 137C182.315 136.783 182.197 136.588 182.031 136.438C181.864 136.289 181.656 136.194 181.435 136.163C181.213 136.133 180.988 136.17 180.787 136.269C180.587 136.369 180.42 136.526 180.31 136.72C177.87 141.37 176.78 146.31 172.06 149.34C165.75 153.34 160.24 140.79 159.78 136.22C159.787 136.186 159.787 136.152 159.779 136.119C159.771 136.085 159.755 136.054 159.734 136.028C159.712 136.001 159.685 135.979 159.654 135.965C159.623 135.95 159.589 135.942 159.555 135.942C159.521 135.942 159.487 135.95 159.456 135.965C159.425 135.979 159.398 136.001 159.376 136.028C159.355 136.054 159.339 136.085 159.331 136.119C159.323 136.152 159.323 136.186 159.33 136.22C158.77 143.52 162.66 151.77 170.33 152.5C176.15 153.05 183.06 142.25 182.37 137Z\\\" fill=\\\"#B5535E\\\"\\\/>\\n<path id=\\\"Vector5656231 284\\\" d=\\\"M130.07 185.53C121.79 180.14 123.23 167.44 118.89 159.7C118.861 159.642 118.813 159.597 118.755 159.57C118.696 159.544 118.63 159.538 118.568 159.555C118.506 159.571 118.451 159.608 118.413 159.66C118.375 159.712 118.357 159.776 118.36 159.84C117.74 164.84 120.01 171.34 121.29 176.08C122.57 180.82 124.35 185.8 128.2 188.85C130.06 190.33 132.13 186.88 130.07 185.53Z\\\" fill=\\\"#B5535E\\\"\\\/>\\n<path id=\\\"Vector5656231 285\\\" d=\\\"M223.1 146.7C223.04 146.6 222.86 146.57 222.81 146.7C221.26 150.45 221.68 155.04 221.26 159.05C220.61 165.34 219.65 171.35 216.6 176.93C215.46 179.02 218.6 180.93 219.71 178.81C222.322 173.835 223.945 168.402 224.49 162.81C225 157.92 225.84 151 223.1 146.7Z\\\" fill=\\\"#B5535E\\\"\\\/>\\n<path id=\\\"Vector5656231 286\\\" d=\\\"M162.78 278C160.98 292 158.78 306 156.99 320C155.41 332.51 153.37 346 155.08 358.62C155.15 359.18 155.92 358.98 155.96 358.5C157.11 345.67 157.09 332.84 158.61 320C160.27 306 162.35 292.12 163.23 278C163.25 277.65 162.81 277.67 162.78 278Z\\\" fill=\\\"#4B3321\\\"\\\/>\\n<path id=\\\"Vector5656231 287\\\" d=\\\"M205.47 316.58C205.66 301.86 205.35 287.35 204.23 272.67C204.23 272.45 203.89 272.44 203.9 272.67C205.42 300.67 203.71 328.13 201.9 355.97C201.9 356.39 202.43 356.4 202.56 356.06C207.21 344.07 205.31 329.23 205.47 316.58Z\\\" fill=\\\"#4B3321\\\"\\\/>\\n<path id=\\\"Vector5656231 288\\\" d=\\\"M341.76 43.7H273.86V135.8H341.76V43.7Z\\\" fill=\\\"#F7E8B4\\\"\\\/>\\n<g id=\\\"fourmsg\\\">\\n<g id=\\\"msg fade\\\">\\n<path id=\\\"Vector5656231 289\\\" d=\\\"M359.53 101.83H313.74C311.362 101.843 309.085 102.797 307.408 104.484C305.731 106.17 304.79 108.452 304.79 110.83V111C304.797 112.835 305.365 114.624 306.418 116.127C307.471 117.63 308.958 118.776 310.68 119.41L305.74 128.58L317.22 119.95H359.53C361.917 119.95 364.206 119.002 365.894 117.314C367.582 115.626 368.53 113.337 368.53 110.95V110.77C368.514 108.393 367.559 106.12 365.873 104.445C364.187 102.77 361.907 101.83 359.53 101.83Z\\\" fill=\\\"#8CD0C4\\\"\\\/>\\n<path id=\\\"Vector5656231 290\\\" d=\\\"M319.13 115L317.92 113H316.09V115H314.75V108H317.67C319.48 108 320.5 108.87 320.5 110.4C320.538 110.875 320.424 111.35 320.177 111.758C319.929 112.165 319.559 112.485 319.12 112.67L320.65 114.99L319.13 115ZM316.13 111.76H317.71C318.71 111.76 319.27 111.33 319.27 110.45C319.27 109.57 318.71 109.18 317.71 109.18H316.13V111.76Z\\\" fill=\\\"white\\\"\\\/>\\n<path id=\\\"Vector5656231 291\\\" d=\\\"M327.09 108.05V109.22H323.31V110.94H326.7V112.11H323.31V113.87H327.21V115H322V108L327.09 108.05Z\\\" fill=\\\"white\\\"\\\/>\\n<path id=\\\"Vector5656231 292\\\" d=\\\"M333.12 113.56H329.71L329.09 115.04H327.7L330.76 108.04H332.15L335.15 115.04H333.71L333.12 113.56ZM332.64 112.41L331.42 109.48L330.19 112.41H332.64Z\\\" fill=\\\"white\\\"\\\/>\\n<path id=\\\"Vector5656231 293\\\" d=\\\"M342.57 111.54C342.577 112.018 342.484 112.492 342.299 112.932C342.113 113.372 341.838 113.769 341.491 114.098C341.145 114.427 340.734 114.68 340.284 114.842C339.835 115.005 339.357 115.072 338.88 115.04H336V108.04H338.91C339.385 108.008 339.862 108.075 340.31 108.238C340.758 108.4 341.167 108.654 341.511 108.983C341.856 109.313 342.128 109.71 342.31 110.15C342.492 110.59 342.581 111.064 342.57 111.54ZM341.21 111.54C341.223 111.234 341.172 110.928 341.061 110.642C340.95 110.356 340.781 110.097 340.566 109.879C340.35 109.661 340.091 109.49 339.806 109.377C339.522 109.264 339.216 109.21 338.91 109.22H337.36V113.85H339C339.298 113.852 339.594 113.793 339.869 113.676C340.144 113.56 340.392 113.389 340.599 113.174C340.805 112.959 340.966 112.704 341.071 112.425C341.176 112.146 341.224 111.848 341.21 111.55V111.54Z\\\" fill=\\\"white\\\"\\\/>\\n<path id=\\\"Vector5656231 294\\\" d=\\\"M345.08 108.05V115.05H343.74V108.05H345.08Z\\\" fill=\\\"white\\\"\\\/>\\n<path id=\\\"Vector5656231 295\\\" d=\\\"M348.06 108.05L351.67 112.83V108.05H353V115.05H351.7L348.1 110.27V115H346.79V108L348.06 108.05Z\\\" fill=\\\"white\\\"\\\/>\\n<path id=\\\"Vector5656231 296\\\" d=\\\"M359.42 111.56H360.59V114.19C359.78 114.767 358.814 115.085 357.82 115.1C357.339 115.12 356.858 115.041 356.409 114.869C355.959 114.697 355.548 114.435 355.203 114.1C354.857 113.764 354.584 113.362 354.398 112.917C354.213 112.472 354.121 111.995 354.126 111.513C354.132 111.031 354.235 110.556 354.43 110.115C354.625 109.675 354.908 109.279 355.261 108.951C355.614 108.623 356.03 108.371 356.484 108.209C356.937 108.047 357.419 107.98 357.9 108.01C358.902 108.014 359.871 108.368 360.64 109.01L359.88 110.01C359.332 109.512 358.62 109.234 357.88 109.23C357.257 109.23 356.659 109.478 356.218 109.918C355.778 110.359 355.53 110.957 355.53 111.58C355.53 112.203 355.778 112.801 356.218 113.242C356.659 113.682 357.257 113.93 357.88 113.93C358.412 113.91 358.931 113.759 359.39 113.49L359.42 111.56Z\\\" fill=\\\"white\\\"\\\/>\\n<\\\/g>\\n<g id=\\\"msg fade 2\\\">\\n<path id=\\\"Vector5656231 297\\\" d=\\\"M254.35 86.0901H300.13C302.508 86.1033 304.785 87.0574 306.462 88.7438C308.139 90.4301 309.08 92.7118 309.08 95.0901V95.2701C309.073 97.1052 308.505 98.8943 307.452 100.397C306.399 101.9 304.912 103.046 303.19 103.68L308.13 112.85L296.65 104.22H254.35C251.963 104.22 249.674 103.272 247.986 101.584C246.298 99.8962 245.35 97.607 245.35 95.2201V95.0001C245.374 92.6288 246.332 90.3626 248.018 88.6942C249.703 87.0258 251.979 86.09 254.35 86.0901Z\\\" fill=\\\"#FF8059\\\"\\\/>\\n<path id=\\\"Vector5656231 298\\\" d=\\\"M256.92 91.9001L258.52 97.4001L260.12 91.9001H261.44L263.04 97.4001L264.63 91.9001H266L263.68 98.9001H262.3L260.74 93.6601L259.16 98.9001H257.78L255.47 91.9001H256.92Z\\\" fill=\\\"white\\\"\\\/>\\n<path id=\\\"Vector5656231 299\\\" d=\\\"M271.15 98.8801L269.94 96.8201H268.11V98.8201H266.78V91.8201H269.69C271.5 91.8201 272.53 92.6901 272.53 94.2201C272.565 94.6964 272.45 95.1717 272.201 95.579C271.951 95.9863 271.58 96.305 271.14 96.4901L272.68 98.8001L271.15 98.8801ZM268.15 95.6501H269.73C270.73 95.6501 271.29 95.2201 271.29 94.3401C271.29 93.4601 270.73 93.0601 269.73 93.0601H268.15V95.6501Z\\\" fill=\\\"white\\\"\\\/>\\n<path id=\\\"Vector5656231 300\\\" d=\\\"M275.33 91.9001V98.9001H274V91.9001H275.33Z\\\" fill=\\\"white\\\"\\\/>\\n<path id=\\\"Vector5656231 301\\\" d=\\\"M282 91.9001V93.0801H279.82V98.8801H278.47V93.0801H276.3V91.9001H282Z\\\" fill=\\\"white\\\"\\\/>\\n<path id=\\\"Vector5656231 302\\\" d=\\\"M284.25 91.9001V98.9001H282.92V91.9001H284.25Z\\\" fill=\\\"white\\\"\\\/>\\n<path id=\\\"Vector5656231 303\\\" d=\\\"M287.24 91.9001L290.84 96.6801V91.9001H292.14V98.9001H290.87L287.28 94.1301V98.9001H286V91.9001H287.24Z\\\" fill=\\\"white\\\"\\\/>\\n<path id=\\\"Vector5656231 304\\\" d=\\\"M298.6 95.4101H299.77V98.0001C298.959 98.5739 297.993 98.8878 297 98.9001C296.513 98.9308 296.024 98.8606 295.565 98.6939C295.106 98.5272 294.686 98.2676 294.332 97.9313C293.978 97.595 293.697 97.1892 293.507 96.7394C293.317 96.2896 293.221 95.8054 293.227 95.317C293.233 94.8287 293.339 94.3467 293.539 93.9013C293.739 93.4559 294.029 93.0566 294.391 92.7284C294.753 92.4001 295.178 92.1501 295.641 91.9938C296.103 91.8375 296.593 91.7784 297.08 91.8201C298.082 91.824 299.051 92.1777 299.82 92.8201L299.06 93.8201C298.514 93.3187 297.801 93.0372 297.06 93.0301C296.738 93.0091 296.415 93.0544 296.111 93.1633C295.807 93.2721 295.528 93.4422 295.293 93.6629C295.057 93.8836 294.869 94.1504 294.741 94.4466C294.613 94.7428 294.546 95.0622 294.546 95.3851C294.546 95.708 294.613 96.0274 294.741 96.3236C294.869 96.6198 295.057 96.8866 295.293 97.1073C295.528 97.328 295.807 97.4981 296.111 97.6069C296.415 97.7158 296.738 97.7611 297.06 97.7401C297.592 97.7201 298.111 97.5689 298.57 97.3001L298.6 95.4101Z\\\" fill=\\\"white\\\"\\\/>\\n<\\\/g>\\n<g id=\\\"msg fade 3\\\">\\n<path id=\\\"Vector5656231 305\\\" d=\\\"M362.19 67.09H316.41C315.226 67.082 314.052 67.3094 312.956 67.7588C311.861 68.2083 310.866 68.8709 310.028 69.7083C309.191 70.5457 308.528 71.5409 308.079 72.6364C307.629 73.732 307.402 74.9059 307.41 76.09V76.27C307.409 78.1071 307.973 79.9002 309.027 81.405C310.081 82.9098 311.573 84.0533 313.3 84.6801L308.3 93.85L319.79 85.2201H362.09C364.468 85.2069 366.745 84.2528 368.422 82.5664C370.099 80.88 371.04 78.5984 371.04 76.2201V76.0001C371.017 73.6545 370.079 71.4107 368.426 69.7464C366.773 68.0822 364.535 67.129 362.19 67.09Z\\\" fill=\\\"#F3B756\\\"\\\/>\\n<path id=\\\"Vector5656231 306\\\" d=\\\"M316.49 74C315.86 74 315.49 74.23 315.49 74.66C315.49 76.08 319.25 75.31 319.24 77.81C319.24 79.12 318.1 79.88 316.56 79.88C315.474 79.8732 314.427 79.4756 313.61 78.76L314.17 77.63C314.834 78.2308 315.685 78.5841 316.58 78.63C317.33 78.63 317.78 78.35 317.78 77.86C317.78 76.41 314.03 77.23 314.03 74.75C314.03 73.53 315.03 72.75 316.64 72.75C317.536 72.7536 318.413 73.0101 319.17 73.49L318.63 74.65C317.983 74.2559 317.247 74.0323 316.49 74Z\\\" fill=\\\"white\\\"\\\/>\\n<path id=\\\"Vector5656231 307\\\" d=\\\"M326.09 75.2C326.09 76.8 325.09 77.72 323.33 77.72H321.8V79.78H320.46V72.78H323.33C325.09 72.79 326.09 73.66 326.09 75.2ZM324.83 75.2C324.83 74.34 324.26 73.92 323.26 73.92H321.8V76.51H323.26C324.26 76.55 324.83 76.12 324.83 75.24V75.2Z\\\" fill=\\\"white\\\"\\\/>\\n<path id=\\\"Vector5656231 308\\\" d=\\\"M332.32 72.79V74H328.54V75.73H331.93V76.9H328.54V78.65H332.44V79.82H327.2V72.82L332.32 72.79Z\\\" fill=\\\"white\\\"\\\/>\\n<path id=\\\"Vector5656231 309\\\" d=\\\"M338.35 78.3H334.94L334.32 79.78H332.93L335.99 72.78H337.38L340.38 79.78H339L338.35 78.3ZM337.87 77.15L336.65 74.22L335.42 77.15H337.87Z\\\" fill=\\\"white\\\"\\\/>\\n<path id=\\\"Vector5656231 310\\\" d=\\\"M345.89 79.78L343.71 76.78L342.59 78V79.76H341.25V72.76H342.59V76.18L345.76 72.76H347.31L344.65 75.76L347.5 79.76L345.89 79.78Z\\\" fill=\\\"white\\\"\\\/>\\n<path id=\\\"Vector5656231 311\\\" d=\\\"M349.84 72.79V79.79H348.5V72.79H349.84Z\\\" fill=\\\"white\\\"\\\/>\\n<path id=\\\"Vector5656231 312\\\" d=\\\"M352.82 72.79L356.43 77.57V72.79H357.72V79.79H356.46L352.86 75V79.77H351.55V72.77L352.82 72.79Z\\\" fill=\\\"white\\\"\\\/>\\n<path id=\\\"Vector5656231 313\\\" d=\\\"M364.18 76.31H365.35V78.93C364.54 79.5074 363.574 79.8248 362.58 79.84C362.099 79.8595 361.618 79.7809 361.169 79.609C360.719 79.437 360.308 79.1752 359.963 78.8397C359.617 78.5041 359.344 78.1017 359.158 77.657C358.973 77.2123 358.881 76.7345 358.886 76.2529C358.892 75.7712 358.995 75.2957 359.19 74.8553C359.385 74.4148 359.668 74.0187 360.021 73.691C360.374 73.3633 360.79 73.1109 361.244 72.9491C361.697 72.7874 362.179 72.7196 362.66 72.75C363.662 72.7539 364.631 73.1076 365.4 73.75L364.64 74.75C364.094 74.2486 363.381 73.9671 362.64 73.96C362.017 73.96 361.419 74.2076 360.978 74.6483C360.538 75.089 360.29 75.6867 360.29 76.31C360.29 76.9333 360.538 77.531 360.978 77.9717C361.419 78.4124 362.017 78.66 362.64 78.66C363.172 78.64 363.691 78.4888 364.15 78.22L364.18 76.31Z\\\" fill=\\\"white\\\"\\\/>\\n<\\\/g>\\n<g id=\\\"msg fade 4\\\">\\n<path id=\\\"Vector5656231 314\\\" d=\\\"M256.14 51.8401H301.93C304.3 51.8532 306.568 52.8004 308.244 54.476C309.92 56.1516 310.867 58.4205 310.88 60.7901V61.0001C310.881 62.8384 310.314 64.6323 309.259 66.1372C308.203 67.6421 306.709 68.785 304.98 69.4101L309.93 78.5801L298.45 69.9501H256.14C253.762 69.9369 251.485 68.9828 249.808 67.2964C248.131 65.61 247.19 63.3284 247.19 60.9501V60.7701C247.208 58.4039 248.158 56.1402 249.833 54.4689C251.508 52.7976 253.774 51.8532 256.14 51.8401Z\\\" fill=\\\"#5198BF\\\"\\\/>\\n<path id=\\\"Vector5656231 315\\\" d=\\\"M254.54 57.6001V63.3801H257.54V64.5901H253.2V57.5901L254.54 57.6001Z\\\" fill=\\\"white\\\"\\\/>\\n<path id=\\\"Vector5656231 316\\\" d=\\\"M259.94 57.6001V64.6001H258.6V57.6001H259.94Z\\\" fill=\\\"white\\\"\\\/>\\n<path id=\\\"Vector5656231 317\\\" d=\\\"M264 58.76C263.37 58.76 263 58.99 263 59.42C263 60.84 266.76 60.07 266.75 62.57C266.75 63.88 265.61 64.64 264.07 64.64C262.967 64.6453 261.9 64.2469 261.07 63.52L261.63 62.39C262.294 62.9908 263.146 63.3441 264.04 63.39C264.79 63.39 265.24 63.11 265.24 62.62C265.24 61.16 261.49 61.99 261.49 59.51C261.49 58.29 262.49 57.51 264.1 57.51C264.996 57.5136 265.873 57.7701 266.63 58.25L266.09 59.41C265.458 59.0239 264.74 58.8005 264 58.76Z\\\" fill=\\\"white\\\"\\\/>\\n<path id=\\\"Vector5656231 318\\\" d=\\\"M272.85 57.6001V58.7901H270.67V64.5901H269.32V58.7901H267.15V57.6001H272.85Z\\\" fill=\\\"white\\\"\\\/>\\n<path id=\\\"Vector5656231 319\\\" d=\\\"M278.91 57.6001V58.7701H275.13V60.5001H278.52V61.6601H275.13V63.4201H279V64.5901H273.76V57.5901L278.91 57.6001Z\\\" fill=\\\"white\\\"\\\/>\\n<path id=\\\"Vector5656231 320\\\" d=\\\"M281.66 57.6001L285.26 62.3801V57.6001H286.56V64.6001H285.29L281.7 59.8301V64.6001H280.39V57.6001H281.66Z\\\" fill=\\\"white\\\"\\\/>\\n<path id=\\\"Vector5656231 321\\\" d=\\\"M289.61 57.6001V64.6001H288.28V57.6001H289.61Z\\\" fill=\\\"white\\\"\\\/>\\n<path id=\\\"Vector5656231 322\\\" d=\\\"M292.6 57.6001L296.2 62.3801V57.6001H297.5V64.6001H296.23L292.64 59.8301V64.6001H291.33V57.6001H292.6Z\\\" fill=\\\"white\\\"\\\/>\\n<path id=\\\"Vector5656231 323\\\" d=\\\"M304 61.1101H305.16V63.7401C304.355 64.3184 303.391 64.636 302.4 64.6501C301.919 64.6696 301.438 64.591 300.989 64.4191C300.539 64.2471 300.128 63.9853 299.783 63.6498C299.437 63.3142 299.164 62.9118 298.978 62.4671C298.793 62.0224 298.701 61.5446 298.706 61.063C298.712 60.5813 298.815 60.1058 299.01 59.6654C299.205 59.2249 299.488 58.8288 299.841 58.5011C300.194 58.1734 300.61 57.921 301.064 57.7592C301.517 57.5974 301.999 57.5297 302.48 57.5601C303.479 57.5621 304.446 57.9162 305.21 58.5601L304.46 59.5601C303.914 59.0587 303.201 58.7772 302.46 58.7701C301.837 58.7701 301.239 59.0177 300.798 59.4584C300.358 59.8991 300.11 60.4968 300.11 61.1201C300.11 61.7434 300.358 62.3411 300.798 62.7818C301.239 63.2225 301.837 63.4701 302.46 63.4701C303.005 63.4459 303.535 63.2842 304 63.0001V61.1101Z\\\" fill=\\\"white\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<path id=\\\"Vector5656231 324\\\" d=\\\"M57.7431 59.1785L54.4738 59.4433L62.5911 159.675L65.8603 159.41L57.7431 59.1785Z\\\" fill=\\\"#1EB1FA\\\"\\\/>\\n<path id=\\\"worlddot\\\" d=\\\"M52.1 86.18C50.4282 86.1795 48.7582 86.0726 47.1 85.86C46.9077 85.8348 46.7333 85.7343 46.6152 85.5805C46.497 85.4267 46.4448 85.2323 46.47 85.04C46.4952 84.8477 46.5957 84.6733 46.7495 84.5552C46.9033 84.437 47.0977 84.3848 47.29 84.41C48.8786 84.6135 50.4784 84.717 52.08 84.72C52.1772 84.7187 52.2737 84.7365 52.364 84.7725C52.4542 84.8085 52.5366 84.8619 52.6062 84.9297C52.6759 84.9974 52.7315 85.0783 52.7699 85.1676C52.8083 85.2569 52.8287 85.3528 52.83 85.45C52.8313 85.5462 52.8134 85.6418 52.7772 85.731C52.741 85.8201 52.6872 85.9011 52.6192 85.9692C52.5511 86.0372 52.4701 86.091 52.3809 86.1272C52.2918 86.1634 52.1962 86.1814 52.1 86.18ZM57 85.86C56.8216 85.8592 56.6495 85.7941 56.5154 85.6765C56.3812 85.5589 56.2941 85.3968 56.27 85.22C56.2574 85.1248 56.2636 85.028 56.2885 84.9352C56.3133 84.8424 56.3563 84.7554 56.4148 84.6792C56.4733 84.6031 56.5463 84.5392 56.6296 84.4913C56.7128 84.4433 56.8047 84.4123 56.9 84.4C58.5017 84.188 60.0883 83.874 61.65 83.46C61.837 83.4096 62.0363 83.4356 62.2042 83.5322C62.372 83.6287 62.4946 83.788 62.545 83.975C62.5954 84.162 62.5694 84.3613 62.4729 84.5292C62.3763 84.697 62.217 84.8196 62.03 84.87C60.4062 85.3079 58.7562 85.6419 57.09 85.87L57 85.86ZM42.32 84.92C42.257 84.9296 42.193 84.9296 42.13 84.92C40.5068 84.4873 38.9134 83.9495 37.36 83.31C37.2714 83.2732 37.1908 83.2194 37.123 83.1515C37.0552 83.0836 37.0014 83.003 36.9647 82.9143C36.928 82.8256 36.9092 82.7306 36.9092 82.6346C36.9093 82.5387 36.9282 82.4437 36.965 82.355C37.0018 82.2664 37.0556 82.1858 37.1235 82.118C37.1914 82.0502 37.272 81.9964 37.3607 81.9597C37.4494 81.9231 37.5444 81.9042 37.6404 81.9042C37.7363 81.9043 37.8314 81.9232 37.92 81.96C39.4167 82.5706 40.9496 83.0882 42.51 83.51C42.6968 83.5593 42.8565 83.6807 42.9539 83.8475C43.0514 84.0144 43.0788 84.213 43.03 84.4C42.984 84.548 42.8926 84.6779 42.7688 84.7712C42.645 84.8645 42.495 84.9165 42.34 84.92H42.32ZM66.51 83.31C66.365 83.3099 66.2233 83.2671 66.1024 83.1871C65.9815 83.1071 65.8868 82.9934 65.83 82.86C65.7858 82.7694 65.7608 82.6706 65.7566 82.5698C65.7525 82.469 65.7693 82.3685 65.8059 82.2746C65.8426 82.1806 65.8983 82.0953 65.9695 82.0239C66.0408 81.9526 66.1261 81.8968 66.22 81.86C67.7074 81.2396 69.1537 80.5248 70.55 79.72C70.634 79.6701 70.7271 79.6372 70.8238 79.6233C70.9206 79.6094 71.0191 79.6146 71.1138 79.6388C71.2086 79.6629 71.2976 79.7055 71.3759 79.764C71.4541 79.8226 71.5201 79.896 71.57 79.98C71.6199 80.0641 71.6528 80.1571 71.6667 80.2539C71.6806 80.3506 71.6754 80.4491 71.6513 80.5439C71.6271 80.6386 71.5845 80.7276 71.526 80.8059C71.4674 80.8841 71.394 80.9501 71.31 81C69.8603 81.8407 68.3571 82.5857 66.81 83.23C66.7229 83.275 66.6277 83.3022 66.53 83.31H66.51ZM33.24 81.16C33.1098 81.1612 32.9818 81.1266 32.87 81.06C31.4196 80.2185 30.0235 79.2867 28.69 78.27C28.6001 78.2168 28.5225 78.1453 28.4623 78.06C28.4021 77.9747 28.3606 77.8776 28.3405 77.7751C28.3205 77.6727 28.3224 77.5671 28.346 77.4654C28.3697 77.3637 28.4146 77.2682 28.4778 77.1851C28.541 77.102 28.6211 77.0332 28.7128 76.9833C28.8045 76.9333 28.9057 76.9033 29.0098 76.8953C29.1139 76.8873 29.2185 76.9013 29.3168 76.9366C29.4151 76.9719 29.5048 77.0276 29.58 77.1C30.8534 78.0827 32.1896 78.9812 33.58 79.79C33.6636 79.8377 33.737 79.9015 33.7959 79.9776C33.8548 80.0538 33.898 80.1409 33.9231 80.2338C33.9482 80.3268 33.9546 80.4238 33.9421 80.5192C33.9296 80.6147 33.8983 80.7067 33.85 80.79C33.79 80.9 33.702 80.9922 33.5949 81.0572C33.4877 81.1222 33.3653 81.1577 33.24 81.16ZM75 78.38C74.8874 78.3804 74.7762 78.3544 74.6755 78.304C74.5748 78.2536 74.4873 78.1803 74.42 78.09C74.3089 77.9386 74.2604 77.7502 74.2846 77.564C74.3088 77.3777 74.4039 77.208 74.55 77.09C75.8289 76.1077 77.0415 75.042 78.18 73.9C78.3175 73.777 78.4955 73.709 78.68 73.709C78.8645 73.709 79.0425 73.777 79.18 73.9C79.3073 74.0354 79.3781 74.2142 79.3781 74.4C79.3781 74.5858 79.3073 74.7646 79.18 74.9C77.9937 76.0878 76.731 77.1969 75.4 78.22C75.2858 78.3124 75.1464 78.3681 75 78.38ZM25.42 75.17C25.2291 75.1694 25.046 75.094 24.91 74.96C23.7215 73.7743 22.6124 72.5116 21.59 71.18C21.4789 71.0286 21.4304 70.8402 21.4546 70.654C21.4788 70.4677 21.5739 70.298 21.72 70.18C21.8734 70.0724 22.062 70.027 22.2476 70.053C22.4332 70.0789 22.602 70.1744 22.72 70.32C23.7049 71.5968 24.7704 72.8092 25.91 73.95C26.0395 74.0842 26.1119 74.2635 26.1119 74.45C26.1119 74.6365 26.0395 74.8158 25.91 74.95C25.8468 75.0171 25.771 75.0711 25.6869 75.1089C25.6029 75.1466 25.5121 75.1674 25.42 75.17ZM82 71.41C81.8401 71.4141 81.6841 71.3609 81.56 71.26C81.4123 71.1435 81.3153 70.9744 81.2892 70.7881C81.2631 70.6018 81.31 70.4126 81.42 70.26C82.4027 68.9866 83.3012 67.6504 84.11 66.26C84.1579 66.1766 84.2218 66.1035 84.298 66.0448C84.3742 65.9861 84.4612 65.943 84.5541 65.9179C84.6469 65.8928 84.7438 65.8863 84.8392 65.8987C84.9346 65.911 85.0266 65.9421 85.11 65.99C85.1934 66.0379 85.2665 66.1018 85.3252 66.178C85.3839 66.2542 85.427 66.3412 85.4521 66.4341C85.4772 66.527 85.4837 66.6238 85.4713 66.7192C85.459 66.8146 85.4279 66.9066 85.38 66.99C84.5385 68.4404 83.6067 69.8365 82.59 71.17C82.5157 71.2514 82.4242 71.3152 82.3221 71.3567C82.2201 71.3983 82.11 71.4165 82 71.41ZM19.43 67.41C19.3007 67.4079 19.174 67.3728 19.062 67.3081C18.95 67.2433 18.8564 67.1511 18.79 67.04C17.9473 65.5913 17.2023 64.088 16.56 62.54C16.5072 62.4495 16.4746 62.3487 16.4642 62.2444C16.4538 62.1402 16.466 62.0349 16.5 61.9358C16.5339 61.8367 16.5888 61.746 16.6609 61.67C16.733 61.594 16.8206 61.5344 16.9178 61.4952C17.0149 61.456 17.1194 61.4383 17.2241 61.4431C17.3287 61.4479 17.4311 61.4751 17.5243 61.523C17.6175 61.5709 17.6993 61.6383 17.7641 61.7206C17.8289 61.8029 17.8753 61.8982 17.9 62C18.5218 63.4886 19.24 64.935 20.05 66.33C20.1448 66.4989 20.1696 66.6982 20.1191 66.8851C20.0687 67.0721 19.9469 67.2318 19.78 67.33C19.6656 67.3748 19.5423 67.3919 19.42 67.38L19.43 67.41ZM86.93 62.92C86.8372 62.9343 86.7428 62.9343 86.65 62.92C86.5571 62.8819 86.4727 62.8255 86.402 62.7541C86.3313 62.6828 86.2756 62.598 86.2383 62.5047C86.201 62.4114 86.1828 62.3116 86.1848 62.2112C86.1868 62.1107 86.209 62.0117 86.25 61.92C86.8664 60.4153 87.3842 58.872 87.8 57.3C87.8493 57.1132 87.9707 56.9536 88.1375 56.8561C88.3044 56.7586 88.503 56.7313 88.69 56.78C88.7839 56.802 88.8724 56.8428 88.95 56.9001C89.0276 56.9574 89.0927 57.0299 89.1414 57.1132C89.19 57.1965 89.2212 57.2888 89.233 57.3845C89.2448 57.4803 89.237 57.5774 89.21 57.67C88.7788 59.2937 88.2409 60.8871 87.6 62.44C87.5432 62.5734 87.4485 62.6871 87.3276 62.7671C87.2067 62.8471 87.065 62.8899 86.92 62.89L86.93 62.92ZM15.64 58.32C15.4799 58.3206 15.3241 58.2679 15.1974 58.1701C15.0706 58.0723 14.98 57.935 14.94 57.78C14.4964 56.161 14.1623 54.5139 13.94 52.85C13.9148 52.6577 13.967 52.4633 14.0852 52.3095C14.2033 52.1558 14.3777 52.0552 14.57 52.03C14.7623 52.0048 14.9567 52.057 15.1105 52.1752C15.2643 52.2933 15.3648 52.4677 15.39 52.66C15.6015 54.2593 15.9189 55.8428 16.34 57.4C16.389 57.5883 16.3619 57.7882 16.2646 57.9567C16.1673 58.1251 16.0076 58.2485 15.82 58.3C15.7565 58.3072 15.6924 58.3038 15.63 58.29L15.64 58.32ZM89.47 53.41H89.38C89.2847 53.3977 89.1928 53.3667 89.1096 53.3188C89.0263 53.2708 88.9533 53.207 88.8948 53.1308C88.8362 53.0546 88.7933 52.9676 88.7685 52.8748C88.7436 52.782 88.7374 52.6852 88.75 52.59C88.9535 50.9914 89.057 49.3816 89.06 47.77V47.61C89.06 47.4164 89.1369 47.2307 89.2738 47.0938C89.4107 46.9569 89.5964 46.88 89.79 46.88C89.9836 46.88 90.1693 46.9569 90.3062 47.0938C90.4431 47.2307 90.52 47.4164 90.52 47.61V47.75C90.5179 49.4217 90.411 51.0917 90.2 52.75C90.1755 52.9276 90.0865 53.0899 89.9501 53.2061C89.8136 53.3222 89.6392 53.3842 89.46 53.38L89.47 53.41ZM14.34 48.5C14.2461 48.5055 14.152 48.4917 14.0636 48.4594C13.9753 48.4272 13.8944 48.3772 13.826 48.3126C13.7577 48.248 13.7032 48.1701 13.6661 48.0836C13.6289 47.9972 13.6098 47.9041 13.61 47.81H14.34L13.61 47.74C13.6055 46.0684 13.7091 44.3983 13.92 42.74C13.9452 42.5477 14.0457 42.3733 14.1995 42.2552C14.3533 42.137 14.5477 42.0848 14.74 42.11C14.9323 42.1352 15.1067 42.2358 15.2248 42.3895C15.343 42.5433 15.3952 42.7377 15.37 42.93C15.1695 44.5054 15.0693 46.0919 15.07 47.68C15.0768 47.782 15.0632 47.8843 15.03 47.9809C14.9968 48.0776 14.9448 48.1666 14.8768 48.243C14.8089 48.3193 14.7264 48.3813 14.6342 48.4254C14.5421 48.4696 14.4421 48.4949 14.34 48.5ZM89.44 43.38C89.2637 43.3814 89.0929 43.318 88.9602 43.2019C88.8275 43.0858 88.742 42.925 88.72 42.75C88.4881 41.1503 88.1541 39.5671 87.72 38.01C87.6942 37.9174 87.6869 37.8207 87.6986 37.7253C87.7103 37.6299 87.7407 37.5377 87.7881 37.4541C87.8355 37.3705 87.8989 37.297 87.9747 37.238C88.0506 37.1789 88.1373 37.1354 88.23 37.11C88.3233 37.0829 88.421 37.075 88.5174 37.0867C88.6138 37.0984 88.7068 37.1295 88.7909 37.178C88.875 37.2266 88.9484 37.2917 89.0066 37.3694C89.0649 37.447 89.1069 37.5357 89.13 37.63C89.5725 39.2459 89.9066 40.8896 90.13 42.55C90.153 42.743 90.1002 42.9374 89.9827 43.0923C89.8652 43.2471 89.6921 43.3503 89.5 43.38H89.44ZM15.59 38.78H15.4C15.2132 38.7307 15.0536 38.6093 14.9561 38.4425C14.8586 38.2756 14.8312 38.077 14.88 37.89C15.3112 36.2663 15.8491 34.6729 16.49 33.12C16.527 33.0262 16.5827 32.9409 16.6539 32.8694C16.725 32.7979 16.81 32.7416 16.9037 32.7042C16.9973 32.6667 17.0976 32.6488 17.1985 32.6515C17.2993 32.6542 17.3985 32.6776 17.49 32.72C17.5839 32.7568 17.6692 32.8126 17.7405 32.8839C17.8117 32.9553 17.8674 33.0406 17.9041 33.1346C17.9407 33.2285 17.9575 33.3291 17.9534 33.4298C17.9492 33.5306 17.9242 33.6294 17.88 33.72C17.2668 35.2113 16.7524 36.7412 16.34 38.3C16.284 38.4506 16.1806 38.5789 16.0453 38.6654C15.91 38.752 15.7502 38.7922 15.59 38.78ZM86.86 33.89C86.7161 33.8905 86.5754 33.8479 86.456 33.7677C86.3366 33.6875 86.2439 33.5734 86.19 33.44C85.5551 31.9505 84.8235 30.5041 84 29.11C83.9513 29.0273 83.9194 28.9358 83.9062 28.8408C83.8929 28.7457 83.8985 28.649 83.9226 28.5561C83.9468 28.4632 83.989 28.376 84.0469 28.2995C84.1048 28.2229 84.1772 28.1585 84.26 28.11C84.4282 28.0169 84.6258 27.992 84.8119 28.0403C84.998 28.0887 85.1584 28.2067 85.26 28.37C86.1 29.8217 86.8482 31.3247 87.5 32.87C87.5427 32.9609 87.5665 33.0595 87.5699 33.1599C87.5733 33.2602 87.5562 33.3602 87.5198 33.4538C87.4833 33.5473 87.4281 33.6325 87.3577 33.704C87.2872 33.7756 87.203 33.8321 87.11 33.87C87.0284 33.8907 86.9439 33.8974 86.86 33.89ZM19.34 29.67C19.213 29.6709 19.0883 29.6363 18.98 29.57C18.8964 29.5223 18.823 29.4585 18.7641 29.3824C18.7052 29.3062 18.662 29.2191 18.6369 29.1262C18.6118 29.0332 18.6054 28.9363 18.6179 28.8408C18.6304 28.7453 18.6617 28.6533 18.71 28.57C19.5479 27.1174 20.4799 25.721 21.5 24.39C21.6165 24.2423 21.7856 24.1453 21.9719 24.1192C22.1582 24.0931 22.3474 24.14 22.5 24.25C22.6456 24.368 22.7411 24.5368 22.7671 24.7224C22.793 24.908 22.7476 25.0966 22.64 25.25C21.6608 26.5237 20.7655 27.8599 19.96 29.25C19.9042 29.3695 19.8171 29.4716 19.708 29.5456C19.5988 29.6195 19.4716 29.6625 19.34 29.67ZM81.91 25.39C81.7974 25.3904 81.6862 25.3644 81.5855 25.314C81.4848 25.2636 81.3973 25.1903 81.33 25.1C80.3378 23.8265 79.2657 22.6174 78.12 21.48C77.9927 21.3446 77.9219 21.1658 77.9219 20.98C77.9219 20.7942 77.9927 20.6154 78.12 20.48C78.2565 20.3549 78.4349 20.2855 78.62 20.2855C78.8051 20.2855 78.9835 20.3549 79.12 20.48C80.3053 21.6652 81.4142 22.9244 82.44 24.25C82.5241 24.3574 82.5764 24.4863 82.591 24.622C82.6056 24.7576 82.5819 24.8947 82.5225 25.0175C82.4632 25.1404 82.3706 25.2442 82.2552 25.3171C82.1399 25.39 82.0064 25.4291 81.87 25.43L81.91 25.39ZM25.32 21.85C25.2253 21.8508 25.1314 21.8326 25.0438 21.7966C24.9562 21.7605 24.8767 21.7073 24.81 21.64C24.6849 21.5035 24.6155 21.3251 24.6155 21.14C24.6155 20.9549 24.6849 20.7765 24.81 20.64C25.9952 19.4547 27.2544 18.3458 28.58 17.32C28.6562 17.2609 28.7432 17.2174 28.8362 17.192C28.9292 17.1665 29.0263 17.1596 29.1219 17.1717C29.2176 17.1838 29.3099 17.2146 29.3936 17.2623C29.4774 17.3101 29.5509 17.3738 29.61 17.45C29.6691 17.5262 29.7126 17.6132 29.7381 17.7062C29.7635 17.7992 29.7704 17.8963 29.7583 17.9919C29.7463 18.0876 29.7155 18.1799 29.6677 18.2637C29.6199 18.3474 29.5562 18.4209 29.48 18.48C28.2033 19.4649 26.9908 20.5304 25.85 21.67C25.7788 21.7349 25.695 21.7843 25.6038 21.8153C25.5126 21.8463 25.416 21.8581 25.32 21.85ZM74.92 18.45C74.7609 18.4493 74.6064 18.3966 74.48 18.3C73.2036 17.3275 71.8677 16.4358 70.48 15.63C70.3131 15.5318 70.1913 15.3721 70.1409 15.1851C70.0904 14.9982 70.1152 14.7989 70.21 14.63C70.2567 14.5454 70.32 14.471 70.396 14.4114C70.4721 14.3517 70.5594 14.308 70.6527 14.2828C70.746 14.2576 70.8435 14.2514 70.9392 14.2647C71.0349 14.278 71.127 14.3104 71.21 14.36C72.6672 15.192 74.067 16.1208 75.4 17.14C75.5461 17.258 75.6412 17.4277 75.6654 17.614C75.6896 17.8002 75.6411 17.9886 75.53 18.14C75.4608 18.237 75.3692 18.3158 75.263 18.3698C75.1568 18.4237 75.0391 18.4513 74.92 18.45ZM33.11 15.84C32.9813 15.8412 32.8547 15.8074 32.7438 15.7423C32.6328 15.6771 32.5416 15.583 32.48 15.47C32.43 15.3877 32.397 15.2961 32.383 15.2008C32.369 15.1054 32.3743 15.0083 32.3985 14.915C32.4228 14.8218 32.4655 14.7343 32.5241 14.6579C32.5828 14.5815 32.6562 14.5176 32.74 14.47C34.1917 13.63 35.6946 12.8819 37.24 12.23C37.3315 12.1876 37.4307 12.1642 37.5315 12.1615C37.6324 12.1588 37.7327 12.1767 37.8263 12.2142C37.92 12.2516 38.005 12.3079 38.0761 12.3794C38.1473 12.4509 38.203 12.5362 38.24 12.63C38.2773 12.7185 38.2966 12.8136 38.2966 12.9096C38.2967 13.0057 38.2775 13.1008 38.2402 13.1893C38.2029 13.2778 38.1483 13.358 38.0796 13.4251C38.0109 13.4922 37.9294 13.5449 37.84 13.58C36.3545 14.2052 34.9114 14.9267 33.52 15.74C33.3944 15.8085 33.2531 15.843 33.11 15.84ZM66.38 13.55C66.2848 13.5468 66.1905 13.5299 66.1 13.5C64.6078 12.9004 63.0778 12.3993 61.52 12C61.3317 11.9509 61.1706 11.8291 61.0721 11.6612C60.9737 11.4934 60.9459 11.2933 60.995 11.105C61.0441 10.9167 61.1659 10.7556 61.3338 10.6572C61.5016 10.5587 61.7017 10.5309 61.89 10.58C63.5121 11.0124 65.1053 11.5468 66.66 12.18C66.8198 12.2423 66.9525 12.3588 67.035 12.5092C67.1174 12.6596 67.1443 12.8342 67.1109 13.0024C67.0775 13.1705 66.9859 13.3216 66.8523 13.4291C66.7187 13.5365 66.5514 13.5935 66.38 13.59V13.55ZM42.19 12C42.0286 12.0012 41.8714 11.9488 41.7429 11.8511C41.6145 11.7534 41.522 11.6158 41.48 11.46C41.431 11.2718 41.4581 11.0718 41.5554 10.9033C41.6527 10.7349 41.8124 10.6116 42 10.56C43.6202 10.1212 45.2669 9.78718 46.93 9.55998C47.1131 9.55496 47.2916 9.61805 47.431 9.73706C47.5703 9.85607 47.6605 10.0226 47.6841 10.2042C47.7078 10.3859 47.6632 10.5699 47.5589 10.7206C47.4547 10.8713 47.2983 10.978 47.12 11.02C45.5206 11.2306 43.937 11.5479 42.38 11.97L42.19 12ZM56.86 11H56.77C55.208 10.7999 53.6348 10.6997 52.06 10.7H51.94C51.7598 10.679 51.5937 10.5925 51.4731 10.457C51.3525 10.3215 51.2859 10.1464 51.2859 9.96498C51.2859 9.78359 51.3525 9.60852 51.4731 9.47302C51.5937 9.33752 51.7598 9.25103 51.94 9.22998H52.05C53.7056 9.24429 55.3588 9.36118 57 9.57998C57.1936 9.59324 57.374 9.68287 57.5015 9.82915C57.6291 9.97543 57.6933 10.1664 57.68 10.36C57.6667 10.5536 57.5771 10.734 57.4308 10.8616C57.2846 10.9891 57.0936 11.0533 56.9 11.04L56.86 11Z\\\" fill=\\\"#1EB1FA\\\"\\\/>\\n<path id=\\\"Vector5656231 325\\\" d=\\\"M52.06 78.17C68.8715 78.17 82.5 64.5416 82.5 47.73C82.5 30.9185 68.8715 17.29 52.06 17.29C35.2484 17.29 21.62 30.9185 21.62 47.73C21.62 64.5416 35.2484 78.17 52.06 78.17Z\\\" fill=\\\"#75DDFF\\\"\\\/>\\n<path id=\\\"Vector5656231 326\\\" d=\\\"M27.21 38.1199C26.81 39.8699 26.83 41.2099 25.92 42.9099C25.0918 44.1575 24.6756 45.6334 24.73 47.1299C24.73 49.5599 23.99 56.8299 28.28 55.6999C31.83 54.7699 29.89 50.0999 32.41 48.0599C33.6 47.0599 35.15 47.4699 35.88 45.9299C36.61 44.3899 35.67 43.0099 36.88 41.7099C38.96 39.3899 43.29 40.3699 44.88 37.5799C42.34 36.0999 39.48 34.8399 40.88 31.0099C41.41 29.5899 43.11 28.4299 43.09 26.7499C43.09 24.5299 41.49 26.1099 40.03 24.9799C38.82 24.0399 40.03 22.2799 38.94 21.4699C38.6802 21.342 38.3946 21.2754 38.105 21.2754C37.8155 21.2754 37.5298 21.342 37.27 21.4699C32.8685 23.5193 29.1805 26.8381 26.68 30.9999C30.59 30.4699 27.55 36.6699 27.21 38.1199Z\\\" fill=\\\"#00B298\\\"\\\/>\\n<path id=\\\"Vector5656231 327\\\" d=\\\"M38.13 48.3301C37.23 49.1701 35.98 48.3301 35.03 49.1201C34.64 49.4501 34.12 52.6701 34.49 53.2201C35.75 55.1001 38.67 49.6601 38.72 48.4401C38.6416 48.3687 38.5449 48.3206 38.4406 48.3012C38.3364 48.2817 38.2288 48.2918 38.13 48.3301Z\\\" fill=\\\"#00B298\\\"\\\/>\\n<path id=\\\"Vector5656231 328\\\" d=\\\"M76.84 65.3999C76.5681 64.8205 76.2071 64.2874 75.77 63.8199C75.4353 63.5772 75.0417 63.4287 74.6301 63.39C74.2185 63.3514 73.804 63.4238 73.43 63.5999L70.16 64.9999C68.16 65.8699 65.64 65.2699 63.52 66.2099C60.24 67.6599 54.91 73.5499 61.99 72.1199C62.86 71.9499 63.99 71.2599 64.76 71.7499C64.8238 72.9557 64.8238 74.1641 64.76 75.3699C69.5854 73.154 73.7492 69.7175 76.84 65.3999Z\\\" fill=\\\"#00B298\\\"\\\/>\\n<path id=\\\"Vector5656231 329\\\" d=\\\"M77 64.1901C77.2245 64.0827 77.4231 63.9278 77.5819 63.7361C77.7407 63.5445 77.8561 63.3207 77.92 63.0801C77.62 63.4601 77.31 63.8201 77 64.1801V64.1901Z\\\" fill=\\\"#00B298\\\"\\\/>\\n<path id=\\\"Vector5656231 330\\\" d=\\\"M76.57 59.7801C75.63 61.1401 77.01 62.6401 76.96 64.1801C77.27 63.8201 77.58 63.4601 77.88 63.0801C78.37 61.6701 78 59.5201 76.57 59.7801Z\\\" fill=\\\"#00B298\\\"\\\/>\\n<path id=\\\"Vector5656231 331\\\" d=\\\"M74 55.46C72.83 56.39 71.14 55.85 70 56.77C69.7361 56.988 69.5353 57.2725 69.4183 57.5941C69.3013 57.9158 69.2724 58.2628 69.3346 58.5994C69.3969 58.9359 69.5479 59.2497 69.7721 59.5083C69.9964 59.7669 70.2856 59.9608 70.61 60.07C73.01 61.07 72.92 58.68 73.61 57.34C73.91 56.75 75.09 56.13 75.05 55.45C75 54.33 74.48 55.07 74 55.46Z\\\" fill=\\\"#00B298\\\"\\\/>\\n<path id=\\\"Vector5656231 332\\\" d=\\\"M64 53.1501C64 54.2301 64.63 55.3901 64.62 56.5001C64.62 57.2701 64.04 61.2101 65.93 58.6001C66.63 57.6001 66.03 53.4401 64.93 52.4101C64.47 52.0501 64 52.8701 64 53.1501Z\\\" fill=\\\"#00B298\\\"\\\/>\\n<path id=\\\"Vector5656231 333\\\" d=\\\"M78.27 49.5399C78.03 48.9699 76.76 48.7699 76.85 49.6799C77.02 52.2899 75.07 53.2099 76.85 55.7599C77.67 54.9299 77.69 54.0199 77.85 52.8599C77.85 52.5099 77.65 51.7899 77.67 51.3999C77.76 50.7299 78.43 50.3999 78.27 49.5399Z\\\" fill=\\\"#00B298\\\"\\\/>\\n<path id=\\\"Vector5656231 334\\\" d=\\\"M50.13 32.9299C49.48 31.9999 49.41 32.2199 49.23 31.0099C49.02 29.6399 49.51 28.3999 48.74 27.2399C48.3164 26.6455 47.7439 26.173 47.08 25.8699C46.9008 25.777 46.7019 25.7285 46.5 25.7285C46.2981 25.7285 46.0992 25.777 45.92 25.8699C44.82 25.8699 43.65 25.9499 43.14 26.9599C42.72 27.7999 42.92 29.9599 42.7 31.0399C41.86 35.2899 44.55 35.3099 47.99 35.3099C49.18 35.3099 51.34 35.8899 51.19 34.2299C51.14 33.6599 50.4 33.3299 50.13 32.9299Z\\\" fill=\\\"#00B298\\\"\\\/>\\n<path id=\\\"Vector5656231 335\\\" d=\\\"M77.11 45.9299C78.99 44.9299 76.83 44.2799 76.61 43.2299C76.33 41.8999 77.88 40.9499 77.31 39.5299C79.31 38.4099 79.24 41.6999 79.31 42.8799C81.15 42.8799 79.42 40.1199 79.24 39.2199C78.94 37.6899 79.8 36.6099 79.61 35.0999C79.61 34.8799 79.53 34.6399 79.48 34.3999C77.0464 29.4357 73.31 25.2259 68.67 22.2199C68.5931 22.2607 68.5195 22.3075 68.45 22.3599C66.45 24.0499 68.94 24.5299 68.6 25.8699C68.39 26.6599 67.38 26.4599 66.8 26.5899C66.93 26.5899 64.57 26.8699 64.9 26.9799C64.8883 27.019 64.8622 27.0522 64.8268 27.0726C64.7915 27.0931 64.7497 27.0993 64.71 27.0899C64.58 25.4099 62.97 23.7899 61.35 24.9499C59.82 23.3599 62.35 22.1599 62.52 20.5699C61.61 20.5199 60.52 20.3499 59.75 20.9299C58.75 21.6999 59.25 22.6199 57.97 22.9899C57.79 23.0399 57.11 22.4899 56.69 22.6599C56.05 22.9099 56.03 23.5699 55.69 24.0899C55.1838 25.0389 54.577 25.9307 53.88 26.7499C53.06 27.4699 52.58 28.1599 52.06 26.7499C51.54 25.3399 53.06 25.2899 53.34 24.0799C53.66 22.3799 50.01 21.5199 50.34 24.2399C49.02 24.3399 48.02 23.0199 46.46 23.2399C44.37 23.4899 45.02 24.0799 46.81 24.6599C50.41 25.8299 50.09 27.3199 50.94 30.4799C51.87 33.9599 55.58 32.3699 55.69 35.8499C55.75 37.6099 56.28 38.0499 56.89 39.5799C57.5 41.1099 56.96 41.9199 56.57 43.4699C56.3 44.5599 55.57 46.4699 56.93 46.6799C58.34 45.9699 59.39 45.7699 60.13 44.1899C60.49 43.4099 59.98 43.0899 60.84 42.5499C61.7 42.0099 62.45 42.6699 63.15 42.5999C64.44 42.4899 65.64 41.3499 66.87 42.2299C68.58 43.4499 67.15 44.9199 67.41 46.3199C67.67 47.7199 69.59 48.0399 69.95 49.3199C70.31 50.5999 67.95 51.3199 68.29 52.5599C68.91 55.1299 69.98 51.3199 70.29 51.0899C70.73 50.6999 71.8 51.0899 72.13 50.6599C72.46 50.2299 72.31 48.9799 72.26 48.4699C72 46.9999 71.23 46.0899 73 45.5699C74.3 45.1999 75.92 46.5499 77.11 45.9299Z\\\" fill=\\\"#00B298\\\"\\\/>\\n<path id=\\\"Vector5656231 336\\\" d=\\\"M51.85 17.65C51.7514 17.5262 51.6445 17.4093 51.53 17.3C49.2308 17.3363 46.9431 17.6315 44.71 18.18C44.8695 18.2265 45.0177 18.3056 45.1451 18.4123C45.2725 18.519 45.3763 18.651 45.45 18.8C46.08 19.91 44.34 21.5801 45.94 22.0401C46.88 22.3101 46.94 21.16 47.7 20.98C48.2738 20.8764 48.8581 20.8428 49.44 20.88C50.68 20.88 51.73 21.7501 52.54 20.2901C52.3346 20.1123 52.1174 19.9485 51.89 19.8C52 18.8 52.5 18.47 51.85 17.65Z\\\" fill=\\\"#00B298\\\"\\\/>\\n<path id=\\\"Vector5656231 337\\\" d=\\\"M38.59 48.4299C25.66 48.4299 15.19 56.1499 15.19 65.6699C15.2463 69.1322 16.5739 72.453 18.92 74.9999L11.09 86.4099L25.78 80.0899C29.7846 81.9783 34.1626 82.9421 38.59 82.9099C51.51 82.9099 61.99 75.1899 61.99 65.6699C61.99 56.1499 51.51 48.4299 38.59 48.4299Z\\\" fill=\\\"#F3B756\\\"\\\/>\\n<path id=\\\"Vector5656231 338\\\" d=\\\"M42.66 69.61H33.76L32.14 73.46H28.53L36.53 55.25H40.15L48 73.46H44.27L42.66 69.61ZM41.41 66.61L38.23 59L35 66.62L41.41 66.61Z\\\" fill=\\\"white\\\"\\\/>\\n<path id=\\\"Vector5656231 339\\\" d=\\\"M73.26 6C84.6 6 93.79 12.78 93.79 21.13C93.7395 24.1702 92.572 27.0854 90.51 29.32L97.38 39.32L84.49 33.79C80.9798 35.4478 77.1419 36.2954 73.26 36.27C61.91 36.27 52.72 29.49 52.72 21.13C52.72 12.77 61.91 6 73.26 6Z\\\" fill=\\\"#EB6D79\\\"\\\/>\\n<path id=\\\"Vector5656231 340\\\" d=\\\"M78.47 13.9399V15.7999L70.34 25.4499H78.57V27.7599H66.76V25.8899L74.9 16.2499H67V13.9399H78.47Z\\\" fill=\\\"white\\\"\\\/>\\n<path id=\\\"Vector5656231 341\\\" d=\\\"M61.48 138.91C62.08 141.67 59.91 142.96 57.69 143.21C55.47 143.46 53.82 141.37 53.47 139.82C53.12 138.27 54.63 136.82 56.84 136.55C59.05 136.28 60.92 136.39 61.48 138.91Z\\\" fill=\\\"#B57D68\\\"\\\/>\\n<path id=\\\"Vector5656231 342\\\" d=\\\"M63.76 143.55C64.2 146.17 61.05 147.23 58.39 147.55C57.9171 147.643 57.4304 147.641 56.9582 147.545C56.486 147.448 56.0375 147.259 55.6387 146.989C55.2398 146.718 54.8985 146.371 54.6344 145.968C54.3703 145.565 54.1887 145.114 54.1 144.64C53.75 143.09 55.63 141.64 58.29 141.29C60.95 140.94 63.33 141.05 63.76 143.55Z\\\" fill=\\\"#B57D68\\\"\\\/>\\n<path id=\\\"Vector5656231 343\\\" d=\\\"M63.64 148.2C64.06 150.81 62.29 151.2 59.83 151.51C57.37 151.82 55.11 150.76 54.76 149.2C54.41 147.64 56.12 146.2 58.57 145.89C61.02 145.58 63.24 145.68 63.64 148.2Z\\\" fill=\\\"#B57D68\\\"\\\/>\\n<path id=\\\"Vector5656231 344\\\" d=\\\"M62.3301 152.21C62.5801 153.6 61.4101 154.51 59.6801 154.71C57.9501 154.91 56.3301 154.1 56.0601 152.91C55.7901 151.72 56.9801 150.6 58.7101 150.41C60.4401 150.22 61.9301 149.92 62.3301 152.21Z\\\" fill=\\\"#B57D68\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n<defs>\\n<filter id=\\\"filter0_d\\\" x=\\\"17.36\\\" y=\\\"0\\\" width=\\\"338.67\\\" height=\\\"388.224\\\" filterUnits=\\\"userSpaceOnUse\\\" color-interpolation-filters=\\\"sRGB\\\">\\n<feFlood flood-opacity=\\\"0\\\" result=\\\"BackgroundImageFix\\\"\\\/>\\n<feColorMatrix in=\\\"SourceAlpha\\\" type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\\\"\\\/>\\n<feOffset dy=\\\"4\\\"\\\/>\\n<feGaussianBlur stdDeviation=\\\"2\\\"\\\/>\\n<feColorMatrix type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in2=\\\"BackgroundImageFix\\\" result=\\\"effect1_dropShadow\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in=\\\"SourceGraphic\\\" in2=\\\"effect1_dropShadow\\\" result=\\\"shape\\\"\\\/>\\n<\\\/filter>\\n<filter id=\\\"filter1_d\\\" x=\\\"74.4199\\\" y=\\\"138.417\\\" width=\\\"60.1344\\\" height=\\\"51.595\\\" filterUnits=\\\"userSpaceOnUse\\\" color-interpolation-filters=\\\"sRGB\\\">\\n<feFlood flood-opacity=\\\"0\\\" result=\\\"BackgroundImageFix\\\"\\\/>\\n<feColorMatrix in=\\\"SourceAlpha\\\" type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\\\"\\\/>\\n<feOffset dy=\\\"4\\\"\\\/>\\n<feGaussianBlur stdDeviation=\\\"2\\\"\\\/>\\n<feColorMatrix type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in2=\\\"BackgroundImageFix\\\" result=\\\"effect1_dropShadow\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in=\\\"SourceGraphic\\\" in2=\\\"effect1_dropShadow\\\" result=\\\"shape\\\"\\\/>\\n<\\\/filter>\\n<filter id=\\\"filter2_d\\\" x=\\\"104.641\\\" y=\\\"143.428\\\" width=\\\"66.8734\\\" height=\\\"46.9711\\\" filterUnits=\\\"userSpaceOnUse\\\" color-interpolation-filters=\\\"sRGB\\\">\\n<feFlood flood-opacity=\\\"0\\\" result=\\\"BackgroundImageFix\\\"\\\/>\\n<feColorMatrix in=\\\"SourceAlpha\\\" type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\\\"\\\/>\\n<feOffset dy=\\\"4\\\"\\\/>\\n<feGaussianBlur stdDeviation=\\\"2\\\"\\\/>\\n<feColorMatrix type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in2=\\\"BackgroundImageFix\\\" result=\\\"effect1_dropShadow\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in=\\\"SourceGraphic\\\" in2=\\\"effect1_dropShadow\\\" result=\\\"shape\\\"\\\/>\\n<\\\/filter>\\n<filter id=\\\"filter3_d\\\" x=\\\"74.4199\\\" y=\\\"142.84\\\" width=\\\"57.93\\\" height=\\\"47.1715\\\" filterUnits=\\\"userSpaceOnUse\\\" color-interpolation-filters=\\\"sRGB\\\">\\n<feFlood flood-opacity=\\\"0\\\" result=\\\"BackgroundImageFix\\\"\\\/>\\n<feColorMatrix in=\\\"SourceAlpha\\\" type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\\\"\\\/>\\n<feOffset dy=\\\"4\\\"\\\/>\\n<feGaussianBlur stdDeviation=\\\"2\\\"\\\/>\\n<feColorMatrix type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in2=\\\"BackgroundImageFix\\\" result=\\\"effect1_dropShadow\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in=\\\"SourceGraphic\\\" in2=\\\"effect1_dropShadow\\\" result=\\\"shape\\\"\\\/>\\n<\\\/filter>\\n<filter id=\\\"filter4_d\\\" x=\\\"108.7\\\" y=\\\"146.42\\\" width=\\\"62.5039\\\" height=\\\"44.0192\\\" filterUnits=\\\"userSpaceOnUse\\\" color-interpolation-filters=\\\"sRGB\\\">\\n<feFlood flood-opacity=\\\"0\\\" result=\\\"BackgroundImageFix\\\"\\\/>\\n<feColorMatrix in=\\\"SourceAlpha\\\" type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\\\"\\\/>\\n<feOffset dy=\\\"4\\\"\\\/>\\n<feGaussianBlur stdDeviation=\\\"2\\\"\\\/>\\n<feColorMatrix type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in2=\\\"BackgroundImageFix\\\" result=\\\"effect1_dropShadow\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in=\\\"SourceGraphic\\\" in2=\\\"effect1_dropShadow\\\" result=\\\"shape\\\"\\\/>\\n<\\\/filter>\\n<filter id=\\\"filter5_d\\\" x=\\\"221.743\\\" y=\\\"128.427\\\" width=\\\"64.777\\\" height=\\\"44.5912\\\" filterUnits=\\\"userSpaceOnUse\\\" color-interpolation-filters=\\\"sRGB\\\">\\n<feFlood flood-opacity=\\\"0\\\" result=\\\"BackgroundImageFix\\\"\\\/>\\n<feColorMatrix in=\\\"SourceAlpha\\\" type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\\\"\\\/>\\n<feOffset dy=\\\"4\\\"\\\/>\\n<feGaussianBlur stdDeviation=\\\"2\\\"\\\/>\\n<feColorMatrix type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in2=\\\"BackgroundImageFix\\\" result=\\\"effect1_dropShadow\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in=\\\"SourceGraphic\\\" in2=\\\"effect1_dropShadow\\\" result=\\\"shape\\\"\\\/>\\n<\\\/filter>\\n<filter id=\\\"filter6_d\\\" x=\\\"221.73\\\" y=\\\"134.23\\\" width=\\\"64.79\\\" height=\\\"38.7877\\\" filterUnits=\\\"userSpaceOnUse\\\" color-interpolation-filters=\\\"sRGB\\\">\\n<feFlood flood-opacity=\\\"0\\\" result=\\\"BackgroundImageFix\\\"\\\/>\\n<feColorMatrix in=\\\"SourceAlpha\\\" type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\\\"\\\/>\\n<feOffset dy=\\\"4\\\"\\\/>\\n<feGaussianBlur stdDeviation=\\\"2\\\"\\\/>\\n<feColorMatrix type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in2=\\\"BackgroundImageFix\\\" result=\\\"effect1_dropShadow\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in=\\\"SourceGraphic\\\" in2=\\\"effect1_dropShadow\\\" result=\\\"shape\\\"\\\/>\\n<\\\/filter>\\n<filter id=\\\"filter7_d\\\" x=\\\"268.38\\\" y=\\\"120.823\\\" width=\\\"40.2329\\\" height=\\\"26.409\\\" filterUnits=\\\"userSpaceOnUse\\\" color-interpolation-filters=\\\"sRGB\\\">\\n<feFlood flood-opacity=\\\"0\\\" result=\\\"BackgroundImageFix\\\"\\\/>\\n<feColorMatrix in=\\\"SourceAlpha\\\" type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\\\"\\\/>\\n<feOffset dy=\\\"4\\\"\\\/>\\n<feGaussianBlur stdDeviation=\\\"2\\\"\\\/>\\n<feColorMatrix type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in2=\\\"BackgroundImageFix\\\" result=\\\"effect1_dropShadow\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in=\\\"SourceGraphic\\\" in2=\\\"effect1_dropShadow\\\" result=\\\"shape\\\"\\\/>\\n<\\\/filter>\\n<filter id=\\\"filter8_d\\\" x=\\\"192.096\\\" y=\\\"278.072\\\" width=\\\"30.1765\\\" height=\\\"98.3212\\\" filterUnits=\\\"userSpaceOnUse\\\" color-interpolation-filters=\\\"sRGB\\\">\\n<feFlood flood-opacity=\\\"0\\\" result=\\\"BackgroundImageFix\\\"\\\/>\\n<feColorMatrix in=\\\"SourceAlpha\\\" type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\\\"\\\/>\\n<feOffset dy=\\\"4\\\"\\\/>\\n<feGaussianBlur stdDeviation=\\\"2\\\"\\\/>\\n<feColorMatrix type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in2=\\\"BackgroundImageFix\\\" result=\\\"effect1_dropShadow\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in=\\\"SourceGraphic\\\" in2=\\\"effect1_dropShadow\\\" result=\\\"shape\\\"\\\/>\\n<\\\/filter>\\n<filter id=\\\"filter9_d\\\" x=\\\"191.499\\\" y=\\\"353.75\\\" width=\\\"33.6398\\\" height=\\\"28.6264\\\" filterUnits=\\\"userSpaceOnUse\\\" color-interpolation-filters=\\\"sRGB\\\">\\n<feFlood flood-opacity=\\\"0\\\" result=\\\"BackgroundImageFix\\\"\\\/>\\n<feColorMatrix in=\\\"SourceAlpha\\\" type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\\\"\\\/>\\n<feOffset dy=\\\"4\\\"\\\/>\\n<feGaussianBlur stdDeviation=\\\"2\\\"\\\/>\\n<feColorMatrix type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in2=\\\"BackgroundImageFix\\\" result=\\\"effect1_dropShadow\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in=\\\"SourceGraphic\\\" in2=\\\"effect1_dropShadow\\\" result=\\\"shape\\\"\\\/>\\n<\\\/filter>\\n<filter id=\\\"filter10_d\\\" x=\\\"190.535\\\" y=\\\"355.46\\\" width=\\\"35.9185\\\" height=\\\"32.46\\\" filterUnits=\\\"userSpaceOnUse\\\" color-interpolation-filters=\\\"sRGB\\\">\\n<feFlood flood-opacity=\\\"0\\\" result=\\\"BackgroundImageFix\\\"\\\/>\\n<feColorMatrix in=\\\"SourceAlpha\\\" type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\\\"\\\/>\\n<feOffset dy=\\\"4\\\"\\\/>\\n<feGaussianBlur stdDeviation=\\\"2\\\"\\\/>\\n<feColorMatrix type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in2=\\\"BackgroundImageFix\\\" result=\\\"effect1_dropShadow\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in=\\\"SourceGraphic\\\" in2=\\\"effect1_dropShadow\\\" result=\\\"shape\\\"\\\/>\\n<\\\/filter>\\n<filter id=\\\"filter11_d\\\" x=\\\"211.3\\\" y=\\\"355.47\\\" width=\\\"15.1438\\\" height=\\\"32.04\\\" filterUnits=\\\"userSpaceOnUse\\\" color-interpolation-filters=\\\"sRGB\\\">\\n<feFlood flood-opacity=\\\"0\\\" result=\\\"BackgroundImageFix\\\"\\\/>\\n<feColorMatrix in=\\\"SourceAlpha\\\" type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\\\"\\\/>\\n<feOffset dy=\\\"4\\\"\\\/>\\n<feGaussianBlur stdDeviation=\\\"2\\\"\\\/>\\n<feColorMatrix type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in2=\\\"BackgroundImageFix\\\" result=\\\"effect1_dropShadow\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in=\\\"SourceGraphic\\\" in2=\\\"effect1_dropShadow\\\" result=\\\"shape\\\"\\\/>\\n<\\\/filter>\\n<filter id=\\\"filter12_d\\\" x=\\\"191.68\\\" y=\\\"377.56\\\" width=\\\"33.42\\\" height=\\\"10.34\\\" filterUnits=\\\"userSpaceOnUse\\\" color-interpolation-filters=\\\"sRGB\\\">\\n<feFlood flood-opacity=\\\"0\\\" result=\\\"BackgroundImageFix\\\"\\\/>\\n<feColorMatrix in=\\\"SourceAlpha\\\" type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\\\"\\\/>\\n<feOffset dy=\\\"4\\\"\\\/>\\n<feGaussianBlur stdDeviation=\\\"2\\\"\\\/>\\n<feColorMatrix type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in2=\\\"BackgroundImageFix\\\" result=\\\"effect1_dropShadow\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in=\\\"SourceGraphic\\\" in2=\\\"effect1_dropShadow\\\" result=\\\"shape\\\"\\\/>\\n<\\\/filter>\\n<filter id=\\\"filter13_d\\\" x=\\\"197.65\\\" y=\\\"365.419\\\" width=\\\"21.7345\\\" height=\\\"11.2115\\\" filterUnits=\\\"userSpaceOnUse\\\" color-interpolation-filters=\\\"sRGB\\\">\\n<feFlood flood-opacity=\\\"0\\\" result=\\\"BackgroundImageFix\\\"\\\/>\\n<feColorMatrix in=\\\"SourceAlpha\\\" type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\\\"\\\/>\\n<feOffset dy=\\\"4\\\"\\\/>\\n<feGaussianBlur stdDeviation=\\\"2\\\"\\\/>\\n<feColorMatrix type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in2=\\\"BackgroundImageFix\\\" result=\\\"effect1_dropShadow\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in=\\\"SourceGraphic\\\" in2=\\\"effect1_dropShadow\\\" result=\\\"shape\\\"\\\/>\\n<\\\/filter>\\n<filter id=\\\"filter14_d\\\" x=\\\"201.055\\\" y=\\\"368.708\\\" width=\\\"15.807\\\" height=\\\"10.4334\\\" filterUnits=\\\"userSpaceOnUse\\\" color-interpolation-filters=\\\"sRGB\\\">\\n<feFlood flood-opacity=\\\"0\\\" result=\\\"BackgroundImageFix\\\"\\\/>\\n<feColorMatrix in=\\\"SourceAlpha\\\" type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\\\"\\\/>\\n<feOffset dy=\\\"4\\\"\\\/>\\n<feGaussianBlur stdDeviation=\\\"2\\\"\\\/>\\n<feColorMatrix type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in2=\\\"BackgroundImageFix\\\" result=\\\"effect1_dropShadow\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in=\\\"SourceGraphic\\\" in2=\\\"effect1_dropShadow\\\" result=\\\"shape\\\"\\\/>\\n<\\\/filter>\\n<filter id=\\\"filter15_d\\\" x=\\\"148.372\\\" y=\\\"279.885\\\" width=\\\"30.3161\\\" height=\\\"99.6578\\\" filterUnits=\\\"userSpaceOnUse\\\" color-interpolation-filters=\\\"sRGB\\\">\\n<feFlood flood-opacity=\\\"0\\\" result=\\\"BackgroundImageFix\\\"\\\/>\\n<feColorMatrix in=\\\"SourceAlpha\\\" type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\\\"\\\/>\\n<feOffset dy=\\\"4\\\"\\\/>\\n<feGaussianBlur stdDeviation=\\\"2\\\"\\\/>\\n<feColorMatrix type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in2=\\\"BackgroundImageFix\\\" result=\\\"effect1_dropShadow\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in=\\\"SourceGraphic\\\" in2=\\\"effect1_dropShadow\\\" result=\\\"shape\\\"\\\/>\\n<\\\/filter>\\n<filter id=\\\"filter16_d\\\" x=\\\"142\\\" y=\\\"353.79\\\" width=\\\"30.8083\\\" height=\\\"22.3245\\\" filterUnits=\\\"userSpaceOnUse\\\" color-interpolation-filters=\\\"sRGB\\\">\\n<feFlood flood-opacity=\\\"0\\\" result=\\\"BackgroundImageFix\\\"\\\/>\\n<feColorMatrix in=\\\"SourceAlpha\\\" type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\\\"\\\/>\\n<feOffset dy=\\\"4\\\"\\\/>\\n<feGaussianBlur stdDeviation=\\\"2\\\"\\\/>\\n<feColorMatrix type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in2=\\\"BackgroundImageFix\\\" result=\\\"effect1_dropShadow\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in=\\\"SourceGraphic\\\" in2=\\\"effect1_dropShadow\\\" result=\\\"shape\\\"\\\/>\\n<\\\/filter>\\n<filter id=\\\"filter17_d\\\" x=\\\"129.734\\\" y=\\\"355.18\\\" width=\\\"45.3005\\\" height=\\\"33.044\\\" filterUnits=\\\"userSpaceOnUse\\\" color-interpolation-filters=\\\"sRGB\\\">\\n<feFlood flood-opacity=\\\"0\\\" result=\\\"BackgroundImageFix\\\"\\\/>\\n<feColorMatrix in=\\\"SourceAlpha\\\" type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\\\"\\\/>\\n<feOffset dy=\\\"4\\\"\\\/>\\n<feGaussianBlur stdDeviation=\\\"2\\\"\\\/>\\n<feColorMatrix type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in2=\\\"BackgroundImageFix\\\" result=\\\"effect1_dropShadow\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in=\\\"SourceGraphic\\\" in2=\\\"effect1_dropShadow\\\" result=\\\"shape\\\"\\\/>\\n<\\\/filter>\\n<filter id=\\\"filter18_d\\\" x=\\\"147.91\\\" y=\\\"355.15\\\" width=\\\"27.1177\\\" height=\\\"32.99\\\" filterUnits=\\\"userSpaceOnUse\\\" color-interpolation-filters=\\\"sRGB\\\">\\n<feFlood flood-opacity=\\\"0\\\" result=\\\"BackgroundImageFix\\\"\\\/>\\n<feColorMatrix in=\\\"SourceAlpha\\\" type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\\\"\\\/>\\n<feOffset dy=\\\"4\\\"\\\/>\\n<feGaussianBlur stdDeviation=\\\"2\\\"\\\/>\\n<feColorMatrix type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in2=\\\"BackgroundImageFix\\\" result=\\\"effect1_dropShadow\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in=\\\"SourceGraphic\\\" in2=\\\"effect1_dropShadow\\\" result=\\\"shape\\\"\\\/>\\n<\\\/filter>\\n<filter id=\\\"filter19_d\\\" x=\\\"129.677\\\" y=\\\"375.69\\\" width=\\\"44.2122\\\" height=\\\"12.4451\\\" filterUnits=\\\"userSpaceOnUse\\\" color-interpolation-filters=\\\"sRGB\\\">\\n<feFlood flood-opacity=\\\"0\\\" result=\\\"BackgroundImageFix\\\"\\\/>\\n<feColorMatrix in=\\\"SourceAlpha\\\" type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\\\"\\\/>\\n<feOffset dy=\\\"4\\\"\\\/>\\n<feGaussianBlur stdDeviation=\\\"2\\\"\\\/>\\n<feColorMatrix type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in2=\\\"BackgroundImageFix\\\" result=\\\"effect1_dropShadow\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in=\\\"SourceGraphic\\\" in2=\\\"effect1_dropShadow\\\" result=\\\"shape\\\"\\\/>\\n<\\\/filter>\\n<filter id=\\\"filter20_d\\\" x=\\\"139.109\\\" y=\\\"363.534\\\" width=\\\"21.8189\\\" height=\\\"12.9059\\\" filterUnits=\\\"userSpaceOnUse\\\" color-interpolation-filters=\\\"sRGB\\\">\\n<feFlood flood-opacity=\\\"0\\\" result=\\\"BackgroundImageFix\\\"\\\/>\\n<feColorMatrix in=\\\"SourceAlpha\\\" type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\\\"\\\/>\\n<feOffset dy=\\\"4\\\"\\\/>\\n<feGaussianBlur stdDeviation=\\\"2\\\"\\\/>\\n<feColorMatrix type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in2=\\\"BackgroundImageFix\\\" result=\\\"effect1_dropShadow\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in=\\\"SourceGraphic\\\" in2=\\\"effect1_dropShadow\\\" result=\\\"shape\\\"\\\/>\\n<\\\/filter>\\n<filter id=\\\"filter21_d\\\" x=\\\"138.082\\\" y=\\\"366.75\\\" width=\\\"15.9883\\\" height=\\\"10.9702\\\" filterUnits=\\\"userSpaceOnUse\\\" color-interpolation-filters=\\\"sRGB\\\">\\n<feFlood flood-opacity=\\\"0\\\" result=\\\"BackgroundImageFix\\\"\\\/>\\n<feColorMatrix in=\\\"SourceAlpha\\\" type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\\\"\\\/>\\n<feOffset dy=\\\"4\\\"\\\/>\\n<feGaussianBlur stdDeviation=\\\"2\\\"\\\/>\\n<feColorMatrix type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in2=\\\"BackgroundImageFix\\\" result=\\\"effect1_dropShadow\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in=\\\"SourceGraphic\\\" in2=\\\"effect1_dropShadow\\\" result=\\\"shape\\\"\\\/>\\n<\\\/filter>\\n<filter id=\\\"filter22_d\\\" x=\\\"174.6\\\" y=\\\"223.67\\\" width=\\\"50.0888\\\" height=\\\"135.949\\\" filterUnits=\\\"userSpaceOnUse\\\" color-interpolation-filters=\\\"sRGB\\\">\\n<feFlood flood-opacity=\\\"0\\\" result=\\\"BackgroundImageFix\\\"\\\/>\\n<feColorMatrix in=\\\"SourceAlpha\\\" type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\\\"\\\/>\\n<feOffset dy=\\\"4\\\"\\\/>\\n<feGaussianBlur stdDeviation=\\\"2\\\"\\\/>\\n<feColorMatrix type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in2=\\\"BackgroundImageFix\\\" result=\\\"effect1_dropShadow\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in=\\\"SourceGraphic\\\" in2=\\\"effect1_dropShadow\\\" result=\\\"shape\\\"\\\/>\\n<\\\/filter>\\n<filter id=\\\"filter23_d\\\" x=\\\"174.6\\\" y=\\\"223.62\\\" width=\\\"50.0901\\\" height=\\\"135.67\\\" filterUnits=\\\"userSpaceOnUse\\\" color-interpolation-filters=\\\"sRGB\\\">\\n<feFlood flood-opacity=\\\"0\\\" result=\\\"BackgroundImageFix\\\"\\\/>\\n<feColorMatrix in=\\\"SourceAlpha\\\" type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\\\"\\\/>\\n<feOffset dy=\\\"4\\\"\\\/>\\n<feGaussianBlur stdDeviation=\\\"2\\\"\\\/>\\n<feColorMatrix type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in2=\\\"BackgroundImageFix\\\" result=\\\"effect1_dropShadow\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in=\\\"SourceGraphic\\\" in2=\\\"effect1_dropShadow\\\" result=\\\"shape\\\"\\\/>\\n<\\\/filter>\\n<filter id=\\\"filter24_d\\\" x=\\\"197.835\\\" y=\\\"238.04\\\" width=\\\"26.6554\\\" height=\\\"27.3393\\\" filterUnits=\\\"userSpaceOnUse\\\" color-interpolation-filters=\\\"sRGB\\\">\\n<feFlood flood-opacity=\\\"0\\\" result=\\\"BackgroundImageFix\\\"\\\/>\\n<feColorMatrix in=\\\"SourceAlpha\\\" type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\\\"\\\/>\\n<feOffset dy=\\\"4\\\"\\\/>\\n<feGaussianBlur stdDeviation=\\\"2\\\"\\\/>\\n<feColorMatrix type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in2=\\\"BackgroundImageFix\\\" result=\\\"effect1_dropShadow\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in=\\\"SourceGraphic\\\" in2=\\\"effect1_dropShadow\\\" result=\\\"shape\\\"\\\/>\\n<\\\/filter>\\n<filter id=\\\"filter25_d\\\" x=\\\"141.1\\\" y=\\\"223.94\\\" width=\\\"49.74\\\" height=\\\"137.129\\\" filterUnits=\\\"userSpaceOnUse\\\" color-interpolation-filters=\\\"sRGB\\\">\\n<feFlood flood-opacity=\\\"0\\\" result=\\\"BackgroundImageFix\\\"\\\/>\\n<feColorMatrix in=\\\"SourceAlpha\\\" type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\\\"\\\/>\\n<feOffset dy=\\\"4\\\"\\\/>\\n<feGaussianBlur stdDeviation=\\\"2\\\"\\\/>\\n<feColorMatrix type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in2=\\\"BackgroundImageFix\\\" result=\\\"effect1_dropShadow\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in=\\\"SourceGraphic\\\" in2=\\\"effect1_dropShadow\\\" result=\\\"shape\\\"\\\/>\\n<\\\/filter>\\n<filter id=\\\"filter26_d\\\" x=\\\"161.78\\\" y=\\\"259.32\\\" width=\\\"23.45\\\" height=\\\"101.4\\\" filterUnits=\\\"userSpaceOnUse\\\" color-interpolation-filters=\\\"sRGB\\\">\\n<feFlood flood-opacity=\\\"0\\\" result=\\\"BackgroundImageFix\\\"\\\/>\\n<feColorMatrix in=\\\"SourceAlpha\\\" type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\\\"\\\/>\\n<feOffset dy=\\\"4\\\"\\\/>\\n<feGaussianBlur stdDeviation=\\\"2\\\"\\\/>\\n<feColorMatrix type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in2=\\\"BackgroundImageFix\\\" result=\\\"effect1_dropShadow\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in=\\\"SourceGraphic\\\" in2=\\\"effect1_dropShadow\\\" result=\\\"shape\\\"\\\/>\\n<\\\/filter>\\n<filter id=\\\"filter27_d\\\" x=\\\"143.72\\\" y=\\\"223.94\\\" width=\\\"47.11\\\" height=\\\"37.2992\\\" filterUnits=\\\"userSpaceOnUse\\\" color-interpolation-filters=\\\"sRGB\\\">\\n<feFlood flood-opacity=\\\"0\\\" result=\\\"BackgroundImageFix\\\"\\\/>\\n<feColorMatrix in=\\\"SourceAlpha\\\" type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\\\"\\\/>\\n<feOffset dy=\\\"4\\\"\\\/>\\n<feGaussianBlur stdDeviation=\\\"2\\\"\\\/>\\n<feColorMatrix type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in2=\\\"BackgroundImageFix\\\" result=\\\"effect1_dropShadow\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in=\\\"SourceGraphic\\\" in2=\\\"effect1_dropShadow\\\" result=\\\"shape\\\"\\\/>\\n<\\\/filter>\\n<filter id=\\\"filter28_d\\\" x=\\\"142.89\\\" y=\\\"240.028\\\" width=\\\"19.6476\\\" height=\\\"28.3321\\\" filterUnits=\\\"userSpaceOnUse\\\" color-interpolation-filters=\\\"sRGB\\\">\\n<feFlood flood-opacity=\\\"0\\\" result=\\\"BackgroundImageFix\\\"\\\/>\\n<feColorMatrix in=\\\"SourceAlpha\\\" type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\\\"\\\/>\\n<feOffset dy=\\\"4\\\"\\\/>\\n<feGaussianBlur stdDeviation=\\\"2\\\"\\\/>\\n<feColorMatrix type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in2=\\\"BackgroundImageFix\\\" result=\\\"effect1_dropShadow\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in=\\\"SourceGraphic\\\" in2=\\\"effect1_dropShadow\\\" result=\\\"shape\\\"\\\/>\\n<\\\/filter>\\n<filter id=\\\"filter29_d\\\" x=\\\"183.14\\\" y=\\\"133.349\\\" width=\\\"54.5304\\\" height=\\\"47.2208\\\" filterUnits=\\\"userSpaceOnUse\\\" color-interpolation-filters=\\\"sRGB\\\">\\n<feFlood flood-opacity=\\\"0\\\" result=\\\"BackgroundImageFix\\\"\\\/>\\n<feColorMatrix in=\\\"SourceAlpha\\\" type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\\\"\\\/>\\n<feOffset dy=\\\"4\\\"\\\/>\\n<feGaussianBlur stdDeviation=\\\"2\\\"\\\/>\\n<feColorMatrix type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in2=\\\"BackgroundImageFix\\\" result=\\\"effect1_dropShadow\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in=\\\"SourceGraphic\\\" in2=\\\"effect1_dropShadow\\\" result=\\\"shape\\\"\\\/>\\n<\\\/filter>\\n<filter id=\\\"filter30_d\\\" x=\\\"125.58\\\" y=\\\"135.305\\\" width=\\\"49.5112\\\" height=\\\"54.6032\\\" filterUnits=\\\"userSpaceOnUse\\\" color-interpolation-filters=\\\"sRGB\\\">\\n<feFlood flood-opacity=\\\"0\\\" result=\\\"BackgroundImageFix\\\"\\\/>\\n<feColorMatrix in=\\\"SourceAlpha\\\" type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\\\"\\\/>\\n<feOffset dy=\\\"4\\\"\\\/>\\n<feGaussianBlur stdDeviation=\\\"2\\\"\\\/>\\n<feColorMatrix type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in2=\\\"BackgroundImageFix\\\" result=\\\"effect1_dropShadow\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in=\\\"SourceGraphic\\\" in2=\\\"effect1_dropShadow\\\" result=\\\"shape\\\"\\\/>\\n<\\\/filter>\\n<filter id=\\\"filter31_d\\\" x=\\\"141.63\\\" y=\\\"130.524\\\" width=\\\"82.16\\\" height=\\\"124.875\\\" filterUnits=\\\"userSpaceOnUse\\\" color-interpolation-filters=\\\"sRGB\\\">\\n<feFlood flood-opacity=\\\"0\\\" result=\\\"BackgroundImageFix\\\"\\\/>\\n<feColorMatrix in=\\\"SourceAlpha\\\" type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\\\"\\\/>\\n<feOffset dy=\\\"4\\\"\\\/>\\n<feGaussianBlur stdDeviation=\\\"2\\\"\\\/>\\n<feColorMatrix type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in2=\\\"BackgroundImageFix\\\" result=\\\"effect1_dropShadow\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in=\\\"SourceGraphic\\\" in2=\\\"effect1_dropShadow\\\" result=\\\"shape\\\"\\\/>\\n<\\\/filter>\\n<filter id=\\\"filter32_d\\\" x=\\\"172.4\\\" y=\\\"133.6\\\" width=\\\"51.38\\\" height=\\\"121.807\\\" filterUnits=\\\"userSpaceOnUse\\\" color-interpolation-filters=\\\"sRGB\\\">\\n<feFlood flood-opacity=\\\"0\\\" result=\\\"BackgroundImageFix\\\"\\\/>\\n<feColorMatrix in=\\\"SourceAlpha\\\" type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\\\"\\\/>\\n<feOffset dy=\\\"4\\\"\\\/>\\n<feGaussianBlur stdDeviation=\\\"2\\\"\\\/>\\n<feColorMatrix type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in2=\\\"BackgroundImageFix\\\" result=\\\"effect1_dropShadow\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in=\\\"SourceGraphic\\\" in2=\\\"effect1_dropShadow\\\" result=\\\"shape\\\"\\\/>\\n<\\\/filter>\\n<filter id=\\\"filter33_d\\\" x=\\\"166.31\\\" y=\\\"130.516\\\" width=\\\"29.35\\\" height=\\\"23.4086\\\" filterUnits=\\\"userSpaceOnUse\\\" color-interpolation-filters=\\\"sRGB\\\">\\n<feFlood flood-opacity=\\\"0\\\" result=\\\"BackgroundImageFix\\\"\\\/>\\n<feColorMatrix in=\\\"SourceAlpha\\\" type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\\\"\\\/>\\n<feOffset dy=\\\"4\\\"\\\/>\\n<feGaussianBlur stdDeviation=\\\"2\\\"\\\/>\\n<feColorMatrix type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in2=\\\"BackgroundImageFix\\\" result=\\\"effect1_dropShadow\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in=\\\"SourceGraphic\\\" in2=\\\"effect1_dropShadow\\\" result=\\\"shape\\\"\\\/>\\n<\\\/filter>\\n<filter id=\\\"filter34_d\\\" x=\\\"126.279\\\" y=\\\"20.3533\\\" width=\\\"102.955\\\" height=\\\"86.2609\\\" filterUnits=\\\"userSpaceOnUse\\\" color-interpolation-filters=\\\"sRGB\\\">\\n<feFlood flood-opacity=\\\"0\\\" result=\\\"BackgroundImageFix\\\"\\\/>\\n<feColorMatrix in=\\\"SourceAlpha\\\" type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\\\"\\\/>\\n<feOffset dy=\\\"4\\\"\\\/>\\n<feGaussianBlur stdDeviation=\\\"2\\\"\\\/>\\n<feColorMatrix type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in2=\\\"BackgroundImageFix\\\" result=\\\"effect1_dropShadow\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in=\\\"SourceGraphic\\\" in2=\\\"effect1_dropShadow\\\" result=\\\"shape\\\"\\\/>\\n<\\\/filter>\\n<filter id=\\\"filter35_d\\\" x=\\\"167.8\\\" y=\\\"118.2\\\" width=\\\"25.11\\\" height=\\\"23.97\\\" filterUnits=\\\"userSpaceOnUse\\\" color-interpolation-filters=\\\"sRGB\\\">\\n<feFlood flood-opacity=\\\"0\\\" result=\\\"BackgroundImageFix\\\"\\\/>\\n<feColorMatrix in=\\\"SourceAlpha\\\" type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\\\"\\\/>\\n<feOffset dy=\\\"4\\\"\\\/>\\n<feGaussianBlur stdDeviation=\\\"2\\\"\\\/>\\n<feColorMatrix type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in2=\\\"BackgroundImageFix\\\" result=\\\"effect1_dropShadow\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in=\\\"SourceGraphic\\\" in2=\\\"effect1_dropShadow\\\" result=\\\"shape\\\"\\\/>\\n<\\\/filter>\\n<filter id=\\\"filter36_d\\\" x=\\\"167.93\\\" y=\\\"118.2\\\" width=\\\"24.96\\\" height=\\\"18.6679\\\" filterUnits=\\\"userSpaceOnUse\\\" color-interpolation-filters=\\\"sRGB\\\">\\n<feFlood flood-opacity=\\\"0\\\" result=\\\"BackgroundImageFix\\\"\\\/>\\n<feColorMatrix in=\\\"SourceAlpha\\\" type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\\\"\\\/>\\n<feOffset dy=\\\"4\\\"\\\/>\\n<feGaussianBlur stdDeviation=\\\"2\\\"\\\/>\\n<feColorMatrix type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in2=\\\"BackgroundImageFix\\\" result=\\\"effect1_dropShadow\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in=\\\"SourceGraphic\\\" in2=\\\"effect1_dropShadow\\\" result=\\\"shape\\\"\\\/>\\n<\\\/filter>\\n<filter id=\\\"filter37_d\\\" x=\\\"206.799\\\" y=\\\"73.585\\\" width=\\\"27.9138\\\" height=\\\"28.791\\\" filterUnits=\\\"userSpaceOnUse\\\" color-interpolation-filters=\\\"sRGB\\\">\\n<feFlood flood-opacity=\\\"0\\\" result=\\\"BackgroundImageFix\\\"\\\/>\\n<feColorMatrix in=\\\"SourceAlpha\\\" type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\\\"\\\/>\\n<feOffset dy=\\\"4\\\"\\\/>\\n<feGaussianBlur stdDeviation=\\\"2\\\"\\\/>\\n<feColorMatrix type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in2=\\\"BackgroundImageFix\\\" result=\\\"effect1_dropShadow\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in=\\\"SourceGraphic\\\" in2=\\\"effect1_dropShadow\\\" result=\\\"shape\\\"\\\/>\\n<\\\/filter>\\n<filter id=\\\"filter38_d\\\" x=\\\"215.904\\\" y=\\\"77.9875\\\" width=\\\"13.6516\\\" height=\\\"18.86\\\" filterUnits=\\\"userSpaceOnUse\\\" color-interpolation-filters=\\\"sRGB\\\">\\n<feFlood flood-opacity=\\\"0\\\" result=\\\"BackgroundImageFix\\\"\\\/>\\n<feColorMatrix in=\\\"SourceAlpha\\\" type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\\\"\\\/>\\n<feOffset dy=\\\"4\\\"\\\/>\\n<feGaussianBlur stdDeviation=\\\"2\\\"\\\/>\\n<feColorMatrix type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in2=\\\"BackgroundImageFix\\\" result=\\\"effect1_dropShadow\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in=\\\"SourceGraphic\\\" in2=\\\"effect1_dropShadow\\\" result=\\\"shape\\\"\\\/>\\n<\\\/filter>\\n<filter id=\\\"filter39_d\\\" x=\\\"130.097\\\" y=\\\"78.4641\\\" width=\\\"26.0171\\\" height=\\\"27.5432\\\" filterUnits=\\\"userSpaceOnUse\\\" color-interpolation-filters=\\\"sRGB\\\">\\n<feFlood flood-opacity=\\\"0\\\" result=\\\"BackgroundImageFix\\\"\\\/>\\n<feColorMatrix in=\\\"SourceAlpha\\\" type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\\\"\\\/>\\n<feOffset dy=\\\"4\\\"\\\/>\\n<feGaussianBlur stdDeviation=\\\"2\\\"\\\/>\\n<feColorMatrix type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in2=\\\"BackgroundImageFix\\\" result=\\\"effect1_dropShadow\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in=\\\"SourceGraphic\\\" in2=\\\"effect1_dropShadow\\\" result=\\\"shape\\\"\\\/>\\n<\\\/filter>\\n<filter id=\\\"filter40_d\\\" x=\\\"134.169\\\" y=\\\"83.0667\\\" width=\\\"13.9787\\\" height=\\\"17.9795\\\" filterUnits=\\\"userSpaceOnUse\\\" color-interpolation-filters=\\\"sRGB\\\">\\n<feFlood flood-opacity=\\\"0\\\" result=\\\"BackgroundImageFix\\\"\\\/>\\n<feColorMatrix in=\\\"SourceAlpha\\\" type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\\\"\\\/>\\n<feOffset dy=\\\"4\\\"\\\/>\\n<feGaussianBlur stdDeviation=\\\"2\\\"\\\/>\\n<feColorMatrix type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in2=\\\"BackgroundImageFix\\\" result=\\\"effect1_dropShadow\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in=\\\"SourceGraphic\\\" in2=\\\"effect1_dropShadow\\\" result=\\\"shape\\\"\\\/>\\n<\\\/filter>\\n<filter id=\\\"filter41_d\\\" x=\\\"140.089\\\" y=\\\"49.7864\\\" width=\\\"81.7319\\\" height=\\\"83.9851\\\" filterUnits=\\\"userSpaceOnUse\\\" color-interpolation-filters=\\\"sRGB\\\">\\n<feFlood flood-opacity=\\\"0\\\" result=\\\"BackgroundImageFix\\\"\\\/>\\n<feColorMatrix in=\\\"SourceAlpha\\\" type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\\\"\\\/>\\n<feOffset dy=\\\"4\\\"\\\/>\\n<feGaussianBlur stdDeviation=\\\"2\\\"\\\/>\\n<feColorMatrix type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in2=\\\"BackgroundImageFix\\\" result=\\\"effect1_dropShadow\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in=\\\"SourceGraphic\\\" in2=\\\"effect1_dropShadow\\\" result=\\\"shape\\\"\\\/>\\n<\\\/filter>\\n<filter id=\\\"filter42_d\\\" x=\\\"153.29\\\" y=\\\"50.01\\\" width=\\\"68.5264\\\" height=\\\"83.7659\\\" filterUnits=\\\"userSpaceOnUse\\\" color-interpolation-filters=\\\"sRGB\\\">\\n<feFlood flood-opacity=\\\"0\\\" result=\\\"BackgroundImageFix\\\"\\\/>\\n<feColorMatrix in=\\\"SourceAlpha\\\" type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\\\"\\\/>\\n<feOffset dy=\\\"4\\\"\\\/>\\n<feGaussianBlur stdDeviation=\\\"2\\\"\\\/>\\n<feColorMatrix type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in2=\\\"BackgroundImageFix\\\" result=\\\"effect1_dropShadow\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in=\\\"SourceGraphic\\\" in2=\\\"effect1_dropShadow\\\" result=\\\"shape\\\"\\\/>\\n<\\\/filter>\\n<filter id=\\\"filter43_d\\\" x=\\\"187.01\\\" y=\\\"81.0701\\\" width=\\\"21.2426\\\" height=\\\"14.6623\\\" filterUnits=\\\"userSpaceOnUse\\\" color-interpolation-filters=\\\"sRGB\\\">\\n<feFlood flood-opacity=\\\"0\\\" result=\\\"BackgroundImageFix\\\"\\\/>\\n<feColorMatrix in=\\\"SourceAlpha\\\" type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\\\"\\\/>\\n<feOffset dy=\\\"4\\\"\\\/>\\n<feGaussianBlur stdDeviation=\\\"2\\\"\\\/>\\n<feColorMatrix type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in2=\\\"BackgroundImageFix\\\" result=\\\"effect1_dropShadow\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in=\\\"SourceGraphic\\\" in2=\\\"effect1_dropShadow\\\" result=\\\"shape\\\"\\\/>\\n<\\\/filter>\\n<filter id=\\\"filter44_d\\\" x=\\\"148.495\\\" y=\\\"81.6499\\\" width=\\\"21.2315\\\" height=\\\"14.7169\\\" filterUnits=\\\"userSpaceOnUse\\\" color-interpolation-filters=\\\"sRGB\\\">\\n<feFlood flood-opacity=\\\"0\\\" result=\\\"BackgroundImageFix\\\"\\\/>\\n<feColorMatrix in=\\\"SourceAlpha\\\" type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\\\"\\\/>\\n<feOffset dy=\\\"4\\\"\\\/>\\n<feGaussianBlur stdDeviation=\\\"2\\\"\\\/>\\n<feColorMatrix type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in2=\\\"BackgroundImageFix\\\" result=\\\"effect1_dropShadow\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in=\\\"SourceGraphic\\\" in2=\\\"effect1_dropShadow\\\" result=\\\"shape\\\"\\\/>\\n<\\\/filter>\\n<filter id=\\\"filter45_d\\\" x=\\\"189.806\\\" y=\\\"72.2227\\\" width=\\\"16.824\\\" height=\\\"11.6498\\\" filterUnits=\\\"userSpaceOnUse\\\" color-interpolation-filters=\\\"sRGB\\\">\\n<feFlood flood-opacity=\\\"0\\\" result=\\\"BackgroundImageFix\\\"\\\/>\\n<feColorMatrix in=\\\"SourceAlpha\\\" type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\\\"\\\/>\\n<feOffset dy=\\\"4\\\"\\\/>\\n<feGaussianBlur stdDeviation=\\\"2\\\"\\\/>\\n<feColorMatrix type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in2=\\\"BackgroundImageFix\\\" result=\\\"effect1_dropShadow\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in=\\\"SourceGraphic\\\" in2=\\\"effect1_dropShadow\\\" result=\\\"shape\\\"\\\/>\\n<\\\/filter>\\n<filter id=\\\"filter46_d\\\" x=\\\"150.426\\\" y=\\\"73.5122\\\" width=\\\"16.9272\\\" height=\\\"11.9294\\\" filterUnits=\\\"userSpaceOnUse\\\" color-interpolation-filters=\\\"sRGB\\\">\\n<feFlood flood-opacity=\\\"0\\\" result=\\\"BackgroundImageFix\\\"\\\/>\\n<feColorMatrix in=\\\"SourceAlpha\\\" type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\\\"\\\/>\\n<feOffset dy=\\\"4\\\"\\\/>\\n<feGaussianBlur stdDeviation=\\\"2\\\"\\\/>\\n<feColorMatrix type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in2=\\\"BackgroundImageFix\\\" result=\\\"effect1_dropShadow\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in=\\\"SourceGraphic\\\" in2=\\\"effect1_dropShadow\\\" result=\\\"shape\\\"\\\/>\\n<\\\/filter>\\n<filter id=\\\"filter47_d\\\" x=\\\"164\\\" y=\\\"104.69\\\" width=\\\"27.23\\\" height=\\\"17.0703\\\" filterUnits=\\\"userSpaceOnUse\\\" color-interpolation-filters=\\\"sRGB\\\">\\n<feFlood flood-opacity=\\\"0\\\" result=\\\"BackgroundImageFix\\\"\\\/>\\n<feColorMatrix in=\\\"SourceAlpha\\\" type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\\\"\\\/>\\n<feOffset dy=\\\"4\\\"\\\/>\\n<feGaussianBlur stdDeviation=\\\"2\\\"\\\/>\\n<feColorMatrix type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in2=\\\"BackgroundImageFix\\\" result=\\\"effect1_dropShadow\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in=\\\"SourceGraphic\\\" in2=\\\"effect1_dropShadow\\\" result=\\\"shape\\\"\\\/>\\n<\\\/filter>\\n<filter id=\\\"filter48_d\\\" x=\\\"166.42\\\" y=\\\"104.71\\\" width=\\\"24.81\\\" height=\\\"11.8575\\\" filterUnits=\\\"userSpaceOnUse\\\" color-interpolation-filters=\\\"sRGB\\\">\\n<feFlood flood-opacity=\\\"0\\\" result=\\\"BackgroundImageFix\\\"\\\/>\\n<feColorMatrix in=\\\"SourceAlpha\\\" type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\\\"\\\/>\\n<feOffset dy=\\\"4\\\"\\\/>\\n<feGaussianBlur stdDeviation=\\\"2\\\"\\\/>\\n<feColorMatrix type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in2=\\\"BackgroundImageFix\\\" result=\\\"effect1_dropShadow\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in=\\\"SourceGraphic\\\" in2=\\\"effect1_dropShadow\\\" result=\\\"shape\\\"\\\/>\\n<\\\/filter>\\n<filter id=\\\"filter49_d\\\" x=\\\"170.75\\\" y=\\\"110.975\\\" width=\\\"17.42\\\" height=\\\"10.8105\\\" filterUnits=\\\"userSpaceOnUse\\\" color-interpolation-filters=\\\"sRGB\\\">\\n<feFlood flood-opacity=\\\"0\\\" result=\\\"BackgroundImageFix\\\"\\\/>\\n<feColorMatrix in=\\\"SourceAlpha\\\" type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\\\"\\\/>\\n<feOffset dy=\\\"4\\\"\\\/>\\n<feGaussianBlur stdDeviation=\\\"2\\\"\\\/>\\n<feColorMatrix type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in2=\\\"BackgroundImageFix\\\" result=\\\"effect1_dropShadow\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in=\\\"SourceGraphic\\\" in2=\\\"effect1_dropShadow\\\" result=\\\"shape\\\"\\\/>\\n<\\\/filter>\\n<filter id=\\\"filter50_d\\\" x=\\\"166.867\\\" y=\\\"83.28\\\" width=\\\"14.0031\\\" height=\\\"22.909\\\" filterUnits=\\\"userSpaceOnUse\\\" color-interpolation-filters=\\\"sRGB\\\">\\n<feFlood flood-opacity=\\\"0\\\" result=\\\"BackgroundImageFix\\\"\\\/>\\n<feColorMatrix in=\\\"SourceAlpha\\\" type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\\\"\\\/>\\n<feOffset dy=\\\"4\\\"\\\/>\\n<feGaussianBlur stdDeviation=\\\"2\\\"\\\/>\\n<feColorMatrix type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in2=\\\"BackgroundImageFix\\\" result=\\\"effect1_dropShadow\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in=\\\"SourceGraphic\\\" in2=\\\"effect1_dropShadow\\\" result=\\\"shape\\\"\\\/>\\n<\\\/filter>\\n<filter id=\\\"filter51_d\\\" x=\\\"131.706\\\" y=\\\"36.9824\\\" width=\\\"93.7519\\\" height=\\\"48.7076\\\" filterUnits=\\\"userSpaceOnUse\\\" color-interpolation-filters=\\\"sRGB\\\">\\n<feFlood flood-opacity=\\\"0\\\" result=\\\"BackgroundImageFix\\\"\\\/>\\n<feColorMatrix in=\\\"SourceAlpha\\\" type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\\\"\\\/>\\n<feOffset dy=\\\"4\\\"\\\/>\\n<feGaussianBlur stdDeviation=\\\"2\\\"\\\/>\\n<feColorMatrix type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in2=\\\"BackgroundImageFix\\\" result=\\\"effect1_dropShadow\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in=\\\"SourceGraphic\\\" in2=\\\"effect1_dropShadow\\\" result=\\\"shape\\\"\\\/>\\n<\\\/filter>\\n<filter id=\\\"filter52_d\\\" x=\\\"170.183\\\" y=\\\"46.9612\\\" width=\\\"15.7859\\\" height=\\\"23.4483\\\" filterUnits=\\\"userSpaceOnUse\\\" color-interpolation-filters=\\\"sRGB\\\">\\n<feFlood flood-opacity=\\\"0\\\" result=\\\"BackgroundImageFix\\\"\\\/>\\n<feColorMatrix in=\\\"SourceAlpha\\\" type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\\\"\\\/>\\n<feOffset dy=\\\"4\\\"\\\/>\\n<feGaussianBlur stdDeviation=\\\"2\\\"\\\/>\\n<feColorMatrix type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in2=\\\"BackgroundImageFix\\\" result=\\\"effect1_dropShadow\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in=\\\"SourceGraphic\\\" in2=\\\"effect1_dropShadow\\\" result=\\\"shape\\\"\\\/>\\n<\\\/filter>\\n<filter id=\\\"filter53_d\\\" x=\\\"150.408\\\" y=\\\"44.9644\\\" width=\\\"24.5196\\\" height=\\\"29.5072\\\" filterUnits=\\\"userSpaceOnUse\\\" color-interpolation-filters=\\\"sRGB\\\">\\n<feFlood flood-opacity=\\\"0\\\" result=\\\"BackgroundImageFix\\\"\\\/>\\n<feColorMatrix in=\\\"SourceAlpha\\\" type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\\\"\\\/>\\n<feOffset dy=\\\"4\\\"\\\/>\\n<feGaussianBlur stdDeviation=\\\"2\\\"\\\/>\\n<feColorMatrix type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in2=\\\"BackgroundImageFix\\\" result=\\\"effect1_dropShadow\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in=\\\"SourceGraphic\\\" in2=\\\"effect1_dropShadow\\\" result=\\\"shape\\\"\\\/>\\n<\\\/filter>\\n<filter id=\\\"filter54_d\\\" x=\\\"152.034\\\" y=\\\"51.655\\\" width=\\\"13.7728\\\" height=\\\"15.819\\\" filterUnits=\\\"userSpaceOnUse\\\" color-interpolation-filters=\\\"sRGB\\\">\\n<feFlood flood-opacity=\\\"0\\\" result=\\\"BackgroundImageFix\\\"\\\/>\\n<feColorMatrix in=\\\"SourceAlpha\\\" type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\\\"\\\/>\\n<feOffset dy=\\\"4\\\"\\\/>\\n<feGaussianBlur stdDeviation=\\\"2\\\"\\\/>\\n<feColorMatrix type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in2=\\\"BackgroundImageFix\\\" result=\\\"effect1_dropShadow\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in=\\\"SourceGraphic\\\" in2=\\\"effect1_dropShadow\\\" result=\\\"shape\\\"\\\/>\\n<\\\/filter>\\n<filter id=\\\"filter55_d\\\" x=\\\"198.788\\\" y=\\\"37.7571\\\" width=\\\"12.8122\\\" height=\\\"31.3963\\\" filterUnits=\\\"userSpaceOnUse\\\" color-interpolation-filters=\\\"sRGB\\\">\\n<feFlood flood-opacity=\\\"0\\\" result=\\\"BackgroundImageFix\\\"\\\/>\\n<feColorMatrix in=\\\"SourceAlpha\\\" type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\\\"\\\/>\\n<feOffset dy=\\\"4\\\"\\\/>\\n<feGaussianBlur stdDeviation=\\\"2\\\"\\\/>\\n<feColorMatrix type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in2=\\\"BackgroundImageFix\\\" result=\\\"effect1_dropShadow\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in=\\\"SourceGraphic\\\" in2=\\\"effect1_dropShadow\\\" result=\\\"shape\\\"\\\/>\\n<\\\/filter>\\n<filter id=\\\"filter56_d\\\" x=\\\"195.555\\\" y=\\\"46.4402\\\" width=\\\"11.2285\\\" height=\\\"19.7596\\\" filterUnits=\\\"userSpaceOnUse\\\" color-interpolation-filters=\\\"sRGB\\\">\\n<feFlood flood-opacity=\\\"0\\\" result=\\\"BackgroundImageFix\\\"\\\/>\\n<feColorMatrix in=\\\"SourceAlpha\\\" type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\\\"\\\/>\\n<feOffset dy=\\\"4\\\"\\\/>\\n<feGaussianBlur stdDeviation=\\\"2\\\"\\\/>\\n<feColorMatrix type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in2=\\\"BackgroundImageFix\\\" result=\\\"effect1_dropShadow\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in=\\\"SourceGraphic\\\" in2=\\\"effect1_dropShadow\\\" result=\\\"shape\\\"\\\/>\\n<\\\/filter>\\n<filter id=\\\"filter57_d\\\" x=\\\"150.217\\\" y=\\\"24.2671\\\" width=\\\"28.2344\\\" height=\\\"17.8443\\\" filterUnits=\\\"userSpaceOnUse\\\" color-interpolation-filters=\\\"sRGB\\\">\\n<feFlood flood-opacity=\\\"0\\\" result=\\\"BackgroundImageFix\\\"\\\/>\\n<feColorMatrix in=\\\"SourceAlpha\\\" type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\\\"\\\/>\\n<feOffset dy=\\\"4\\\"\\\/>\\n<feGaussianBlur stdDeviation=\\\"2\\\"\\\/>\\n<feColorMatrix type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in2=\\\"BackgroundImageFix\\\" result=\\\"effect1_dropShadow\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in=\\\"SourceGraphic\\\" in2=\\\"effect1_dropShadow\\\" result=\\\"shape\\\"\\\/>\\n<\\\/filter>\\n<filter id=\\\"filter58_d\\\" x=\\\"213.404\\\" y=\\\"47.311\\\" width=\\\"11.0345\\\" height=\\\"28.5393\\\" filterUnits=\\\"userSpaceOnUse\\\" color-interpolation-filters=\\\"sRGB\\\">\\n<feFlood flood-opacity=\\\"0\\\" result=\\\"BackgroundImageFix\\\"\\\/>\\n<feColorMatrix in=\\\"SourceAlpha\\\" type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\\\"\\\/>\\n<feOffset dy=\\\"4\\\"\\\/>\\n<feGaussianBlur stdDeviation=\\\"2\\\"\\\/>\\n<feColorMatrix type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in2=\\\"BackgroundImageFix\\\" result=\\\"effect1_dropShadow\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in=\\\"SourceGraphic\\\" in2=\\\"effect1_dropShadow\\\" result=\\\"shape\\\"\\\/>\\n<\\\/filter>\\n<filter id=\\\"filter59_d\\\" x=\\\"134.309\\\" y=\\\"46.9958\\\" width=\\\"18.0024\\\" height=\\\"35.5647\\\" filterUnits=\\\"userSpaceOnUse\\\" color-interpolation-filters=\\\"sRGB\\\">\\n<feFlood flood-opacity=\\\"0\\\" result=\\\"BackgroundImageFix\\\"\\\/>\\n<feColorMatrix in=\\\"SourceAlpha\\\" type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\\\"\\\/>\\n<feOffset dy=\\\"4\\\"\\\/>\\n<feGaussianBlur stdDeviation=\\\"2\\\"\\\/>\\n<feColorMatrix type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in2=\\\"BackgroundImageFix\\\" result=\\\"effect1_dropShadow\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in=\\\"SourceGraphic\\\" in2=\\\"effect1_dropShadow\\\" result=\\\"shape\\\"\\\/>\\n<\\\/filter>\\n<filter id=\\\"filter60_d\\\" x=\\\"64.9144\\\" y=\\\"129.476\\\" width=\\\"24.4945\\\" height=\\\"27.3194\\\" filterUnits=\\\"userSpaceOnUse\\\" color-interpolation-filters=\\\"sRGB\\\">\\n<feFlood flood-opacity=\\\"0\\\" result=\\\"BackgroundImageFix\\\"\\\/>\\n<feColorMatrix in=\\\"SourceAlpha\\\" type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\\\"\\\/>\\n<feOffset dy=\\\"4\\\"\\\/>\\n<feGaussianBlur stdDeviation=\\\"2\\\"\\\/>\\n<feColorMatrix type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in2=\\\"BackgroundImageFix\\\" result=\\\"effect1_dropShadow\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in=\\\"SourceGraphic\\\" in2=\\\"effect1_dropShadow\\\" result=\\\"shape\\\"\\\/>\\n<\\\/filter>\\n<filter id=\\\"filter61_d\\\" x=\\\"62.2369\\\" y=\\\"126.19\\\" width=\\\"27.5666\\\" height=\\\"26.8281\\\" filterUnits=\\\"userSpaceOnUse\\\" color-interpolation-filters=\\\"sRGB\\\">\\n<feFlood flood-opacity=\\\"0\\\" result=\\\"BackgroundImageFix\\\"\\\/>\\n<feColorMatrix in=\\\"SourceAlpha\\\" type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\\\"\\\/>\\n<feOffset dy=\\\"4\\\"\\\/>\\n<feGaussianBlur stdDeviation=\\\"2\\\"\\\/>\\n<feColorMatrix type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in2=\\\"BackgroundImageFix\\\" result=\\\"effect1_dropShadow\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in=\\\"SourceGraphic\\\" in2=\\\"effect1_dropShadow\\\" result=\\\"shape\\\"\\\/>\\n<\\\/filter>\\n<filter id=\\\"filter62_d\\\" x=\\\"165.547\\\" y=\\\"129.942\\\" width=\\\"31.1408\\\" height=\\\"24.5782\\\" filterUnits=\\\"userSpaceOnUse\\\" color-interpolation-filters=\\\"sRGB\\\">\\n<feFlood flood-opacity=\\\"0\\\" result=\\\"BackgroundImageFix\\\"\\\/>\\n<feColorMatrix in=\\\"SourceAlpha\\\" type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\\\"\\\/>\\n<feOffset dy=\\\"4\\\"\\\/>\\n<feGaussianBlur stdDeviation=\\\"2\\\"\\\/>\\n<feColorMatrix type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in2=\\\"BackgroundImageFix\\\" result=\\\"effect1_dropShadow\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in=\\\"SourceGraphic\\\" in2=\\\"effect1_dropShadow\\\" result=\\\"shape\\\"\\\/>\\n<\\\/filter>\\n<filter id=\\\"filter63_d\\\" x=\\\"124.525\\\" y=\\\"153.545\\\" width=\\\"20.6714\\\" height=\\\"37.6665\\\" filterUnits=\\\"userSpaceOnUse\\\" color-interpolation-filters=\\\"sRGB\\\">\\n<feFlood flood-opacity=\\\"0\\\" result=\\\"BackgroundImageFix\\\"\\\/>\\n<feColorMatrix in=\\\"SourceAlpha\\\" type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\\\"\\\/>\\n<feOffset dy=\\\"4\\\"\\\/>\\n<feGaussianBlur stdDeviation=\\\"2\\\"\\\/>\\n<feColorMatrix type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in2=\\\"BackgroundImageFix\\\" result=\\\"effect1_dropShadow\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in=\\\"SourceGraphic\\\" in2=\\\"effect1_dropShadow\\\" result=\\\"shape\\\"\\\/>\\n<\\\/filter>\\n<filter id=\\\"filter64_d\\\" x=\\\"222.625\\\" y=\\\"140.613\\\" width=\\\"16.6844\\\" height=\\\"41.1211\\\" filterUnits=\\\"userSpaceOnUse\\\" color-interpolation-filters=\\\"sRGB\\\">\\n<feFlood flood-opacity=\\\"0\\\" result=\\\"BackgroundImageFix\\\"\\\/>\\n<feColorMatrix in=\\\"SourceAlpha\\\" type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\\\"\\\/>\\n<feOffset dy=\\\"4\\\"\\\/>\\n<feGaussianBlur stdDeviation=\\\"2\\\"\\\/>\\n<feColorMatrix type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in2=\\\"BackgroundImageFix\\\" result=\\\"effect1_dropShadow\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in=\\\"SourceGraphic\\\" in2=\\\"effect1_dropShadow\\\" result=\\\"shape\\\"\\\/>\\n<\\\/filter>\\n<filter id=\\\"filter65_d\\\" x=\\\"160.702\\\" y=\\\"271.745\\\" width=\\\"16.7985\\\" height=\\\"89.2141\\\" filterUnits=\\\"userSpaceOnUse\\\" color-interpolation-filters=\\\"sRGB\\\">\\n<feFlood flood-opacity=\\\"0\\\" result=\\\"BackgroundImageFix\\\"\\\/>\\n<feColorMatrix in=\\\"SourceAlpha\\\" type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\\\"\\\/>\\n<feOffset dy=\\\"4\\\"\\\/>\\n<feGaussianBlur stdDeviation=\\\"2\\\"\\\/>\\n<feColorMatrix type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in2=\\\"BackgroundImageFix\\\" result=\\\"effect1_dropShadow\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in=\\\"SourceGraphic\\\" in2=\\\"effect1_dropShadow\\\" result=\\\"shape\\\"\\\/>\\n<\\\/filter>\\n<filter id=\\\"filter66_d\\\" x=\\\"208.17\\\" y=\\\"266.501\\\" width=\\\"11.8219\\\" height=\\\"91.8\\\" filterUnits=\\\"userSpaceOnUse\\\" color-interpolation-filters=\\\"sRGB\\\">\\n<feFlood flood-opacity=\\\"0\\\" result=\\\"BackgroundImageFix\\\"\\\/>\\n<feColorMatrix in=\\\"SourceAlpha\\\" type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\\\"\\\/>\\n<feOffset dy=\\\"4\\\"\\\/>\\n<feGaussianBlur stdDeviation=\\\"2\\\"\\\/>\\n<feColorMatrix type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in2=\\\"BackgroundImageFix\\\" result=\\\"effect1_dropShadow\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in=\\\"SourceGraphic\\\" in2=\\\"effect1_dropShadow\\\" result=\\\"shape\\\"\\\/>\\n<\\\/filter>\\n<filter id=\\\"filter67_d\\\" x=\\\"280.13\\\" y=\\\"37.7\\\" width=\\\"75.9\\\" height=\\\"100.1\\\" filterUnits=\\\"userSpaceOnUse\\\" color-interpolation-filters=\\\"sRGB\\\">\\n<feFlood flood-opacity=\\\"0\\\" result=\\\"BackgroundImageFix\\\"\\\/>\\n<feColorMatrix in=\\\"SourceAlpha\\\" type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\\\"\\\/>\\n<feOffset dy=\\\"4\\\"\\\/>\\n<feGaussianBlur stdDeviation=\\\"2\\\"\\\/>\\n<feColorMatrix type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in2=\\\"BackgroundImageFix\\\" result=\\\"effect1_dropShadow\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in=\\\"SourceGraphic\\\" in2=\\\"effect1_dropShadow\\\" result=\\\"shape\\\"\\\/>\\n<\\\/filter>\\n<filter id=\\\"filter68_d\\\" x=\\\"60.7457\\\" y=\\\"53.179\\\" width=\\\"19.3866\\\" height=\\\"108.497\\\" filterUnits=\\\"userSpaceOnUse\\\" color-interpolation-filters=\\\"sRGB\\\">\\n<feFlood flood-opacity=\\\"0\\\" result=\\\"BackgroundImageFix\\\"\\\/>\\n<feColorMatrix in=\\\"SourceAlpha\\\" type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\\\"\\\/>\\n<feOffset dy=\\\"4\\\"\\\/>\\n<feGaussianBlur stdDeviation=\\\"2\\\"\\\/>\\n<feColorMatrix type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in2=\\\"BackgroundImageFix\\\" result=\\\"effect1_dropShadow\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in=\\\"SourceGraphic\\\" in2=\\\"effect1_dropShadow\\\" result=\\\"shape\\\"\\\/>\\n<\\\/filter>\\n<filter id=\\\"filter69_d\\\" x=\\\"19.8799\\\" y=\\\"3.22998\\\" width=\\\"84.9001\\\" height=\\\"84.9501\\\" filterUnits=\\\"userSpaceOnUse\\\" color-interpolation-filters=\\\"sRGB\\\">\\n<feFlood flood-opacity=\\\"0\\\" result=\\\"BackgroundImageFix\\\"\\\/>\\n<feColorMatrix in=\\\"SourceAlpha\\\" type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\\\"\\\/>\\n<feOffset dy=\\\"4\\\"\\\/>\\n<feGaussianBlur stdDeviation=\\\"2\\\"\\\/>\\n<feColorMatrix type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in2=\\\"BackgroundImageFix\\\" result=\\\"effect1_dropShadow\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in=\\\"SourceGraphic\\\" in2=\\\"effect1_dropShadow\\\" result=\\\"shape\\\"\\\/>\\n<\\\/filter>\\n<filter id=\\\"filter70_d\\\" x=\\\"27.89\\\" y=\\\"11.29\\\" width=\\\"68.88\\\" height=\\\"68.88\\\" filterUnits=\\\"userSpaceOnUse\\\" color-interpolation-filters=\\\"sRGB\\\">\\n<feFlood flood-opacity=\\\"0\\\" result=\\\"BackgroundImageFix\\\"\\\/>\\n<feColorMatrix in=\\\"SourceAlpha\\\" type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\\\"\\\/>\\n<feOffset dy=\\\"4\\\"\\\/>\\n<feGaussianBlur stdDeviation=\\\"2\\\"\\\/>\\n<feColorMatrix type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in2=\\\"BackgroundImageFix\\\" result=\\\"effect1_dropShadow\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in=\\\"SourceGraphic\\\" in2=\\\"effect1_dropShadow\\\" result=\\\"shape\\\"\\\/>\\n<\\\/filter>\\n<filter id=\\\"filter71_d\\\" x=\\\"30.9513\\\" y=\\\"15.2754\\\" width=\\\"28.1987\\\" height=\\\"42.5429\\\" filterUnits=\\\"userSpaceOnUse\\\" color-interpolation-filters=\\\"sRGB\\\">\\n<feFlood flood-opacity=\\\"0\\\" result=\\\"BackgroundImageFix\\\"\\\/>\\n<feColorMatrix in=\\\"SourceAlpha\\\" type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\\\"\\\/>\\n<feOffset dy=\\\"4\\\"\\\/>\\n<feGaussianBlur stdDeviation=\\\"2\\\"\\\/>\\n<feColorMatrix type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in2=\\\"BackgroundImageFix\\\" result=\\\"effect1_dropShadow\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in=\\\"SourceGraphic\\\" in2=\\\"effect1_dropShadow\\\" result=\\\"shape\\\"\\\/>\\n<\\\/filter>\\n<filter id=\\\"filter72_d\\\" x=\\\"40.6333\\\" y=\\\"42.2886\\\" width=\\\"12.3667\\\" height=\\\"13.3226\\\" filterUnits=\\\"userSpaceOnUse\\\" color-interpolation-filters=\\\"sRGB\\\">\\n<feFlood flood-opacity=\\\"0\\\" result=\\\"BackgroundImageFix\\\"\\\/>\\n<feColorMatrix in=\\\"SourceAlpha\\\" type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\\\"\\\/>\\n<feOffset dy=\\\"4\\\"\\\/>\\n<feGaussianBlur stdDeviation=\\\"2\\\"\\\/>\\n<feColorMatrix type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in2=\\\"BackgroundImageFix\\\" result=\\\"effect1_dropShadow\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in=\\\"SourceGraphic\\\" in2=\\\"effect1_dropShadow\\\" result=\\\"shape\\\"\\\/>\\n<\\\/filter>\\n<filter id=\\\"filter73_d\\\" x=\\\"64.7639\\\" y=\\\"57.3799\\\" width=\\\"26.3461\\\" height=\\\"19.99\\\" filterUnits=\\\"userSpaceOnUse\\\" color-interpolation-filters=\\\"sRGB\\\">\\n<feFlood flood-opacity=\\\"0\\\" result=\\\"BackgroundImageFix\\\"\\\/>\\n<feColorMatrix in=\\\"SourceAlpha\\\" type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\\\"\\\/>\\n<feOffset dy=\\\"4\\\"\\\/>\\n<feGaussianBlur stdDeviation=\\\"2\\\"\\\/>\\n<feColorMatrix type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in2=\\\"BackgroundImageFix\\\" result=\\\"effect1_dropShadow\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in=\\\"SourceGraphic\\\" in2=\\\"effect1_dropShadow\\\" result=\\\"shape\\\"\\\/>\\n<\\\/filter>\\n<filter id=\\\"filter74_d\\\" x=\\\"83.23\\\" y=\\\"57.0801\\\" width=\\\"8.92\\\" height=\\\"9.11\\\" filterUnits=\\\"userSpaceOnUse\\\" color-interpolation-filters=\\\"sRGB\\\">\\n<feFlood flood-opacity=\\\"0\\\" result=\\\"BackgroundImageFix\\\"\\\/>\\n<feColorMatrix in=\\\"SourceAlpha\\\" type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\\\"\\\/>\\n<feOffset dy=\\\"4\\\"\\\/>\\n<feGaussianBlur stdDeviation=\\\"2\\\"\\\/>\\n<feColorMatrix type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in2=\\\"BackgroundImageFix\\\" result=\\\"effect1_dropShadow\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in=\\\"SourceGraphic\\\" in2=\\\"effect1_dropShadow\\\" result=\\\"shape\\\"\\\/>\\n<\\\/filter>\\n<filter id=\\\"filter75_d\\\" x=\\\"82.5112\\\" y=\\\"53.7585\\\" width=\\\"9.84369\\\" height=\\\"12.4216\\\" filterUnits=\\\"userSpaceOnUse\\\" color-interpolation-filters=\\\"sRGB\\\">\\n<feFlood flood-opacity=\\\"0\\\" result=\\\"BackgroundImageFix\\\"\\\/>\\n<feColorMatrix in=\\\"SourceAlpha\\\" type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\\\"\\\/>\\n<feOffset dy=\\\"4\\\"\\\/>\\n<feGaussianBlur stdDeviation=\\\"2\\\"\\\/>\\n<feColorMatrix type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in2=\\\"BackgroundImageFix\\\" result=\\\"effect1_dropShadow\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in=\\\"SourceGraphic\\\" in2=\\\"effect1_dropShadow\\\" result=\\\"shape\\\"\\\/>\\n<\\\/filter>\\n<filter id=\\\"filter76_d\\\" x=\\\"75.5626\\\" y=\\\"48.8572\\\" width=\\\"13.7484\\\" height=\\\"13.4509\\\" filterUnits=\\\"userSpaceOnUse\\\" color-interpolation-filters=\\\"sRGB\\\">\\n<feFlood flood-opacity=\\\"0\\\" result=\\\"BackgroundImageFix\\\"\\\/>\\n<feColorMatrix in=\\\"SourceAlpha\\\" type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\\\"\\\/>\\n<feOffset dy=\\\"4\\\"\\\/>\\n<feGaussianBlur stdDeviation=\\\"2\\\"\\\/>\\n<feColorMatrix type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in2=\\\"BackgroundImageFix\\\" result=\\\"effect1_dropShadow\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in=\\\"SourceGraphic\\\" in2=\\\"effect1_dropShadow\\\" result=\\\"shape\\\"\\\/>\\n<\\\/filter>\\n<filter id=\\\"filter77_d\\\" x=\\\"70.23\\\" y=\\\"46.3203\\\" width=\\\"10.2306\\\" height=\\\"15.1617\\\" filterUnits=\\\"userSpaceOnUse\\\" color-interpolation-filters=\\\"sRGB\\\">\\n<feFlood flood-opacity=\\\"0\\\" result=\\\"BackgroundImageFix\\\"\\\/>\\n<feColorMatrix in=\\\"SourceAlpha\\\" type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\\\"\\\/>\\n<feOffset dy=\\\"4\\\"\\\/>\\n<feGaussianBlur stdDeviation=\\\"2\\\"\\\/>\\n<feColorMatrix type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in2=\\\"BackgroundImageFix\\\" result=\\\"effect1_dropShadow\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in=\\\"SourceGraphic\\\" in2=\\\"effect1_dropShadow\\\" result=\\\"shape\\\"\\\/>\\n<\\\/filter>\\n<filter id=\\\"filter78_d\\\" x=\\\"82.3654\\\" y=\\\"43.0547\\\" width=\\\"10.1984\\\" height=\\\"14.7052\\\" filterUnits=\\\"userSpaceOnUse\\\" color-interpolation-filters=\\\"sRGB\\\">\\n<feFlood flood-opacity=\\\"0\\\" result=\\\"BackgroundImageFix\\\"\\\/>\\n<feColorMatrix in=\\\"SourceAlpha\\\" type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\\\"\\\/>\\n<feOffset dy=\\\"4\\\"\\\/>\\n<feGaussianBlur stdDeviation=\\\"2\\\"\\\/>\\n<feColorMatrix type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in2=\\\"BackgroundImageFix\\\" result=\\\"effect1_dropShadow\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in=\\\"SourceGraphic\\\" in2=\\\"effect1_dropShadow\\\" result=\\\"shape\\\"\\\/>\\n<\\\/filter>\\n<filter id=\\\"filter79_d\\\" x=\\\"48.8217\\\" y=\\\"19.7285\\\" width=\\\"16.6457\\\" height=\\\"17.6795\\\" filterUnits=\\\"userSpaceOnUse\\\" color-interpolation-filters=\\\"sRGB\\\">\\n<feFlood flood-opacity=\\\"0\\\" result=\\\"BackgroundImageFix\\\"\\\/>\\n<feColorMatrix in=\\\"SourceAlpha\\\" type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\\\"\\\/>\\n<feOffset dy=\\\"4\\\"\\\/>\\n<feGaussianBlur stdDeviation=\\\"2\\\"\\\/>\\n<feColorMatrix type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in2=\\\"BackgroundImageFix\\\" result=\\\"effect1_dropShadow\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in=\\\"SourceGraphic\\\" in2=\\\"effect1_dropShadow\\\" result=\\\"shape\\\"\\\/>\\n<\\\/filter>\\n<filter id=\\\"filter80_d\\\" x=\\\"51.4263\\\" y=\\\"14.5078\\\" width=\\\"42.9937\\\" height=\\\"40.9389\\\" filterUnits=\\\"userSpaceOnUse\\\" color-interpolation-filters=\\\"sRGB\\\">\\n<feFlood flood-opacity=\\\"0\\\" result=\\\"BackgroundImageFix\\\"\\\/>\\n<feColorMatrix in=\\\"SourceAlpha\\\" type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\\\"\\\/>\\n<feOffset dy=\\\"4\\\"\\\/>\\n<feGaussianBlur stdDeviation=\\\"2\\\"\\\/>\\n<feColorMatrix type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in2=\\\"BackgroundImageFix\\\" result=\\\"effect1_dropShadow\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in=\\\"SourceGraphic\\\" in2=\\\"effect1_dropShadow\\\" result=\\\"shape\\\"\\\/>\\n<\\\/filter>\\n<filter id=\\\"filter81_d\\\" x=\\\"50.98\\\" y=\\\"11.3\\\" width=\\\"15.83\\\" height=\\\"12.7809\\\" filterUnits=\\\"userSpaceOnUse\\\" color-interpolation-filters=\\\"sRGB\\\">\\n<feFlood flood-opacity=\\\"0\\\" result=\\\"BackgroundImageFix\\\"\\\/>\\n<feColorMatrix in=\\\"SourceAlpha\\\" type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\\\"\\\/>\\n<feOffset dy=\\\"4\\\"\\\/>\\n<feGaussianBlur stdDeviation=\\\"2\\\"\\\/>\\n<feColorMatrix type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in2=\\\"BackgroundImageFix\\\" result=\\\"effect1_dropShadow\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in=\\\"SourceGraphic\\\" in2=\\\"effect1_dropShadow\\\" result=\\\"shape\\\"\\\/>\\n<\\\/filter>\\n<filter id=\\\"filter82_d\\\" x=\\\"17.36\\\" y=\\\"42.4299\\\" width=\\\"58.9\\\" height=\\\"45.98\\\" filterUnits=\\\"userSpaceOnUse\\\" color-interpolation-filters=\\\"sRGB\\\">\\n<feFlood flood-opacity=\\\"0\\\" result=\\\"BackgroundImageFix\\\"\\\/>\\n<feColorMatrix in=\\\"SourceAlpha\\\" type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\\\"\\\/>\\n<feOffset dy=\\\"4\\\"\\\/>\\n<feGaussianBlur stdDeviation=\\\"2\\\"\\\/>\\n<feColorMatrix type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in2=\\\"BackgroundImageFix\\\" result=\\\"effect1_dropShadow\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in=\\\"SourceGraphic\\\" in2=\\\"effect1_dropShadow\\\" result=\\\"shape\\\"\\\/>\\n<\\\/filter>\\n<filter id=\\\"filter83_d\\\" x=\\\"34.7999\\\" y=\\\"49.25\\\" width=\\\"27.49\\\" height=\\\"26.21\\\" filterUnits=\\\"userSpaceOnUse\\\" color-interpolation-filters=\\\"sRGB\\\">\\n<feFlood flood-opacity=\\\"0\\\" result=\\\"BackgroundImageFix\\\"\\\/>\\n<feColorMatrix in=\\\"SourceAlpha\\\" type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\\\"\\\/>\\n<feOffset dy=\\\"4\\\"\\\/>\\n<feGaussianBlur stdDeviation=\\\"2\\\"\\\/>\\n<feColorMatrix type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in2=\\\"BackgroundImageFix\\\" result=\\\"effect1_dropShadow\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in=\\\"SourceGraphic\\\" in2=\\\"effect1_dropShadow\\\" result=\\\"shape\\\"\\\/>\\n<\\\/filter>\\n<filter id=\\\"filter84_d\\\" x=\\\"59\\\" y=\\\"0\\\" width=\\\"52.65\\\" height=\\\"41.32\\\" filterUnits=\\\"userSpaceOnUse\\\" color-interpolation-filters=\\\"sRGB\\\">\\n<feFlood flood-opacity=\\\"0\\\" result=\\\"BackgroundImageFix\\\"\\\/>\\n<feColorMatrix in=\\\"SourceAlpha\\\" type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\\\"\\\/>\\n<feOffset dy=\\\"4\\\"\\\/>\\n<feGaussianBlur stdDeviation=\\\"2\\\"\\\/>\\n<feColorMatrix type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in2=\\\"BackgroundImageFix\\\" result=\\\"effect1_dropShadow\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in=\\\"SourceGraphic\\\" in2=\\\"effect1_dropShadow\\\" result=\\\"shape\\\"\\\/>\\n<\\\/filter>\\n<filter id=\\\"filter85_d\\\" x=\\\"73\\\" y=\\\"7.93994\\\" width=\\\"19.84\\\" height=\\\"21.82\\\" filterUnits=\\\"userSpaceOnUse\\\" color-interpolation-filters=\\\"sRGB\\\">\\n<feFlood flood-opacity=\\\"0\\\" result=\\\"BackgroundImageFix\\\"\\\/>\\n<feColorMatrix in=\\\"SourceAlpha\\\" type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\\\"\\\/>\\n<feOffset dy=\\\"4\\\"\\\/>\\n<feGaussianBlur stdDeviation=\\\"2\\\"\\\/>\\n<feColorMatrix type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in2=\\\"BackgroundImageFix\\\" result=\\\"effect1_dropShadow\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in=\\\"SourceGraphic\\\" in2=\\\"effect1_dropShadow\\\" result=\\\"shape\\\"\\\/>\\n<\\\/filter>\\n<filter id=\\\"filter86_d\\\" x=\\\"59.6896\\\" y=\\\"130.448\\\" width=\\\"16.1616\\\" height=\\\"14.7819\\\" filterUnits=\\\"userSpaceOnUse\\\" color-interpolation-filters=\\\"sRGB\\\">\\n<feFlood flood-opacity=\\\"0\\\" result=\\\"BackgroundImageFix\\\"\\\/>\\n<feColorMatrix in=\\\"SourceAlpha\\\" type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\\\"\\\/>\\n<feOffset dy=\\\"4\\\"\\\/>\\n<feGaussianBlur stdDeviation=\\\"2\\\"\\\/>\\n<feColorMatrix type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in2=\\\"BackgroundImageFix\\\" result=\\\"effect1_dropShadow\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in=\\\"SourceGraphic\\\" in2=\\\"effect1_dropShadow\\\" result=\\\"shape\\\"\\\/>\\n<\\\/filter>\\n<filter id=\\\"filter87_d\\\" x=\\\"60.2981\\\" y=\\\"135.144\\\" width=\\\"17.7435\\\" height=\\\"14.4745\\\" filterUnits=\\\"userSpaceOnUse\\\" color-interpolation-filters=\\\"sRGB\\\">\\n<feFlood flood-opacity=\\\"0\\\" result=\\\"BackgroundImageFix\\\"\\\/>\\n<feColorMatrix in=\\\"SourceAlpha\\\" type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\\\"\\\/>\\n<feOffset dy=\\\"4\\\"\\\/>\\n<feGaussianBlur stdDeviation=\\\"2\\\"\\\/>\\n<feColorMatrix type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in2=\\\"BackgroundImageFix\\\" result=\\\"effect1_dropShadow\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in=\\\"SourceGraphic\\\" in2=\\\"effect1_dropShadow\\\" result=\\\"shape\\\"\\\/>\\n<\\\/filter>\\n<filter id=\\\"filter88_d\\\" x=\\\"60.9845\\\" y=\\\"139.765\\\" width=\\\"16.9873\\\" height=\\\"13.7985\\\" filterUnits=\\\"userSpaceOnUse\\\" color-interpolation-filters=\\\"sRGB\\\">\\n<feFlood flood-opacity=\\\"0\\\" result=\\\"BackgroundImageFix\\\"\\\/>\\n<feColorMatrix in=\\\"SourceAlpha\\\" type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\\\"\\\/>\\n<feOffset dy=\\\"4\\\"\\\/>\\n<feGaussianBlur stdDeviation=\\\"2\\\"\\\/>\\n<feColorMatrix type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in2=\\\"BackgroundImageFix\\\" result=\\\"effect1_dropShadow\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in=\\\"SourceGraphic\\\" in2=\\\"effect1_dropShadow\\\" result=\\\"shape\\\"\\\/>\\n<\\\/filter>\\n<filter id=\\\"filter89_d\\\" x=\\\"62.2917\\\" y=\\\"144.282\\\" width=\\\"14.3418\\\" height=\\\"12.4583\\\" filterUnits=\\\"userSpaceOnUse\\\" color-interpolation-filters=\\\"sRGB\\\">\\n<feFlood flood-opacity=\\\"0\\\" result=\\\"BackgroundImageFix\\\"\\\/>\\n<feColorMatrix in=\\\"SourceAlpha\\\" type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\\\"\\\/>\\n<feOffset dy=\\\"4\\\"\\\/>\\n<feGaussianBlur stdDeviation=\\\"2\\\"\\\/>\\n<feColorMatrix type=\\\"matrix\\\" values=\\\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0.25 0\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in2=\\\"BackgroundImageFix\\\" result=\\\"effect1_dropShadow\\\"\\\/>\\n<feBlend mode=\\\"normal\\\" in=\\\"SourceGraphic\\\" in2=\\\"effect1_dropShadow\\\" result=\\\"shape\\\"\\\/>\\n<\\\/filter>\\n<\\\/defs>\\n<\\\/svg>\\n\",\"id\":\"boy2\",\"class\":\"uk-position-bottom\",\"css\":\"@media only screen and (max-width:1023px) {.el-element{width:85vw;\\n   left:7.5vw !important;}}\"}}]},{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"media_overlay_gradient\":\"\",\"width_medium\":\"1-5\",\"width_small\":\"1-3\"},\"children\":[{\"type\":\"image\",\"props\":{\"margin\":\"default\",\"image_svg_color\":\"emphasis\",\"image\":\"wp-content\\\/uploads\\\/2021\\\/05\\\/Ladder1.svg\",\"class\":\"uk-position-bottom\",\"id\":\"boy3\",\"css\":\"@media only screen and (max-width:1023px) {.el-element{display:none;}}\"}}]}]},{\"type\":\"row\",\"children\":[{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"media_overlay_gradient\":\"\"},\"children\":[{\"type\":\"text\",\"props\":{\"margin\":\"default\",\"column_breakpoint\":\"m\",\"content\":\"<a class=\\\"\\\" href=\\\"#bsec\\\" uk-scroll>\\n    <span class=\\\"arro-hero uk-icon-button\\\" uk-icon=\\\"icon: arrow-down; ratio: 3;\\\"><\\\/span><\\\/a>\",\"class\":\"uk-position-center\",\"css\":\"@media only screen and (max-width:1023px) {.el-element{display:none;}}\\n\\n\",\"id\":\"arro-boom\"}}]}]}]},{\"type\":\"section\",\"props\":{\"style\":\"default\",\"width\":\"default\",\"vertical_align\":\"middle\",\"title_position\":\"top-left\",\"title_rotation\":\"left\",\"title_breakpoint\":\"xl\",\"image_position\":\"center-center\",\"animation_delay\":\"200\",\"class\":\"gsap-sec bsec\",\"animation\":\"slide-bottom\",\"id\":\"bsec\"},\"children\":[{\"type\":\"row\",\"props\":{\"layout\":\"1-3,2-3\"},\"children\":[{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"media_overlay_gradient\":\"\",\"width_medium\":\"1-3\"},\"children\":[{\"type\":\"text\",\"props\":{\"margin\":\"default\",\"column_breakpoint\":\"m\",\"content\":\"\n\n<div><svg width=\\\"409\\\" height=\\\"409\\\" viewBox=\\\"0 0 409 409\\\" fill=\\\"none\\\" xmlns=\\\"http:\\\/\\\/www.w3.org\\\/2000\\\/svg\\\">\\n<g id=\\\"about-svg 1\\\">\\n<g id=\\\"Layer 2\\\">\\n<g id=\\\"Layer 1\\\">\\n<path id=\\\"Vector13326\\\" d=\\\"M204.5 409C317.442 409 409 317.442 409 204.5C409 91.5578 317.442 0 204.5 0C91.5578 0 0 91.5578 0 204.5C0 317.442 91.5578 409 204.5 409Z\\\" fill=\\\"#F4F4F4\\\"\\\/>\\n<path id=\\\"cog-abouts\\\" d=\\\"M112.5 298.79C114.055 298.819 115.599 299.057 117.09 299.5L120.09 296.4L126.18 300.09L124.81 304.17C125.893 305.285 126.819 306.543 127.56 307.91L131.86 307.83L133.55 314.74L129.7 316.66C129.671 318.211 129.435 319.751 129 321.24L132.09 324.24L128.4 330.32L124.3 329C123.186 330.08 121.931 331.005 120.57 331.75L120.64 336.04L113.73 337.74L111.81 333.89C110.258 333.862 108.717 333.623 107.23 333.18L104.23 336.28L98.15 332.59L99.51 328.51C98.4332 327.392 97.5116 326.134 96.77 324.77L92.47 324.85L90.78 317.94L94.63 316C94.6627 314.449 94.9015 312.908 95.34 311.42L92.25 308.42L95.93 302.34L100.01 303.7C101.13 302.625 102.388 301.704 103.75 300.96L103.67 296.66L110.58 294.97L112.5 298.81V298.79ZM110.66 308.79C109.194 309.148 107.866 309.933 106.846 311.046C105.826 312.159 105.159 313.549 104.93 315.041C104.7 316.533 104.918 318.06 105.556 319.428C106.195 320.796 107.224 321.944 108.515 322.727C109.806 323.509 111.3 323.891 112.808 323.825C114.316 323.758 115.77 323.245 116.987 322.352C118.204 321.458 119.128 320.224 119.643 318.805C120.158 317.386 120.241 315.846 119.88 314.38C119.391 312.423 118.146 310.74 116.417 309.699C114.689 308.659 112.619 308.346 110.66 308.83V308.79Z\\\" fill=\\\"#5198BF\\\"\\\/>\\n<path id=\\\"Vector13326_2\\\" d=\\\"M80.61 223.88C80.61 223.88 34.31 150.42 118.61 113.88\\\" stroke=\\\"#1A2E35\\\" stroke-width=\\\"0.43\\\" stroke-miterlimit=\\\"10\\\" stroke-dasharray=\\\"2.59 2.59\\\"\\\/>\\n<path id=\\\"Vector13326_3\\\" d=\\\"M319.78 167.46H114.65V305.36H319.78V167.46Z\\\" fill=\\\"#8CD0C4\\\"\\\/>\\n<path id=\\\"Vector13326_4\\\" d=\\\"M114.65 181H319.78\\\" stroke=\\\"#231F20\\\" stroke-miterlimit=\\\"10\\\"\\\/>\\n<path id=\\\"Vector13326_5\\\" d=\\\"M123.27 177.81C125.175 177.81 126.72 176.265 126.72 174.36C126.72 172.455 125.175 170.91 123.27 170.91C121.365 170.91 119.82 172.455 119.82 174.36C119.82 176.265 121.365 177.81 123.27 177.81Z\\\" fill=\\\"#D7ECF4\\\" stroke=\\\"#231F20\\\" stroke-miterlimit=\\\"10\\\"\\\/>\\n<path id=\\\"Vector13326_6\\\" d=\\\"M133.61 177.81C135.515 177.81 137.06 176.265 137.06 174.36C137.06 172.455 135.515 170.91 133.61 170.91C131.705 170.91 130.16 172.455 130.16 174.36C130.16 176.265 131.705 177.81 133.61 177.81Z\\\" fill=\\\"#D7ECF4\\\" stroke=\\\"#231F20\\\" stroke-miterlimit=\\\"10\\\"\\\/>\\n<path id=\\\"Vector13326_7\\\" d=\\\"M143.96 177.81C145.865 177.81 147.41 176.265 147.41 174.36C147.41 172.455 145.865 170.91 143.96 170.91C142.055 170.91 140.51 172.455 140.51 174.36C140.51 176.265 142.055 177.81 143.96 177.81Z\\\" fill=\\\"#D7ECF4\\\" stroke=\\\"#231F20\\\" stroke-miterlimit=\\\"10\\\"\\\/>\\n<g id=\\\"box-about\\\">\\n<path id=\\\"Vector13326_8\\\" d=\\\"M311.01 267.87H286.04V293.54H311.01V267.87Z\\\" fill=\\\"#EB6D79\\\"\\\/>\\n<path id=\\\"Vector13326_9\\\" d=\\\"M301.28 267.87H275.8V293.62H301.28V267.87Z\\\" fill=\\\"#F3B756\\\"\\\/>\\n<path id=\\\"Vector13326_10\\\" d=\\\"M252 180.5H276.88C276.88 180.5 276.88 159.62 298.58 159.24C309.86 159.05 315.7 166.43 318.08 172.09C319.394 175.35 319.919 178.875 319.611 182.377C319.303 185.879 318.172 189.259 316.31 192.24C312.09 199.24 303 206.19 286.23 203.24L286.07 258.67H310.67V225.8C310.67 225.8 345.18 216.88 345.18 178.86C345.18 142.48 315.76 134.62 299.95 134.12C291.15 133.84 287.95 133.46 277.08 135C263.24 137 251.73 153.07 252 180.5Z\\\" fill=\\\"#EB6D79\\\"\\\/>\\n<path id=\\\"Vector13326_11\\\" d=\\\"M241.72 180.5H266.6C266.6 180.5 266.6 159.62 288.31 159.24C299.58 159.05 305.43 166.43 307.8 172.09C309.112 175.352 309.633 178.879 309.32 182.381C309.007 185.884 307.87 189.262 306 192.24C301.78 199.24 292.54 205.52 275.77 202.57V258.66H300.37V225.8C300.37 225.8 334.87 216.88 334.87 178.86C334.87 142.48 302.25 134.03 288.28 134.03C277.63 134 241.25 136.61 241.72 180.5Z\\\" fill=\\\"#F3B756\\\"\\\/>\\n<\\\/g>\\n<path id=\\\"box-about_2\\\" d=\\\"M252.61 267.51H226.86V293.26H252.61V267.51Z\\\" fill=\\\"#F3B756\\\"\\\/>\\n<path id=\\\"box-about_3\\\" d=\\\"M205.91 267.51H180.16V293.26H205.91V267.51Z\\\" fill=\\\"#F3B756\\\"\\\/>\\n<path id=\\\"box-about_4\\\" d=\\\"M159.2 267.51H133.45V293.26H159.2V267.51Z\\\" fill=\\\"#F3B756\\\"\\\/>\\n<path id=\\\"cog-about\\\" d=\\\"M87.42 214.68C90.5054 214.739 93.5691 215.21 96.53 216.08L102.47 209.93L114.56 217.26L111.85 225.37C113.992 227.593 115.828 230.092 117.31 232.8L125.85 232.65L129.22 246.39L121.57 250.2C121.516 253.289 121.045 256.357 120.17 259.32L126.32 265.26L119 277.35L110.89 274.64C108.667 276.782 106.168 278.618 103.46 280.1L103.61 288.64L89.86 292L86.05 284.35C82.9612 284.291 79.8942 283.82 76.93 282.95L71 289.11L58.9 281.77L61.61 273.67C59.468 271.449 57.6348 268.95 56.16 266.24L47.61 266.39L44.25 252.65L51.89 248.83C51.9495 245.745 52.4203 242.681 53.29 239.72L47.14 233.78L54.48 221.69L62.58 224.4C64.7985 222.257 67.294 220.421 70 218.94L69.85 210.4L83.6 207L87.42 214.65V214.68ZM83.75 234.63C80.8356 235.343 78.198 236.904 76.1708 239.116C74.1437 241.328 72.818 244.092 72.3614 247.057C71.9048 250.022 72.3378 253.057 73.6057 255.776C74.8736 258.495 76.9194 260.778 79.4844 262.334C82.0494 263.891 85.0184 264.652 88.0159 264.521C91.0134 264.39 93.9048 263.374 96.3245 261.6C98.7442 259.825 100.583 257.374 101.61 254.554C102.636 251.735 102.803 248.674 102.09 245.76C101.131 241.854 98.6616 238.487 95.2229 236.4C91.7842 234.314 87.6578 233.677 83.75 234.63V234.63Z\\\" fill=\\\"#5198BF\\\"\\\/>\\n<path id=\\\"Vector13326_12\\\" d=\\\"M311.77 82.7C314.405 78.1677 315.775 73.011 315.737 67.7684C315.699 62.5258 314.253 57.3897 311.552 52.8964C308.851 48.4031 304.993 44.7176 300.381 42.2246C295.769 39.7316 290.572 38.5227 285.333 38.7241C280.094 38.9255 275.005 40.5299 270.598 43.3696C266.191 46.2093 262.627 50.1802 260.279 54.8676C257.931 59.555 256.884 64.787 257.249 70.017C257.613 75.2471 259.375 80.2834 262.35 84.6L258.64 91L280.83 103.91C280.83 103.91 283.04 100.4 284.95 97.23C290.324 97.5075 295.671 96.2982 300.402 93.7348C305.134 91.1714 309.067 87.3533 311.77 82.7V82.7Z\\\" fill=\\\"#FCD545\\\"\\\/>\\n<path id=\\\"Vector13326_13\\\" d=\\\"M272.86 99.12L273.07 98.83L273.7 97.97C274.27 97.23 275.1 96.13 276.21 94.74C277.32 93.35 278.69 91.67 280.41 89.82C282.352 87.7128 284.496 85.8004 286.81 84.11C288.158 83.1285 289.59 82.2684 291.09 81.54C291.909 81.1347 292.817 80.9453 293.73 80.99C294.214 81.0275 294.681 81.1817 295.092 81.4395C295.503 81.6972 295.846 82.0509 296.09 82.47C296.343 82.9121 296.418 83.4344 296.3 83.93C296.186 84.4398 295.878 84.8848 295.44 85.17C294.565 85.709 293.521 85.9049 292.51 85.72C291.457 85.5044 290.459 85.0789 289.574 84.469C288.69 83.8591 287.937 83.0772 287.361 82.1701C286.785 81.2629 286.398 80.249 286.223 79.189C286.047 78.1289 286.087 77.0443 286.34 76C286.569 74.8757 287.105 73.837 287.89 73C288.309 72.5531 288.87 72.2658 289.478 72.1874C290.085 72.109 290.701 72.2442 291.22 72.57C291.473 72.7574 291.677 73.004 291.812 73.2881C291.948 73.5722 292.013 73.8853 292 74.2C291.964 74.8252 291.714 75.4188 291.29 75.88C290.38 76.7129 289.227 77.2317 288 77.36C286.793 77.5698 285.556 77.5251 284.368 77.2289C283.18 76.9327 282.067 76.3915 281.1 75.64C280.147 74.8613 279.397 73.8631 278.915 72.731C278.432 71.5989 278.232 70.3667 278.33 69.14C278.377 68.5299 278.55 67.9362 278.838 67.3959C279.125 66.8556 279.521 66.3804 280 66C280.244 65.8022 280.526 65.6581 280.83 65.5771C281.133 65.4961 281.45 65.48 281.76 65.53C282.063 65.5839 282.351 65.7008 282.606 65.873C282.861 66.0453 283.077 66.2691 283.24 66.53C283.552 67.0509 283.698 67.6541 283.66 68.26C283.617 68.8446 283.461 69.4152 283.2 69.94C282.698 70.9613 281.994 71.8698 281.13 72.61C279.48 74.0715 277.333 74.8477 275.13 74.78C273.031 74.7034 271.027 73.8808 269.48 72.46C268.686 71.812 268.13 70.9185 267.9 69.92C267.799 69.4172 267.87 68.895 268.102 68.4377C268.335 67.9805 268.714 67.6149 269.18 67.4C269.662 67.2446 270.186 67.284 270.64 67.51C271.076 67.719 271.447 68.0442 271.71 68.45C272.174 69.2434 272.364 70.1678 272.25 71.08C272.09 72.83 271.82 74.46 271.6 76.08C270.66 82.36 269.6 87.4 268.91 90.87C268.55 92.61 268.24 93.95 268.03 94.87C267.92 95.31 267.84 95.65 267.78 95.87L267.69 96.22C267.703 96.099 267.723 95.9788 267.75 95.86L267.96 94.86C268.15 93.93 268.42 92.58 268.78 90.86C269.47 87.38 270.44 82.33 271.35 76.06C271.56 74.49 271.82 72.83 271.97 71.13C272.072 70.2776 271.896 69.4151 271.47 68.67C271.303 68.2364 270.97 67.8869 270.546 67.6984C270.121 67.5099 269.639 67.4979 269.205 67.665C268.771 67.8321 268.422 68.1646 268.233 68.5894C268.045 69.0141 268.033 69.4964 268.2 69.93C268.431 70.8561 268.953 71.6835 269.69 72.29C271.192 73.6493 273.125 74.4354 275.15 74.51C277.279 74.5756 279.352 73.8284 280.95 72.42C281.783 71.7107 282.463 70.8398 282.95 69.86C283.219 69.3934 283.366 68.8663 283.376 68.3277C283.387 67.7891 283.261 67.2567 283.01 66.78C282.878 66.552 282.7 66.3546 282.486 66.2012C282.272 66.0477 282.028 65.9416 281.77 65.89C281.508 65.851 281.241 65.8673 280.986 65.9379C280.731 66.0085 280.494 66.1319 280.29 66.3C279.854 66.6546 279.498 67.0971 279.245 67.5984C278.992 68.0998 278.847 68.6489 278.82 69.21C278.727 70.3783 278.918 71.5518 279.378 72.6299C279.838 73.7079 280.552 74.6585 281.46 75.4C282.38 76.1044 283.437 76.6103 284.562 76.8857C285.688 77.1611 286.858 77.2 288 77C289.118 76.8715 290.167 76.3958 291 75.64C291.369 75.2403 291.585 74.7233 291.61 74.18C291.63 73.9223 291.583 73.6637 291.475 73.4291C291.366 73.1944 291.199 72.9916 290.99 72.84C290.548 72.5473 290.014 72.4296 289.49 72.51C288.967 72.6034 288.486 72.8547 288.11 73.23C287.373 74.0204 286.871 75.0004 286.66 76.06C286.421 77.0605 286.384 78.0987 286.552 79.1137C286.719 80.1286 287.087 81.1 287.635 81.9708C288.183 82.8416 288.898 83.5943 289.741 84.1849C290.583 84.7754 291.535 85.192 292.54 85.41C293.473 85.5826 294.437 85.4083 295.25 84.92C295.619 84.6778 295.882 84.3037 295.984 83.8743C296.086 83.4448 296.02 82.9925 295.8 82.61C295.579 82.2342 295.272 81.9171 294.903 81.6856C294.534 81.4541 294.114 81.315 293.68 81.28C292.817 81.238 291.957 81.4134 291.18 81.79C289.715 82.5089 288.316 83.3555 287 84.32C284.688 85.9868 282.544 87.8758 280.6 89.96C278.87 91.79 277.48 93.46 276.36 94.83C275.24 96.2 274.36 97.28 273.8 98.02L273.14 98.85C273 99 272.86 99.12 272.86 99.12Z\\\" fill=\\\"#1A2E35\\\"\\\/>\\n<path id=\\\"Vector13326_14\\\" d=\\\"M276.73 107L257.68 95.93C257.492 95.8213 257.327 95.6766 257.195 95.5041C257.063 95.3315 256.966 95.1346 256.91 94.9246C256.855 94.7147 256.841 94.4957 256.87 94.2804C256.899 94.0651 256.97 93.8577 257.08 93.67V93.67C257.189 93.4819 257.333 93.3171 257.506 93.185C257.678 93.053 257.875 92.9563 258.085 92.9006C258.295 92.8448 258.514 92.8311 258.729 92.8602C258.945 92.8893 259.152 92.9606 259.34 93.07L278.39 104.15C278.578 104.259 278.743 104.403 278.875 104.576C279.007 104.748 279.104 104.945 279.159 105.155C279.215 105.365 279.229 105.584 279.2 105.8C279.171 106.015 279.099 106.222 278.99 106.41V106.41C278.88 106.597 278.735 106.761 278.562 106.892C278.389 107.023 278.192 107.119 277.982 107.174C277.772 107.229 277.554 107.241 277.339 107.212C277.124 107.182 276.917 107.11 276.73 107V107Z\\\" fill=\\\"#1A2E35\\\"\\\/>\\n<path id=\\\"Vector13326_15\\\" d=\\\"M276 108.26L257 97.18C256.621 96.9598 256.17 96.8994 255.746 97.0119C255.322 97.1244 254.96 97.4007 254.74 97.78C254.52 98.1592 254.459 98.6104 254.572 99.0342C254.684 99.4581 254.961 99.8198 255.34 100.04L257.43 101.25L257.13 108.15C257.116 108.537 257.208 108.921 257.394 109.261C257.581 109.601 257.856 109.884 258.19 110.08L264.99 114.08C265.323 114.286 265.708 114.396 266.1 114.396C266.492 114.396 266.877 114.286 267.21 114.08L272.97 110.38L274.39 111.21C274.578 111.319 274.785 111.39 275 111.419C275.216 111.448 275.434 111.434 275.644 111.378C275.854 111.322 276.051 111.226 276.224 111.094C276.396 110.962 276.541 110.798 276.65 110.61C276.759 110.422 276.83 110.215 276.859 110C276.888 109.784 276.874 109.566 276.818 109.356C276.762 109.146 276.666 108.949 276.534 108.776C276.402 108.604 276.238 108.459 276.05 108.35L276 108.26Z\\\" fill=\\\"#1A2E35\\\"\\\/>\\n<g id=\\\"Group\\\" opacity=\\\"0.2\\\">\\n<path id=\\\"Vector13326_16\\\" opacity=\\\"0.2\\\" d=\\\"M279.58 42.39C281.874 41.8647 284.239 41.7194 286.58 41.96C288.148 42.1097 289.686 42.494 291.14 43.1C292.14 43.56 292.65 43.97 292.58 44.2C292.42 44.72 290.1 44.29 286.51 44.51C281.891 44.6858 277.42 46.1856 273.629 48.8309C269.839 51.4761 266.889 55.1552 265.13 59.43C263.69 62.73 263.3 65.05 262.75 65.02C262.51 65.02 262.3 64.4 262.22 63.29C262.148 61.7169 262.317 60.1421 262.72 58.62C263.301 56.3272 264.254 54.1451 265.54 52.16C267.118 49.7006 269.155 47.5684 271.54 45.88\\\" fill=\\\"white\\\"\\\/>\\n<\\\/g>\\n<g id=\\\"Group_2\\\" opacity=\\\"0.2\\\">\\n<path id=\\\"Vector13326_17\\\" opacity=\\\"0.2\\\" d=\\\"M298.06 48.83C296.46 47.88 295.3 46.62 295.63 45.67C295.81 45.21 296.36 44.94 297.15 44.92C298.114 44.9634 299.053 45.2421 299.884 45.732C300.716 46.2218 301.415 46.9078 301.92 47.73C302.098 47.9727 302.201 48.2624 302.215 48.563C302.229 48.8636 302.154 49.1617 302 49.42\\\" fill=\\\"white\\\"\\\/>\\n<\\\/g>\\n<path id=\\\"Vector13326_18\\\" d=\\\"M266.54 114.23C266.162 113.863 265.805 113.476 265.47 113.07C263.71 111.236 261.426 109.992 258.93 109.51C258.405 109.45 257.885 109.359 257.37 109.24C257.899 109.145 258.441 109.145 258.97 109.24C260.258 109.418 261.505 109.824 262.65 110.44C263.789 111.065 264.806 111.892 265.65 112.88C266.031 113.268 266.333 113.727 266.54 114.23V114.23Z\\\" fill=\\\"#375A64\\\"\\\/>\\n<path id=\\\"Vector13326_19\\\" d=\\\"M272.92 110.38C272.87 110.47 269.39 108.53 265.14 106.06C260.89 103.59 257.49 101.52 257.54 101.43C257.59 101.34 261.07 103.28 265.32 105.75C269.57 108.22 273 110.29 272.92 110.38Z\\\" fill=\\\"#375A64\\\"\\\/>\\n<path id=\\\"Vector13326_20\\\" d=\\\"M270.41 112C269.719 111.756 269.05 111.455 268.41 111.1C267.2 110.49 265.56 109.63 263.77 108.62C261.98 107.61 260.38 106.62 259.24 105.94C258.608 105.579 258.006 105.168 257.44 104.71C258.111 104.986 258.757 105.321 259.37 105.71L263.95 108.29L268.53 110.86C269.19 111.183 269.819 111.564 270.41 112V112Z\\\" fill=\\\"#375A64\\\"\\\/>\\n<path id=\\\"Vector13326_21\\\" d=\\\"M189.58 197.51H267.81\\\" stroke=\\\"#231F20\\\" stroke-miterlimit=\\\"10\\\"\\\/>\\n<path id=\\\"Vector13326_22\\\" d=\\\"M189.58 207.66H267.81\\\" stroke=\\\"#231F20\\\" stroke-miterlimit=\\\"10\\\"\\\/>\\n<path id=\\\"Vector13326_23\\\" d=\\\"M189.58 217.8H267.81\\\" stroke=\\\"#231F20\\\" stroke-miterlimit=\\\"10\\\"\\\/>\\n<path id=\\\"Vector13326_24\\\" d=\\\"M189.58 227.95H267.81\\\" stroke=\\\"#231F20\\\" stroke-miterlimit=\\\"10\\\"\\\/>\\n<path id=\\\"Vector13326_25\\\" d=\\\"M189.58 238.1H267.81\\\" stroke=\\\"#231F20\\\" stroke-miterlimit=\\\"10\\\"\\\/>\\n<path id=\\\"Vector13326_26\\\" d=\\\"M189.58 248.24H267.81\\\" stroke=\\\"#231F20\\\" stroke-miterlimit=\\\"10\\\"\\\/>\\n<path id=\\\"Vector13326_27\\\" d=\\\"M189.58 258.39H267.81\\\" stroke=\\\"#231F20\\\" stroke-miterlimit=\\\"10\\\"\\\/>\\n<path id=\\\"Vector13326_28\\\" d=\\\"M172.83 157.12C204.006 157.12 229.28 131.846 229.28 100.67C229.28 69.4935 204.006 44.22 172.83 44.22C141.653 44.22 116.38 69.4935 116.38 100.67C116.38 131.846 141.653 157.12 172.83 157.12Z\\\" fill=\\\"#8AD5F2\\\"\\\/>\\n<path id=\\\"Vector13326_29\\\" d=\\\"M172.83 139.02C194.01 139.02 211.18 121.85 211.18 100.67C211.18 79.4898 194.01 62.3199 172.83 62.3199C151.65 62.3199 134.48 79.4898 134.48 100.67C134.48 121.85 151.65 139.02 172.83 139.02Z\\\" fill=\\\"#FFB616\\\"\\\/>\\n<path id=\\\"Vector13326_30\\\" d=\\\"M172.83 119.2C183.064 119.2 191.36 110.904 191.36 100.67C191.36 90.4362 183.064 82.14 172.83 82.14C162.596 82.14 154.3 90.4362 154.3 100.67C154.3 110.904 162.596 119.2 172.83 119.2Z\\\" fill=\\\"#EB6D79\\\"\\\/>\\n<path id=\\\"Vector13326_31\\\" d=\\\"M233 59.65C213.56 73.21 192.48 86.65 173 100.2Z\\\" fill=\\\"#F5F5F5\\\"\\\/>\\n<path id=\\\"Vector13326_32\\\" d=\\\"M173 100.2C172.9 100.05 186.23 90.84 202.79 79.65C219.35 68.46 232.85 59.5 232.95 59.65C233.05 59.8 219.76 69 203.2 80.2C186.64 91.4 173.14 100.35 173 100.2Z\\\" fill=\\\"#1A2E35\\\"\\\/>\\n<path id=\\\"Vector13326_33\\\" d=\\\"M226.39 63.5699C226.39 63.3899 229.51 63.3499 233.39 63.4899C237.27 63.6299 240.33 63.8899 240.32 64.0799C240.31 64.2699 237.2 64.3 233.32 64.16C229.44 64.02 226.38 63.7599 226.39 63.5699Z\\\" fill=\\\"#1A2E35\\\"\\\/>\\n<path id=\\\"Vector13326_34\\\" d=\\\"M228.75 54.45C228.93 54.45 228.62 56.61 228.06 59.2C227.5 61.79 226.91 63.86 226.73 63.82C226.55 63.78 226.85 61.65 227.41 59.06C227.97 56.47 228.57 54.41 228.75 54.45Z\\\" fill=\\\"#1A2E35\\\"\\\/>\\n<path id=\\\"Vector13326_35\\\" d=\\\"M225.35 55.52C225.53 55.52 225.28 57.77 224.8 60.52C224.32 63.27 223.8 65.4 223.58 65.37C223.36 65.34 223.65 63.11 224.14 60.37C224.63 57.63 225.17 55.48 225.35 55.52Z\\\" fill=\\\"#1A2E35\\\"\\\/>\\n<path id=\\\"Vector13326_36\\\" d=\\\"M233.33 67.5799C233.33 67.7599 231.13 67.3999 228.5 66.7799C225.87 66.1599 223.78 65.5199 223.83 65.3399C223.88 65.1599 226.03 65.5099 228.66 66.1299C231.29 66.7499 233.37 67.3999 233.33 67.5799Z\\\" fill=\\\"#1A2E35\\\"\\\/>\\n<\\\/g>\\n<\\\/g>\\n<\\\/g>\\n    <\\\/svg><\\\/div>\\n\"}}]},{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"media_overlay_gradient\":\"\",\"width_medium\":\"2-3\",\"vertical_align\":\"middle\"},\"children\":[{\"type\":\"headline\",\"props\":{\"title_element\":\"h1\",\"class\":\"color-primary\",\"content\":\"<strong>Sul progetto<\\\/strong>\",\"title_style\":\"heading-small\"}},{\"type\":\"text\",\"props\":{\"margin\":\"default\",\"column_breakpoint\":\"m\",\"content\":\"\n\n<p>L'inclusione di studentesse e studenti migranti nei sistemi educativi europei \\u00e8 una priorit\\u00e0 per i responsabili delle politiche nell'Unione europea, poich\\u00e9 ci sono ancora molte sfide al riguardo.<\\\/p>\\n\n\n<p>Il progetto FEINAMC si concentra sulla diffusione e l'approfondimento di buone pratiche (un programma di mentoring e uno strumento di valutazione dell'apprendimento precedente) per favorire l'inclusione dei bambini migranti appena arrivati nei sistemi educativi formali in Austria, Cipro, Grecia, Italia e Spagna e nei paesi dell\\u2019UE<\\\/p>\"}},{\"type\":\"button\",\"props\":{\"grid_column_gap\":\"small\",\"grid_row_gap\":\"small\",\"margin\":\"default\",\"text_align\":\"right\"},\"children\":[{\"type\":\"button_item\",\"props\":{\"button_style\":\"primary\",\"icon_align\":\"left\",\"content\":\"Scopri di pi\\u00f9 >\",\"link\":\"\\\/it\\\/about\"}}]}]}]},{\"type\":\"row\",\"props\":{\"layout\":\"1-3,1-3,1-3\"},\"children\":[{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"media_overlay_gradient\":\"\",\"width_medium\":\"1-3\"},\"children\":[{\"type\":\"module\",\"props\":{\"menu_style\":\"nav\",\"widget\":\"custom_html-9\",\"type\":\"custom_html\",\"text_align\":\"center\",\"margin_remove_bottom\":true}},{\"type\":\"headline\",\"props\":{\"title_element\":\"h2\",\"content\":\"Obiettivi\",\"text_align\":\"center\",\"title_style\":\"h3\",\"class\":\"color-primary\",\"margin_remove_top\":true}}]},{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"media_overlay_gradient\":\"\",\"width_medium\":\"1-3\"},\"children\":[{\"type\":\"module\",\"props\":{\"menu_style\":\"nav\",\"widget\":\"custom_html-13\",\"type\":\"custom_html\",\"text_align\":\"center\"}},{\"type\":\"headline\",\"props\":{\"title_element\":\"h2\",\"content\":\"Risorse\",\"text_align\":\"center\",\"title_style\":\"h3\",\"class\":\"color-primary\",\"margin_remove_top\":true}}]},{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"media_overlay_gradient\":\"\",\"width_medium\":\"1-3\"},\"children\":[{\"type\":\"module\",\"props\":{\"menu_style\":\"nav\",\"widget\":\"custom_html-17\",\"type\":\"custom_html\",\"text_align\":\"center\"}},{\"type\":\"headline\",\"props\":{\"title_element\":\"h2\",\"content\":\"Metodologia\",\"text_align\":\"center\",\"title_style\":\"h3\",\"class\":\"color-primary\",\"margin_remove_top\":true}}]}]}]},{\"type\":\"section\",\"props\":{\"style\":\"default\",\"width\":\"default\",\"vertical_align\":\"middle\",\"title_position\":\"top-left\",\"title_rotation\":\"left\",\"title_breakpoint\":\"xl\",\"image_position\":\"center-center\",\"css\":\".el-section{background-color:#F4F4F4;}\",\"class\":\"gsap-sec2\",\"animation\":\"slide-bottom\",\"animation_delay\":\"300\"},\"children\":[{\"type\":\"row\",\"children\":[{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"media_overlay_gradient\":\"\"},\"children\":[{\"type\":\"headline\",\"props\":{\"title_element\":\"h1\",\"class\":\"color-primary\",\"content\":\"<strong>NEWS<\\\/strong>\",\"title_style\":\"heading-small\",\"text_align\":\"center\"}},{\"type\":\"text\",\"props\":{\"margin\":\"default\",\"column_breakpoint\":\"m\",\"content\":\"[widgetkit id=\\\"13\\\"]\",\"css\":\".uk-card-body {padding:0;border:2px solid #000;background-color:#fff;transition:all .5s ease-out;}\\nimg{margin-top:-1px;\\n\\n}\\n\\n.uk-card {\\n-webkit-box-shadow: 7px 7px 0px 0px rgba(51,45,45,0.15);\\n-moz-box-shadow: 7px 7px 0px 0px rgba(51,45,45,0.15);\\nbox-shadow: 7px 7px 0px 0px rgba(51,45,45,0.15);\\n}\\n\\nh3{padding-left:10px;padding-right:10px;font-size:20px;font-weight:bold;}\\n\\n.foo3{\\n  padding-left:10px;padding-right:10px;padding-bottom:10px;\\n}\\n\\n.uk-card{position:relative;border:0px;transition:all .5s ease-out;}\\n\\n.uk-card:hover{position:relative;\\n-webkit-box-shadow: 7px 7px 0px 0px rgba(51,45,45,0);\\n-moz-box-shadow: 7px 7px 0px 0px rgba(51,45,45,0);\\nbox-shadow: 7px 7px 0px 0px rgba(51,45,45,0);\\n   \\n}\"}},{\"type\":\"button\",\"props\":{\"grid_column_gap\":\"small\",\"grid_row_gap\":\"small\",\"margin\":\"default\",\"text_align\":\"center\"},\"children\":[{\"type\":\"button_item\",\"props\":{\"button_style\":\"primary\",\"icon_align\":\"left\",\"content\":\"Leggi tutte le news\",\"link\":\"\\\/it\\\/news\"}}]}]}]}]},{\"type\":\"section\",\"props\":{\"style\":\"muted\",\"width\":\"default\",\"vertical_align\":\"middle\",\"title_position\":\"top-left\",\"title_rotation\":\"left\",\"title_breakpoint\":\"xl\",\"image_position\":\"center-center\",\"css\":\".el-section{background-color:#8AD5F2 !important;}\",\"animation\":\"slide-bottom\",\"animation_delay\":true},\"children\":[{\"type\":\"row\",\"children\":[{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"media_overlay_gradient\":\"\"},\"children\":[{\"type\":\"headline\",\"props\":{\"title_element\":\"h1\",\"class\":\"color-primary\",\"content\":\"<strong>Contattaci<\\\/strong>\",\"title_style\":\"heading-small\",\"text_align\":\"center\",\"css\":\".el-element{color:#fff;}\"}},{\"type\":\"text\",\"props\":{\"margin\":\"default\",\"column_breakpoint\":\"m\",\"content\":\"[contact-form-7 id=\\\"153\\\" title=\\\"Contact form 1\\\"]\",\"maxwidth\":\"xlarge\",\"block_align\":\"center\"}},{\"type\":\"image\",\"props\":{\"margin\":\"default\",\"image_svg_color\":\"emphasis\",\"image\":\"wp-content\\\/uploads\\\/2021\\\/05\\\/contact-home.png\",\"text_align\":\"center\",\"margin_remove_bottom\":true}}]}]}]}],\"version\":\"2.4.14\"} --><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Diffondere ed approfondire buone pratiche per promuovere l\u2019inclusione educativa di migranti appena arrivati Sul progetto L&#8217;inclusione di studentesse e studenti&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-548","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/feinamc.eu\/it\/wp-json\/wp\/v2\/pages\/548","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/feinamc.eu\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/feinamc.eu\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/feinamc.eu\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/feinamc.eu\/it\/wp-json\/wp\/v2\/comments?post=548"}],"version-history":[{"count":3,"href":"https:\/\/feinamc.eu\/it\/wp-json\/wp\/v2\/pages\/548\/revisions"}],"predecessor-version":[{"id":665,"href":"https:\/\/feinamc.eu\/it\/wp-json\/wp\/v2\/pages\/548\/revisions\/665"}],"wp:attachment":[{"href":"https:\/\/feinamc.eu\/it\/wp-json\/wp\/v2\/media?parent=548"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}